{"id":80331,"date":"2022-09-11T14:31:06","date_gmt":"2022-09-11T14:31:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/09\/11\/ukrisis-aux-origines\/"},"modified":"2022-09-11T14:31:06","modified_gmt":"2022-09-11T14:31:06","slug":"ukrisis-aux-origines","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/09\/11\/ukrisis-aux-origines\/","title":{"rendered":"&lsquo;<em>Ukrisis<\/em>&lsquo; aux origines"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&lsquo;<em>Ukrisis<\/em>&lsquo; aux origines<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; <strong>La guerre en Ukraine, que nous nommons &lsquo;<em>Ukrisis<\/em>&lsquo;<\/strong>, commence pour certains qui interpr\u00e8tent la chansonnette suivant la partition du Parti, le 24 f\u00e9vrier 2022. &bull; Pour d&rsquo;autres, tout de m\u00eame plus attentifs aux \u00e9v\u00e9nements en-cours, il faut remonter \u00e0 2014, avec le coup d&rsquo;&Eacute;tat de Kiev de f\u00e9vrier de cette ann\u00e9e-l\u00e0. &bull; D&rsquo;autres enfin, <strong>t\u00e9moignent que le drame s&rsquo;est nou\u00e9 dans les premi\u00e8res ann\u00e9es post-URSS<\/strong>. &bull; Un t\u00e9moin exceptionnel, <strong>l&rsquo;un des principaux acteurs du c\u00f4t\u00e9 US, c&rsquo;est l&rsquo;\u00e9conomiste Jeffrey Sachs<\/strong>. &bull; Contribution : <em>dedefensa.org <\/em>et interview de &lsquo;<em>Democracy Now !<\/em>&lsquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Donc, remonter aux origines, c&rsquo;est-\u00e0-dire en 1989-1993, et le traitement qui fut appliqu\u00e9 aux restes \u00e9pars de l&rsquo;Union Sovi\u00e9tique, essentiellement \u00e0 son c&oelig;ur et \u00e0 son \u00e2me russes. Notre t\u00e9moin, Jeffrey Sachs, prestigieux universitaire, \u00e9conomiste fameux, acteur essentiel de toute cette p\u00e9riode, n&rsquo;a pas de \u00ab\u00a0langue de coton\u00a0\u00bb ni la langue dans sa poche. Il remonte, lui, aux origines des origines, retrouvant l&rsquo;un des trois composants essentiels du \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00a0\u00bb selon PhG :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Employant l&rsquo;expression de \u00ab\u00a0r\u00e9volution du choix de la thermodynamique\u00a0\u00bb, nous ne d\u00e9signons pas un \u00e9v\u00e9nement historique pr\u00e9cis mais une dynamique, une succession de choix conjoncturels, essentiellement faits en Angleterre, le tout aboutissant \u00e0 une r\u00e9volution industrielle et manufacturi\u00e8re de rupture, appuy\u00e9e sur le \u00ab\u00a0choix de la thermodynamique\u00a0\u00bb. Ici, nous pouvons citer des extraits du passage de la Gr\u00e2ce de l&rsquo;Histoire se rapportant \u00e0 l&rsquo;\u00e9v\u00e9nement, qui pr\u00e9sentent parfaitement ce qu&rsquo;est cet \u00e9v\u00e9nement selon notre perception&hellip; (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-premi_re_partie_de_i_na_verdun_25_01_2010.html\">25 janvier 2010<\/a>.)<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0&hellip;Chaunu fait allusion aux \u00ab\u00a0progr\u00e8s\u00a0\u00bb d\u00e9cisifs accomplis en Angleterre pendant la p\u00e9riode de temps influenc\u00e9e directement par la R\u00e9volution, &ndash; disons entre 1780 et 1820, &ndash; dans le domaine du d\u00e9veloppement des techniques et du machinisme. C&rsquo;est pendant cette p\u00e9riode que s&rsquo;est forg\u00e9e la matrice technique du progr\u00e8s industriel de l&rsquo;\u00e9poque moderne ; c&rsquo;est pendant cette p\u00e9riode que le choix est fait de la thermodynamique pour la production d&rsquo;\u00e9nergie et le d\u00e9veloppement de la machine qui va servir de fondement \u00e0 notre \u00e8re technologique. Dans &lsquo;Le choix du feu&rsquo;, le philosophe des techniques Alain Gras montre combien ce choix n&rsquo;\u00e9tait nullement in\u00e9luctable&#8230;\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Jeffrey Sachs distingue de m\u00eame cette p\u00e9riode du \u00ab\u00a0d\u00e9cha&icirc;nement\u00a0\u00bb, selon les m\u00eames r\u00e9f\u00e9rences, &ndash; anglo-saxonne et invention de la machine \u00e0 vapeur (dat\u00e9e symboliquement de 1784) qui ent\u00e9rine le &lsquo;<em>choix du feu<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le pouvoir disproportionn\u00e9 du monde occidental, et surtout du monde anglo-saxon, qui a commenc\u00e9 avec l&rsquo;Empire britannique, et maintenant les &Eacute;tats-Unis, a environ 250 ans, donc une courte p\u00e9riode dans l&rsquo;histoire du monde. Il se trouve que, pour de nombreuses raisons tr\u00e8s int\u00e9ressantes, la r\u00e9volution industrielle est arriv\u00e9e en Angleterre en premier. Le moteur \u00e0 vapeur a \u00e9t\u00e9 invent\u00e9 l\u00e0-bas. C&rsquo;est probablement l&rsquo;invention la plus importante de l&rsquo;histoire moderne<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p><a href=\"https:\/\/en.wikipedia.org\/wiki\/Jeffrey_Sachs\">Jeffrey Sachs<\/a> est donc un \u00e9conomiste, un universitaire prestigieux et un homme d&rsquo;influence et d&rsquo;action comme les Etats-Unis sont capables de produire, restant \u00e0 la fois totalement int\u00e9gr\u00e9 au Syst\u00e8me (de l&rsquo;am\u00e9ricanisme, bras arm\u00e9 du Syst\u00e8me), portant \u00e0 la fois sur ce Syst\u00e8me lorsque le temps et les circonstances le permettent un &oelig;il critique, tr\u00e8s-critique. C&rsquo;est effectivement sa d\u00e9marche pour cette p\u00e9riode, cette s\u00e9quence cruciale des trente ann\u00e9es qui nous s\u00e9parent de la chute de l&rsquo;URSS, de la fin (?) de la Guerre Froide, du retour de la Russie en tant que telle, identit\u00e9 retrouv\u00e9e et r\u00e9affirm\u00e9e.<\/p>\n<\/p>\n<p><p>Sachs fut le ma&icirc;tre d&rsquo;&oelig;uvre des \u00ab\u00a0conseils\u00a0\u00bb \u00e9conomiques des USA aux pays communistes perdant brusquement toutes leurs r\u00e9f\u00e9rences. Professeur \u00e0 Harvard, et donc d\u00e9tach\u00e9 aupr\u00e8s des dirigeants russes et polonais durant la derni\u00e8re d\u00e9cennie du XX\u00e8me si\u00e8cle. Ainsi eut-il tout le loisir (?) d&rsquo;assister directement aux \u00e9v\u00e9nements et aux responsabilit\u00e9s engag\u00e9s dans ces \u00e9v\u00e9nements, d\u00e9bouchant \u00e9videmment sur les \u00e9v\u00e9nements actuels.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Cela dit, je pense que ce qu&rsquo;il est important d&rsquo;observer c&rsquo;est qu&rsquo;il n&rsquo;y a pas de d\u00e9terminisme lin\u00e9aire, m\u00eame \u00e0 partir d&rsquo;\u00e9v\u00e9nements comme ceux-l\u00e0<\/em> [les ann\u00e9es 1990 en Russie]<em>, qui \u00e9taient d\u00e9stabilisants et tr\u00e8s malheureux et inutiles, jusqu&rsquo;\u00e0 ce qui se passe maintenant, parce que lorsque le pr\u00e9sident Poutine est arriv\u00e9, il n&rsquo;\u00e9tait pas anti-europ\u00e9en, il n&rsquo;\u00e9tait pas anti-am\u00e9ricain. Ce qu&rsquo;il a vu, cependant, c&rsquo;est l&rsquo;incroyable arrogance des &Eacute;tats-Unis, l&rsquo;expansion de l&rsquo;OTAN, les guerres en Irak, la guerre secr\u00e8te en Syrie, la guerre en Libye, contre la r\u00e9solution de l&rsquo;ONU. Donc, nous avons nous-m\u00eames cr\u00e9\u00e9 une si grande partie de ce \u00e0 quoi nous sommes confront\u00e9s en ce moment par notre propre ineptie et notre arrogance. Il n&rsquo;y a pas eu de d\u00e9termination lin\u00e9aire. C&rsquo;est l&rsquo;arrogance des &Eacute;tats-Unis, \u00e9tape par \u00e9tape, qui a contribu\u00e9 \u00e0 nous amener l\u00e0 o&ugrave; nous sommes aujourd&rsquo;hui. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Jeffrey Sachs mena par cons\u00e9quent deux combats parall\u00e8les dans les ann\u00e9es 1990 : l&rsquo;un pour relever les pays de l&rsquo;ancienne URSS, l&rsquo;autre contre ce qu&rsquo;il jugeait \u00eatre une incompr\u00e9hensible volont\u00e9 de Washington de ne pas aider la Russie. Le paradoxe, sur lequel on reviendra tr\u00e8s vite parce qu&rsquo;il est de taille apr\u00e8s tout, est que ces conceptions \u00e9taient le pendant \u00e9conomiques de la politique des n\u00e9oconservateurs qu&rsquo;il accuse aujourd&rsquo;hui, &ndash; c&rsquo;est-\u00e0-dire les th\u00e8ses fameuses autour de la \u00ab\u00a0destruction cr\u00e9atrice\u00a0\u00bb, autant que les embrassades \u00e0 propos de la globalisation.<\/p>\n<\/p>\n<p><p>Mais Sachs ne voyait rien de cela, il ne voyait rien de la construction en train de se faire de ce que William Pfaff baptisa &laquo; <em><a href=\"https:\/\/www.dedefensa.org\/article\/1992-la-crise-americaine-post-guerre-froide\">The Burlesque of Empire<\/a><\/em> &raquo;, parlant des premiers \u00e9chos des plans h\u00e9g\u00e9moniques de Cheney (alors secr\u00e9taire \u00e0 la d\u00e9fense de Bush-p\u00e8re), de son adjoint Wolfowitz et du comp\u00e8re Rumsfeld :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Et il m&rsquo;a fallu, en fait, un certain temps pour comprendre la g\u00e9opolitique sous-jacente. C&rsquo;\u00e9tait exactement l&rsquo;\u00e9poque de Cheney et Wolfowitz et Rumsfeld et de ce qui est devenu le &lsquo;Project for a New American Century&rsquo;, c&rsquo;est-\u00e0-dire pour la poursuite de l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaine<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi en fut-il, la dynamique de l&rsquo;encerclement de la Russie \u00e9tait lanc\u00e9e, avec au terme l&rsquo;investissement de l&rsquo;Ukraine, jusqu&rsquo;\u00e0 notre &lsquo;<em>Ukrisis<\/em>&lsquo; dont tant de nos petits-marquis t\u00e9l\u00e9vis\u00e9s attribuent la paternit\u00e9 au monstrueux Poutine. Jusqu&rsquo;au bout, il nous en fait t\u00e9moin, Sachs aura essay\u00e9 d&#8217;emp\u00eacher l&rsquo;in\u00e9vitable&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La guerre en Ukraine aurait pu \u00eatre \u00e9vit\u00e9e et aurait d&ucirc; l&rsquo;\u00eatre par la diplomatie. Pendant des ann\u00e9es, le pr\u00e9sident russe Poutine a r\u00e9p\u00e9t\u00e9 que l&rsquo;OTAN ne devait pas s&rsquo;\u00e9tendre jusqu&rsquo;\u00e0 la mer Noire, ni jusqu&rsquo;\u00e0 l&rsquo;Ukraine, et encore moins jusqu&rsquo;\u00e0 la G\u00e9orgie, qui, si l&rsquo;on regarde la carte, se trouve directement sur le bord oriental de la mer Noire. La Russie n&rsquo;a cess\u00e9 de nous dire : \u00ab\u00a0Cela va nous encercler. Cela va mettre en p\u00e9ril notre s\u00e9curit\u00e9. Ayons recours \u00e0 la diplomatie.\u00a0\u00bb Les &Eacute;tats-Unis ont rejet\u00e9 toute diplomatie. J&rsquo;ai essay\u00e9 de contacter la Maison Blanche \u00e0 la fin de 2021, &ndash; en fait, j&rsquo;ai contact\u00e9 la Maison Blanche et j&rsquo;ai dit qu&rsquo;il y aurait une guerre \u00e0 moins que les &Eacute;tats-Unis n&rsquo;entament des discussions diplomatiques avec le pr\u00e9sident Poutine sur cette question de l&rsquo;\u00e9largissement de l&rsquo;OTAN. On m&rsquo;a r\u00e9pondu que les &Eacute;tats-Unis ne feraient jamais cela. C&rsquo;\u00e9tait hors de question. Ce n&rsquo;\u00e9tait pas sur la table. Maintenant nous avons une guerre qui est extraordinairement dangereuse<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;interview de Sachs a \u00e9t\u00e9 r\u00e9alis\u00e9 le 30 ao&ucirc;t par le r\u00e9seau (radio\/vid\u00e9os) &lsquo;<em>Democracy Now !&rsquo;<\/em>, un des m\u00e9dias alternatifs de gauche les plus anciens et les plus fameux aux USA. Les deux intervieweurs (signal\u00e9s entre parenth\u00e8ses) sont Amy Goodman et Juan Gonzales. On trouve une vid\u00e9o et un <em>verbatim<\/em> de l&rsquo;interview <a href=\"https:\/\/www.democracynow.org\/2022\/8\/30\/wests_false_narrative_china_russia_ukraine\">sur le site du r\u00e9seau<\/a>, et une vid\u00e9o de l&rsquo;entretien <a href=\"https:\/\/www.youtube.com\/watch?v=wmOePNsNFw0\">sur YouTube<\/a>.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Interview de Jeffrey Sachs<\/h2>\n<\/p>\n<p><p><strong>&lsquo;<em>Democracy Now !<\/em>&lsquo; <\/strong><strong>(Amy Goodman)<\/strong> : Quelle est l&rsquo;histoire que les gens en Occident et dans le monde entier devraient savoir pour comprendre ce qui se passe actuellement avec ces conflits, avec la Russie, avec la Russie et l&rsquo;Ukraine, et avec la Chine ?<\/p>\n<\/p>\n<p><p><strong>JEFFREY SACHS <\/strong>: Le point principal, Amy, est que nous n&rsquo;utilisons pas la diplomatie, nous utilisons des armes. Cette vente annonc\u00e9e \u00e0 Ta\u00efwan, dont vous avez parl\u00e9 ce matin, en est un autre exemple. Cela ne rend pas Taiwan plus s&ucirc;r. Cela ne rend pas le monde plus s&ucirc;r. Cela ne rend certainement pas les &Eacute;tats-Unis plus s&ucirc;rs.<\/p>\n<\/p>\n<p><p>Cela remonte \u00e0 loin. Je pense qu&rsquo;il est utile de commencer il y a 30 ans. L&rsquo;Union sovi\u00e9tique s&rsquo;\u00e9tait effondr\u00e9e et certains dirigeants am\u00e9ricains se mirent en t\u00eate qu&rsquo;il y avait d\u00e9sormais ce qu&rsquo;ils appelaient le monde unipolaire, que les &Eacute;tats-Unis \u00e9taient la seule superpuissance et que nous pouvions r\u00e9gler et diriger le spectacle. Les r\u00e9sultats ont \u00e9t\u00e9 d\u00e9sastreux. Nous avons maintenant trois d\u00e9cennies de militarisation de la politique \u00e9trang\u00e8re am\u00e9ricaine. Une nouvelle base de donn\u00e9es tenue par Tufts vient de montrer qu&rsquo;il y a eu plus de 100 interventions militaires des &Eacute;tats-Unis depuis 1991. C&rsquo;est vraiment incroyable.<\/p>\n<\/p>\n<p><p>Et j&rsquo;ai pu constater, au cours de ma propre exp\u00e9rience des 30 derni\u00e8res ann\u00e9es de travail intensif en Russie, en Europe centrale, en Chine et dans d&rsquo;autres parties du monde, que l&rsquo;approche am\u00e9ricaine est une approche militaire d&rsquo;abord, et souvent uniquement militaire. Nous armons qui nous voulons. Nous appelons \u00e0 l&rsquo;\u00e9largissement de l&rsquo;OTAN, peu importe ce que les autres pays disent qui pourrait nuire \u00e0 leurs int\u00e9r\u00eats de s\u00e9curit\u00e9. Nous faisons fi des int\u00e9r\u00eats de s\u00e9curit\u00e9 des autres. Et lorsqu&rsquo;ils se plaignent, nous envoyons davantage d&rsquo;armements \u00e0 nos alli\u00e9s dans cette r\u00e9gion. Nous partons en guerre quand nous voulons, o&ugrave; nous voulons, qu&rsquo;il s&rsquo;agisse de l&rsquo;Afghanistan ou de l&rsquo;Irak ou de la guerre secr\u00e8te contre Assad en Syrie, qui n&rsquo;est toujours pas bien comprise par le peuple am\u00e9ricain, ou de la guerre en Libye. Et nous disons : \u00ab\u00a0Nous sommes pacifistes. Qu&rsquo;est-ce qui ne va pas avec la Russie et la Chine ? Ils sont si belliqueux. Ils veulent miner le monde.\u00a0\u00bb Et nous nous retrouvons dans de terribles confrontations.<\/p>\n<\/p>\n<p><p>La guerre en Ukraine, &ndash; pour terminer notre introduction, &ndash; aurait pu \u00eatre \u00e9vit\u00e9e et aurait d&ucirc; l&rsquo;\u00eatre par la diplomatie. Pendant des ann\u00e9es, le pr\u00e9sident russe Poutine a r\u00e9p\u00e9t\u00e9 que l&rsquo;OTAN ne devait pas s&rsquo;\u00e9tendre jusqu&rsquo;\u00e0 la mer Noire, ni jusqu&rsquo;\u00e0 l&rsquo;Ukraine, et encore moins jusqu&rsquo;\u00e0 la G\u00e9orgie, qui, si l&rsquo;on regarde la carte, se trouve directement sur le bord oriental de la mer Noire. La Russie n&rsquo;a cess\u00e9 de nous dire : \u00ab\u00a0Cela va nous encercler. Cela va mettre en p\u00e9ril notre s\u00e9curit\u00e9. Ayons recours \u00e0 la diplomatie.\u00a0\u00bb Les &Eacute;tats-Unis ont rejet\u00e9 toute diplomatie. J&rsquo;ai essay\u00e9 de contacter la Maison Blanche \u00e0 la fin de 2021, &ndash; en fait, j&rsquo;ai contact\u00e9 la Maison Blanche et j&rsquo;ai dit qu&rsquo;il y aurait une guerre \u00e0 moins que les &Eacute;tats-Unis n&rsquo;entament des discussions diplomatiques avec le pr\u00e9sident Poutine sur cette question de l&rsquo;\u00e9largissement de l&rsquo;OTAN. On m&rsquo;a r\u00e9pondu que les &Eacute;tats-Unis ne feraient jamais cela. C&rsquo;\u00e9tait hors de question. Et ce n&rsquo;\u00e9tait pas sur la table. Maintenant nous avons une guerre qui est extraordinairement dangereuse.<\/p>\n<\/p>\n<p><p>Et nous adoptons exactement les m\u00eames tactiques en Asie de l&rsquo;Est qui ont conduit \u00e0 la guerre en Ukraine. Nous organisons des alliances, nous construisons des armes, nous critiquons la Chine, nous envoyons la pr\u00e9sidente de la Chambre Pelosi \u00e0 Taiwan, quand le gouvernement chinois nous dit : \u00ab\u00a0S&rsquo;il vous pla&icirc;t, abaissez la temp\u00e9rature, abaissez les tensions\u00a0\u00bb. Nous r\u00e9pondons \u00ab\u00a0Non, nous faisons ce que nous voulons\u00a0\u00bb, et nous envoyons maintenant plus d&rsquo;armes. C&rsquo;est une recette pour une autre guerre. Et \u00e0 mon avis, c&rsquo;est terrifiant.<\/p>\n<\/p>\n<p><p>Nous sommes au 60e anniversaire de la crise des missiles cubains, que j&rsquo;ai \u00e9tudi\u00e9e toute ma vie et sur laquelle j&rsquo;ai \u00e9crit, j&rsquo;ai \u00e9crit un livre sur les cons\u00e9quences. Nous nous dirigeons vers le pr\u00e9cipice, et nous sommes remplis d&rsquo;enthousiasme en le faisant. Et toute l&rsquo;approche de la politique \u00e9trang\u00e8re am\u00e9ricaine est incroyablement dangereuse et malavis\u00e9e. Et c&rsquo;est bipartisan.<\/p>\n<\/p>\n<p><p><strong>&lsquo;<em>Democracy Now !<\/em>&lsquo; (Juan Gonzales)<\/strong>: Jeffrey Sachs, je voulais vous demander&#8230; L&rsquo;une des choses que vous avez mentionn\u00e9es dans un <a href=\"https:\/\/www.commondreams.org\/views\/2022\/08\/23\/wests-dangerously-simple-minded-narrative-about-russia-and-china\">article r\u00e9cent<\/a> publi\u00e9 dans Consortium News est cette insistance des &Eacute;tats-Unis, entra&icirc;nant l&rsquo;Europe dans leur sillage, \u00e0 maintenir leur h\u00e9g\u00e9monie dans le monde entier \u00e0 un moment o&ugrave; la puissance \u00e9conomique de l&rsquo;Occident d\u00e9cline. Vous mentionnez, par exemple, que les BRICS, &ndash; Br\u00e9sil, Russie, Inde, Chine et Afrique du Sud, &ndash; repr\u00e9sentent plus de 40 % de la population mondiale et ont un PIB sup\u00e9rieur \u00e0 celui des nations du G7, et pourtant leurs int\u00e9r\u00eats et leurs pr\u00e9occupations sont pratiquement ignor\u00e9s ou, dans le cas, \u00e9videmment, de la Russie et de la Chine, pr\u00e9sent\u00e9s au peuple am\u00e9ricain comme les agresseurs, les autoritaires, ceux qui cr\u00e9ent des troubles dans le monde.<\/p>\n<\/p>\n<p><p><strong>JEFFREY SACHS<\/strong>: Ce que vous voulez dire, c&rsquo;est que&#8230;<\/p>\n<\/p>\n<p><p><strong>&lsquo;<em>Democracy Now !<\/em>&lsquo; (Juan Gonzales)<\/strong>: Je me demandais si vous pouviez d\u00e9velopper ce point.<\/p>\n<\/p>\n<p><p><strong>JEFFREY SACHS <\/strong>: Oui, absolument, et nous orienter vers cela est extr\u00eamement important. Le pouvoir disproportionn\u00e9 du monde occidental, et surtout du monde anglo-saxon, qui a commenc\u00e9 avec l&rsquo;Empire britannique, et maintenant les &Eacute;tats-Unis, est vieux d&rsquo;environ 250 ans, donc une courte p\u00e9riode dans l&rsquo;histoire du monde. Il se trouve que, pour de nombreuses raisons tr\u00e8s int\u00e9ressantes, la r\u00e9volution industrielle est arriv\u00e9e en Angleterre en premier. Le moteur \u00e0 vapeur a \u00e9t\u00e9 invent\u00e9 l\u00e0-bas. C&rsquo;est probablement l&rsquo;invention la plus importante de l&rsquo;histoire moderne. La Grande-Bretagne est devenue militairement dominante au 19e si\u00e8cle, comme les &Eacute;tats-Unis l&rsquo;ont \u00e9t\u00e9 dans la seconde moiti\u00e9 du 20e si\u00e8cle. La Grande-Bretagne dirigeait le spectacle. La Grande-Bretagne avait l&#8217;empire sur lequel le soleil ne se couchait jamais. Et l&rsquo;Occident, c&rsquo;est-\u00e0-dire les &Eacute;tats-Unis et l&rsquo;Europe occidentale, c&rsquo;est-\u00e0-dire maintenant les &Eacute;tats-Unis et l&rsquo;Union europ\u00e9enne, le Royaume-Uni, le Canada, le Japon, &ndash; en d&rsquo;autres termes, le G7, avec l&rsquo;Union europ\u00e9enne &ndash; ne repr\u00e9sente qu&rsquo;une petite partie de la population mondiale, peut-\u00eatre aujourd&rsquo;hui environ 10 %, un peu plus, peut-\u00eatre 12,5 % si vous ajoutez le Japon \u00e0 l&rsquo;Europe occidentale et aux &Eacute;tats-Unis. Et c&rsquo;\u00e9tait comme \u00e7a pendant 200 ans, dans cet \u00e2ge industriel.<\/p>\n<\/p>\n<p><p>Mais les temps ont chang\u00e9. Et vraiment, depuis les ann\u00e9es 1950, le reste du monde, lorsqu&rsquo;il a obtenu son ind\u00e9pendance de l&rsquo;imp\u00e9rialisme europ\u00e9en, a commenc\u00e9 \u00e0 \u00e9duquer ses populations, a commenc\u00e9 \u00e0 adopter et adapter et innover les technologies. Et voil\u00e0 qu&rsquo;une petite partie du monde ne dirige pas vraiment le monde ou n&rsquo;a pas le monopole de la sagesse, du savoir, de la science ou de la technologie. Et c&rsquo;est merveilleux. La connaissance et la possibilit\u00e9 de vivre d\u00e9cemment se r\u00e9pandent dans le monde entier.<\/p>\n<\/p>\n<p><p>Aux &Eacute;tats-Unis, il y a un ressentiment devant cela, un profond ressentiment. Je pense qu&rsquo;il y a aussi une \u00e9norme ignorance historique, car je pense que beaucoup de dirigeants am\u00e9ricains n&rsquo;ont aucune id\u00e9e de l&rsquo;histoire moderne. Ils n&rsquo;appr\u00e9cient pas la mont\u00e9e en puissance de la Chine. C&rsquo;est un affront aux &Eacute;tats-Unis. Comment la Chine ose-t-elle se d\u00e9velopper ? C&rsquo;est notre monde ! C&rsquo;est notre si\u00e8cle ! Et donc, \u00e0 partir de 2014 \u00e0  peu pr\u00e8s, j&rsquo;ai vu, \u00e9tape par \u00e9tape, &ndash; je l&rsquo;ai observ\u00e9 avec minutie, parce que c&rsquo;est mon activit\u00e9 quotidienne, &ndash; comment les &Eacute;tats-Unis ont transmut\u00e9 la Chine, et d&rsquo;un pays qui se remettait d&rsquo;un si\u00e8cle et demi de grandes difficult\u00e9s ils ont fait un ennemi. Et nous avons consciemment, dans le cadre de la politique \u00e9trang\u00e8re am\u00e9ricaine, commenc\u00e9 \u00e0 dire : \u00ab\u00a0Nous devons contenir la Chine. L&rsquo;essor de la Chine n&rsquo;est plus dans notre int\u00e9r\u00eat\u00a0\u00bb, comme si les &Eacute;tats-Unis avaient le pouvoir l\u00e9gitime de d\u00e9terminer si la Chine doit \u00eatre prosp\u00e8re ou non. Les Chinois ne sont pas na\u00effs ; en fait, ils sont extraordinairement sophistiqu\u00e9s. Ils ont observ\u00e9 tout cela exactement de la m\u00eame mani\u00e8re que moi. Je connais les auteurs des textes am\u00e9ricains. Ce sont mes coll\u00e8gues, \u00e0 Harvard ou ailleurs. J&rsquo;ai \u00e9t\u00e9 choqu\u00e9 lorsque ce genre d&rsquo;id\u00e9e d&rsquo;endiguement a commenc\u00e9 \u00e0 \u00eatre appliqu\u00e9e.<\/p>\n<\/p>\n<p><p>Mais le point fondamental est que l&rsquo;Occident a dirig\u00e9 le monde pendant une br\u00e8ve p\u00e9riode, 250 ans, mais qu&rsquo;il a le sentiment que \u00ab\u00a0C&rsquo;est notre droit. C&rsquo;est un monde occidental. Nous sommes le G7. Nous avons le droit de d\u00e9terminer qui \u00e9crit les r\u00e8gles du jeu\u00a0\u00bb. En effet, Obama, vous savez un type assez bon dans le spectre de ce que nous avons en politique \u00e9trang\u00e8re, Obama a dit : \u00ab\u00a0&Eacute;crivons les r\u00e8gles du commerce pour l&rsquo;Asie, ne laissons pas la Chine \u00e9crire ces r\u00e8gles. Les &Eacute;tats-Unis \u00e9criront les r\u00e8gles\u00a0\u00bb. C&rsquo;est une fa\u00e7on incroyablement na\u00efve, dangereuse et d\u00e9pass\u00e9e de comprendre le monde. Nous, les &Eacute;tats-Unis, repr\u00e9sentons 4,2 % de la population mondiale. Nous ne dirigeons pas le monde. Nous ne sommes pas les leaders du monde. Nous sommes un pays de 4,2 % de la population dans un monde vaste et diversifi\u00e9, et nous devrions apprendre \u00e0 nous entendre, \u00e0 jouer dans le bac \u00e0 sable de mani\u00e8re pacifique, sans exiger d&rsquo;avoir tous les jouets du bac \u00e0 sable. Nous n&rsquo;avons pas encore d\u00e9pass\u00e9 ce stade de r\u00e9flexion. Et malheureusement, c&rsquo;est le cas des deux partis politiques. C&rsquo;est ce qui pousse la <em>Speaker<\/em> Pelosi \u00e0 se rendre \u00e0 Ta\u00efwan au milieu de tout cela, comme si elle devait vraiment y aller pour attiser les tensions. C&rsquo;est l&rsquo;\u00e9tat d&rsquo;esprit selon lequel les &Eacute;tats-Unis sont aux commandes.<\/p>\n<\/p>\n<p><p><strong>&lsquo;<em>Democracy Now !<\/em>&lsquo; (Juan Gonzales)<\/strong> : Je voulais revenir un peu en arri\u00e8re, dans les ann\u00e9es 90. Vous vous souvenez, j&rsquo;en suis s&ucirc;r, de l&rsquo;\u00e9norme effondrement financier qui s&rsquo;est produit au Mexique dans les ann\u00e9es 1990, lorsque l&rsquo;administration Clinton a autoris\u00e9 un renflouement de 50 milliards de dollars pour le Mexique, qui \u00e9tait en fait destin\u00e9 aux investisseurs de Wall Street. &Agrave; l&rsquo;\u00e9poque, vous conseilliez le gouvernement russe post-sovi\u00e9tique, qui avait \u00e9galement des probl\u00e8mes financiers, mais qui n&rsquo;avait pas pu obtenir d&rsquo;aide occidentale significative, m\u00eame du Fonds mon\u00e9taire international. Et vous avez critiqu\u00e9 cette situation \u00e0 l&rsquo;\u00e9poque. Je me demande si vous pouvez parler des diff\u00e9rences entre la r\u00e9ponse des &Eacute;tats-Unis \u00e0 la crise mexicaine et la r\u00e9ponse \u00e0 la crise financi\u00e8re russe, et quelles ont \u00e9t\u00e9 les racines de ces diff\u00e9rences dans la situation actuelle de la Russie.<\/p>\n<\/p>\n<p><p><strong>JEFFREY SACHS<\/strong> : Absolument. Et j&rsquo;ai eu une exp\u00e9rience contr\u00f4l\u00e9e, car j&rsquo;ai \u00e9t\u00e9 conseiller \u00e9conomique \u00e0 la fois pour la Pologne et pour l&rsquo;Union sovi\u00e9tique au cours de la derni\u00e8re ann\u00e9e du pr\u00e9sident Gorbatchev et pour le pr\u00e9sident Eltsine au cours des deux premi\u00e8res ann\u00e9es de l&rsquo;ind\u00e9pendance de la Russie, en 1992 et 1993. Mon travail consistait \u00e0 aider la Russie \u00e0 trouver un moyen de faire face, comme vous l&rsquo;avez d\u00e9crit, \u00e0 une crise financi\u00e8re massive. Et ma recommandation de base en Pologne, puis en Union sovi\u00e9tique et en Russie, \u00e9tait la suivante : pour \u00e9viter une crise soci\u00e9tale et une crise g\u00e9opolitique, le monde occidental riche devrait aider \u00e0 juguler cette crise financi\u00e8re extraordinaire qui se produisait avec l&rsquo;effondrement de l&rsquo;ancienne Union sovi\u00e9tique.<\/p>\n<\/p>\n<p><p>Eh bien, il est int\u00e9ressant de noter que, dans le cas de la Pologne, j&rsquo;ai fait une s\u00e9rie de recommandations tr\u00e8s sp\u00e9cifiques, et elles ont toutes \u00e9t\u00e9 accept\u00e9es par le gouvernement am\u00e9ricain, &ndash; cr\u00e9er un fonds de stabilisation, annuler une partie des dettes de la Pologne, permettre de nombreuses man&oelig;uvres financi\u00e8res pour sortir la Pologne de la difficult\u00e9. Et, vous savez, je me suis frott\u00e9 les mains de satisfaction : \u00ab\u00a0Oh, regardez \u00e7a ! Je fais une recommandation, et l&rsquo;une d&rsquo;entre elles, pour un milliard de dollars, un fonds de stabilisation, est accept\u00e9e en huit heures par la Maison Blanche\u00a0\u00bb. Donc, j&rsquo;ai pens\u00e9, \u00ab\u00a0la formule marche bien\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Puis vint l&rsquo;appel analogue au nom, d&rsquo;abord, de Gorbatchev, dans les derniers jours, puis du pr\u00e9sident Eltsine. Tout ce que j&rsquo;ai recommand\u00e9, qui reposait sur la m\u00eame base de dynamique \u00e9conomique, a \u00e9t\u00e9 rejet\u00e9 cat\u00e9goriquement par la Maison Blanche. Je ne l&rsquo;ai pas compris, je dois vous le dire, \u00e0 l&rsquo;\u00e9poque. J&rsquo;ai dit : \u00ab\u00a0Mais \u00e7a a march\u00e9 en Pologne\u00a0\u00bb. Et, en fait, comme toute r\u00e9ponse j&rsquo;avais un regard vide. En fait, un secr\u00e9taire d&rsquo;&Eacute;tat par int\u00e9rim m&rsquo;a dit en 1992 : \u00ab\u00a0Professeur Sachs, peu importe que je sois d&rsquo;accord ou non avec vous. Cela ne se fera pas, c&rsquo;est tout\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Et il m&rsquo;a fallu, en fait, un certain temps pour comprendre la g\u00e9opolitique sous-jacente. C&rsquo;\u00e9tait exactement l&rsquo;\u00e9poque de Cheney et Wolfowitz et Rumsfeld et de ce qui est devenu le &lsquo;<em>Project for a New American Century<\/em>&lsquo;, c&rsquo;est-\u00e0-dire pour la poursuite de l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaine. Je ne l&rsquo;ai pas vu \u00e0 ce moment-l\u00e0, parce que je r\u00e9fl\u00e9chissais, en tant qu&rsquo;\u00e9conomiste, \u00e0 la mani\u00e8re d&rsquo;aider \u00e0 surmonter une crise financi\u00e8re. Mais la politique unipolaire prenait forme, et elle \u00e9tait d\u00e9vastatrice. Bien s&ucirc;r, elle a laiss\u00e9 la Russie dans une crise financi\u00e8re massive qui a conduit \u00e0 beaucoup d&rsquo;instabilit\u00e9 qui a eu ses propres implications pour les ann\u00e9es \u00e0 venir.<\/p>\n<\/p>\n<p><p>Mais plus encore, ce que ces gens planifiaient, d\u00e8s le d\u00e9but, malgr\u00e9 les promesses explicites faites \u00e0 Gorbatchev et Eltsine, c&rsquo;\u00e9tait l&rsquo;expansion de l&rsquo;OTAN. Et Clinton a commenc\u00e9 l&rsquo;expansion de l&rsquo;OTAN avec les trois pays d&rsquo;Europe centrale, &ndash; la Pologne, la Hongrie et la R\u00e9publique tch\u00e8que&#8230; Puis George W. Bush Jr. a ajout\u00e9 sept pays, &ndash; la Bulgarie, la Roumanie, la Slovaquie, la Slov\u00e9nie et les trois &Eacute;tats baltes, &ndash; tout \u00e7a, juste face \u00e0 la Russie. Et puis, en 2008, ce fut le coup de gr\u00e2ce, c&rsquo;est-\u00e0-dire l&rsquo;insistance des &Eacute;tats-Unis, malgr\u00e9 l&rsquo;opposition priv\u00e9e des dirigeants europ\u00e9ens, &ndash; et les dirigeants europ\u00e9ens m&rsquo;en ont parl\u00e9 en priv\u00e9 \u00e0 l&rsquo;\u00e9poque&#8230; Mais en 2008, Bush a d\u00e9clar\u00e9 que l&rsquo;OTAN s&rsquo;\u00e9tendrait \u00e0 l&rsquo;Ukraine et \u00e0 la G\u00e9orgie. Et l\u00e0 encore, si vous sortez une carte et que vous regardez la mer Noire, l&rsquo;objectif explicite \u00e9tait d&rsquo;encercler la Russie en mer Noire. D&rsquo;ailleurs, c&rsquo;est un vieux projet&#8230; C&rsquo;est le m\u00eame que celui de Palmerston, de 1853 \u00e0 1856, lors de la premi\u00e8re guerre de Crim\u00e9e : encercler la Russie en mer Noire, lui couper la possibilit\u00e9 d&rsquo;avoir une pr\u00e9sence militaire et de projeter une quelconque influence en M\u00e9diterran\u00e9e orientale. Brzezinski lui-m\u00eame a d\u00e9clar\u00e9 en 1997 que l&rsquo;Ukraine serait le pivot g\u00e9ographique de l&rsquo;Eurasie.<\/p>\n<\/p>\n<p><p>Donc, ce que ces n\u00e9oconservateurs faisaient au d\u00e9but des ann\u00e9es 1990, c&rsquo;\u00e9tait construire le monde unipolaire des &Eacute;tats-Unis. Et ils envisageaient d\u00e9j\u00e0 de nombreuses guerres afin d&rsquo;\u00e9liminer les anciens pays alli\u00e9s de l&rsquo;Union sovi\u00e9tique, &ndash; des guerres pour renverser Saddam, des guerres pour renverser Assad, des guerres pour renverser Kadhafi. Tout cela s&rsquo;est d\u00e9roul\u00e9 au cours des 20 ann\u00e9es suivantes. Elles ont \u00e9t\u00e9 un d\u00e9sastre complet, une d\u00e9b\u00e2cle pour ces pays, horrible pour les &Eacute;tats-Unis, des milliers de milliards de dollars gaspill\u00e9s. Mais c&rsquo;\u00e9tait un plan. Et ce plan n\u00e9oconservateur est \u00e0 son apog\u00e9e en ce moment sur deux fronts : en Ukraine et dans le d\u00e9troit de Taiwan. Et c&rsquo;est extraordinairement dangereux, ce que ces gens font \u00e0 la politique \u00e9trang\u00e8re am\u00e9ricaine, qui n&rsquo;est pas, vous savez, une politique de d\u00e9mocratie. C&rsquo;est la politique d&rsquo;un petit groupe qui a l&rsquo;id\u00e9e qu&rsquo;un monde unipolaire et l&rsquo;h\u00e9g\u00e9monie des Etats-Unis sont la voie \u00e0 suivre.<\/p>\n<\/p>\n<p><p><strong>&lsquo;<em>Democracy Now !<\/em>&lsquo; (Amy Goodman)<\/strong> : Jeffrey Sachs, nous n&rsquo;avons pas beaucoup de temps, mais puisque c&rsquo;\u00e9tait un sujet si important, &ndash; Naomi Klein vous a pris \u00e0 partie avec son livre &lsquo;<em>The Shock Doctrine<\/em>&lsquo;, en disant que vous recommandiez une th\u00e9rapie de choc. Pouvez-vous \u00e9tablir un lien entre ce qui s&rsquo;est pass\u00e9 lorsque l&rsquo;\u00e9conomie russe s&rsquo;est effondr\u00e9e et les conditions qui ont conduit \u00e0 l&rsquo;invasion de l&rsquo;Ukraine ? Je veux dire, comment la catastrophe \u00e9conomique qui a suivi l&rsquo;effondrement de l&rsquo;Union sovi\u00e9tique a conduit \u00e0 la mont\u00e9e de la classe oligarchique et, en fait, \u00e0 la pr\u00e9sidence de Vladimir Poutine ?<\/p>\n<\/p>\n<p><p><strong>JEFFREY SACHS<\/strong>: Oui, j&rsquo;ai essay\u00e9 pendant des ann\u00e9es d&rsquo;expliquer \u00e0 Naomi, que j&rsquo;admire beaucoup, que ce que je recommandais, c&rsquo;\u00e9tait d&rsquo;apporter une aide financi\u00e8re \u00e0 la Pologne, \u00e0 l&rsquo;Union sovi\u00e9tique ou \u00e0 la Russie. J&rsquo;\u00e9tais absolument horrifi\u00e9 par la tricherie, la corruption et les nombreux  passe-droits. Je l&rsquo;ai dit tr\u00e8s explicitement \u00e0 l&rsquo;\u00e9poque et j&rsquo;ai d\u00e9missionn\u00e9, \u00e0 la fois parce qu&rsquo;il \u00e9tait inutile d&rsquo;essayer d&rsquo;obtenir une aide occidentale et parce que je n&rsquo;aimais pas du tout ce qui se passait.<\/p>\n<\/p>\n<p><p>Et je dirais que l&rsquo;\u00e9chec d&rsquo;une approche ordonn\u00e9e, qui a \u00e9t\u00e9 r\u00e9alis\u00e9e en Pologne mais a \u00e9chou\u00e9 dans l&rsquo;ancienne Union sovi\u00e9tique parce qu&rsquo;il n&rsquo;y avait pas d&rsquo;engagement constructif de l&rsquo;Occident, a certainement jou\u00e9 un r\u00f4le dans l&rsquo;instabilit\u00e9 des ann\u00e9es 1990 et dans la mont\u00e9e de la classe des oligarques. En fait, j&rsquo;ai absolument expliqu\u00e9 aux &Eacute;tats-Unis, au FMI et \u00e0 la Banque mondiale en 1994 et 1995 ce qui se passait. Ils ne s&rsquo;en sont pas souci\u00e9s, parce qu&rsquo;ils ont pens\u00e9 : \u00ab\u00a0Oh, \u00e7a ira, C&rsquo;est bon pour Eltsine, peut-\u00eatre\u00a0\u00bb, toute cette tricherie dans le processus \u00ab\u00a0actions contre pr\u00eats\u00a0\u00bb. Cela dit, c&rsquo;\u00e9tait un&#8230;<\/p>\n<\/p>\n<p><p><strong>&lsquo;<em>Democracy Now !<\/em>&lsquo; (Amy Goodman)<\/strong> : Il nous reste moins d&rsquo;une minute.<\/p>\n<\/p>\n<p><p><strong>JEFFREY SACHS<\/strong>: OK. Cela dit, je pense que ce qu&rsquo;il est important d&rsquo;observer c&rsquo;est qu&rsquo;il n&rsquo;y a pas de d\u00e9terminisme lin\u00e9aire, m\u00eame entre des \u00e9v\u00e9nements comme ceux-l\u00e0, qui \u00e9taient d\u00e9stabilisants, tr\u00e8s malheureux et inutiles, et ce qui se passe maintenant, parce que lorsque le pr\u00e9sident Poutine est arriv\u00e9, il n&rsquo;\u00e9tait pas anti-europ\u00e9en, il n&rsquo;\u00e9tait pas anti-am\u00e9ricain. Ce qu&rsquo;il a vu, cependant, c&rsquo;est l&rsquo;incroyable arrogance des &Eacute;tats-Unis, l&rsquo;expansion de l&rsquo;OTAN, les guerres en Irak, la guerre secr\u00e8te en Syrie, la guerre en Libye, contre la r\u00e9solution de l&rsquo;ONU. Donc, nous avons cr\u00e9\u00e9 une si grande partie de ce \u00e0 quoi nous sommes confront\u00e9s en ce moment par notre propre ineptie et arrogance. Il n&rsquo;y a pas eu de d\u00e9termination lin\u00e9aire. C&rsquo;est l&rsquo;arrogance des &Eacute;tats-Unis, \u00e9tape par \u00e9tape, qui a contribu\u00e9 \u00e0 nous amener l\u00e0 o&ugrave; nous sommes aujourd&rsquo;hui.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lsquo;Ukrisis&lsquo; aux origines &bull; La guerre en Ukraine, que nous nommons &lsquo;Ukrisis&lsquo;, commence pour certains qui interpr\u00e8tent la chansonnette suivant la partition du Parti, le 24 f\u00e9vrier 2022. &bull; Pour d&rsquo;autres, tout de m\u00eame plus attentifs aux \u00e9v\u00e9nements en-cours, il faut remonter \u00e0 2014, avec le coup d&rsquo;&Eacute;tat de Kiev de f\u00e9vrier de cette ann\u00e9e-l\u00e0.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9767,2631,5774,13785,1104,5775,2827,2730,8478,21761,963],"class_list":["post-80331","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-choc","tag-de","tag-democracy","tag-jeffrey","tag-neocons","tag-now","tag-pologne","tag-russie","tag-sachs","tag-therapie","tag-urss"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80331"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80331\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}