{"id":80332,"date":"2022-09-12T15:16:34","date_gmt":"2022-09-12T15:16:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/09\/12\/simulacre-danniversaire-du-simulacre\/"},"modified":"2022-09-12T15:16:34","modified_gmt":"2022-09-12T15:16:34","slug":"simulacre-danniversaire-du-simulacre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/09\/12\/simulacre-danniversaire-du-simulacre\/","title":{"rendered":"Simulacre d&rsquo;anniversaire du simulacre"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Simulacre d&rsquo;anniversaire du simulacre<\/h2>\n<\/p>\n<p><p>12 septembre 2022 (15H15) &ndash; L&rsquo;anniversaire de l&rsquo;attaque du 11 septembre 2001 est pass\u00e9, hier, \u00ab\u00a0comme une lettre \u00e0 la poste\u00a0\u00bb, sans beaucoup de monde pour ouvrir le courrier. Jusqu&rsquo;alors, on faisait survivre une sorte de consensus national am\u00e9ricaniste (et occidentaliste en arri\u00e8re-plan de soutien), ou d&rsquo;obligation de concentration nationale avec une sorte de th\u00e8me suppos\u00e9 faire resurgir l&rsquo;unit\u00e9 nationale perdue, et qu&rsquo;on aurait une fois de plus intitul\u00e9 (le th\u00e8me) pour cette occasion bien difficile : \u00ab\u00a0Malheur &#038; Grandeur de l&rsquo;Am\u00e9rique\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>Ce th\u00e8me est peut-\u00eatre us\u00e9 jusqu&rsquo;\u00e0 la corde, mais on aurait pu esp\u00e9rer qu&rsquo;il susciterait \u00e0 nouveau des \u00e9lans magnifiques, \u00e0 d\u00e9faut de cette indiff\u00e9rence tout \u00e0 fait extraordinaire pour qui \u00e0 connu l&rsquo;atmosph\u00e8re fi\u00e9vreuse des semaines qui suivirent le 11-septembre, &ndash; le vrai, veux-je dire, <a href=\"https:\/\/thescotfree.com\/canada\/september-11-2001-21-years-later-renowned-architect-and-cia-whistleblower-contradict-the-official-story\/\">quelque arrangement<\/a> qu&rsquo;on ait pris avec l&rsquo;exactitude des faits, &ndash; mais je parle ici, finalement, du symbolisme et de l&#8217;emportement exalt\u00e9e de la psychologie, pas des complots et autres \u00ab\u00a0<em>false flags<\/em>\u00a0\u00bb d&rsquo;op\u00e9rette&#8230;<\/p>\n<p>\u00ab\u00a0Malheur\u00a0\u00bb parce que des volont\u00e9s mauvaises et d\u00e9testables port\u00e8rent un coup en tra&icirc;tre \u00e0 des USA n\u00e9cessairement innocents ;<\/p>\n<p>\u00ab\u00a0Grandeur\u00a0\u00bb parce que la Nation se rassembla en un bloc h\u00e9ro\u00efque qui exsuda, qu&rsquo;on s&rsquo;en souvienne encore, le &lsquo;<em>Patriot Act<\/em>&lsquo; et la &lsquo;Guerre contre la Terreur&rsquo; (ou GWOT, pour &lsquo;<em>Great War On Terror<\/em>&lsquo;).<\/p>\n<\/p>\n<p><p>Las ! Tout cela semble bien fini dans les affrontements int\u00e9rieurs pleins de haine qui d\u00e9chirent \u00e0 belles dents l&rsquo;unit\u00e9 nationale en Am\u00e9rique et dans le monde adjacent par cons\u00e9quent. D\u00e9sormais, apr\u00e8s l&rsquo;immense racl\u00e9e symbolique de la fuite de Kaboul, la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> s&rsquo;est hyst\u00e9riquement tourn\u00e9e, comme le 7<sup>\u00e8me<\/sup> de Cavalerie arrivant \u00e0 temps pour sauver le camp retranch\u00e9 d&rsquo;une psychologie aux abois, vers l&rsquo;anath\u00e8me antirusse et la vertu retrouv\u00e9e de l&rsquo;Occident humaniste, dans le chef de la cause de la d\u00e9fense de la vertueuse et d\u00e9mocratique Ukraine entretenue par les bons soins du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> depuis le coup d&rsquo;&Eacute;tat absolument d\u00e9mocratique de f\u00e9vrier 2014, \u00e0 Kiev, au Maidan de mon c&oelig;ur.<\/p>\n<\/p>\n<p><p>Non, hier 11-septembre, bien plus que du souvenir de ce jour terrible de 2001 il \u00e9tait question d&rsquo;une perc\u00e9e \u00ab\u00a0d\u00e9cisive\u00a0\u00bb des forces ukrainiennes dans la r\u00e9gion de Kharkov, sous l&rsquo;&oelig;il du Secr\u00e9taire d&rsquo;&Eacute;tat Blinken (USA) en visite \u00e0 Kiev, et de la ministre des affaires \u00e9trang\u00e8res <s>Brodbeck<\/s> Baerbock (Allemagne) qui lui succ\u00e9da le jour d&rsquo;apr\u00e8s, et entre deux coups de fil de Zelenski, notamment un \u00e0 Macron (France). D\u00e8s lors, il ne fit plus de doute que l&rsquo;offensive n&rsquo;\u00e9tait pas du chef de l&rsquo;Ukraine, mais bien de celui de l&rsquo;OTAN. Est-ce pour autant la promesse d&rsquo;une heure de gloire sur ce nouveau th\u00e9\u00e2tre des ambitions n\u00e9oconservatrices ? On verra et l&rsquo;on doutera encore plus, car plus les informations font leur chemin dans la jungle touffue de la d\u00e9sinformation et de la <em>narrative<\/em>, plus l&rsquo;on comprend qu&rsquo;il vaut mieux garder pour plus tard des qualificatifs comme \u00ab\u00a0d\u00e9cisif\u00a0\u00bb lorsqu&rsquo;il s&rsquo;agit de l&rsquo;ivresse am\u00e9ricaniste-occidentaliste.<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, eh bien, cela est dit : on ne f\u00eata gu\u00e8re le 11-septembre pour ce qu&rsquo;il fut depuis 2001, et le commentateur Scott Ritter ne fut pas <a href=\"https:\/\/www.rt.com\/news\/562511-911-attack-terrorist-us\/\">sans le remarquer<\/a>.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;ann\u00e9e derni\u00e8re, les &Eacute;tats-Unis et le monde entier ont c\u00e9l\u00e9br\u00e9 le 20e anniversaire des attentats du 11 septembre. Ce qui a rendu cette date<\/em><em> plus importante que le simple passage du temps, c&rsquo;est qu&rsquo;elle \u00e9tait pertinente, &ndash; l&rsquo;anniversaire-2021 de l&rsquo;\u00e9v\u00e9nement marquant l&rsquo;entr\u00e9e de l&rsquo;Am\u00e9rique dans ce qui allait devenir la \u00ab\u00a0guerre mondiale contre le terrorisme\u00a0\u00bb s&rsquo;est produit moins d&rsquo;un mois apr\u00e8s la retraite ignominieuse de l&rsquo;Am\u00e9rique d&rsquo;Afghanistan. L&rsquo;\u00e9vacuation de Kaboul en ao&ucirc;t 2021 a \u00e9t\u00e9 le dernier acte d&rsquo;un drame qui a dur\u00e9 deux d\u00e9cennies et qui a vu la vision d&rsquo;un \u00ab\u00a0New American Century\u00a0\u00bb d\u00e9velopp\u00e9e par une \u00e9lite n\u00e9oconservatrice am\u00e9ricaine, qui cherchait \u00e0 exploiter l&rsquo;horreur du 11 septembre en en faisant un catalyseur de la domination mondiale, se dissoudre sur le roc de la r\u00e9alit\u00e9 g\u00e9opolitique, et finalement s&rsquo;envoler comme du sable dans une temp\u00eate que cette \u00e9lite avait elle-m\u00eame provoqu\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;Am\u00e9rique qui a \u00e9merg\u00e9 du d\u00e9sastre politique de 20 ans qu&rsquo;a \u00e9t\u00e9 la \u00ab\u00a0guerre contre le terrorisme\u00a0\u00bb (compos\u00e9e de plusieurs conflits distincts, dont l&rsquo;Afghanistan et, peut-\u00eatre surtout, l&rsquo;Irak) a \u00e9t\u00e9 ch\u00e2ti\u00e9e et humili\u00e9e, mais nullement vaincue ni rendue plus humble. Il existe une dichotomie entre la r\u00e9alit\u00e9 g\u00e9opolitique dans laquelle les &Eacute;tats-Unis se sont retrouv\u00e9s apr\u00e8s 20 ans de n\u00e9gligence mondiale, alors qu&rsquo;ils gaspillaient le sang, le tr\u00e9sor et la r\u00e9putation de la nation dans les d\u00e9serts et les montagnes du Moyen-Orient, et l&rsquo;arrogance narcissique d&rsquo;une \u00e9lite dirigeante am\u00e9ricaine incapable et\/ou non d\u00e9sireuse de reconna&icirc;tre les dommages qu&rsquo;elle a caus\u00e9s au projet am\u00e9ricain originel, et donc d&rsquo;annuler son utilit\u00e9 collective qu&rsquo;elle aurait pu retrouver dans l&rsquo;\u00e9laboration de strat\u00e9gies diplomatiques, \u00e9conomiques et de s\u00e9curit\u00e9 appropri\u00e9es pour le redressement<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;occasion, observe donc Ritter, aurait \u00e9t\u00e9 bonne pour que l&rsquo;Am\u00e9rique songe\u00e2t \u00e0 se retourner sur cette p\u00e9riode extraordinaire et extravagante d&rsquo;une puissance d\u00e9cha&icirc;n\u00e9e allant de catastrophe en catastrophe. Elle aurait trouv\u00e9 mati\u00e8re \u00e0 grave r\u00e9flexion sur ce chemin parcouru, et sur l&rsquo;effet obtenu, aussi bien et particuli\u00e8rement \u00e0 l&rsquo;int\u00e9rieur d&rsquo;elle-m\u00eame.. Je veux dire \u00e0 l&rsquo;int\u00e9rieur de cette immense puissance fig\u00e9e dans un affrontement de <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2022-le-tournant-de-la-haine\">haines incroyables<\/a> dont nul ne peut plus croire qu&rsquo;elles puissent jamais s&rsquo;apaiser dans l&rsquo;esprit d&rsquo;une concorde retrouv\u00e9e tant bien que mal, dont on se demande m\u00eame si vraiment elle exist\u00e2t jamais, dont on croirait presque qu&rsquo;elle fut la matrice invisible et diabolique de ce mirage de la modernit\u00e9 qu&rsquo;on nomma &lsquo;<em>American Dream<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>De tout cela, il ne fut pas question hier, 11 septembre 2022, puisqu&rsquo;on se trouve d\u00e9sormais emport\u00e9 dans des chim\u00e8res extraordinaires, qui semblent d\u00e9passer en folie les exploits pr\u00e9c\u00e9dents, avec l&rsquo;id\u00e9e d&rsquo;un affrontement direct avec la Russie. C&rsquo;est une autre et pi\u00e8tre fa\u00e7on d&rsquo;\u00e9viter de s&rsquo;observer soi-m\u00eame, dans l&rsquo;\u00e9tat o&ugrave; l&rsquo;on se trouve apr\u00e8s une telle p\u00e9riode de troubles sem\u00e9s \u00e0 l&rsquo;ext\u00e9rieur \u00e0 la poursuite d&rsquo;un chaos dont on attend qu&rsquo;enfin surgisse l&rsquo;ordre h\u00e9g\u00e9monique tant attendu comme r\u00e9compense supr\u00eame. Les commentateurs \u00ab\u00a0s\u00e9rieux\u00a0\u00bb et \u00ab\u00a0r\u00e9alistes\u00a0\u00bb font leur compte et nous disent qu&rsquo;une fois de plus l&rsquo;Am\u00e9rique l&#8217;emporte dans cette affaire &lsquo;<em>Ukrisis<\/em>&lsquo; et met l&rsquo;Europe ivre de soumission dans sa poche en l&rsquo;envoyant dans une crise dont elle, l&rsquo;Am\u00e9rique, tirera b\u00e9n\u00e9fice : calculs d&rsquo;\u00e9picier, tout cela !<\/p>\n<\/p>\n<p><p>Au contraire, nous sommes collectivement li\u00e9s les uns aux autres, dans le destin catastrophique de cette civilisation emport\u00e9e par l&rsquo;ivresse des drogues infernales. Passons outre les calculs d&rsquo;\u00e9picier pour en venir \u00e0 l&rsquo;essentiel : nous sommes pass\u00e9s d&rsquo;une chim\u00e8re l&rsquo;autre et de mal en pis, comme fascin\u00e9s par la perspective de l&rsquo;autodestruction qui ach\u00e8verait parfaitement cette mise en chaos universel&#8230; C&rsquo;est cela que Ritter nomme &laquo; <em>cette nouvelle r\u00e9alit\u00e9<\/em> &raquo;, non ?<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le 11 septembre de 20 ans plus 1 apr\u00e8s est le premier anniversaire de cette nouvelle r\u00e9alit\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Contrairement \u00e0 un anniversaire de mariage, o&ugrave; les mari\u00e9s sont conscients de la date initiale et des r\u00e9sultats ult\u00e9rieurs qui sont c\u00e9l\u00e9br\u00e9s, l&rsquo;incapacit\u00e9 de la collectivit\u00e9 am\u00e9ricaine, &ndash; le peuple, ses dirigeants et les m\u00e9dias grand public, &ndash; \u00e0 s&rsquo;engager dans une r\u00e9flexion factuelle et sans \u00e9motion sur la situation au moment du 20e anniversaire du 11 septembre, sur la fa\u00e7on dont ils en sont arriv\u00e9s l\u00e0 et sur la direction qu&rsquo;ils prennent, signifie qu&rsquo;ils ne parviennent pas \u00e0 saisir le fait qu&rsquo;ils marquent le premier anniversaire d&rsquo;une r\u00e9alit\u00e9 post-11 septembre, qu&rsquo;ils semblent largement ignorer.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Apr\u00e8s 20 ans d&rsquo;errance dans le d\u00e9sert g\u00e9opolitique du Moyen-Orient et de l&rsquo;Asie centrale, l&rsquo;Am\u00e9rique est apparue comme une nation beaucoup plus faible, &ndash; militairement, \u00e9conomiquement et diplomatiquement. Cet affaiblissement a \u00e9t\u00e9 aggrav\u00e9 par le fait que, tandis que l&rsquo;Am\u00e9rique \u00e9tait engag\u00e9e dans son acte d&rsquo;auto-immolation depuis deux d\u00e9cennies, le reste du monde ne faisait pas du sur-place, mais allait plut\u00f4t de l&rsquo;avant, construisant ses propres capacit\u00e9s qui, bien que n&rsquo;\u00e9tant pas n\u00e9cessairement con\u00e7ues pour affronter les &Eacute;tats-Unis, les mettaient dans une position bien plus avantageuse si le moment \u00e9tait venu de le faire<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Devant un tel paysage d\u00e9sol\u00e9, il ne reste plus \u00e0 Scott Ritter qu&rsquo;\u00e0 entonner le refrain fameux que tous les esprits loyaux r\u00e9p\u00e8tent sans autres sentiments que la tristesse d\u00e9sesp\u00e9r\u00e9e, le d\u00e9couragement \u00e9puisant, le fatalisme in\u00e9vitable devant cette machinerie impitoyable qui les emporte tous et nous emporte tous : \u00ab\u00a0Pleure, \u00f4 mon pays bien-aim\u00e9 \u00ab\u00a0&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le leadership am\u00e9ricain a toujours repos\u00e9 sur la pr\u00e9misse que le mod\u00e8le am\u00e9ricain de gouvernance d\u00e9mocratique contribuait \u00e0 produire la force sociale, \u00e9conomique et militaire sur laquelle les &Eacute;tats-Unis s&rsquo;appuyaient pour affronter les forces du mal dans le monde. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce mod\u00e8le n&rsquo;existe plus, en grande partie \u00e0 cause de la fa\u00e7on dont l&rsquo;Am\u00e9rique s&rsquo;est comport\u00e9e au cours des vingt premi\u00e8res ann\u00e9es qui ont suivi les attentats du 11 septembre.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Apr\u00e8s 20 ans et un an de plus, les &Eacute;tats-Unis sont confront\u00e9s \u00e0 la r\u00e9alit\u00e9 de ce qu&rsquo;ils ont provoqu\u00e9, en Ukraine, dans le Pacifique, au Moyen-Orient, en Afrique, en Asie&#8230; et chez eux. Semer le vent, dit la Bible, c&rsquo;est r\u00e9colter la temp\u00eate<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Alors, pour \u00e9viter d&rsquo;\u00eatre d\u00e9coiff\u00e9s, les &Eacute;tats-Unis, flanqu\u00e9s des domestiques europ\u00e9ens habituels, ont mis en place la strat\u00e9gie hollywoodienne de l&rsquo;excellence cr\u00e9ative, dite strat\u00e9gie-&lsquo;<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/M\u00e9tavers\">M\u00e9tavers<\/a><\/em>&lsquo;, sous l&rsquo;impulsion suggestive de l&rsquo;excellent jeune homme, gendre id\u00e9al, qui dirige l&rsquo;ancien &lsquo;<em>Facebook<\/em>&lsquo; relook\u00e9 en &lsquo;<em>M\u00e9ta<\/em>&lsquo; et habill\u00e9 d&rsquo;une <em>narrative <\/em>s\u00e9duisante. Il s&rsquo;agit de l&rsquo;aventure ukrainienne, sous le nom d\u00a0\u00bb<em>Ukrisis<\/em>&lsquo;, o&ugrave; le bloc-BAO s&rsquo;est engag\u00e9 pour le combat supr\u00eame, pr\u00eat \u00e0 lutter jusqu&rsquo;au bout, jusqu&rsquo;\u00e0 la victoire, jusqu&rsquo;au \u00ab\u00a0dernier des Mohicans\u00a0\u00bb. Jamais les ma&icirc;tres, eux-m\u00eames esclaves d&rsquo;une logique de la politiqueSyst\u00e8me \u00e0 laquelle ils ne comprennent strictement rien, ne se sont trouv\u00e9s si pr\u00e8s de leurs &lsquo;<em>proxies<\/em>&lsquo; jusqu&rsquo;\u00e0 presque se confondre avec eux, donc aussi pr\u00e8s de l&rsquo;ennemi proclam\u00e9 qu&rsquo;ils d\u00e9fient fort imprudemment, donc bien proches de l&rsquo;ab&icirc;me qu&rsquo;ils creusent en chantant.<\/p>\n<\/p>\n<p><p>&#8230; Alors (suite et fin), pour terminer, il reste \u00e0 \u00e9grener des d\u00e9clarations et des messages de ce genre, qui nous conduisent aux confins de notre &lsquo;<em>M\u00e9tavers<\/em>&lsquo;, dans les effets des ressources infinies de nos constructions transcendantales. Apr\u00e8s tout, ce tweet venu d&rsquo;on ne sait o&ugrave;, repris par Karpov sur sa cha&icirc;ne-&lsquo;<em>Telegram<\/em>&lsquo;, qui pourrait aussi bien avoir \u00e9t\u00e9 con\u00e7u par Karpov lui-m\u00eame, o&ugrave; l&rsquo;on dit ce que le ministre des affaires \u00e9trang\u00e8res de Lituanie a imagin\u00e9 comme initiative diplomatique audacieuse, pour mettre fin \u00e0 tout ce g\u00e2chis et qu&rsquo;enfin les gens s\u00e9rieux puissent prendre la parole :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Lithuanian Foreign Minister urged Putin to surrender unconditionnaly.<\/em> &raquo; (23:42 11 Sep 22)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et ainsi la messe fut-elle dite, oh vous braves enfants du Bon-Dieu&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Simulacre d&rsquo;anniversaire du simulacre 12 septembre 2022 (15H15) &ndash; L&rsquo;anniversaire de l&rsquo;attaque du 11 septembre 2001 est pass\u00e9, hier, \u00ab\u00a0comme une lettre \u00e0 la poste\u00a0\u00bb, sans beaucoup de monde pour ouvrir le courrier. Jusqu&rsquo;alors, on faisait survivre une sorte de consensus national am\u00e9ricaniste (et occidentaliste en arri\u00e8re-plan de soutien), ou d&rsquo;obligation de concentration nationale avec&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[16316,3612,5463,3613,2800,7147,13670],"class_list":["post-80332","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-11-septembre","tag-american","tag-anniversaire","tag-dream","tag-ritter","tag-scott","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80332"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80332\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}