{"id":80338,"date":"2022-09-16T16:33:44","date_gmt":"2022-09-16T16:33:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/09\/16\/croisee-des-destinees\/"},"modified":"2022-09-16T16:33:44","modified_gmt":"2022-09-16T16:33:44","slug":"croisee-des-destinees","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/09\/16\/croisee-des-destinees\/","title":{"rendered":"Crois\u00e9e des destin\u00e9es"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Crois\u00e9e des destin\u00e9es<\/h2>\n<\/p>\n<p><p>16 septembre 2022 (16H40) &ndash; Alors que les derniers contre-\u00e9chos des derniers \u00e9chos de la retentissante \u00ab\u00a0contre-offensive\u00a0\u00bb ukrotanienne dans la r\u00e9gion de Kharkov se sont dissip\u00e9s surgit (une nouvelle fois, mais ne boudons pas notre plaisir) une puissante rumeur annon\u00e7ant quasiment la fin de la Russie, assortie de la liquidation (assassinat, expulsion, etc.) de Poutine. \u00ab\u00a0Je n&rsquo;invente rien\u00a0\u00bb, puisque c&rsquo;est Larry Johnson lui-m\u00eame qui \u00e9crit dans ce sens, <a href=\"https:\/\/sonar21.com\/putin-and-his-army-on-the-ropes-again\/\">le 15 septembre<\/a>, puisque je ne fais que le plagier :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Poutine et son arm\u00e9e \u00e0 nouveau dans les cordes !<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Je n&rsquo;invente rien. Il y a une conviction croissante dans de nombreux cercles \u00e9minents aux &Eacute;tats-Unis et en Europe, qui croient et adoptent cet article de &lsquo;<a href=\"https:\/\/www.newsbreak.com\/news\/2745565199405\/the-army-putin-spent-2-decades-building-has-been-largely-destroyed-in-ukraine-and-russia-s-strategic-defeat-could-threaten-his-regime?noAds=1&#038;_f=app_share&#038;s=i3\">Business Insider<\/a>&lsquo; : \u00ab\u00a0L&rsquo;arm\u00e9e que Poutine a mis deux  d\u00e9cennies \u00e0 construire a \u00e9t\u00e9 largement d\u00e9truite en Ukraine, et la &lsquo;d\u00e9faite strat\u00e9gique&rsquo; de la Russie pourrait menacer son r\u00e9gime.\u00a0\u00bb &raquo;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce n&rsquo;est qu&rsquo;en lisant l&rsquo;article et en examinant les \u00ab\u00a0experts\u00a0\u00bb consult\u00e9s que l&rsquo;on se rend compte qu&rsquo;il s&rsquo;agit encore d&rsquo;une absurdit\u00e9 d\u00e9lirante sans la moindre preuve.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Suit une liste de consid\u00e9rations, de r\u00e9futations, de coups de plume rageurs devant telle et telle affirmation. Johnson a raison lorsqu&rsquo;il dit que ce qui vaut pour les USA vaut \u00e9galement pour les Europ\u00e9ens, bref tout <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> compris, bien rang\u00e9, sagement align\u00e9, disant \u00ab\u00a0hourra, hourra\u00a0\u00bb quand il le faut ; et comme, selon diverses enqu\u00eates (on reste dans le vague, n&rsquo;ayant pas moi-m\u00eame le chiffre pr\u00e9cis en t\u00eate mais l&rsquo;ordre de grandeur est l\u00e0), comme entre 30% et 50% des lecteurs courants se contentent de lire les titres\/sous-titres, il suffit de lire le titre de &lsquo;<em>Business Insider<\/em>&lsquo; pour savoir o&ugrave; en est l&rsquo;aventure russo-poutinienne&#8230; Au reste, le \u00ab\u00a0<a href=\"https:\/\/planetes360.fr\/ursula-von-der-leyen-son-discours-fou-%EF%BF%BC\/\">discours fou<\/a>\u00a0\u00bb de von der Leyen devant le Parlement Europ\u00e9en me conforte dans nos certitudes : &laquo; <em>L&rsquo;heure n&rsquo;est pas \u00e0 l&rsquo;apaisement !<\/em> &raquo;, &ndash; effectivement, alors que la Russie poutinienne est au bord de l&rsquo;effondrement&#8230; Nous irons bient\u00f4t remplir nous-m\u00eames nos bonbonnes de gaz dans les vaguelettes de la ligne-Moscova (\u00ab\u00a0Maginot\u00a0\u00bb en fran\u00e7ais).<\/p>\n<\/p>\n<p><p>Il ne me para&icirc;t pas n\u00e9cessaire, \u00e0 moi, d&rsquo;aller plus avant, ni dans la d\u00e9monstration, ni dans le sarcasme (quoi que&#8230;). Il y a d&rsquo;autres t\u00e2ches plus urgentes qui appellent l&rsquo;honn\u00eate homme ; l&rsquo;on sait d&rsquo;ailleurs que les cr\u00e9tins et les zombies restent, en g\u00e9n\u00e9ral et alternativement, des zombies et des cr\u00e9tins, et que l&rsquo;argument des autres leur est inaudible parce qu&rsquo;inversement superf\u00e9tatoire par rapport \u00e0 leurs certitudes. La sid\u00e9ration devant la <em>narrative <\/em>que les \u00e9litesSyst\u00e8me ont d\u00e9velopp\u00e9e est compl\u00e8te chez les \u00e9litesSyst\u00e8me, je dis bien : \u00ab\u00a0chez les \u00e9litesSyst\u00e8me\u00a0\u00bb. Que l&rsquo;on me comprenne bien : si la <em>narrative<\/em> est faite \u00e9videmment pour h\u00e9b\u00e9ter et interdire le &lsquo;<em>vulgum pecus<\/em>&lsquo; du genre courant (c&rsquo;est-\u00e0-dire vous, moi, le n\u00f4tre, le public en g\u00e9n\u00e9ral), pour l&rsquo;ensorceler litt\u00e9ralement, &ndash; elle ensorcelle et m\u00eame envo&ucirc;te beaucoup plus, vraiment beaucoup plus, ces \u00e9litesSyst\u00e8me elles-m\u00eames.<\/p>\n<\/p>\n<p><p>J&rsquo;ai une hypoth\u00e8se \u00e0 pr\u00e9senter, \u00e0 ce point, pour expliquer la relance de cet envo&ucirc;tement dans un tonnerre d&rsquo;impr\u00e9cations antirusses et anti-poutiniennes, avec la certitude de leur effondrement commun d&rsquo;ores et d\u00e9j\u00e0 en cours. Cette hypoth\u00e8se tient \u00e0 la pr\u00e9sence manifeste et quasi-magique qui nous est apparue, dans la \u00ab\u00a0contre-offensive\u00a0\u00bb de Kharkov, de troupes de pays de l&rsquo;OTAN grim\u00e9es en \u00ab\u00a0volontaires\u00a0\u00bb, eux-m\u00eames grim\u00e9s en soldats ukrainiens mais gardant leur accent du Bronx, leur chewing-gum de Wichita et \u00e9ventuellement leur peau sombre du rythme &lsquo;<em>Black Lives Matter<\/em>&lsquo;. L&rsquo;image a provoqu\u00e9 une ivresse et emport\u00e9 le morceau.<\/p>\n<\/p>\n<p><p>Vous comprenez, enfin ! Ce n&rsquo;est plus Zelenski soutenu par l&rsquo;OTAN qui se bat, c&rsquo;est l&rsquo;OTAN qui prend les choses en main, soul\u00e8ve Zelenski pour en faire un g\u00e9ant ukrotanien et conquiert au pas de charge des espaces vides et des villes d\u00e9sert\u00e9es ! C&rsquo;est alors comme une vol\u00e9e de moineaux qui s&rsquo;envolent, affol\u00e9s et russes les moineaux, et l&rsquo;effondrement poutinien ne fait plus de doute. Vous comprenez qu&rsquo;ils sont ivres de puissance, brandissant leur hubris comme si les dieux avaient couronn\u00e9 leurs augustes cranes bien pleins de la<em> corona triomphalis <\/em>du laurier des empereurs de Rome&#8230; Tout cela tourne dans leurs petites t\u00eates bourdonnantes !<\/p>\n<\/p>\n<p><p>C&rsquo;est ainsi que les \u00e9v\u00e9nements se bousculent en descriptions martiales sous la plume enfi\u00e9vr\u00e9e des commentateurs du s\u00e9rail. Il ne faut jamais oublier les choses importantes, vous autres&#8230; Il ne faudra donc jamais oublier ceci : ils ne nous ont pas zombifi\u00e9s en nous rendant d\u00e9pendant de leur <em>narrative <\/em>comme d&rsquo;une drogue ; ils se sont zombifi\u00e9s eux-m\u00eames et leur <em>narrative <\/em>est devenue leur &lsquo;<em>coke<\/em>&lsquo;<em>&#8230; <\/em>C&rsquo;est \u00e9videmment pour cette raison que la situation est particuli\u00e8rement dangereuse, parce qu&rsquo;il n&rsquo;y a rien de plus dangereux que de d\u00e9pendre pour le sort commun d&rsquo;une entit\u00e9 elle-m\u00eame d\u00e9pendante, sorte de zombie cam\u00e9, hallucin\u00e9, hoquetant et cahotant.<\/p>\n<\/p>\n<p><p>Dans cette fa\u00e7on de voir, je vais poursuivre et conclure en citant la conclusion <a href=\"https:\/\/alawata-rebellion.blogspot.com\/2022\/09\/ou-est-larmee-ukrainienne.html\">d&rsquo;un texte<\/a> de Ewan Castel, vieux combattant fran\u00e7ais (breton, ajoute-t-on) du Donbass. Je le dis clairement et nettement : je ne partage pas toutes ses positions, voire ses fougues et ses emportements. Dans le texte cit\u00e9 non plus, je ne partage pas toutes ses appr\u00e9ciations et ses pr\u00e9cisions. Je ne sais pas non plus quand et comment Poutine va dans sa r\u00e9sidence de Sotchi, s&rsquo;il y va, alors que Castel termine justement son texte sur cette circonstance. Je cite ce passage de conclusion parce qu&rsquo;il me semble s&rsquo;imposer comme un tr\u00e8s puissant symbole de l&rsquo;extraordinaire dangerosit\u00e9 de cette crise, en laissant sa part de calvaire et d&rsquo;h\u00e9ro\u00efsme \u00e0 celui que les zombies tra&icirc;nent dans la boue et dans leur folie parce que, ma foi, \u00e0 part la boue et la folie, ils n&rsquo;ont jamais rien rencontr\u00e9 qui vaille, dans tous les cas selon la feuille de route de leurs \u00ab\u00a0communicants\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le texte est titr\u00e9 &laquo; <em>O&ugrave; est l&rsquo;arm\u00e9e ukrainienne ?<\/em> &raquo;, et pour ma part &laquo; <em>La crois\u00e9e des destin\u00e9es<\/em> &raquo; me va aussi bien, sachant effectivement que, d&rsquo;une fa\u00e7on ou l&rsquo;autre, nous sommes dans le temps des \u00ab\u00a0graves d\u00e9cisions\u00a0\u00bb.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em>&laquo; <\/em><em>D&rsquo;aucuns pr\u00e9tendent que si le pr\u00e9sident russe Vladimir Poutine s&rsquo;est isol\u00e9 momentan\u00e9ment dans sa r\u00e9sidence de Sotchi sur les bords de la Mer Noire, c&rsquo;est parce qu&rsquo;il est en plein d\u00e9sarroi et m\u00eame, selon certains chacals des plateaux t\u00e9l\u00e9, menac\u00e9 dans son pouvoir apr\u00e8s la victoire ukrainienne pr\u00e8s de Kharkov. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Libre \u00e0 ces thurif\u00e9raires des fantasmes russophobes de croire encore au P\u00e8re No\u00ebl !<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Je pense pour ma part, si toutefois la venue de Vladimir Poutine \u00e0 Sotchi est li\u00e9e \u00e0 la situation tendue du front russo-ukrainien, que nous assistons ici de la part d&rsquo;un pr\u00e9sident assumant en conscience ses responsabilit\u00e9s, \u00e0 la n\u00e9cessaire &quot;solitude du chef&quot; au moment de prendre une d\u00e9cision grave. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Sachant que ce conflit est une guerre existentielle pour la Russie accul\u00e9e sur ses fronti\u00e8res, <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Sachant que l&rsquo;Ukraine r\u00e9siste \u00e0 la coercition initiale des &quot;op\u00e9rations sp\u00e9ciales&quot; russes,<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Sachant que la cobellig\u00e9rance technique de l&rsquo;OTAN est devenue une bellig\u00e9rance factuelle,<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Sachant que gr\u00e2ce \u00e0 l&rsquo;OTAN et pour elle; l&rsquo;Ukraine menace aujourd&rsquo;hui l&rsquo;int\u00e9grit\u00e9 de la Russie, <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le pr\u00e9sident Poutine, n&rsquo;a pas d&rsquo;autre choix que de relever le gant de l&rsquo;OTAN jet\u00e9 au visage de la Russie par le valet ukrainien du globalisme, et sous les applaudissements serviles des collabos capitalistes. Le chef du Kremlin, quel que soit son nom, porte sur ses \u00e9paules l&rsquo;avenir de la F\u00e9d\u00e9ration et le poids de l&rsquo;Histoire au cours de laquelle la Russie a \u00e9t\u00e9 pouss\u00e9e par les Occidentaux depuis 30 ans, malgr\u00e9 tous ses efforts diplomatiques, \u00e9conomiques et militaires vers un nouveau chaos mondial, dont il disait il y a quelques ann\u00e9es dans un avertissement qu&rsquo;il voulait dissuasif que \u00ab\u00a0personne n&rsquo;en sortirait vainqueur\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce qui est s&ucirc;r c&rsquo;est que la Russie ne peut pas capituler et dispara&icirc;tre, et se laisser happ\u00e9e par ce vampirisme mondialiste (on voit le r\u00e9sultat en Europe de l&rsquo;Ouest !). Et m\u00eame si le pouvoir en Russie est majoritairement soutenu par ses peuples, m\u00eame si la majorit\u00e9 des autres peuples (Asie, Afrique, Inde&#8230;) soutiennent Moscou dans cette r\u00e9sistance commune et juste contre un monde multipolaire, relever le d\u00e9fi et faire \u00e9voluer encore plus ce combat vital vers son paroxysme est un devoir qui doit peser sur l&rsquo;\u00e2me.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cette lutte existentielle de la Russie, qui est devenue aujourd&rsquo;hui un conflit sym\u00e9trique de haute intensit\u00e9 est encore pouss\u00e9e plus loin vers cette nouvelle guerre mondiale de plus en plus  in\u00e9vitable. Et il est naturel que l&rsquo;homme qui accepte cette destin\u00e9e, m\u00eame s&rsquo;il n&rsquo;a pas d&rsquo;autre choix, veuille \u00e9couter le silence des dieux et les murmures du vent et de la mer pour mieux assumer sa responsabilit\u00e9 politique et son devoir historique.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Au lieu de se gausser de la m\u00e9ditation de Vladimir Poutine \u00e0 la crois\u00e9e des destin\u00e9es, les vautours de guerre occidentaux devraient plut\u00f4t s&rsquo;en inqui\u00e9ter car la col\u00e8re de l&rsquo;ours russe est en train de se r\u00e9veiller pleinement devant cette folie de l&rsquo;OTAN qui veut nous entrainer tous une nouvelle fois, dans le paroxysme meurtrier de cette Trag\u00e9die humaine plurimill\u00e9naire.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Crois\u00e9e des destin\u00e9es 16 septembre 2022 (16H40) &ndash; Alors que les derniers contre-\u00e9chos des derniers \u00e9chos de la retentissante \u00ab\u00a0contre-offensive\u00a0\u00bb ukrotanienne dans la r\u00e9gion de Kharkov se sont dissip\u00e9s surgit (une nouvelle fois, mais ne boudons pas notre plaisir) une puissante rumeur annon\u00e7ant quasiment la fin de la Russie, assortie de la liquidation (assassinat, expulsion,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[18909,16919,21766,8022,4019,16942,13803,14550,4321,916,5456,13670,4164],"class_list":["post-80338","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-came","tag-decisions","tag-dependant","tag-der","tag-drogue","tag-graves","tag-kharkov","tag-layen","tag-narrative","tag-poutine","tag-sotchi","tag-ukrisis","tag-van"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80338"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80338\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}