{"id":80362,"date":"2022-10-07T17:24:42","date_gmt":"2022-10-07T17:24:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/10\/07\/on-a-trouve-le-saboteur-de-la-baltique\/"},"modified":"2022-10-07T17:24:42","modified_gmt":"2022-10-07T17:24:42","slug":"on-a-trouve-le-saboteur-de-la-baltique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/10\/07\/on-a-trouve-le-saboteur-de-la-baltique\/","title":{"rendered":"On a trouv\u00e9 le saboteur de la Baltique !"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">On a trouv\u00e9 le saboteur de la Baltique !<\/h2>\n<\/p>\n<p><p>7 septembre 2022 (17H30) &ndash; Exactement, on en vient \u00e0 croire que Tucker Carlson lui-m\u00eame, en direct sur FoxNews, avec un tuba \u00e9lectromagn\u00e9tique et des palmes acad\u00e9miques-hypersoniques, est all\u00e9 en personne et en combinaison qui rend invisible glisser les trois p\u00e9tards sous les deux gazoducs, les fr\u00e8res NordStream. Et il y \u00e9tait en mission poutinienne, vous pensez bien.<\/p>\n<\/p>\n<p><p>Il vous raconte tout cela, &ndash; vraie confession, la main dans le sac ! &ndash; dans un \u00e9tourdissant segment de quinze minutes o&ugrave; il d\u00e9crit les diverses attitudes, questions, r\u00e9ponses, d\u00e9n\u00e9gations, du monde de la politique audiovisuelle et de communication, confront\u00e9 \u00e0 l&rsquo;\u00e9vidence absolument \u00e9blouissante de la culpabilit\u00e9 de Vladimir Vladimirovitch dans cette entreprise de terrorisme international, dans les eaux sacr\u00e9es de la communaut\u00e9 atlantico-otanienne.<\/p>\n<\/p>\n<p><p>Qu&rsquo;on me pardonne, mais en \u00e9coutant Carlson, son incroyable abattage, sa fa\u00e7on inarr\u00eatable de ridiculiser ce monde empes\u00e9, emprisonn\u00e9, englu\u00e9 dans cette obligation sacr\u00e9e du mensonge, &ndash;  tout autre projet cessant, je me suis dit que le verbatim de la chose valait publication. On retrouve tout cela, <a href=\"https:\/\/www.youtube.com\/watch?v=E0Abayg3k_o\">la vid\u00e9o<\/a> de Carlson, le verbatim, les diverses interventions qu&rsquo;il cite, \u00e0 sa place, sur le site de FoxNews le <a href=\"https:\/\/www.foxnews.com\/opinion\/tucker-carlson-explanation-allowed-nord-stream-government-wants-you-believe\">5 octobre 2022<\/a>.<\/p>\n<\/p>\n<p><p>Ce qui est remarquable, et m&rsquo;a pouss\u00e9 \u00e0 reprendre ce verbatim, c&rsquo;est qu&rsquo;aussi bien par \u00e9crit qu&rsquo;\u00e0 l&rsquo;audition, Carlson nous fait ressentir l&rsquo;extraordinaire folie collective qui nous enveloppe tous, absolument tous !&#8230; \u00ab\u00a0Tous\u00a0\u00bb, je veux dire toutes nos \u00e9lites, tous nos communicants, tous nos \u00e9lus, toutes nos vedettes et autres &lsquo;<em>people<\/em>&lsquo;, toutes nos &lsquo;<em>bagatelles pour une narrative<\/em>&lsquo;, emport\u00e9s dans cette incroyable saga de la v\u00e9rit\u00e9-\u00e0-la-place-de-la-v\u00e9rit\u00e9, cette puissance formidable de l&rsquo;hyst\u00e9rie partag\u00e9e, de l&rsquo;hallucination v\u00e9cue comme un bien commun, de l&rsquo;\u00e9pisode maniaque surmont\u00e9 d&rsquo;un superbe entonnoir aux couleurs de la d\u00e9mocratie surmont\u00e9e du drapeau arc-en-ciel LGTBQ plaqu\u00e9 sur la rose des vents frais et revigorants de l&rsquo;OTAN&#8230; C&rsquo;est une messe, une Grand&rsquo;Messe c\u00e9l\u00e9brant la sacralit\u00e9 absolue du Mensonge.<\/p>\n<\/p>\n<p><p>&Eacute;coutez puis lisez Carlson. Il est vraiment tr\u00e8s bon. (Bon Dieu ! Mais je deviens pro-am\u00e9ricain, moi !)<\/p>\n<\/p>\n<p><h4>PhG, <em>Semper Phi<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Tucker enqu\u00eate : NordStream, qui t&rsquo;a fait bobo ?<\/h2>\n<\/p>\n<p><p>Il y a peu de choses plus exasp\u00e9rantes que de subir les mensonges de  son propre gouvernement, le gouvernement pour lequel vous payez, celui pour lequel vos anc\u00eatres ont risqu\u00e9 leur vie. Cela vous arrive-t-il ? Bien s&ucirc;r que oui. Cela vous met en col\u00e8re.<\/p>\n<\/p>\n<p><p>Mais si cela se produit encore et encore, si cela se produit assez souvent, si votre gouvernement prend l&rsquo;habitude de vous mentir, alors avec le temps, cela devient autre chose. Avec le temps, vous r\u00e9alisez que vous ne vivez pas vraiment dans une d\u00e9mocratie. C&rsquo;est impossible, car dans une d\u00e9mocratie, le gouvernement a l&rsquo;obligation morale et l\u00e9gale de toujours vous dire la v\u00e9rit\u00e9. Point final. <\/p>\n<\/p>\n<p><p>C&rsquo;est logique, car dans une d\u00e9mocratie, vous n&rsquo;\u00eates pas un sujet ou un simple consommateur. Vous \u00eates un citoyen. Vous \u00eates un actionnaire du syst\u00e8me. Vous en \u00eates propri\u00e9taire. Les gens qui dirigent votre gouvernement sont vos employ\u00e9s. Ils sont comme votre femme de m\u00e9nage. Vous pouvez appr\u00e9cier le travail qu&rsquo;ils font (\u00ab\u00a0Bon travail\u00a0\u00bb), mais d\u00e8s que vous les surprenez \u00e0 voler vos boutons de manchette, vous les renvoyez. Ce sont les r\u00e8gles parce que c&rsquo;est votre maison, pas la leur.<\/p>\n<\/p>\n<p><p>Mais que se passerait-il si les r\u00e8gles \u00e9taient invers\u00e9es ? Et si vous surpreniez un employ\u00e9 en train de voler, mais qu&rsquo;au lieu de para&icirc;tre honteux et p\u00e9nitent, il se retournait et vous attaquait comme si vous \u00e9tiez le criminel ? Eh bien, c&rsquo;est l&rsquo;exp\u00e9rience que l&rsquo;on fait en regardant le porte-parole de la Maison Blanche, John Kirby, parler de la destruction des pipelines Nord Stream. Quiconque imagine, qui pense un seul instant que l&rsquo;administration Biden a \u00e9t\u00e9 impliqu\u00e9e de quelque mani\u00e8re que ce soit dans ce sabotage, directement ou indirectement, n&rsquo;a pas simplement tort, non. Quiconque imagine cela est une mauvaise personne, un outil de Vladimir Poutine. Regardez, \u00e9coutez.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Bret Baier<\/em><\/strong><em> : Les &Eacute;tats-Unis ou un mandataire des &Eacute;tats-Unis ont-ils quelque chose \u00e0 voir avec l&rsquo;explosion du gazoduc Nord Stream ?  <\/em><\/p>\n<\/p>\n<p><p><strong><em>John Kirby<\/em><\/strong><em> : Les &Eacute;tats-Unis n&rsquo;ont rien \u00e0 voir avec cela. C&rsquo;est juste de la propagande russe et de la d\u00e9sinformation. Nous savons maintenant qu&rsquo;il s&rsquo;agissait d&rsquo;un acte de sabotage, mais une enqu\u00eate est en cours. Je ne pense pas que nous allons chercher \u00e0 d\u00e9terminer qui est responsable. Nous allons laisser les enqu\u00eateurs se pencher sur la question, mais il est clair qu&rsquo;il s&rsquo;agit d&rsquo;un acte de sabotage.  <\/em><\/p>\n<\/p>\n<p><p><strong><em>Bret Baier<\/em><\/strong><em> : Donc, vous pouvez dire officiellement que les &Eacute;tats-Unis n&rsquo;ont pas \u00e9t\u00e9 impliqu\u00e9s d&rsquo;aucune fa\u00e7on dans cette attaque ?  <\/em><\/p>\n<\/p>\n<p><p><strong><em>John Kirby<\/em><\/strong><em>  : C&rsquo;est exact. C&rsquo;est exact. <\/em><\/p>\n<\/p>\n<p><p><strong><em>Bret Baier<\/em><\/strong><em> : Je ne veux pas insister sur ce point, mais pour les gens qui regardent cela et disent, pourquoi la Russie attaquerait-elle son propre pipeline ? Cela cr\u00e9e un effet de levier sur l&rsquo;Europe et peut-\u00eatre l&rsquo;Occident, que leur r\u00e9pondez-vous ? <\/em><\/p>\n<\/p>\n<p><p><strong><em>John Kirby<\/em><\/strong><em>  : Encore une fois, je ne peux pas parler de responsabilit\u00e9 sp\u00e9cifique pour cet acte de sabotage. Je peux simplement vous assurer que les &Eacute;tats-Unis n&rsquo;ont rien \u00e0 voir avec cela. Bien s&ucirc;r, c&rsquo;est juste de la propagande russe.  <\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Remarquez que Bret Baier a pos\u00e9 la question suivante : \u00ab\u00a0Les &Eacute;tats-Unis, l&rsquo;administration Biden ou l&rsquo;un de ses mandataires ont-ils eu quelque chose \u00e0 voir avec le sabotage ?\u00a0\u00bb Ce \u00e0 quoi John Kirby r\u00e9pond que nous ne l&rsquo;avons pas fait, puis passe directement \u00e0 l&rsquo;essentiel, \u00e0 savoir que quiconque dit que nous l&rsquo;avons fait r\u00e9p\u00e8te la propagande russe. C&rsquo;est ce que John Kirby a dit. C&rsquo;est de la d\u00e9sinformation venant de tra&icirc;tres plus loyaux envers Vladimir Poutine qu&rsquo;envers notre propre pays.<\/p>\n<\/p>\n<p><p>C&rsquo;est le genre de choses que seules les personnes vraiment mauvaises disent. Ok, si la Maison Blanche le dit, \u00e9videmment nous n&rsquo;avons pas d&rsquo;autre choix que de le croire, mais vous devez quand m\u00eame vous demander si tout le monde le croit \u00e9galement. Pourquoi ? <\/p>\n<\/p>\n<p><p>O&ugrave; certains Am\u00e9ricains ont-ils pu trouver l&rsquo;id\u00e9e que l&rsquo;administration Biden aurait pu \u00eatre impliqu\u00e9e, directement ou par procuration, dans la destruction des pipelines Nord Stream ? Pourquoi penseraient-ils cela ? Ils ne l&rsquo;ont certainement pas regard\u00e9 sur Russia Today. RT a \u00e9t\u00e9 retir\u00e9e des ondes. Ils ne l&rsquo;ont pas entendu de la bouche de Poutine ou de l&rsquo;un de ses ministres.<\/p>\n<\/p>\n<p><p>Vous pouvez \u00e0 peine trouver quelque chose du gouvernement russe sur Google et, bien s&ucirc;r, tout livre sympathique \u00e0 l&rsquo;\u00e9gard de Poutine a \u00e9t\u00e9 interdit sur Amazon. En fait, chaque information qui refl\u00e8te le point de vue de la Russie moderne a \u00e9t\u00e9 censur\u00e9e aux &Eacute;tats-Unis, car il s&rsquo;agit d&rsquo;un pays libre qui se bat pour la d\u00e9mocratie. Vous ne pouvez tout simplement pas lire ce que vous voulez ou penser ce que vous voulez.<\/p>\n<\/p>\n<p><p>En fait, si l&rsquo;on y r\u00e9fl\u00e9chit, si les Am\u00e9ricains se font des illusions sur ce qui s&rsquo;est pass\u00e9 avec le gazoduc Nord Stream, ces illusions ne viennent pas de Moscou, car il n&rsquo;y a aucun moyen pour Moscou d&rsquo;envoyer cette d\u00e9sinformation aux &Eacute;tats-Unis, car le gouvernement am\u00e9ricain l&rsquo;a bloqu\u00e9e, tout comme les entreprises GAFAM. Alors, d&rsquo;o&ugrave; vient cette id\u00e9e ? Pourquoi pensent-ils cela ?<\/p>\n<\/p>\n<p><p>Eh bien, peut-\u00eatre l&rsquo;ont-ils appris de Joe Biden lui-m\u00eame. Il est le pr\u00e9sident. Cet hiver, \u00e0 la t\u00e9l\u00e9vision am\u00e9ricaine, Joe Biden s&rsquo;est engag\u00e9 \u00e0 d\u00e9truire les pipelines Nord Stream si la Russie fait quelque chose qu&rsquo;il ne veut pas qu&rsquo;elle fasse. <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Pr\u00e9sident Biden<\/em><\/strong><em> : Si la Russie lance son invasion&#8230; alors il n&rsquo;y aura plus de NordStream 2. Nous y mettrons fin.<\/em><\/p>\n<\/p>\n<p><p><strong><em>Journaliste<\/em><\/strong><em> : Mais comment allez-vous faire, exactement, puisque&#8230; le projet est sous le contr\u00f4le de l&rsquo;Allemagne ?\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p><strong><em>Pr\u00e9sident Biden<\/em><\/strong><em> : Je vous promets que nous serons en mesure de le faire. <\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Donc, c&rsquo;est aussi clair que possible. Biden ne dit pas que nous allons le fermer. Il dit, \u00ab\u00a0Il n&rsquo;y aura pas de pipeline Nord Stream. Nous y mettrons fin.\u00a0\u00bb Et le journaliste de dire : \u00ab\u00a0Mais attendez une seconde, ce n&rsquo;est pas votre gazoduc. Comment allez-vous pouvoir faire \u00e7a ?\u00a0\u00bb Donc, il a une chance de recadrer la question, de r\u00e9viser sa r\u00e9ponse, d&rsquo;\u00eatre plus pr\u00e9cis, mais il ne le fait pas. Il dit carr\u00e9ment : \u00ab\u00a0Je vous promets que nous serons capable de supprimer Nord Stream.\u00a0\u00bb Joe Biden, pr\u00e9sident des &Eacute;tats-Unis. <\/p>\n<\/p>\n<p><p>Donc, il y a cet indice et c&rsquo;est comme si cela ne suffisait pas, la semaine derni\u00e8re, vendredi dernier, le secr\u00e9taire d&rsquo;&Eacute;tat de l&rsquo;administration Biden, M. Tony Blinken, s&rsquo;est vant\u00e9 de la bonne nouvelle du sabotage du Nord Stream et nous citons \u00ab\u00a0C&rsquo;est une opportunit\u00e9 formidable, a dit Tony Blinken. C&rsquo;est une grande chose, pas une trag\u00e9die, une victoire, quelque chose que nous approuvons. Nous sommes enthousiastes \u00e0 ce sujet. <a href=\"https:\/\/www.foxnews.com\/world\/europe-activates-two-new-pipelines-decreasing-reliance-russian-gas-winter-crunch-report\">D\u00e9truire le gazoduc<\/a> ? Nous sommes pour.\u00a0\u00bb Donc, cela pourrait \u00eatre un autre indice que l&rsquo;administration Biden pourrait avoir quelque chose \u00e0 voir avec \u00e7a. <\/p>\n<\/p>\n<p><p>Oh, mais non, dit la Maison Blanche, malgr\u00e9 le fait que nous ayons promis de le faire, et que nous nous soyons exclam\u00e9s  en disant \u00e0 quel point c&rsquo;\u00e9tait g\u00e9nial apr\u00e8s que \u00e7a se soit produit, nous n&rsquo;avons rien \u00e0 voir avec \u00e7a. Qui l&rsquo;a fait ? Eh bien, la Russie l&rsquo;a fait. Ils ont fait exploser leur propre pipeline, rendant leur propre pays plus pauvre et plus faible au milieu d&rsquo;une guerre majeure, parce que c&rsquo;est \u00e0 ce point que les Russes sont fous mais aussi diaboliquement efficaces : suicidaires, mais brillants, et si vous ne croyez pas cette histoire sans r\u00e9serve, si vous avez des questions sur la fa\u00e7on dont cela peut fonctionner, vous \u00eates un Am\u00e9ricain d\u00e9loyal. Taisez-vous.<\/p>\n<\/p>\n<p><p>Voici Chris Stewart, un membre r\u00e9publicain du Congr\u00e8s de l&rsquo;Utah, qui fait exactement la m\u00eame remarque.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Bret Baier<\/em><\/strong><em> : John Kirby, du Conseil national de s\u00e9curit\u00e9, a d\u00e9clar\u00e9 plus t\u00f4t, en termes tr\u00e8s clairs, que les &Eacute;tats-Unis n&rsquo;\u00e9taient pas derri\u00e8re l&rsquo;explosion du gazoduc Nord Stream et qu&rsquo;un mandataire des &Eacute;tats-Unis n&rsquo;\u00e9tait pas derri\u00e8re. De votre point de vue, tous les deux, \u00eates-vous d&rsquo;accord avec cela ?  <\/em><\/p>\n<\/p>\n<p><p><strong><em>D\u00e9put\u00e9 Seth Moulton, D-Mass<\/em><\/strong><em>. : Oh, absolument. C&rsquo;est la derni\u00e8re chose que nous voulons pour augmenter davantage les prix du gaz en Europe. Il est assez \u00e9vident qu&rsquo;il s&rsquo;agit d&rsquo;une op\u00e9ration de sabotage russe. <\/em><\/p>\n<\/p>\n<p><p><strong><em>Bret Baier<\/em><\/strong><em>: Et pour les personnes, Monsieur le D\u00e9put\u00e9 Stewart, qui disent, pourquoi la Russie ferait-elle cela sur son propre pipeline, que dites-vous ?<\/em><\/p>\n<\/p>\n<p><p><strong><em>D\u00e9put\u00e9 Chris Stewart, R-Utah<\/em><\/strong><em> : Eh bien, les gens qui sugg\u00e8rent que ce sont les &Eacute;tats-Unis, c&rsquo;est exactement ce que Vladimir Poutine veut<\/em>. <\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est vraiment g\u00e9nial. Je veux dire, c&rsquo;est parfaitement bipartisan ici. Vous avez un r\u00e9publicain de l&rsquo;Utah, Chris Stewart, et un d\u00e9mocrate du Massachusetts, Seth Moulton, qui sont pr\u00e9cis\u00e9ment d&rsquo;accord. C&rsquo;est exactement ce que veut Vladimir Poutine. Il veut que vous bl\u00e2miez l&rsquo;administration Biden pour quelque chose qu&rsquo;il a fait. C&rsquo;est le point de vue bipartisan \u00e0 Washington. Ce qui est int\u00e9ressant, c&rsquo;est qu&rsquo;ils ne le savent pas vraiment. Ils n&rsquo;ont aucune preuve que c&rsquo;est vrai. Les informateurs des agences de renseignement ont, d\u00e8s cet apr\u00e8s-midi, dit aux membres du Congr\u00e8s qu&rsquo;ils n&rsquo;ont aucune id\u00e9e de qui a commis le terrorisme industriel contre ces pipelines. Maintenant, c&rsquo;est un mensonge en soi, bien s&ucirc;r. La CIA n&rsquo;a aucune id\u00e9e du tout ? C&rsquo;est vrai, ils n&rsquo;en ont aucune id\u00e9e, mais pour les membres du Congr\u00e8s, Chris Stewart et Seth Moulton, il n&rsquo;y a aucune preuve dans un sens ou dans l&rsquo;autre. Ils n&rsquo;ont aucun fait. C&rsquo;est un fait. Ils n&rsquo;ont aucun fait. <\/p>\n<\/p>\n<p><p>Donc, encore une fois, d&rsquo;un point de vue factuel, aucun de ces gars ni aucun membre du Congr\u00e8s, quelle que soit la commission \u00e0 laquelle il si\u00e8ge, n&rsquo;a la moindre id\u00e9e de qui a fait \u00e7a, mais si vous sugg\u00e9rez l&rsquo;\u00e9vidence, la Russie ne l&rsquo;a probablement pas fait, parce que pourquoi le feraient-ils, c&rsquo;est contre leur propre int\u00e9r\u00eat, peu importe l&rsquo;histoire d\u00e9bile que vous essayez de nous vendre, si vous sugg\u00e9rez cela, si vous appliquez le bon sens, vous \u00eates mauvais, et ensuite ils vont plus loin et disent des choses qui sont comme compl\u00e8tement invraisemblables. Seth Moulton et nous citons, \u00ab\u00a0La derni\u00e8re chose que nous voulons est d&rsquo;augmenter le prix de l&rsquo;essence en Europe\u00a0\u00bb. Vraiment ? Seth Moulton, c&rsquo;est vrai ? Parce que l&rsquo;administration Biden n&rsquo;est-elle pas philosophiquement oppos\u00e9e aux prix bas de l&rsquo;essence ? Ne sont-ils pas oppos\u00e9s \u00e0 tous les combustibles fossiles ? Oh, oui, ils le sont. Comment le savons-nous ? C&rsquo;est de la propagande russe? Non, car nous ne pouvons pas lire la propagande russe parce qu&rsquo;elle a \u00e9t\u00e9 interdite au profit de notre propagande. Nous le savons parce que Joe Biden lui-m\u00eame l&rsquo;a dit \u00e0 plusieurs reprises \u00e0 la t\u00e9l\u00e9vision. Ok. Donc peut-\u00eatre qu&rsquo;il y a un motif ici. Peut-\u00eatre qu&rsquo;il y a plus d&rsquo;un motif, mais ne posez pas la question car, pr\u00e9viennent les m\u00e9dias, il est interdit de poser des questions \u00e9videntes. <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Katie Phang<\/em><\/strong><em> : L&rsquo;animateur de Fox News Tucker Carlson a pr\u00e9tendu de fa\u00e7on irresponsable que les &Eacute;tats-Unis \u00e9taient responsables de la fuite. <\/em><\/p>\n<\/p>\n<p><p><strong><em>Josh Rogin, Washington Post<\/em><\/strong><em> : A part Poutine et Tucker Carlson, il semble assez clair que tout le monde sait que Poutine a fait \u00e7a lui-m\u00eame.  <\/em><\/p>\n<\/p>\n<p><p><strong><em>Jonathan Karl<\/em><\/strong><em> : Et Tucker Carlson, la semaine derni\u00e8re, a en fait une fois de plus directement r\u00e9p\u00e9t\u00e9 la propagande russe, sugg\u00e9rant que les &Eacute;tats-Unis \u00e9taient en quelque sorte derri\u00e8re l&rsquo;attaque du gazoduc Nord Stream. Dans quelle mesure ce mouvement est-il r\u00e9el ? Est-ce qu&rsquo;il grandit ?<\/em> <\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est de la propagande russe ! Comment osent-ils ? Vraiment ? C&rsquo;est vraiment le cas ? Il s&rsquo;agit probablement d&rsquo;une exp\u00e9rience de pens\u00e9e dirig\u00e9e. Beaucoup d&rsquo;Am\u00e9ricains qui ne ressentent aucune all\u00e9geance \u00e0 la Russie, n&rsquo;aiment pas Poutine (pourquoi l&rsquo;aimeriez-vous, si vous \u00eates Am\u00e9ricain ?) mais se soucient beaucoup de leur propre pays et du comportement de leur propre gouvernement. Donc, leur propre gouvernement (encore une fois celui qu&rsquo;ils paient, celui qu&rsquo;ils sont cens\u00e9s contr\u00f4ler), fait des choses contraires \u00e0 leurs int\u00e9r\u00eats et ment ensuite \u00e0 ce sujet. <\/p>\n<\/p>\n<p><p>Ils pensent peut-\u00eatre qu&rsquo;ils ont le droit de savoir et posent des questions \u00e9videntes comme \u00ab\u00a0Est-ce que vous mentez ? Et si vous ne mentez pas, parlez lentement et dites-nous comment votre histoire, celle que vous voulez nous faire croire, a du sens\u00a0\u00bb. Il est possible que poser des questions soit un devoir patriotique des Am\u00e9ricains. Taisez-vous. &Ccedil;a aide Poutine. Vous n&rsquo;avez pas le droit de le dire. Vous n&rsquo;avez pas le droit de citer le pr\u00e9sident des &Eacute;tats-Unis promettant d&rsquo;\u00e9liminer les pipelines Nord Stream. Vous n&rsquo;avez pas le droit de citer son secr\u00e9taire d&rsquo;&Eacute;tat c\u00e9l\u00e9brant ce sabotage. Vous \u00eates oblig\u00e9s de croire que Poutine a d\u00e9truit sa propre infrastructure. Vous le devez. <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em><strong>Pam Brown, CNN<\/strong> : Comment cela s&rsquo;inscrit-il dans le plan de jeu de Poutine ? Bien s&ucirc;r, comme on peut s&rsquo;y attendre, Susan, la Russie dit : &quot;Oh, nous n&rsquo;avons rien \u00e0 voir avec \u00e7a. Nous allons lancer une enqu\u00eate&quot;, mais allons-y.  <\/em><\/p>\n<\/p>\n<p><p><strong><em>Susan Glaser, analyste, CNN<\/em><\/strong><em> : &Eacute;coutez, vous savez, les indications sont qu&rsquo;un acte criminel a \u00e9t\u00e9 commis et qu&rsquo;il semble que, vous savez, la Russie soit certainement le suspect le plus probable.  <\/em><\/p>\n<\/p>\n<p><p><strong><em>John Brennan, ancien directeur de la CIA<\/em><\/strong><em> : Je pense qu&rsquo;il s&rsquo;agit clairement d&rsquo;un acte de sabotage, en quelque sorte, et la Russie est certainement le suspect le plus probable. Je pense que ce n&rsquo;est peut-\u00eatre que la premi\u00e8re salve d&rsquo;autres actions qui pourraient \u00eatre men\u00e9es contre l&rsquo;Europe. <\/em><\/p>\n<\/p>\n<p><p><strong><em>Bill Browder, PDG, Hermitage Capital Management<\/em><\/strong><em> : Ce que Poutine nous dit, en faisant sauter son pipeline, c&rsquo;est : \u00ab\u00a0&Eacute;coutez, je peux faire sauter un pipeline si n\u00e9cessaire. Je peux faire sauter les c\u00e2bles Internet qui entrent dans votre pays. Je peux faire sauter des pipelines qui fonctionnent. Je peux faire toutes sortes de choses v terribles\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Oh, c&rsquo;est Bill Browder. C&rsquo;est un expert en la mati\u00e8re. Croyez Bill Browder. Ne croyez pas vos propres yeux qui mentent. Il y a eu un moment, apr\u00e8s qu&rsquo;il ait \u00e9t\u00e9 tr\u00e8s clair que la guerre en Irak n&rsquo;aidait en rien les &Eacute;tats-Unis et qu&rsquo;en fait, elle nuisait \u00e0 leurs int\u00e9r\u00eats fondamentaux, o&ugrave; les m\u00e9dias se sont livr\u00e9s \u00e0 une rare nanoseconde d&rsquo;autor\u00e9flexion. Comment en sommes-nous arriv\u00e9s l\u00e0 ? Quel r\u00f4le avons-nous jou\u00e9, par exemple le New York Times, pour convaincre le public que Saddam avait des ADM alors qu&rsquo;il n&rsquo;en avait pas ? <\/p>\n<\/p>\n<p><p>Pendant un instant, vous avez pens\u00e9 : \u00ab\u00a0Wow, peut-\u00eatre qu&rsquo;ils apprennent quelque chose. Peut-\u00eatre qu&rsquo;ils ne le referont pas\u00a0\u00bb. Mais il s&rsquo;av\u00e8re que c&rsquo;est le contraire qui s&rsquo;est produit. Maintenant, ils ne font que doubler ce qui est manifestement un mensonge et attaquent quiconque demande \u00e0 l&rsquo;entendre expliqu\u00e9 rationnellement.<\/p>\n<\/p>\n<p><p>Et ce n&rsquo;est pas seulement les m\u00e9dias, d&rsquo;ailleurs. Les groupes de r\u00e9flexion de [Washington] D.C., par exemple, qui travaillent dur depuis si longtemps dans le but dire quel est le but d&rsquo;un groupe de r\u00e9flexion de D.C. ? Oh, sans doute produire des interf\u00e9rences pour la classe dirigeante, soutenir le r\u00e9gime de la Garde Pr\u00e9torienne. La Brookings Institution a rempli ce r\u00f4le pendant de nombreuses ann\u00e9es. Ils viennent de produire cette analyse : \u00ab\u00a0Les podcasters am\u00e9ricains diffusent les r\u00e9cits du Kremlin sur le sabotage du Nord Stream\u00a0\u00bb. <\/p>\n<\/p>\n<p><p>Ce qui est int\u00e9ressant dans cette analyse, c&rsquo;est que nulle part l&rsquo;auguste Brookings Institution ne r\u00e9fute les preuves que les &Eacute;tats-Unis ou un mandataire de l&rsquo;administration Biden ont quelque chose \u00e0 voir avec cela. En fait, il n&rsquo;y a aucune preuve dans un sens ou dans l&rsquo;autre. Au lieu de cela, ils attaquent tous ceux qui posent des questions. \u00ab\u00a0Les th\u00e9ories avanc\u00e9es par ces animateurs de podcasts s&rsquo;alignent sur les messages du Kremlin\u00a0\u00bb. Oh, align\u00e9es sur les messages du Kremlin ? Avant, on appelait \u00e7a la culpabilit\u00e9 par association. Vladimir Poutine aime les chiens, mais vous aimez les chiens. Alors, vous \u00eates un sympathisant russe, pas vrai? En alliance avec la propagande russe ?<\/p>\n<\/p>\n<p><p>Le fait est que peu importe si c&rsquo;est vrai ou non, cela s&rsquo;aligne sur le message du Kremlin. Par cons\u00e9quent, vous devez \u00eatre censur\u00e9.<\/p>\n<\/p>\n<p><p>Mais tout le monde n&rsquo;a pas re\u00e7u le m\u00e9mo. Il y a, cach\u00e9s dans les recoins profonds de la soci\u00e9t\u00e9 am\u00e9ricaine, quelques lib\u00e9raux honn\u00eates encore en vie. Peut-\u00eatre \u00e9taient-ils, je ne sais pas, \u00e0 Saint-Barth\u00e9lemy ces trois derni\u00e8res ann\u00e9es et n&rsquo;ont-ils pas r\u00e9alis\u00e9 qu&rsquo;il n&rsquo;\u00e9tait plus possible de s&rsquo;exprimer librement dans ce pays. L&rsquo;un d&rsquo;eux est un professeur de Columbia, <a href=\"https:\/\/www.dedefensa.org\/article\/ukrisis-aux-origines\">Jeffrey Sachs.<\/a> Il a d\u00e9cid\u00e9 de r\u00e9pondre de mani\u00e8re rationnelle et a dit qu&rsquo;en fait, il y avait de nombreuses preuves que l&rsquo;administration Biden \u00e9tait impliqu\u00e9e, mais plut\u00f4t que de poursuivre, le pr\u00e9sentateur, r\u00e9alisant que des sujets interdits \u00e9taient abord\u00e9s, (nous ne sommes pas autoris\u00e9s \u00e0 parler de cela) a simplement arr\u00eat\u00e9 la s\u00e9quence, mais pas avant que Jeffrey Sachs ne dise ceci :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Jeffrey Sachs<\/em><\/strong><em> : La destruction du gazoduc Nord Stream, qui, je parie, \u00e9tait une action des Etats-Unis, peut-\u00eatre des Etats-Unis et de la Pologne.  <\/em><\/p>\n<\/p>\n<p><p><strong><em>Jourbakuste Bloomberg<\/em><\/strong><em> : Jeff, nous devons nous arr\u00eater l\u00e0 ! C&rsquo;est une sacr\u00e9e d\u00e9claration. Pourquoi pensez-vous que c&rsquo;\u00e9tait une action am\u00e9ricaine ? <\/em><em>Quelles sont les preuves que vous avez de cela ?<\/em><\/p>\n<\/p>\n<p><p><strong><em>Jeffrey Sachs<\/em><\/strong><em> : Eh bien, tout d&rsquo;abord, il y a des preuves radar directes que des h\u00e9licopt\u00e8res am\u00e9ricains, des h\u00e9licopt\u00e8res militaires qui sont normalement bas\u00e9s \u00e0 Gdansk, tournaient au-dessus de cette zone. Nous avons \u00e9galement eu les menaces des &Eacute;tats-Unis plus t\u00f4t dans l&rsquo;ann\u00e9e que d&rsquo;une mani\u00e8re ou d&rsquo;une autre nous allons mettre fin \u00e0 Nord Stream. Vous n&rsquo;\u00eates pas autoris\u00e9 \u00e0 dire ces choses en Occident, mais le fait est que, partout dans le monde, quand je parle aux gens, ils pensent que les &Eacute;tats-Unis l&rsquo;ont fait. Bien. D&rsquo;ailleurs, m\u00eame les journalistes et nos journaux qui sont impliqu\u00e9s me disent en priv\u00e9, \u00ab\u00a0Bien s&ucirc;r\u00a0\u00bb. Eh bien, \u00e7a ne se voit pas dans nos m\u00e9dias.<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le pr\u00e9sentateur re\u00e7oit clairement des instructions. <\/p>\n<\/p>\n<p><p>Arr\u00eatez-le ! Arr\u00eatez-le !<\/p>\n<\/p>\n<p><p>Quelle preuve avez-vous ? <\/p>\n<\/p>\n<p><p>Eh bien, il y a une preuve radar. <\/p>\n<\/p>\n<p><p>Quoi ? Taisez-vous. Taisez-vous. Coupez-leur les vivres. Ne les invitez jamais \u00e0 revenir. Arr\u00eatez.<\/p>\n<\/p>\n<p><p>La seule explication autoris\u00e9e, bien s&ucirc;r, est celle que le gouvernement veut que vous croyiez : Vladimir Poutine est si mauvais qu&rsquo;il d\u00e9truit ses propres pipelines.<\/p>\n<\/p>\n<p><h4>Tucker Carlson<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On a trouv\u00e9 le saboteur de la Baltique ! 7 septembre 2022 (17H30) &ndash; Exactement, on en vient \u00e0 croire que Tucker Carlson lui-m\u00eame, en direct sur FoxNews, avec un tuba \u00e9lectromagn\u00e9tique et des palmes acad\u00e9miques-hypersoniques, est all\u00e9 en personne et en combinaison qui rend invisible glisser les trois p\u00e9tards sous les deux gazoducs, les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2972,2651,16682,2702,19588,13348,8746],"class_list":["post-80362","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-carlson","tag-du","tag-gazoduc","tag-mensonge","tag-nordstream","tag-sacralite","tag-tucker"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80362"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80362\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}