{"id":80383,"date":"2022-10-23T18:38:53","date_gmt":"2022-10-23T18:38:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/10\/23\/turquie-et-arabie-exemplaires\/"},"modified":"2022-10-23T18:38:53","modified_gmt":"2022-10-23T18:38:53","slug":"turquie-et-arabie-exemplaires","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/10\/23\/turquie-et-arabie-exemplaires\/","title":{"rendered":"Turquie et Arabie exemplaires"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Turquie et Arabie exemplaires<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Pourtant, Dieu sait que ces deux pays, Turquie et Arabie, <strong>sont bien mal plac\u00e9s \u00e0 la cotation de la vertu<\/strong> \u00e9tablie par le vaste Camp du Bien qui rythme notre conformit\u00e9 morale et notre pertinence \u00e0 \u00eatre de ce monde. &bull; Quoi qu&rsquo;il en soit, ces deux pays, <strong>alli\u00e9s si importants des USA, sont accabl\u00e9s d&rsquo;injures et d&rsquo;accusations par les USA<\/strong>. &bull; Dr\u00f4le de fa\u00e7on de prot\u00e9ger son capital d&rsquo;influence dans un monde que l&rsquo;on pr\u00e9tend \u00eatre sous l&#8217;empire de son h\u00e9g\u00e9monie exceptionnelle. &bull; La Turquie et l&rsquo;Arabie, <strong>exemples convaincants de la folie am\u00e9ricaniste<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans le Grand Affrontement qui a lieu aujourd&rsquo;hui, qui d\u00e9passe tr\u00e8s largement l&rsquo;Ukraine, ce qui compte n&rsquo;est pas celui qui l&#8217;emportera mais bien celui qui sera vaincu. L&rsquo;important n&rsquo;est pas que la Russie (ou la Chine, o&ugrave; le \u00ab\u00a0Grand Sud&rsquo;, ou n&rsquo;importe quoi, y compris le chaos pr\u00f4n\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/ode-au-chaos-vrai\">par Mercouris<\/a>) l&#8217;emporte, mais bien que les USA (le bloc-BAO) soient vaincus ; ce qui compte n&rsquo;est pas d&rsquo;\u00eatre avec un tel ou tel autre, quitte \u00e0 changer, mais bien d&rsquo;\u00eatre contre les USA dans cette occurrence de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> o&ugrave; les USA ne laissent aucun choix au terme de tout, &ndash; que d&rsquo;\u00eatre contre eux. Les USA n&rsquo;ont pas compris cela, comme un certain nombre d&rsquo;autres choses, et par cons\u00e9quent ils ne cessent de se faire de plus en plus d&rsquo;ennemis m\u00eame parmi ceux qui furent les plus stipendi\u00e9s, les plus acoquin\u00e9s, les plus soumis sur le fond pourvu que la forme les \u00e9pargn\u00e2t ; et ils ne cessent de faire tout cela simplement parce qu&rsquo;avec leurs singuliers travers initiaux ils sont devenus fous.<\/p>\n<\/p>\n<p><p>Il est vrai que les USA sont prot\u00e9g\u00e9s comme par une cuirasse infranchissable de toute perception acceptable de la r\u00e9alit\u00e9 du monde (autre d\u00e9finition de la folie) par deux ph\u00e9nom\u00e8nes, sortes de \u00ab\u00a0technologies psychologiques\u00a0\u00bb absolument imp\u00e9n\u00e9trables. Nous en parlons et nous les r\u00e9p\u00e9tons souvent car nous pensons qu&rsquo;il faut se convaincre du ph\u00e9nom\u00e8ne et en prendre la mesure et les cons\u00e9quences. Ces deux \u00ab\u00a0technologies psychologiques\u00a0\u00bb (nous adoptons ce terme pour marquer combien tout est de moins en moins humain dans l&rsquo;am\u00e9ricanisme, jusqu&rsquo;\u00e0 l&rsquo;humain lui-m\u00eame, car la folie fait son &oelig;uvre) sont deux traits psychologiques qui rel\u00e8vent de la f\u00e9\u00e9rie-<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fantasy\">fantasy<\/a><\/em> propre \u00e0 l&rsquo;am\u00e9ricanisme, et qui sont aujourd&rsquo;hui exacerb\u00e9es jusqu&rsquo;\u00e0 la folie, &ndash; soit l&rsquo;inculpabilit\u00e9 (&laquo; <em>sentiment de l&rsquo;absence \u00e0 terme et d\u00e9cisivement de culpabilit\u00e9 de l&rsquo;am\u00e9ricanisme quelle que soit son action<\/em> &raquo;) et l&rsquo;ind\u00e9fectibilit\u00e9 (&laquo; <em>sentiment de la certitude <\/em>[de l&rsquo;am\u00e9ricanisme] <em>de ne pouvoir \u00eatre battu dans tout ce qui figure conflit et affrontement<\/em> &raquo;), tels qu&rsquo;ils sont explicit\u00e9s dans cet extrait <a href=\"https:\/\/www.dedefensa.org\/article\/les-usa-face-a-lhypersonique\">d&rsquo;un texte<\/a> qui rappelle leurs caract\u00e8res :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nous avons toujours suivi avec le plus grand int\u00e9r\u00eat, sur ce site, les caract\u00e9ristiques de la psychologie de l&rsquo;am\u00e9ricanisme, que nous tenons comme sp\u00e9cifique, \u00ab\u00a0exceptionnelle\u00a0\u00bb dans le sens de n&rsquo;\u00eatre radicalement pas comme les autres (ce qui ne signifie nullement dans notre interpr\u00e9tation \u00ab\u00a0sup\u00e9rieure\u00a0\u00bb aux autres types psychologiques, cel va de soi). Il existe aux USA <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-lempire-de-la-communication\">d\u00e8s les origines<\/a><\/em> <em>un tel usage intensif de la communication pour formater le sentiment du citoyen vis-\u00e0-vis de son pays, dans un pays b\u00e2ti sur la communication et nullement sur la v\u00e9rit\u00e9 historique, qu&rsquo;il y a effectivement une v\u00e9ritable cr\u00e9ation permanente d&rsquo;une psychologie am\u00e9ricaniste typique. Au cours de nos recherches, nous avons isol\u00e9 deux traits sp\u00e9cifiques de cette psychologie, qui constituent non pas des capacit\u00e9s sp\u00e9cifiques de perception, mais des perceptions impos\u00e9es \u00e0 la psychologie am\u00e9ricaniste \u00e0 la diff\u00e9rence des autres. Outre le trait de <a href=\"http:\/\/www.dedefensa.org\/article\/linculpabilite-et-la-psychologie-americaniste-1\">l&rsquo;inculpabilit\u00e9<\/a> qui est le sentiment de l&rsquo;absence \u00e0 terme et d\u00e9cisivement de culpabilit\u00e9 de l&rsquo;am\u00e9ricanisme quelle que soit son action, il y a \u00e9galement le caract\u00e8re de <a href=\"http:\/\/www.dedefensa.org\/article\/apres-linculpabilite-lindefectibilite\">l&rsquo;ind\u00e9fectibilit\u00e9<\/a>, compl\u00e9ment du pr\u00e9c\u00e9dent, qui est la certitude de ne pouvoir \u00eatre battu dans tout ce qui figure conflit et affrontement<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La Turquie d\u00e9fend l&rsquo;Arabie<\/h3>\n<\/p>\n<p><p>C&rsquo;est donc \u00e0 cette lumi\u00e8re brillante de la \u00ab\u00a0technologie psychologique\u00a0\u00bb de l&rsquo;am\u00e9ricanisme-devenu-fou que nous devons d\u00e9tailler rapidement les agacements diplomatiques du ministre turc des affaires \u00e9trang\u00e8res, dissimulant \u00e0 peine ce que nous jugerons \u00eatre une rupture irr\u00e9versible avec les USA, et avec l&rsquo;Arabie dans le m\u00eame sac puisque les r\u00e9centes remontrances US concernent ces deux pays. (L\u00e0 aussi, consid\u00e9rons le fait de la rupture due \u00e0 l&rsquo;insupportabilit\u00e9 des USA, sans nous attarder aux coups tordus et man&oelig;uvres diverses des Turcs et des Saoudiens qui sont, en cette circonstance, compl\u00e8tement secondaires : ce qui compte est d&rsquo;\u00eatre contre.)<\/p>\n<\/p>\n<p><p>Voici donc l&rsquo;expos\u00e9 du conflit dont il est question, o&ugrave; il est remarquable d&rsquo;entendre le ministre truc d\u00e9fendre l&rsquo;Arabie seule, comme si la Turquie n&rsquo;\u00e9tait pas en cause. Elle l&rsquo;est, mais indirectement, sur d&rsquo;autres affaires essentielles (le \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/comme-larrons-en-foire\">centre gazier<\/a>\u00ab\u00a0) et l&rsquo;on voit bien ainsi que l&rsquo;essentiel n&rsquo;est pas d&rsquo;\u00eatre \u00ab\u00a0pour\u00a0\u00bb puisque la Turquie n&rsquo;est pas membre de l&rsquo;OPEP+, mais bien d&rsquo;\u00eatre \u00ab\u00a0contre\u00a0\u00bb (les USA) ce que la Turquie est tout \u00e0 fait, comme l&rsquo;Arabie, comme la Russie, comme&#8230;, etc.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les &Eacute;tats-Unis devraient cesser de menacer l&rsquo;Arabie Saoudite au sujet des prix \u00e9lev\u00e9s du p\u00e9trole et trouver d&rsquo;autres moyens de r\u00e9soudre le probl\u00e8me, a d\u00e9clar\u00e9 vendredi le ministre turc des affaires \u00e9trang\u00e8res.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;Organisation des pays exportateurs de p\u00e9trole (OPEP), dont Riyad est le chef de file de facto, a accept\u00e9 de r\u00e9duire sa production de p\u00e9trole d\u00e9but octobre, provoquant la col\u00e8re de Washington, qui avait \u00e0 plusieurs reprises exhort\u00e9 le groupe \u00e0 augmenter sa production.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Les brimades contre l&rsquo;Arabie saoudite sont inappropri\u00e9es. Nous traversons des difficult\u00e9s similaires en mati\u00e8re de prix de l&rsquo;\u00e9nergie, mais nous ne mena\u00e7ons personne\u00a0\u00bb, a d\u00e9clar\u00e9 Mevlut Cavusoglu.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>S&rsquo;exprimant \u00e0 Mersin, dans le sud de la Turquie, Cavusoglu a d\u00e9clar\u00e9 qu&rsquo;il \u00e9tait acceptable que les &Eacute;tats-Unis critiquent l&rsquo;OPEP+, un groupement des principaux producteurs de p\u00e9trole comprenant la Russie et l&rsquo;Arabie saoudite, pour avoir r\u00e9duit la production, mais il a averti Washington que menacer Riyad \u00e9tait \u00ab\u00a0incorrect, injuste et d\u00e9plac\u00e9\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Puis le ministre, son devoir de solidarit\u00e9 entre pays-\u00ab\u00a0contre\u00a0\u00bb accompli, se lance \u00e0 l&rsquo;offensive, qui est celle justifiant pour ce cas  le \u00ab\u00a0contre\u00a0\u00bb. Il met les USA en accusation pour leurs incroyables contradictions entre leurs g\u00e9missements devant le prix du p\u00e9trole du \u00e0 la raret\u00e9 de ce produit, existante essentiellement du fait des innombrables sanctions qu&rsquo;ils ont \u00e9dict\u00e9es contre un nombre respectable de producteurs. Ce qui est critiqu\u00e9 ici n&rsquo;est pas tant l&rsquo;usage de la force (la Turquie, comme d&rsquo;autres, ne s&rsquo;en prive pas \u00e0 l&rsquo;occasion), mais l&rsquo;usage totalement irresponsable de la force illustrant en une parabole incroyablement rapide et aveuglante la fameuse maxime concernant les ceux dont &laquo; <em>Dieu se rit <\/em>&raquo; parce qu&rsquo;ils &laquo; <em>se plaignent des effets dont ils sont les causes <\/em>[presque instantan\u00e9es dans ce cas] &raquo;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le ministre a ensuite laiss\u00e9 entendre que la flamb\u00e9e des prix du p\u00e9trole, qui constitue une pr\u00e9occupation majeure pour les &Eacute;tats-Unis, r\u00e9sulte des propres politiques de Washington.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Vous ne pouvez pas r\u00e9soudre cette question en vous contentant de menacer un pays. Vous devriez permettre aux producteurs de p\u00e9trole de reprendre leur production\u00a0\u00bb, a-t-il not\u00e9, faisant r\u00e9f\u00e9rence aux embargos que Washington a impos\u00e9s \u00e0 l&rsquo;Iran et au Venezuela.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cavusoglu a exhort\u00e9 les &Eacute;tats-Unis \u00e0 \u00ab\u00a0lever ces sanctions\u00a0\u00bb, arguant : \u00ab\u00a0Si vous voulez que les prix du p\u00e9trole baissent, supprimez les embargos sur les pays qui offrent leurs produits sur le march\u00e9\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;on sait qu&rsquo;au d\u00e9but du mois, l&rsquo;OPEP+ a r\u00e9duit la production de p\u00e9trole de deux millions de barils par jour, ignorant les appels des &Eacute;tats-Unis \u00e0 pomper davantage, dans le but de faire baisser les prix. L&rsquo;on sait \u00e9galement que les am\u00e9ricanistes, \u00e0 qui on ne la fait pas, non monsieur, ont aussit\u00f4t mis \u00e0 nu le pot-aux-roses et largement arros\u00e9 les belles fleurs, &ndash; qui sont d&rsquo;une nouvelle esp\u00e8ce tr\u00e8s r\u00e9pandue, nomm\u00e9 \u00ab\u00a0C\u00e9l\u00e9russes\u00a0\u00bb. Comme l&rsquo;a brillamment expliqu\u00e9 la jeune attach\u00e9e de presse d&rsquo;origine ha\u00eftiennne du pr\u00e9sident am\u00e9ricain Joe Biden, Karine Jean-Pierre, &ndash; son pays d&rsquo;origine pourrait \u00eatre prochainement honor\u00e9 de la venue non r\u00e9clam\u00e9e de soldats am\u00e9ricanistes selon la doctrine \u00ab\u00a0C\u00e9l\u00e9russes\u00a0\u00bb, bien s&ucirc;r sans la scandaleuse ill\u00e9galit\u00e9 et l&rsquo;inhumaine brutalit\u00e9 russes, &ndash; selon elle, donc, les Saoudiens, dans ce cas, ne font que &laquo; <em>s&rsquo;aligner certainement sur la Russie<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>L&rsquo;Arabie saoudite dit que sa d\u00e9cision de r\u00e9duire la production est &laquo; <em>fond\u00e9e sur des consid\u00e9rations purement \u00e9conomiques qui tiennent compte du maintien de l&rsquo;\u00e9quilibre entre l&rsquo;offre et la demande sur les march\u00e9s p\u00e9troliers<\/em> &raquo;. On s&rsquo;en fiche. Le ministre de la d\u00e9fense saoudien d\u00e9clare que lui et d&rsquo;autres hauts responsables sont &laquo; <em>\u00e9tonn\u00e9s<\/em> &raquo; par les accusations selon lesquelles Riyad se range du c\u00f4t\u00e9 de la Russie. On s&rsquo;en balance&#8230; En fait, \u00e7a oui par contre, on menace !<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&Agrave; la suite de la r\u00e9duction du prix du p\u00e9trole, le s\u00e9nateur d\u00e9mocrate am\u00e9ricain Bob Menendez, qui pr\u00e9side la commission des affaires \u00e9trang\u00e8res, est all\u00e9 jusqu&rsquo;\u00e0 demander aux &Eacute;tats-Unis de \u00ab\u00a0geler tous les aspects\u00a0\u00bb de leur coop\u00e9ration avec l&rsquo;Arabie saoudite, et d&rsquo;autres responsables am\u00e9ricains ont exprim\u00e9 un point de vue similaire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le conseiller de Biden pour la s\u00e9curit\u00e9 nationale, Jake Sullivan, a confirm\u00e9 dimanche que le pr\u00e9sident Biden agirait \u00ab\u00a0m\u00e9thodiquement\u00a0\u00bb pour r\u00e9\u00e9valuer la relation des &Eacute;tats-Unis avec l&rsquo;Arabie saoudite. L&rsquo;administration a menac\u00e9 de \u00ab\u00a0r\u00e9\u00e9valuer\u00a0\u00bb le partenariat depuis l&rsquo;annonce de la baisse des prix. Toutefois, si le pr\u00e9sident a pr\u00e9venu qu&rsquo;il y aurait \u00ab\u00a0certaines cons\u00e9quences\u00a0\u00bb pour les Saoudiens, aucune mesure sp\u00e9cifique n&rsquo;a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e publiquement<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le plus int\u00e9ressant dans cette affaire n&rsquo;est \u00e9videmment pas l&rsquo;attitude am\u00e9ricaniste dont on a vu les causes et dont les traits biaisant leur psychologie confinent d\u00e9sormais \u00e0 la folie pure. Rien de nouveau chez eux, sinon de pire en pire. Par contre, il est int\u00e9ressant de voir ainsi la Turquie prendre la d\u00e9fense de l&rsquo;Arabie, sans doute sans arri\u00e8re-pens\u00e9e vicieuse (\u00e0-la-Erdogan), mais simplement parce que, vraiment, les USA commence \u00e0 exasp\u00e9rer tout le monde. (Pas les Europ\u00e9ens, non pas eux certes ! Ils sont dans leur zoo, compl\u00e8tement \u00e0 part, on les y laisse.)<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, certes, les bureaucrates de Washington D.C. ont fait un fabuleux \u00ab\u00a0doubl\u00e9\u00a0\u00bb en liant finalement la Turquie et l&rsquo;Arabie dans un m\u00eame combat, alors qu&rsquo;il s&rsquo;agissait d&rsquo;un enjeu diff\u00e9rent. Ils ont envoy\u00e9 la m\u00eame d\u00e9l\u00e9gation de combat en un seul d\u00e9placement \u00e0 Ankara et \u00e0 Ryad pour parler de choses somme toute si diff\u00e9rente (le \u00ab\u00a0centre gazier\u00a0\u00bb d&rsquo;Erdogan, le refus d&rsquo;augmenter la production de p\u00e9trole de l&rsquo;OPEP+) ; d\u00e9l\u00e9gation dirig\u00e9e par une dame Rozenberg, du d\u00e9partement d&rsquo;&Eacute;tat, qui s&rsquo;\u00e9tait illustr\u00e9e en 2010-2012 en faisant dans le &lsquo;<em>regime change<\/em>&lsquo; ici et l\u00e0 (Libye, Syrie). Ainsi se trouvaient rassembl\u00e9es les menaces contre la Turquie et l&rsquo;Arabie et l&rsquo;arri\u00e8re-pens\u00e9e flottante de la possibilit\u00e9 d&rsquo;op\u00e9rations de cette sorte contre les ci-devant r\u00e9calcitrants. Et alors s&rsquo;\u00e9claire beaucoup mieux, \u00e0 notre sens, cette intervention turque pour d\u00e9fendre l&rsquo;Arabie, selon la doctrine du \u00ab\u00a0Je suis contre\u00a0\u00bb (les USA). Ce faisant, les USA, \u00e0 la fois \u00ab\u00a0incoupables\u00a0\u00bb (plut\u00f4t qu'\u00a0\u00bbinnocent\u00a0\u00bb qui supposerait qu&rsquo;existe la possibilit\u00e9 impensable du choix de les juger coupables) et ind\u00e9fectibles, parviennent \u00e0 faire de formidables \u00ab\u00a0d&rsquo;une pierre deux coups\u00a0\u00bb en cimentant, en aggravant, en rendant presque ontologique l&rsquo;hostilit\u00e9 qu&rsquo;ils suscitent chez leurs alli\u00e9s les plus utiles, &ndash; deux dans ce cas, &ndash; qu&rsquo;ils eurent durant le gros trois-quarts de si\u00e8cle de leur splendeur h\u00e9g\u00e9monique depuis 1945.<\/p>\n<\/p>\n<p><p>On ne peut \u00eatre, bouche b\u00e9e, qu&rsquo;admiratifs devant la perfection d&rsquo;une telle <a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">d\u00e9constructuration<\/a> de soi-m\u00eame. C&rsquo;est notre cas.<\/p>\n<\/p>\n<p><p>Mis en ligne le 22 octobre 2022 \u00e0 18H40<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Turquie et Arabie exemplaires &bull; Pourtant, Dieu sait que ces deux pays, Turquie et Arabie, sont bien mal plac\u00e9s \u00e0 la cotation de la vertu \u00e9tablie par le vaste Camp du Bien qui rythme notre conformit\u00e9 morale et notre pertinence \u00e0 \u00eatre de ce monde. &bull; Quoi qu&rsquo;il en soit, ces deux pays, alli\u00e9s si&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[17694,5017,2651,14696,3634,4735,16140,5650,3600,3477],"class_list":["post-80383","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-cavusoglu","tag-centre","tag-du","tag-gazier","tag-inculpabilite","tag-indefectibilite","tag-insultes","tag-opep","tag-petrole","tag-prix"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80383"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80383\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}