{"id":80410,"date":"2022-11-15T15:29:21","date_gmt":"2022-11-15T15:29:21","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/11\/15\/le-desordre-de-lempire-facon-puzzle\/"},"modified":"2022-11-15T15:29:21","modified_gmt":"2022-11-15T15:29:21","slug":"le-desordre-de-lempire-facon-puzzle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/11\/15\/le-desordre-de-lempire-facon-puzzle\/","title":{"rendered":"Le d\u00e9sordre de l\u00a0\u00bbEmpire&rsquo;, \u201cfa\u00e7on puzzle\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le d\u00e9sordre de l\u00a0\u00bbEmpire&rsquo;, \u00ab\u00a0fa\u00e7on puzzle\u00a0\u00bb<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Erdogan fait beaucoup parler de lui, en ce moment. &bull; Il  serait plut\u00f4t dans le camp des contestataires avec notamment <strong>son formidable geste de refuser les condol\u00e9ances des USA<\/strong> pour les victimes de l&rsquo;attentat d&rsquo;Istanboul la semaine derni\u00e8re. &bull; <strong>Rarement, l'\u00a0\u00bbEmpire\u00a0\u00bb aura essuy\u00e9 un affront pareil<\/strong>, dans ses entreprises de terrorisme et de d\u00e9stabilisation <strong>qui devraient imposer respect, admiration et all\u00e9geance<\/strong>. &bull; Pendant ce temps, Zelenski marque contre son camp (du Bien) <strong>en votant contre Isra\u00ebl \u00e0 l&rsquo;ONU<\/strong>.&bull; En toutes choses, il s&rsquo;agit du \u00ab\u00a0d\u00e9sordre de l\u00a0\u00bbEmpire'\u00a0\u00bb, <strong>sans but et sans fin<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&lsquo;<em>Ukrisis<\/em>&lsquo; bouillonne dans tous les sens, et l&rsquo;on ne peut s&rsquo;en tenir \u00e0 l&rsquo;\u00e9trange \u00e9pop\u00e9e de Kherson, qui continue \u00e0 entretenir un certain  myst\u00e8re, tandis que les arm\u00e9es lib\u00e9ratrices font la chasse aux &lsquo;collabos&rsquo; apr\u00e8s avoir priv\u00e9 les journalistes \u00ab\u00a0convenables\u00a0\u00bb (CNN, par exemple) de toute accr\u00e9ditation sur place. La presse libre am\u00e9ricaniste-occidentaliste ne t\u00e9moigne des horreurs commises par les russes que sous le consentement des victimes, et l&rsquo;affaire ukrainienne ne cesse de reculer les domaines d&rsquo;intervention de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a>&#8230;<\/p>\n<\/p>\n<p><p>En attendant, nous avons quitt\u00e9 Kherson, class\u00e9 \u00ab\u00a0victoire historique\u00a0\u00bb, pour des domaines bien plus larges, au-del\u00e0 des fronti\u00e8res. Erdogan et la Turquie, actuellement, y r\u00e8gnent en ma&icirc;tres du jeu, \u00e0 la plus grande satisfaction de Poutine. L&rsquo;attentat de la semaine derni\u00e8res (20 morts et bless\u00e9s dans une rue commer\u00e7ante d&rsquo;Istanboul) constitue d\u00e9sormais un redoutable exercice de communication qui se fiche en plein c&oelig;ur de l&rsquo;OTAN, avec notre compl\u00e8te admiration pour les capacit\u00e9s am\u00e9ricaniste d&rsquo;organisation chronologique et de coordination des \u00e9v\u00e9nements dont on sait qu&rsquo;ils sont les seuls scribes divins autoris\u00e9s&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nous <a href=\"https:\/\/www.dedefensa.org\/article\/valsez-mensonges\">sommes un empire maintenant<\/a> et quand nous agissons nous cr\u00e9ons notre propre r\u00e9alit\u00e9&#8230; <\/em>[&#8230;] <em>Nous sommes <\/em>[les cr\u00e9ateurs] <em>de l&rsquo;histoire&#8230; Et vous, vous tous, il ne vous restera qu&rsquo;\u00e0 \u00e9tudier ce que nous avons <\/em>[cr\u00e9\u00e9]<em>.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Larry Johnson s&rsquo;y emploie et <a href=\"https:\/\/sonar21.com\/angry-turks-talking-turkey-in-turkiye\/\">r\u00e9sume tout cela<\/a> pour nous, et fort bien&#8230; Il reproduit d&rsquo;abord le communiqu\u00e9 turc <a href=\"https:\/\/www.cnnturk.com\/video\/turkiye\/son-dakika-istiklal-caddesinde-pkk-saldirisi-bakan-soylu-abdnin-taziyesini-kabul-etmiyoruz%C2%AD\">repris par la presse du pays<\/a> en m\u00eame temps qu&rsquo;il est diffus\u00e9 officiellement&#8230; On notera la compl\u00e8te absence d&rsquo;ambigu\u00eft\u00e9 des accusations implicitement lanc\u00e9es contre les &Eacute;tats-Unis dont les condol\u00e9ances pour les victimes de l&rsquo;attentat ont \u00e9t\u00e9 refus\u00e9es. (\u00ab\u00a0Geste fort\u00a0\u00bb, dit-on en langage diplomatique, extr\u00eamement fort \u00e0 la limite de l&rsquo;incident diplomatique majeur selon notre estime : ainsi se permet-on d\u00e9sormais d&rsquo;agir avec l\u00a0\u00bbEmpire&rsquo;, comme on s&rsquo;essuie les pieds sur un paillasson ?) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Selon les derni\u00e8res nouvelles, le ministre de l&rsquo;Int\u00e9rieur, S\u00fcleyman Soylu, a d\u00e9clar\u00e9 dans un communiqu\u00e9 apr\u00e8s l&rsquo;explosion survenue dans la rue Istiklal de Taksim \u00e0 Istanbul : \u00ab\u00a0Nous n&rsquo;acceptons pas le message de condol\u00e9ances de l&rsquo;ambassade des &Eacute;tats-Unis. Si nous n&rsquo;avions pas attrap\u00e9 l&rsquo;assaillant, il se serait enfui en Gr\u00e8ce aujourd&rsquo;hui\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Soylu a pr\u00e9cis\u00e9 : \u00ab\u00a0Les op\u00e9rations se poursuivent. Tous nos services de s\u00e9curit\u00e9, nos forces de s\u00e9curit\u00e9 et toutes les unit\u00e9s de renseignement sont en alerte ensemble. Nous avons dit ce que nous allions dire hier soir. Nous savons comment l&rsquo;incident a \u00e9t\u00e9 coordonn\u00e9. Nous savons comment il a \u00e9t\u00e9 coordonn\u00e9. Nous allons enterrer nos corps. <\/em>[&#8230;]<em> Il faut le dire. Nous connaissons le message qui nous a \u00e9t\u00e9 donn\u00e9, nous avons re\u00e7u le message qui nous a \u00e9t\u00e9 donn\u00e9 et nous savons quel est le message qui nous a \u00e9t\u00e9 donn\u00e9. Nous allons r\u00e9pondre par un message tr\u00e8s fort \u00e0 ce message&rsquo;, a-t-il d\u00e9clar\u00e9. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Ensuite, Johnson donne son interpr\u00e9tation, qu&rsquo;il pimente de pr\u00e9cisions et d&rsquo;interpr\u00e9tations de l&rsquo;ancien officier de renseignement qu&rsquo;il est. Une telle interpr\u00e9tation, venant d&rsquo;une telle source, a l&rsquo;avantage de nous dispenser de circonvolutions embarrass\u00e9es pour arriver \u00e0 l&rsquo;\u00e9vidence : une attaque directe des USA contre la Turquie, avec la complicit\u00e9 de la Gr\u00e8ce redevenue depuis la pi\u00e8tre aventure de Tsipras-2015 une colonie absolument bien rang\u00e9e des USA en Europe ! C&rsquo;est bien de ce \u00ab\u00a0message\u00a0\u00bb dont parle Soylu, auquel il sera r\u00e9pondu par un \u00ab\u00a0message\u00a0\u00bb de la m\u00eame eau<\/p>\n<\/p>\n<p><p>Johnson prend la nouvelle de cette hostilit\u00e9 entre la Turquie et les USA quant aux cons\u00e9quences qui sont se seront multiples, d&rsquo;un seul des nombreux points de vue qui la caract\u00e9risent : point de vue de l&rsquo;OTAN, de l&rsquo;entr\u00e9e de la Finlande et de la Su\u00e8de dans l&rsquo;OTAN et ainsi de suite. C&rsquo;est-\u00e0-dire que nous bondissons ainsi de la Mer Noire \u00e0 la Baltique, en passant par l&rsquo;Ukraine \u00e9videmment&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Laissez-moi traduire : la Turquie rend les &Eacute;tats-Unis responsables de l&rsquo;attaque en raison de leur r\u00f4le dans le financement et l&rsquo;armement des Kurdes en Syrie et en Irak. Le gouvernement turc est en guerre contre le Parti des travailleurs kurdes (c&rsquo;est-\u00e0-dire le PKK) depuis les ann\u00e9es 1970. Pour tout vous dire, mon ancien patron au D\u00e9partement d&rsquo;&Eacute;tat, l&rsquo;ambassadeur Morris Busby, et moi-m\u00eame avions \u00e9t\u00e9 engag\u00e9s en 1996 (apr\u00e8s avoir quitt\u00e9 le service du gouvernement am\u00e9ricain) par le gouvernement turc pour produire une \u00e9tude concernant le soutien de la Gr\u00e8ce au PKK. Ce fut un choc, &ndash; nous avions conclu que le gouvernement grec fournissait un soutien financier au PKK, faisant des Grecs un &Eacute;tat sponsor de facto du terrorisme, du moins aux yeux de la Turquie.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La d\u00e9claration du ministre turc de l&rsquo;int\u00e9rieur n&rsquo;est pas une simple r\u00e9action passag\u00e8re et \u00e9motionnelle. Il envoie un message clair \u00e0 Biden et \u00e0 son \u00e9quipe<\/em> <em>: nous d\u00e9non\u00e7ons votre compl\u00e8te responsabilit\u00e9. C&rsquo;est une rupture potentielle du processus visant \u00e0 faire entrer deux nouveaux membres de l&rsquo;OTAN dans le giron de l&rsquo;organisation. Cela risque de rendre la Turquie encore plus d\u00e9termin\u00e9e \u00e0 faire pression sur la Su\u00e8de et la Finlande pour qu&rsquo;elles cessent d&rsquo;h\u00e9berger des membres du PKK. Si les deux aspirants \u00e0 l&rsquo;OTAN ne se soumettent pas aux exigences de la Turquie, celle-ci continuera \u00e0 bloquer leur admission. Cela cr\u00e9era un dilemme pour l&rsquo;OTAN. Faire pression sur la Su\u00e8de et la Finlande pour qu&rsquo;elles acc\u00e8dent aux demandes de la Turquie sur la question ou ignorer la Turquie et risquer qu&rsquo;elle se retire de l&rsquo;OTAN.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La Turquie, arrangeuse du Bosphore<\/h3>\n<\/p>\n<p><p>Autre aspect des choses, toujours avec la Turquie en vedette super-am\u00e9ricaine, toujours <a href=\"https:\/\/sonar21.com\/angry-turks-talking-turkey-in-turkiye\/\">selon Johnson<\/a>, tr\u00e8s complet l\u00e0-dessus et ayant consult\u00e9 les sources qui importent (Martyanov et &lsquo;<em>TheMoonofAlabama<\/em>&lsquo; [MoA]).<\/p>\n<\/p>\n<p><p>&#8230; Alors qu&rsquo;il nous a montr\u00e9 une Turquie furieuse, qui encaisse et riposte, il nous signale ici une Turquie qui r\u00e8gne en interm\u00e9diaire indispensable. Nul ne s&rsquo;\u00e9tonnera de la contradiction ? Ici, la Turquie prend un coup des USA, le d\u00e9nonce et se dit pr\u00eate \u00e0 riposter ; l\u00e0, elle se montre comme  un maillon n\u00e9cessaire et essentiel pour les entreprises arrangeuses des USA vis-\u00e0-vis de l&rsquo;Ukraine, dans une occurrence qui ne d\u00e9pla&icirc;t point \u00e0 la Russie et qui risque fort d&rsquo;approfondir la m\u00e9fiance entre les USA et leurs amis z\u00e9lenkistes. Dans cette affaire, en liant les deux \u00e9pisodes et bien d&rsquo;autres, le vilain et surtout tr\u00e8s incoh\u00e9rent petit canard ce sont les USA, pas la Turquie. (La Russie, elle, regarde l&rsquo;agitation d&rsquo;un &oelig;il rigolard.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La Turquie semble savourer son influence croissante en tant que courtier politique international. En mai, elle a \u00e9t\u00e9 le th\u00e9\u00e2tre de pourparlers de paix futiles entre la Russie et l&rsquo;Ukraine. Elle a jou\u00e9 un r\u00f4le cl\u00e9 dans la n\u00e9gociation de l&rsquo;accord autorisant l&rsquo;exp\u00e9dition de c\u00e9r\u00e9ales ukrainiennes vers des pays pr\u00e9tendument dans le besoin. Hier (lundi), les chefs de l&rsquo;espionnage russe et am\u00e9ricain se sont rencontr\u00e9s en Turquie :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Des rapports ont circul\u00e9 dans les m\u00e9dias russes sur des discussions secr\u00e8tes am\u00e9ricano-russes accueillies par la Turquie. Le quotidien Kommersant rapporte, en citant des sources anonymes, que la r\u00e9union non annonc\u00e9e se serait tenue lundi dans la capitale turque, Ankara. Selon le quotidien, Moscou a envoy\u00e9 Sergei Narichkine, directeur du Service russe de renseignement ext\u00e9rieur (SVR), aux discussions. Le porte-parole du Kremlin, Dmitri Pechkov, a ensuite confirm\u00e9 aux m\u00e9dias russes que des discussions bilat\u00e9rales avaient eu lieu \u00e0 Ankara, ajoutant qu&rsquo;elles \u00e9taient organis\u00e9es \u00e0 l&rsquo;initiative des &Eacute;tats-Unis. Au d\u00e9but du mois, les m\u00e9dias occidentaux ont rapport\u00e9 que de hauts responsables russes et am\u00e9ricains entretenaient des contacts non d\u00e9clar\u00e9s. Selon le Wall Street Journal, le conseiller am\u00e9ricain \u00e0 la s\u00e9curit\u00e9 nationale, Jake Sullivan, s&rsquo;est entretenu avec Youri Ouchakov, un conseiller principal en politique \u00e9trang\u00e8re du pr\u00e9sident Vladimir Poutine, et avec Nikolai Patrouchev, qui occupe au sein du gouvernement russe la m\u00eame fonction que celle de Sullivan dns l&rsquo;administration Biden.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">L&rsquo;Ukraine \u00e0 l&rsquo;ONU, sabre au clair<\/h3>\n<\/p>\n<p><p>On ne s&rsquo;arr\u00eatera pas l\u00e0 dans notre qu\u00eate du d\u00e9sordre salvateur. A c\u00f4t\u00e9 des p\u00e9rip\u00e9ties turco-am\u00e9ricanistes et autour de la Turquie, on placera une \u00e9quip\u00e9e diplomatique assez inattendue de l&rsquo;Ukraine.<\/p>\n<\/p>\n<p><p>Assez curieusement, ou bien d&rsquo;une fa\u00e7on bien synchronis\u00e9 par les architectes de l&rsquo;inversion du Camp du Bien, l&rsquo;Ukraine a couronn\u00e9 sa \u00ab\u00a0victoire\u00a0\u00bb de Kherson d&rsquo;une \u00e9nigmatique man&oelig;uvre, \u00e0 New York, \u00e0 l&rsquo;ONU et aux d\u00e9pens d&rsquo;Isra\u00ebl que Zelenski courtise assid&ucirc;ment pour obtenir son soutien et des armes. La passe d&rsquo;armes dont on se demande \u00e0 quelle ligne politique elle correspond, a fait un bruit de ferraille que l&rsquo;on entend en g\u00e9n\u00e9ral dans les usines \u00e0 gaz d\u00e9saffect\u00e9es. &lsquo;<em>ZeroHedge.com<\/em>&lsquo; <a href=\"https:\/\/www.zerohedge.com\/geopolitical\/ukraine-votes-favor-sending-israel-international-court-while-begging-weapons\">nous conte<\/a> l&rsquo;aventure dont nous donnons quelques rapides d\u00e9tails assez marquants, comme notamment le teint \u00ab\u00a0livide\u00a0\u00bb de l&rsquo;&Eacute;tat d&rsquo;Isra\u00ebl, selon la phras\u00e9ologie journalistique, commentant la nouvelle de la trahison rocambolesque l&rsquo;Ukraine :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Bien que l&rsquo;Ukraine ait suppli\u00e9 pendant des mois le gouvernement isra\u00e9lien de lui fournir des armes l\u00e9tales dans le cadre de l&rsquo;invasion russe, elle a vot\u00e9 \u00e0 l&rsquo;ONU pour envoyer Isra\u00ebl devant la Cour internationale de justice (CIJ) bas\u00e9e \u00e0 La Haye<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Isra\u00ebl \u00e9tait livide \u00e0 la suite de ce vote et a convoqu\u00e9 l&rsquo;ambassadeur ukrainien pour lui adresser un bl\u00e2me et une r\u00e9primande formels. \u00ab\u00a0Le soutien de l&rsquo;Ukraine \u00e0 la r\u00e9solution de l&rsquo;ONU sur les pratiques isra\u00e9liennes, qui nie les liens entre les Juifs et le Mont du Temple et demande un avis consultatif de la CIJ, est extr\u00eamement d\u00e9cevant\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;envoy\u00e9 isra\u00e9lien Michael Brodsky. \u00ab\u00a0Soutenir des initiatives anti-isra\u00e9liennes \u00e0 l&rsquo;ONU n&rsquo;aide pas \u00e0 \u00e9tablir la confiance\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le vote ukrainien illustre \u00e9galement un certain d\u00e9sordre \u00e0 l&rsquo;int\u00e9rieur du camp z\u00e9lenkiste. T\u00e9moignage et <a href=\"https:\/\/www.timesofisrael.com\/zelensky-aide-says-ukraines-vote-against-israel-at-un-a-grave-mistake\/\">illustration tr\u00e8s vivante<\/a> de ce d\u00e9sordre, cette intervention d&rsquo;un assistant personnel de Zelenski qui attaque et critique violemment le \u00ab\u00a0minist\u00e8re des affaires \u00e9trang\u00e8res de l&rsquo;Ukraine\u00a0\u00bb comme si l&rsquo;on parlait d&rsquo;un pays \u00e9tranger, la Russie par exemple. L\u00e0 aussi, on observe cette tr\u00e8s curieuse fa\u00e7on de f\u00eater la \u00ab\u00a0victoire\u00a0\u00bb de Kherson&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;assistant personnel du pr\u00e9sident ukrainien Zelenski, Alexey Arestovich, a d\u00e9clar\u00e9 dimanche que le r\u00e9cent soutien de l&rsquo;Ukraine \u00e0 une r\u00e9solution des Nations unies contre Isra\u00ebl \u00e9tait \u00ab\u00a0une grave erreur\u00a0\u00bb. Il a d\u00e9clar\u00e9 que \u00ab\u00a0la position du minist\u00e8re ukrainien des Affaires \u00e9trang\u00e8res \u00e9tait illogique et inacceptable\u00a0\u00bb. \u00ab\u00a0Nous nous retrouvons dans le m\u00eame camp que la Russie et l&rsquo;Iran qui nous attaquent, et nous nous \u00e9loignons d&rsquo;Isra\u00ebl, &ndash; que nous voulons comme alli\u00e9\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">D\u00e9sordre dans le d\u00e9sordre, dans le d\u00e9sordre, dans le&#8230;<\/h3>\n<\/p>\n<p><p>On tirera de ces diff\u00e9rents \u00e9pisodes, sans chercher n\u00e9cessairement les causes et arri\u00e8re-pens\u00e9es derri\u00e8re leurs impulsions, plusieurs enseignements constituant la confirmation de ce qu&rsquo;on peut consid\u00e9rer comme des <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a> nouvelles en cours de formation dans l&rsquo;ensemble strat\u00e9gique.<\/p>\n<\/p>\n<p><p>&bull; Le premier point concerne la Turquie. On a ici, indirectement dans tous les cas, la confirmation d&rsquo;une \u00e9volution strat\u00e9gique importante de la Turquie, confirm\u00e9e par <a href=\"https:\/\/www.dedefensa.org\/article\/comme-larrons-en-foire\">l&rsquo;accord avec la Russie<\/a> sur le r\u00f4le de \u00ab\u00a0centre gazier\u00a0\u00bb attribu\u00e9 \u00e0 la Turquie. Cette confirmation se nourrit largement de la violence de la r\u00e9action turque apr\u00e8s l&rsquo;attentat, dont nul ne doute de la nature am\u00e9ricaniste de l&rsquo;impulsion originelle. Ce constat, renforc\u00e9 par <a href=\"https:\/\/www.rt.com\/news\/566399-erdogan-west-attacks-russia\/\">les mots d&rsquo;encouragement<\/a> du pr\u00e9sident turc pour la Russie face aux USA, place de plus en plus la Turquie dans une situation strat\u00e9gique objective, devenant naturelle, d&rsquo;entrer dans la sph\u00e8re eurasiatique contre le monde euroatlantique&#8230; D&rsquo;o&ugrave; l&rsquo;accent mis sur ce qui devient de plus en plus un hiatus strat\u00e9gique, dans le chef de l&rsquo;appartenance de la Turquie \u00e0 l&rsquo;OTAN.<\/p>\n<\/p>\n<p><p>&bull; Le deuxi\u00e8me point concerne la nature absolument terroriste, &ndash; soutien des terrorismes, emploi de m\u00e9thodes terroristes, etc., &ndash; de l&rsquo;action de ce qui fait figure de gouvernement de l\u00a0\u00bbEmpire&rsquo;. Pour le commentateur normalement inform\u00e9, c&rsquo;est une confirmation, pour le commentateur-zombie courant c&rsquo;est un affreux sacril\u00e8ge qui vaudrait excommunication&#8230; Quoi qu&rsquo;il en soit et puisque ce qui est n&rsquo;est pas autrement, c&rsquo;est dans ce sens des USA-terroristes que les Turcs ont per\u00e7u l&rsquo;attentat de la semaine derni\u00e8re, le \u00ab\u00a0message\u00a0\u00bb dont parle le ministre turc de l&rsquo;Int\u00e9rieur. Le constat correspond \u00e0 des remarques de certains commentateurs, concernant des tentatives US terroristes ou\/et de &lsquo;<em>regime change<\/em>&lsquo;, notamment contre <a href=\"https:\/\/www.dedefensa.org\/article\/turquie-et-arabie-exemplaires\">la Turquie et l&rsquo;Arabie<\/a> dont le comportement est en ce moment l&rsquo;objet de toutes les critiques. Cela est l&rsquo;analyse notamment d&rsquo;Alastair Crooke et d&rsquo;Alexander Mercouris, comme <a href=\"https:\/\/www.dedefensa.org\/article\/comme-larrons-en-foire\">on le voit ci-apr\u00e8s<\/a> concernant justement la Turquie :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Effectivement, note Mercouris, les deux pr\u00e9sidents sont conscients du risque qu&rsquo;ils prennent. Si les expressions de \u00ab\u00a0regime change\u00a0\u00bb et de \u00ab\u00a0r\u00e9volution de couleur\u00a0\u00bb ont un sens, contrairement au \u00ab\u00a0hub gazier\u00a0\u00bb, c&rsquo;est aujourd&rsquo;hui, dans les mois qui viennent dans tous les cas, qu&rsquo;il faut y prendre garde<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Cela va rendre l&rsquo;Ouest extr\u00eamement nerveux et je pense qu&rsquo;il faut s&rsquo;attendre dans les prochains mois, tr\u00e8s rapidement, \u00e0 des tentatives de faire tomber Erdogan&#8230; Je crois qu&rsquo;il faut se pr\u00e9parer \u00e0 cette possibilit\u00e9\u00a0\u00bb<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le troisi\u00e8me point embrasse le d\u00e9sordre am\u00e9ricaniste tel qu&rsquo;il se d\u00e9veloppe et interf\u00e8re sur les relations de l\u00a0\u00bbEmpire&rsquo; avec les autres, vassaux, marionnettes ou r\u00e9sistants. Les innombrables variations de ces derniers jours autour de possibles\/probables\/certaines\/confirm\u00e9es prises de contact et rencontres officieuses entre Russie et USA sur des perspectives diverses o&ugrave; pourrait figurer un \u00e9ventuel apaisement du conflit, tout cela <a href=\"https:\/\/www.rt.com\/russia\/566533-us-ukraine-talks-russia\/\">met \u00e0 rude \u00e9preuve les nerfs<\/a> des dirigeants z\u00e9lenskistes et peut en bonne part expliquer l&rsquo;\u00e9trange vote ukrainien, &ndash; d\u00e9sordre plut\u00f4t que recherche d&rsquo;un but politique, &ndash; concernant Isra\u00ebl. Or, et c&rsquo;est bien cela qui est int\u00e9ressant : ces diverses man&oelig;uvres (?) am\u00e9ricanistes illustrent d&rsquo;abord et avant toute chose <a href=\"https:\/\/www.rt.com\/russia\/566533-us-ukraine-talks-russia\/\">une bataille interne<\/a> \u00e0 Washington entre la faction belliciste (<em>neocon <\/em>et Cie) et les faction plus \u00ab\u00a0r\u00e9aliste\u00a0\u00bb dont le g\u00e9n\u00e9ral Milley nous a donn\u00e9 un bel \u00e9cho.  <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> &laquo; <em>Selon des responsables am\u00e9ricains, les messages contradictoires de Washington concernant une solution diplomatique au conflit ukrainien \u00ab\u00a0mettent \u00e0 rude \u00e9preuve<\/em>&#8230; [les] <em>relations\u00a0\u00bb entre Washington et Kiev. Cette situation est encore accentu\u00e9e par l&rsquo;\u00e9mergence d&rsquo;un clivage entre les responsables am\u00e9ricains, certains estimant qu&rsquo;il est trop t\u00f4t pour des pourparlers de paix, tandis que d&rsquo;autres pensent que l&rsquo;hiver offre une chance \u00e0 la diplomatie.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ces derniers ont fait pression sur leurs homologues \u00e0 Washington pour qu&rsquo;ils consid\u00e8rent cette opportunit\u00e9 &quot;plus s\u00e9rieusement&quot;, mais ils n&rsquo;ont pas r\u00e9ussi jusqu&rsquo;\u00e0 pr\u00e9sent \u00e0 convaincre le pr\u00e9sident am\u00e9ricain Joe Biden et de nombreux membres de son administration, indique le rapport<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le d\u00e9sordre am\u00e9ricaniste touche aussi bien les rapports des USA avec ses vassaux et ses oblig\u00e9s corrompus que ses ennemis quant au sens et au but de sa <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>. Plus encore, il touche ses multiples propres centres de pouvoir, agences, bureaucraties, bureaux, d\u00e9partements, etc. Il est tr\u00e8s probable qu&rsquo;aucune information, donc aucune coordination n&rsquo;ont \u00e9t\u00e9 \u00e9tablies entre l&rsquo;attentat d&rsquo;Istanboul, la rencontre entre les directeurs de la CIA et du SVR en Turquie et la tenue du G20 o&ugrave; repr\u00e9sentants US et repr\u00e9sentants turcs seront oblig\u00e9s de se c\u00f4toyer, avec tous les possibles incidents que pourrait provoquer cette corr\u00e9lation. Le d\u00e9sordre am\u00e9ricaniste est quelque chose qui ne se justifie pas ni ne s&rsquo;explique ; il cro&icirc;t et se multiplie sans n\u00e9cessit\u00e9 de s&rsquo;en expliquer.<\/p>\n<\/p>\n<p><p>Arriv\u00e9 au stade o&ugrave; il se trouve, le d\u00e9sordre am\u00e9ricaniste est universaliste, globaliste en un sens, et pourrait effectivement se d\u00e9signer am\u00e9ricaniste-occidentaliste ; il est \u00e0 la fois totalement aveugle et sans possibilit\u00e9 de freinage, compl\u00e8tement indiff\u00e9rent \u00e0 ses contradictions par rapport \u00e0 son origine et \u00e0 ses effets. Si demain, un accord de cessez-le-feu \u00e9tait pass\u00e9 en Ukraine, &ndash; chose bien improbable mais prenons l\u00e0 pour r\u00e9f\u00e9rence th\u00e9orique, &ndash; on pourra se demander \u00e0 quoi ont servi ces efforts \u00e9chevel\u00e9s d&rsquo;armement, de simulacres, ces d\u00e9vastations, ce saccage des politiques et des liens internationaux. &laquo; <em>A d\u00e9truire l&rsquo;Europe <\/em>&raquo;, r\u00e9pondait Christoforou, ce qui est une absurdit\u00e9 puisque, dans ce cas, l&rsquo;Europe est partie int\u00e9grante de l\u00a0\u00bbordre&rsquo; am\u00e9ricaniste-occidentaliste, et que sa destruction implique une destruction d&rsquo;une partie de soi-m\u00eame. Pourtant, dira-t-on comme dans un r\u00eave, le but \u00e9tait clair et net : d\u00e9truire la puissance russe, chasser Poutine et &lsquo;<em>regime change<\/em>&lsquo;, cela dans un laps de temps record (quelques semaines). Voyez ce qu&rsquo;il en reste&#8230;<\/p>\n<\/p>\n<p><p>Il reste que l&rsquo;ordre r\u00e8gne \u00e0 Moscou, et le d\u00e9sordre \u00e0 Washington. Que faire maintenant ? Continuer sans rel\u00e2che, comme il est fait sans aucune restriction ni r\u00e9f\u00e9rence depuis 1989-1991. Ne rien apprendre de ce qu&rsquo;on fait et poursuivre dans ce m\u00eame tourbillon. Il en na&icirc;tra bien une Chute Finale.<\/p>\n<\/p>\n<p><p>Mis en ligne le 15 novembre 2022 \u00e0 15H30<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9sordre de l\u00a0\u00bbEmpire&rsquo;, \u00ab\u00a0fa\u00e7on puzzle\u00a0\u00bb &bull; Erdogan fait beaucoup parler de lui, en ce moment. &bull; Il serait plut\u00f4t dans le camp des contestataires avec notamment son formidable geste de refuser les condol\u00e9ances des USA pour les victimes de l&rsquo;attentat d&rsquo;Istanboul la semaine derni\u00e8re. &bull; Rarement, l&rsquo;\u00a0\u00bbEmpire\u00a0\u00bb aura essuy\u00e9 un affront pareil, dans ses&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2998,3104,21832,2631,21833,3737,2774,4447,3478,8798,2726,13768,1267,2613,1296,13670,2804],"class_list":["post-80410","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-change","tag-cia","tag-condoleance","tag-de","tag-directeurs","tag-erdogan","tag-israel","tag-kurdes","tag-onu","tag-refus","tag-regime","tag-svb","tag-terrorisme","tag-turquie","tag-ukraine","tag-ukrisis","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80410"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80410\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}