{"id":80447,"date":"2022-12-16T17:09:40","date_gmt":"2022-12-16T17:09:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/12\/16\/qatargate-corrupteur-du-pe\/"},"modified":"2022-12-16T17:09:40","modified_gmt":"2022-12-16T17:09:40","slug":"qatargate-corrupteur-du-pe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/12\/16\/qatargate-corrupteur-du-pe\/","title":{"rendered":"\u2018<em>Qatargate<\/em>&lsquo;, corrupteur du PE\u00a0!"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&lsquo;<em>Qatargate<\/em>&lsquo;, corrupteur du PE !<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Effectivement, le PE, nom-pr\u00e9nom Parlement-Europ\u00e9en, se promenait joyeusement, comme le gentil chaperon rouge, quand l&rsquo;immonde Corrupteur-des-Grands-Chemins (le &lsquo;<em>Qatargate<\/em>&lsquo;)<strong> a hautement attent\u00e9 \u00e0 sa vertueuse pudeur<\/strong>. &bull; Et l&rsquo;on ose dire que le PE et ses h\u00e9ro\u00efques parlementaires sont corrompu.es ? Il ne faudrait <strong>tout de m\u00eame pas inverser r\u00f4les et vices !<\/strong> &bull; Dans son texte pour  RT.com, Rachel Marsden nous conte l&rsquo;\u00e9tonnante <strong>aventure de l&rsquo;attaque de la Corruption lanc\u00e9e contre l&rsquo;incorruptible PE<\/strong> : s&rsquo;il a c\u00e9d\u00e9, c&rsquo;est parce que \u00e7a glissait.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>\u00ab\u00a0PE\u00a0\u00bb ? C&rsquo;est du Parlement Europ\u00e9en que nous parlons, qui est sous le coup d&rsquo;une incroyable attaque d&rsquo;un ennemi innommable, &ndash; mais qu&rsquo;il faut bien nommer : la corruption. En effet, dans les proclamations indign\u00e9es des parlementaires (femmes &#038; hommes, avantage aux premi\u00e8res), la corruption c&rsquo;est l&rsquo;ennemi, une sorte de Poutine si vous voulez, donc l&rsquo;agresseur qui attaque tra&icirc;treusement et compl\u00e8tement \u00e0 l&rsquo;insu de leur plein gr\u00e9, les h\u00e9ro\u00efques et vertueux.ses parlementaires.<\/p>\n<\/p>\n<p><p>Si vous lisez comme il faut l&rsquo;article persifleur de Rachel Marsden, c&rsquo;est bien de cette fa\u00e7on qu&rsquo;il faut comprendre l&rsquo;aventure. Le PE, si vous voulez, c&rsquo;est l&rsquo;Ukraine, o&ugrave; vivait paisiblement une population laborieuse et vertueuse, pour le plus grand bien de ses d\u00e9mocratiques \u00e9lecteurs. Soudain, sur la fronti\u00e8re ainsi contest\u00e9e, se dresse un envahisseur immonde : Poutine ! Non, pardon, la Corruption, et bien entendu c&rsquo;est la m\u00eame chose.<\/p>\n<\/p>\n<p><p>Lisez donc comment Marsden, la fine muche, introduit son appr\u00e9ciation de la situation \u00e0 l&rsquo;occasion de la citation de la pr\u00e9sident.e du PE, &ndash; dame Roberta Mesola, &ndash;qui vient d&rsquo;\u00eatre priv\u00e9e, comme si on lui arrachait un de ses mille visages de gorgone comme on est amput\u00e9 de son bras droit, de l&rsquo;une de ses 15-20 vice-pr\u00e9sident.es. Il s&rsquo;agit de la pin-up grecque <a href=\"https:\/\/www.dedefensa.org\/article\/cherche-verite-desesperement-obstinement\">Eva Kaili<\/a>, avec son sac Herm\u00e8s charg\u00e9 de quelques centaines de de liasses, de &euro;mille et de &euro;mille comme l&rsquo;on dit, \u00e0 propos de laquelle nous \u00e9crivions :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; [Les Eva &#038; Cie] <em>ne peinent<\/em>[-ils] <em>pas trop \u00e0 porter les valises pleines de billets (&euro;600 000, ont calcul\u00e9 les pandores belges) que les Qataris font distribuer lorsque l&rsquo;on entend clamer \u00e0 la tribune les vertus d\u00e9mocratiques de l&rsquo;organisateur de la Coupe du Monde du Football ?<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et Rachel nous r\u00e9pond, en citant ses sources, pour bien marteler qu&rsquo;effectivement le drame doit \u00eatre interpr\u00e9t\u00e9 de cette fa\u00e7on. Le compte-rendu de police nous dira que le PE, perdu comme le petit  chaperon rouge dans la for\u00eat, et soudain la m\u00e9chante Corruption, au visage de Poutine et aux dents pleines de &euro;mille et de &euro;mille, se pr\u00e9cipitant sur lui ou sur elle, s&rsquo;acharnant, malmenant sa vertu et outrageant sa conscience !<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La pr\u00e9sidente du Parlement europ\u00e9en, Roberta Metsola, a d\u00e9peint le scandale comme quelque chose qui arrive \u00e0 l&rsquo;UE, plut\u00f4t qu&rsquo;un ph\u00e9nom\u00e8ne dont elle est r\u00e9ellement responsable ou dont elle doit r\u00e9pondre par ses pratiques syst\u00e9miques au pire ou par son manque de garanties li\u00e9es au lobbying au mieux. \u00ab\u00a0Ne vous y trompez pas : le Parlement europ\u00e9en, chers coll\u00e8gues, est attaqu\u00e9. La d\u00e9mocratie europ\u00e9enne est attaqu\u00e9e. Et notre fa\u00e7on de<\/em> [faire fleurir] <em>des soci\u00e9t\u00e9s d\u00e9mocratiques libres est attaqu\u00e9e\u00a0\u00bb, a d\u00e9clar\u00e9 Metsola<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Redevenant s\u00e9rieuse, Marsden nous explique donc ce qu&rsquo;il en est : ces gens et gentes dames sont fort m\u00e9content.es qu&rsquo;on puisse ainsi les qualifier de \u00ab\u00a0corrompu.es\u00a0\u00bb, tandis qu&rsquo;il est \u00e9vident que ce m\u00e9contentement n&rsquo;a pas de raison d&rsquo;\u00eatre. On dit alors, pour laver le coupable de tout soup\u00e7on d\u00e9plac\u00e9, \u00ab\u00a0scandale du Qatar\u00a0\u00bb, ou &lsquo;<em>Qatargate<\/em>&lsquo; : ne serait-ce pas plut\u00f4t \u00ab\u00a0scandale au Parlement\u00a0\u00bb, ou &lsquo;<em>PEgate<\/em>&lsquo;, non ? Dire qu&rsquo;il faut encore expliquer cette sorte de chose&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les commentaires de Metsola font \u00e9cho aux rapports de la presse grand public faisant r\u00e9f\u00e9rence \u00e0 un scandale de \u00ab\u00a0corruption du Qatar&quot; au sein de l&rsquo;UE alors qu&rsquo;il faut consid\u00e9rer qu&rsquo;il s&rsquo;agit avant tout d&rsquo;un probl\u00e8me de corruption de l&rsquo;Union europ\u00e9enne. En rejetant la faute sur le Qatar, l&rsquo;UE se d\u00e9charge de ses responsabilit\u00e9s et donne la fausse impression que les probl\u00e8mes commencent et se terminent avec un seul pays<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans tous les cas, si l&rsquo;on veut une explication qui tranche tout, s&rsquo;adresser \u00e0 la von der Layen (orthographe r\u00e9form\u00e9e). Elle a donn\u00e9 une conf\u00e9rence de presse pour cela, o&ugrave; elle allait tout expliquer, &ndash; mais il est vrai que son c&oelig;ur \u00e9tait loin de toutes ces embrouilles, plut\u00f4t du c\u00f4t\u00e9 de Kiev et de Mister Z. Rachel nous rapporte quelques \u00e9chos de la conf\u00e9rence de presse comme si elle s&rsquo;y \u00e9tait trouv\u00e9e, et sans doute y \u00e9tait-elle en pens\u00e9e.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Lorsque Mme von der Leyen a eu l&rsquo;occasion d&rsquo;aborder la question avec la presse bruxelloise lundi, elle a fait obstruction aux journalistes<\/em>&#8230; [&#8230;] <em>Selon Politico, un journaliste a m\u00eame cri\u00e9 \u00e0 Mme von der Leyen au moment o&ugrave; elle partait : \u00ab\u00a0Vous n&rsquo;avez pas r\u00e9pondu \u00e0 une seule de nos questions\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Si l&rsquo;on admet ais\u00e9ment la possibilit\u00e9 d&rsquo;une vaste <a href=\"https:\/\/southfront.org\/qatargate-optical-illusion-that-hides-the-proxy-wars-in-north-africa\/\">machination g\u00e9opolitique<\/a> impliquant notamment l&rsquo;UE, le Qatar, le Maroc et la France comme pris dan tourbillon tournant aussi rondement qu&rsquo;un ballon autour de la Coupe du Monde, on admettra tout aussi ais\u00e9ment pour notre compte que l&rsquo;essentiel ici est de nous faire d\u00e9couvrir sans fard la psychologie schizophr\u00e9nique des troupes de l&rsquo;Union Europ\u00e9enne, et particuli\u00e8rement  du PE, disons \u00e0 la mesure de son inutilit\u00e9 et de l&rsquo;extraordinaire toxicit\u00e9 de ses actions de communication et d&rsquo;influence. Cette schizophr\u00e9nie est du mod\u00e8le g\u00e9n\u00e9ral utilis\u00e9 pour la sorte de simulacre qui fait (notamment) appr\u00e9cier les \u00e9v\u00e9nements de l&rsquo;Ukraine, et &lsquo;<em>Ukrisis<\/em>&lsquo; en g\u00e9n\u00e9ral, comme l&rsquo;UE et toutes ses \u00e9minences l&rsquo;appr\u00e9cient, avec cette m\u00eame d\u00e9formation, cette m\u00eame inversion de la perception, cette m\u00eame assurance dans le complet saccage de la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de l&rsquo;\u00e9trange conviction d&rsquo;\u00eatre v\u00e9ritablement la vertu politique m\u00eame, en soi, <em>per se<\/em>. La corruption ne saurait y na&icirc;tre, et elle n&rsquo;y peut p\u00e9n\u00e9trer que par l&rsquo;attaque tra&icirc;tresse d&rsquo;une force ext\u00e9rieure \u00e0 cette Vertu, cette force m\u00e9ritant d&rsquo;ailleurs la majuscule (la Corruption attaquant la Vertu). A la lumi\u00e8re de cette appr\u00e9ciation parabolistique, l&rsquo;objurgation de la pr\u00e9sident.e du PE prend tout son sens : \u00ab\u00a0On nous attaque ! On nous harc\u00e8le !\u00a0\u00bb (Le nombre de femmes politiques dans cette fable politique-wokeniste est consid\u00e9rable.)&#8230; Ou encore :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ne vous y trompez pas : le Parlement Europ\u00e9en, chers coll\u00e8gues, est attaqu\u00e9. La d\u00e9mocratie europ\u00e9enne est attaqu\u00e9e. Et notre fa\u00e7on de<\/em> [faire fleurir] <em>des soci\u00e9t\u00e9s d\u00e9mocratiques libres est attaqu\u00e9e.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bref, cet aspect de l&rsquo;affaire, bien plus que le complot g\u00e9opolitique, nous renvoie dans les m\u00e9andres du soutien aveugle et inconditionnel de l&rsquo;UE \u00e0 Mister Z., et de toutes les autres affaires de cette sorte. Il s&rsquo;agit des m\u00eames valeurs modernes-postmodernes, wokenistes et ainsi de suite, qui sont en jeu, anim\u00e9es par une extraordinaire puissance de la communication orient\u00e9e selon les penchants habituels. Il s&rsquo;agit par cons\u00e9quent, dans la m\u00eame veine, d&rsquo;un grave \u00e9chec du simulacre habituellement \u00e0 l&rsquo;affiche et \u00e0 guichets ferm\u00e9s, le &lsquo;<em>Russiagate<\/em>&lsquo; imit\u00e9 du parti d&rsquo;Hillary Clinton et adapt\u00e9 \u00e0 l&rsquo;UE, qui fait de toutes les infamies de l&rsquo;UE le produit de l&rsquo;infamie perfide de l&rsquo;effroyable (et fort corrompu) Poutine.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit en fait de la m\u00eame aculturation faite \u00e0 la fois d&rsquo;inculture et de croyance dans des comportements primaires avec l&#8217;emploi de mots ronflants et trompeurs. Tout est faux et inverti dans cette danse de Saint-Guy&#8230; Soit ! Mais le r\u00e9sultat, selon l&rsquo;image employ\u00e9e par Rachel Marsden, constitue une preuve absolument \u00e9tourdissante de la puissance du r\u00e9chauffement climatique : faire du &lsquo;<em>Qatargate<\/em>&lsquo; un iceberg !<\/p>\n<\/p>\n<p><p>Rachel Marsden nous conte donc cette aventure haletante ce <a href=\"file:\/\/\/Ne%20vous%20y%20trompez%20pas%20\/%20le%20Parlement%20europeen,%20chers%20collegues,%20est%20attaque.%20La%20democratie%20europeenne%20est%20attaquee.%20Et%20notre%20facon%20de%20%5Bfaire%20fleurir%5D%20des%20societes%20democratiques%20libres%20est%20attaquee\">15 d\u00e9cembre 2022<\/a> en nous montrant qu&rsquo;il ne s&rsquo;agit que de la partie \u00e9merg\u00e9e de l&rsquo;iceberg.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p><em>_________________________<\/em><\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le &lsquo;<em>Qatargate<\/em>&lsquo;, ou la partie \u00e9merg\u00e9e de l&rsquo;iceberg<\/h2>\n<\/p>\n<p><p>Dans un scandale de corruption qui frappe au c&oelig;ur de la gouvernance de l&rsquo;Union europ\u00e9enne, une vice-pr\u00e9sidente du Parlement europ\u00e9en, la Grecque Eva Kaili, a \u00e9t\u00e9 d\u00e9chue de ses responsabilit\u00e9s par le Parlement europ\u00e9en, ses avoirs ont \u00e9t\u00e9 gel\u00e9s et elle a \u00e9t\u00e9 inculp\u00e9e apr\u00e8s que la police a pr\u00e9tendument trouv\u00e9 des &laquo; <em>sacs d&rsquo;argent liquide<\/em> &raquo; \u00e0 son domicile.<\/p>\n<\/p>\n<p><p>Une descente a \u00e9galement eu lieu au domicile d&rsquo;un d\u00e9put\u00e9 europ\u00e9en belge, Marc Tarabella, vice-pr\u00e9sident de la d\u00e9l\u00e9gation de l&rsquo;UE pour les relations avec la p\u00e9ninsule arabe. Les autorit\u00e9s belges ont effectu\u00e9 une autre visite sans pr\u00e9avis au domicile d&rsquo;un assistant d&rsquo;un autre d\u00e9put\u00e9 europ\u00e9en. En d\u00e9but de semaine, les autorit\u00e9s ont fouill\u00e9 les bureaux du Parlement europ\u00e9en comme s&rsquo;il s&rsquo;agissait d&rsquo;une vulgaire sc\u00e8ne de crime, et auraient saisi des donn\u00e9es. Jusqu&rsquo;\u00e0 pr\u00e9sent, 1,5 million d&rsquo;euros ont \u00e9t\u00e9 saisis au domicile de particuliers. Le parquet f\u00e9d\u00e9ral belge accuse les quatre personnes arr\u00eat\u00e9es et inculp\u00e9es de \u00ab\u00a0participation \u00e0 une organisation criminelle, blanchiment d&rsquo;argent et corruption\u00a0\u00bb.  Il s&rsquo;av\u00e8re que les fonctionnaires pr\u00e9sum\u00e9s impliqu\u00e9s sont \u00e9galement accus\u00e9s d&rsquo;avoir fait pression pour que l&rsquo;UE et le Qatar puissent voyager sans visa, et de valoriser le bilan du Qatar en mati\u00e8re de droits du travail.<\/p>\n<\/p>\n<p><p>Pour une institution comme l&rsquo;Union europ\u00e9enne, qui pr\u00eache constamment aux autres pays pour qu&rsquo;ils fassent le m\u00e9nage dans leurs affaires, on pourrait penser qu&rsquo;elle a mis en place des garde-fous solides pour emp\u00eacher le genre de choses que ces accusations all\u00e8guent. Ce n&rsquo;est pas le cas. &laquo; <em>Les all\u00e9gations sont extr\u00eamement pr\u00e9occupantes et tr\u00e8s s\u00e9rieuses<\/em> &raquo;, a d\u00e9clar\u00e9 Ursula von der Leyen, pr\u00e9sidente de la Commission europ\u00e9enne, d&rsquo;un ton inhabituellement mesur\u00e9. Elle a propos\u00e9 la cr\u00e9ation d&rsquo;un organe d&rsquo;\u00e9thique ind\u00e9pendant charg\u00e9 d&rsquo;\u00e9tablir des r\u00e8gles pour les institutions de l&rsquo;UE &laquo; <em>o&ugrave; il existe des r\u00e8gles tr\u00e8s claires<\/em> &raquo;, ajoutant que cela &laquo; constituerait un grand pas en avant &raquo;. Vous voulez dire que cela n&rsquo;existait pas encore ? Pourquoi une telle n\u00e9gligence ?<\/p>\n<\/p>\n<p><p>C&rsquo;est un fait assez stup\u00e9fiant de constater que ceux qui croient que les institutions d\u00e9mocratiques occidentales mettent en pratique ce qu&rsquo;elles ne cessent de pr\u00eacher puissent \u00eatre surpris de d\u00e9couvrir l&rsquo;absence de freins et de contrepouvoir pour pr\u00e9venir la corruption dans ces institutions. Au d\u00e9but de l&rsquo;ann\u00e9e, par exemple, trois repr\u00e9sentants du Congr\u00e8s am\u00e9ricain ont pr\u00e9sent\u00e9 un projet de loi bipartisan visant \u00e0 combler les lacunes permettant le financement \u00e9tranger des groupes de r\u00e9flexion, des responsables gouvernementaux et des \u00e9lections. &laquo; <em>&Agrave; l&rsquo;heure actuelle, les gouvernements \u00e9trangers sont en mesure de financer secr\u00e8tement des groupes de r\u00e9flexion pour promouvoir leurs propres programmes, d&rsquo;engager d&rsquo;anciens fonctionnaires et officiers militaires pour faire pression en faveur de leurs int\u00e9r\u00eats et de demander \u00e0 leurs agents de collecter des millions de dollars pour des campagnes politiques<\/em> &raquo;, a expliqu\u00e9 le parrain du projet de loi, le d\u00e9put\u00e9 Jared Golden.<\/p>\n<\/p>\n<p><p>Tout se passe comme si la corruption syst\u00e9mique \u00e9tait un secret de polichinelle b\u00e9n\u00e9fi\u00e7iant d&rsquo;une <em>omert\u00e0<\/em> sans faille, car bien peu de fonctionnaires semblent vouloir reconna&icirc;tre ou aborder le probl\u00e8me.<\/p>\n<\/p>\n<p><p>Lorsque Mme von der Leyen a eu l&rsquo;occasion d&rsquo;aborder la question avec la presse bruxelloise lundi, elle a tant fait obstruction aux journalistes qu&rsquo;ils n&rsquo;ont pas h\u00e9sit\u00e9 \u00e0 exprimer leur grande frustration sur Twitter. Selon Politico, un journaliste a m\u00eame cri\u00e9 \u00e0 Mme von der Leyen au moment o&ugrave; elle partait : &laquo; <em>Vous n&rsquo;avez pas r\u00e9pondu \u00e0 une seule de nos questions<\/em> &raquo;. Ce n&rsquo;est pas exactement le genre de comportement auquel on pourrait s&rsquo;attendre de la part d&rsquo;une personne qui exige r\u00e9guli\u00e8rement de tenir les autres responsables de la corruption, du manque de transparence et d&rsquo;autres pratiques antid\u00e9mocratiques.<\/p>\n<\/p>\n<p><p>La pr\u00e9sidente du Parlement europ\u00e9en, Roberta Metsola, a d\u00e9peint le scandale comme quelque chose qui arrive \u00e0 l&rsquo;UE, plut\u00f4t qu&rsquo;un ph\u00e9nom\u00e8ne dont l&rsquo;UE est r\u00e9ellement responsable ou dont elle doit r\u00e9pondre par ses pratiques syst\u00e9miques au pire ou par son manque de garanties li\u00e9es au lobbying au mieux. &laquo; <em>Ne vous y trompez pas : le Parlement europ\u00e9en, chers coll\u00e8gues, est attaqu\u00e9. La d\u00e9mocratie europ\u00e9enne est attaqu\u00e9e. Et notre fa\u00e7on de<\/em> [faire fleurir] <em>des soci\u00e9t\u00e9s d\u00e9mocratiques libres est attaqu\u00e9e<\/em> &raquo;, a d\u00e9clar\u00e9 Metsola.<\/p>\n<\/p>\n<p><p>Les commentaires de Metsola font \u00e9cho aux rapports de la presse grand public faisant r\u00e9f\u00e9rence \u00e0 un scandale de \u00ab\u00a0corruption du Qatar\u00a0\u00bb au sein de l&rsquo;UE alors qu&rsquo;il faut consid\u00e9rer qu&rsquo;il s&rsquo;agit avant tout d&rsquo;un probl\u00e8me de corruption de l&rsquo;Union europ\u00e9enne. En rejetant la faute sur le Qatar, l&rsquo;UE se d\u00e9charge de ses responsabilit\u00e9s et donne la fausse impression que les probl\u00e8mes commencent et se terminent avec un seul pays. Combien d&rsquo;autres pays b\u00e9n\u00e9ficieraient en fait d'\u00a0\u00bbaccords de lobbying\u00a0\u00bb similaires avec des personnes occupant des postes de pouvoir politique et d&rsquo;influence \u00e0 Bruxelles ? <\/p>\n<\/p>\n<p><p>Transparency International sugg\u00e8re que ce genre de choses est en fait assez courant. &laquo; <em>Il ne s&rsquo;agit pas d&rsquo;un incident isol\u00e9. Pendant plusieurs d\u00e9cennies, le Parlement a laiss\u00e9 se d\u00e9velopper une culture de l&rsquo;impunit\u00e9, en combinant des r\u00e8gles et des contr\u00f4les financiers laxistes et une absence totale de contr\u00f4le \u00e9thique ind\u00e9pendant (ou m\u00eame inexistant)<\/em> &raquo; a d\u00e9clar\u00e9 le directeur de l&rsquo;ONG, Michiel van Hulten.<\/p>\n<\/p>\n<p><p>Un autre probl\u00e8me de ce fiasco pour l&rsquo;UE est qu&rsquo;il nuit \u00e0 son message souvent r\u00e9p\u00e9t\u00e9 qui fait constamment ressortir deux points. Le premier point est la volont\u00e9 forcen\u00e9e de l&rsquo;Europe de faire croire aux gens qu&rsquo;elle est vertueuse et juste. Ce scandale braque les projecteurs sur une question sordide rang\u00e9e dans un coin sombre que personne n&rsquo;\u00e9voque jamais, et ternit notablement cette aur\u00e9ole qu&rsquo;ils brandissent constamment. Le deuxi\u00e8me point que l&rsquo;UE promeut toujours, &ndash; et que &lsquo;<em>Qatargate<\/em>&lsquo; entrave consid\u00e9rablement, &ndash; est la <em>narrative <\/em>de l&rsquo;UE selon laquelle la Russie est responsable de toutes les blessures auto-inflig\u00e9es de l&rsquo;UE parce que l&rsquo;UE est si innocente et si infiniment comp\u00e9tente, et si digne de confiance, et si exempte d&rsquo;aucun int\u00e9r\u00eat cach\u00e9 ou particulier.<\/p>\n<\/p>\n<p><p>D&rsquo;ailleurs, la corruption pour et dans l&rsquo;UE semble \u00eatre une mati\u00e8re relative sinon marchandable. Elle peut \u00eatre utilis\u00e9e comme monnaie d&rsquo;\u00e9change ou pour augmenter ou diminuer la pression. L&rsquo;Union avait r\u00e9cemment bloqu\u00e9 les fonds destin\u00e9s \u00e0 la Hongrie sous pr\u00e9texte que les institutions du pays sont si fragiles que l&rsquo;argent pourrait servir \u00e0 alimenter la corruption. Mais lorsque la Hongrie a accept\u00e9 de lever son veto \u00e0 l&rsquo;octroi de fonds suppl\u00e9mentaires \u00e0 l&rsquo;Ukraine, les fonds ont soudainement \u00e9t\u00e9 d\u00e9bloqu\u00e9s et les craintes de corruption ont disparu. <\/p>\n<\/p>\n<p><p>Si tout cela n&rsquo;est que la partie visible de l&rsquo;iceberg en ce qui concerne les activit\u00e9s louches de l&rsquo;UE, quelle est la taille r\u00e9elle de l&rsquo;iceberg ? Et quelqu&rsquo;un est-il int\u00e9ress\u00e9 \u00e0 plonger davantage pour le mesurer ?<\/p>\n<\/p>\n<p><h4>Rachel Marsden<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lsquo;Qatargate&lsquo;, corrupteur du PE ! &bull; Effectivement, le PE, nom-pr\u00e9nom Parlement-Europ\u00e9en, se promenait joyeusement, comme le gentil chaperon rouge, quand l&rsquo;immonde Corrupteur-des-Grands-Chemins (le &lsquo;Qatargate&lsquo;) a hautement attent\u00e9 \u00e0 sa vertueuse pudeur. &bull; Et l&rsquo;on ose dire que le PE et ses h\u00e9ro\u00efques parlementaires sont corrompu.es ? Il ne faudrait tout de m\u00eame pas inverser r\u00f4les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2824,21870,13267,3090,21869,3049,5006,4859,3048],"class_list":["post-80447","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-europeen","tag-eva","tag-football","tag-influence","tag-kaili","tag-marsden","tag-parlement","tag-qatar","tag-rachel"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80447"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80447\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}