{"id":80464,"date":"2022-12-30T04:11:25","date_gmt":"2022-12-30T04:11:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2022\/12\/30\/un-destin-pour-medvedev\/"},"modified":"2022-12-30T04:11:25","modified_gmt":"2022-12-30T04:11:25","slug":"un-destin-pour-medvedev","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2022\/12\/30\/un-destin-pour-medvedev\/","title":{"rendered":"Un destin pour Medvedev"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Un destin pour Medvedev<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Beaucoup d&rsquo;agitations ces derniers temps au Kremlin, avec d\u00e9sormais des perspectives d&rsquo;importants changements structurels <strong>pour adapter la Russie \u00e0 une tr\u00e8s longue p\u00e9riode de confrontation<\/strong>. &bull; La Commission Militaro-Industrielle prend une place importante en <strong>organisant une expansion formidable<\/strong> de l&rsquo;industrie de production militaire.&bull; <strong>Un poste tr\u00e8s puissant de vice-pr\u00e9sident est cr\u00e9\u00e9<\/strong>, le pr\u00e9sident Poutine ayant d&rsquo;autres occupations. &bull; Medvedev occupe ce nouveau poste d&rsquo;o&ugrave; il pr\u00e9parerait <strong>sa succession de Poutine, voulue pour 2024<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>\u00ab\u00a0Beaucoup d&rsquo;agitations ces derniers temps au Kremlin\u00a0\u00bb, autour de Poutine, autour de Medvedev aussi et de son voyage \u00e0 P\u00e9kin, etc. Enfin, il y a une d\u00e9cision jug\u00e9e importante de restructuration de la Commission du pouvoir supr\u00eame qui supervise l&rsquo;industrie militaire et la s\u00e9curit\u00e9, qui indique l&rsquo;installation de la Russie et de son pouvoir dans une p\u00e9riode longue, tr\u00e8s longue de confrontation avec l'\u00a0\u00bbOuest collectif\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>On \u00e9coute notamment Alexandre Mercouris (<a href=\"https:\/\/theduran.com\/russia-maintains-bakhmut-pressure-repels-kremennaya-attack-medvedev-armaments-chief-putin-decree\/\">le 28 d\u00e9cembre<\/a> et <a href=\"https:\/\/theduran.com\/pr-spin-and-peace-proposals-medvedev-to-oversee-military-industry\/\">le 29 d\u00e9cembre<\/a>), particuli\u00e8rement int\u00e9ress\u00e9 par ces perspectives, comme l&rsquo;amorce d&rsquo;un tournant structurel et politique consid\u00e9rable. C&rsquo;est comme si la Russie postcommuniste prenait structurellement et psychologiquement acte de l&rsquo;affrontement qui s&rsquo;est ouvert :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230; <em>Il est clair que les Russes envisagent au moins une d\u00e9cennie ! &#8230;Au moins une d\u00e9cennie de confrontation avec l&rsquo;Ouest, m\u00eame si ce conflit en Ukraine est r\u00e9solu rapidement<\/em> [en 2023-2024]&#8230; <em>Nous sommes dans une guerre tr\u00e8s, tr\u00e8s froide, plus froide qu&rsquo;elle ne l&rsquo;a jamais \u00e9t\u00e9 depuis les ann\u00e9es 1950<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voyons d&rsquo;abord le fait du renforcement radical de la Commission Militaro-Industriel, contr\u00f4lant les affaires de s\u00e9curit\u00e9 nationale, et de l&rsquo;industrie militaire en priorit\u00e9, et l&rsquo;\u00e9volution qui touche la position et les pouvoirs de Medvedev. Il s&rsquo;agit d&rsquo;une r\u00e9forme qui, selon nos commentateurs pr\u00e9f\u00e9r\u00e9s, devrait avoir des dimensions consid\u00e9rables, &ndash; pr\u00e9sent\u00e9e ici d&rsquo;une fa\u00e7on tr\u00e8s neutre par <a href=\"https:\/\/www.rt.com\/russia\/568959-medvedev-military-industrial-commission\/\">RT.com <\/a>:.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;ancien pr\u00e9sident russe Dimitri Medvedev a \u00e9t\u00e9 nomm\u00e9 premier adjoint de la Commission Militaro-Industrielle du pays. Cette fonction a \u00e9t\u00e9 officiellement cr\u00e9\u00e9e lundi par d\u00e9cret pr\u00e9sidentiel par Vladimir Poutine, qui dirige cette commission.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Dans ses nouvelles fonctions, Medvedev, qui est actuellement vice-pr\u00e9sident du Conseil de S\u00e9curit\u00e9 russe, aura le droit de cr\u00e9er des groupes de travail et des conseils qui s&rsquo;occuperont des activit\u00e9s de la Commission Militaro-Industrielle, selon le d\u00e9cret.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ses anciennes fonctions au sein du Conseil de S\u00e9curit\u00e9, consistant \u00e0 superviser les mesures de contr\u00f4le de l&rsquo;industrie de la d\u00e9fense, continueront d&rsquo;\u00eatre exerc\u00e9es dans le cadre de son travail au sein de la commission, a d\u00e9clar\u00e9 l&rsquo;assistant de Medvedev \u00e0 RIA apr\u00e8s la nomination.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La Commission Militaro-Industrielle est un organe permanent qui supervise l&rsquo;industrie de la d\u00e9fense du pays et est charg\u00e9 d&rsquo;organiser la politique de l&rsquo;&Eacute;tat dans les domaines de la garantie des capacit\u00e9s d\u00e9fensives de la Russie, de la s\u00e9curit\u00e9 de l&rsquo;&Eacute;tat et de l&rsquo;application de la loi. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;organe est \u00e9galement charg\u00e9 de veiller \u00e0 ce que l&rsquo;\u00e9conomie russe soit pr\u00e9par\u00e9e \u00e0 la mobilisation et a le droit de passer des commandes publiques dans le domaine de la d\u00e9fense \u00e0 hauteur de 1 000 milliards de roubles (14,6 milliards de dollars) par an<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il faut voir qu&rsquo;il n&rsquo;y a pas \u00e0 proprement parler de changement disons \u00ab\u00a0de format\u00a0\u00bb de la Commission, mais un changement du domaine de l&rsquo;\u00e9tat d&rsquo;esprit. Soudain, cette Commission acquiert une importance consid\u00e9rable et un point essentiel qui la rend si efficace op\u00e9rationnellement, &ndash; et qui la diff\u00e9rencie du Pentagone, &ndash; est que cette ma&icirc;trise, cette orientation et cette expansion consid\u00e9rable de l&rsquo;industrie militaire dans son fonctionnement le plus pr\u00e9cis est directement dans les mains du pouvoir civil. Aux USA, le Pentagone g\u00e8re lui-m\u00eame l&rsquo;industrie militaire, les commandes qu&rsquo;il lui passe, les programmes qu&rsquo;il lui commande, etc. Il n&rsquo;est contr\u00f4l\u00e9 que pour le financement par le Congr\u00e8s qui vote son budget, par des parlementaires dont on sait les liens d&rsquo;affection et de tendresse avec les conseils d&rsquo;administration des grandes soci\u00e9t\u00e9s d&rsquo;armement, et l&rsquo;int\u00e9r\u00eat de ces grandes soci\u00e9t\u00e9s pour leurs \u00e9lections.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Notes de PhG-Bis<\/em><\/strong><em> : &laquo; \u00ab\u00a0On reviendra l\u00e0-dessus\u00a0\u00bb, me confie PhG, qui semble soudain avoir compris quelque chose d&rsquo;important&#8230; Il poursuit : \u00ab\u00a0Il y a l\u00e0 une explication fondamentale qui rejoint en partie, &ndash; en partie seulement, &ndash; ce que James Carroll disait de Gorbatchev et de la chute de l&rsquo;URSS et de son complexe militaro-industriel, son Pentagone, <a href=\"https:\/\/www.dedefensa.org\/article\/regarder-le-monstre-dans-les-yeux\">en juillet 2006<\/a> : &lsquo;Et regardez le plus grand exemple de ce changement, &ndash; il a eu lieu en Union Sovi\u00e9tique, qui s&rsquo;est d\u00e9mantel\u00e9e elle-m\u00eame. Au lieu de tout mettre sur le dos de l&rsquo;ennemi ext\u00e9rieur, elle a fait face \u00e0 ses propres corruptions et s&rsquo;est d\u00e9mantel\u00e9e. Ce grand \u00e9v\u00e9nement du 20e si\u00e8cle, &ndash; la disparition non violente de l&rsquo;Union sovi\u00e9tique, &ndash; est une source d&rsquo;espoir que nous, Am\u00e9ricains, devrions examiner de plus pr\u00e8s.&rsquo; Carroll aurait d&ucirc; pr\u00e9ciser d&rsquo;une fa\u00e7on appuy\u00e9e qu&rsquo;en s&rsquo;\u00e9croulant, l&rsquo;URSS avait fait s&rsquo;\u00e9crouler son propre Pentagone&#8230;\u00a0\u00bb &raquo; <\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>La d\u00e9cision de la nomination, si l&rsquo;on veut, d&rsquo;un \u00ab\u00a0pr\u00e9sident \u00e0 temps plein\u00a0\u00bb de cette Commission (le v\u00e9ritable pr\u00e9sident, Poutine, ayant d&rsquo;autres chats \u00e0 fouetter) r\u00e9sume et synth\u00e9tise \u00e0 elle seule l&rsquo;importance primordiale de la r\u00e9forme. C&rsquo;est-\u00e0-dire qu&rsquo;il y a d\u00e9sormais une direction politique \u00e0 temps plein, qui examine les questions de la production et de l&rsquo;industrie militaire en ayant \u00e0 l&rsquo;esprit l&rsquo;essentiel des questions politiques. Son autorit\u00e9, &ndash; l&rsquo;autorit\u00e9 de la pr\u00e9sidence si l&rsquo;on veut, &ndash; en est renforc\u00e9e ; mais en est renforc\u00e9e aussi l&rsquo;importance devenue fondamentale de cette Commission, en raison de la grande dynamique de d\u00e9veloppement de l&rsquo;industrie militaire exig\u00e9e par la situation politique.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>Pr\u00e9cision de Mercouris : &laquo; <em>Le point essentiel est qu&rsquo;il s&rsquo;agit d&rsquo;un poste<\/em> [vice-pr\u00e9sident] <em>et d&rsquo;une nomination permanentes<\/em> [et non pour la seule guerre d&rsquo;Ukraine] &#8230; <em>C&rsquo;est acte important dans la construction institutionnelle mais c&rsquo;est aussi une d\u00e9monstration de l&rsquo;importance \u00e9norme que la Russie accorde d\u00e9sormais au secteur militaire&#8230; Nous parlons d&rsquo;un \u00e9norme renforcement militaire au soi, du complexe militaro-industriel<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Peut-\u00eatre Mercouris n&rsquo;aurait-il pas d&ucirc; employer l&rsquo;expression de \u00ab\u00a0complexe militaro-industriel\u00a0\u00bb, trop connot\u00e9e, mais l&rsquo;id\u00e9e est bien d&rsquo;organiser une expansion consid\u00e9rable de l&rsquo;industrie militaire. Aux USA, un tel poste, &ndash; celui que Medvedev occupe d\u00e9sormais, &ndash; aurait \u00e9t\u00e9 donn\u00e9 au secr\u00e9taire \u00e0 la d\u00e9fense, ou \u00e0 un de ses adjoints, voire \u00e0 un g\u00e9n\u00e9ral charg\u00e9 au moins de quatre \u00e9toiles. Dans le cas russe, l&rsquo;\u00e9norme effort d&rsquo;expansion de la puissance militaire doit \u00eatre conduite par un homme d&rsquo;&Eacute;tat, qui place avant toutes choses les buts politiques du pays, autant que sa stabilit\u00e9 sociale.<\/p>\n<\/p>\n<p><p>A cette occasion, Mercouris rend un vibrant hommage \u00e0 Medvedev, \u00e9cartant tous les soup\u00e7ons d'\u00a0\u00bbatlanticisme\u00a0\u00bb et de pro-occidentalisme, et en g\u00e9n\u00e9ral de grande mollesse, qui furent souvent soulev\u00e9s \u00e0 son encontre. Il rappelle que c&rsquo;est lui, et lui seul, alors pr\u00e9sident, qui d\u00e9cida de lancer l&rsquo;arm\u00e9e contre la G\u00e9orgie en 2008, avant de proposer en novembre 2008 un accord de s\u00e9curit\u00e9 europ\u00e9enne \u00e0 fort belle allure, \u00e0 un Sarko (alors pr\u00e9sident du Conseil europ\u00e9en) qui s&rsquo;enthousiasma deux jours, dur\u00e9e maximale de sa pens\u00e9e conceptuelle, et rata \u00e9videmment le coche. Ce n&rsquo;est pas nous qui d\u00e9mentirions ce jugement sur sa personnalit\u00e9, comme vous pouviez le lire le <a href=\"https:\/\/www.dedefensa.org\/article\/medvedev-existe-il-a-rencontre-son-911\">13 septembre 2008<\/a>, o&ugrave; nous nous faisions l&rsquo;\u00e9cho d&rsquo;un Medvedev comparant l&rsquo;attaque g\u00e9orgienne du 8 ao&ucirc;t 2008 et la haine antirusse qu&rsquo;elle montrait \u00e0 \u00ab\u00a0son 11-septembre\u00a0\u00bb \u00e0 lui\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Eh bien, au diable ce qu&rsquo;il paraissait \u00eatre&hellip; Medvedev appara&icirc;t dans ces d\u00e9clarations comme beaucoup plus consistant, beaucoup plus humain et solide \u00e0 la fois. Il appara&icirc;t comme un pr\u00e9sident en exercice, \u00ab\u00a0in charge\u00a0\u00bb comme ils disent, prenant des d\u00e9cisions, ayant des avis tranch\u00e9s et parlant sans avoir froid aux yeux. (Les d\u00e9tails qu&rsquo;il donne sur Saakachvili sont r\u00e9v\u00e9lateurs de l&rsquo;humeur et du caract\u00e8re de Medvedev; il le nomme \u00ab\u00a0le gamin\u00a0\u00bb <\/em>[<em>&laquo;&hellip; and the boy changed miraculously&hellip;&raquo;<\/em>]<em> et donne des d\u00e9tails in\u00e9dits, certainement en provenance du renseignement russe, sur les habitudes pathologiques et d&rsquo;accoutumance du pr\u00e9sident g\u00e9orgien.)<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Steele note que Poutine et Medvedev parlent selon la m\u00eame ligne (selon une expression un peu m\u00e9prisante, typiquement anglo-saxonne pour les autres alors que les Anglo-Saxons en usent tant eux-m\u00eames: \u00ab\u00a0from the same script\u00a0\u00bb), &ndash; pour aussit\u00f4t mettre en \u00e9vidence les diff\u00e9rences (\u00ab\u00a0&hellip;though there were important differences between the two\u00a0\u00bb). Diff\u00e9rences de g\u00e9n\u00e9rations, notamment, entre un Poutine qui a eu une partie de sa carri\u00e8re dans l&rsquo;URSS encore existante, et Medvedev pas. Le jeune pr\u00e9sident russe (on r\u00e9alise alors qu&rsquo;il n&rsquo;a que 42 ans) a des mots tr\u00e8s durs pour l&rsquo;URSS, rien de la nostalgie qu&rsquo;on per\u00e7oit chez Poutine. Il n&rsquo;en est que plus frappant que Medvedev soit plus dur que Poutine vis-\u00e0-vis de l&rsquo;attaque du 7 ao&ucirc;t (du 8 ao&ucirc;t), de Saakachvili, de l&rsquo;\u00e9v\u00e9nement et de son caract\u00e8re bouleversant pour lui<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi Mercouris estime-t-il que c&rsquo;est le vrai Medvedev qui s&rsquo;est montr\u00e9, ces derniers mois, d&rsquo;une incroyable fermet\u00e9 contre l&rsquo;Occident, et essentiellement les Anglo-Saxons, qu&rsquo;il conna&icirc;t bien. Certainement, en fait, plus dur que Poutine, plus dur que le diable d\u00e9nonc\u00e9 par l'\u00a0\u00bbOuest collectif\u00a0\u00bb&#8230; Nous n&rsquo;avons pas manqu\u00e9 de mentionner ses sorties furieuses sur son fil &lsquo;<em>Telegram<\/em>&lsquo; (voir par exemple le <a href=\"https:\/\/www.dedefensa.org\/article\/ukrisis-medvedev-super-faucon-nucleaire\">4 juin 2022<\/a>, le <a href=\"https:\/\/www.dedefensa.org\/article\/les-mille-et-une-nuances-de-la-haine\">9 juin 2022<\/a>, le <a href=\"https:\/\/www.dedefensa.org\/article\/le-rebus-puzzle-de-kherson\">13 novembre 2022<\/a>).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">En route pour 2024 ?<\/h3>\n<\/p>\n<p><p>Ainsi et aussi, Mercouris n&rsquo;entretient-il plus gu\u00e8re de doute sur les enjeux et sur les hostilit\u00e9s. Le poste fondamental donn\u00e9 \u00e0 Medvedev, c&rsquo;est un marchepied que lui donne Poutine pour sa succession, parce que Poutine a le jugement s&ucirc;r et conna&icirc;t son homme. D&rsquo;ailleurs, Poutine \u00ab\u00a0rencontre\u00a0\u00bb Xi aujourd&rsquo;hui, en virtuel, comme l&rsquo;ont si bien compris <a href=\"https:\/\/www.dedefensa.org\/article\/posture-de-la-france\">les \u00ab\u00a0experts\u00a0\u00bb fran\u00e7ais<\/a>, et tout cela \u00e9tait bien ordonn\u00e9, selon un bon coup \u00e0 la Poutine qui sent le poids de l&rsquo;\u00e2ge pour 2024&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; [Medvedev] <em>commence \u00e0 ressembler \u00e0 un potentiel successeur de Poutine&#8230; Et le fait qu&rsquo;il ait \u00e9t\u00e9 \u00e0 P\u00e9kin rencontrer Xi seul \u00e0 seul ressemble \u00e0 une sorte de pr\u00e9sentation par Poutine de son successeur au pr\u00e9sident chinois&#8230; Et je ferais bien l&rsquo;hypoth\u00e8se que la lettre de Poutine que Medvedev a donn\u00e9e en mains propres \u00e0 Xi constituait justement l&rsquo;annonce et la pr\u00e9sentation de son successeur<\/em>&#8230; [le porteur de la lettre lui-m\u00eame !] &raquo; (Mercouris)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mercouris, qui annon\u00e7ait d\u00e8s avant-hier cette entretient-surprise Poutine-Xi pour parler de cette affaire et du calendrier, estime que l&rsquo;affaire ukrainienne sera r\u00e9gl\u00e9e en 2023, les Russes se pr\u00e9parant \u00e0 une attaque d\u00e9cisive devant ce qu&rsquo;ils estiment \u00eatre un blocage total de l&rsquo;Ukraine et de sa pantomime de pouvoir par les exigences US, tout cela permettant de faire en Russie des pr\u00e9sidentielles assur\u00e9es et stables,  avec un nouveau pr\u00e9sident, pour entrer \u00ab\u00a0dans le dur\u00a0\u00bb de cette terrible super-Guerre Froide.<\/p>\n<\/p>\n<p><p>Mis en ligne le 30 d\u00e9cembre 2022 \u00e0 04H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un destin pour Medvedev &bull; Beaucoup d&rsquo;agitations ces derniers temps au Kremlin, avec d\u00e9sormais des perspectives d&rsquo;importants changements structurels pour adapter la Russie \u00e0 une tr\u00e8s longue p\u00e9riode de confrontation. &bull; La Commission Militaro-Industrielle prend une place importante en organisant une expansion formidable de l&rsquo;industrie de production militaire.&bull; Un poste tr\u00e8s puissant de vice-pr\u00e9sident est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[13657,3977,4903,3106,3535,21896,3084,3340,21897,13670,12236],"class_list":["post-80464","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-13657","tag-chine","tag-conseil","tag-froide","tag-industrielle","tag-militao-industriel","tag-mobilisation","tag-presidentielles","tag-super-guerre","tag-ukrisis","tag-xi"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80464"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80464\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}