{"id":80467,"date":"2023-01-01T12:12:53","date_gmt":"2023-01-01T12:12:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/01\/la-guerre-globaliste-en-marche\/"},"modified":"2023-01-01T12:12:53","modified_gmt":"2023-01-01T12:12:53","slug":"la-guerre-globaliste-en-marche","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/01\/la-guerre-globaliste-en-marche\/","title":{"rendered":"La guerre globaliste en marche"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La guerre globaliste en marche<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; La guerre par \u00ab\u00a0proxy\u00a0\u00bb de Washington en Ukraine est un projet globaliste pour transcender la continuit\u00e9 de l&rsquo;histoire, de la culture et de la g\u00e9ographie incarn\u00e9e par l&rsquo;&Eacute;tat-nation. &bull; Contribution du colonel Douglas Macgregor.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cet article d\u00e9j\u00e0 paru en mai de cette ann\u00e9e, est repris le <a href=\"https:\/\/www.veteranstoday.com\/2022\/12\/29\/the-war-for-globalism-in-ukraine\/\">29 d\u00e9cembre 2022<\/a> dans &lsquo;<em>Veterans Today<\/em>&lsquo;. L&rsquo;auteur est le tr\u00e8s fameux colonel Macgregor, quasiment le meilleur analyste de la situation en Ukraine. (Il n&rsquo;est publi\u00e9 ni dans le New York &lsquo;<em>Times<\/em>&lsquo;, ni dans le Washington &lsquo;<em>Post<\/em>&lsquo;, ni dans l&rsquo;im-&lsquo;<em>Monde<\/em>&lsquo;, &ndash; Dieu soit lou\u00e9 et Ainsi Soit-Il.)<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui, cet article d\u00e9j\u00e0 pr\u00e9monitoire \u00e9claire comme un soleil la crise en cours. Et le colonel Macgregor se r\u00e9v\u00e8le, ou se confirme, comme bien autre chose qu&rsquo;un officier haut grad\u00e9 de l&rsquo;US Army pass\u00e9 \u00e0 l&rsquo;honneur de la R\u00e9sistance. Il a aussi une vue per\u00e7ante de la situation m\u00e9tahistorique.<\/p>\n<\/p>\n<p><p>Il faut revenir en d\u00e9tails sur l&rsquo;article, l&rsquo;homme et les circonstances : on le fait dans <a href=\"https:\/\/www.dedefensa.org\/article\/traitre-au-systeme-ou-a-la-nation\">un autre texte du jour<\/a>. L&rsquo;US Army perd toutes ses guerres mais sait fabriquer de beaux rebelles.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La guerre du globalisme en Ukraine<\/h2>\n<\/p>\n<p><p>Au cours de la campagne a\u00e9rienne de 1999 au Kosovo, le pr\u00e9sident Bill Clinton avait d\u00e9clar\u00e9 \u00e0 l&rsquo;intention des Am\u00e9ricains : &laquo; Voil\u00e0 de quoi il s&rsquo;agit dans cette affaire du Kosovo&#8230;. C&rsquo;est le globalisme contre le tribalisme. &raquo;<\/p>\n<\/p>\n<p><p>En 1999, tr\u00e8s peu d&rsquo;Am\u00e9ricains ont pr\u00eat\u00e9 attention aux remarques de Clinton. Le Kosovo \u00e9tait un conflit de plus sur le sol d&rsquo;un autre pays, avec peu ou pas de rapport avec la vie quotidienne en Am\u00e9rique. Franchement, l&rsquo;utilisation par Clinton du mot \u00ab\u00a0tribalisme\u00a0\u00bb a probablement d\u00e9rout\u00e9 de nombreux Am\u00e9ricains. Pour la plupart des Am\u00e9ricains, le nationalisme signifie <a href=\"https:\/\/www.heritage.org\/conservatism\/commentary\/the-problem-nationalism\">la d\u00e9votion au pays<\/a>, la disposition du citoyen am\u00e9ricain, en cas de crise ou de conflit, \u00e0 placer les besoins du pays au-dessus de ceux du citoyen. Les nationalistes am\u00e9ricains ne sont pas tribaux. Ils veulent prot\u00e9ger et d\u00e9fendre les &Eacute;tats-Unis, leurs institutions historiques et les droits consacr\u00e9s par leurs lois, et <a href=\"https:\/\/www.amazon.com\/Case-Nationalism-Rich-Lowry\/dp\/0062839640\">non d\u00e9clencher des guerres<\/a>.<\/p>\n<\/p>\n<p><p>Le terme \u00ab\u00a0globalisme\u00a0\u00bb a <a href=\"https:\/\/fee.org\/articles\/is-good-globalism-being-undermined-by-bad-globalism\/\">depuis \u00e9volu\u00e9<\/a> pour signifier bien plus que le libre-\u00e9change et la courtoisie entre les nations. Aujourd&rsquo;hui, l&rsquo;&Eacute;tat-nation occidental et le nationalisme qu&rsquo;il inspire sont condamn\u00e9s par les globalistes comme \u00e9tant les sources de pr\u00e9jug\u00e9s, d&rsquo;exclusivisme et de guerre. R\u00e9trospectivement, l&rsquo;utilisation du terme \u00ab\u00a0globalisme\u00a0\u00bb par Clinton s&rsquo;inscrit dans la continuit\u00e9 de la guerre par procuration de l&rsquo;administration Biden contre la Russie.<\/p>\n<\/p>\n<p><p>Pour la classe politique dirigeante contemporaine de Washington, le globalisme <a href=\"https:\/\/www.theglobalist.com\/united-states-globalism-patriotism-donald-trump\/\">implique davantage<\/a> que l&rsquo;achat de produits fabriqu\u00e9s par une main-d&rsquo;&oelig;uvre bon march\u00e9 dans des pays non occidentaux. Le globalisme dirig\u00e9 par Washington promet d\u00e9sormais la dissolution des formes politiques et sociales traditionnelles de l&rsquo;organisation humaine, &ndash; gouvernements nationaux, fronti\u00e8res, identit\u00e9s, cultures, &ndash; et les remplace par un monde de consommateurs unis uniquement par leur d\u00e9pendance \u00e0 l&rsquo;\u00e9gard de soci\u00e9t\u00e9s amorphes, d&rsquo;organisations non gouvernementales (ONG) non responsables et d&rsquo;institutions supranationales.<\/p>\n<\/p>\n<p><p>En d&rsquo;autres termes, le mondialisme est d\u00e9sormais synonyme de la vision de la gauche progressiste de l&rsquo;ordre de s\u00e9curit\u00e9 international lib\u00e9ral d&rsquo;apr\u00e8s-guerre qui doit s&rsquo;\u00e9tendre pour survivre. La guerre par procuration de Washington en Ukraine est un projet mondialiste visant \u00e0 transcender la continuit\u00e9 de l&rsquo;histoire, de la culture et de la g\u00e9ographie incarn\u00e9e par l&rsquo;&Eacute;tat-nation, afin d&rsquo;homog\u00e9n\u00e9iser des peuples disparates dans le processus d&rsquo;assimilation des changements sociaux et technologiques rapides. En ce sens, <a href=\"https:\/\/www.foxnews.com\/world\/ukraine-concerns-zelenskyy-global-control-russian-nukes\">le r\u00e9cent appel<\/a> du pr\u00e9sident ukrainien Volodymyr Zelenski \u00e0 Washington et \u00e0 ses partenaires strat\u00e9giques pour \u00e9tablir un contr\u00f4le mondial des armes nucl\u00e9aires russes s&rsquo;aligne parfaitement sur la vision mondialiste progressiste de l&rsquo;administration Biden.<\/p>\n<\/p>\n<p><p>Et c&rsquo;est l\u00e0 que r\u00e9side le probl\u00e8me. Les nations et leurs peuples n&rsquo;\u00e9voluent pas dans le vide et ne renoncent pas \u00e0 leur existence sans se battre.<\/p>\n<\/p>\n<p><p>Ces points devraient alerter Washington sur le fait que sa guerre par procuration pour le mondialisme en Ukraine <a href=\"https:\/\/www.foreignaffairs.com\/reviews\/capsule-review\/1981-12-01\/political-pilgrims-travels-western-intellectuals-soviet-union\">implique l&rsquo;identit\u00e9 nationale<\/a>, une force dynamique qui suscite les \u00e9motions humaines les plus profondes. Pourtant, ce ne sont pas seulement deux types de nationalisme, ukrainien et russe, enracin\u00e9s dans la langue, la culture et l&rsquo;histoire, qui sont en conflit. Le globalisme de Washington, sous le couvert de l&rsquo;expansion de l&rsquo;OTAN, remet directement en question l&rsquo;identit\u00e9 et la culture nationales russes. C&rsquo;est le r\u00f4le g\u00e9ographique unique de la Russie, qui relie les civilisations europ\u00e9enne et asiatique, ainsi que sa culture chr\u00e9tienne orthodoxe, &ndash; un syst\u00e8me de croyance consacr\u00e9 par l&rsquo;id\u00e9ologie actuelle de l&rsquo;&Eacute;tat russe et sa politique \u00e9trang\u00e8re et de s\u00e9curit\u00e9, &ndash; qui sont menac\u00e9s.<\/p>\n<\/p>\n<p><p>&Agrave; la lumi\u00e8re des interventions militaires de l&rsquo;OTAN dirig\u00e9es par les &Eacute;tats-Unis dans les Balkans, en Afghanistan et en Irak, il est fondamentalement malhonn\u00eate de pr\u00e9tendre que l&#8217;empi\u00e8tement de l&rsquo;OTAN sur la fronti\u00e8re occidentale de la Russie est b\u00e9nin. Mais il est bien plus dangereux d&rsquo;ignorer la v\u00e9rit\u00e9 selon laquelle, aux yeux de Moscou, l&rsquo;expansion de l&rsquo;OTAN en Ukraine est <a href=\"https:\/\/internationaltimes.it\/putin-calls-out-wests-pedophile-satanic-cult\/\">inextricablement li\u00e9e<\/a> \u00e0 l&rsquo;extension du globalisme \u00e0 la Russie.<\/p>\n<\/p>\n<p><p>Les d\u00e9clarations des secr\u00e9taires d&rsquo;&Eacute;tat et de la d\u00e9fense des &Eacute;tats-Unis selon lesquelles Washington veut <a href=\"https:\/\/www.nytimes.com\/2022\/04\/25\/us\/politics\/ukraine-russia-us-dynamic.html\">\u00ab\u00a0affaiblir\u00a0\u00bb la Russie<\/a> montrent clairement que l'\u00a0\u00bbordre fond\u00e9 sur des r\u00e8gles\u00a0\u00bb pr\u00e9tendument bienveillant de Washington n&rsquo;est d&rsquo;aucune utilit\u00e9 pour la Russie. En fait, ces d\u00e9clarations ne font que confirmer dans l&rsquo;esprit des Russes la conviction que les &Eacute;tats-Unis sont un co-bellig\u00e9rant dans la guerre que m\u00e8ne l&rsquo;Ukraine pour l&rsquo;expansion de l&rsquo;OTAN.<\/p>\n<\/p>\n<p><p>Ce qui est peut-\u00eatre encore plus important, c&rsquo;est <a href=\"https:\/\/www.reuters.com\/world\/europe\/poland-propose-ukraine-peacekeeping-mission-nato-summit-says-pm-2022-03-18\/\">la suggestion que la Pologne<\/a>, l&rsquo;enfant sauvage proverbial de l&rsquo;OTAN, fournisse \u00e0 l&rsquo;Ukraine des forces dites de \u00ab\u00a0maintien de la paix\u00a0\u00bb. Ce n&rsquo;est pas un secret pour les Europ\u00e9ens que la Pologne a domin\u00e9 la majeure partie de l&rsquo;Ukraine pendant pr\u00e8s de 400 ans, ou que la Moldavie, bien que techniquement roumaine, a \u00e9t\u00e9 pendant 300 ans un &Eacute;tat vassal de l&rsquo;Empire ottoman. L&#8217;empressement apparent de Washington \u00e0 introduire des forces polonaises revanchardes en Ukraine occidentale et, potentiellement, des forces roumaines revanchardes en Moldavie sugg\u00e8re que les globalistes de Washington sont <a href=\"https:\/\/www.aljazeera.com\/news\/2022\/4\/29\/putins-middle-finger-to-the-un-sends-clear-message-to-the-west\">pr\u00eats \u00e0 tout<\/a> pour nuire \u00e0 la Russie, m\u00eame si cela implique de faire avancer les ambitions territoriales des ennemis historiques de la Russie.<\/p>\n<\/p>\n<p><p>La guerre met toujours \u00e0 l&rsquo;\u00e9preuve la l\u00e9gitimit\u00e9 de ceux qui gouvernent les &Eacute;tats en guerre, ainsi que la r\u00e9silience de leurs soci\u00e9t\u00e9s. Cette observation s&rsquo;applique autant \u00e0 l&rsquo;administration Biden qu&rsquo;aux gouvernements de Zelenski et de Poutine. Alors qu&rsquo;il pr\u00e9side \u00e0 la crise fiscale, \u00e0 la p\u00e9nurie et \u00e0 la mont\u00e9e de la criminalit\u00e9 en Am\u00e9rique, et qu&rsquo;il affiche son ignorance d\u00e9lib\u00e9r\u00e9e de l&rsquo;Europe de l&rsquo;Est et de ses peuples, le pr\u00e9sident Biden et ses partisans au Congr\u00e8s remuent une marmite r\u00e9gionale qui pourrait rapidement d\u00e9border et avoir des cons\u00e9quences dangereuses pour Washington et ses partenaires de l&rsquo;OTAN. Comme Sigmund Freud <a href=\"https:\/\/www.abebooks.com\/book-search\/title\/thomas-woodrow-wilson-psychological-study\/author\/freud-sigmund-bullitt-william\/\">l&rsquo;a \u00e9crit<\/a> \u00e0 propos du pr\u00e9d\u00e9cesseur \u00ab\u00a0internationaliste\u00a0\u00bb de Biden, Woodrow Wilson, Biden &laquo; a une merveilleuse capacit\u00e9 \u00e0 ignorer les faits et \u00e0 croire ce qu&rsquo;il veut &raquo;. Cependant, il est beaucoup plus difficile aujourd&rsquo;hui qu&rsquo;en 1917 de tromper les Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>Washington a <a href=\"https:\/\/www.foreignaffairs.com\/articles\/russia-fsu\/2014-08-18\/why-ukraine-crisis-west-s-fault\">activement cultiv\u00e9<\/a> la guerre entre l&rsquo;Ukraine et la Russie pendant de nombreuses ann\u00e9es, en mettant le nationalisme ukrainien, &ndash; une force incendiaire que les globalistes pr\u00e9tendent d\u00e9tester, &ndash; au service de leur cause. Cela a fonctionn\u00e9. Aujourd&rsquo;hui, les m\u00eames globalistes <a href=\"https:\/\/www.washingtonexaminer.com\/policy\/defense-national-security\/in-for-the-long-haul-bidens-33-billion-request-foreshadows-extended-war-in-ukraine\">prolongent la guerre<\/a> avec des armes, des conseils et des encouragements, m\u00eame si l&rsquo;Ukraine est d\u00e9truite.<\/p>\n<\/p>\n<p><p>Au cours des 30 derni\u00e8res ann\u00e9es, l&rsquo;importance excessive accord\u00e9e par Washington \u00e0 l&rsquo;assistance et \u00e0 l&rsquo;intervention militaires dans le but de changer de r\u00e9gime a entra&icirc;n\u00e9 les &Eacute;tats-Unis dans des conflits et des crises dans les Balkans, au Proche-Orient, en Afrique du Nord et en Asie du Sud-Ouest. Les <a href=\"https:\/\/news.yahoo.com\/rand-paul-heres-prevent-war-180055675.html\">nationalistes am\u00e9ricains<\/a> ne sont pas responsables de la guerre actuelle en Ukraine ou des trois derni\u00e8res d\u00e9cennies de guerres autodestructrices de Washington. Mais les nationalistes am\u00e9ricains sont plus que jamais n\u00e9cessaires pour arr\u00eater la guerre globaliste <a href=\"https:\/\/www.thenation.com\/article\/world\/ukraine-donbas-russia-conflict\/\">visant \u00e0 d\u00e9truire la Russie<\/a> avant que cette guerre ne se propage comme un cancer en Europe de l&rsquo;Est.<\/p>\n<\/p>\n<p><h4>Douglas Macgregor<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerre globaliste en marche &bull; La guerre par \u00ab\u00a0proxy\u00a0\u00bb de Washington en Ukraine est un projet globaliste pour transcender la continuit\u00e9 de l&rsquo;histoire, de la culture et de la g\u00e9ographie incarn\u00e9e par l&rsquo;&Eacute;tat-nation. &bull; Contribution du colonel Douglas Macgregor. Cet article d\u00e9j\u00e0 paru en mai de cette ann\u00e9e, est repris le 29 d\u00e9cembre 2022&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[1235,4124,2632,2796,4271,13670],"class_list":["post-80467","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-biden","tag-douglas","tag-globalisation","tag-macgregor","tag-nationalisme","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80467"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80467\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}