{"id":80468,"date":"2023-01-02T14:16:47","date_gmt":"2023-01-02T14:16:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/02\/bataille-avec-le-chaos\/"},"modified":"2023-01-02T14:16:47","modified_gmt":"2023-01-02T14:16:47","slug":"bataille-avec-le-chaos","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/02\/bataille-avec-le-chaos\/","title":{"rendered":"Bataille avec le chaos"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Bataille avec le chaos<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Description et interpr\u00e9tation religieuse d&rsquo;un \u00e9v\u00e9nement extraordinaire : la Sainte-Russie partant en guerre contre les arm\u00e9es &lsquo;<em>Collective-West<\/em>&lsquo; de la civilisation du chaos. &bull; Contribution : Alexandre Douguine.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voici un texte du philosophe russe Alexandre Douguine qui d\u00e9veloppe une analyse m\u00e9taphysique de l&rsquo;Op\u00e9ration Militaire Sp\u00e9ciale (OMS) lanc\u00e9e par la Russie en Ukraine. Il l&rsquo;identifie aussit\u00f4t, selon sa d\u00e9marche de g\u00e9opolitique m\u00e9taphysique et ses r\u00e9f\u00e9rences au r\u00f4le spirituel et religieux fondamental de la Russie comme \u00ab\u00a0Troisi\u00e8me Rome\u00a0\u00bb, comme un affrontement de la Russie contre le chaos que repr\u00e9sente l&rsquo;offensive globaliste (voir <a href=\"https:\/\/www.dedefensa.org\/article\/la-guerre-globaliste-en-marche\">le colonel Macgregor<\/a>) de ce qu&rsquo;il nomme \u00ab\u00a0la nouvelle d\u00e9mocratie\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Si nous consid\u00e9rons le probl\u00e8me du chaos dans une perspective philosophique et historique, il devient tout \u00e0 fait clair que l&rsquo;Op\u00e9ration militaire sp\u00e9ciale (OMS) rel\u00e8ve de la lutte de la Russie contre la civilisation du chaos, qui est, en fait, la &quot;nouvelle d\u00e9mocratie&quot;, repr\u00e9sent\u00e9e par l&rsquo;Occident collectif et sa proxy-structure enrag\u00e9e (l&rsquo;Ukraine)<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Douguine temp\u00e8re aussit\u00f4t ce caract\u00e8re de bataille apocalyptique en observant que la Russie n&rsquo;y \u00e9tait absolument pas pr\u00e9par\u00e9e et qu&rsquo;elle a \u00e9t\u00e9 compl\u00e8tement surprise de se trouver engag\u00e9e dans une telle bataille (ce qui peut correspondre assez joliment et avec une habilet\u00e9 dialectique rare \u00e0 une explication op\u00e9rationnelle des difficiles d\u00e9buts de l&rsquo;OMS et des possibles erreurs commises par les Russes dans les premi\u00e8res semaines). Il \u00e9crit ainsi, &ndash; mais avec une r\u00e9serve de notre part puisqu&rsquo;il parle du &laquo; <em>chaos mod\u00e9r\u00e9 du globalisme<\/em> &raquo;, ce qui nous semble tr\u00e8s contradictoire du reste de la description (mais le qualificatif \u00ab\u00a0mod\u00e9r\u00e9\u00a0\u00bb est peut-\u00eatre une erreur, un faux-sens de la traduction)&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&Eacute;videmment, en premi\u00e8re approximation, la Russie n&rsquo;attendait rien d&rsquo;autre que la reconnaissance de sa souverainet\u00e9 en tant qu&rsquo;&Eacute;tat-nation et la protection de ses int\u00e9r\u00eats nationaux, et le fait qu&rsquo;elle ait d&ucirc; affronter le chaos mod\u00e9r\u00e9 du globalisme pour y parvenir a \u00e9t\u00e9 en quelque sorte une surprise pour Moscou, qui a entam\u00e9 l&rsquo;OMS avec des objectifs beaucoup plus concrets et pragmatiques<\/em>. [&#8230;] <em>&#8230;et les dirigeants russes ne s&rsquo;attendaient pas ou m\u00eame ne soup\u00e7onnaient pas une confrontation s\u00e9rieuse avec l&rsquo;institution du chaos, &ndash; surtout sous sa forme aggrav\u00e9e<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Douguine cite encore l&rsquo;une ou l&rsquo;autre faiblesse de la Russie dans cette affaire. S&rsquo;il donne un r\u00f4le m\u00e9taphysique fondamental \u00e0 la Russie dans l&rsquo;absolu, on voit qu&rsquo;il ne porte gu\u00e8re d&rsquo;estime \u00e0 l&rsquo;actuelle direction et \u00e0 l&rsquo;actuelle politique, dont il estime qu&rsquo;elles ne sont pas consciente de l&rsquo;enjeu, m\u00eame si elles y viennent par la force des choses&#8230; Et cette \u00ab\u00a0force des choses\u00a0\u00bb, bien entendu, c&rsquo;est le &laquo; <em>chaos du globalisme<\/em> &raquo;, qui nous semble donc bien ne pas \u00eatre &laquo; <em>mod\u00e9r\u00e9<\/em> &raquo; du tout :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Mais comme l&rsquo;Occident globaliste moderne refuse \u00e0 la Russie toute souverainet\u00e9, m\u00eame relative, il l&rsquo;oblige \u00e0 faire monter les ench\u00e8res sans cesse. Elle se retrouve ainsi dans la position d&rsquo;une soci\u00e9t\u00e9 en r\u00e9bellion contre le monde moderne, contre le chaos \u00e9galitaire, contre la croissance rapide du vide et l&rsquo;acc\u00e9l\u00e9ration de la dissipation<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230;Alors, il fallut bien y aller :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La Russie, &ndash; peut-\u00eatre pas sur la base d&rsquo;un choix clair et conscient, &ndash;s&rsquo;est retrouv\u00e9e en opposition \u00e0 la civilisation du chaos<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On retrouve assez souvent ce pessimisme peut-\u00eatre outrancier de Douguine sur l&rsquo;actuelle direction (ce qui r\u00e9duit \u00e0 une rumeur de salon le r\u00f4le d'\u00a0\u00bb\u00e9minence grise \u00a0\u00bb de Poutine qu&rsquo;on lui fait volontiers jouer). Ainsi lorsqu&rsquo;il parle d&rsquo;une confrontation entre le chaos unipolaire de l'\u00a0\u00bbOuest collectif\u00a0\u00bb et la multipolarit\u00e9 voulu par &laquo; <em>la Russie et ses alli\u00e9s prudents et souvent h\u00e9sitants<\/em> &raquo;, on peut effectivement juger ce propos exag\u00e9r\u00e9ment pessimistes. Les \u00ab\u00a0alli\u00e9s\u00a0\u00bb de la Russie (des Chinois et des Indiens aux Saoudiens, aux Turcs, aux Indon\u00e9siens, etc., et le reste du monde non-OTAN) se r\u00e9v\u00e8lent \u00e0 une vitesse fulgurante qui est le contraire de la prudence et de l&rsquo;h\u00e9sitation, \u00e0 partir d&rsquo;une position attentiste et souvent align\u00e9e sur Washington.<\/p>\n<\/p>\n<p><p>Mais l&rsquo;on retrouve bien ici l&rsquo;exc\u00e8s de la pens\u00e9e m\u00e9taphysique et de la foi de l&rsquo;orthodoxe eurasien qu&rsquo;est Douguine. Il applique effectivement un jugement m\u00e9taphysique sur des \u00e9v\u00e9nements qui ne le sont pas par eux-m\u00eames, et peuvent donc para&icirc;tre fades. Selon nous, l&rsquo;aspect m\u00e9taphysique de la m\u00e9tahistoire ne se manifestent pas bruyamment ; ils existent et se font directement sous nos yeux, &ndash; c&rsquo;est l&rsquo;exceptionnalit\u00e9 tout \u00e0 fait extraordinaire du temps, &ndash; mais notre t\u00e2che ardue est bien entendu de les distinguer au milieu d&rsquo;un chaos de communication&#8230; Ainsi d\u00e9signons-nous les <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> (VdS) qu&rsquo;il s&rsquo;agit d&rsquo;identifier dans un temps courant devenu fou, et nous atteignons ainsi \u00e0 la m\u00e9taphysique.<\/p>\n<\/p>\n<p><p>On dirait que Douguine attend que, dans cette \u00e9poque extraordinaire, la m\u00e9taphysique se manifeste d&rsquo;elle-m\u00eame de l&rsquo;\u00e9v\u00e9nement, comme si l&rsquo;\u00e9v\u00e9nement n&rsquo;\u00e9tait que m\u00e9taphysique ; nous proposons plut\u00f4t l&rsquo;id\u00e9e que le fait extraordinaire de cette \u00e9poque qui l&rsquo;est autant est que l&rsquo;on trouve directement de la m\u00e9taphysique dans l&rsquo;\u00e9v\u00e9nement, mais qu&rsquo;il faut pouvoir l&rsquo;identifier.<\/p>\n<\/p>\n<p><p>Pour le g\u00e9n\u00e9ral, on dira que l&rsquo;analyse de Douguine est extr\u00eamement utile parce qu&rsquo;elle \u00e9l\u00e8ve l&rsquo;\u00e9v\u00e9nement en cours \u00e0 la hauteur qui est la sienne, qui est \u00e9videmment spirituelle.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pour r\u00e9sister \u00e0 la puissance du chaos de mani\u00e8re vraiment efficace, il faut un r\u00e9veil spirituel \u00e0 grande \u00e9chelle, une transformation profonde et un renouveau des fondements, principes et priorit\u00e9s spirituels de l&rsquo;ordre sacr\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il s&rsquo;agit bien d&rsquo;un bouleversement civilisationnel et anthropologique total, et nullement d&rsquo;un simple avatar g\u00e9opolitique de plus. On acceptera ou pas son interpr\u00e9tation religieuse qui lui est propre, ou bien on l&rsquo;acceptera en la discutant, etc., &ndash; cet aspect est pour nous somme toute secondaire, &ndash; m\u00eame s&rsquo;il ne l&rsquo;est \u00e9videmment pas pour Douguine. L&rsquo;essentiel est l&rsquo;interpr\u00e9tation qu&rsquo;il donne de l&rsquo;\u00e9v\u00e9nement perceptible par tous, &ndash; l&rsquo;OMS en Ukraine, &ndash; qui rencontre un sentiment de plus en plus g\u00e9n\u00e9ral qu&rsquo;on se trouve devant ce que nous qualifiions hier (rappel\u00e9 par un de nos lecteurs) de cette fa\u00e7on tumultueuse :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;&#8230; <em>cette \u00ab\u00a0\u00e9poque terrible\u00a0\u00bb que nous vivons<\/em> [&#8230;] <em>d&rsquo;une rupture tectonique des civilisations, un \u00e9v\u00e9nement historique (m\u00e9tahistorique) qui \u00e9gale, et peut-\u00eatre m\u00eame d\u00e9passe tous les plus grands \u00e9v\u00e9nements de l&rsquo;histoire notre civilisation. Nous vivons des temps \u00e9piques et sublimes o&ugrave; le monde historique et le cosmos m\u00e9taphysique basculent dans une \u00e8re nouvelle.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le texte d&rsquo;Alexandre Douguine est en fran\u00e7ais sur &lsquo;<em>euro-synergies ;hautefort.com<\/em>&lsquo; le <a href=\"http:\/\/euro-synergies.hautetfort.com\/archive\/2023\/01\/01\/alexandre-douguine-ordre-katechonique-6419845.html\">1<sup>er<\/sup> janvier 2023<\/a>, venu du texte russe publi\u00e9 sur &lsquo;<em><a href=\"https:\/\/www.geopolitika.ru\/article\/katehonicheskiy-poryadok\">geopolitika.ru<\/a><\/em>&lsquo;.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Ordre kat\u00e9chonique<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">La Russie dans une bataille avec une civilisation du chaos<\/h3>\n<\/p>\n<p><p>Si nous consid\u00e9rons le probl\u00e8me du chaos dans une perspective philosophique et historique, il devient tout \u00e0 fait clair que l&rsquo;Op\u00e9ration militaire sp\u00e9ciale (OMS) rel\u00e8ve de la lutte de la Russie contre la civilisation du chaos, qui est, en fait, la &quot;nouvelle d\u00e9mocratie&quot;, repr\u00e9sent\u00e9e par l&rsquo;Occident collectif et sa proxy-structure enrag\u00e9e (l&rsquo;Ukraine). Les param\u00e8tres de cette civilisation, son profil historique et culturel, son id\u00e9ologie en g\u00e9n\u00e9ral sont assez faciles \u00e0 identifier. Nous pouvons reconna&icirc;tre le mouvement vers le chaos d\u00e8s la premi\u00e8re r\u00e9bellion contre l&rsquo;orbitalit\u00e9, la hi\u00e9rarchie, le volume pyramidal ontologique qui incarnait l&rsquo;ordre de la civilisation traditionnelle. En outre, le d\u00e9sir d&rsquo;horizontalit\u00e9 et d&rsquo;\u00e9galitarisme dans tous les domaines n&rsquo;a fait qu&rsquo;augmenter. Enfin, la &quot;nouvelle d\u00e9mocratie&quot; et le globalisme repr\u00e9sentent le triomphe de syst\u00e8mes chaotiques que l&rsquo;Occident peine encore \u00e0 contr\u00f4ler, mais qui prennent de plus en plus le dessus et imposent leurs propres algorithmes chaotiques \u00e0 l&rsquo;humanit\u00e9. L&rsquo;histoire de l&rsquo;Occident \u00e0 l&rsquo;\u00e9poque moderne et jusqu&rsquo;\u00e0 ce moment est une histoire de la croissance du chaos, &ndash; sa puissance, son intensit\u00e9 et sa radicalit\u00e9. <\/p>\n<\/p>\n<p><p>La Russie, &ndash; peut-\u00eatre pas sur la base d&rsquo;un choix clair et conscient, &ndash;s&rsquo;est retrouv\u00e9e en opposition \u00e0 la civilisation du chaos. Et ceci est devenu un fait irr\u00e9versible et indiscutable imm\u00e9diatement apr\u00e8s le d\u00e9but de l&rsquo;OMS. Le profil m\u00e9taphysique de l&rsquo;adversaire est g\u00e9n\u00e9ralement clair. Mais la question de savoir ce qui constitue la Russie elle-m\u00eame dans ce conflit, et comment elle peut vaincre le chaos, compte tenu de ses fondements ontologiques fondamentaux, est loin d&rsquo;\u00eatre simple. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Quelque chose de bien plus s\u00e9rieux que le r\u00e9alisme <\/h3>\n<\/p>\n<p><p>Nous avons vu que formellement, du point de vue de la th\u00e9orie des relations internationales, il s&rsquo;agit d&rsquo;une confrontation entre deux types d&rsquo;ordre: l&rsquo;unipolaire (l&rsquo;Occident) et le multipolaire (la Russie et ses alli\u00e9s prudents et souvent h\u00e9sitants). Une analyse plus approfondie r\u00e9v\u00e8le que l&rsquo;unipolarit\u00e9 est un triomphe de la &quot;nouvelle d\u00e9mocratie&quot; et donc du chaos, tandis que la multipolarit\u00e9, fond\u00e9e sur le principe des civilisations souveraines, tout en \u00e9tant un ordre, ne r\u00e9v\u00e8le rien sur l&rsquo;essence de l&rsquo;ordre propos\u00e9. En outre, la notion classique de souverainet\u00e9, telle qu&rsquo;elle est comprise par l&rsquo;\u00e9cole r\u00e9aliste des relations internationales, pr\u00e9suppose elle-m\u00eame le chaos entre les &Eacute;tats, ce qui sape le fondement philosophique si nous consid\u00e9rons la confrontation avec l&rsquo;unipolarit\u00e9 et le globalisme comme une lutte pr\u00e9cis\u00e9ment pour l&rsquo;ordre et contre le chaos.<\/p>\n<\/p>\n<p><p>&Eacute;videmment, en premi\u00e8re approximation, la Russie n&rsquo;attendait rien d&rsquo;autre que la reconnaissance de sa souverainet\u00e9 en tant qu&rsquo;&Eacute;tat-nation et la protection de ses int\u00e9r\u00eats nationaux, et le fait qu&rsquo;elle ait d&ucirc; affronter le chaos mod\u00e9r\u00e9 du globalisme pour y parvenir a \u00e9t\u00e9 en quelque sorte une surprise pour Moscou, qui a entam\u00e9 l&rsquo;OMS avec des objectifs beaucoup plus concrets et pragmatiques. L&rsquo;intention des dirigeants russes \u00e9tait uniquement d&rsquo;affirmer le r\u00e9alisme dans les relations internationales contre le lib\u00e9ralisme, et les dirigeants russes ne s&rsquo;attendaient pas ou m\u00eame ne soup\u00e7onnaient pas une confrontation s\u00e9rieuse avec l&rsquo;institution du chaos, &ndash; surtout sous sa forme aggrav\u00e9e. Et pourtant, nous nous trouvons dans cette m\u00eame situation. La Russie est en guerre contre le chaos dans tous les sens de ce ph\u00e9nom\u00e8ne aux multiples facettes, ce qui signifie que toute cette lutte rev\u00eat une nature m\u00e9taphysique. Si nous voulons gagner, nous devons vaincre le chaos. Et cela signifie \u00e9galement que nous nous positionnons d\u00e8s le d\u00e9part comme l&rsquo;antith\u00e8se du chaos, c&rsquo;est-\u00e0-dire comme le commencement qui en est l&rsquo;oppos\u00e9.<\/p>\n<\/p>\n<p><p>C&rsquo;est le bon moment pour revoir les d\u00e9finitions fondamentales du chaos. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Les limites du chaos<\/h3>\n<\/p>\n<p><p>&bull; Premi\u00e8rement, dans l&rsquo;interpr\u00e9tation grecque originale, le chaos \u00e9tait un vide, un territoire o&ugrave; l&rsquo;ordre n&rsquo;a pas encore \u00e9t\u00e9 \u00e9tabli. Bien s&ucirc;r, ce n&rsquo;est pas \u00e0 cela que ressemble le chaos moderne de la civilisation occidentale, &ndash; ce n&rsquo;est pas un vide, au contraire, c&rsquo;est une explosion de mat\u00e9rialit\u00e9 omnipr\u00e9sente; mais face \u00e0 un v\u00e9ritable ordre ontologique, il n&rsquo;est, en effet, rien, sa signification et son contenu spirituel tendent vers z\u00e9ro.<\/p>\n<\/p>\n<p><p>&bull; Deuxi\u00e8mement, le chaos est un m\u00e9lange, et ce m\u00e9lange est bas\u00e9 sur la disharmonie, les conflits d\u00e9sordonn\u00e9s et les affrontements agressifs. Dans les syst\u00e8mes chaotiques, l&rsquo;impr\u00e9visibilit\u00e9 pr\u00e9vaut, car tous les \u00e9l\u00e9ments ne sont pas \u00e0 leur place. La d\u00e9-centricit\u00e9, l&rsquo;excentricit\u00e9 devient le moteur de tous les processus. Les choses du monde se rebellent contre l&rsquo;ordre et tendent \u00e0 renverser toute construction ou structure logique. <\/p>\n<\/p>\n<p><p>&bull; Troisi\u00e8mement, l&rsquo;histoire de la civilisation ouest-europ\u00e9enne r\u00e9v\u00e8le une inflation constante d&rsquo;un degr\u00e9 de chaos, c&rsquo;est-\u00e0-dire une accumulation progressive de chaos, &ndash; comme un vide, une agression par m\u00e9lange et fractionnement de particules de plus en plus petites. Et ceci est accept\u00e9 comme le vecteur moral du d\u00e9veloppement de la civilisation et de la culture. <\/p>\n<\/p>\n<p><p>Le globalisme est le stade final de ce processus, o&ugrave; toutes ces tendances atteignent leur plus haut degr\u00e9 de saturation et d&rsquo;intensit\u00e9. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Le grand vide n\u00e9cessite un grand ordre<\/h3>\n<\/p>\n<p><p>La Russie dans l&rsquo;OMS remet en question l&rsquo;ensemble de ce processus &#8211; m\u00e9taphysique et historique. Par cons\u00e9quent, dans tous les sens, il parle au nom d&rsquo;une alternative au chaos.<\/p>\n<\/p>\n<p><p>Cela signifie que la Russie doit proposer un mod\u00e8le capable de combler ce vide croissant. De plus, le volume du vide est corr\u00e9l\u00e9 \u00e0 la force et \u00e0 la puissance int\u00e9rieure de l&rsquo;ordre qui pr\u00e9tend le remplacer. Un grand vide n\u00e9cessite un grand ordre. En fait, elle correspond \u00e0 l&rsquo;acte de naissance d&rsquo;Eros ou de Psych\u00e9 entre le Ciel et la Terre. Ou le ph\u00e9nom\u00e8ne de l&rsquo;homme comme m\u00e9diateur entre les principaux p\u00f4les ontologiques. Nous avons affaire \u00e0 une nouvelle cr\u00e9ation, \u00e0 une affirmation de l&rsquo;ordre l\u00e0 o&ugrave; il n&rsquo;existe plus, l\u00e0 o&ugrave; il a \u00e9t\u00e9 renvers\u00e9.<\/p>\n<\/p>\n<p><p>Pour \u00e9tablir l&rsquo;ordre dans une telle situation, il est n\u00e9cessaire de soumettre les \u00e9l\u00e9ments lib\u00e9r\u00e9s de la mat\u00e9rialit\u00e9. C&rsquo;est-\u00e0-dire faire face aux torrents d&rsquo;un pouvoir fragment\u00e9 et fractur\u00e9, vaincre les r\u00e9sultats d&rsquo;un \u00e9galitarisme port\u00e9 \u00e0 sa limite logique. Par cons\u00e9quent, la Russie doit \u00eatre inspir\u00e9e par un principe c\u00e9leste sup\u00e9rieur qui est seul capable de soumettre la r\u00e9bellion chtonique. <\/p>\n<\/p>\n<p><p>Et cette mission m\u00e9taphysique fondamentale doit \u00eatre accomplie dans une confrontation directe avec la civilisation occidentale, qui est la somme historique de l&rsquo;escalade du chaos. <\/p>\n<\/p>\n<p><p>Pour vaincre les puissances titanesques de la Terre, il est n\u00e9cessaire d&rsquo;\u00eatre des repr\u00e9sentants du Ciel, d&rsquo;avoir une quantit\u00e9 critique de son soutien de leur c\u00f4t\u00e9.<\/p>\n<\/p>\n<p><p>Il est clair que la Russie moderne en tant qu&rsquo;&Eacute;tat et soci\u00e9t\u00e9 ne peut pr\u00e9tendre \u00eatre d\u00e9j\u00e0 l&rsquo;incarnation d&rsquo;un tel \u00e9l\u00e9ment comique organisateur. Elle est elle-m\u00eame impr\u00e9gn\u00e9e d&rsquo;influences occidentales et tente de d\u00e9fendre uniquement sa souverainet\u00e9 sans remettre en question la th\u00e9orie du progr\u00e8s, les fondements mat\u00e9rialistes des sciences naturelles du Nouvel &Acirc;ge, les inventions techniques, le capitalisme ou le mod\u00e8le occidental de d\u00e9mocratie lib\u00e9rale. Mais comme l&rsquo;Occident globaliste moderne refuse \u00e0 la Russie toute souverainet\u00e9, m\u00eame relative, il l&rsquo;oblige \u00e0 faire monter les ench\u00e8res sans cesse. Elle se retrouve ainsi dans la position d&rsquo;une soci\u00e9t\u00e9 en r\u00e9bellion contre le monde moderne, contre le chaos \u00e9galitaire, contre la croissance rapide du vide et l&rsquo;acc\u00e9l\u00e9ration de la dissipation. <\/p>\n<\/p>\n<p><p>N&rsquo;\u00e9tant pas encore vraiment un ordre, la Russie a affront\u00e9 le chaos dans une bataille mortelle. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Katechon &#8211; la troisi\u00e8me Rome<\/h3>\n<\/p>\n<p><p>Dans une telle situation, la Russie n&rsquo;a tout simplement pas d&rsquo;autre choix que de devenir ce qu&rsquo;elle n&rsquo;est pas en ce moment, mais doit en cons\u00e9quence prendre une position \u00e0 laquelle elle est forc\u00e9e par le hasard m\u00eame des circonstances. La plate-forme pour une telle confrontation, dans les racines de l&rsquo;histoire et de la culture russes, existe certainement. C&rsquo;est avant tout l&rsquo;orthodoxie, les valeurs sacr\u00e9es et l&rsquo;id\u00e9al \u00e9lev\u00e9 d&rsquo;un Empire dot\u00e9 d&rsquo;une fonction kat\u00e9chonique, qui doivent \u00eatre consid\u00e9r\u00e9s comme un rempart contre le chaos [1]. Dans une mesure r\u00e9siduelle, la soci\u00e9t\u00e9 a conserv\u00e9 les concepts d&rsquo;harmonie, de justice et de pr\u00e9servation des institutions traditionnelles, &ndash; famille, communaut\u00e9, moralit\u00e9, qui ont surv\u00e9cu \u00e0 plusieurs si\u00e8cles de modernisation et d&rsquo;occidentalisation, et surtout \u00e0 la derni\u00e8re \u00e9poque ath\u00e9e et mat\u00e9rialiste. Toutefois, cela est loin d&rsquo;\u00eatre suffisant. Pour r\u00e9sister \u00e0 la puissance du chaos de mani\u00e8re vraiment efficace, il faut un r\u00e9veil spirituel \u00e0 grande \u00e9chelle, une transformation profonde et un renouveau des fondements, principes et priorit\u00e9s spirituels de l&rsquo;ordre sacr\u00e9.<\/p>\n<\/p>\n<p><p>La Russie doit rapidement affirmer en son sein les pr\u00e9mices de l&rsquo;ordre kat\u00e9chonique sacr\u00e9, qui s&rsquo;est \u00e9tabli au 15\u00e8me si\u00e8cle dans la continuit\u00e9 de l&rsquo;h\u00e9ritage byzantin, et dans la proclamation de Moscou comme la Troisi\u00e8me Rome. <\/p>\n<\/p>\n<p><p>Seule une Rome \u00e9ternelle peut s&rsquo;opposer au flux tout \u00e0 fait destructeur du temps lib\u00e9r\u00e9. Mais pour cela, elle doit elle-m\u00eame \u00eatre une projection terrestre de la verticale c\u00e9leste.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Etymasia<\/h3>\n<\/p>\n<p><p>Dans l&rsquo;art eccl\u00e9siastique, il existe un th\u00e8me appel\u00e9 &quot;Tr\u00f4ne pr\u00e9par\u00e9&quot; &#8212; en grec <em>Etymasia<\/em>, &tau;&omicron;&iota;&mu;&alpha;&sigma;&alpha;. Cette iconographie nous montre un tr\u00f4ne vide flanqu\u00e9 d&rsquo;anges, de saints ou de souverains. Cette image symbolise le tr\u00f4ne de J\u00e9sus-Christ, sur lequel il s&rsquo;assi\u00e9ra pour juger les nations lors de la seconde venue. Pour l&rsquo;instant &#8211; jusqu&rsquo;\u00e0 la seconde venue &#8211; le tr\u00f4ne est vide. Pas enti\u00e8rement. La Croix est plac\u00e9e dessus.<\/p>\n<\/p>\n<p><p>Cette image fait r\u00e9f\u00e9rence \u00e0 la pratique byzantine et romaine plus ancienne consistant \u00e0 placer une lance ou une \u00e9p\u00e9e sur le tr\u00f4ne au moment o&ugrave; l&#8217;empereur quitte la capitale, par exemple pour une guerre. L&rsquo;arme montre que le tr\u00f4ne n&rsquo;est pas vide. L&rsquo;Empereur n&rsquo;est pas l\u00e0, mais sa pr\u00e9sence l&rsquo;est. Et personne ne peut empi\u00e9ter sur le pouvoir supr\u00eame en toute impunit\u00e9.<\/p>\n<\/p>\n<p><p>Dans la tradition chr\u00e9tienne, cela a \u00e9t\u00e9 r\u00e9interpr\u00e9t\u00e9 dans le contexte du royaume des cieux et donc du tr\u00f4ne de Dieu lui-m\u00eame. Apr\u00e8s l&rsquo;Ascension, le Christ s&rsquo;est retir\u00e9 au ciel, mais cela ne signifie pas qu&rsquo;il n&rsquo;existe pas. Il est, et Il est le seul \u00e0 \u00eatre vraiment. Et son royaume \u00ab\u00a0n&rsquo;a pas de fin\u00a0\u00bb. Elle est dans l&rsquo;\u00e9ternit\u00e9, &ndash; pas dans le temps. C&rsquo;est pourquoi les Vieux Croyants ont tant insist\u00e9 sur l&rsquo;ancienne version du Credo en russe, &ndash; \u00ab\u00a0Son Royaume n&rsquo;a pas de fin\u00a0\u00bb, et non \u00ab\u00a0il n&rsquo;y aura pas de fin\u00a0\u00bb. Le Christ habite sur son tr\u00f4ne pour toujours. Mais pour nous, mortels, terrestres, dans une certaine p\u00e9riode historique, &ndash; entre la Premi\u00e8re et la Seconde Venue, &ndash; elle devient imperceptible. Et comme un rappel de la principale figure absente (pour nous, l&rsquo;humanit\u00e9), la Croix est plac\u00e9e sur le tr\u00f4ne. En contemplant la Croix, nous voyons le Crucifi\u00e9. En pensant au Crucifi\u00e9, nous connaissons le Ressuscit\u00e9. En tournant nos c&oelig;urs vers le Ressuscit\u00e9, nous le voyons se lever, revenir. \u00ab\u00a0Le Tr\u00f4ne pr\u00e9par\u00e9\u00a0\u00bb est Son royaume, Sa puissance. Tant lorsqu&rsquo;Il y est pr\u00e9sent que lorsqu&rsquo;Il s&rsquo;en retire. Il reviendra. Car tout ceci est un mouvement au sein de l&rsquo;\u00e9ternit\u00e9&#8230; En derni\u00e8re analyse, Son r\u00e8gne n&rsquo;a jamais \u00e9t\u00e9 interrompu. <\/p>\n<\/p>\n<p><p>La Russie, qui entre aujourd&rsquo;hui dans la bataille finale contre le chaos, se trouve dans la position de celle qui combat l&rsquo;anti-Christ lui-m\u00eame. Mais combien nous sommes loin de ce haut id\u00e9al, que la radicalit\u00e9 de la bataille finale exige. Et pourtant&#8230; la Russie est le \u00ab\u00a0tr\u00f4ne pr\u00e9par\u00e9\u00a0\u00bb. Il peut sembler de l&rsquo;ext\u00e9rieur qu&rsquo;il est vide. Mais ce n&rsquo;est pas le cas. Le peuple russe et l&rsquo;&Eacute;tat russe portent les cat\u00e9chum\u00e8nes. C&rsquo;est \u00e0 nous aujourd&rsquo;hui que s&rsquo;appliquent les mots de la liturgie \u00ab\u00a0Comme le Tsar qui \u00e9l\u00e8ve tout\u00a0\u00bb. Avec un effort extraordinaire de volont\u00e9 et d&rsquo;esprit, nous nous chargeons du fardeau du Titulaire. Et cette action de notre part ne sera jamais vaine. <\/p>\n<\/p>\n<p><p>Contre le chaos, nous n&rsquo;avons pas seulement besoin de notre ordre, nous avons besoin de Son ordre, de Son autorit\u00e9, de Son royaume. Nous, les Russes, portons sur nous le \u00ab\u00a0Tr\u00f4ne des Pr\u00e9par\u00e9s\u00a0\u00bb. Et dans l&rsquo;histoire de l&rsquo;humanit\u00e9, il n&rsquo;y a pas de mission plus sacr\u00e9e, plus \u00e9lev\u00e9e, plus sacrificielle, que d&rsquo;\u00e9lever le Christ, le Roi des rois, sur nos \u00e9paules. <\/p>\n<\/p>\n<p><p>Mais tant qu&rsquo;il y a une Croix sur le tr\u00f4ne. Il s&rsquo;agit de la Croix russe. La Russie y est crucifi\u00e9e. Elle saigne avec ses fils et ses filles. Et tout cela pour une raison&#8230; Nous sommes sur le droit chemin de la r\u00e9surrection des morts. Et nous jouerons un r\u00f4le essentiel dans ce myst\u00e8re mondial. Car nous sommes les gardiens du tr\u00f4ne. Les soldats du Katechon. <\/p>\n<\/p>\n<p><h4>Alexandre Douguine<\/h4>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>[1] Douguine A.G. Gen\u00e8se et Empire. MOSCOU : AST, 2022.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bataille avec le chaos &bull; Description et interpr\u00e9tation religieuse d&rsquo;un \u00e9v\u00e9nement extraordinaire : la Sainte-Russie partant en guerre contre les arm\u00e9es &lsquo;Collective-West&lsquo; de la civilisation du chaos. &bull; Contribution : Alexandre Douguine. Voici un texte du philosophe russe Alexandre Douguine qui d\u00e9veloppe une analyse m\u00e9taphysique de l&rsquo;Op\u00e9ration Militaire Sp\u00e9ciale (OMS) lanc\u00e9e par la Russie en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3934,2792,2651,16720,2622,21898,8664,4607,1296],"class_list":["post-80468","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-chaos","tag-douguine","tag-du","tag-eurasie","tag-la","tag-nouvelle-democratie","tag-oms","tag-politique","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80468"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80468\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}