{"id":80494,"date":"2023-01-23T17:17:37","date_gmt":"2023-01-23T17:17:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/23\/guerre-totale-et-au-dela\/"},"modified":"2023-01-23T17:17:37","modified_gmt":"2023-01-23T17:17:37","slug":"guerre-totale-et-au-dela","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/23\/guerre-totale-et-au-dela\/","title":{"rendered":"\u201cGuerre totale\u201d et au-del\u00e0&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0Guerre totale\u00a0\u00bb et au-del\u00e0&#8230;<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Apr\u00e8s la grande r\u00e9union (tout de m\u00eame mensuelle) des ministres de la d\u00e9fense du Camp du Bien \u00e0 Ramstein, o&ugrave; l&rsquo;on entendit surtout des r\u00e9criminations et des promesses insaisissables, <strong>la psychologie r\u00e9alise que la Tr\u00e8s-Grande Partie est engag\u00e9e<\/strong>. &bull; Plus personne ne se le dissimule : dans la bataille d&rsquo;Ukraine<strong>, c&rsquo;est la peau de la Russie que veut le &lsquo;<em>Collective West<\/em>&lsquo;<\/strong>. &bull; Pour la Russie, cela signifie que <strong>la \u00ab\u00a0guerre totale\u00a0\u00bb est engag\u00e9e<\/strong>.&bull; Sans doute parlera-t-on de Troisi\u00e8me Guerre Patriotique (et Mondiale).&bull; <strong>Nous, nous parlons de fin de notre cycle m\u00e9tahistorique<\/strong>.<\/p>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>La r\u00e9union (vendredi) \u00e0 Ramstein des ministres de la d\u00e9fense du &lsquo;<em>Collective West<\/em>&lsquo; (combien \u00e9taient-ils ? 30 ? 40 ? 50 ? Qu&rsquo;importe puisque ce sont toujours les m\u00eames m\u00e9caniques qui fonctionnent, parlent et d\u00e9cident). L\u00e0-dessus, on mesure la foudroyante d\u00e9g\u00e9n\u00e9rescence de l&rsquo;appareil politique de cette bande. Il y a 25 ans, 30 ans, 35 ans, c&rsquo;\u00e9taient les r\u00e9unions des ministres des affaires \u00e9trang\u00e8res qui se faisaient pour d\u00e9cider de l&rsquo;action politique \u00e0 mener, qu&rsquo;elle f&ucirc;t d&rsquo;apaisement ou de menace. Aujourd&rsquo;hui, ce sont les ministres de la d\u00e9fense, et l&rsquo;on d\u00e9cide de la politique selon le poids des chars, qui enverra le premier, et les cris hyst\u00e9riques et Polonais appelant \u00e0 raser le Carthage des temps modernes qu&rsquo;est Moscou.<\/p>\n<\/p>\n<p><p>A part cela, quasiment pas de nuances entre les uns et les autres, ni de d\u00e9viation de la ligne centrale du &lsquo;<em>Delenda est<\/em>&lsquo;. Le seul point original que nous rel\u00e8verons est la diff\u00e9rence persistante entre le secr\u00e9taire US \u00e0 la d\u00e9fense, &ndash; lourd, massif, sans originalit\u00e9 aucune, simple voix de la bureaucratie du Pentagone et de l&rsquo;industrie d&rsquo;armement, &ndash; et le g\u00e9n\u00e9ral Milley, pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major, qui ne cesse de r\u00e9p\u00e9ter \u00e0 la moindre occasion que la situation de l&rsquo;Ukraine est &laquo; <em>tr\u00e8s, tr\u00e8s difficile<\/em> &raquo;, et qu&rsquo;il serait peut-\u00eatre habile de tenter de chercher une sorte d&rsquo;accord de cessez-le-feu au moins temporaire avec les Russes. Milley semble la seule voix humaine indiquant une inqui\u00e9tude quelconque vis-\u00e0-vis des perspectives de la bataille, ce qui refl\u00e8te sans doute, &ndash; sans aucun doute, dirions-nous, &ndash; un sentiment s\u00e9rieux chez les chefs militaires US.<\/p>\n<\/p>\n<p><p>Les divers bruits entendus et d\u00e9cisions annonc\u00e9es, portant sur du mat\u00e9riel de plus en plus lourd, sur des perspectives de tir sur la Crim\u00e9e, voire en Russie continentale et plus profonde, etc., ont tout pour activer l&rsquo;incendie alors que les forces russes semblent avoir trouv\u00e9 un tr\u00e8s bon rythme et adoptent sur divers points une attitude offensive. Les Russes semblent d\u00e9sormais pr\u00eats apr\u00e8s plusieurs mois de certaines h\u00e9sitations et incertitudes (ce qui ne les a pas emp\u00each\u00e9s de prendre et de tenir une partie importante du Donbass).<\/p>\n<\/p>\n<p><p>Les annonces de renforcement faites dans la confusion (voit le cirque USA-Allemagne pour savoir qui <a href=\"https:\/\/www.rt.com\/news\/570322-one-abrams-german-leopards\/\">ne sera pas le premier<\/a> \u00e0 livrer un de ses chars lourds) et ne contiennent aucune perspective d&rsquo;une aide d\u00e9cisive pour les Ukrainiens qui sont dans une position de plus en plus difficile. Mais la rh\u00e9torique, le climat, l&rsquo;ambiance, l&rsquo;esp\u00e8ce <a href=\"https:\/\/www.dedefensa.org\/article\/les-mille-et-une-nuances-de-la-haine\">de haine permanente<\/a> qui caract\u00e9risent ces d\u00e9bats, rencontres et autres conseils de guerre, constituent une v\u00e9ritable \u00ab\u00a0escalade\u00a0\u00bb au sens militaire, sans les v\u00e9ritables moyens n\u00e9cessaires \u00e0 une relance d&rsquo;une telle ampleur. Mais qu&rsquo;importe : on sait que 90% et plus de l&rsquo;action, aujourd&rsquo;hui, est de la communication, &ndash; dans tous les cas pour le bloc-BAO.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">&laquo; <em>Les masques tombent<\/em> &raquo;<\/h3>\n<\/p>\n<p><p>&#8230;C&rsquo;est dire qu&rsquo;on est en pleine escalade, &ndash; et les commentaires (ici &lsquo;<em><a href=\"https:\/\/southfront.org\/all-masks-thrown-off\/\">SouthFront.org<\/a><\/em>&lsquo;, sous le titre &laquo; <em>Les masques tombent<\/em> &raquo;) enregistrent l&rsquo;\u00e9v\u00e9nement de cette fa\u00e7on, comme d&rsquo;une grande aggravation, ce qui inattendu et illogique, mais finalement se justifie&#8230; Ils constatent surtout une nouveaut\u00e9 dont tout le monde se doutait mais qui est dite d\u00e9sormais. L&rsquo;objectif n&rsquo;est plus dissimul\u00e9 aujourd&rsquo;hui : la destruction de la Russie, &ndash; et ainsi \u00ab\u00a0les masques\u00a0\u00bb tombent-ils&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>En janvier 2023, tous les masques sont tomb\u00e9s. Les \u00e9lites euro-atlantiques, motiv\u00e9es apr\u00e8s leurs r\u00e9unions \u00e0 Davos, ont compris qu&rsquo;il n&rsquo;\u00e9tait plus n\u00e9cessaire de couvrir leurs v\u00e9ritables intentions par des appels hypocrites \u00e0 \u00ab\u00a0sauver la jeune d\u00e9mocratie ukrainienne pour le bien de la paix mondiale.\u00a0\u00bbDe plus en plus de repr\u00e9sentants du soi-disant \u00ab\u00a0<a href=\"https:\/\/en.wikipedia.org\/wiki\/Golden_billion\">milliard d&rsquo;or<\/a>\u00a0\u00bb de l&rsquo;Occident reconnaissent les v\u00e9ritables objectifs de la politique belliqueuse qu&rsquo;ils m\u00e8nent contre la Russie depuis des d\u00e9cennies, \u00e0 savoir la destruction de l&rsquo;int\u00e9grit\u00e9 de la F\u00e9d\u00e9ration de Russie en tant qu&rsquo;&Eacute;tat et la privation du peuple russe de son statut d&rsquo;&Eacute;tat afin de prendre le contr\u00f4le d&rsquo;\u00e9normes ressources qui \u00ab\u00a0pour une certaine injustice historique appartiennent aux barbares russes\u00a0\u00bb. Le sort de l&rsquo;&Eacute;tat ukrainien et la vie de sa population ne les int\u00e9ressent gu\u00e8re, car en cas de victoire, son territoire fertile deviendra un agr\u00e9able bonus.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les \u00e9lites euroatlantiques ont d\u00e9clench\u00e9 et m\u00e8nent une guerre agressive contre la F\u00e9d\u00e9ration de Russie dans leur int\u00e9r\u00eat personnel. De plus, le d\u00e9veloppement continu du conflit militaire, le manque de volont\u00e9 politique de l&rsquo;Occident pour le r\u00e9soudre et le renforcement de la rh\u00e9torique belliqueuse avec la reconnaissance des v\u00e9ritables objectifs de la guerre indiquent que ces \u00e9lites sont pr\u00eates \u00e0 escalader le conflit jusqu&rsquo;\u00e0 la troisi\u00e8me guerre mondiale, et m\u00eame la menace nucl\u00e9aire ne les arr\u00eatera pas<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le m\u00eame article de &lsquo;<em><a href=\"https:\/\/southfront.org\/all-masks-thrown-off\/\">SouthFront.org<\/a><\/em>&lsquo; rapporte diff\u00e9rentes interventions de personnalit\u00e9s antirusses clairement identifi\u00e9es comme des objurgations \u00e0 lancer une attaque contre la Russie elle-m\u00eame. On y trouve les sornettes <a href=\"https:\/\/www.dedefensa.org\/article\/ah-si-napoleon-avait-eu-des-leopard\">d\u00e9j\u00e0 signal\u00e9es hier<\/a> du Haut Repr\u00e9sentant de l&rsquo;UE Borrell, qu&rsquo;on peut consulter \u00e0 nouveau, comme excellente r\u00e9f\u00e9rence historique.<\/p>\n<\/p>\n<p><p>Il y a \u00e9galement l&rsquo;intervention int\u00e9ressante de la Vice-Premi\u00e8re ministre canadienne Chrystia Freeland, dont on vous a <a href=\"https:\/\/www.dedefensa.org\/article\/tc-104-big-bang-canadien\">d\u00e9j\u00e0 parl\u00e9<\/a> avec tout son p\u00e9digr\u00e9e, et qu&rsquo;on devrait probablement retrouver parfaitement \u00e0 sa place, comme <a href=\"https:\/\/www.dedefensa.org\/article\/lotan-fait-ses-gammes\">premi\u00e8re femme<\/a> Secr\u00e9taire G\u00e9n\u00e9rale de l&rsquo;OTAN. Freeland nous promet, avec la fin de la Russie en 2023, des lendemains qui chantent et quasiment la fin de tous les malheurs des hommes et des transgenres. Affirmer de telles tornades de sottise nous laisse grand espoir pour l&rsquo;avenir de l&rsquo;OTAN.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Au milieu des r\u00e9v\u00e9lations des dirigeants occidentaux, les propos de la vice-premi\u00e8re ministre et ministre des finances du Canada, Chrystia Freeland, ont paru particuli\u00e8rement int\u00e9ressants au forum de Davos. Elle a \u00e9galement soutenu la position de M. Borrel, pr\u00e9cisant que la d\u00e9faite de la Russie \u00ab\u00a0serait un \u00e9norme coup de pouce pour l&rsquo;\u00e9conomie mondiale\u00a0\u00bb. Mme Freeland, dont le grand-p\u00e8re \u00e9tait membre du groupe nationaliste OUN-UPA d&rsquo;Andrei Melnik, a fait parler d&rsquo;elle \u00e0 plusieurs reprises ces derni\u00e8res ann\u00e9es en prenant la parole pour soutenir les nazis ukrainiens et en faisant des d\u00e9clarations russophobes.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Une victoire de l&rsquo;Ukraine dans sa guerre contre la Russie cette ann\u00e9e &quot;donnerait un \u00e9norme coup de fouet \u00e0 l&rsquo;\u00e9conomie mondiale&quot;, affirme Chrystia Freeland, vice-premi\u00e8re ministre de M. Trudeau et membre du conseil d&rsquo;administration du WEF.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est la guerre du XXIe si\u00e8cle pour les ressources, \u00e0 grande \u00e9chelle et en toute simplicit\u00e9. &#8211; La porte-parole du minist\u00e8re russe des affaires \u00e9trang\u00e8res a comment\u00e9 ses affirmations<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">De Lavrov \u00e0 Medvedev<\/h3>\n<\/p>\n<p><p>Dans cette p\u00e9riode-clef (une de plus) que le secr\u00e9taire \u00e0 la d\u00e9fense Austin a clairement qualifi\u00e9e de \u00ab\u00a0<em>turning point<\/em>\u00a0\u00bb (un de plus), l&rsquo;interpr\u00e9tation des Russes est clairement que l'\u00a0\u00bbOuest collectif\u00a0\u00bb ne cherche m\u00eame plus \u00e0 cacher son engagement, ni \u00e0 la moindre mascarade de maquillage, mais pose clairement sa volont\u00e9 d&rsquo;interventionnisme liquidateurs. (La Russie ? Une balle dans la nuque, comme faisait le NKVD.) Les officiels russes le disent au plus haut niveau, ils le disent avec une nettet\u00e9 sans crier gare ; Lavrov, par exemple, <a href=\"https:\/\/www.mid.ru\/ru\/foreign_policy\/news\/1848395\/?lang=en\">le 18 janvier <\/a>:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ce qui se passe actuellement en Ukraine est le r\u00e9sultat des pr\u00e9paratifs des &Eacute;tats-Unis et de leurs satellites pour le d\u00e9but d&rsquo;une guerre hybride mondiale contre la F\u00e9d\u00e9ration de Russie. Personne ne cache ce fait. Cela ressort clairement des d\u00e9clarations de politologues, de scientifiques et de politiciens occidentaux impartiaux. Dans son r\u00e9cent article, Ian Bremmer, professeur de sciences politiques \u00e0 l&rsquo;universit\u00e9 de Columbia, \u00e9crit : \u00ab\u00a0Nous ne sommes pas dans une guerre froide avec la Russie. Nous sommes dans une guerre chaude avec la Russie. Maintenant, c&rsquo;est une guerre par procuration. Et l&rsquo;OTAN ne la combat pas directement. Nous la combattons \u00e0 travers l&rsquo;Ukraine\u00a0\u00bb. Cet aveu est franc et cette conclusion est une \u00e9vidence. Il est \u00e9trange que certaines personnes tentent de la r\u00e9futer. R\u00e9cemment, le pr\u00e9sident de la Croatie, Zoran Milanovic, a d\u00e9clar\u00e9 qu&rsquo;il s&rsquo;agissait d&rsquo;une guerre de l&rsquo;OTAN. Une d\u00e9claration ouverte et honn\u00eate. Il y a plusieurs semaines, Henry Kissinger (avant qu&rsquo;il n&rsquo;exhorte l&rsquo;OTAN \u00e0 accepter l&rsquo;Ukraine dans son r\u00e9cent article) a \u00e9crit en termes clairs que les \u00e9v\u00e9nements en Ukraine \u00e9taient un affrontement, une rivalit\u00e9 de deux puissances nucl\u00e9aires pour le contr\u00f4le de ce territoire. Ce qu&rsquo;il voulait dire est assez clair.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nos partenaires occidentaux rusent tout en essayant avec v\u00e9h\u00e9mence de prouver qu&rsquo;ils ne combattent pas la Russie mais qu&rsquo;ils aident seulement l&rsquo;Ukraine \u00e0 r\u00e9pondre \u00e0 une \u00ab\u00a0agression\u00a0\u00bb et \u00e0 restaurer son int\u00e9grit\u00e9 territoriale. L&rsquo;ampleur de leur soutien montre clairement que l&rsquo;Occident a mis\u00e9 gros sur sa guerre contre la Russie ; c&rsquo;est \u00e9vident.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les \u00e9v\u00e9nements entourant l&rsquo;Ukraine ont mis en lumi\u00e8re la pouss\u00e9e implicite des &Eacute;tats-Unis \u00e0 abandonner les tentatives de renforcement de leur position mondiale par des moyens l\u00e9gitimes et \u00e0 adopter des m\u00e9thodes ill\u00e9gitimes pour assurer leur domination. Tout est permis. Les m\u00e9canismes et institutions autrefois v\u00e9n\u00e9r\u00e9s, cr\u00e9\u00e9s par l&rsquo;Occident dirig\u00e9 par les &Eacute;tats-Unis, ont \u00e9t\u00e9 mis au rebut (et pas \u00e0 cause de ce que nous voyons en Ukraine). Le march\u00e9 libre, la concurrence loyale, la libre entreprise, l&rsquo;inviolabilit\u00e9 de la propri\u00e9t\u00e9 et la pr\u00e9somption d&rsquo;innocence, en un mot, tout ce sur quoi reposait le mod\u00e8le de mondialisation occidental s&rsquo;est effondr\u00e9 du jour au lendemain. Des sanctions ont \u00e9t\u00e9 impos\u00e9es \u00e0 la Russie et \u00e0 d&rsquo;autres pays r\u00e9pr\u00e9hensibles qui ne respectent pas ces principes et m\u00e9canismes. Il est clair que des sanctions peuvent \u00eatre impos\u00e9es \u00e0 tout moment \u00e0 tout pays qui, d&rsquo;une mani\u00e8re ou d&rsquo;une autre, refuse de suivre aveugl\u00e9ment les ordres am\u00e9ricains.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;Union europ\u00e9enne a \u00e9t\u00e9 compl\u00e8tement subsum\u00e9e par cette dictature am\u00e9ricaine (il est inutile de s&rsquo;\u00e9tendre sur ce sujet).<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La conf\u00e9rence de Ramstein a \u00e9t\u00e9 \u00e9voqu\u00e9e de fa\u00e7on plus directe par d&rsquo;autres, en mettant l&rsquo;accent sur des mesures \u00e9voqu\u00e9es d\u00e9sormais d&rsquo;aide ou d&rsquo;accompagnement US d&rsquo;attaques ukrainiennes vers des territoires russes (dont bien s&ucirc;r la Crim\u00e9e et les territoires ukrainiens du Donbass pass\u00e9s sous administration russe).Il s&rsquo;agit l\u00e0 de r\u00e9f\u00e9rences \u00e0 des attaques dont on conna&icirc;t la forme, avec l&rsquo;\u00e9vocation de ripostes qui, \u00e0 notre sens et selon la gravit\u00e9 la plus extr\u00eame que peuvent prendre ces attaques, pourraient impliquer <a href=\"https:\/\/www.dedefensa.org\/article\/lhypersonique-entre-dans-la-dissuasion\">des missiles hypersoniques<\/a> auquel l&rsquo;\u00e9nergie cin\u00e9tique donne une consid\u00e9rable force de frappe, m\u00eame avec une charge conventionnelle (non-nucl\u00e9aire). C&rsquo;est le cas des hypoth\u00e8ses dans l&rsquo;intervention du pr\u00e9sident de la Douma, qui repr\u00e9sente sans aucun doute un message direct du pouvoir russe :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Une \u00ab\u00a0trag\u00e9die mondiale\u00a0\u00bb pourrait s&rsquo;abattre sur l&rsquo;humanit\u00e9 si l&rsquo;Occident continue de fournir des armes \u00e0 l&rsquo;Ukraine, a averti le plus haut l\u00e9gislateur russe. Viatcheslav Volodine, le pr\u00e9sident de la Douma d&rsquo;&Eacute;tat, a \u00e9galement sugg\u00e9r\u00e9 que Moscou pourrait riposter avec des armes plus puissantes, si son territoire \u00e9tait menac\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les remarques de Volodine sont intervenues quelques jours apr\u00e8s une r\u00e9union \u00e0 la base a\u00e9rienne am\u00e9ricaine de Ramstein, en Allemagne, au cours de laquelle les puissances occidentales se sont engag\u00e9es \u00e0 continuer de soutenir Kiev.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Dimanche, M. Volodine s&rsquo;est exprim\u00e9 sur Telegram pour souligner que si les armes fournies par les &Eacute;tats-Unis et les autres &Eacute;tats membres de l&rsquo;OTAN \u00e9taient utilis\u00e9es pour \u00ab\u00a0frapper des villes civiles et tenter de s&#8217;emparer de nos territoires, comme ils menacent de le faire\u00a0\u00bb, Moscou r\u00e9pondrait avec \u00ab\u00a0des armes plus puissantes\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Enfin, le m\u00eame article d\u00e9j\u00e0 cit\u00e9 de &lsquo;<em>SouthFront.org<\/em>&lsquo; signale diverses dispositions prises par les Russes dans leurs structures de s\u00e9curit\u00e9 et sur leur territoire, signifiant que la Russie s&rsquo;engage d\u00e9sormais sur la voie et sur la n\u00e9cessit\u00e9 d&rsquo;une guerre totale avec l&rsquo;Occident. On note par exemple dans ces mesures des \u00ab\u00a0purges\u00a0\u00bb \u00e9cartant des fonctionnaires jug\u00e9s trop accommodant avec &lsquo;Occident, sinon d&rsquo;une tendance dite \u00ab\u00a0occidentaliste\u00a0\u00bb en Russie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>R\u00e9cemment, des rapports ont fait \u00e9tat de certains changements au sein de la direction politique et militaire russe. En particulier, certains fonctionnaires occupant des postes de haut niveau dans des organes politiques cl\u00e9s tels que l&rsquo;administration pr\u00e9sidentielle, le Conseil de s\u00e9curit\u00e9, les services sp\u00e9ciaux, etc. ont \u00e9t\u00e9 chang\u00e9s. Des inspections ont \u00e9t\u00e9 lanc\u00e9es pour clarifier la conformit\u00e9 de plusieurs hauts fonctionnaires \u00e0 leurs postes, leurs liens avec des pays \u00e9trangers et les \u00e9ventuelles actions de corruption sont en cours de v\u00e9rification.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Des changements ont \u00e9galement eu lieu au sein du minist\u00e8re russe de la D\u00e9fense. Le g\u00e9n\u00e9ral d&rsquo;arm\u00e9e Valery Gerasimov a \u00e9t\u00e9 nomm\u00e9 commandant du groupe de troupes russes dans la zone d&rsquo;une op\u00e9ration militaire sp\u00e9ciale (SVO) en Ukraine. Il a combattu les militants tch\u00e9tch\u00e8nes \u00e0 la t\u00eate de l&rsquo;arm\u00e9e, a organis\u00e9 une op\u00e9ration en Syrie et dirige l&rsquo;\u00e9tat-major g\u00e9n\u00e9ral des forces arm\u00e9es russes depuis novembre 2012. Les changements au sein du commandement militaire russe pourraient indiquer la nouvelle \u00e9tape des hostilit\u00e9s en Ukraine. De plus, de nouveaux g\u00e9n\u00e9raux ont \u00e9t\u00e9 nomm\u00e9s \u00e0 un certain nombre d&rsquo;autres postes cl\u00e9s du minist\u00e8re de la D\u00e9fense.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En janvier, les militaires russes ont commenc\u00e9 \u00e0 renforcer par d\u00e9fi le syst\u00e8me de d\u00e9fense a\u00e9rienne de la capitale. Ces derniers jours, des images de nouveaux syst\u00e8mes de d\u00e9fense a\u00e9rienne d\u00e9ploy\u00e9s pr\u00e8s des centres de d\u00e9cision, comme le Kremlin de Moscou et le b\u00e2timent du minist\u00e8re de la D\u00e9fense, ont \u00e9t\u00e9 largement diffus\u00e9es sur Internet<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Apr\u00e8s une ann\u00e9e d&rsquo;hostilit\u00e9 en Ukraine, les Russes sont arriv\u00e9s \u00e0 la conclusion qu&rsquo;il est devenu impossible d&rsquo;esp\u00e9rer un arrangement avec l&rsquo;Occident dans les conditions actuelles, qu&rsquo;il n&rsquo;y a donc plus que l&rsquo;issue du conflit. M\u00eame par rapport \u00e0 la situation cr\u00e9\u00e9e le 24 f\u00e9vrier 2022, c&rsquo;est une situation compl\u00e8tement nouvelle qui s&rsquo;est impos\u00e9e avec la conf\u00e9rence de Ramstein prise comme \u00e9v\u00e9nement symbolique de la volont\u00e9 d&rsquo;engagement des &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Les Russes vont \u00eatre forc\u00e9s de passer \u00e0 des op\u00e9rations d&rsquo;offensive plus profonde s&rsquo;ils veulent effectivement soutenir ce rythme de \u00ab\u00a0guerre totale\u00a0\u00bb dont ils conviennent d\u00e9sormais de l&rsquo;existence. Il n&rsquo;est plus question de la seule Ukraine. On entre dans le domaine le plus pur et le plus in\u00e9dit pour notre \u00e9poque de la \u00ab\u00a0guerre civilisationnelle\u00a0\u00bb et les Russes vont devoir se pr\u00e9occuper d&rsquo;une action \u00e0 l&rsquo;\u00e9chelle mondiale. Le mot de Medvedev sur les coalitions antiam\u00e9ricanistes \u00e0 former ne doit pas rester symbolique si les Russes veulent s&rsquo;affirmer. Ils ont pour cela des instruments qu&rsquo;il leur faut d\u00e9sormais tenter de politiser : les BRICS et l&rsquo;OCS, notamment.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0La r\u00e9union de Ramstein et l&rsquo;attribution d&rsquo;armes lourdes \u00e0 Kiev ne laissent aucun doute sur le fait que nos ennemis vont tenter de nous \u00e9puiser pendant une p\u00e9riode ind\u00e9finie, ou, de pr\u00e9f\u00e9rence, de nous d\u00e9truire\u00a0\u00bb, a \u00e9crit l&rsquo;ex-pr\u00e9sident. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Toutefois, la prolongation des hostilit\u00e9s en Ukraine pourrait finalement conduire \u00e0 l&rsquo;\u00e9mergence d&rsquo;un nouveau bloc militaire r\u00e9unissant des nations \u00ab\u00a0qui en ont assez des Am\u00e9ricains\u00a0\u00bb, a sugg\u00e9r\u00e9 Medvedev. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Cela s&rsquo;est toujours produit dans l&rsquo;histoire de l&rsquo;humanit\u00e9 pendant les longues guerres. Les &Eacute;tats-Unis finiront alors par abandonner la vieille Europe et ce qui reste des malheureux Ukrainiens, et le monde retrouvera son \u00e9quilibre\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;ancien dirigeant, avertissant toutefois qu&rsquo;il pourrait \u00eatre \u00ab\u00a0trop tard\u00a0\u00bb <\/em>[\u00e0 cause du nucl\u00e9aire] <em>avant que cela ne se produise<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Du &laquo; <em>turning point<\/em> &raquo; au &laquo; <em>perfect storm<\/em> &raquo;<\/h3>\n<\/p>\n<p><p>Que conclure de cette s\u00e9quence ? Qu&rsquo;une fois de plus r\u00e8gne la communication, c&rsquo;est-\u00e0-dire l&rsquo;information utilis\u00e9e comme simulacre ou comme lanterne pour tenter de rencontrer une <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>. C&rsquo;est-\u00e0-dire qu&rsquo;on ne peut avancer l&rsquo;observation que des d\u00e9cisions radicales ont \u00e9t\u00e9 prises \u00e0 la r\u00e9union de Ramstein. Au contraire, on a vu mettre en \u00e9vidence les querelles entre \u00ab\u00a0amis\u00a0\u00bb, entre les Allemands attach\u00e9s \u00e0 ne pas pr\u00e9cipiter leurs &lsquo;<em>Leopard<\/em>&lsquo; dans des mains ukrainiennes, et les am\u00e9ricanistes ordonnant \u00e0 tout le monde de donner des chars en promettant de faire \u00e9galement don de quelques &lsquo;<em>Abrams<\/em>&lsquo;, mais plus tard ; on a appris l\u00e0-dessus que la ministre des affaires \u00e9trang\u00e8res allemandes, extr\u00eamement pacifistes comme sont les \u00e9cologistes, soutient les Polonais hyst\u00e9riques qui r\u00e9clament au chancelier Scholz, effray\u00e9, une donation imm\u00e9diate de &lsquo;<em>Leopard<\/em>&lsquo; aux Ukrainiens. Certes, il y a des rumeurs sur l&rsquo;implication US dans des attaques ukrainiennes vers des territoires anciennement et nouvellement russes, mais ces rumeurs ne sont pas nouvelles, elles ne sont pas confirm\u00e9es, elles viennent du New York &lsquo;<em>Times<\/em>&lsquo; qui a peut-\u00eatre voulu faire plaisir \u00e0 ses amis <em>neocons<\/em>.<\/p>\n<\/p>\n<p><p>Il n&#8217;emp\u00eache : c&rsquo;est bien un &laquo; <em>turning point<\/em> &raquo;, comme dit l&rsquo;impavide et massif Austin. Il dit tout le temps cela, mais cette fois cela pourrait \u00eatre vrai. Il y a une conjonction qui est une <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> qui compte : celle de l&rsquo;\u00e9volution russe sur le terrain, vers la structuration d&rsquo;une v\u00e9ritable arm\u00e9e de guerre, et l&rsquo;\u00e9volution psychologique des Russes qui va avec. Les paroles de Lavrov, &ndash; encore lui, &ndash; aujourd&rsquo;hui en Afrique du Sud <a href=\"https:\/\/www.rt.com\/russia\/570357-russia-west-real-war\/\">sont terribles<\/a>, lorsqu&rsquo;il accuse l&rsquo;Occident de pr\u00e9parer la destruction de la Russie depuis des d\u00e9cennies..<\/p>\n<\/p>\n<p><p>Partout s&rsquo;installe la conviction qu&rsquo;il s&rsquo;agit d&rsquo;une \u00ab\u00a0guerre totale\u00a0\u00bb, sans doute la v\u00e9ritable Troisi\u00e8me Guerre Mondiale que nous annon\u00e7ons et attendons tous (et surtout Troisi\u00e8me Guerre Patriotique pour la Russie ?), qui est et sera n\u00e9cessairement d&rsquo;une forme particuli\u00e8re, qui ne sera pas n\u00e9cessairement l&rsquo;apocalypse nucl\u00e9aire, mais qui est certainement et d&rsquo;ores et d\u00e9j\u00e0 une apocalypse psychologique. Ce dernier domaine (la psychologie) est si touch\u00e9 parce que cette guerre est une catastrophe terminale, une rupture de notre fa\u00e7on de percevoir le monde, une crise finale d&rsquo;un cycle port\u00e9 \u00e0 son terme.<\/p>\n<\/p>\n<p><p>Le &laquo; <em>turning point<\/em> &raquo;, qui est n\u00e9goci\u00e9 d\u00e9j\u00e0 depuis quelques ann\u00e9es, prend l&rsquo;allure d&rsquo;un &laquo; <em>perfect storm<\/em> &raquo;, comme ils disent.<\/p>\n<\/p>\n<p><p>Mis en ligne le 23 janvier 2023 \u00e0 17H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Guerre totale\u00a0\u00bb et au-del\u00e0&#8230; &bull; Apr\u00e8s la grande r\u00e9union (tout de m\u00eame mensuelle) des ministres de la d\u00e9fense du Camp du Bien \u00e0 Ramstein, o&ugrave; l&rsquo;on entendit surtout des r\u00e9criminations et des promesses insaisissables, la psychologie r\u00e9alise que la Tr\u00e8s-Grande Partie est engag\u00e9e. &bull; Plus personne ne se le dissimule : dans la bataille d&rsquo;Ukraine,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[13665,5518,9767,2631,2830,3741,4558,1296],"class_list":["post-80494","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-austin","tag-base","tag-choc","tag-de","tag-lavrov","tag-psychologique","tag-ramstein","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80494"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80494\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}