{"id":80498,"date":"2023-01-31T06:48:15","date_gmt":"2023-01-31T06:48:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/31\/le-tango-blinken-nuland\/"},"modified":"2023-01-31T06:48:15","modified_gmt":"2023-01-31T06:48:15","slug":"le-tango-blinken-nuland","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/01\/31\/le-tango-blinken-nuland\/","title":{"rendered":"Le tango Blinken-Nuland"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le tango Blinken-Nuland<\/h2>\n<\/p>\n<p><p>31 janvier 2023 (07H00) &ndash; J&rsquo;avoue platement avoir compl\u00e8tement rat\u00e9 l&rsquo;histoire du si\u00e8cle, je veux dire \u00ab\u00a0de la semaine derni\u00e8re\u00a0\u00bb, avec mercredi l&rsquo;interview de Blinken par l&rsquo;ami Ignatius (du &lsquo;<em>Post<\/em>&lsquo;, entre amis), suivi par l&rsquo;audition de l&rsquo;impressionnante Victoria Nuland, en pleine sant\u00e9 et adjointe du pr\u00e9c\u00e9dent, jeudi devant la Commission des Relations Ext\u00e9rieures du S\u00e9nat. John Helmer, qui s&rsquo;amuse bien en ce moment en \u00ab\u00a0dansant avec les ours\u00a0\u00bb (&lsquo;<em>DancewithBears.com<\/em>&lsquo;), rapporte ces deux interventions qui se sont magnifiquement t\u00e9lescop\u00e9es, selon une parfaite coordination psycho-technologique, comme l&rsquo;on danse le tango sur le rythme de la java chaloup\u00e9e au rythme de la valse.<\/p>\n<\/p>\n<p><p>Je lui <a href=\"http:\/\/johnhelmer.net\/blinken-explainer-nuland-too\/#more-70580\">laisse la parole<\/a> tandis que Mercouris rapporte l&rsquo;aventure entre divers \u00e9clats de rire (fin de la vid\u00e9o du <a href=\"https:\/\/theduran.com\/russia-close-to-capture-vuhledar-launches-big-missile-attack-blinken-nuland-floats-peace-offer-russia-says-no\/\">27 janvier<\/a>) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Depuis que James Forrestal a saut\u00e9 du seizi\u00e8me \u00e9tage d&rsquo;un h\u00f4pital de la marine am\u00e9ricaine en 1949, aucun secr\u00e9taire de cabinet am\u00e9ricain n&rsquo;a pr\u00e9sent\u00e9 autant de sympt\u00f4mes psychopathologiques qu&rsquo;Antony Blinken, l&rsquo;actuel secr\u00e9taire d&rsquo;&Eacute;tat. L&rsquo;annonce faite par Blinken cette semaine sur les conditions de la fin de la guerre en Ukraine peut-elle \u00eatre crue dans une clinique psychiatrique militaire am\u00e9ricaine, et encore plus au Kremlin \u00e0 Moscou<\/em> <em>?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Et que peut-on croire lorsque, le lendemain des remarques de Blinken, Victoria Nuland, la sous-secr\u00e9taire d&rsquo;&Eacute;tat la plus psychopathologique de l&rsquo;histoire de la fonction, a annonc\u00e9 \u00e0 la commission des affaires \u00e9trang\u00e8res du S\u00e9nat qu&rsquo;elle et Blinken sont pr\u00eats \u00ab\u00a0dans le contexte de la d\u00e9cision de la Russie de n\u00e9gocier s\u00e9rieusement, de retirer ses troupes d&rsquo;Ukraine et de restituer des territoires <\/em>[qu&rsquo;elle occupe]\u00a0\u00bb, [\u00e0 soutenir l&rsquo;assouplissement des sanctions]<em>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce que Nuland entendait par l&rsquo;Ukraine et les territoires \u00ab\u00a0\u00e0 restituer\u00a0\u00bb, Blinken l&rsquo;avait d\u00e9taill\u00e9 la veille <\/em>[dans sa proposition]<em>. La Crim\u00e9e, Zaporozhye et \u00ab\u00a0le pont terrestre qui relie la Crim\u00e9e et la Russie\u00a0\u00bb, c&rsquo;est-\u00e0-dire Kherson, Donetsk et Lugansk, resteront russes et ne seront ni n\u00e9goci\u00e9s ni \u00ab\u00a0restitu\u00e9s\u00a0\u00bb car, selon Blinken, \u00ab\u00a0un assaut contre la Crim\u00e9e serait un d\u00e9clencheur d&rsquo;escalade nucl\u00e9aire\u00a0\u00bb<\/em>. &raquo; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est vrai que tout le monde  (sauf moi, qui pensais \u00e0 autre chose) fut ou aurait d&ucirc; \u00eatre fort surpris de cet \u00e9trange pas de deux. On chercha des hypoth\u00e8ses rationnelles \u00e0 cet expos\u00e9 de politique schizophr\u00e9nique, pour ceux qui ont du temps \u00e0 perdre. Moi-m\u00eame, qui ai du temps \u00e0 perdre entre mes angoisses diverses, favorise l&rsquo;hypoth\u00e8se que ce n&rsquo;est pas un hasard si l&rsquo;ahurissante proposition Blinken, aussit\u00f4t rectifi\u00e9e-Nuland, est rendue publique le jour o&ugrave; le rapport de la RAND <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2023-la-rand-devient-colombe\">est rendu public<\/a>. On remarque que Blinken s&rsquo;affirme notamment, pour au moins 24 heures, contre une attaque et une reprise de la Crim\u00e9e, notamment parce qu&rsquo;&laquo; <em>un assaut contre la Crim\u00e9e serait un d\u00e9clencheur d&rsquo;escalade nucl\u00e9aire<\/em> &raquo;. Cela doit rassurer les militaires \u00e9toil\u00e9s du Pentagone, non ?<\/p>\n<\/p>\n<p><p>Je me r\u00e9p\u00e8te&#8230; \u00ab\u00a0Il est vrai que tout le monde [&#8230;] fut ou aurait d&ucirc; \u00eatre fort surpris de cet \u00e9trange pas de deux\u00a0\u00bb&#8230; Et je compl\u00e8te : tout le monde sauf les Russes, indiff\u00e9rents ou m\u00e9prisants c&rsquo;est selon, comme le montre ce commentaire de Maria Zakharova la brillantissime porte-parole du minist\u00e8re des affaires \u00e9trang\u00e8res. (Toujours <a href=\"http:\/\/johnhelmer.net\/russian-foreign-ministry-rejects-blinken-and-nuland-proposals-condemns-scholz-for-reviving-hitlers-plan-to-destroy-russia\/#more-70590\">d&rsquo;apr\u00e8s John Helmer<\/a>, qui s&rsquo;est bien amus\u00e9.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&raquo; &#8230;<em>Il me semble que tout le monde a compris depuis longtemps de quoi nous parlons &#8211; la confrontation avec notre pays, la strat\u00e9gie de l&rsquo;isoler. Auparavant, cela n&rsquo;\u00e9tait possible par aucun moyen, ni \u00e9conomique, ni politique, ni financier. M\u00eame avec des appels \u00e0 mettre fin aux contrats lucratifs entre entreprises priv\u00e9es.  Cela n&rsquo;a pas fonctionn\u00e9. Alors ils ont impos\u00e9 des sanctions et des listes, et des listes d&rsquo;arr\u00eat, et ont menac\u00e9 toute la communaut\u00e9 internationale, mais rien n&rsquo;en est sorti. On est pass\u00e9 \u00e0 la phase suivante. Comment l&rsquo;appeler autrement ? Par cons\u00e9quent, le \u00ab\u00a0d\u00e9veloppement des relations\u00a0\u00bb d\u00e9coulera de tout cela, de l&rsquo;expos\u00e9 de la situation r\u00e9elle \u00ab\u00a0sur le terrain\u00a0\u00bb, &ndash; et non de quelques d\u00e9clarations mineures.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Aujourd&rsquo;hui, j&rsquo;ai entendu que Washington a dit que si la Russie fait quelque chose comme ceci ou cela, peut-\u00eatre que certaines sanctions ou autre chose seront lev\u00e9es. Qui \u00e9coute tout cela ? Qui en a besoin ? Qui y pr\u00eate attention ? Quelqu&rsquo;un a dit quelque chose, des sanctions. Ce n&rsquo;est pas la question. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Dans le contexte du fait que des armes lourdes sont fournies, il n&rsquo;est pas n\u00e9cessaire de parler de ce qui se passera si quelqu&rsquo;un fait quelque chose l\u00e0-bas. Il y a une situation sur le terrain dont nous nous occupons. Nous nous occupons de tout<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La m\u00eame Zakharova est superbe dans le m\u00e9pris par d\u00e9rision et indiff\u00e9rence. Lorsque, lors de cette m\u00eame conf\u00e9rence de presse du 27 janvier, elle se met \u00e0 parler des Allemands (voir la partie suivante) et qu&rsquo;elle attaque, Scholz en t\u00eate&#8230; Vous vous dites : elle aurait d&ucirc; s&rsquo;en prendre \u00e0 la m\u00e9g\u00e8re atlantico-\u00e9colo et &lsquo;<em>American Ecolo<\/em>&lsquo;, la Baerbock, par exemple pour l&rsquo;affubler du surnom \u00ab\u00a0<em>Baerbockrossa<\/em>\u00a0\u00bb qui e&ucirc;t \u00e9t\u00e9 de circonstance ; mais non, elle m\u00e9prise, Zakharova ! On ne s&rsquo;adresse pas aux petites mains quand on tient le g\u00e9rant de la boutique, agissant au nom des actionnaires d&rsquo;au-del\u00e0 du grand oc\u00e9an&#8230; Dans cette phrase, le &laquo; <em>inutile<\/em> &raquo; dit tout un monde de m\u00e9pris indiff\u00e9rent :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Je veux rappeler \u00e0<\/em> [Olaf] <em>Scholz<\/em>&quot;<em>, a d\u00e9clar\u00e9 Zakharova, &ndash; \u00ab\u00a0je ne fais pas r\u00e9f\u00e9rence \u00e0 <\/em>[la ministre des Affaires \u00e9trang\u00e8res Annalena] <em>Baerbock, cela me semble inutile<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Une col\u00e8re russe<\/h3>\n<\/p>\n<p><p>Puisqu&rsquo;on est dans du Zakharova, on continue. Cette ravissante porte-parole \u00e0 la langue bien pendue fonctionne au sein de la politique de s\u00e9curit\u00e9 nationale russe comme une voix de d\u00e9foulement complet pour la lib\u00e9ration de la profonde pens\u00e9e russe. Zakharova dit tout haut, mais vraiment tr\u00e8s haut, ce que tous les dirigeants russes pensent tout bas et marmonnent entre leurs dents, &ndash; et ce qu&rsquo;elle dit doit plaire \u00e0 beaucoup de Russes.<\/p>\n<\/p>\n<p><p>Ici, sa fureur est grandiose, \u00ab\u00a0wagn\u00e9rienne\u00a0\u00bb pourrait-on dire au second degr\u00e9 (le <a href=\"https:\/\/www.rt.com\/news\/570075-us-blackwater-russia-wagner-group\/\">groupe PMC<\/a> plut\u00f4t que Richard), parce qu&rsquo;elle concerne la perspective de voir des chars allemands \u00e9craser la terre russe de leurs chenilles, &ndash; \u00e0 nouveau&#8230; Il n&rsquo;y a aucune retenue dans la phrase, m\u00eame si le ton est contenu (&laquo; <em>Je parle doucement ici mais dans la vie de tous les jours ce serait diff\u00e9rent<\/em> &raquo;) et les dirigeants allemands sont rudement interpell\u00e9s par leur seul nom (Helmer souligne ironiquement la chose en rajoutant les pr\u00e9noms entre braquets), avec la volont\u00e9 de n&rsquo;y mettre aucun ingr\u00e9dient apaisant de l&rsquo;habituelle diplomatie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> &laquo; &#8230;<em>\u00ab\u00a0Vous avez pos\u00e9 une question sur la d\u00e9cision des &Eacute;tats-Unis de fournir des chars am\u00e9ricains. Pourquoi le souligner en particulier ? Il est clair que cette position s&rsquo;applique \u00e0 tous les pays. Un seul pays se distingue. Il s&rsquo;agit de l&rsquo;Allemagne. C&rsquo;est une histoire entre nous et eux. Nous nous souvenons bien de ce que sont les chars allemands. Ce sont des machines qui sont devenues un symbole non seulement de la mort et d&rsquo;une id\u00e9ologie mortif\u00e8re, mais aussi de la haine de l&rsquo;humanit\u00e9, &ndash; une menace globale, existentielle, pour la plan\u00e8te enti\u00e8re.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Quand on conna&icirc;t le fascisme, le nazisme et l&rsquo;\u00e9poque de la Seconde Guerre mondiale, je pense qu&rsquo;il est \u00e9vident que l&rsquo;uniforme SS, les chars allemands avec les symboles du Troisi\u00e8me Reich sont devenus un symbole mondial de la chute de l&rsquo;humanit\u00e9 dans l&rsquo;ab&icirc;me de la haine, de l&rsquo;horreur et du meurtre. De cet ab&icirc;me, nous avons tous &#8211; ceux qui \u00e9taient vivants \u00e0 l&rsquo;\u00e9poque et ceux qui sont n\u00e9s plus tard &#8211; \u00e9t\u00e9 extirp\u00e9s par les combattants de l&rsquo;Arm\u00e9e rouge et de la coalition anti-Hitler. Ce sont les jeunes qui ont combattu au front et tous ceux qui \u00e9taient \u00e0 l&rsquo;arri\u00e8re, li\u00e9s \u00e0 eux. Ce sont les chars allemands qui sont devenus l&rsquo;anti-symbole qui s&rsquo;est imprim\u00e9 \u00e0 jamais dans la m\u00e9moire de l&rsquo;humanit\u00e9. Maintenant, ces chars, comme <\/em>[les Allemands]<em> le supposent, vont \u00e0 nouveau se d\u00e9placer sur nos terres. Du moins, c&rsquo;est la t\u00e2che qui leur a \u00e9t\u00e9 confi\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Qu&rsquo;esp\u00e8rent-ils, en Allemagne ? Que des v\u00e9hicules blind\u00e9s peints et couverts de croix de fer &#8211; symboles des forces arm\u00e9es allemandes d&rsquo;hier et d&rsquo;aujourd&rsquo;hui &#8211; traversent nos villes et nos villages ? Nous nous souvenons comment cela s&rsquo;est termin\u00e9 \u00e0 l&rsquo;\u00e9poque. S&rsquo;en souviennent-ils \u00e0 Berlin ?&#8230; Chacun inscrit son nom dans l&rsquo;histoire, \u00e0 sa fa\u00e7on. L&rsquo;Allemagne elle-m\u00eame comprend parfaitement que Berlin n&rsquo;a aucun droit moral, l\u00e9gal ou \u00e9thique de fournir des v\u00e9hicules blind\u00e9s et des chars pour tuer des Russes.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Zakharova a poursuivi en rappelant aux Allemands le meurtre planifi\u00e9 de plus de 3 millions de prisonniers de guerre russes entre 1941 et 1945.  &quot;Je veux rappeler \u00e0 <\/em>[Olaf] <em>Scholz\u00a0\u00bb, a d\u00e9clar\u00e9 Zakharova, \u00ab\u00a0je ne fais pas r\u00e9f\u00e9rence \u00e0<\/em> [la ministre des Affaires \u00e9trang\u00e8res Annalena] <em>Baerbock, cela me semble inutile, &ndash; et lui dire peut-\u00eatre parce qu&rsquo;il ne le sait pas<\/em> <em>: lorsque les prisonniers allemands \u00e9taient sur le territoire de l&rsquo;Union sovi\u00e9tique apr\u00e8s notre victoire, ils n&rsquo;ont pas \u00e9t\u00e9 tortur\u00e9s, ils n&rsquo;ont pas \u00e9t\u00e9 maltrait\u00e9s de la m\u00eame mani\u00e8re que les Allemands l&rsquo;ont fait avec nos soldats et nos civils dans les camps de concentration allemands. Ils \u00e9taient nourris par ceux<\/em> [les Russes]<em> qui n&rsquo;avaient pas eu assez pendant de nombreuses ann\u00e9es, qui n&rsquo;avaient rien \u00e0 manger pour eux-m\u00eames. (Je parle doucement ici mais dans la vie de tous les jours ce serait diff\u00e9rent<\/em> <em>)&#8230; Je me souviens bien comment en 2015, dans le cadre d&rsquo;une d\u00e9l\u00e9gation officielle, le ministre des Affaires \u00e9trang\u00e8res allemand de l&rsquo;\u00e9poque <\/em>[Frank-Walter] <em>Steinmeier est arriv\u00e9 \u00e0 Volgograd.  Il s&rsquo;est repenti et a inclin\u00e9 la t\u00eate devant les tombes des soldats sovi\u00e9tiques et allemands qui sont rest\u00e9s sur notre terre. Et il a dit que cela ne devait plus jamais se reproduire. Vous<\/em> [Scholz]<em>, vous \u00eates en train de le reproduire<\/em>\u00ab\u00a0. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est vrai qu&rsquo;on se demande comment, si ce n&rsquo;est pas l&rsquo;action d&rsquo;un simulacre qui ressemble d\u00e9sormais \u00e0 une drogue diabolique et psych\u00e9d\u00e9lique prescrite par des psychopathes du type-Blinken-Nuland eux-m\u00eames sous totale d\u00e9pendance, &ndash; comment il n&rsquo;est pas apparu \u00e9vident aux yeux de nos d\u00e9cideurs, dirigeants, \u00e9litesSyst\u00e8me et autres zombies en cravate bleue fonc\u00e9e (le col ouvert se porte moins depuis \u00ab\u00a0l&rsquo;inf\u00e2me agression\u00a0\u00bb), que l&rsquo;envoi de chars allemands contre les Russes constituerait un symbole terrible, presque m\u00e9taphysique, comme un signe du Diable.<\/p>\n<\/p>\n<p><p>Tant il est vrai qu&rsquo;avec une telle finesse d&rsquo;\u00e2me, conduite par des Polonais enfi\u00e9vr\u00e9s et de ravissantes &lsquo;<em><a href=\"https:\/\/www.dedefensa.org\/article\/hillary-et-ses-harpies-ou-le-feminisme-guerrier\">Harpies<\/a><\/em>&lsquo; de <a href=\"https:\/\/www.theamericanconservative.com\/speak-loudly-and-carry-someone-elses-big-stick\/\">nouvelle g\u00e9n\u00e9ration<\/a>, on est en train de construire une m\u00e9fiance mortelle, nourrie d&rsquo;une inconfiance qui d\u00e9finit parfaitement la fa\u00e7on dont on assassine sauvagement une confiance maintenue jusqu&rsquo;alors et tant bien que mal, avec une sorte de bienveillance presque na\u00efve. Au fond, les Russes, qui furent les premi\u00e8res victimes de l&rsquo;oppression communiste, avaient, via Gorbatchev, accueilli les Occidentaux comme des \u00ab\u00a0lib\u00e9rateurs\u00a0\u00bb, psychologiquement sans aucun doute mais aussi politiquement. Certains (un Mitterrand certainement, voire un Chirac moins paresseux) \u00e9taient pr\u00eats \u00e0 jouer ce jeu de la confiance. Tout ce qui a suivi, en m\u00eame temps que la prise de pouvoir par les psychopathes, de Blair aux <em>neocon<\/em>, a \u00e9t\u00e9 un long saccage de toutes ces chances de d\u00e9part. L&rsquo;affaire des &lsquo;<em>Leopard<\/em>&lsquo;, d&rsquo;une exquise d\u00e9licatesse, nous met une <em>kolossal <\/em>cerise rouge-sang sur le g\u00e2teau.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le tango Blinken-Nuland 31 janvier 2023 (07H00) &ndash; J&rsquo;avoue platement avoir compl\u00e8tement rat\u00e9 l&rsquo;histoire du si\u00e8cle, je veux dire \u00ab\u00a0de la semaine derni\u00e8re\u00a0\u00bb, avec mercredi l&rsquo;interview de Blinken par l&rsquo;ami Ignatius (du &lsquo;Post&lsquo;, entre amis), suivi par l&rsquo;audition de l&rsquo;impressionnante Victoria Nuland, en pleine sant\u00e9 et adjointe du pr\u00e9c\u00e9dent, jeudi devant la Commission des Relations&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[16324,21962,3917,13743,3805,21931,7165,21961,12642],"class_list":["post-80498","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-barbarossa","tag-boerbeck","tag-chars","tag-helmer","tag-hitler","tag-leopard","tag-proposition","tag-psychoparhe","tag-zakharova"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80498"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80498\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}