{"id":80550,"date":"2023-03-16T18:26:44","date_gmt":"2023-03-16T18:26:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/03\/16\/notre-perfect-storm-crisique-1\/"},"modified":"2023-03-16T18:26:44","modified_gmt":"2023-03-16T18:26:44","slug":"notre-perfect-storm-crisique-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/03\/16\/notre-perfect-storm-crisique-1\/","title":{"rendered":"Notre \u201c<em>perfect storm<\/em>\u201d crisique"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notre \u00ab\u00a0<em>perfect storm<\/em>\u00a0\u00bb crisique<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Notre constat est d&rsquo;observer <strong>que se met en place, c\u00f4te-\u00e0-c\u00f4te<\/strong> avec la crise de la s\u00e9curit\u00e9 strat\u00e9gique et g\u00e9opolitique qu&rsquo;est la guerre ukrainienne, une crise du syst\u00e8me bancaire de la puissance financi\u00e8re mondiale, &ndash; d&rsquo;autres crises pouvant se rajouter. &bull; Le caract\u00e8re peu ordinaire de l&rsquo;\u00e9v\u00e9nement est <strong>que les deux crises semblent d&rsquo;installer et se renforcer l&rsquo;une l&rsquo;autre<\/strong>, alors qu&rsquo;habituellement, comme ce fut le cas en ao&ucirc;t-septembre 2008, une crise chasse l&rsquo;autre du champ de notre perception. &bull; Nous ne parlons en effet que de perception, c&rsquo;est-\u00e0-dire <strong>l&rsquo;effet sur notre psychologie<\/strong>, c&rsquo;est-\u00e0-<strong>dire la p\u00e9n\u00e9tration de nous-m\u00eames par la <a href=\"\/verite-de-situation\">v\u00e9rit\u00e9-de-situation<\/a> de la crise, et m\u00eame de la <a href=\"\/GrandeCrise\">GrandeCrise<\/a><\/strong>. &bull; Ce que nous observons, c&rsquo;est un ph\u00e9nom\u00e8ne d&rsquo;op\u00e9rationnalisation de la \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-structure-crisique\">structure crisique<\/a>\u00ab\u00a0, comme <strong>un \u00ab\u00a0tourbillon crisique\u00a0\u00bb artistiquement ma&icirc;tris\u00e9, qui devient le composant unique de notre monde, de notre univers<\/strong>. &bull; Nous sommes dans une situation de \u00ab\u00a0<em>perfect storm<\/em>\u00a0\u00bb o&ugrave; les conditions sont r\u00e9unies pour que cette \u00ab\u00a0structure crisique\u00a0\u00bb se r\u00e9v\u00e8le en tant que GrandeCrise, <strong>ou \u00ab\u00a0Crise-Dieu\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>16 mars 2023 (16H30) &ndash; On conna&icirc;t l&rsquo;expression \u00ab\u00a0<em>perfect storm<\/em>\u00a0\u00bb [une \u00ab\u00a0temp\u00eate parfaite\u00a0\u00bb ou un \u00ab\u00a0ouragan parfait\u00a0\u00bb] employ\u00e9e par les Anglo-Saxons pour des \u00e9v\u00e9nements politiques : lorsque toutes les conditions sont r\u00e9unies, comme dans l&rsquo;\u00e9v\u00e9nement m\u00e9t\u00e9orologique, pour que la temp\u00eate atteigne son plus haut degr\u00e9 d&rsquo;intensit\u00e9 possible. Nous avons souvent employ\u00e9 cette expression depuis presque vingt ans (<a href=\"https:\/\/www.dedefensa.org\/article\/la-vision-2006-de-liiss-est-crepusculaire\">depuis 2006<\/a>, selon notre r\u00e9f\u00e9rencier), cela montrant que nous nous trouvons dans des temps de fureur atmosph\u00e9riques o&ugrave; les conditions propices ne cessent de se r\u00e9p\u00e9ter et de se multiplier, &ndash; que cela se fera selon un ajustement parfait, &ndash; que nous y sommes peut-\u00eatre d\u00e9j\u00e0&#8230;<\/p>\n<\/p>\n<p><p>Nous employons en effet l&rsquo;expression une nouvelle fois, dans une p\u00e9riode de &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">tourbillon crisique<\/a>&lsquo; \u00e9videmment sans pr\u00e9c\u00e9dent, &ndash; les choses avan\u00e7ant toutes dans le m\u00eame sens entropique ou catastrophique pour les structures en place, sans possibilit\u00e9 de se retourner, ni m\u00eame d&#8217;emp\u00eacher l&rsquo;acc\u00e9l\u00e9ration du flux puisqu&rsquo;elles le favorisent, &ndash; cela nous montant sans le moindre doute qu&rsquo;un \u00e9v\u00e9nement-haut, d&rsquo;au-dessus de notre histoire courante et de nos grandioses illusions sur nous-m\u00eames et sur la ma&icirc;trise par nous-m\u00eames de notre propre destin, domine et imprime le sens g\u00e9n\u00e9ral de la marche des choses. La logique humaine et terrestre de l&rsquo;encha&icirc;nement de cause \u00e0 effet fait le reste, lorsque la cause est universellement et exclusivement d\u00e9constructrice et destructrice ; elle travaille \u00e0 rendre invuln\u00e9rable la perfection de ce \u00ab\u00a0<em>&lsquo;perfect storm&rsquo; <\/em>crisique\u00a0\u00bb, alors que la destruction et la d\u00e9construction, ou <a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">d\u00e9constructuration<\/a>, se r\u00e9alisent \u00e0 l&rsquo;encontre des structures et des constructions du Syst\u00e8me install\u00e9 sur les ruines d\u00e9truites et d\u00e9construites de ce qui pr\u00e9c\u00e9da la modernit\u00e9, &ndash; dans ce cas, d\u00e9constructuration et destruction vertueuses, armes de l&rsquo;adversaire retourn\u00e9e contre lui (Sun-tsu).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">L&rsquo;Art des deux-crises<\/h3>\n<\/p>\n<p><p>De quelle sorte de \u00ab\u00a0<em>&lsquo;perfect storm&rsquo; <\/em>crisique\u00a0\u00bb parlons-nous ? D&rsquo;une sorte presque artistique, &ndash; par la marque de l&rsquo;harmonie et de la stabilit\u00e9 d&rsquo;\u00e9quilibre entre eux, telles que nous les constatons, &ndash; dans la mesure o&ugrave; deux \u00e9v\u00e9nements d&rsquo;une semblable force qui en g\u00e9n\u00e9ral se concurrencent avec l&rsquo;un l&#8217;emportant sur l&rsquo;autre, avec des liens constitutionnels entre eux mais des diff\u00e9rences souveraines, demeurent pareillement en place et conjuguent leur puissance pour atteindre la perfection en question.<\/p>\n<\/p>\n<p><p>L&rsquo;aspect artistique de la situation est de parvenir \u00e0 une sorte d&rsquo;harmonie et \u00e0 une sorte de stabilit\u00e9 avec des \u00e9v\u00e9nements furieux et des \u00e9l\u00e9ments d\u00e9cha&icirc;n\u00e9s, c&rsquo;est-\u00e0-dire avec le mouvement m\u00eame, et souvent le mouvement fou. L&rsquo;on sent bien qu&rsquo;il y a l\u00e0 une action sup\u00e9rieure, quelque chose qui ressemblerait ironiquement \u00e0 un double, contradictoire pour le sens invoqu\u00e9, de \u00ab\u00a0la main invisible du march\u00e9\u00a0\u00bb, &ndash; ce serait \u00ab\u00a0la main invisible de la <em>&lsquo;perfect storm&rsquo; <\/em>crisique\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de deux \u00e9v\u00e9nements crisiques fondamentaux, tous deux pr\u00e9par\u00e9s, esquiss\u00e9s, renforc\u00e9s, mis en veille, etc., auparavant, &ndash; et qui, pour ce cas chronologique, se mettent en place parall\u00e8lement et pareillement (m\u00eame si l&rsquo;un a pris de l&rsquo;avance sur l&rsquo;autre, peu importe : notre remarque n&rsquo;est pas de l&rsquo;ordre de l&rsquo;\u00e9volution de la substance mais de l&rsquo;ordre de la stabilit\u00e9 de l&rsquo;essence).<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;une part, la guerre en Ukraine n\u00e9e directement de l&rsquo;encha&icirc;nement strat\u00e9gique que l&rsquo;on conna&icirc;t, depuis 1989-1991, avec l&rsquo;\u00e9largissement de l&rsquo;OTAN, la catastrophique \u00e9volution europ\u00e9enne, le gigantisme pathologique et financier de la puissance militaire US jusqu&rsquo;au bin\u00f4me paralysie-impuissance ; et la guerre en Ukraine avec tout son train de cons\u00e9quences g\u00e9opolitiques, de relations internationales, de puissance militaire, d&rsquo;actions et de r\u00e9actions psychologiques ;<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;autre part, l&rsquo;\u00e9branlement du syst\u00e8me bancaire (BSV et la suite), venu directement de la crise de 2007-2008 jamais r\u00e9solue, laquelle est venue directement des conditions financi\u00e8res mises en place avec la fin de la Guerre Froide, la d\u00e9vastation de la Russie et la globalisation, la compl\u00e8te d\u00e9r\u00e9gulation de la fin des ann\u00e9es 1990 (liquidation du <a href=\"https:\/\/www.history.com\/topics\/great-depression\/glass-steagall-act\"><em>Glass-Steagall Act<\/em><\/a>) ; \u00e9branlement avec tout son train de cons\u00e9quences structurelles et psychologiques tueuses de toute possibilit\u00e9 de stabilit\u00e9 et d&rsquo;harmonie sociales et soci\u00e9tales<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0deuxi\u00e8me crise\u00a0\u00bb, avec quelques banques liquid\u00e9es aux USA et des menaces directes contre d&rsquo;autres, notamment le consid\u00e9rable Cr\u00e9dit Suisse, est entr\u00e9e dans la communication crisique publique depuis une bonne d\u00e9cade, dans un climat survolt\u00e9 d&rsquo;attente (espoir, crainte, pr\u00e9visionnisme, etc.) pour cette sorte de crise financi\u00e8re globale. On peut d\u00e9j\u00e0 faire l&rsquo;hypoth\u00e8se qu&rsquo;une logique d&rsquo;encha&icirc;nement (plut\u00f4t que d&rsquo;effondrement) est en marche. Cette logique est brutale, puissante, mais elle n&rsquo;est pas pour l&rsquo;instant explosive ; elle semble faite pour durer dans cette structure \u00e9v\u00e9nementielle avec une place de premier plan dans la communication, donc dans la perception, &ndash; car c&rsquo;est bien de perception que nous parlons, celle qui fait la psychologie et produit l&rsquo;histoire telle que nous la percevons dans sa dimension m\u00e9tahistorique.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">2023 n&rsquo;est pas 2008 malgr\u00e9 la parent\u00e8le<\/h3>\n<\/p>\n<p><p>Ce qui est remarquable est que la \u00ab\u00a0deuxi\u00e8me crise\u00a0\u00bb n&rsquo;a pas rejet\u00e9 la \u00ab\u00a0premi\u00e8re crise\u00a0\u00bb (l&rsquo;Ukraine et le reste) dans une position secondaire. Plut\u00f4t, elle s&rsquo;est plac\u00e9e \u00e0 c\u00f4t\u00e9 d&rsquo;elle, contrairement \u00e0 ce que l&rsquo;on sait de cette sorte de circonstances. Une comparaison peut \u00eatre propos\u00e9e avec les mois d&rsquo;ao&ucirc;t-septembre 2008 :<\/p>\n<\/p>\n<p><p>&bull; Le 7 ao&ucirc;t 2008 commence la crise de l&rsquo;Oss\u00e9tie du Sud et la deuxi\u00e8me \u00ab\u00a0guerre de l&rsquo;Oss\u00e9tie du Sud\u00a0\u00bb, ou \u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Guerre_russo-g\u00e9orgienne_de_2008\">guerre russo-g\u00e9orgienne<\/a>\u00a0\u00bb de 2008. La situation est extr\u00eamement tendue et fait craindre un embrasement europ\u00e9en. Un cessez-le-feu puis un retrait russe interviennent mais la tension se poursuit en septembre, bien entendu, avec le surgissement de questions br&ucirc;lantes de s\u00e9curit\u00e9 europ\u00e9enne.<\/p>\n<\/p>\n<p><p>&bull; Le 15 septembre 2008, la \u00ab\u00a0deuxi\u00e8me guerre&#8230;\u00a0\u00bb passe \u00e0 la trappe, remplac\u00e9e en premi\u00e8re ligne de la communication par le faillite de Lehman Brothers et l&rsquo;explosion du Wall Street puis de la suite. La \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/la-crise-crescendo-et-fortissimo\">deuxi\u00e8me crise<\/a>\u00a0\u00bb a compl\u00e8tement  \u00e9clips\u00e9 la \u00ab\u00a0premi\u00e8re crise\u00a0\u00bb, &ndash; laquelle durera bien s&ucirc;r, et m\u00eame des ann\u00e9es, &ndash; jusqu&rsquo;\u00e0 nous, certes ! (Sollicit\u00e9 par Medvedev, Sarko <a href=\"https:\/\/www.dedefensa.org\/article\/sarko-dans-la-breche-medvedev-en-bandouliere\">ratera compl\u00e8tement le coche<\/a>.) Mais dans la perception, et dans l&rsquo;appr\u00e9ciation de directions politiques de plus en plus affaiblies et rejet\u00e9es dans une perception de l&rsquo;instant, elle s&rsquo;efface.<\/p>\n<\/p>\n<p><p>Effectivement, l&rsquo;int\u00e9r\u00eat de cette comparaison est que les deux crises d&rsquo;ao&ucirc;t-septembre 2008 sont les deux parents des deux crises actuelles, comme deux \u00ab\u00a0r\u00e9pliques sismiques\u00a0\u00bb \u00e0 l&rsquo;envers, mais qu&rsquo;elles ont \u00e9volu\u00e9 selon des perceptions diff\u00e9rentes, avec des \u00e0-coups pour l&rsquo;une et pour l&rsquo;autre, chaque fois l&rsquo;une s&rsquo;effa\u00e7ant au profit de l&rsquo;autre. La diff\u00e9rence avec aujourd&rsquo;hui, &ndash; nous parlons toujours de perception, &ndash; est que les deux \u00ab\u00a0crises\u00a0\u00bb, ces deux \u00e9normes brandons ardents mena\u00e7ant l&rsquo;ordre de la structure s\u00e9curitaire mondiale dans tous ses aspects et l&rsquo;ordre de la structure \u00e9conomique mondiale dans tous ses aspects, se tiennent c\u00f4te-\u00e0-c\u00f4te sans qu&rsquo;aucune n&rsquo;exclue l&rsquo;autre. Nous avons en m\u00eame temps l&rsquo;\u00e9branlement de Cr\u00e9dit Suisse et la noyade du drone MQ-9 de l&rsquo;USAF \u00e0 cause d&rsquo;un pet intempestif d&rsquo;un Su-27, &ndash; c&rsquo;est cela, non ? L&rsquo;un ne chasse pas l&rsquo;autre, on cohabite, &ndash; 2023 n&rsquo;est pas 2008.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La \u00ab\u00a0Crise-Dieu\u00a0\u00bb est op\u00e9rationnelle<\/h3>\n<\/p>\n<p><p>Notre hypoth\u00e8se op\u00e9rationnelle rejoint une hypoth\u00e8se th\u00e9orique d\u00e9velopp\u00e9e dans le &lsquo;<em>Glossaire.dde<\/em>&lsquo; : la &laquo; <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-structure-crisique\">Structure crisique<\/a><\/em> &raquo;. On rappellera ici ce que nous disions dans le &lsquo;<em>chap\u00f4<\/em>&lsquo; du sujet, qui tentait d&rsquo;en expliquer le m\u00e9canisme. Ce \u00e0 quoi nous assistons aujourd&rsquo;hui est l&rsquo;accomplissement, ou plut\u00f4t la \u00ab\u00a0banalisation\u00a0\u00bb de la ma&icirc;trise d&rsquo;un \u00ab\u00a0tourbillon crisique\u00a0\u00bb en un univers nouveau, beaucoup plus ferme, structure solide mais qui est bien entendu une \u00ab\u00a0structure crisique\u00a0\u00bb en pleine \u00e9volution acc\u00e9l\u00e9r\u00e9e ; &ndash; \u00ab\u00a0structure crisique\u00a0\u00bb o&ugrave; tout est crise, et o&ugrave; donc la cohabitation de deux crises diff\u00e9rentes, chacune d&rsquo;elle \u00e9norme, et pourtant chacune d&rsquo;elle supportant l&rsquo;autre, est tout \u00e0 fait possible, sinon recommand\u00e9e, sinon favoris\u00e9e&#8230;<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit bien, comme mentionn\u00e9 dans l&rsquo;extrait ci-dessous, d&rsquo;une m\u00e9tahistoire directement accessible \u00e0 la lumi\u00e8re d&rsquo;une m\u00e9tapolitique, ou &laquo; <em>m\u00e9taphysique directement accessible<\/em> &raquo;, &ndash; \u00e0 la lumi\u00e8re de la  r\u00e9f\u00e9rence <a href=\"https:\/\/www.dedefensa.org\/article\/constat-de-finkielkraut\">d&rsquo;une remarque<\/a> du philosophe Alain Finkielkraut, &ndash; qui comprend aussi parfaitement la texture de &laquo; <em>nos-temps-devenus-fous<\/em> &raquo; qu&rsquo;il ne comprend rien \u00e0 la guerre en Ukraine.<\/p>\n<\/p>\n<p><p>(Le &lsquo;<em>chap\u00f4<\/em>&lsquo; de la &laquo; <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-structure-crisique\">Structure crisique<\/a><\/em> &raquo; que nous reprenons ci-dessous est sous une autre pr\u00e9sentation, plus l\u00e9g\u00e8re, \u00e9barb\u00e9e de ses caract\u00e8res gras et de ses signes typographiques imp\u00e9ratifs, pour lui donner un aspect plus &lsquo;digestible&rsquo; de texte normal&#8230; Bonne lecture tout de m\u00eame !)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> &laquo; <em>Quelle \u00e9poque ! Et dans quels temps vivons-nous ? L&rsquo;on pourrait r\u00e9pondre : \u00ab\u00a0dans nos temps-devenus-fous\u00a0\u00bb, mais ce serait insuffisant, indication du caract\u00e8re principal de \u00ab\u00a0nos temps\u00a0\u00bb mais nullement leur description ni leur explication.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nous d\u00e9veloppons donc ici une explication conceptuelle plus ambitieuse, que nous avons d\u00e9j\u00e0 souvent effleur\u00e9e en d\u00e9crivant tel ou tel aspect de \u00ab\u00a0la crise\u00a0\u00bb, \u00ab\u00a0des crises\u00a0\u00bb, etc. Notre hypoth\u00e8se est celle de la \u00ab\u00a0structure crisique\u00a0\u00bb, c&rsquo;est-\u00e0-dire l&rsquo;id\u00e9e que le temps et la forme des \u00e9v\u00e9nements, et par cons\u00e9quent l&rsquo;espace \u00e9galement, ne sont que crisiques et rien d&rsquo;autre.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il s&rsquo;agit au fond d&rsquo;une adaptation de la composante dynamique de l&rsquo;univers (temps, espace et mati\u00e8re) transpos\u00e9e \u00e0 une p\u00e9riode tout \u00e0 fait particuli\u00e8re, si particuli\u00e8re que la torsion des trois composants (temps, \u00e9v\u00e9nements, espace) institue une autre dimension, nous faisant passer en une \u00ab\u00a0p\u00e9riode m\u00e9tahistorique\u00a0\u00bb, m\u00e9taphysique directement accessible.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans la deuxi\u00e8me partie de cette pr\u00e9sentation de la &laquo; <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-structure-crisique\">Structure crisique<\/a><\/em> &raquo;, nos retrouvons une description de l&rsquo;\u00e9volution identifi\u00e9e \u00e0 travers deux crises, consid\u00e9r\u00e9es ici pour les sujets qu&rsquo;elles affectent mais que nous citons dans notre d\u00e9marche de description op\u00e9rationnelle pour leurs aspects m\u00e9thodologiques.<\/p>\n<\/p>\n<p><p>&bull; La crise du Covid repr\u00e9sente une m\u00e9thode d&rsquo;op\u00e9rationnalisation par la surveillance, l'\u00a0\u00bbautoritarisme bienveillant\u00a0\u00bb (pour notre bien, &ndash; notre bonne sant\u00e9) que l&rsquo;on retrouve, &ndash; d&rsquo;une part, dans les conditions de plus en plus restrictives impos\u00e9es au trafic de l&rsquo;argent et \u00e0 la forme de l&rsquo;argent avec la complicit\u00e9 des banques, \u00e9l\u00e9ment tr\u00e8s pr\u00e9sent dans la crise bancaire ; &ndash; d&rsquo;autre part, dans le conformisme du jugement r\u00e9clam\u00e9 imp\u00e9rativement selon le contr\u00f4le de la communication, l&rsquo;utilisation d\u00e9ment du simulacre, etc., \u00e9l\u00e9ments \u00ab\u00a0tr\u00e8s pr\u00e9sents\u00a0\u00bb dans le regard que nous sommes aimablement invit\u00e9s \u00e0 porter sur la guerre ukrainienne.<\/p>\n<\/p>\n<p><p>&bull; Le wokenisme est le terminus-bouffe de la  tendance absolument partout pr\u00e9sente \u00e0 la d\u00e9constructuration, jusqu&rsquo;\u00e0 une sorte de comportement suicidaire dans la m\u00e9thodologie caract\u00e9risant l&rsquo;action du Syst\u00e8me dans les deux grandes crises consid\u00e9r\u00e9es. C&rsquo;est une \u00e9vidence pour l&rsquo;Ukraine dont le th\u00e8me central est la <a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">d\u00e9constructuration<\/a>, que ce soit pour l&rsquo;Ukraine elle-m\u00eame, que ce soit dans les r\u00eaves de l'\u00a0\u00bbOccident-solidaire\u00a0\u00bb pour la Russie. Dans la crise bancaire, c&rsquo;est encore plus remarquable et original, dans la mesure o&ugrave; les \u00e9tablissements bancaires se sont pr\u00e9cipit\u00e9s d&rsquo;une fa\u00e7on \u00e9tonnante dans l&rsquo;adoption de toutes les mesures du wokenisme, des LGTBQ+ etc., comme nous l&rsquo;avons signal\u00e9, &ndash; ce qui permet aux banquiers de faire du trangenre des $millions aux $trillions.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nous offrons une description de la structure crisique, compos\u00e9e de crises diverses qui, dans cette s\u00e9quence, n&rsquo;ont ni d\u00e9but ni fin, mais d\u00e9pendent toutes de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me<strong>, <\/strong>cette <a href=\"\/GCES\">GCES<\/a> devenant une sorte de \u00ab\u00a0crise-Dieu\u00a0\u00bb \u00e0 laquelle tout nous renvoie. Pour nous, cette r\u00e9volution structurelle d\u00e9cisive, pr\u00e9par\u00e9e par divers \u00e9v\u00e9nements (diverses crises) s&rsquo;est faite avec l&rsquo;ensemble Covid-wokenisme apparu en 2020, &ndash; dont il est \u00e9videmment compl\u00e8tement inutile de chercher une explication historique et rationnelle, &ndash; ni du Covid, ni du wokenisme, ni du reste.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous parlons de \u00ab\u00a0Crise-Dieu\u00a0\u00bb dans le chef de la GCES, ce qui implique effectivement l&rsquo;installation d&rsquo;une structure crisique universelle et cosmique, o&ugrave; la \u00ab\u00a0crise\u00a0\u00bb devient le composant essentiel de l&rsquo;univers en complet bouleversement. Dans ce cas, aucune crise ne le c\u00e8de \u00e0 aucune autre, il s&rsquo;agit d&rsquo;un processus de transformation dynamique qui affecte le monde lui-m\u00eame, &ndash; \u00ab\u00a0crise globalis\u00e9e\u00a0\u00bb dirions-nous banalement, pour ce qui concerne le domaine dont la perception nous est permise, &ndash; ce qui est bien autre chose que la \u00ab\u00a0crise de la globalisation\u00a0\u00bb, bien entendu.<\/p>\n<\/p>\n<p><p>Nous voguons sur les flots d\u00e9cha&icirc;n\u00e9s de la \u00ab\u00a0&lsquo;<em>perfect storm<\/em>&lsquo; crisique\u00a0\u00bb. Et Cerb\u00e8re ricane en nous disant \u00ab\u00a0Peut-\u00eatre sont-ce les portes de l&rsquo;enfer\u00a0\u00bb ! C&rsquo;est bien connu, Cerb\u00e8re plaisante \u00e0 tout propos&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre \u00ab\u00a0perfect storm\u00a0\u00bb crisique &bull; Notre constat est d&rsquo;observer que se met en place, c\u00f4te-\u00e0-c\u00f4te avec la crise de la s\u00e9curit\u00e9 strat\u00e9gique et g\u00e9opolitique qu&rsquo;est la guerre ukrainienne, une crise du syst\u00e8me bancaire de la puissance financi\u00e8re mondiale, &ndash; d&rsquo;autres crises pouvant se rajouter. &bull; Le caract\u00e8re peu ordinaire de l&rsquo;\u00e9v\u00e9nement est que les deux&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4906,22001,7519,8294,5519,2719,7114,6220,12735,1296],"class_list":["post-80550","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-4906","tag-bsv","tag-credit","tag-crisique","tag-georgie","tag-grandecrise","tag-structure","tag-suisse","tag-tourbillon","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80550"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80550\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}