{"id":80558,"date":"2023-03-26T16:10:14","date_gmt":"2023-03-26T16:10:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/03\/26\/junior-partner-ou-lempire-contre-attaque\/"},"modified":"2023-03-26T16:10:14","modified_gmt":"2023-03-26T16:10:14","slug":"junior-partner-ou-lempire-contre-attaque","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/03\/26\/junior-partner-ou-lempire-contre-attaque\/","title":{"rendered":"\u201c<em>Junior Partner<\/em>\u201d, ou \u201cl&rsquo;Empire contre-attaque\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0<em>Junior Partner<\/em>\u00ab\u00a0, ou \u00ab\u00a0l&rsquo;Empire contre-attaque\u00a0\u00bb<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; La longue rencontre poutine-Xi vue par le monde du simulacre de l'\u00a0\u00bbOccident-collectif\u00a0\u00bb ? <strong>Un pensum adress\u00e9 par le patron (Xi) au &lsquo;<em>Junior Partner<\/em>&lsquo; (Poutine)<\/strong>. &bull; La contre-offensive de l\u00a0\u00bbEmpire&rsquo; devant cette longue offense que furent les trois jours de Moscou, c&rsquo;est bien de tourner la <em>narrative <\/em>et <strong>d&rsquo;orienter le simulacre de fa\u00e7on \u00e0 ce que la Russie semble se transformer en vaincue de l&rsquo;Ukraine et \u00ab\u00a0r\u00e9gime-chang\u00e9\u00a0\u00bb \u00e0 Moscou<\/strong>. &bull; L&rsquo;arme absolue se trouve dans la formule magique : &lsquo;<em>Junior Partner<\/em>&lsquo;, qui tient lieu de parabole du leadership mondial.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><\/p>\n<p>Que dire de la longue rencontre Poutine-Xi ? Quelle est sa v\u00e9ritable signification ? Qu&rsquo;en pensent nos \u00e9litesSyst\u00e8me, ces zombies jamais d\u00e9courag\u00e9s de l&rsquo;\u00eatre de plus en plus ? Aussit\u00f4t, la consigne est pass\u00e9e, &ndash; non pas une note de service complotiste, ni une exhortation bureaucratique, ni un m\u00e2chouilli de Joe Biden, &ndash; non, une formule magique venue d&rsquo;on ne sait o&ugrave; ; devenue aussit\u00f4t un puissant effet de mode, de mim\u00e9tisme, d&rsquo;automatisme de psychologie collective, une bou\u00e9e de sauvetage rh\u00e9torique impos\u00e9e par la toute-puissance syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0formule magique\u00a0\u00bb du zombie-standard est : la Russie a capitul\u00e9 devant la Chine, elle est devenue le \u00ab\u00a0<em>Junior Partner<\/em>\u00a0\u00bb de l&rsquo;Empire du Milieu. Le r\u00e9sultat stra-t\u00e9-gi-que, &ndash; sinon on-to-lo-gi-que, &ndash;  de cet automatisme de la perception des \u00e9litesSyst\u00e8me est implicitement de r\u00e9duire \u00e0 &laquo; <em>un mis\u00e9rable petit tas d&rsquo;ambitions vaines et perdues<\/em> &raquo; la stature de la Russie, &ndash; avant que l&rsquo;on ne s&rsquo;occupe tr\u00e8s s\u00e9rieusement de la Chine, &ndash; mais cela est une autre <em>narrative<\/em>.<\/p>\n<\/p>\n<p><p>C&rsquo;est ce th\u00e8me que d\u00e9veloppe <a href=\"https:\/\/www.moonofalabama.org\/2023\/03\/the-junior-partner-meme-gives-no-insight-to-real-changes.html#more\">le 23 mars<\/a> &lsquo;<em>TheMoonofAlabama<\/em>&lsquo; (MoA en traduction fran\u00e7aise du &lsquo;<em>Sakerfrancophone<\/em>&lsquo; <a href=\"https:\/\/lesakerfrancophone.fr\/la-russie-partenaire-junior-de-la-chine-le-nouveau-meme-a-la-mode\">le 24 mars<\/a>)&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il est assez int\u00e9ressant de voir comment les concepts politiques \u00ab\u00a0occidentaux\u00a0\u00bb sont cr\u00e9\u00e9s et diffus\u00e9s.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Le nouveau vassal de la Chine. La guerre en Ukraine a transform\u00e9 Moscou en <strong>partenaire junior<\/strong> de P\u00e9kin\u00a0\u00bb, 9 ao&ucirc;t 2022, <a href=\"https:\/\/www.foreignaffairs.com\/china\/chinas-new-vassal?check_logged_in=1\">Foreign Affairs<\/a>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0La Chine \u00e9tait le <strong>partenaire junior<\/strong> de la Russie. L&rsquo;Ukraine a chang\u00e9 la donne\u00a0\u00bb, 24 f\u00e9vrier 2023, <a href=\"https:\/\/www.msnbc.com\/opinion\/msnbc-opinion\/war-ukraine-exposed-russia-chinas-junior-partner-rcna72003\">MSNBC<\/a>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0La Russie devient le <strong>partenaire junior<\/strong> de la Chine\u00a0\u00bb, <a href=\"https:\/\/menafn.com\/1105758653\/Russia-Becoming-Chinas-Junior-Partner-Bolton\">John Bolton<\/a> le 13 mars 2023, MENAFN.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Le fatalisme n&rsquo;est pas une option pour aborder les relations Chine-Russie\u00a0\u00bb, 17 mars 2023, <a href=\"https:\/\/www.brookings.edu\/blog\/order-from-chaos\/2023\/03\/17\/fatalism-is-not-an-option-for-addressing-china-russia-relations\/\">Brookings Institute<\/a> : \u00ab\u00a0Les dirigeants chinois semblent guid\u00e9s par trois objectifs principaux dans leur approche de la Russie. Le premier est de s&rsquo;accaparer la Russie sur le long terme en tant que <strong>partenaire junior<\/strong> de la Chine\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La Maison Blanche qualifie la Russie de \u00ab\u00a0<strong>partenaire junior<\/strong>\u00a0\u00bb de la Chine, 21 mars 2023, &lsquo;<a href=\"https:\/\/www.washingtonpost.com\/politics\/2023\/03\/21\/white-house-knocks-russia-chinas-junior-partner\/\">Washington Post<\/a>&lsquo; : \u00ab\u00a0La Russie est-elle d\u00e9sormais un &Eacute;tat client de la Chine, a demand\u00e9 un journaliste au porte-parole du Conseil de s\u00e9curit\u00e9 nationale, John Kirby, lors de la conf\u00e9rence de presse quotidienne de la Maison Blanche. &lsquo;La Russie en est certainement le <strong>partenaire junior<\/strong>&lsquo;, a r\u00e9pondu Kirby, une r\u00e9ponse qui ne manquera pas de faire \u00e9cho au Kremlin et au si\u00e8ge du Parti communiste chinois.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>D&rsquo;un vieil article de Foreign Affairs \u00e0 un r\u00e9dacteur d&rsquo;opinion de MSNBC, en passant par le belliciste Bolton et le groupe de r\u00e9flexion lib\u00e9ral Brookings, jusqu&rsquo;\u00e0 la Maison Blanche.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Et de l\u00e0, ce terme se retrouve, de mani\u00e8re synchronis\u00e9e, dans tous les m\u00e9dias&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Puis, MoA appuie sa d\u00e9monstration de quelques autres titres de journaux comme autant de copi\u00e9s-coll\u00e9s, avant de montrer toute l&rsquo;\u00e9vidente fausset\u00e9 du concept. Il suffit de montrer l&rsquo;\u00e9vidence, effectivement, inutile de \u00ab\u00a0d\u00e9montrer\u00a0\u00bb tant le niveau de la pens\u00e9e est effectivement, du c\u00f4t\u00e9 du \u00ab\u00a0Zombie-collectif\u00a0\u00bb, juste caract\u00e9ris\u00e9 par un &laquo; <em>un mis\u00e9rable petit tas<\/em>&#8230; &raquo; d&rsquo;on ne sait trop quoi.<\/p>\n<\/p>\n<p><p>On signale une approche et une d\u00e9monstration similaires dans <a href=\"https:\/\/caityjohnstone.medium.com\/us-officials-really-really-want-you-to-know-the-us-is-the-worlds-leader-676ee8d455ba\">le chef de Caitline Johnstone<\/a>, qui d\u00e9taille les comportements \u00e0 la fois \u00e9tranges, bureaucratiquement hyst\u00e9riques et robotis\u00e9s de repr\u00e9sentants du syst\u00e8me de l&rsquo;am\u00e9ricanisme, \u00ab\u00a0ma&icirc;tre du monde\u00a0\u00bb&#8230; Si le \u00ab\u00a0<em>Junior Partner<\/em>\u00a0\u00bb n&rsquo;est pas s\u00e9mantiquement pr\u00e9sent, la r\u00e9ponse est positive \u00e0 la question centrale : \u00ab\u00a0Esprit, es-tu l\u00e0 ?\u00a0\u00bb.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>En r\u00e9ponse aux questions qui lui ont \u00e9t\u00e9 pos\u00e9es lors d&rsquo;une <a href=\"https:\/\/www.youtube.com\/watch?v=r3KwvqkNlfk\">conf\u00e9rence de presse lundi<\/a> sur la rencontre Xi Jinping-Vladimir Poutine cimentant une &quot;nouvelle \u00e8re&quot; dans le partenariat strat\u00e9gique entre la Chine et la Russie, John Kirby, du Conseil de s\u00e9curit\u00e9 nationale de la Maison Blanche, a affirm\u00e9 pas moins de sept fois que les &Eacute;tats-Unis sont le &quot;leader&quot; du monde.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Voici quelques extraits de <a href=\"https:\/\/www.whitehouse.gov\/briefing-room\/press-briefings\/2023\/03\/20\/press-briefing-by-press-secretary-karine-jean-pierre-the-cast-of-ted-lasso-and-nsc-coordinator-for-strategic-communications-john-kirby\/\">ses commentaires<\/a> :<\/em><\/p>\n<\/p>\n<p><p>&raquo;  &ndash; <em>Les deux pays se sont rapproch\u00e9s. Mais ce sont tous deux des pays qui s&rsquo;irritent du leadership des &Eacute;tats-Unis dans le monde\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p><em>&raquo; <\/em>[<em>&#8230; <\/em>etc., etc<em>&#8230;<\/em>]<\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;effet de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Illusory_truth_effect\">v\u00e9rit\u00e9 illusoire<\/a> est un biais cognitif qui pousse les gens \u00e0 prendre une chose qu&rsquo;ils ont entendue plusieurs fois pour un fait \u00e9tabli, parce que la fa\u00e7on dont le cerveau humain re\u00e7oit et interpr\u00e8te les informations tend \u00e0 faire peu ou pas de distinction entre la r\u00e9p\u00e9tition et la v\u00e9rit\u00e9. Les propagandistes et les gestionnaires d&#8217;empire tirent souvent parti de cette faille dans notre syst\u00e8me nerveux, et c&rsquo;est ce qui se passe lorsque vous les voyez r\u00e9p\u00e9ter sans cesse des phrases cl\u00e9s qu&rsquo;ils veulent faire croire aux gens.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cette phrase a \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9e r\u00e9cemment lors d&rsquo;une conf\u00e9rence en ligne organis\u00e9e par la Chambre de commerce des &Eacute;tats-Unis, au cours de laquelle l&rsquo;ambassadeur am\u00e9ricain en Chine a affirm\u00e9 que P\u00e9kin <a href=\"https:\/\/caitlinjohnstone.substack.com\/p\/us-ambassador-to-china-were-the-leader\">devait accepter<\/a> que les &Eacute;tats-Unis soient le &lsquo;leader&rsquo; de la r\u00e9gion occup\u00e9e par la Chine.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les gestionnaires de l&#8217;empire am\u00e9ricain s&rsquo;affirment de plus en plus comme les &lsquo;leaders&rsquo; du monde parce que ce &lsquo;leadership&rsquo; autoproclam\u00e9 est contest\u00e9 par la Chine et les nations qui la soutiennent de plus en plus ouvertement, comme la Russie. La plupart des grands sujets d&rsquo;actualit\u00e9 internationale sont directement ou indirectement li\u00e9s \u00e0 cette dynamique, dans laquelle les &Eacute;tats-Unis s&rsquo;efforcent d&rsquo;assurer leur domination plan\u00e9taire unipolaire en contrecarrant la mont\u00e9e en puissance de la Chine et en affaiblissant leurs partenaires.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le message qu&rsquo;ils envoient est le suivant : \u00ab\u00a0Ce monde est \u00e0 nous. C&rsquo;est nous qui commandons. Quiconque pr\u00e9tend le contraire est bizarre et anormal, et il faut s&rsquo;y opposer\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On s&rsquo;attardera enfin \u00e0 la franche rigolade [retour au \u00ab\u00a0<em>Junior partner<\/em>\u00ab\u00a0] que nous offre Alexander Mercouris, qui rel\u00e8ve (\u00e0 partir de la 35<sup>\u00e8me<\/sup> minute sur sa vid\u00e9o de la soir\u00e9e de <a href=\"https:\/\/theduran.com\/russia-advances-bakhmut-avdeyevka-kremennaya-kiev-offensive-rumours-india-relaxed-china-russia\/\">ce 24 mars<\/a>) le m\u00eame \u00e9pisode maniaque de la communication essentiellement anglo-saxonne pour pouvoir se sortir victorieusement de la longue rencontre Poutine-Xi.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230; <em>Il y a aussi une cascade d&rsquo;articles et de d\u00e9clarations officielles \u00e0 propos du fait que la Russie est le \u00ab\u00a0Junior Partner\u00a0\u00bb de cette relation <\/em>[entre la Chine et la Russie]<em>, ce qui est effectivement le cas <\/em>[du point de vue quantitatif] <em>sans que je puisse distinguer en quoi cela constitue un probl\u00e8me<\/em> [marquant une grave d\u00e9faite de la Russie]<em> et sur quelle base en faire un probl\u00e8me, alors qu&rsquo;on voit bien <\/em>[que les Occidentaux] <em>voudraient que la Russie soit subordonn\u00e9e \u00e0 l\u00a0\u00bbOccident-collectif&rsquo; beaucoup plus que la Chine ne veuille qu&rsquo;elle lui soit subordonn\u00e9e &#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>J&rsquo;irais m\u00eame jusqu&rsquo;\u00e0 penser que les Russes et les Chinois ne sont pas m\u00e9contents de cette interpr\u00e9tation qui retarde le moment <\/em>[o&ugrave; les Occidentaux] <em>vont prendre conscience des v\u00e9ritables dimensions d&rsquo;une nouvelle relation qui est beaucoup plus une alliance qu&rsquo;une simple relation amicale&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mercouris pense en effet qu&rsquo;une certaine discr\u00e9tion russo-chinoise, notamment sur le retard apport\u00e9 \u00e0 la publication des documents complets adopt\u00e9s \u00e0 l&rsquo;issue de la rencontre, justifie cette satisfaction d&rsquo;une si compl\u00e8te erreur d&rsquo;interpr\u00e9tation du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> \u00e0 propos des nouveaux liens entre la Russie et la Chine. Cela donne un peu de temps et un peu d&rsquo;air pour permettre la mise en place de ces nouvelles relations sans avoir \u00e0 se garder des coups fourr\u00e9s de la puissance occidentale en plein naufrage.<\/p>\n<\/p>\n<p><p>On comprend l&rsquo;argument de Mercouris qui va dans \u00ab\u00a0le sens du bon sens\u00a0\u00bb, le mot &lsquo;Junior&rsquo; signifiant le plus petit des deux et n&rsquo;ayant pas \u00e0 ses yeux de connotations de servilit\u00e9, de domination, etc. Une telle interpr\u00e9tation qu&rsquo;\u00e9carte Mercouris de fa\u00e7on \u00e9vidente est absurde lorsqu&rsquo;on voit le nombre de domaines o&ugrave; l&rsquo;apport russe \u00e0 la Chine est vital, &ndash; on citera notamment celui des armements, pour les armes anti-a\u00e9riennes et les armes hypersoniques&#8230; Ce n&rsquo;est pas le cas des Anglo-Saxons, qui ont abandonn\u00e9 l&rsquo;anglais shakespearien pour le sabir anglo-am\u00e9ricaniste empreint de n\u00e9ologismes pompeux et sans n\u00e9cessit\u00e9 de d\u00e9monstration, \u00e0 la fois technologisme et \u00ab\u00a0id\u00e9al de puissance\u00a0\u00bb selon Guglielmo Ferrero, constituant les seules \u00ab\u00a0r\u00e9f\u00e9rences principielles\u00a0\u00bb acceptables, compl\u00e8tement conformes au &lsquo;<em>r\u00e8gne de la quantit\u00e9<\/em>&lsquo; de Gu\u00e9non.<\/p>\n<\/p>\n<p><p>Dans tous les cas, il nous semble non seulement utile mais imp\u00e9ratif de nous arr\u00eater \u00e0 cet incident de rh\u00e9torique qui nous en dit bien plus sur le caract\u00e8re, le comportement, et donc les ambitions et les objectifs du syst\u00e8me de l&rsquo;am\u00e9ricanisme, de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, de l&rsquo;Occident-collectif\u00a0\u00bb, du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>, &ndash; selon l&rsquo;expression qui vous plaira, &ndash; que mille et mille rapports et synth\u00e8ses universitaires des <em>tank-thinkers <\/em>choy\u00e9s par le Syst\u00e8me&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Rh\u00e9torique et comportement<\/h3>\n<\/p>\n<p><p>Pour pr\u00e9senter notre structure critique et crisique de l&rsquo;appr\u00e9ciation de cette rh\u00e9torique et de ce comportement, nous suivons deux voies m\u00e9thodologiques : l&rsquo;une psychologique, l&rsquo;autre disons \u00ab\u00a0id\u00e9ologico-symbolique\u00a0\u00bb (o&ugrave; l&rsquo;id\u00e9e de l&rsquo;id\u00e9ologie est repr\u00e9sent\u00e9e symboliquement).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_d.deepblue\" style=\"color:#0f3955; font-size:1.05em\">Projection inculpabilit\u00e9-ind\u00e9fectibilit\u00e9<\/h3>\n<\/p>\n<p><p>Pour nous, l&rsquo;id\u00e9e du \u00ab\u00a0<em>Junior Partner<\/em>\u00a0\u00bb est de l&rsquo;ordre de la projection psychologique et symbolique et r\u00e9pond au duo psychologique de l&rsquo;am\u00e9ricanisme inculpabilit\u00e9-ind\u00e9fectibilit\u00e9, &ndash; comme nous <a href=\"https:\/\/www.dedefensa.org\/article\/avec-le-bonjour-de-poutine\">rappelions r\u00e9cemment<\/a> leur signification, o&ugrave; triomphent les deux principes fondamentaux de cet Outre-Monde, &ndash; le fait indubitable que l&rsquo;Am\u00e9rique n&rsquo;est jamais coupable (jamais du c\u00f4t\u00e9 du Mal) et le fait interminable que l&rsquo;Am\u00e9rique ne peut pas perdre (ne peut \u00eatre vaincue) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Il est vrai que les USA sont prot\u00e9g\u00e9s comme par une cuirasse infranchissable de toute perception acceptable de la r\u00e9alit\u00e9 du monde (autre d\u00e9finition de la folie) par deux ph\u00e9nom\u00e8nes, sortes de \u00ab\u00a0technologies psychologiques\u00a0\u00bb absolument imp\u00e9n\u00e9trables. Nous en parlons et nous les r\u00e9p\u00e9tons souvent car nous pensons qu&rsquo;il faut se convaincre du ph\u00e9nom\u00e8ne et en prendre la mesure et les cons\u00e9quences. Ces deux \u00ab\u00a0technologies psychologiques\u00a0\u00bb (nous adoptons ce terme pour marquer combien tout est de moins en moins humain dans l&rsquo;am\u00e9ricanisme, jusqu&rsquo;\u00e0 l&rsquo;humain lui-m\u00eame, car la folie fait son &oelig;uvre) sont deux traits psychologiques qui rel\u00e8vent de la f\u00e9\u00e9rie-<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fantasy\">fantasy<\/a> propre \u00e0 l&rsquo;am\u00e9ricanisme, et qui sont aujourd&rsquo;hui exacerb\u00e9es jusqu&rsquo;\u00e0 la folie, &ndash; soit l&rsquo;inculpabilit\u00e9 (\u00ab\u00a0sentiment de l&rsquo;absence \u00e0 terme et d\u00e9cisivement de culpabilit\u00e9 de l&rsquo;am\u00e9ricanisme quelle que soit son action\u00a0\u00bb) et l&rsquo;ind\u00e9fectibilit\u00e9 (\u00ab\u00a0sentiment de la certitude <\/em>[de l&rsquo;am\u00e9ricanisme] <em>de ne pouvoir \u00eatre battu dans tout ce qui figure conflit et affrontement\u00a0\u00bb), tels qu&rsquo;ils sont explicit\u00e9s dans<\/em> [ce <a href=\"https:\/\/www.dedefensa.org\/article\/les-usa-face-a-lhypersonique\">texte<\/a>] <em>qui rappelle leurs caract\u00e8res<\/em>&#8230; &raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Pour nous, il existe, face \u00e0 la repr\u00e9sentation-&lsquo;<em>Junior Partner<\/em>&lsquo; de la r\u00e9union Chine-Russie o&ugrave; la Russie serait domin\u00e9e et soumise \u00e0 la Chine un ph\u00e9nom\u00e8ne inconscient de projection des USA, dans le chef de ses \u00e9lites-Zombie engag\u00e9es dans le syst\u00e8me de la communication ; c&rsquo;est-\u00e0-dire une pulsion de projection de l&rsquo;entit\u00e9 US dans l&rsquo;entit\u00e9 chinoise. Dans cette posture psychologique inconsciente, les USA \u00ab\u00a0sont\u00a0\u00bb la Chine (sans les travers de la Chine : inculpabilit\u00e9) qui soumet la Russie en un &lsquo;<em>Junior Partner<\/em>&lsquo; terriblement humili\u00e9. C&rsquo;est une impeccable revanche de la situation ukrainienne et une fa\u00e7on implacable de r\u00e9aliser un <em>regime change <\/em>\u00e0 Moscou (victoires partout : ind\u00e9fectibilit\u00e9). Les USA exercent toujours \u00ab\u00a0leur leadership\u00a0\u00bb sur le monde, &ndash; qui devient un \u00ab\u00a0l(e)asership\u00a0\u00bb tant l&rsquo;intervention est technologiquement impeccable-implacable. Xi n&rsquo;y voit que du feu, ce qui sied aux \u00ab\u00a0brid\u00e9s\u00a0\u00bb.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_d.deepblue\" style=\"color:#0f3955; font-size:1.05em\">Pulsion \u00ab\u00a0id\u00e9al de puissance\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Nous sommes <a href=\"https:\/\/www.dedefensa.org\/article\/surprise-panique-de-louest-collectif\">revenus il y a peu<\/a> sur la notion d'\u00a0\u00bbid\u00e9al de puissance\u00a0\u00bb de Guglielmo Ferrero, par opposition  \u00e0 l'\u00a0\u00bbid\u00e9al de perfection\u00a0\u00bb. C&rsquo;est \u00e0 nouveau ce concept que nous sollicitions pour expliquer la notion de &lsquo;<em>Junior Partner<\/em>&lsquo; selon l&rsquo;entendement am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>Selon l'\u00a0\u00bbid\u00e9al de puissance\u00a0\u00bb, toute dynamique, toute relation, toute entente sont une question de rapport des forces o&ugrave; la quantit\u00e9 joue un r\u00f4le essentiel sinon exclusif, et un rapport de forces \u00e9valu\u00e9 selon une logique de confrontation, d&rsquo;affrontement, de comp\u00e9tition. Dans ce cas, un &lsquo;<em>Junior Partner<\/em>&lsquo; dans une association, voire une alliance, ne peut \u00eatre que soumis \u00e0 la puissance et \u00e0 la domination de son \u00ab\u00a0partenaire\u00a0\u00bb. Cette conception ach\u00e8ve la d\u00e9marche pr\u00e9c\u00e9dente en faisant de la Russie n\u00e9cessairement une victime de la Chine, et de leur alliance une d\u00e9faite compl\u00e8te de la Russie. C&rsquo;est une autre fa\u00e7on d&rsquo;envisager, et donc de conforter la revanche de l&rsquo;Ukraine et le <em>regime change <\/em>de Moscou. L\u00e0 encore le \u00ab\u00a0leadership\u00a0\u00bb-\u00ab\u00a0l(e)asership\u00a0\u00bb des USA est sain et sauf.<\/p>\n<\/p>\n<p><p>Il nous para&icirc;t \u00e9vident que cette construction fantasmagorique est la seule appr\u00e9ciation possible de la position des USA, au travers du d\u00e9tail r\u00e9v\u00e9lateur de la <em>narrative <\/em>du \u00ab\u00a0&lsquo;<em>Junior Partner<\/em>&lsquo; terriblement humili\u00e9\u00a0\u00bb, et en g\u00e9n\u00e9ral du simulacre que constitue dans la perception des USA la crise &lsquo;<em>Ukrisis<\/em>&lsquo; depuis son paroxysme du 24 f\u00e9vrier 2023. La \u00ab\u00a0contre-offensive de l&rsquo;Empire\u00a0\u00bb ne peut, comme celle de l&rsquo;Ukraine elle-m\u00eame, se r\u00e9aliser que dans la m\u00eame dimension de simulacre de l&rsquo;ensemble de la situation.<\/p>\n<\/p>\n<p><p>La question de savoir si tous ceux qui rapportent cette <em>narrative <\/em>y croient ou non est superflue d\u00e8s lors que l&rsquo;effet r\u00e9p\u00e9titif massif tient lieu de v\u00e9rification sourc\u00e9e et que le bin\u00f4me inculpabilit\u00e9-ind\u00e9fectibilit\u00e9 assure un bouclage psychologique herm\u00e9tique contre toute contestation de type autocritique. Cela garantit d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale une poursuite appuy\u00e9e des m\u00eames <em>narrative <\/em>politiques fantasm\u00e9es jusqu&rsquo;\u00e0 la rencontre des premiers obstacles infranchissables de la r\u00e9alit\u00e9 et des premiers naufrages pavillon haut (avec l&rsquo;inscription : \u00ab\u00a0Je ne coule pas, glou glou glou&#8230;\u00a0\u00bb). Tout est donc dit&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&#8230;Que ce soit par leur grand pr\u00e9sident Abraham Lincoln : &laquo; <em>Si la destruction devait un jour nous atteindre, nous devrions en \u00eatre nous-m\u00eames les premiers et les ultimes artisans. En tant que nation d&rsquo;hommes libres, nous devons \u00e9ternellement survivre, ou mourir en nous suicidant<\/em> &raquo; ;<\/p>\n<\/p>\n<p><p>que ce soit par leur grand po\u00e8te Walt Whitman : &laquo; <em>Les &Eacute;tats-Unis sont destin\u00e9s \u00e0 remplacer et \u00e0 surpasser l&rsquo;histoire merveilleuse des temps f\u00e9odaux ou ils constitueront le plus retentissant \u00e9chec que le monde ait jamais connu&hellip;<\/em> &raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 26 mars 2023 \u00e0 16H05<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Junior Partner\u00ab\u00a0, ou \u00ab\u00a0l&rsquo;Empire contre-attaque\u00a0\u00bb &bull; La longue rencontre poutine-Xi vue par le monde du simulacre de l&rsquo;\u00a0\u00bbOccident-collectif\u00a0\u00bb ? Un pensum adress\u00e9 par le patron (Xi) au &lsquo;Junior Partner&lsquo; (Poutine). &bull; La contre-offensive de l\u00a0\u00bbEmpire&rsquo; devant cette longue offense que furent les trois jours de Moscou, c&rsquo;est bien de tourner la narrative et d&rsquo;orienter le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[13826,3977,3015,8617,9692,22013,2667,15106,2730,3965],"class_list":["post-80558","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-caitline","tag-chine","tag-communication","tag-formule","tag-johnstone","tag-magiquede","tag-mercouris","tag-moa","tag-russie","tag-simulacre"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80558"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80558\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}