{"id":80577,"date":"2023-04-10T12:29:48","date_gmt":"2023-04-10T12:29:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/04\/10\/haut-niveau-de-panique\/"},"modified":"2023-04-10T12:29:48","modified_gmt":"2023-04-10T12:29:48","slug":"haut-niveau-de-panique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/04\/10\/haut-niveau-de-panique\/","title":{"rendered":"Haut niveau de panique&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Haut niveau de panique&#8230;<\/h2>\n<\/p>\n<p><p>10 avril 2023 (12H30) &ndash; Voil\u00e0 qu&rsquo;on commence \u00e0 nous dire que c&rsquo;est la panique au Pentagone et un peu partout chez les amis, les divers petites mains de l&rsquo;aventure z\u00e9lenskiste. Cela fait peur \u00e0 tout le monde, les fuites, et plus encore les \u00ab\u00a0fuites\u00a0\u00bb entre guillemets, &ndash; je veux dire, parfaitement identifi\u00e9es dans leur intentionnalit\u00e9. Voyez le Washington &lsquo;<em>Post<\/em>&lsquo; r\u00e9sum\u00e9 par notre <a href=\"https:\/\/www.rt.com\/news\/574426-pentagon-panic-intel-leak\/\">diabolico-fid\u00e8le RT.com<\/a>, &ndash; en ayant \u00e0 l&rsquo;esprit que c&rsquo;est moins le &laquo; <em>haut niveau de panique<\/em> &raquo; que nous voulons vous d\u00e9crire que la cause de la chose et ce qui se cache derri\u00e8re.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Plusieurs responsables occidentaux interrog\u00e9s par le &lsquo;Post&rsquo; ont d\u00e9clar\u00e9 qu&rsquo;ils essayaient toujours d&rsquo;\u00e9valuer les dommages caus\u00e9s par des dizaines de documents de s\u00e9curit\u00e9 nationale divulgu\u00e9s ces derniers jours, beaucoup se demandant comment la violation \u00e9tait pass\u00e9e inaper\u00e7ue pendant si longtemps. Alors que les premiers reportages m\u00e9diatiques sur l&rsquo;affaire ne sont apparus que cette semaine, un lot de documents avait \u00e9t\u00e9 partag\u00e9 sur la plateforme de chat Discord fin f\u00e9vrier et d\u00e9but mars. L&rsquo;authenticit\u00e9 des renseignements reste non v\u00e9rifi\u00e9e.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Deux responsables am\u00e9ricains ont d\u00e9clar\u00e9 au &lsquo;Post&rsquo; que la direction du Pentagone avait \u00ab\u00a0restreint le flux de renseignements\u00a0\u00bb en r\u00e9action \u00e0 la fuite. Une source a d\u00e9crit les mesures comme inhabituellement strictes et t\u00e9moignant d&rsquo;un \u00ab\u00a0haut niveau de panique\u00a0\u00bb parmi les hauts grad\u00e9s. Les responsables am\u00e9ricains et leurs partenaires \u00e9trangers ont \u00e9t\u00e9 \u00ab\u00a0stup\u00e9faits\u00a0\u00bb et m\u00eame \u00ab\u00a0exasp\u00e9r\u00e9s\u00a0\u00bb par le niveau de d\u00e9tail fourni dans les documents, qui ont r\u00e9v\u00e9l\u00e9 comment les &Eacute;tats-Unis \u00ab\u00a0espionnent leurs amis et leurs ennemis\u00a0\u00bb, indique le rapport, sugg\u00e9rant que les fichiers pourraient secouer le monde diplomatique.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce tapage, ce tohu-bohu ne cesse de m&rsquo;\u00e9tonner, &ndash; je veux dire, quant \u00e0 la fragilit\u00e9 de nos dirigeants, leur crainte de \u00ab\u00a0fuites\u00a0\u00bb, d&rsquo;ailleurs selon et concernant des informations qui s&rsquo;av\u00e8rent fabriqu\u00e9es par eux-m\u00eames, fausse, abracadabrantesques, et que l&rsquo;on conna&icirc;t d\u00e9j\u00e0 ainsi que leurs manipulations. (Voyez et \u00e9coutez Chistoforou <a href=\"https:\/\/theduran.com\/nyt-nightmare-doc-leak-running-out-of-s300-putin-super-popular-in-us-bbc-state-news-label-u-1\/\">parler<\/a> d&rsquo;une des \u00ab\u00a0informations\u00a0\u00bb contenues dans le premier paquet de documents, qui est l&rsquo;affirmation publique, d&rsquo;il y a un mois, du ministre anglais de la d\u00e9fense Wallace, selon laquelle 97% de l&rsquo;arm\u00e9e russe est en Ukraine, &ndash; quelle ridicule canard, et voil\u00e0 tout le poulailler qui s&rsquo;affole !)<\/p>\n<\/p>\n<p><p>Bref, tout cela, ces \u00ab\u00a0renseignements\u00a0\u00bb, ces informations secr\u00e8tes et d\u00e9taill\u00e9es que tout le monde conna&icirc;t, ce &lsquo;<em>Top Secret<\/em>&lsquo; en sources ouvertes et en simulacre ferm\u00e9, quelle ridiculerie, th\u00e9\u00e2tre de l&rsquo;absurde r\u00e9duit au flou du rien de l&rsquo;incomp\u00e9tence satisfaite, mascarade, cirque de basse-cour&#8230; &lsquo;<em>Clown World<\/em>&lsquo;, dit Christoforou, &ndash; et, comme dit <a href=\"https:\/\/www.dedefensa.org\/article\/ukrisis-simulacres-et-contre-simulacres\">l&rsquo;autre anonyme<\/a>, &laquo; <em>Nous ne pouvons plus d\u00e9terminer o&ugrave; est la v\u00e9rit\u00e9 et o&ugrave; est le mensonge<\/em> &raquo;. Alors, moi, ce qui m&rsquo;int\u00e9resse beaucoup plus que ces \u00e9nigmes de carnaval, c&rsquo;est cette double question : qui et pourquoi ?<\/p>\n<\/p>\n<p><p>J&rsquo;y viens, parce que nos commentateurs favoris, tous ces anciens officiers du renseignement pass\u00e9s \u00e0 la dissidence, \u00e9voquent la question. Et tous, ils semblent d&rsquo;accord : ce sont des gens des services US, des \u00ab\u00a0lanceurs d&rsquo;alerte\u00a0\u00bb, &ndash; si vous voulez, en r\u00e9f\u00e9rence tr\u00e8s pr\u00e9cise (on le verra plus loin) \u00e0 Daniel Ellsberg et \u00e0 ses &lsquo;<em>Pentagon Papers<\/em>&lsquo; de 1971, &ndash; des officiers qui veulent vraiment mettre un d\u00e9sordre paradoxalement r\u00e9parateur, &ndash; sorte de tactique du \u00ab\u00a0contre-feu\u00a0\u00bb, &ndash;  dans cet asile de fou qu&rsquo;est devenue l&rsquo;administration Biden avec son annexe sympathique et rassembleuse de l&rsquo;OTAN-Bruxelles ; et leurs intentions seraient \u00e9videmment d&rsquo;entraver et de mettre un terme \u00e0 la folle intervention US en Ukraine et aux perspectives de guerre avec la Russie.<\/p>\n<\/p>\n<p><p>Dans un article du <a href=\"https:\/\/sonar21.com\/are-the-leaked-military-intelligence-docs-legit\/\">7 avril 2023<\/a> sur son site, Larry Johnson \u00e9crit notamment :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;un de mes amis, toujours actif au sein de la communaut\u00e9 du renseignement, s&rsquo;est \u00e9tonn\u00e9 que cela <\/em>[les fuites]<em> n&rsquo;ait pas eu lieu plus t\u00f4t, compte tenu de l&rsquo;agitation qui r\u00e8gne dans certains rangs de la communaut\u00e9 du renseignement au sujet de la politique am\u00e9ricaine en Ukraine et des craintes que les &Eacute;tats-Unis ne s&rsquo;acheminent vers une guerre inutile avec la Russie<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Un peu plus loin, Johnson cite longuement un courriel d&rsquo;un autre de ses amis toujours en service dans le renseignement, qui examine en d\u00e9tails, en se r\u00e9f\u00e9rant \u00e0 l&rsquo;identit\u00e9 et aux sigles bureaucratiques des divers documents fuit\u00e9s, d&rsquo;o&ugrave; ils peuvent venir. Pour lui et pour clore son enqu\u00eate, les fuites sont n\u00e9cessairement d&rsquo;origine US et ne peuvent venir que de deux services :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&#8230; Il nous reste donc l&rsquo;\u00e9tat-major interarm\u00e9es<\/em> [JCS] et l&rsquo;EUCOM [commandement US en Europe].  <em>&Agrave; mon avis, c&rsquo;est l&rsquo;EUCOM.  Ce n&rsquo;est qu&rsquo;une supposition.  Quelqu&rsquo;un qui est plus proche de la boucherie<\/em> [en Ukraine] <em>serait plus motiv\u00e9 pour faire quelque chose \u00e0 ce sujet<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Une autre source va dans le m\u00eame sens de la protestation contre la guerre en Ukraine, dans les textes que j&rsquo;ai consult\u00e9s, sans recherches particuli\u00e8res sur ce sujet pr\u00e9cis. Il s&rsquo;agit d&rsquo;une intervention de la colonelle [USAF] \u00e0 la retraite Karen Kwiatkowski, devenue analyste de renseignement en 1999, puis retrait\u00e9e volontaire et \u00ab\u00a0dissidente\u00a0\u00bb <a href=\"https:\/\/www.dedefensa.org\/article\/souvenir-de-la-maison-des-fables\">depuis 2003<\/a>, apr\u00e8s avoir constat\u00e9 l&rsquo;impunit\u00e9 extraordinaire dont disposaient les <em>neocon <\/em>dans l&rsquo;administration GW Bush et la fa\u00e7on dont ils distordaient compl\u00e8tement le renseignement pour favoriser les guerres d&rsquo;agression qui eurent lieu dans la p\u00e9riode. Kwiatkowski est rest\u00e9e tr\u00e8s active dans la dissidence. Elle est interrog\u00e9e par &lsquo;<em><a href=\"https:\/\/fr.sputniknews.africa\/20230408\/fuite-du-pentagone-le-fruit-de-frustrations-face-a-ladministration-biden-1058450478.html\">Sputnik<\/a><\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Cette fuite m&rsquo;\u00e9voque une frustration de militaires ou d&#8217;employ\u00e9s vis-\u00e0-vis de l&rsquo;administration Biden et de son exigence d&rsquo;une victoire am\u00e9ricaine contre la Russie, laquelle n&rsquo;est aucunement possible. Cela pourrait aussi \u00eatre la frustration d&rsquo;agents des renseignements face aux exigences d&rsquo;une production fa\u00e7onn\u00e9e et adapt\u00e9e, une production qui \u00e9limine l&rsquo;analyse objective pour s&rsquo;aligner sur les d\u00e9sirs politiques de l&rsquo;administration et les soutenir\u00a0\u00bb, d\u00e9clare-t-elle ainsi \u00e0 Sputnik.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;officier \u00e0 la retraite estime que ces fuites pourraient b\u00e9n\u00e9ficier \u00e0 la Russie, lui permettant de confirmer ou de corriger les donn\u00e9es de ses services de renseignement sur l&rsquo;\u00e9tat des forces ukrainiennes. Cela permet aussi \u00e0 Moscou d&rsquo;\u00e9valuer la qualit\u00e9 des renseignements am\u00e9ricains.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Sur le plan du contenu, les fuites peuvent confirmer ou infirmer les donn\u00e9es russes sur les livraisons d&rsquo;armes \u00e0 l&rsquo;Ukraine, sur leur \u00e9tat, sur le statut de formation des op\u00e9rateurs ukrainiens, et elles peuvent donner une id\u00e9e de l&rsquo;int\u00e9r\u00eat strat\u00e9gique des &Eacute;tats-Unis pour le champ de bataille ukrainien\u00a0\u00bb, explique Kwiatkowski<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Une appr\u00e9ciation diff\u00e9rente conduit \u00e0 nuancer mais aussi \u00e0 renforcer d&rsquo;une certaine fa\u00e7on l&rsquo;hypoth\u00e8se de l&rsquo;intervention d&rsquo;un ou de plusieurs dissidents \u00e0 l&rsquo;int\u00e9rieur des services de s\u00e9curit\u00e9 nationale. Cette appr\u00e9ciation appara&icirc;t sur le site de Johnson, mais sous la plume d&rsquo;un invit\u00e9, Thomas Lipscomb, <a href=\"https:\/\/sonar21.com\/why-putin-may-have-exposed-the-us-nato-ukraine-operations-documents\/\">hier 9 avril<\/a>.<\/p>\n<\/p>\n<p><p>Lipscomb \u00e9crit \u00e0 plusieurs reprises que la fuite des documents profitent tr\u00e8s largement \u00e0 \u00ab\u00a0Poutine\u00a0\u00bb (\u00e0 la Russie), comme le dit d&rsquo;ailleurs Kwiatkowski, mais pour une autre raison qui est une d\u00e9l\u00e9gitimation selon les sources US\/OTAN elles-m\u00eames de l&rsquo;intervention US et de l&rsquo;OTAN en Ukraine. On est amen\u00e9 \u00e0 interpr\u00e9ter que ce sont donc les Russes qui ont diffus\u00e9 les documents sans que cela ne soit nulle part affirm\u00e9 directement, \u00ab\u00a0techniquement\u00a0\u00bb dirais-je ; l&rsquo;affirmation la plus \u00ab\u00a0directe\u00a0\u00bb est dans le titre, et encore est-elle interpr\u00e9tative : &laquo; <em>Why Putin may have exposed the US\/NATO Ukraine operations documents<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Lipscomb explique tr\u00e8s bien le super-l\u00e9galisme de Poutine, et sa volont\u00e9 de tout faire selon les r\u00e8gles l\u00e9gales les plus pr\u00e9cises possibles, y compris bien entendu l'\u00a0\u00bbOp\u00e9ration Militaire Sp\u00e9ciale\u00a0\u00bb. Il expose diverses actions de Poutine dans ce sens pour arriver \u00e0 s&rsquo;interroger sur le rapport qui existerait entre ce fait et la divulgation des documents qui sont assez peu sensibles bien que couverts par diverses classifications selon l&rsquo;obsession US\/OTAN du \u00ab\u00a0secret&rsquo; bureaucratique&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Qu&rsquo;est-ce que cela a \u00e0 voir avec la publication bizarre de ce qui ressemble \u00e0 100 pages d&rsquo;authentiques m\u00e9morandums secrets d&rsquo;op\u00e9rations US\/OTAN sur l&rsquo;Ukraine ? Apr\u00e8s tout, beaucoup ont correctement observ\u00e9 qu&rsquo;on y trouve vraiment peu d&rsquo;informations exclusives et secr\u00e8tes, et il n&rsquo;y a rien de vraiment surprenant que quelqu&rsquo;un ait pu mettre la main sur les documents. Alors, \u00e0 quoi sert la publication de ces documents et au profit de qui ?<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Peut-\u00eatre permettent-ils d&rsquo;utiliser des documents US\/OTAN, plut\u00f4t que les seules affirmations russes, pour \u00e9tablir un cadre juridique et constituer le dossier de tout r\u00e8glement que Poutine envisage d&rsquo;imposer \u00e0 l&rsquo;Ukraine. Cela aide \u00e0 prouver la th\u00e8se de Poutine selon lequel son intervention \u00e9tait requise par un complot actif et continu men\u00e9 par les &Eacute;tats-Unis pour utiliser l&rsquo;Ukraine pour attaquer et renverser le r\u00e9gime en Russie.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Dans le monde o&ugrave; la guerre d&rsquo;Ukraine a commenc\u00e9, sous une h\u00e9g\u00e9monie am\u00e9ricaine pr\u00e9dominante suppos\u00e9e bas\u00e9e sur des &quot;r\u00e8gles&quot; dict\u00e9es par l&rsquo;inclination du jour de l&rsquo;Am\u00e9rique, le \u00ab\u00a0dossier\u00a0\u00bb de Poutine aurait pu \u00eatre exact selon les normes du droit international mais n&rsquo;avait aucun pouvoir r\u00e9el. Et la puissance financi\u00e8re et militaire occidentale avait subverti de nombreux tribunaux internationaux et organismes de r\u00e9glementation pour servir les int\u00e9r\u00eats occidentaux plut\u00f4t que ceux de la communaut\u00e9 internationale. Mais \u00e9tant donn\u00e9 les immenses changements dans la structure du pouvoir international provoqu\u00e9s par l&rsquo;affrontement en Ukraine, les &Eacute;tats-Unis et l&rsquo;Occident sont entra&icirc;n\u00e9s \u00e0 coups de pied et de cris dans un monde dans lequel ils ne sont que quelques-unes des nombreuses puissances et ne sont plus pr\u00e9dominants. La diplomatie russe a habilement retourn\u00e9 la majorit\u00e9 du monde contre les illusions occidentales de domination. Maintenant que la guerre touche \u00e0 sa fin dans une d\u00e9faite ukrainienne qui expose la faiblesse militaire et \u00e9conomique des puissances occidentales, le bilan &lsquo;de jure&rsquo; de Poutine pourrait devenir op\u00e9rationnel et &lsquo;de facto&rsquo; dans un monde multi-souverain revenant aux normes du droit international.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il y a aussi d&rsquo;autres usages. Avec l&rsquo;exposition de ces documents, Poutine jette les bases d&rsquo;une action de communication visant \u00e0 d\u00e9tourner une partie de la col\u00e8re de la nouvelle Ukraine contre les &Eacute;tats-Unis et l&rsquo;Occident pour l&rsquo;avoir utilis\u00e9e dans une guerre par procuration qui n&rsquo;\u00e9tait pas tant pro-ukrainienne qu&rsquo;antirusse. Cela renforcerait encore plus sa position devant la communaut\u00e9 internationale et devant l&rsquo;histoire elle-m\u00eame<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est remarquable d&rsquo;observer combien cette th\u00e8se et cette analyse rejoignent la situation et la signification du premier des grands lanceurs d&rsquo;alerte, d\u00e9j\u00e0 cit\u00e9 plus haut. Les &lsquo;<em>Pentagon Papers<\/em>&lsquo; de Ellsberg \u00e9taient classifi\u00e9s non pas parce qu&rsquo;ils divulguaient des secrets ultra-sensibles, mais parce qu&rsquo;ils constituaient un ensemble \u00e9norme (des milliers de pages) d&rsquo;informations \u00e0 peu pr\u00e8s toute connues, qui, mises ensemble comme dans un livre d&rsquo;histoire, accablaient totalement les USA et leur responsabilit\u00e9, leur ill\u00e9gitimit\u00e9 dans la guerre du Vietnam. C&rsquo;est la m\u00eame chose que sugg\u00e8re Lipscomb, et l&rsquo;on voit qu&rsquo;il n&rsquo;y a dans l&rsquo;interpr\u00e9tation de l&rsquo;\u00e9v\u00e9nement aucune n\u00e9cessit\u00e9 de l&rsquo;intervention directe des Russes, comme il n&rsquo;y eut pas n\u00e9cessit\u00e9 de l&rsquo;intervention directe des Nord-Vietnamiens dans le cas Ellsberg.<\/p>\n<\/p>\n<p><p>&#8230; Mais l&rsquo;un n&#8217;emp\u00eache pas l&rsquo;autre puisqu&rsquo;ils se compl\u00e8tent ! Dans les deux cas, comme l&rsquo;on comprend bien, les buts et les ambitions de l&rsquo;action des lanceurs d&rsquo;alerte rencontrent ceux des pays victimes de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> d\u00e9velopp\u00e9e par Washington (je classe \u00e9videmment la guerre du Vietnam dans cette cat\u00e9gorie, sans h\u00e9sitation). Toutes ces hypoth\u00e8ses se rencontrent en un bouquet final que je d\u00e9signerais volontiers comme un instant int\u00e9ressant de compl\u00e8te mise \u00e0 nu du simulacre, avec une interpr\u00e9tation op\u00e9rationnelle d&rsquo;un choc frontal entre la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> et une exigence imp\u00e9rative de <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>.<\/p>\n<\/p>\n<p><p>Finalement, le plus spectaculaire se trouve dans ce qui nous est d\u00e9crit comme un &laquo; <em>haut niveau de panique\u00a0\u00bb parmi les hauts grad\u00e9s. <\/em>&raquo; Puis, la pr\u00e9cision, \u00e9galement hautement burlesque sinon franchement-bouffe, entre tous ces divers dirigeants et  g\u00e9n\u00e9raux qui savent parfaitement le comportement US et de l&rsquo;OTAN, et qui jouent les vertueux outrag\u00e9s (\u00ab\u00a0comment, nos amis nous espionnent !\u00a0\u00bb), et jusqu&rsquo;aux \u00e9toil\u00e9s am\u00e9ricanistes eux-m\u00eames (\u00ab\u00a0comment, nous espionnons nos amis !\u00a0\u00bb)&#8230;<\/p>\n<\/p>\n<p><p>Bref, cette r\u00e9p\u00e9tition restera ma chute finale pour ce jour, devant la nudit\u00e9 compl\u00e8te du simulacre, &ndash; \u00ab\u00a0le roi\u00a0\u00bb, non ! &ndash;  \u00ab\u00a0le simulacre est nu !\u00a0\u00bb Certes, nous sommes, nous vertueux dirigeants du \u00ab\u00a0camp du Bien\u00a0\u00bb, nous sommes \u00ab\u00a0stup\u00e9faits\u00a0\u00bb et m\u00eame \u00ab\u00a0exasp\u00e9r\u00e9s\u00a0\u00bb ! Vite, des sels, ils d\u00e9faillent&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les responsables am\u00e9ricains et leurs partenaires \u00e9trangers ont \u00e9t\u00e9 \u00ab\u00a0stup\u00e9faits\u00a0\u00bb et m\u00eame \u00ab\u00a0exasp\u00e9r\u00e9s\u00a0\u00bb par le niveau de d\u00e9tail fourni dans les documents, qui ont r\u00e9v\u00e9l\u00e9 comment les &Eacute;tats-Unis \u00ab\u00a0espionnent leurs amis et leurs ennemis\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Haut niveau de panique&#8230; 10 avril 2023 (12H30) &ndash; Voil\u00e0 qu&rsquo;on commence \u00e0 nous dire que c&rsquo;est la panique au Pentagone et un peu partout chez les amis, les divers petites mains de l&rsquo;aventure z\u00e9lenskiste. Cela fait peur \u00e0 tout le monde, les fuites, et plus encore les \u00ab\u00a0fuites\u00a0\u00bb entre guillemets, &ndash; je veux dire,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[12598,3147,2866,4100,12597,2906,11661,22034,916],"class_list":["post-80577","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-dalerte","tag-ellsberg","tag-johnson","tag-kwiatkowski","tag-lanceur","tag-larry","tag-legalisme","tag-lipscomb","tag-poutine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80577"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80577\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}