{"id":80589,"date":"2023-04-22T16:57:34","date_gmt":"2023-04-22T16:57:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/04\/22\/dedollarisation-woke-dollar-et-le-texas\/"},"modified":"2023-04-22T16:57:34","modified_gmt":"2023-04-22T16:57:34","slug":"dedollarisation-woke-dollar-et-le-texas","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/04\/22\/dedollarisation-woke-dollar-et-le-texas\/","title":{"rendered":"D\u00e9dollarisation, <em>Woke-<\/em>dollar et le Texas"},"content":{"rendered":"<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">D\u00e9dollarisation, <em>Woke-<\/em>dollar et le Texas<\/h3>\n<\/p>\n<blockquote>\n<p><p>&bull; Points de vue divers sur la d\u00e9dollarisation, ce mouvement qui a acquis <strong>une dynamique et une vitesse extraordinaire et qui r\u00e9v\u00e8le la fragilit\u00e9 de l&rsquo;hyperpuissante monnaie US<\/strong>, &ndash; entre ch\u00e2teau de cartes et syst\u00e8me de Ponzi. &bull; Un coup d&rsquo;&oelig;il sur un plan de l&rsquo;Indon\u00e9sie, qui se trouve \u00e0 la porte des BRICS, et des BRICS eux-m\u00eames, qui ne cessent de tirer des plans. &bull; Et surtout, le constat que, <strong>comme une r\u00e9plique, la d\u00e9dollarisation touche les USA eux-m\u00eames<\/strong> et s&rsquo;av\u00e8re une porte ouverte vers la s\u00e9cession, <strong>&Eacute;tat du Texas en t\u00eate bien entendu<\/strong>.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Chacun apporte sa pierre \u00e0 l&rsquo;\u00e9difice : la d\u00e9dollarisation est devenu le principal sujets de conversation du \u00ab\u00a0Village Global\u00a0\u00bb, particuli\u00e8rement dans les quartiers du &lsquo;<em>Global South<\/em>&lsquo;. Les autres, du <a href=\"\/bloc-BAO\">bloc-BAO<\/a> alias &lsquo;Occident-collectif&rsquo;, travaillent \u00e0 affiner l&rsquo;industrie des sanctions et \u00e0 d\u00e9velopper pour le si\u00e8cle prochain un complexe transatlantique capable de produire des obus de 155mm &ndash; pour l&rsquo;instant, tout cela &lsquo;<em>Top Secret<\/em>&lsquo;, m\u00eame pas dans les &lsquo;<em>Pentagon-Papers-II<\/em>&lsquo; du jeune Teixeira.<\/p>\n<\/p>\n<p><p>Le contraste est tout simplement saisissant entre ces activit\u00e9s de d\u00e9dollarisation du &lsquo;reste du monde&rsquo; et les pr\u00e9occupations de l\u00a0\u00bbOccident-collectif&rsquo; conduit par Washington D.C. dont le prince est un vieillard g\u00e2teux et s\u00e9nescent et le Congr\u00e8s un ensemble fi\u00e9vreux d&rsquo;hyst\u00e9ries aveugl\u00e9ment guerri\u00e8res. Nullement pr\u00e9occup\u00e9 de la d\u00e9dollarisation, l\u00a0\u00bbOccident-collectif\u00a0\u00bb \u00e9volue ainsi dans un monde diff\u00e9rent.<\/p>\n<\/p>\n<p><p>On d\u00e9couvre pourtant un coin inattendu dans cette barricade apparemment infranchissable radicale. Il vient de l&rsquo;int\u00e9rieur des &Eacute;tats-Unis, o&ugrave; certains &Eacute;tats, &ndash; le Texas en premier lieu, &ndash; s&rsquo;inqui\u00e8tent de cette situation et comparent l&rsquo;\u00e9volution du dollar et sa possible\/probable catastrophique issue au collapsus de l&rsquo;Union Sovi\u00e9tique. La d\u00e9dollarisation devient alors une des voies majeures possibles, non plus pour un simple changement d&rsquo;organisation des relations internationales, mais pour une mise en cause de l&rsquo;enti\u00e8ret\u00e9 du Syst\u00e8me de notre civilisation.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Au rythme des BRICS<\/h3>\n<\/p>\n<p><p>Commen\u00e7ons par la d\u00e9dollarisation, disons \u00ab\u00a0classique\u00a0\u00bb. Chacun sort un plan de ses laboratoires secrets, comme si chacun se tenait pr\u00eat, comme c&rsquo;est le cas le plus r\u00e9cemment <a href=\"https:\/\/www.rt.com\/business\/575111-brics-dollar-trade-indonesia\/\">de l&rsquo;Indon\u00e9sie<\/a>, &ndash; dont on rappelle sans \u00e9tonnement qu&rsquo;elle est une candidate potentielle \u00e0 l&rsquo;entr\u00e9e dans les BRICS :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;Indon\u00e9sie suit l&rsquo;exemple du groupe BRICS dans sa politique d&rsquo;abandon du dollar am\u00e9ricain dans les transactions commerciales et financi\u00e8res, selon la banque centrale du pays. Jakarta a introduit des transactions en monnaie locale pour r\u00e9gler les \u00e9changes transfrontaliers, a rapport\u00e9 le portail SINDOnews, citant le gouverneur de la Banque d&rsquo;Indon\u00e9sie, Perry Warjiyo.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0L&rsquo;Indon\u00e9sie a commenc\u00e9 \u00e0 diversifier l&rsquo;utilisation de la monnaie sous la forme de transactions en monnaie locale. L&rsquo;orientation est la m\u00eame que celle des BRICS. En fait, l&rsquo;Indon\u00e9sie est plus concr\u00e8te\u00a0\u00bb, a d\u00e9clar\u00e9 M. Warjiyo vendredi, lors d&rsquo;une conf\u00e9rence de presse organis\u00e9e en marge de la r\u00e9union du conseil des gouverneurs.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;Indon\u00e9sie a d\u00e9j\u00e0 mis en &oelig;uvre cette pratique avec un certain nombre de pays, tels que la Tha\u00eflande, la Malaisie, la Chine et le Japon, a-t-il ajout\u00e9. Elle pr\u00e9voit \u00e9galement de signer un accord de coop\u00e9ration avec la Cor\u00e9e du Sud concernant les transactions en monnaie locale au d\u00e9but du mois de mai<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>A Ce point, on peut faire une synth\u00e8se des diverses pouss\u00e9es de fi\u00e8vre dans le domaine de la d\u00e9dollarisation, devenue une activit\u00e9 aussi populaire que la mystique de Wall Street ou le PMU. Bien entendu, les BRICS sont en premi\u00e8re ligne et l&rsquo;on peut d\u00e9j\u00e0 offrir un historique sur plusieurs ann\u00e9es d&rsquo;une des grandes r\u00e9volutions des relations internationales, avec d&rsquo;innombrables cons\u00e9quences politiques en plus des aspects \u00e9conomiques \u00e9vidents.<\/p>\n<\/p>\n<p><p>&#8230;Allant au-del\u00e0 dans le domaine de la psychologie par la perception de la symbolique des grands mouvements internationaux, on peut m\u00eame avancer l&rsquo;id\u00e9e que la d\u00e9dollarisation s&rsquo;impose comme le verrou qui fait sauter \u00e0 une vitesse proprement extraordinaire, et dans un climat psychologique qui semblait n&rsquo;attendre que cela, une <em>narrative <\/em>qui ne croit plus gu\u00e8re \u00e0 elle-m\u00eame et qui devient ainsi un complet simulacre de l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaniste.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La d\u00e9claration de M. Warjiyo intervient alors que le bloc \u00e9conomique des BRICS (Br\u00e9sil, Russie, Inde, Chine et Afrique du Sud) affirme travailler \u00e0 la mise en place d&rsquo;un r\u00e9seau de paiement commun afin de r\u00e9duire la d\u00e9pendance \u00e0 l&rsquo;\u00e9gard du syst\u00e8me financier occidental, et du dollar en particulier. Les pays membres ont accru l&rsquo;utilisation des monnaies locales dans leurs \u00e9changes commerciaux et travaillent \u00e9galement \u00e0 l&rsquo;\u00e9tablissement d&rsquo;une nouvelle monnaie de r\u00e9serve.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le mois dernier, le Br\u00e9sil et la Chine ont sign\u00e9 un accord pour commercer dans leurs propres monnaies, abandonnant ainsi le billet vert comme interm\u00e9diaire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les tentatives de la Chine d&rsquo;abandonner le dollar dans le commerce international se sont intensifi\u00e9es dans le contexte des sanctions radicales prises par les pays occidentaux \u00e0 l&rsquo;encontre de la Russie, l&rsquo;un des principaux producteurs et exportateurs mondiaux d&rsquo;\u00e9nergie. Les responsables politiques indiens ont \u00e9galement pris plusieurs mesures pour abandonner le billet vert au profit du rouble et de la roupie dans leurs \u00e9changes avec Moscou.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La Russie a commenc\u00e9 \u00e0 d\u00e9dollariser son \u00e9conomie en 2014, lorsque l&rsquo;Occident a introduit la premi\u00e8re s\u00e9rie de sanctions contre le pays \u00e0 propos de la Crim\u00e9e. Depuis l&rsquo;ann\u00e9e derni\u00e8re, Moscou encourage l&rsquo;utilisation de monnaies alternatives dans les transactions, le pr\u00e9sident Vladimir Poutine ayant sugg\u00e9r\u00e9 plus t\u00f4t que le yuan chinois soit utilis\u00e9 plus largement, non seulement dans les \u00e9changes avec la Chine, mais aussi dans les transactions de la Russie avec les pays d&rsquo;Afrique et d&rsquo;Am\u00e9rique latine. Les derni\u00e8res donn\u00e9es de la Banque de Russie montrent que le yuan est devenu un acteur majeur du commerce ext\u00e9rieur russe<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le Texas et la d\u00e9dollarisation<\/h3>\n<\/p>\n<p><p>C&rsquo;est \u00e0 ce point que nous voudrions proposer la mise en \u00e9vidence <a href=\"https:\/\/theduran.com\/biden-white-house-out-of-control-w-mike-adams-live\/\">d&rsquo;une intervention<\/a> faite sur le site &lsquo;<em>TheDuran.com<\/em>&lsquo; par le duo Christoforou-Mercouris recevant le commentateur US (texan) Mike Adams, de &lsquo;<em><a href=\"https:\/\/www.brighteon.tv\/Home\">Brighteon.TV<\/a><\/em>&lsquo;. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, nous suivons volontiers Christoforou-Mercouris dans leurs choix, notamment pour leurs interlocuteurs qu&rsquo;ils invitent \u00e0 un entretien. C&rsquo;est donc le cas pour Adams, que nos d\u00e9couvrons \u00e0 l&rsquo;occasion de cette rencontre o&ugrave; il est question de la situation aux USA.<\/p>\n<\/p>\n<p><p>Selon notre exp\u00e9rience et notre appr\u00e9ciation, un commentateur US d&rsquo;une cha&icirc;ne TV grand public parlant sur un r\u00e9seau europ\u00e9en qui est d&rsquo;une audience beaucoup plus restreinte et s\u00e9lectionn\u00e9e, sera inclin\u00e9e \u00e0 parler beaucoup plus librement de certains points sensibles dont il a connaissance de ses contacts. C&rsquo;est de cette fa\u00e7on que nous avons \u00e9cout\u00e9 cet entretien, et notamment un passage compl\u00e8tement fascinant o&ugrave; Adams nous parle de la situation au Texas par rapport \u00e0 Washington et par rapport \u00e0 la d\u00e9dollarisation.<\/p>\n<\/p>\n<p><p>Adams intervient \u00e0 la suite d&rsquo;une intervention de Mercouris sur la fa\u00e7on dont certains amendements essentiels de la Constitution (notamment le deuxi\u00e8me, sur la libert\u00e9 d&rsquo;expression) sont massacr\u00e9s par l&rsquo;administration Biden. Mercouris insiste sur le fait que les USA sont, au contraire des nations europ\u00e9ennes, b\u00e2tis non sur l&rsquo;histoire mais leur Constitution elle-m\u00eame, qui les pr\u00e9c\u00e8de, au contraire de l&rsquo;habitude ; et de ce fait,<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Si la Constitution est bafou\u00e9e, si elle n&rsquo;est plus op\u00e9rative, vous ne vivez plus aux Etats-Unis mais dans quelque chose de diff\u00e9rent&#8230; <\/em> <em>Sans la Constitution, les &Eacute;tats-Unis n&rsquo;existent plus.<\/em>.. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Sur ces phrases, Adams intervient presque en interrompant Mercouris, estimant ainsi dire quelque chose d&rsquo;important, d&rsquo;essentiel, &ndash; et c&rsquo;est bien le cas :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> &laquo; <em>Je dois vous dire que j&rsquo;ai beaucoup de liens avec des personnes tr\u00e8s actives dans la politique<\/em> [dans l&rsquo;&Eacute;tat du Texas] <em>et je peux vous dire que nombre d&rsquo;entre elles travaillent selon la possibilit\u00e9 que les &Eacute;tats-Unis pourraient se d\u00e9sagr\u00e9ger, peut-\u00eatre selon le sch\u00e9ma de l&rsquo;\u00e9clatement de l&rsquo;URSS en 1991 et il existe des plans en cours d&rsquo;\u00e9tude selon l&rsquo;id\u00e9e que le Texas pourrait lancer son propre syst\u00e8me mon\u00e9taire&#8230; Par exemple, il y a deux parlementaires de notre l\u00e9gislature qui pr\u00e9parent un projet de loi qui pr\u00e9voirait une monnaie digitale<\/em> [texane]<em> bas\u00e9e \u00e0 100% sur des r\u00e9serves d&rsquo;or de l&rsquo;&Eacute;tat conserv\u00e9es pr\u00e8s de Waco, au Texas bien entendu, qui sont constitu\u00e9es depuis plusieurs ann\u00e9es<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les propos d&rsquo;Adams montrent, autant par le ton que par les informations qu&rsquo;il donne, qu&rsquo;il s&rsquo;agit d&rsquo;une d\u00e9marche \u00e0 la fois institutionnelle et bureaucratique, c&rsquo;est-\u00e0-dire poursuivie par les autorit\u00e9s de l&rsquo;&Eacute;tat (et d&rsquo;autres &Eacute;tats dit-il sans pr\u00e9ciser lesquels) et non pas par des centres s\u00e9cessionnistes politiquement partisans. L&rsquo;impression qu&rsquo;on \u00e9prouve est celle d&rsquo;une politique d\u00e9lib\u00e9r\u00e9e (et discr\u00e8te) des milieux dirigeants.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le Texas, comme d&rsquo;autres &Eacute;tats<\/em> [de l&rsquo;Union]<em>, se pr\u00e9parent \u00e0 la possibilit\u00e9 de devenir sa propre nation&#8230; Cela ne veut pas dire que le gouverneur pousse en ce moment pour la s\u00e9paration, mais un certain nombre de personnes tr\u00e8s influentes et tr\u00e8s avis\u00e9es sont en train de se pr\u00e9parer \u00e0 une d\u00e9sint\u00e9gration des USA sur le mod\u00e8le sovi\u00e9tique, compte tenu du fait que Washington D.C. est en train d&rsquo;\u00e9voluer vers un mod\u00e8le sovi\u00e9tique, avec un d\u00e9partement de la Justice agissant de cette fa\u00e7on<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>D&rsquo;autres pr\u00e9cisions placent la situation d\u00e9crite par Adams dans le flux de la d\u00e9dollarisation, liant ainsi les situations ext\u00e9rieure et int\u00e9rieure des USA et \u00e9clairant la responsabilit\u00e9 de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> dans la fragilisation et sans doute la d\u00e9sint\u00e9gration des USA. La situation de la s\u00e9cession est envisag\u00e9e avec un grand optimisme, ce qui mesure par contraste le pessimisme extr\u00eame concernant la situation actuelle de l&rsquo;Union \u00e0 partir d&rsquo;un Washington devenu \u00e0 la fois fou, g\u00e2teux et sovi\u00e9tis\u00e9. Adams termine en saluant Robert Kennedy Jr., dont la candidature soul\u00e8ve effectivement beaucoup d&rsquo;int\u00e9r\u00eat (et beaucoup d&rsquo;opposition du Syst\u00e8me, comme on l&rsquo;imagine).<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Mais, dans le cas d&rsquo;une d\u00e9sint\u00e9gration, les &Eacute;tats qui auront leur propre monnaie conna&icirc;tront une sorte de nouvel \u00e2ge d&rsquo;or, n&rsquo;ayant plus \u00e0 payer les taxes f\u00e9d\u00e9rales et ayant un syst\u00e8me mon\u00e9taire efficace et honn\u00eate&#8230; Le Texas et d&rsquo;autres &Eacute;tats envisagent tr\u00e8s fortement de b\u00e9n\u00e9ficier consid\u00e9rablement d&rsquo;un effondrement du dollar&#8230; Avec un tr\u00e8s fort courant de d\u00e9dollarisation qui acc\u00e9l\u00e8re, le dollar pourrait tomber \u00e0 z\u00e9ro, ce qui ne fait aucun doute dans mon esprit, et le gouvernement qu&rsquo;il alimente pourrait s&rsquo;effondrer en cons\u00e9quence dans le chaos et il y aurait alors des &Eacute;tats, ou des regroupements r\u00e9gionaux avec leurs propres monnaies, temporairement ou d\u00e9finitivement, et l&rsquo;Union pourrait alors se r\u00e9former avec une nouvelle capitale, je suis ouvert \u00e0 de telles possibilit\u00e9s&#8230; H\u00e8 ! Peut-\u00eatre Robert Kennedy Junior pourrait devenir le pr\u00e9sident de nouveaux &Eacute;tats-Unis ! Qui sait, et bien des gens se pr\u00e9parent \u00e0 de telles possibilit\u00e9s<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le fil rouge de la d\u00e9dollarisation<\/h3>\n<\/p>\n<p><p>L&rsquo;essentiel dans cet assemblage de nouvelles, c&rsquo;est le lien qu&rsquo;on trouve \u00e9tabli d&rsquo;une fa\u00e7on structurelle entre la situation politique ext\u00e9rieure des USA (l&rsquo;expansion, l&rsquo;h\u00e9g\u00e9monie) et la situation int\u00e9rieure des USA (l&rsquo;union des &Eacute;tats, \u00e9tablie d&rsquo;une main de fer en 1865 avec la victoire du Nord de la Guerre de S\u00e9cession). Comme l&rsquo;observe Mercouris \u00e0 un autre propos, mais proche de celui qu&rsquo;on constate, il s&rsquo;agit de l&rsquo;extr\u00eame n\u00e9cessit\u00e9 pour l&rsquo;existence des USA, d&rsquo;un lien entre la situation de stabilit\u00e9 int\u00e9rieure et la situation d&rsquo;extension et d&rsquo;h\u00e9g\u00e9monie ext\u00e9rieure.<\/p>\n<\/p>\n<p><p>Ce ph\u00e9nom\u00e8ne la d\u00e9dollarisation tel qu&rsquo;il se appara&icirc;t d\u00e9sormais dans sa compl\u00e8te <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> montre qu&rsquo;il existe un lien absolu entre l&rsquo;existence des USA et la politique expansionniste des USA (la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, avatar du Syst\u00e8me, comme les USA eux-m\u00eames). Si l&rsquo;on veut, c&rsquo;est le d\u00e9menti cinglant apport\u00e9 au discours d&rsquo;adieu de Washington en1796, lorsque le premier pr\u00e9sident des USA affirma que les &Eacute;tats-Unis ne devraient jamais se laisser aller \u00e0 des aventures ext\u00e9rieures impliquant des engagements politiques. Il justifiait l&rsquo;isolationnisme, que toute l&rsquo;histoire des USA depuis 1865 combat et qui est aujourd&rsquo;hui devenu absolument impossible \u00e0 admettre psychologiquement.<\/p>\n<\/p>\n<p><p>La d\u00e9dollarisation tel qu&rsquo;on l&rsquo;observe d\u00e9montre absolument la validit\u00e9 de l&rsquo;\u00e9quation \u00ab\u00a0surpuissance (aventure ext\u00e9rieure, h\u00e9g\u00e9monie) = autodestruction (d\u00e9dollarisation, effondrement de l&rsquo;unit\u00e9 int\u00e9rieure)\u00a0\u00bb. Il s&rsquo;agit de rien moins que de l&rsquo;affrontement ultime entre des composants des USA (les &Eacute;tats) qui veulent \u00e9chapper \u00e0 un destin tragique et <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2023-echos-de-dallas-1963\">\u00ab\u00a0l&rsquo;Indicible\u00a0\u00bb<\/a> d\u00e9sign\u00e9 par l&rsquo;historien James W. Douglass \u00e0 propos de l&rsquo;assassinat de Kennedy \u00e0 Dallas en novembre 1963.<\/p>\n<\/p>\n<p><p>Mis en ligne le 22 avril 2023 \u00e0 17H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9dollarisation, Woke-dollar et le Texas &bull; Points de vue divers sur la d\u00e9dollarisation, ce mouvement qui a acquis une dynamique et une vitesse extraordinaire et qui r\u00e9v\u00e8le la fragilit\u00e9 de l&rsquo;hyperpuissante monnaie US, &ndash; entre ch\u00e2teau de cartes et syst\u00e8me de Ponzi. &bull; Un coup d&rsquo;&oelig;il sur un plan de l&rsquo;Indon\u00e9sie, qui se trouve \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7849,11035,9359,3650,9117,2949],"class_list":["post-80589","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alternative","tag-brics","tag-expansionnisme","tag-hegemonie","tag-monnaie","tag-secession"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80589"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80589\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}