{"id":80623,"date":"2023-05-26T10:19:44","date_gmt":"2023-05-26T10:19:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/05\/26\/contre-offensiver-la-contre-offensive\/"},"modified":"2023-05-26T10:19:44","modified_gmt":"2023-05-26T10:19:44","slug":"contre-offensiver-la-contre-offensive","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/05\/26\/contre-offensiver-la-contre-offensive\/","title":{"rendered":"Contre-offensiver la contre-offensive"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Contre-offensiver la contre-offensive<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; C&rsquo;est dans l&rsquo;esprit du plus grand s\u00e9rieux de l'\u00a0\u00bbart op\u00e9ratif\u00a0\u00bb des directions gouvernementales et strat\u00e9giques de l&rsquo;Occident-tardif que nous envisageons la contre-offensive. &bull; Avec un texte d&rsquo;Andrew Korybko.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>&#8230; En effet, dans cette \u00e9poque baroque-bouffe de l&rsquo;hyst\u00e9rie permanente du mensonge enrob\u00e9 de simulacre et qui ne signifie rien du tout du rien, on peut bien fabriquer des langages de passage et de fortune comme on fabrique du papier \u00e0 Wall Street ; &ndash; d&rsquo;o&ugrave; le verbe (?!?) &lsquo;contre-offensiver&rsquo; pour d\u00e9crire la somptueuse parade vieille de bien six-huit mois de la contre-offensive de l&rsquo;arm\u00e9e zalenskistanaise. S&oelig;ur Anne ne verrait rien venir mais \u00e0 nous on ne la fait pas.<\/p>\n<\/p>\n<p><p>Nous n&rsquo;allons pas tenter d&rsquo;offrir un r\u00e9sum\u00e9, &ndash; maintenant on dirait un \u00ab\u00a0historique\u00a0\u00bb &ndash; des annonces de la contre-offensive, que ce soit les dates pr\u00e9vues, ou les annonces qu&rsquo;elle (la contre-offensive) est d\u00e9j\u00e0 en cours, voire m\u00eame qu&rsquo;elle a d\u00e9j\u00e0 victorieusement eu lieu sans que personne n&rsquo;y prenne vraiment garde (d&rsquo;o&ugrave; les plaintes du Zelenskistan \u00e0 propos du d\u00e9sint\u00e9r\u00eat des m\u00e9dias, &ndash; c&rsquo;est bien connu, &ndash; pour sa cause). Alors, on observera simplement&#8230;<\/p>\n<\/p>\n<p><p>&bull; que jeudi en d\u00e9but de soir\u00e9e, l&rsquo;excellent <a href=\"https:\/\/theduran.com\/russia-resumes-advance-near-bakhmut-avdeyevka-ukr-belgorod-psyops-zaluzhny-mystery-russia-iran-finance-talks\/\">Alexander Mercouris<\/a> s&rsquo;est h\u00e9ro\u00efquement acharn\u00e9 \u00e0 tenter de comprendre comment l&rsquo;\u00e9trange \u00ab\u00a0invasion\u00a0\u00bb de Belgorod-en-Russie par une poign\u00e9e de soldats ukrainiens pouvait \u00eatre pr\u00e9sent\u00e9e (par Podolyak, conseiller de Z.) comme la \u00ab\u00a0contre-offensive\u00a0\u00bb, ou une partie de la contre-offensive d\u00e9j\u00e0 en-cours. Mercouris tente d&rsquo;avancer l&rsquo;id\u00e9e d&rsquo;une contre-offensive de communication, voire d&rsquo;un test d&rsquo;une telle sorte, &ndash; courageux Alexander&#8230;<\/p>\n<\/p>\n<p><p>&bull; Auparavant ou parall\u00e8lement, plut\u00f4t hier en fin d&rsquo;apr\u00e8s-midi, son complice <a href=\"https:\/\/theduran.com\/desantis-twitter-spaces-disaster-turkstream-sabotage-thwarted-poland-ready-for-belarus-coup-u-2\/\">Alex Christoforou<\/a> s&rsquo;est franchement moqu\u00e9 de la pirouette Podolyak-Belgorod, suivant une autre d\u00e9claration de Podolyak annon\u00e7ant que Z. attendait des F-16 pour sa contre-offensive. Christoforou a class\u00e9 le tout comme r\u00e9cipiendaire du troph\u00e9e &lsquo;<em>clown-world<\/em>&lsquo; du jour, &ndash; &lsquo;<em>clown of the day<\/em>&lsquo;, disons.<\/p>\n<\/p>\n<p><p>&bull; L\u00e0-dessus, s\u00e9rieux, &ndash; car voici que Victoria Nuland s&rsquo;avance et que le &lsquo;<em>clown-world<\/em>&lsquo; retient son souffle. La s\u00e9millante h\u00e9ro\u00efne du Maidan, qui p\u00e8te de sant\u00e9, nous a fait la r\u00e9v\u00e9lation majeure, &ndash; car voici qu&rsquo;elle, elle sait bien entendu. On vous laisse savourer et apprendre que nous pourrons savourer nos barbecue contre-offensifs en plein mois de juillet. Ainsi devinons-nous que la r\u00e9union de l&rsquo;OTAN du 11 juillet aura bien comme ordre du jour classifi\u00e9 \u00ab\u00a0top-secret&rsquo; : \u00ab\u00a0barbecue contre-offensifs\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>Voici une bonne partie du compte-rendu que nous donne le r\u00e9seau interdit et maudit, <a href=\"https:\/\/www.rt.com\/news\/576926-us-ukraine-counteroffensive-nuland\/\">RT.com<\/a>, &ndash; et il faut lire attentivement car il semble qu&rsquo;elle, la Nuland, nous signifie que \u00ab\u00a0peu importe le temps qu&rsquo;il faudra pour \u00ab\u00a0dissuader la Russie\u00a0\u00bb (c&rsquo;est-\u00e0-dire l&rsquo;an\u00e9antir, non ?), &ndash; que \u00ab\u00a0cela prenne un an, six ans, 16 ans\u00a0\u00bb (pourquoi 6 et pas 5 ? Pourquoi 16 et pas 15 ? Adressez-vous \u00e0 la CIA ou \u00e0 Biden), &ndash; eh bien, euh, eh bien, \u00ab\u00a0euh, cela se fera\u00a0\u00bb, ah ah&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La sous-secr\u00e9taire d&rsquo;&Eacute;tat am\u00e9ricaine aux affaires politiques, Victoria Nuland, a d\u00e9clar\u00e9 jeudi \u00e0 Kiev que Washington aidait \u00e0 planifier la \u00ab\u00a0contre-offensive\u00a0\u00bb ukrainienne contre la Russie depuis pr\u00e8s de six mois.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Alors m\u00eame que vous pr\u00e9parez la contre-offensive, sur laquelle nous travaillons avec vous depuis 4 \u00e0 5 mois, nous commen\u00e7ons d\u00e9j\u00e0 \u00e0 discuter avec le gouvernement ukrainien et avec nos amis \u00e0 Kiev, &ndash; tant du c\u00f4t\u00e9 civil que du c\u00f4t\u00e9 militaire, &ndash; de l&rsquo;avenir \u00e0 long terme de l&rsquo;Ukraine\u00a0\u00bb, a d\u00e9clar\u00e9 Mme Nuland lors du Forum sur la s\u00e9curit\u00e9 de Kiev, par liaison vid\u00e9o depuis le d\u00e9partement d&rsquo;&Eacute;tat.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Elle a ajout\u00e9 que l&rsquo;attaque \u00ab\u00a0commencera et se d\u00e9roulera probablement en m\u00eame temps\u00a0\u00bb que des \u00e9v\u00e9nements tels que le sommet de l&rsquo;OTAN en Lituanie, pr\u00e9vu pour le 11 juillet.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Selon Nuland, les &Eacute;tats-Unis planifient \u00e9galement l&rsquo;avenir militaire de l&rsquo;Ukraine pour dissuader la Russie, de sorte que \u00ab\u00a0peu importe o&ugrave; et comment cela se termine, &ndash; un an, six ans, 16 ans &ndash; nous ne recommencerons pas\u00a0\u00bb. Elle a \u00e9galement bross\u00e9 un tableau idyllique d&rsquo;un avenir dans lequel l&rsquo;Ukraine serait le \u00ab\u00a0moteur de la revitalisation de l&rsquo;Europe\u00a0\u00bb et \u00ab\u00a0l&rsquo;exemple d\u00e9mocratique&#8230; pour le monde entier\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le forum \u00e9tait organis\u00e9 par l&rsquo;Open Ukraine Foundation, cr\u00e9\u00e9e par l&rsquo;ancien premier ministre ukrainien Arseny Yatseniouk, qui a anim\u00e9 la table ronde au cours de laquelle Nuland s&rsquo;est exprim\u00e9e. Une autre table ronde \u00e9tait coparrain\u00e9e par le Conseil atlantique, dont les repr\u00e9sentants ont affirm\u00e9 que \u00ab\u00a0l&rsquo;unit\u00e9 transatlantique et un soutien solide peuvent aider l&rsquo;Ukraine \u00e0 vaincre la Russie et \u00e0 renouveler la s\u00e9curit\u00e9 europ\u00e9enne\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Donc, impression d&rsquo;entendre des clowns fous, extr\u00eamement s\u00e9rieux, qui crient leur m\u00e9pris pour les clowns pas s\u00e9rieux, en dansant la tarentelle, &ndash; cette folle musique populaire du XV\u00e8me-XVI\u00e8me peut-\u00eatre, faite pour exorciser la folie inocul\u00e9e chez les braves clowns s\u00e9rieux par des piqures de tarentules compl\u00e8tement ins\u00e9rieuses&#8230;<\/p>\n<\/p>\n<p><p>Dans l&rsquo;attente d&rsquo;une contre-offensive qui a peut-\u00eatre d\u00e9j\u00e0 eu lieu, lisez un texte (le <a href=\"https:\/\/korybko.substack.com\/p\/bidens-re-election-hinges-on-the\">25 mai 2023<\/a>) de Andrew Korybko sur le sujet. Bien plus s\u00e9rieux sans \u00eatre ennuyeux, parfois sarcastique entre les lignes, ce texte permet de contre-offensiver en attendant l&rsquo;in\u00e9vitable, &ndash; la r\u00e9\u00e9lection de Biden, &ndash; il l&rsquo;a bien m\u00e9rit\u00e9e, Biden&#8230;<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La contre-offensive et la r\u00e9\u00e9lection de Biden<\/h2>\n<\/p>\n<p><p>Le principal conseiller pr\u00e9sidentiel ukrainien, Mikhail Podolyak, a d\u00e9clar\u00e9 <a href=\"https:\/\/substack.com\/redirect\/97cd2c09-0a6d-4b87-81fd-21bc2e18b57d?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">\u00e0 un m\u00e9dia italien<\/a> que la contre-offensive <a href=\"https:\/\/substack.com\/redirect\/c8036d58-08f2-4fb8-b217-b9241e24b299?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">tant annonc\u00e9e<\/a> de son pays avait d\u00e9j\u00e0 commenc\u00e9 il y a quelques jours, ce qui est curieux puisque ce d\u00e9lai co\u00efncide avec l&rsquo;invasion par procuration de la r\u00e9gion russe de Belgorod, qui n&rsquo;\u00e9tait qu&rsquo;un <a href=\"https:\/\/substack.com\/redirect\/1733b3ee-3e2b-420d-8507-83ab30c81c08?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">simulacre<\/a> destin\u00e9 \u00e0 d\u00e9tourner l&rsquo;attention de la <a href=\"https:\/\/substack.com\/redirect\/f38e2732-6792-4b09-bd93-827bebae9f4f?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">perte d&rsquo;Artyomovsk<\/a>. Ce coup d&rsquo;\u00e9clat m\u00e9diatique n&rsquo;a toutefois pas permis d&rsquo;obtenir des r\u00e9sultats tangibles, ce qui soul\u00e8ve plus que jamais la question de savoir si la contre-offensive sera couronn\u00e9e de succ\u00e8s.<\/p>\n<\/p>\n<p><p>En mars, le <a href=\"https:\/\/substack.com\/redirect\/dc620bd0-04f2-488a-8b3d-b2ba9c88ffc7?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">Washington Post<\/a> a attir\u00e9 l&rsquo;attention sur la pi\u00e8tre performance des troupes de Kiev dans la guerre par procuration entre l&rsquo;OTAN et la Russie. Un mois plus tard, <a href=\"https:\/\/substack.com\/redirect\/06449ea7-66a5-4bc4-9855-c927e4f16145?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">Politico<\/a> a cit\u00e9 des responsables anonymes de l&rsquo;administration Biden qui s&rsquo;inqui\u00e9taient des cons\u00e9quences d&rsquo;une contre-offensive qui ne r\u00e9pondrait pas aux attentes de l&rsquo;opinion publique. L&rsquo;ancien champion d&rsquo;\u00e9checs russe Garry Kasparov a ensuite concoct\u00e9 <a href=\"https:\/\/www.dedefensa.org\/article\/ukrisis-et-la-necessite-du-complotisme\">une th\u00e9orie du complot<\/a> selon laquelle des agents du Kremlin auraient infiltr\u00e9 la Maison Blanche et sabot\u00e9 la contre-offensive avant m\u00eame qu&rsquo;elle ne commence.<\/p>\n<\/p>\n<p><p>Cette figure populaire pro-Kiev semble avoir \u00e9t\u00e9 effray\u00e9e par le pr\u00e9sident de la commission des affaires \u00e9trang\u00e8res de la Chambre des repr\u00e9sentants, Michael McCaul, qui a <a href=\"https:\/\/substack.com\/redirect\/de2d06d3-9d19-49cb-a2a3-fb94287aa326?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">d\u00e9clar\u00e9 \u00e0 Bloomberg<\/a> : &laquo; Je pense que cette contre-offensive va peser lourd dans la balance. Si l&rsquo;Ukraine r\u00e9ussit aux yeux du peuple am\u00e9ricain et du monde, je pense que cela changera la donne pour la poursuite du soutien. Si elle \u00e9choue, cela aura \u00e9galement un impact, mais n\u00e9gatif dans ce cas &raquo;. En d&rsquo;autres termes, son \u00e9chec pourrait conduire les &Eacute;tats-Unis \u00e0 r\u00e9duire consid\u00e9rablement leur aide \u00e0 Kiev.<\/p>\n<\/p>\n<p><p>C&rsquo;est l\u00e0 que se trouve la v\u00e9ritable raison pour laquelle la contre-offensive se poursuit malgr\u00e9 la probabilit\u00e9 \u00e9crasante d&rsquo;insucc\u00e8s qui a \u00e9t\u00e9 d\u00e9taill\u00e9e au cours des mois pr\u00e9c\u00e9dents par le Washington Post et Politico. La r\u00e9\u00e9lection de Joe Biden d\u00e9pend du succ\u00e8s de cette campagne, alors que l&rsquo;OTAN a d\u00e9j\u00e0 envoy\u00e9 \u00e0 Kiev plus de 165 milliards de dollars d&rsquo;aide fournie par les contribuables, dont la grande majorit\u00e9 provient des &Eacute;tats-Unis. Biden a besoin de tout ce que ses responsables de la communication peuvent faire passer pour une victoire afin de justifier cette d\u00e9cision avant les \u00e9lections de l&rsquo;ann\u00e9e prochaine.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas seulement d&rsquo;apaiser les contribuables dans ce conflit de plus en plus partisan, qui voit un nombre croissant de r\u00e9publicains appeler \u00e0 plus de pragmatisme et de retenue, contrairement \u00e0 leurs rivaux d\u00e9mocrates qui restent d\u00e9termin\u00e9s \u00e0 aller jusqu&rsquo;au bout, aussi longtemps qu&rsquo;il le faudra. Biden a pr\u00e9sid\u00e9 \u00e0 l&rsquo;\u00e9chec militaire la plus humiliant de l&rsquo;histoire des &Eacute;tats-Unis avec l&rsquo;\u00e9vacuation chaotique de l&rsquo;Afghanistan en ao&ucirc;t 2021, qui s&rsquo;est sold\u00e9e par l&rsquo;abandon d&rsquo;un grand nombre d&rsquo;Am\u00e9ricains et d&rsquo;habitants alli\u00e9s \u00e0 un sort inconnu.<\/p>\n<\/p>\n<p><p>Lui et son \u00e9quipe se moquent de savoir combien de dizaines de milliers d&rsquo;Ukrainiens devront \u00eatre sacrifi\u00e9s dans ce conflit, tant qu&rsquo;ils peuvent obtenir quelque chose que les d\u00e9mocrates pourront d\u00e9former en disant que le conflit le plus important sur le plan g\u00e9ostrat\u00e9gique depuis la Seconde Guerre mondiale valait la peine d&rsquo;\u00eatre provoqu\u00e9. La plupart des Am\u00e9ricains consid\u00e8rent qu&rsquo;un raid rat\u00e9 en Russie et <a href=\"https:\/\/substack.com\/redirect\/828e9f0a-f4b8-4aef-be32-f2d26a7ac4a4?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">une tentative d&rsquo;assassinat<\/a> infructueuse contre le pr\u00e9sident Poutine ne valent pas le risque d&rsquo;une troisi\u00e8me guerre mondiale par erreur de calcul.<\/p>\n<\/p>\n<p><p>Apr\u00e8s 15 mois de combats, Kiev n&rsquo;a r\u00e9ussi \u00e0 reconqu\u00e9rir qu&rsquo;une petite partie du territoire [pris par les Russes], ce qui n&rsquo;est pas tr\u00e8s impressionnant si l&rsquo;on consid\u00e8re qu&rsquo;elle b\u00e9n\u00e9ficie du soutien total de ce que les &Eacute;tats-Unis pr\u00e9sentent comme \u00e9tant l&rsquo;alliance militaire la plus puissante de l&rsquo;histoire. La \u00ab\u00a0course \u00e0 la logistique\u00a0\u00bb\/\u00a0\u00bbguerre d&rsquo;usure\u00a0\u00bb que le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN a d\u00e9clar\u00e9 en f\u00e9vrier mener contre la Russie a prouv\u00e9 par inadvertance que le complexe militaro-industriel russe peut rivaliser avec celui de l&rsquo;Occident tout entier.<\/p>\n<\/p>\n<p><p>Cela a port\u00e9 un coup involontaire \u00e0 la r\u00e9putation de superpuissance militaire de ce nouveau bloc de facto de la guerre froide et a \u00e9galement discr\u00e9dit\u00e9 leur discours de guerre de l&rsquo;information selon lequel l&rsquo;\u00e9conomie russe est en train de s&rsquo;effondrer. Fin janvier, le New York Times a admis que les sanctions occidentales <a href=\"https:\/\/substack.com\/redirect\/ca92d741-bb01-4cad-9f97-49015d3d0e39?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">avaient \u00e9chou\u00e9<\/a>, puis, fin f\u00e9vrier, apr\u00e8s la d\u00e9claration spectaculaire du chef de l&rsquo;OTAN, qu&rsquo;elles n&rsquo;avaient pas <a href=\"https:\/\/substack.com\/redirect\/6f12fa2b-b359-4fc8-970a-6dc47e27d49d?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">non plus r\u00e9ussi<\/a> \u00e0 isoler la Russie.<\/p>\n<\/p>\n<p><p>Les faits susmentionn\u00e9s font d\u00e9j\u00e0 passer M. Biden <a href=\"https:\/\/substack.com\/redirect\/138f5233-8d22-4f34-8248-0d93822e4cf9?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">pour un imb\u00e9cile<\/a> ayant provoqu\u00e9 ce conflit, qui n&rsquo;a fait que prouver \u00e0 quel point l&rsquo;influence et le pouvoir des Etats-Unis <a href=\"https:\/\/substack.com\/redirect\/0cfe080a-6dd3-4284-8593-6dcda4c2ac87?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">se sont r\u00e9duits<\/a> ces derni\u00e8res ann\u00e9es, mais il appara&icirc;t encore plus malheureux si l&rsquo;on consid\u00e8re la situation dans son ensemble. Le chancelier allemand Olaf Scholz, l&rsquo;ancien membre du Conseil national de s\u00e9curit\u00e9 des &Eacute;tats-Unis Fiona Hill et le pr\u00e9sident des affaires mondiales de Goldman Sachs Jared Cohen ont tous reconnu au d\u00e9but du mois de mai que la multipolarit\u00e9 \u00e9tait d\u00e9sormais une r\u00e9alit\u00e9 g\u00e9opolitique \u00e0 la suite de ce conflit.<\/p>\n<\/p>\n<p><p>Seuls l&rsquo;administration Biden et les propagandistes alli\u00e9s \u00e0 l&rsquo;\u00e9tranger continuent de le nier, ce qui accro&icirc;t encore la pression sur leurs mandataires \u00e0 Kiev pour qu&rsquo;ils obtiennent quelque chose de tangible au cours de leur contre-offensive, qu&rsquo;ils pourront ensuite pr\u00e9senter comme ayant justifi\u00e9 la provocation de ce conflit. Le temps presse \u00e9galement, puisqu&rsquo;il existe un consensus de plus en plus large \u00e0 travers le monde sur le fait qu&rsquo;il s&rsquo;agit du \u00ab\u00a0dernier baroud d&rsquo;honneur\u00a0\u00bb de leur camp avant le d\u00e9but probable d&rsquo;un cessez-le-feu et de pourparlers de paix d&rsquo;ici la fin de l&rsquo;ann\u00e9e ou au plus tard au d\u00e9but de l&rsquo;ann\u00e9e 2024.<\/p>\n<\/p>\n<p><p>La crise militaro-industrielle de l&rsquo;Occident limitera in\u00e9vitablement le rythme, l&rsquo;ampleur et la port\u00e9e de l&rsquo;aide arm\u00e9e \u00e0 Kiev, sans parler de la saison \u00e9lectorale am\u00e9ricaine qui verra ce conflit faire l&rsquo;objet d&rsquo;une politisation sans pr\u00e9c\u00e9dent. Au lieu d&rsquo;admettre sobrement les lacunes de son camp et d&rsquo;essayer de mani\u00e8re proactive de parvenir \u00e0 une sorte d&rsquo;accord de paix qui pourrait ensuite \u00eatre exploit\u00e9 comme pr\u00e9texte pour lui permettre de remporter le prix Nobel de la paix et d&rsquo;am\u00e9liorer ainsi ses chances de r\u00e9\u00e9lection, Joe Biden parie contre les chances de succ\u00e8s de la contre-offensive.<\/p>\n<\/p>\n<p><p>M\u00eame le pr\u00e9sident de l&rsquo;\u00e9tat-major interarm\u00e9es, Mark Milley, a pr\u00e9vu fin janvier qu&rsquo;il serait probablement impossible pour Kiev de d\u00e9loger la Russie de tout le territoire qu&rsquo;elle revendique comme sien d&rsquo;ici cette ann\u00e9e, ce qui signifie que Biden et son \u00e9quipe tentent de prouver que le plus haut responsable militaire des &Eacute;tats-Unis a tort. Cela confirme qu&rsquo;ils donnent la priorit\u00e9 \u00e0 la politique plut\u00f4t qu&rsquo;aux conseils militaires, accr\u00e9ditant encore plus l&rsquo;id\u00e9e que cette contre-offensive a pour seul objectif la r\u00e9\u00e9lection de Biden et non le retour de la Russie \u00e0 ses fronti\u00e8res d&rsquo;avant 2014.<\/p>\n<\/p>\n<p><p>Si elle n&rsquo;atteint pas cet objectif maximal, comme le pr\u00e9voient Milley et les m\u00e9dias am\u00e9ricains cit\u00e9s plus haut, les r\u00e9publicains se jetteront \u00e0 juste titre sur Biden pour l&rsquo;accuser de pr\u00e9parer le pire conflit depuis la Seconde Guerre mondiale, dans une tentative d\u00e9sesp\u00e9r\u00e9e de se faire r\u00e9\u00e9lire en d\u00e9tournant l&rsquo;attention de sa perte humiliante en Afghanistan. Dos au mur, on ne peut exclure que son \u00e9quipe lui conseille une escalade jusqu&rsquo;\u00e0 des niveaux impensables, m\u00eame si les missiles hypersoniques russes l&#8217;emp\u00eacheront probablement de franchir l&rsquo;ultime ligne rouge.<\/p>\n<\/p>\n<p><p>Quelle que soit la solution retenue, il n&rsquo;y a pratiquement aucune chance que la contre-offensive de Kiev r\u00e9ponde aux attentes de l&rsquo;opinion publique occidentale, sauf en cas de &lsquo;<em><a href=\"https:\/\/www.ig.com\/fr\/strategies-de-trading\/Theorie-du-cygne-noir-200813\">black swann<\/a><\/em>&lsquo;, ce qui signifie que Joe Biden se pr\u00e9sentera aux \u00e9lections avec deux d\u00e9faites \u00e0 son actif, en Afghanistan et en Ukraine. Il est difficile d&rsquo;imaginer que les Am\u00e9ricains lui donneront, ainsi qu&rsquo;\u00e0 son \u00e9quipe, quatre ann\u00e9es suppl\u00e9mentaires de mandat apr\u00e8s avoir humili\u00e9 les &Eacute;tats-Unis \u00e0 ce point, mais des dizaines de milliers de personnes pourraient encore mourir avant que ces bellicistes ne soient \u00e9cart\u00e9s du pouvoir.<\/p>\n<\/p>\n<p><h4>Andrew Korybko<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contre-offensiver la contre-offensive &bull; C&rsquo;est dans l&rsquo;esprit du plus grand s\u00e9rieux de l&rsquo;\u00a0\u00bbart op\u00e9ratif\u00a0\u00bb des directions gouvernementales et strat\u00e9giques de l&rsquo;Occident-tardif que nous envisageons la contre-offensive. &bull; Avec un texte d&rsquo;Andrew Korybko. _________________________ &#8230; En effet, dans cette \u00e9poque baroque-bouffe de l&rsquo;hyst\u00e9rie permanente du mensonge enrob\u00e9 de simulacre et qui ne signifie rien du tout&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[12498,1235,2952,4172,13670],"class_list":["post-80623","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-andrew","tag-biden","tag-korybko","tag-reelection","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80623"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80623\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}