{"id":80649,"date":"2023-06-18T20:39:36","date_gmt":"2023-06-18T20:39:36","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/06\/18\/brusquement-reveille-le-geant-dort-toujours\/"},"modified":"2023-06-18T20:39:36","modified_gmt":"2023-06-18T20:39:36","slug":"brusquement-reveille-le-geant-dort-toujours","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/06\/18\/brusquement-reveille-le-geant-dort-toujours\/","title":{"rendered":"Brusquement r\u00e9veill\u00e9, le g\u00e9ant dort toujours"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Brusquement r\u00e9veill\u00e9, le g\u00e9ant dort toujours<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Le Pentagone ne cesse de s&rsquo;agiter et de faire donner ses correspondants fid\u00e8les dans la presseSyst\u00e8me : pour lui, <strong>le vrai danger c&rsquo;est la Chine et toute l&rsquo;attention port\u00e9e \u00e0 l&rsquo;Ukraine est mauvaise conseill\u00e8re<\/strong>. &bull; Mais il existe au d\u00e9partement d&rsquo;&Eacute;tat et sous l&rsquo;oreiller de Biden <strong>un clan fid\u00e8le \u00e0 Mister Z. de tr\u00e8s forte influence<\/strong>. &bull; Que faire, alors que le Pentagone ne serait m\u00eame pas s&ucirc;r du tout de battre la Chine si la chose se pr\u00e9sentait ? &bull; La r\u00e9ponse est simple : <strong>puisqu&rsquo;on ne peut ni affronter ni battre la Chine, attaquons la Chine et la Russie<\/strong>.<\/p>\n<\/p>\n<p><p>__________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Nous pourrions commencer cet article par la phrase de d\u00e9but de l&rsquo;article que l&rsquo;historien Eric Zuesse publie <a href=\"https:\/\/theduran.com\/u-s-empire-will-either-lose-ukraine-to-russia-or-fail-to-win-taiwan-from-china-or-both\/\">le 18 juin 2023<\/a> sur le site &lsquo;<em>TheDuran.com<\/em>&lsquo;, de nos comp\u00e8res Christoforou-Mercouris. L&rsquo;article de Zuesse (comme le n\u00f4tre, certes) concerne la vid\u00e9o de Christoforou-Mercouris <a href=\"https:\/\/theduran.com\/china-war-party-vs-russia-war-party\/\">du 17 juin<\/a>, &laquo; <em>China&rsquo;s War Party vs Russia&rsquo;s War Party<\/em> &raquo;, qui nous avait beaucoup int\u00e9ress\u00e9s et d\u00e9termin\u00e9s nous-m\u00eames \u00e0 \u00e9crire un article, &ndash; celui que vous lisez en ce moment.<\/p>\n<\/p>\n<p><p>Zuesse est tr\u00e8s \u00e9logieux pour Mercouris, et ce n&rsquo;est certainement pas flagornerie d&rsquo;auteur pour l&rsquo;h\u00f4te qui publie son article. On conna&icirc;t Zuesse, comme on conna&icirc;t Mercouris, et c&rsquo;est cela qui doit conduire notre jugement. Il se trouve qu&rsquo;ainsi Zuesse nous donne un condens\u00e9 de l&rsquo;intervention de Mercouris, ce qui nous permet d&rsquo;intervenir \u00e0 partir de deux sources de tr\u00e8s bonne facture.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Note de PhG-Bis<\/em><\/strong><em> : &laquo; Ce que PhG ne dit pas, mais il le pense et va jusqu&rsquo;\u00e0 le chuchoter, l&rsquo;acc\u00e8s \u00e0 deux sources de bonne qualit\u00e9 permet certes de prendre une bonne distance d&rsquo;appr\u00e9ciation, mais surtout, surtout, de v\u00e9rifier que l&rsquo;on ne se trouve pas nous-m\u00eames dans un univers fictif, dit de-&lsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fantasy\">fantasy<\/a>&lsquo;&#8230; &raquo;<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Zuesse intervient donc \u00e0 partir d&rsquo;une analyse assez courte, mais tr\u00e8s g\u00e9n\u00e9rale et pratiqu\u00e9e en profondeur, de la politique \u00e9trang\u00e8re, c&rsquo;est-\u00e0-dire militaire, des Etats-Unis. C&rsquo;est une chose essentielle de bien comprendre cette politique, et de revenir r\u00e9guli\u00e8rement sur cette compr\u00e9hension pour la mettre \u00e0 jour, parce que nos continuons \u00e0 d\u00e9pendre tous de cette politique, d&rsquo;autant plus si elle est conduite par des fols qui n&rsquo;entendent rien des fureurs et des exclamations du monde, &ndash; comme c&rsquo;est le cas, dans une mesure inimaginable et rocambolesque :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;  <em>Comme d&rsquo;habitude, la meilleure analyse de la politique \u00e9trang\u00e8re des &Eacute;tats-Unis est celle d&rsquo;Alexander Mercouris sur The Duran. Le 17 juin, il titre son article \u00ab\u00a0China war party vs. Russia war party\u00a0\u00bb et d\u00e9montre (puisque chaque source \u00e0 laquelle il se r\u00e9f\u00e8re dit ce qu&rsquo;il d\u00e9crit) que le pr\u00e9sident am\u00e9ricain Biden et son \u00e9quipe \u00e0 la Maison Blanche sont des fantaisistes qui refusent tout simplement d&rsquo;accepter la r\u00e9alit\u00e9, \u00e0 savoir que l&rsquo;Am\u00e9rique ne peut pas gagner simultan\u00e9ment des guerres contre la Russie et contre la Chine. Le d\u00e9partement d&rsquo;&Eacute;tat neocon de Biden exige la conqu\u00eate de la Russie, tandis que le d\u00e9partement neocon de la \u00ab\u00a0d\u00e9fense\u00a0\u00bb de Biden exige la conqu\u00eate de la Chine<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Zuesse utilise le terme \u00ab\u00a0<em>fantasists<\/em>\u00a0\u00bb \u00e0 propos de l&rsquo;\u00e9quipe Biden, \u00e0 propos du mot US (d&rsquo;origine fran\u00e7aise, bien s&ucirc;r) \u00ab\u00a0<em>fantasy<\/em>\u00a0\u00bb dans sa signification bien particuli\u00e8re, &ndash; \u00e0 la fois bande dessin\u00e9e et cin\u00e9ma hollywoodien, &ndash; dont la signification est celle-ci, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fantasy\">du &lsquo;Wiki&rsquo;<\/a> pour ce cas qui n&rsquo;est pas syst\u00e9matiquement d\u00e9form\u00e9 par leur censure :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230;<em>Un genre artistique et litt\u00e9raire qui repr\u00e9sente des ph\u00e9nom\u00e8nes surnaturels imaginaires, souvent associ\u00e9s au mythe et souvent figur\u00e9s par l&rsquo;intervention ou l&#8217;emploi de la magie et de l&rsquo;anachronisme<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela signifie effectivement que Biden et sa bande vivent r\u00e9ellement dans ce monde imaginaire, &ndash; bande dessin\u00e9e et cinoche, &ndash; d\u00e9j\u00e0 souvent caract\u00e9ris\u00e9e par nous par la <a href=\"https:\/\/www.dedefensa.org\/article\/valsez-mensonges\">fameuse citation de 2002<\/a> de Karl Rove (&laquo; &#8230; <em>quand nous agissons nous cr\u00e9ons notre propre r\u00e9alit\u00e9&#8230;  Nous sommes<\/em> [les cr\u00e9ateurs] <em>de l&rsquo;histoire<\/em>&#8230; &raquo;, etc.). Tous ont la psychologie qui importe pour cela, \u00e0 commencer par l&#8217;empereur lui-m\u00eame, avec ses 80 ans et son apostrophe pour saluer l&rsquo;audience de son discours d&rsquo;hier : &laquo; <em><a href=\"https:\/\/www.rt.com\/news\/578201-us-biden-god-save-queen\/\">God save the Queen, man<\/a><\/em> &raquo;.<\/p>\n<\/p>\n<p><p>S\u00e9rieux, tout cela&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Un Pearl-Harbor postmoderne<\/h3>\n<\/p>\n<p><p>L&rsquo;article du site &lsquo;<em>Politico<\/em>&lsquo;, site washingtonien tr\u00e8s proche du pouvoir et souvent pris comme canal d&rsquo;informations officieuses, porte comme titre cette affirmation sans ambigu\u00eft\u00e9s, qui nous sugg\u00e8re que le Pentagone a voulu nous faire savoir la gravit\u00e9 de la situation de son point de vue :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>The Pentagon Is Freaking Out About a Potential War With China (Because America might lose)<\/em> &raquo; &ndash; &laquo; <em>Le Pentagone panique \u00e0 propos d&rsquo;une guerre potentielle avec la Chine (parce que l&rsquo;Am\u00e9rique pourrait perdre)<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Zuesse explique la signification fondamentale du texte, du point de vue du Pentagone. M\u00eame si \u00e0 aucun moment il n&rsquo;est sugg\u00e9r\u00e9 que l&rsquo;Am\u00e9rique devrait se \u00ab\u00a0d\u00e9sengager\u00a0\u00bb quasi-compl\u00e8tement de la guerre en Ukraine, l&rsquo;analyse qui est faite de la situation face \u00e0 la Chine le sugg\u00e8re avec la plus grande force, par simple effet de cons\u00e9quence, &ndash; par \u00ab\u00a0la force des choses\u00a0\u00bb, comme disait le G\u00e9n\u00e9ral :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230; [I]<em>l n&rsquo;y a pratiquement aucune chance que l&rsquo;Am\u00e9rique soit capable de gagner une guerre contre la Chine SAUF si l&rsquo;Am\u00e9rique prend imm\u00e9diatement un engagement de mort contre la Chine, comme elle l&rsquo;a fait contre le Japon et l&rsquo;Allemagne en r\u00e9ponse \u00e0 l&rsquo;attaque de Pearl Harbor par le Japon, le 7 d\u00e9cembre 1941<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est dire si l&rsquo;on trouve de l&rsquo;argumentation par pellet\u00e9es de tonnes en faveur d&rsquo;un \u00ab\u00a0r\u00e9armement\u00a0\u00bb US dans le Pacifique, brass\u00e9s par tous les experts imaginables, du Pentagone lui-m\u00eame, dans l&rsquo;orbite du Pentagone, dans son champ d&rsquo;attraction, etc. Du coup, toute la communication autour d&rsquo;un nouveau Pearl-Harbor est r\u00e9activ\u00e9e, avec l&rsquo;id\u00e9e-ma&icirc;tresse que si la Chine attaque et conquiert Ta\u00efwan, ce sera comme un second Pearl-Harbor, &ndash; puisque, apr\u00e8s tout, Ta\u00efwan \u00e9tant la proie de la Chine, Ta\u00efwan c&rsquo;est un peu l&rsquo;Am\u00e9rique, &ndash; un peu, beaucoup, passionn\u00e9ment&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em>&laquo; <\/em><em>La Chine repr\u00e9sente la m\u00eame menace pour l&rsquo;existence de l&rsquo;Am\u00e9rique que le Japon le 7 d\u00e9cembre 1941; et l&rsquo;article dit des choses comme que l&rsquo;Am\u00e9rique a gaspill\u00e9 \u00ab\u00a0des d\u00e9cennies de ce que beaucoup consid\u00e8rent comme une r\u00e9flexion illusoire des deux partis politiques sur la transformation de la Chine en une &lsquo;partie prenante&rsquo; amicale dans un syst\u00e8me international pacifique\u00a0\u00bb, &ndash; et une hypoth\u00e8se sous-jacente est que l&rsquo;Am\u00e9rique poss\u00e8de d\u00e9j\u00e0 Ta\u00efwan, et donc que si cette province de Chine fait officiellement s\u00e9cession de la Chine, et que la Chine envahit Ta\u00efwan, ce sera comme le Japon l&rsquo;a fait lorsqu&rsquo;il a envahi Pearl Harbor ; et, donc, l&rsquo;Am\u00e9rique doit \u00ab\u00a0armer Ta\u00efwan\u00a0\u00bb maintenant, afin de devenir capable de gagner la guerre de l&rsquo;Am\u00e9rique pour prendre Ta\u00efwan \u00e0 la Chine<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce d\u00e9veloppement d\u00e9crit assez bien la fi\u00e8vre qui s&rsquo;est empar\u00e9e du Pentagone durant les dix derni\u00e8res ann\u00e9es, depuis que la Chine s&rsquo;est impos\u00e9e comme une redoutable concurrente des USA, avec une flotte qui d\u00e9pass\u00e9 en nombre (bient\u00f4t plus de 400 unit\u00e9s) l&rsquo;US Navy. Par cons\u00e9quent, si on le fait au moins parce qu&rsquo;il n&rsquo;est pas politiquement correct de seulement le laisser voir, on y montre, &ndash; dans cet article et sans doute au Pentagone, &ndash; fort peu de consid\u00e9ration pour l&rsquo;Ukraine de Mister Z.<\/p>\n<\/p>\n<p><p>&#8230; Mais l&rsquo;Ukraine de Mister Z., c&rsquo;est le d\u00e9partement d&rsquo;&Eacute;tat avec ses vedettes hurleuses \u00e0 la mort (Blinken, Nuland), &ndash; et c&rsquo;est aussi Biden lui-m\u00eame, dont toute la famille a des liens sentimentaux si nombreux et sonnants et tr\u00e9buchants avec Kiev et ses alentours, &ndash;  &laquo; <em><a href=\"https:\/\/www.rt.com\/news\/578201-us-biden-god-save-queen\/\">God save the Queen, man<\/a><\/em> &raquo; ! Christoforou-Mercouris font valoir fort justement qu&rsquo;il y a plus d&rsquo;attachement passionn\u00e9 \u00e0 \u00ab\u00a0leur\u00a0\u00bb guerre du c\u00f4t\u00e9 des <em>neocon <\/em>antirusses que du c\u00f4t\u00e9 du syndrome chinois de l&rsquo;immense b\u00e2timent pentagonal sur le Potomac. On en arrive donc \u00e0 conclure que la seule issue \u00e0 cet affrontement, c&rsquo;est bien entendu de faire les deux d&rsquo;un coup : qui ne peut pas le moins-que-rien peut le super-plus. Ainsi, commente Zuesse, il faudra bien se faire \u00e0 la conclusion \u00e9vidente : nous aurons donc les deux guerres dans le monde de \u00ab\u00a0<em>fantasy<\/em>\u00a0\u00bb exceptionnaliste de D.C. :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le fait que Joe Biden n&rsquo;ait pas renvoy\u00e9 toute son \u00e9quipe de politique \u00e9trang\u00e8re, y compris les personnes qu&rsquo;il a nomm\u00e9es au d\u00e9partement d&rsquo;&Eacute;tat et au d\u00e9partement de la \u00ab\u00a0d\u00e9fense\u00a0\u00bb, et plus de 90 % des deux chambres du Congr\u00e8s am\u00e9ricain, prouve \u00e0 quel point il est stupide de n&rsquo;exiger rien de moins que le r\u00eave n\u00e9oconservateur d&rsquo;une conqu\u00eate simultan\u00e9e de la Russie et de la Chine par l&rsquo;Am\u00e9rique. Aucun de ces deux objectifs n&rsquo;est r\u00e9alistement possible, mais lui (et eux) continuent d&rsquo;exiger les DEUX. C&rsquo;est la raison pour laquelle le r\u00e9cent projet de loi sur la limitation de la dette a augment\u00e9 le financement de l&rsquo;arm\u00e9e, mais rien d&rsquo;autre, et a r\u00e9duit les d\u00e9penses pour les pauvres. Ils consid\u00e8rent que les pauvres ne sont pas indispensables, mais que la poursuite de la domination mondiale de l&rsquo;Am\u00e9rique ne l&rsquo;est pas, &ndash; elle est \u00ab\u00a0existentielle\u00a0\u00bb, pour tous les neocon, y compris Biden et la quasi-totalit\u00e9 des membres du Congr\u00e8s<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le cyclope qui clignait de l&rsquo;&oelig;il<\/h3>\n<\/p>\n<p><p>Autrement dit, il est temps de convenir qu&rsquo;il est temps de s&rsquo;y mettre : relancer la machine, mobiliser la machine, refaire l&rsquo;Am\u00e9rique de 1940-1945, partie d&rsquo;une arm\u00e9e de rien du tout pour aboutir \u00e0 un effectif de 15 millions d&rsquo;hommes, 17 500 avions de combat en Europe occidentale et une marine de 99 porte-avions ! (Chiffres de 1945.) Mais rien ne se passe&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;article de &lsquo;Politico&rsquo;, r\u00e9dig\u00e9 par Michael Hirsh, l&rsquo;indique clairement, puisqu&rsquo;il se termine par ces mots :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Apr\u00e8s Pearl Harbor, l&rsquo;amiral japonais Isoroku Yamamoto a lanc\u00e9 son<\/em> <em>c\u00e9l\u00e8bre avertissement (la citation est apocryphe) disant que tout ce que le Japon avait accompli avec cette attaque-surprise \u00e9tait de \u00ab\u00a0r\u00e9veiller un g\u00e9ant endormi et de le remplir d&rsquo;une terrible d\u00e9termination\u00a0\u00bb. C&rsquo;est \u00e0 peu pr\u00e8s ce qui s&rsquo;est pass\u00e9, et les &Eacute;tats-Unis ont compl\u00e8tement d\u00e9truit la machine militaire japonaise.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Mais aujourd&rsquo;hui, selon <\/em>[Seth] <em>Jones<\/em> [un responsable du Pentagone sous la pr\u00e9sidence d&rsquo;Obama]<em>, le g\u00e9ant \u00ab\u00a0reste couch\u00e9 dans son lit. Ses yeux sont ouverts et il reconna&icirc;t qu&rsquo;il y a un probl\u00e8me. Mais il doit sortir du lit\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>El\u00e9mentaire mon cher Watson, puisque la d\u00e9monstration par l&rsquo;hypersonique a largement pr\u00e9c\u00e9d\u00e9 l&rsquo;\u00e9nonc\u00e9 m\u00eame du probl\u00e8me de l&rsquo;appel \u00e0 la mobilisation du g\u00e9ant endormi. Si l&rsquo;on avait esp\u00e9r\u00e9 que le g\u00e9ant ne dormait que d&rsquo;un &oelig;il et qu&rsquo;il serait ainsi tr\u00e8s vite \u00e9veill\u00e9, n&rsquo;est-ce pas parce qu&rsquo;on avait oubli\u00e9 qu&rsquo;il a pris, sur la pente de sa d\u00e9g\u00e9n\u00e9rescence, le nom de \u00ab\u00a0Cyclope\u00a0\u00bb ?<\/p>\n<\/p>\n<p><p>L&rsquo;Am\u00e9rique du XXI\u00e8me si\u00e8cle a d\u00e9j\u00e0 montr\u00e9 ce qu&rsquo;elle est capable de faire en mati\u00e8re de mobilisation, l&rsquo;inertie extraordinaire qu&rsquo;elle est capable de produire comme si \u00ab\u00a0inertie\u00a0\u00bb \u00e9tait le concept nouveau producteur d&rsquo;\u00e9nergie cr\u00e9atrice et industrieuse d\u00e9voreuses d&rsquo;elles-m\u00eames. Nous avons suivi cette affaire du d\u00e9veloppement des syst\u00e8mes hypersoniques, depuis le <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-la-communication-hypersonique\">printemps 2018<\/a> (r\u00e9v\u00e9lation par Poutine de l&rsquo;avance russe) avec les <a href=\"https:\/\/www.dedefensa.org\/article\/aujourdhui-ce-sont-eux-qui-essaient-de-nous-rattraper\">diff\u00e9rents constats<\/a>, \u00e0 <a href=\"https:\/\/www.dedefensa.org\/article\/simulacre-hypersonique\">mesure<\/a> du <a href=\"https:\/\/www.dedefensa.org\/article\/hypersonique-catastrophe\">temps passant<\/a> ; 5-10 d&rsquo;avance des Russes, cinq ann\u00e9es depuis cette r\u00e9v\u00e9lation, aucune urgence dans les actes sinon des \u00e9checs de programmes tandis que les hypersoniques (russes) sont entr\u00e9s dans la danse en Ukraine&#8230; Le g\u00e9ant a entr&rsquo;ouvert un &oelig;il, &ndash; m\u00eame pas les deux, selon notre observation attentive du cyclope, &ndash; et rien d&rsquo;autre \u00e0 l&rsquo;horizon, sinon des budget qui s&rsquo;accumulent \u00e0 la vitesse de l&rsquo;endettement sans rien donner, une chute qui se poursuit, du mat\u00e9riel qui vieillit, des forces qui se wokenisent de toutes les couleurs et \u00e0 tr\u00e8s grande vitesse, les LGTBQ qui <a href=\"https:\/\/www.zerohedge.com\/political\/space-force-chief-says-state-anti-lgbt-laws-threaten-us-military-readiness\">sont acclam\u00e9s<\/a> comme une priorit\u00e9, des programmes mirifiques qui donneront des choses magnifiques dans 30 ans ou 40 ans.<\/p>\n<\/p>\n<p><p>&#8230;  D&rsquo;ailleurs, est-ce bien la faute du g\u00e9ant, &ndash; si par \u00ab\u00a0g\u00e9ant\u00a0\u00bb, on entend le Pentagone, si m\u00eame on entend \u00ab\u00a0l&rsquo;Am\u00e9rique\u00a0\u00bb ? Le g\u00e9ant est-il encore ma&icirc;tre de lui-m\u00eame, paralys\u00e9 par ses lilliputiens sans nombre comme autant de termites calamiteuses de gaspillages, sa corruption sans limites, ses in\u00e9galit\u00e9s et ses incons\u00e9quences, ses d\u00e9g\u00e9n\u00e9rescences immondes, ses illusions comme de la drogue, une drogue qu&rsquo;il infuse \u00e0 son tour vers ses serviteurs, ses fournisseurs, ses inspirateurs, dans une ronde sans fin tournant autour de l&rsquo;immense simulacre qu&rsquo;il est devenu ?<\/p>\n<\/p>\n<p><p>Et monsieur Christian Brose, directeur de la strat\u00e9gie chez Anduril Industries, un des experts que &lsquo;<em>Politico<\/em>&lsquo; a largement consult\u00e9s, de nous sugg\u00e9rer en guise de conclusion cette hypoth\u00e8se de prospective finalement sans grand risque au point o&ugrave; l&rsquo;on en est :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nous pourrions injecter mille milliards de dollars par an dans le budget de la d\u00e9fense aujourd&rsquo;hui, nous n&rsquo;obtiendrions pas d&rsquo;augmentation significative des capacit\u00e9s militaires traditionnelles au cours des cinq <\/em>[dix ? quinze ?] <em>prochaines ann\u00e9es<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous signons des deux mains cette estimation. Pour le budget de la d\u00e9fense, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Principe_de_Peter\">Principe de Peter<\/a> a frapp\u00e9 depuis pas mal de temps et le mal ne fait que s&rsquo;aggraver au rythme de la pente d&rsquo;apr\u00e8s : plus on met de l&rsquo;argent, plus l&rsquo;on gaspille et plus l&rsquo;on corrompt.<\/p>\n<\/p>\n<p><p>Mis en ligne le 18 juin 2023 \u00e0 20H40<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brusquement r\u00e9veill\u00e9, le g\u00e9ant dort toujours &bull; Le Pentagone ne cesse de s&rsquo;agiter et de faire donner ses correspondants fid\u00e8les dans la presseSyst\u00e8me : pour lui, le vrai danger c&rsquo;est la Chine et toute l&rsquo;attention port\u00e9e \u00e0 l&rsquo;Ukraine est mauvaise conseill\u00e8re. &bull; Mais il existe au d\u00e9partement d&rsquo;&Eacute;tat et sous l&rsquo;oreiller de Biden un clan&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3977,2645,3176,2667,3175,3194,10028,1296,2804,12643],"class_list":["post-80649","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chine","tag-guerre","tag-harbor","tag-mercouris","tag-pearl","tag-pentagone","tag-politico","tag-ukraine","tag-usa","tag-zuesse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80649"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80649\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}