{"id":80656,"date":"2023-06-24T17:00:15","date_gmt":"2023-06-24T17:00:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/06\/24\/obama-prigozine-ou-wagner-en-crimee\/"},"modified":"2023-06-24T17:00:15","modified_gmt":"2023-06-24T17:00:15","slug":"obama-prigozine-ou-wagner-en-crimee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/06\/24\/obama-prigozine-ou-wagner-en-crimee\/","title":{"rendered":"Obama &amp; Prigozine, ou \u2018<em>Wagner<\/em>&lsquo; en Crim\u00e9e"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Obama &#038; Prigozine, ou &lsquo;<em>Wagner<\/em>&lsquo; en Crim\u00e9e<\/h2>\n<\/p>\n<p><p>24 juin 2023 (17H00) &ndash; Dans ces temps aventureux, je voudrais faire un parall\u00e8le qui l&rsquo;est tout autant, aventureux, mais qui pr\u00e9sente quelques vertus. On s&rsquo;en \u00e9tonnera peut-\u00eatre parce qu&rsquo;il y a d&rsquo;un c\u00f4t\u00e9 un \u00e9v\u00e9nement \u00e9norme qui se poursuit et, de l&rsquo;autre, l&rsquo;\u00e9v\u00e9nement d&rsquo;un instant qu&rsquo;on a d\u00e9j\u00e0 oubli\u00e9. Ce qui m&rsquo;int\u00e9resse pourtant, c&rsquo;est une interpr\u00e9tation parall\u00e8le, pour montrer des similitudes cach\u00e9es et, par cons\u00e9quent, le r\u00f4le de r\u00e9v\u00e9lateurs de ces deux \u00e9v\u00e9nements.<\/p>\n<\/p>\n<p><p>Les deux \u00e9v\u00e9nements sont les suivants :<\/p>\n<\/p>\n<p><p>&bull; Prigozine et le PMC &lsquo;<em>Wagner<\/em>&lsquo;, bien s&ucirc;r, dans une sorte de <em>remake <\/em>\u00e0 la sauce postmoderne d&rsquo;un passage ou l&rsquo;autre de l&rsquo;ann\u00e9e 1917.<\/p>\n<\/p>\n<p><p>&bull; Une d\u00e9claration d&rsquo;Obama \u00e0 CNN, \u00e0 propos des \u00e9v\u00e9nements de 2014 (il \u00e9tait alors pr\u00e9sident) en Ukraine, et sp\u00e9cifiquement le cas crim\u00e9en, avec l&rsquo;intervention de l&rsquo;arm\u00e9e russe \u00e0 l&rsquo;appel des autorit\u00e9s locales, un r\u00e9f\u00e9rendum et le rattachement \u00e0 la Russie.<\/p>\n<\/p>\n<p><p>Je passe rapidement les deux choses en revue, avec le principal que je m&rsquo;attache \u00e0 en dire, selon ma perception. Puis on verra bien o&ugrave; je veux en venir, si je le sais moi-m\u00eame&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Prigozine sur la musique de Wagner<\/h3>\n<\/p>\n<p><p>On s&rsquo;attend bien \u00e0 ce que je dise qu&rsquo;il ne faut rien attendre de moi, ni de pr\u00e9cis sur les troubles, ni des intentions des uns et des autres, ni des situations pr\u00e9sentes et imm\u00e9diatement \u00e0 venir, ni des positions des principaux acteurs. Une seule chose m&rsquo;a arr\u00eat\u00e9e, qui m&rsquo;est souffl\u00e9e par &lsquo;<em><a href=\"http:\/\/siteveillestrategique.blogspot.com\/2023\/06\/russie-quoi-joue-la-smp-wagner-24-juin.html\">Military Summary<\/a><\/em>&lsquo;, repris par &lsquo;<em>Veille Strat\u00e9gique<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9diteur de ce travail quotidien, qui suit la situation au jour le jour estime que les \u00e9v\u00e9nements, quels qu&rsquo;ils soient, &ndash;  que ce soit un simulacre (&lsquo;<em>maskirovska<\/em>&lsquo;) ou un coup r\u00e9el, &ndash; plongent la soci\u00e9t\u00e9 russe dans une situation tragique et autorise certaines mesures radicales \u00e0 un moment crucial, alors qu&rsquo;une mobilisation g\u00e9n\u00e9rale se d\u00e9veloppe en Ukraine et que les conditions d&rsquo;une possibilit\u00e9 d&rsquo;intervention directe de l&rsquo;OTAN se pr\u00e9cise.<\/p>\n<\/p>\n<p><p>Ainsi fait-il cette hypoth\u00e8se, que je place en contrepoint de l&rsquo;hypoth\u00e8se d&rsquo;une situation de d\u00e9sordre civil puis au-del\u00e0 des fronti\u00e8res russes si l&rsquo;ordre n&rsquo;est pas restaur\u00e9&#8230; Poutine, qui n&rsquo;est par ailleurs pas contest\u00e9 comme pr\u00e9sident par aucun des acteurs, partisans et opposants, du &lsquo;<em>Wagnergate<\/em>&lsquo;, se trouverait dans l&rsquo;hypoth\u00e8se envisag\u00e9e renforc\u00e9 dans un sens par les \u00e9v\u00e9nements, l\u00e9gitim\u00e9  en quelque sorte pour prendre des mesures draconiennes qu&rsquo;il jugerait indispensables dans une situation per\u00e7ue comme <a href=\"https:\/\/theduran.com\/decision-making-centers-will-be-destroyed-russia-warns-us-uk\/\">en constante aggravation<\/a> depuis la mise en \u00e9vidence de perspectives d&rsquo;affrontement direct avec l&rsquo;OTAN :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Cette situation donne \u00e0 Poutine le pouvoir, premi\u00e8rement d&rsquo;instaurer la loi martiale sur le territoire de la F\u00e9d\u00e9ration de Russie, et deuxi\u00e8mement de d\u00e9cr\u00e9ter la mobilisation g\u00e9n\u00e9rale<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Obama, lorsqu&rsquo;il \u00e9tait BHO<\/h3>\n<\/p>\n<p><p>Pour ce qui est d&rsquo;Obama, il s&rsquo;agit d&rsquo;une <a href=\"https:\/\/www.zerohedge.com\/geopolitical\/obama-issues-words-seen-sympathetic-russia-cnn-interview\">interview de Christian Armanpour<\/a>, toujours de CNN et toujours aussi agressive. Elle a surtout pouss\u00e9 l&rsquo;ancien pr\u00e9sident dans ses plus vieux retranchements pour ce qui concerne l&rsquo;Ukraine, c&rsquo;est-\u00e0-dire 2014, l&rsquo;ann\u00e9e du putsch de Kiev. Pourquoi, aboie-t-elle, a-t-on laiss\u00e9 la Russie envahir la Crim\u00e9e sans r\u00e9agir ? Parce que observe Obama, il n&rsquo;y a pas eu vraiment d&rsquo;invasion :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Il y a une raison pour laquelle il n&rsquo;y a pas eu d&rsquo;invasion arm\u00e9e de la Crim\u00e9e<\/em> [en 2014]<em>, c&rsquo;est parce que la Crim\u00e9e \u00e9tait pleine de russophones\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 \u00e0 Christiane Amanpour, sur CNN. Il a ajout\u00e9 qu'\u00a0\u00bbil y avait une certaine sympathie pour le point de vue selon lequel la Russie repr\u00e9sentait ses int\u00e9r\u00eats\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La principale d\u00e9fense d&rsquo;Obama a \u00e9t\u00e9 de dire que \u00ab\u00a0l&rsquo;Ukraine de l&rsquo;\u00e9poque n&rsquo;\u00e9tait pas l&rsquo;Ukraine dont nous parlons aujourd&rsquo;hui\u00a0\u00bb. Il a n\u00e9anmoins affirm\u00e9 que les sanctions qu&rsquo;il avait prises avaient emp\u00each\u00e9 la Russie d&rsquo;aller plus loin \u00e0 l&rsquo;\u00e9poque<\/em>. [&#8230;] <em>Il a ajout\u00e9 : \u00ab\u00a0Il y avait en effet<\/em> [en Crim\u00e9e] <em>une faction suffisamment importante d&rsquo;hommes politiques qui soutenaient l&rsquo;id\u00e9e de d\u00e9velopper de bonnes relations avec la Russie<\/em> [et] <em>qui se sont \u00e9lev\u00e9s contre l&rsquo;imposition de la russophobie\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Il est int\u00e9ressant de noter que le Kremlin a accueilli positivement l&rsquo;\u00e9valuation de M. Obama, le porte-parole de Poutine, Dimitri Pechkov, d\u00e9clarant que les nouvelles remarques de M. Obama repr\u00e9sentaient une \u00ab\u00a0pens\u00e9e rationnelle\u00a0\u00bb. Il a ajout\u00e9 que \u00ab\u00a0de temps en temps, une telle pens\u00e9e rationnelle se fraie un chemin<\/em> [aux &Eacute;tats-Unis]\u00a0\u00bb. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On a aussit\u00f4t interpr\u00e9t\u00e9 les propos d&rsquo;Obama, dans un sens extr\u00eamement d\u00e9favorable \u00e0 l&rsquo;ancien pr\u00e9sident soudain soup\u00e7onn\u00e9 d&rsquo;\u00eatre prorusse et ami de Poutine, ce qui est une surprise consid\u00e9rable et une mesure du d\u00e9sordre des esprits si l&rsquo;on consid\u00e8re le statut de quasi-sanctification dont Obama jouit aux USA.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ces commentaires ont suscit\u00e9 l&rsquo;indignation des experts ukrainiens et am\u00e9ricains&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;interview d&rsquo;Obama a imm\u00e9diatement suscit\u00e9 des condamnations de la part d&rsquo;\u00e9minents experts en ligne, certains qualifiant de \u00ab\u00a0honteuses\u00a0\u00bb ses remarques sur la repr\u00e9sentation des int\u00e9r\u00eats de la Crim\u00e9e par la Russie, d&rsquo;autres estimant que cela revient \u00e0 justifier l'\u00a0\u00bbannexion\u00a0\u00bb de la Crim\u00e9e comme \u00e9tant l\u00e9gale et justifi\u00e9e. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Jonathan Eyal, du Royal United Services Institute (RUSI, le think tank le plus fameux au Royaume-Uni), a d\u00e9clar\u00e9 qu&rsquo;Obama \u00ab\u00a0colportait des absurdit\u00e9s int\u00e9ress\u00e9es\u00a0\u00bb. Pourtant, on peut dire qu&rsquo;Obama fait preuve de r\u00e9alisme en \u00e9valuant les circonstances historiques de la guerre<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Deux situation symboliques<\/h3>\n<\/p>\n<p><p>Ce que je juge de similaire dans ces deux situations, c&rsquo;est leur caract\u00e8re symbolique de ce que j&rsquo;estime \u00eatre l&rsquo;in\u00e9vitable aggravation de la situation. Pour Prigogine, \u00e9gocentrique psychotique, ou com\u00e9dien assum\u00e9 \u00e0 l&rsquo;ambition monstrueuse, ou martyr d\u00e9nonciateur d&rsquo;une bureaucratie d\u00e9vorante, ou tra&icirc;tre et agent provocateur de l&rsquo;Ouest-psychoactif, il s&rsquo;agit au minimum de la courroie de transmission d&rsquo;un &lsquo;<em>deus ex machina<\/em>&lsquo; qui entend imposer la trag\u00e9die \u00e0 la Russie et au monde.<\/p>\n<\/p>\n<p><p>Pour Obama, il s&rsquo;agit d&rsquo;une d\u00e9marche provoqu\u00e9e de la recherche des sources cach\u00e9es de l&rsquo;\u00e9norme simulacre ukrainien o&ugrave; Washington s&rsquo;\u00e9broue activement, et une ic\u00f4ne de la stature d&rsquo;Obama est toute indiqu\u00e9e pour donner \u00e0 cette recherche un vernis de respectabilit\u00e9, et au fond une sorte d&rsquo;autorisation d&rsquo;enfreindre les r\u00e8gles du simulacre et de retrouver quelques <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a>. Du coup, les USA, emport\u00e9s dans leur folie guerri\u00e8re, se trouvent confront\u00e9s \u00e0 la possibilit\u00e9 que la r\u00e9alit\u00e9 de cette folie leur soit impos\u00e9e par des rappels historiques, alors que l&rsquo;on s&rsquo;achemine vers la possibilit\u00e9 d&rsquo;une explosion globale. Cette sorte de symbolisme peut produire, de ce c\u00f4t\u00e9 de la bataille qui est si sensible \u00e0 la communication, des \u00e9volutions, des affrontements, des r\u00e9alignements jusqu&rsquo;alors absolument improbables.<\/p>\n<\/p>\n<p><p>On ajoutera, pour ce m\u00eame c\u00f4t\u00e9 de l&rsquo;Atlantique, le constat affreux du directeur de Raytheon rapport\u00e9 par le &lsquo;<em>Financial Times<\/em>&lsquo; (via <a href=\"https:\/\/sonar21.com\/u-s-military-shackled-to-china-because-of-rare-earth-minerals-and-prigozhin-has-a-psychotic-break\/\">Larry Johnson<\/a>), constatant que la d\u00e9pendance des livraisons de \u00ab\u00a0terres rares\u00a0\u00bb par la Chine rend son entreprise, comme l&rsquo;industrie de l&rsquo;armement US en g\u00e9n\u00e9ral, incapable de produire normalement des syst\u00e8mes d&rsquo;arme sans les livraisons chinoises.<\/p>\n<\/p>\n<p><p>Johnson rapporte alors :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Les observations ironiques de l&rsquo;entrepreneur Arnaud Bertrand r\u00e9sument bien la situation :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>C&rsquo;est hilarant. Le patron de Raytheon, l&rsquo;un des principaux fabricants d&rsquo;armes am\u00e9ricains, d\u00e9clare que son entreprise a &quot;plusieurs milliers de fournisseurs en Chine et que le d\u00e9couplage est impossible&quot;.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Nous avons besoin de la Chine pour combattre la Chine<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce commentaire est compl\u00e9t\u00e9 par l&rsquo;identification d&rsquo;un \u00ab\u00a0bonne nouvelle\u00a0\u00bb puisque ce \u00ab\u00a0besoin de Chine\u00a0\u00bb &laquo; &#8230;<em>rend la guerre<\/em> [avec la Chine]<em> moins probable<\/em> &raquo;&#8230; La guerre comme on la con\u00e7oit, peut-\u00eatre, mais c&rsquo;est au contraire, &ndash; comme on l&rsquo;a vu plus haut et comme on le voit souvent puisque c&rsquo;est toujours la m\u00eame chanson, &ndash; un formidable accroissement des tensions et des oppositions aux USA, avec toutes ces psychologies totalement exacerb\u00e9es et radicalis\u00e9es, pour certaines rendues folles si l&rsquo;on se trouve dans l&rsquo;impossibilit\u00e9 de guerroyer comme elles en ont absolument besoin.<\/p>\n<\/p>\n<p><p>Cet amoncellement de nouvelles, consid\u00e9r\u00e9es par rapport \u00e0 notre point de vue crisique central, constitue un facteur d&rsquo;acc\u00e9l\u00e9ration et de renforcement de l&rsquo;\u00e9norme <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">tourbillon crisique<\/a> o&ugrave; nous nous trouvons emport\u00e9s. Rien de nouveau dira-t-on \u00e9galement, sinon la poursuite toujours acc\u00e9l\u00e9r\u00e9e d&rsquo;une marche folle vers une <em>terra incognita <\/em>qui sera bien plus que \u00ab\u00a0quelque chose de nouveau\u00a0\u00bb.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obama &#038; Prigozine, ou &lsquo;Wagner&lsquo; en Crim\u00e9e 24 juin 2023 (17H00) &ndash; Dans ces temps aventureux, je voudrais faire un parall\u00e8le qui l&rsquo;est tout autant, aventureux, mais qui pr\u00e9sente quelques vertus. On s&rsquo;en \u00e9tonnera peut-\u00eatre parce qu&rsquo;il y a d&rsquo;un c\u00f4t\u00e9 un \u00e9v\u00e9nement \u00e9norme qui se poursuit et, de l&rsquo;autre, l&rsquo;\u00e9v\u00e9nement d&rsquo;un instant qu&rsquo;on a&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[12298,3642,14810,18103,1296,9254],"class_list":["post-80656","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-12298","tag-cnn","tag-mutinerie","tag-pmc","tag-ukraine","tag-wagner"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80656"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80656\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}