{"id":80711,"date":"2023-08-11T19:17:42","date_gmt":"2023-08-11T19:17:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/08\/11\/la-nego-bouffe-de-djeddah\/"},"modified":"2023-08-11T19:17:42","modified_gmt":"2023-08-11T19:17:42","slug":"la-nego-bouffe-de-djeddah","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/08\/11\/la-nego-bouffe-de-djeddah\/","title":{"rendered":"La n\u00e9go-bouffe de Djeddah"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La n\u00e9go-bouffe de Djeddah<\/h2>\n<\/p>\n<p><p>11 ao&ucirc;t 2023 (19H20) &ndash; Oui, sans nul doute, la r\u00e9union, dite peut-\u00eatre \u00ab\u00a0conf\u00e9rence de la paix\u00a0\u00bb, r\u00e9unie samedi-dimanche \u00e0 Djeddah a \u00e9t\u00e9 un \u00e9v\u00e9nement baroque, une sorte de ballon gonfl\u00e9 \u00e0 la fum\u00e9e de Marie-Jeanne et d\u00e9gonfl\u00e9 par la gr\u00e2ce douteuse d&rsquo;une injection d&rsquo;un vaccun Pfitzer, comme un simulacre qui pr\u00e9tendrait \u00eatre un stratag\u00e8me parlant de strat\u00e9gie en semant partout des pi\u00e8ges pour culs de jatte aveugles, et qui se r\u00e9v\u00e9la \u00eatre une balourdise incons\u00e9quente, une brioche d&rsquo;une lourdeur incroyable. Les empires sur le d\u00e9clin d\u00e9g\u00e9n\u00e9r\u00e9, comme \u00e7a, deviennent d&rsquo;une incroyable m\u00e9diocrit\u00e9, et d&rsquo;une sottise surprenante. Il para&icirc;t que c&rsquo;est une trouvaille-perso de Jack Sullivan : cela me donne plein d&rsquo;espoir pour la campagne de r\u00e9\u00e9lection de Biden dont il a la charge.<\/p>\n<\/p>\n<p><p>Que s&rsquo;est-il pass\u00e9 exactement ? Ecoutez <a href=\"https:\/\/theduran.com\/saudi-peace-summit-fails-zelensky-warns-russian-navy\/\">nos deux comp\u00e8res<\/a> faire leur doagnostic en rigolant int\u00e9rieurement ou en s&rsquo;exclamant emphatiquement. Christoforou, lui, y voir un \u00ab\u00a0<em>nothing-burger<\/em>\u00a0\u00bb dont il n&rsquo;est rien sorti, aucun communiqu\u00e9, aucune d\u00e9claration commune, m\u00eame pas un souhait pour la paix&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Christoforou<\/em><\/strong> : &#8230;&laquo; <em>Ce fut un \u00e9chec complet et absolu, parce qu&rsquo;il n&rsquo;y a rien, pas m\u00eame un communiqu\u00e9&#8230; Qu&rsquo;est-ce que vous faites de cela, finalement ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Mercouris<\/em><\/strong> : &laquo; <em>Oh, je suis absolument d&rsquo;accord avec vous, vous avez absolument raison&#8230; Ce fut un v\u00e9ritable \u00e9chec, je dirais m\u00eame que ce fut une d\u00e9bacle&#8230; !<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Est-il tellement n\u00e9cessaire d&rsquo;en dire plus ? Je veux dire, pour r\u00e9pondre \u00e0 la question \u00ab\u00a0Que s&rsquo;est-il pass\u00e9 exactement ?\u00a0\u00bb La conf\u00e9rence manqua tellement de substance, en r\u00e9unissant tout le monde autour d&rsquo;un plan (le \u00ab\u00a0plan\u00a0\u00bben 10 points de Zelenski) auquel personne ne croit, &ndash; ni m\u00eame Zelenski, ni Sullivan, &ndash; et en omettant de mani\u00e8re appuy\u00e9e et comme si l&rsquo;on faisait une g\u00e9niale strat\u00e9gie, d&rsquo;inviter le deuxi\u00e8me adversaire sur le terrain, celui qui est en train d&rsquo;\u00e9craser le premier avec son plan en 10 points ! Vous voyez le s\u00e9rieux de la chose ?<\/p>\n<\/p>\n<p><p>D&rsquo;autant plus dr\u00f4le, &ndash; \u00ab\u00a0dr\u00f4le de n\u00e9go\u00a0\u00bb pour une \u00ab\u00a0dr\u00f4le de guerre\u00a0\u00bb, &ndash;  que chacun avait son propre plan en poche, les Saoudiens, les Chinois, etc., et n&rsquo;avait que faire de ces couillonnades de Mister Z qui n&rsquo;int\u00e9ressent personne. On avait l&rsquo;impression que le gouvernement des Etats-Unis avait r\u00e9uni cette conf\u00e9rence simplement pour pouvoir dire : \u00ab\u00a0Vous voyez, vous voyez ! Moi aussi, je peux r\u00e9unir des conf\u00e9rences !\u00a0\u00bb Certains \u00e9taient m\u00eame venus pour dire qu&rsquo;ils ne viendraient pas \u00e0 la prochaine \u00e9dition si les Russes n&rsquo;\u00e9taient pas invit\u00e9s, &ndash; les Br\u00e9siliens et les Chinois, et peut-\u00eatre m\u00eame les Indiens, ont annonc\u00e9 \u00e7a, selon Mercouris.<\/p>\n<\/p>\n<p><p>Edward Korybko, qui parle par moment d&rsquo;une plume tr\u00e8s mesur\u00e9e, a comment\u00e9 \u00e0 plusieurs reprises les n\u00e9go-bouffe (exactement : \u00ab\u00a0n\u00e9gociations-bouffe\u00a0\u00bb) de Djeddah avec un calme imperturbable, comme si l&rsquo;affaire \u00e9tait vraiment s\u00e9rieuse. On peut le suivre ici ou l\u00e0, ne serait-ce que pour <a href=\"https:\/\/korybko.substack.com\/p\/western-media-is-trying-in-vain-to\">avoir une id\u00e9e<\/a> de ce que les m\u00e9dias bien dans le rang, &ndash; les m\u00e9das <a href=\"https:\/\/www.dedefensa.org\/article\/honnetete-et-franchise-de-la-pressesysteme\">\u00ab\u00a0honn\u00eates\u00a0\u00bb et \u00ab\u00a0francs\u00a0\u00bb<\/a> de la presseSyst\u00e8me, &ndash; ont dit de la confrence, CNN notamment qui ne sait plus tr\u00e8s bien o&ugrave; il en est, tant\u00f4t presque antiSyst\u00e8me tant\u00f4t&#8230;  <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>CNN a publi\u00e9 lundi un article d\u00e9clarant de mani\u00e8re provocante que \u00ab\u00a0la Chine fait l&rsquo;\u00e9loge des pourparlers avec l&rsquo;Ukraine en Arabie saoudite que la Russie a qualifi\u00e9s de &lsquo;vou\u00e9s \u00e0 l&rsquo;\u00e9chec'\u00a0\u00bb, qui visait \u00e0 faire des pourparlers de Djeddah un probl\u00e8me dans les relations sino-russes en pr\u00e9sentant faussement la participation de P\u00e9kin \u00e0 ceux-ci. comme une l\u00e9g\u00e8re contre Moscou. Les deux membres de l&rsquo;Entente sino-russo, qui n&rsquo;est pas une \u00ab\u00a0alliance\u00a0\u00bb mais plut\u00f4t un partenariat strat\u00e9gique d&rsquo;une proximit\u00e9 sans pr\u00e9c\u00e9dent visant \u00e0 acc\u00e9l\u00e9rer la multipolarit\u00e9, savent qu&rsquo;il ne faut pas tomber dans cette sorte de pi\u00e8ge criant<\/em>&#8230; [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Loin de ce que les m\u00e9dias<\/em> [de la presseSyst\u00e8me] <em>et m\u00eame certains membres de l\u00a0\u00bb<a href=\"https:\/\/thealtworld.com\/andrew_korybko\/a-review-of-the-most-common-roles-in-the-alt-media-community\">Alt-Media Community<\/a>&lsquo; ont fait des pourparlers de Djeddah comme d&rsquo;un probl\u00e8me  pour les liens des participants avec la Russie, ces pays neutres comme la Chine et l&rsquo;Inde qui y ont particip\u00e9 ont en fait renforc\u00e9 leurs liens. avec la Russie en cons\u00e9quence. Ils ont montr\u00e9 \u00e0 Moscou qu&rsquo;ils tiendront non seulement fermement leurs positions sous une immense pression, mais qu&rsquo;ils repousseront m\u00eame l&rsquo;Occident en partageant avec d&rsquo;autres leurs propres solutions pragmatiques \u00e0 ce conflit. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Aussi Korybko, pour redresser ces commentaires malheureux des \u00ab\u00a0francs\u00a0\u00bb et \u00ab\u00a0honn\u00eates\u00a0\u00bb z\u00e9lotes de la presseSyst\u00e8me, entend montrer que ce sommet, malgr\u00e9 son extraordinaire et quasi extra-terrestre inutilit\u00e9, a tout de m\u00eame servi \u00e0 quelque chose, &ndash; disons, dans le champ des bonnes mani\u00e8res et des amabilit\u00e9s. Il note donc, contre les observations goguenardes et venimeuses des commentateurs de l&rsquo;absence de Moscou :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Dans le m\u00eame temps, cependant, cela ne signifie pas que les pourparlers de Djeddah n&rsquo;ont eu aucun aspect positif. Comme expliqu\u00e9 ici, ils se sont retourn\u00e9s contre Zelenski en offrant aux repr\u00e9sentants chinois et indiens l&rsquo;occasion de partager leurs fins de partie envisag\u00e9es dans la guerre par procuration OTAN-Russie avec le plus grand nombre de d\u00e9cideurs jusqu&rsquo;\u00e0 pr\u00e9sent. Les pays qui souhaitent sinc\u00e8rement mettre fin au conflit le plus t\u00f4t possible pr\u00e9f\u00e9reront naturellement leurs propositions de compromis aux exigences maximalistes irr\u00e9alistes de Kiev.<\/em><\/p>\n<\/p>\n<p><p><strong>&raquo; <\/strong><em>Tout comme \u00ab\u00a0l&rsquo;Inde a montr\u00e9 sa neutralit\u00e9 lors des pourparlers de paix centr\u00e9s sur l&rsquo;ouest du week-end dernier sur l&rsquo;Ukraine\u00a0\u00bb, la Chine l&rsquo;a fait aussi. Selon le minist\u00e8re chinois des Affaires \u00e9trang\u00e8res, leur repr\u00e9sentant \u00ab\u00a0a eu de nombreux contacts et \u00e9changes avec les parties participantes, a clarifi\u00e9 la position et les propositions de la Chine, a \u00e9cout\u00e9 les opinions et les conseils de diverses parties et a travaill\u00e9 pour une compr\u00e9hension plus commune du r\u00e8glement politique de la crise ukrainienne\u00a0\u00bb. Le r\u00f4le positif de la Chine dans la promotion des pourparlers de paix a \u00e9t\u00e9 pleinement reconnu<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le commentaire rend curieusement compte, dans cette partie constructive, d&rsquo;une esp\u00e8ce d&rsquo;atmosph\u00e8re bon-enfant entre les amis de Moscou. On a l&rsquo;impression qu&rsquo;ils discutent entre eux de leurs visions r\u00e9ciproques, qu&rsquo;ils sont si proches les uns des autres qu&rsquo;elles pourraient faire l&rsquo;affaire de Moscou. Peut-\u00eatre se sont-ils entretenus, pendant que l&rsquo;horripilant Mister Z \u00e9grenait ses dix points, du prochain sommet des BRICS, \u00e9galement avec les Sud-Africains, \u00e9videmment pr\u00e9sents (les USA s&rsquo;y entendent pour faire des plans de table avec pour but de subvertir les amis de Moscou).<\/p>\n<\/p>\n<p><p>Peut-\u00eatre m\u00eame l&rsquo;un ou l&rsquo;autre, l&rsquo;Indien ou le Br\u00e9silien, at-il pass\u00e9 un coup de fil \u00e0 Poutine pendant une suspension de  s\u00e9ance, pour le rassurer sur l&rsquo;avancement des travaux. Ils ont \u00e9chang\u00e9 sur les derni\u00e8res nouvelles : &laquo; <em>L&rsquo;Ouest ne peut pas vaincre la Russie<\/em> &raquo;, dit le pr\u00e9sident serbe <a href=\"https:\/\/www.rt.com\/news\/581140-west-cant-defeat-russia-vucic\/\">Vucic<\/a> ; &laquo; <em>Biden est devenu fou<\/em> &raquo;, dit <a href=\"https:\/\/www.rt.com\/news\/581126-trump-biden-insane-migration-indictments\/\">Trump<\/a>. Ou bien encore, dans un coup de t\u00e9l\u00e9phone \u00e0 Poutine toujours entre deux s\u00e9ances, l&rsquo;annonce de la formidable id\u00e9e de mademoiselle (madame, plut\u00f4t) <a href=\"https:\/\/cepa.org\/article\/natos-future-must-be-global\/\">Jessica Berlin<\/a>, du CEPA (&lsquo;<em>Center for European Policy Analysis<\/em>&lsquo;), de faire de l&rsquo;OTAN une alliance mondiale de toutes les d\u00e9mocraties contre toutes les menaces contre toutes les d\u00e9mocraties, &ndash; \u00ab\u00a0une alliance <a href=\"https:\/\/www.zerohedge.com\/geopolitical\/nato-without-limits\">sans limites ni fronti\u00e8res<\/a>\u00ab\u00a0, &ndash; comme il y avait &lsquo;Jeux sans fronti\u00e8res&rsquo;, ce serait l&rsquo;OTAN sans fronti\u00e8res&rsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La situation des menaces au XXIe si\u00e8cle exige une alliance mondiale capable de se d\u00e9fendre mutuellement. L&rsquo;OTAN a peut-\u00eatre des d\u00e9fauts, mais elle reste l&rsquo;alliance d\u00e9fensive la plus efficace dont dispose le monde d\u00e9mocratique. Nous devons renforcer ses fondations existantes et nous pr\u00e9parer \u00e0 ouvrir ses portes. Dans la tradition de la logique fondatrice de l&rsquo;OTAN, mais \u00e9voluant pour faire face \u00e0 un nouveau paysage g\u00e9opolitique, la Nouvelle Organisation du Trait\u00e9 d&rsquo;Alliance prot\u00e9gerait le monde libre en emp\u00eachant les anciens ennemis d&rsquo;entrer, en gardant les alli\u00e9s, nouveaux et anciens, \u00e0 l&rsquo;int\u00e9rieur, et en r\u00e9duisant les nouvelles menaces<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>\u00ab\u00a0Quel rapport avec les n\u00e9gos-bouffe de Djeddah ?\u00a0\u00bb demande Poutine \u00e0 son interlocuteur d&rsquo;occasion.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Aucun\u00a0\u00bb, lui r\u00e9pond-on, \u00ab\u00a0mais il faut bien s&rsquo;occuper, ne trouvez-vous pas ? De toutes les fa\u00e7ons, tout le monde est d&rsquo;accord pour ne parvenir \u00e0 aucun acord\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&#8230; Ainsi se termina la n\u00e9go-bouffe de Djeddah, en attendant la prochaine fiesta. Puis-je introduire ici un souvenir de vieil emmerdeur bougon et r\u00e2leur ? N&rsquo;ayez crainte, ce souvenir n&rsquo;apportera rien \u00e0 personne.<\/p>\n<\/p>\n<p><p>Je fais mon travail de voltigeur du commentaire depuis pr\u00e8s de soixante ans. A mes d\u00e9buts, d\u00e9j\u00e0 dans les affaires internationales et diplomatiques, je me rappelle, il y avait toujours des incidents, plus ou moins importants ; une crise, une tension, une d\u00e9claration furieuse, bref l&rsquo;une ou l&rsquo;autre agitation dans les rangs. Alors, il y avait toujours quelqu&rsquo;un pour appeler \u00e0 une conf\u00e9rence et tout le monde applaudissait. On se rencontrait, on se parlait, on se disait ses quatre v\u00e9rit\u00e9s tr\u00e8s poliment, on restait tr\u00e8s amis, on n&rsquo;arrivait pas vraiment \u00e0 r\u00e9soudre le probl\u00e8me mais on comprenait qu&rsquo;on pouvait vivre avec et l&rsquo;on sortait bras-dessus bras-dessous en annon\u00e7ant que tout \u00e9tait r\u00e9solu et les affaires du monde continuant dans la concorde retrouv\u00e9e.<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui, on annonce cette conf\u00e9rence en marmonnant \u00ab\u00a0nous sommes fous\u00a0\u00bb. On y va en se disant \u00ab\u00a0C&rsquo;est inutile, elle ne sert strictement \u00e0 rien\u00a0\u00bb. On y entre en disant : \u00ab\u00a0C&rsquo;est une impasse qui m\u00e8ne \u00e0 une voie sans issue\u00a0\u00bb. On en sort en marmonnant et en haussant les \u00e9paules, avec certains qui font des cabrioles, un entonnoir sur la t\u00eate, en parlant de rien et de rien. Et l&rsquo;on dit : \u00ab\u00a0C&rsquo;est une voie sans issue qui m\u00e8ne \u00e0 une impasse\u00a0\u00bb. On est des Modernes et il n&rsquo;y a pas un seul mensonge dans tout cela<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La n\u00e9go-bouffe de Djeddah 11 ao&ucirc;t 2023 (19H20) &ndash; Oui, sans nul doute, la r\u00e9union, dite peut-\u00eatre \u00ab\u00a0conf\u00e9rence de la paix\u00a0\u00bb, r\u00e9unie samedi-dimanche \u00e0 Djeddah a \u00e9t\u00e9 un \u00e9v\u00e9nement baroque, une sorte de ballon gonfl\u00e9 \u00e0 la fum\u00e9e de Marie-Jeanne et d\u00e9gonfl\u00e9 par la gr\u00e2ce douteuse d&rsquo;une injection d&rsquo;un vaccun Pfitzer, comme un simulacre qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3259,2631,2952,2667,2697,6157,2681,2730,9726,13670,2829],"class_list":["post-80711","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-arabie","tag-de","tag-korybko","tag-mercouris","tag-negociations","tag-paix","tag-plan","tag-russie","tag-sullivan","tag-ukrisis","tag-zelenski"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80711"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80711\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}