{"id":80755,"date":"2023-09-16T19:20:29","date_gmt":"2023-09-16T19:20:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/09\/16\/plus-neocon-gateux-que-jamais\/"},"modified":"2023-09-16T19:20:29","modified_gmt":"2023-09-16T19:20:29","slug":"plus-neocon-gateux-que-jamais","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/09\/16\/plus-neocon-gateux-que-jamais\/","title":{"rendered":"Plus <em>neocon <\/em>g\u00e2teux que jamais"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Plus <em>neocon <\/em>g\u00e2teux que jamais<\/h2>\n<\/p>\n<p><p>16 septembre 2023 (19H20) &ndash; On conna&icirc;t le constant int\u00e9r\u00eat que j&rsquo;attache au travail d&rsquo;Alexander Mercouris, que je suis r\u00e9guli\u00e8rement sur son programme &lsquo;<em>TheDuran<\/em>&lsquo;. Je signale ici <a href=\"https:\/\/theduran.com\/blinken-hints-wants-ukr-conflict-freeze-focus-china-shoigu-victory-only-option-attrition-war\/\">sa chronique d&rsquo;hier<\/a>, au contenu particuli\u00e8rement int\u00e9ressant. Il concerne le discours de Blinken, dont j&rsquo;avais dit un tout petit mot dans la <a href=\"https:\/\/www.dedefensa.org\/article\/lillusion-de-la-contrition\">page pr\u00e9c\u00e9dente<\/a> de ce &lsquo;<em>Journal<\/em>&lsquo;, hier, pour asseoir l&rsquo;examen de l&rsquo;illusion qu&rsquo;entretiennent les Indiens de pouvoir &lsquo;jouer&rsquo; en partenariat avec les USA :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La campagne de redressement civilisationnel que sont en train de mener les &Eacute;tats-Unis est compl\u00e8tement foudroyante, grandguignolesque et abracadabrantesque. En a-t-entendu quelques \u00e9chos ? Il suffit de citer le tr\u00e8s civilis\u00e9 et antirusse Blinken, et tout est dit de ce que vous retrouvez <a href=\"https:\/\/washingtondc.jhu.edu\/news\/antony-blinken-the-post-cold-war-era-is-over\/\">en boucle<\/a> dans la presseSyst\u00e8me et au sein des hordes de consultants des plateaux-TV<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je n&rsquo;avais pas \u00e9t\u00e9 plus loin que cette allusion indirecte pour l&rsquo;expos\u00e9 de mon sujet qui ne concernait pas ce discours. Mercouris, lui, le prend \u00e0 bras le corps pour l&rsquo;analyser. Il le fait avec rigueur, pr\u00e9cision et le regard critique qui importe. L&rsquo;analyse, vraiment d&rsquo;un tr\u00e8s grand int\u00e9r\u00eat, va de 00 58&prime; 10&Prime; \u00e0 la fin <a href=\"https:\/\/theduran.com\/blinken-hints-wants-ukr-conflict-freeze-focus-china-shoigu-victory-only-option-attrition-war\/\">de la vid\u00e9o<\/a> (01 23&prime; 10&Prime;), soit un bon quart d&rsquo;heure hautement instructif.<\/p>\n<\/p>\n<p><p>Je mentionne rapidement les points politiques principaux qui sont affirm\u00e9s derri\u00e8re les formules ronflantes et creuses et les diverses aspects du simulacre qui sert d&rsquo;argument politique et historique \u00e0 Blinken sur le th\u00e8me \u00ab\u00a0l&rsquo;\u00e8re de la Guerre Froide est finie, nous entrons dans une nouvelle \u00e8re\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&bull; La guerre d&rsquo;Ukraine n&rsquo;est plus l&rsquo;essentiel. Elle doit \u00eatre fix\u00e9e par un gel des positions et un cessez-le-feu qui actera la &laquo; <em>d\u00e9faite strat\u00e9gique<\/em> &raquo; de la Russie qui n&rsquo;a pas atteint son but principal qui est la conqu\u00eate totale de l&rsquo;Ukraine. La Russie n&rsquo;a jamais au grand jamais affirm\u00e9 cela mais l&rsquo;Occident-maladif l&rsquo;affirme et cela suffit car ainsi en est-il du simulacre.<\/p>\n<\/p>\n<p><p>&bull; Sur ces points pr\u00e9cis, on ne se pr\u00e9occupe pas de savoir ce que pensent et envisagent les Russes, qui refusent cat\u00e9goriquement l&rsquo;id\u00e9e d&rsquo;un cessez-le-feu gel\u00e9 et n&rsquo;envisage d&rsquo;autre issue que &laquo; <em>la victoire<\/em> &raquo;, la vraie bien s&ucirc;r, celle que Shoigou a fix\u00e9 comme objectif jeudi. \u00ab\u00a0Ainsi en est-il du simulacre\u00a0\u00bb, suite&#8230;<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;Ukraine r\u00e9duite \u00e0 une peau de chagrin t\u00e9moignant de ses terribles revers et de la perte de territoires consid\u00e9rables, restera un avant-poste occidental triomphant et se d\u00e9veloppera en une &laquo; <em>d\u00e9mocratie vibrante<\/em> &raquo; qui fera p\u00e2lir d&rsquo;avis la Russie frustre et rustre qui a \u00e9t\u00e9 battue partout sous la forme des divers \u00e9pisodes de la <em>narrative<\/em>.<\/p>\n<\/p>\n<p><p>&bull; Mais l&rsquo;Ukraine ainsi r\u00e9gl\u00e9e  n&rsquo;\u00e9tait qu&rsquo;une &laquo; <em>distraction<\/em> &raquo;, r\u00e9sume Mercouris traduisant Blinken. L&rsquo;essentiel est d\u00e9sormais l&rsquo;attaque de la Chine.<\/p>\n<\/p>\n<p><p>&bull; Pourquoi la Chine ? Cette puissance, interpr\u00e8tent les am\u00e9ricanistes, est directement responsable de la fin de l&rsquo;unipolarit\u00e9 de la Guerre Froide, qui a maintenu une relative stabilit\u00e9 qui permettait la marche en avant d&rsquo;un progr\u00e8s constructif. (&Eacute;tapes r\u00e9centes de la stabilit\u00e9 fa\u00e7on-Blinken : Serbie-1999, 11-septembre, Irak-2003, crise des subprimes-2008, Libye, Syrie 2010-2015, Ukraine-2014, Covid-2020&#8230; Un calme idyllique.) Les USA ayant donc perdu leur position de seule hyperpuissance h\u00e9g\u00e9monique pour le bien du <em>rest of the world <\/em> \u00e0 cause de la Chine, ils entendent r\u00e9gler son compte \u00e0 cette Chine-l\u00e0 pour r\u00e9tablir leur primaut\u00e9-h\u00e9g\u00e9monique si bienfaisante et bvienpensante.<\/p>\n<\/p>\n<p><p>&bull; Observation de Mercouris en forme de commentaire g\u00e9n\u00e9ral sur la forme m\u00eame et l&rsquo;organisation du gouvernement du syst\u00e8me de l&rsquo;am\u00e9ricanisme :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La direction politique du gouvernement am\u00e9ricain est aujourd&rsquo;hui totalement p\u00e9n\u00e9tr\u00e9e, manipul\u00e9e et dirig\u00e9e par les neocon <\/em>[dont Blinken est] <em>le parfait repr\u00e9sentant et l&rsquo;op\u00e9rateur&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il y a \u00e9galement une appr\u00e9ciation g\u00e9n\u00e9rale de la perception que Mercouris a eu de ce texte du discours de Blinken pour dire que lui-m\u00eame a eu du mal \u00e0 aller jusqu&rsquo;au bout, presque comme s&rsquo;il \u00e9tait \u00e9puis\u00e9 par cette lecture. Ce qu&rsquo;il nous sugg\u00e8re ainsi c&rsquo;est que l&rsquo;accumulation d&rsquo;une part de la \u00ab\u00a0connerie politique\u00a0\u00bb (pour paraphraser l&rsquo;expression de &laquo; <em>connerie \u00e9conomique<\/em> &raquo; de Jacques G\u00e9n\u00e9reux selon sa th\u00e8se que <a href=\"https:\/\/www.youtube.com\/watch?v=OCypn_jjC9k\">la b\u00eatise des dirigeants<\/a> est une explication essentielle des actuels \u00e9v\u00e8nements), &ndash; et d&rsquo;autre part du recours absolu et int\u00e9gral au mensonge (simulacre, <em>narrative<\/em>, etc.) conduit tr\u00e8s vite \u00e0 l&rsquo;\u00e9puisement psychologique de l&rsquo;auditeur et du lecteur. Cela est pour sugg\u00e9rer dans quel \u00e9tat psychologique, proche de la folie pure et simple, se trouvent n\u00e9cessairement ceux qui comme Blinken conduisent ces politiques, qu&rsquo;ils aient ou non obscur\u00e9ment conscience de la b\u00eatise et du simulacre. Cette combinaison \u00e9puisante existe sans que nous en ayons nous-m\u00eame n\u00e9cessairement conscience et nous accable sans qu&rsquo;elle affiche sa responsabilit\u00e9.<\/p>\n<\/p>\n<p><p>La m\u00e9diocrit\u00e9 et la banalit\u00e9 catastrophique du propos en d\u00e9coulent naturellement et r\u00e9veillent chez Mercouris de tristes souvenirs. Comme \u00e9puis\u00e9 effectivement, il nous dit :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&#8230; Et alors, le reste du discours que je ne vous lirai certainement pas est devenu pour moi un objet extr\u00eame de d\u00e9pression pour le jugement qu&rsquo;on peut avoir sur Blinken et les gens qui l&rsquo;entourent, et il y a m\u00eame un passage extraordinaire o&ugrave; il fait des commentaires \u00e0 propos de son coll\u00e8gue Jack Sullivan <\/em>[conseiller de Biden et directeur du NSC]<em>, d\u00e9taillant combien Jack Sullivan est un personnage merveilleux qui a r\u00e9ussi \u00e0 int\u00e9grer les politiques ext\u00e9rieure et int\u00e9rieure des &Eacute;tats-Unis, les mettant ensemble dans le trou sans fond que nous voyons et observons&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Je dois dire alors qu&rsquo;\u00e0 certains moments, la fa\u00e7on dont Blinken parle de ses coll\u00e8gues, dont il les couvre d&rsquo;\u00e9loges, m&rsquo;a rappel\u00e9 le style des anciens discours sovi\u00e9tiques, il y a si longtemps&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Leonid-Jack Sullivan-Brejnev ! Tout s&rsquo;explique maintenant&#8230; Pour le reste et pour faire court mais terrifiant, Mercouris nous dit son estimation que cette \u00ab\u00a0politique\u00a0\u00bb expos\u00e9e par Blinken ne peut se terminer qu&rsquo;en affrontement \u00e0 cause de la compl\u00e8te dystopie de perception, entre un Blinken et les autres clones qui suivent en aveugle le simulacre commun restituant ce qui est suppos\u00e9 \u00eatre la haute pens\u00e9e du pr\u00e9sident Biden, &ndash; et une direction russe qui tient avec une in\u00e9branlable fermet\u00e9 \u00e0 la r\u00e9alit\u00e9 et sa <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> et n&rsquo;accepte absolument rien des \u00e9puisantes sornettes am\u00e9ricanistes-occidentalistes :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La premi\u00e8re Guerre Froide s&rsquo;\u00e9tait termin\u00e9e par une n\u00e9gociation. Celle-ci ne pourra l&rsquo;\u00eatre, si l&rsquo;on suit les positions exprim\u00e9es par les uns et les autres, que par l&rsquo;affrontement. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">RapSit-USA2023 : Terreur g\u00e9rontocratique<\/h3>\n<\/p>\n<p><p>On en revient donc \u00e0 ce qui fait notre seul v\u00e9ritable espoir d&rsquo;une rupture brutale de la situation qui en changerait ce cours qui semble in\u00e9luctable : la crise int\u00e9rieure du pouvoir am\u00e9ricaniste. De ce point de vue, bonne nouvelle, &ndash; les nouvelles sont catastrophiques. Aux &Eacute;tats-Unis rien ne change, sinon de pire en pire, tandis que la &lsquo;sovi\u00e9tisation&rsquo; du syst\u00e8me mise en \u00e9vidence par Mercouris se signale \u00e9galement par une \u00ab\u00a0crise g\u00e9rontocratique\u00a0\u00bb comme en connut l&rsquo;URSS dans les derni\u00e8res ann\u00e9es avant l&rsquo;explosion gorbatch\u00e9vienne, une v\u00e9ritable \u00ab\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=OCypn_jjC9k\">paralysie par l&rsquo;\u00e2ge<\/a>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>En effet, rien ne bouge \u00e0 cause de cette paralysie mais tout \u00e9volue vers une explosion autour du Huntergate (de Hunter Biden) multipli\u00e9 par le Bidengate. Steven Abramovicz, propri\u00e9taire et directeur g\u00e9n\u00e9ral du r\u00e9seau &lsquo;<em>Mill Creek View<\/em>&lsquo; et animateur du podcast qui y est publi\u00e9, observe dans son interview <a href=\"https:\/\/sputnikglobe.com\/20230915\/bidengate-why-joes-2024-bid-seems-doomed-1113402827.html\">par &lsquo;<em>SputnikNews<\/em>&lsquo;<\/a> (beaucoup plus actif sur cette crise US que RT.com) l&rsquo;\u00e9trange situation existant aujourd&rsquo;hui avec Joe et Hunter Biden :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ce qui est particuli\u00e8rement frustrant, selon Abramovicz, c&rsquo;est qu&rsquo;il existe un grand nombre de documents authentiques impliquant la famille Biden et que le parti d\u00e9mocrate et la Maison Blanche continuent de pr\u00e9tendre qu&rsquo;il n&rsquo;y a rien<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0C&rsquo;est la <\/em> <em>trag\u00e9die de l&rsquo;Am\u00e9rique de 2023 : nous n&rsquo;aurions jamais permis \u00e0 un Thomas Jefferson ou \u00e0 un Abraham Lincoln de s&rsquo;en tirer comme \u00e7a. Et nous voici donc dans notre nouvelle \u00e8re <\/em>[de la corruption reconnue et proclam\u00e9e]<em> avec notre lot actuel de dirigeants\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les documents s&#8217;empilent, impliquant  et sur-impliquant le p\u00e8re et le fils, et tous les verrous institutionnels que tient la \u00ab\u00a0vieille g\u00e9n\u00e9ration\u00a0\u00bb sont encore plus resserr\u00e9s dans la panique. Cette \u00ab\u00a0vieille g\u00e9n\u00e9ration\u00a0\u00bb est terrifi\u00e9e, non plus du seul Trump mais de tout ce qui est neuf, diff\u00e9rent, un peu r\u00e9formiste.<\/p>\n<\/p>\n<p><p>Ainsi doit-on insister, apr\u00e8s avoir souvent visit\u00e9 et revisit\u00e9 les scandales Bidengate\/Huntergate, sur ceci qui nous appara&icirc;t finalement relativement nouveau dans sa r\u00e9alisation et sa formulation. Cette \u00ab\u00a0crise g\u00e9rontocratique\u00a0\u00bb est, elle, typique de l&rsquo;effondrement, comme nous le v&icirc;mes en 1985-1991.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Fondamentalement, les &Eacute;tats-Unis sont pris dans une crise de l&rsquo;\u00e2ge de type sovi\u00e9tique\u00a0\u00bb, dit l&rsquo;historien constitutionnaliste Daniel Lazare. &quot;Rappelez-vous ce que disait Reagan lorsqu&rsquo;on lui avait demand\u00e9 pourquoi il ne parlait pas avec les dirigeants sovi\u00e9tiques<\/em> [d&rsquo;avant Gorbatchev] <em>: \u00ab\u00a0Parce qu&rsquo;ils risquent de mourir de g\u00e2tisme dans mes bras\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Si la r\u00e9plique de Reagan fait bien fait rire, ajoute Lazare, c&rsquo;est aujourd&rsquo;hui des &Eacute;tats-Unis que l&rsquo;on se moque, avec ses l\u00e9gislateurs \u00e2g\u00e9s qui s&rsquo;accrochent d\u00e9sesp\u00e9r\u00e9ment \u00e0 leur si\u00e8ge au S\u00e9nat, sans parler de la \u00ab\u00a0s\u00e9nilit\u00e9 croissante\u00a0\u00bb de Biden.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Apr\u00e8s qu&rsquo;une superpuissance a sombr\u00e9 dans la g\u00e9rontocratie, comment se fait-il qu&rsquo;une autre fasse la m\u00eame chose 40 ans plus tard ? La r\u00e9ponse \u00e0 cette question est le blocage politique <\/em>[c&rsquo;est-\u00e0-dire la g\u00e9rontocratie]<em>\u00ab\u00a0,  dit Lazare. \u00ab\u00a0Tout le monde est terrifi\u00e9 par ce que le changement pourrait signifier\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Faites-le enfin : comparez cette situation avec les ambitions de l&rsquo;hyper-<em>neocon <\/em>Blinken qui \u00e9crase Mercouris de sa stupidit\u00e9 et de ses mensonges, &ndash; et interrogez-vous. La r\u00e9ponse, mon ami, &laquo; <em>is blowing in the wind<\/em> &raquo;.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus neocon g\u00e2teux que jamais 16 septembre 2023 (19H20) &ndash; On conna&icirc;t le constant int\u00e9r\u00eat que j&rsquo;attache au travail d&rsquo;Alexander Mercouris, que je suis r\u00e9guli\u00e8rement sur son programme &lsquo;TheDuran&lsquo;. Je signale ici sa chronique d&rsquo;hier, au contenu particuli\u00e8rement int\u00e9ressant. Il concerne le discours de Blinken, dont j&rsquo;avais dit un tout petit mot dans la page&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[22167,4151,3977,3228,22165,3650,22166,2667,1296,2671],"class_list":["post-80755","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-bidengate","tag-blinken","tag-chine","tag-crise","tag-gerontocratique","tag-hegemonie","tag-huntergate","tag-mercouris","tag-ukraine","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80755"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80755\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}