{"id":80771,"date":"2023-09-29T18:29:14","date_gmt":"2023-09-29T18:29:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/09\/29\/belle-competition-entre-stupidite-et-servilite\/"},"modified":"2023-09-29T18:29:14","modified_gmt":"2023-09-29T18:29:14","slug":"belle-competition-entre-stupidite-et-servilite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/09\/29\/belle-competition-entre-stupidite-et-servilite\/","title":{"rendered":"Belle comp\u00e9tition entre stupidit\u00e9 et servilit\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Belle comp\u00e9tition entre stupidit\u00e9 et servilit\u00e9<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Macron est l&rsquo;incontestable m\u00e9daille d&rsquo;or pour les deux. &bull; Constat retir\u00e9 de la lecture de l&rsquo;analyse d&rsquo;Andrew Korybko sur l&rsquo;\u00e9viction de la France du Niger, par les USA. &bull; Deux ans apr\u00e8s l&rsquo;affaire AUKUS\/Australie.<\/p>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Macron est certainement le &lsquo;plus-parfait&rsquo; des parfaits pr\u00e9sidents de notre temps. Nous l&rsquo;avons sans doute dit d\u00e9j\u00e0 plusieurs fois, mais il n&rsquo;est pas mauvais de le r\u00e9p\u00e9ter. C&rsquo;est l&rsquo;impression qui se d\u00e9gage, comme un fumet odorant et d\u00e9licat, de l&rsquo;affaire de l&rsquo;\u00e9viction de la France du Niger.<\/p>\n<\/p>\n<p><p>Andrew Korybko nous donne son interpr\u00e9tation de l&rsquo;affaire qui nous semble assez bien convenir aux niveaux et \u00e0 la beaut\u00e9 des relations entre les deux acteurs concern\u00e9s. Il nous rappelle que l&rsquo;exceptionnelle servilit\u00e9 fran\u00e7aise ne date pas d&rsquo;aujourd&rsquo;hui et nous signale que tout cela se passe exactement deux ans apr\u00e8s l&rsquo;affaire des sous-marins australiens : command\u00e9s \u00e0 la France, puis commande annul\u00e9e pour acheter des sous-marins US et former l&rsquo;association AUKUS, &ndash;  Australie, U K, USA.<\/p>\n<\/p>\n<p><p>Korybko parle de trahison\u00a0\u00bb. On pourrait aussi avancer \u00a0\u00bb coup de poignard dans le dos\u00a0\u00bb, ou bien exercice coutumier de \u00ab\u00a0sodomie habillement consentie\u00a0\u00bb. Apr\u00e8s tout, l&rsquo;op\u00e9rations AUKUS s&rsquo;\u00e9tant d\u00e9roul\u00e9e dans les m\u00eames conditions de simulacre de copinage que celles du Niger : le serviteur a trop cru au comptant les clins d&rsquo;yeux complices de son ma&icirc;tre.<\/p>\n<\/p>\n<p><p>Macron peut donc \u00eatre satisfait : la France est un alli\u00e9 exemplaire des USA. Sa servilit\u00e9 parvient \u00e0 lui faire accomplir l&rsquo;exploit de montrer encore plus de stupidit\u00e9 que les USA. Pour le reste, si Korybko craint que les USA parviennent \u00e0 freiner l&rsquo;influence sino-russe, nous le rassurons en en doutant grandement. La stupidit\u00e9 des USA, qui est d&rsquo;une autre facture que celle de la France, compense largement leur d\u00e9loyaut\u00e9, leur trahison cynique et leur hypocrisie. Les USA sont assez infect\u00e9s de leurs <a href=\"https:\/\/www.dedefensa.org\/article\/ineluctabilite-catastrophique-dukrisis\">inculpabilt\u00e9\/ind\u00e9fectibilit\u00e9<\/a> pour nous faire pr\u00e9voir pr\u00e9voir que leur intrusion dans ces pays d&rsquo;Afrique sera essentiellement contre-productive ; nous parlons de ces deux \u00e9tranges &laquo; <em>\u00ab\u00a0technologies psychologiques\u00a0\u00bb<\/em> &raquo; telles que nous les d\u00e9finissons :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; &#8230;<em>comme une cuirasse infranchissable de toute perception acceptable de la r\u00e9alit\u00e9 du monde (autre d\u00e9finition de la folie) par deux ph\u00e9nom\u00e8nes, sortes de \u00ab\u00a0technologies psychologiques\u00a0\u00bb absolument imp\u00e9n\u00e9trables<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Enfin, voici donc une \u00ab\u00a0aventure bien fran\u00e7aise\u00a0\u00bb <a href=\"https:\/\/korybko.substack.com\/p\/heres-why-the-us-is-responsible-for\">racont\u00e9e par Korybko<\/a>, &ndash; laquelle aventure s&rsquo;av\u00e8re \u00eatre, &ndash; honneur au h\u00e9ros, &ndash; une \u00ab\u00a0aventure bien macronienne\u00a0\u00bb. Il est difficile de retrouver son chemin de critique tant celle-ci est sollicit\u00e9e dans cet univers de fange mac-croniste encombr\u00e9 d&rsquo;amas divers de pens\u00e9es r\u00e9duites au n\u00e9ant et pourtant divis\u00e9es en autant de d\u00e9bris de simulacre que possible. Chez nous, en notre temps, du n\u00e9ant surgit l&rsquo;\u00eatre si bien \u00e0 son image.<\/p>\n<\/p>\n<p><p>(Le titre est de la r\u00e9daction incorrecte de &lsquo;<em>dedefensa.org<\/em>&lsquo;. Korybko avait titr\u00e9, plus sagement on en convient : &laquo; <em>Voici pourquoi les USA sont responsables du retrait de la France du Niger<\/em> &raquo;.)<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Vir\u00e9 du Niger par Biden !<\/h2>\n<\/p>\n<p><p>Les &Eacute;tats-Unis ont trahi la France en Afrique de l&rsquo;Ouest apr\u00e8s avoir conclu un accord secret au Niger, presque deux ans jour pour jour, apr\u00e8s avoir trahi ce m\u00eame pays en Asie-Pacifique apr\u00e8s avoir conclu un accord secret avec l&rsquo;Australie et le Royaume-Uni pour cr\u00e9er l&rsquo;AUKUS.<\/p>\n<\/p>\n<p><p>La France a d\u00e9clar\u00e9 qu&rsquo;elle ne laisserait pas la junte nig\u00e9rienne l&rsquo;expulser du pays il y a un peu moins de deux mois d\u00e9but ao&ucirc;t, pour ensuite d\u00e9clarer fin septembre que ses 1 500 soldats partiraient d&rsquo;ici la fin de l&rsquo;ann\u00e9e. Paris s&rsquo;\u00e9tait jusqu&rsquo;ici accroch\u00e9 aux revendications de l\u00e9gitimit\u00e9 du leader d\u00e9chu Mohamed Bazoum et a refus\u00e9 de partir \u00e0 moins qu&rsquo;il ne le demande. L&rsquo;ancien colonisateur de son pays a \u00e9galement d\u00e9clar\u00e9 qu&rsquo;il soutiendrait une invasion de la CEDEAO visant \u00e0 le ramener au pouvoir si ce bloc d\u00e9cidait d&rsquo;en lancer une.<\/p>\n<\/p>\n<p><p>Ce renversement retentissant repr\u00e9sente donc une d\u00e9faite strat\u00e9gique humiliante pour la France et prouve l&rsquo;\u00e9chec complet de sa politique n\u00e9ocoloniale en Afrique. S&rsquo;il s&rsquo;\u00e9tait retir\u00e9 plus t\u00f4t, selon ses propres conditions et sous quelque pr\u00e9texte que ce soit, apr\u00e8s le coup d&rsquo;&Eacute;tat militaire patriotique de cet \u00e9t\u00e9 et avant la demande pr\u00e9visible de la junte, il aurait pu encore tenter de remodeler partiellement les perceptions en sa faveur. Au lieu de cela, la d\u00e9cision a \u00e9t\u00e9 prise de rester au Niger, probablement parce que la France pensait que la CEDEAO allait l&rsquo;envahir.<\/p>\n<\/p>\n<p><p>Apr\u00e8s tout, si les d\u00e9cideurs politiques \u00e0 Paris ne s&rsquo;attendaient pas vraiment \u00e0 de nouveaux changements politiques et n&rsquo;\u00e9taient pas dispos\u00e9s \u00e0 ramener Bazoum au pouvoir par eux-m\u00eames, alors cela n&rsquo;aurait aucun sens de rester dans ce pays plus longtemps. Ce faisant, ils ont envoy\u00e9 le signal qu&rsquo;il existait un plan selon lequel la junte annulerait cette demande ou serait remplac\u00e9e, peut-\u00eatre m\u00eame ne serait-ce que par une faction militaire pro-fran\u00e7aise lors d&rsquo;un autre coup d&rsquo;&Eacute;tat. Rien de tout cela ne s&rsquo;est concr\u00e9tis\u00e9, pas plus que l&rsquo;invasion de la CEDEAO, ce qui sugg\u00e8re que quelque chose s&rsquo;est mal pass\u00e9.<\/p>\n<\/p>\n<p><p>C&rsquo;est ici qu&rsquo;il convient de rappeler ce que le commandant en chef de l&rsquo;US Air Force pour l&rsquo;Europe et l&rsquo;Afrique a r\u00e9v\u00e9l\u00e9 mi-septembre la reprise des missions de renseignement et de surveillance de son pays au Niger. Selon ce responsable, cela est le r\u00e9sultat de n\u00e9gociations avec la junte, dont l&rsquo;issue fait suite au voyage de la secr\u00e9taire d&rsquo;&Eacute;tat adjointe Victoria Nuland \u00e0 Niamey d\u00e9but ao&ucirc;t, peu apr\u00e8s que les autorit\u00e9s militaires int\u00e9rimaires ont exig\u00e9 le retrait des forces fran\u00e7aises.<\/p>\n<\/p>\n<p><p>Cette analyse explique ici comment cette \u00e9volution a mis la France en retrait strat\u00e9gique puisqu&rsquo;elle a montr\u00e9 que l&rsquo;Am\u00e9rique profitait de la fr\u00e9n\u00e9sie de revers r\u00e9gionaux de son partenaire nominal de l&rsquo;OTAN. En s&rsquo;adaptant avec souplesse aux tendances multipolaires qui ont balay\u00e9 le Sahel, Washington a pu remplacer le r\u00f4le s\u00e9curitaire traditionnel de Paris au Niger. Cela a eu pour effet d&rsquo;int\u00e9grer deux bases am\u00e9ricaines dans l&rsquo;Alliance sah\u00e9lienne fond\u00e9e quelques jours plus tard entre ce pays, le Burkina Faso et le Mali.<\/p>\n<\/p>\n<p><p>La contrepartie sp\u00e9culative semble avoir \u00e9t\u00e9 que les &Eacute;tats-Unis d\u00e9joueraient l&rsquo;invasion envisag\u00e9e par la France dans la CEDEAO si la junte la laissait conserver ces installations militaires. Pour parler franchement, les &Eacute;tats-Unis ont poignard\u00e9 dans le dos la France en Afrique de l&rsquo;Ouest apr\u00e8s avoir conclu un accord secret au Niger presque deux ans jour pour jour apr\u00e8s avoir poignard\u00e9 dans le dos ce m\u00eame pays en Asie-Pacifique apr\u00e8s avoir conclu un accord secret avec l&rsquo;Australie et le Royaume-Uni pour cr\u00e9er AUKUS. Seul un accord secret am\u00e9ricano-nig\u00e9rien explique de mani\u00e8re convaincante pourquoi la France a attendu jusqu&rsquo;\u00e0 pr\u00e9sent pour se retirer.<\/p>\n<\/p>\n<p><p>Jusqu&rsquo;alors, la France esp\u00e9rait encore que les &Eacute;tats-Unis ordonneraient \u00e0 la CEDEAO d&rsquo;envahir le Niger et ainsi de sauver leurs deux bases l\u00e0-bas, ce que ses d\u00e9cideurs politiques pensaient in\u00e9vitablement se produire puisqu&rsquo;ils pensaient que les &Eacute;tats-Unis avaient peur de l&rsquo;influence russe et des attaques terroristes qui y d\u00e9ferlaient. Ce qu&rsquo;ils n&rsquo;avaient pas pr\u00e9vu, c&rsquo;est que les &Eacute;tats-Unis concluraient un accord dans leur dos pour remplacer le r\u00f4le traditionnel de s\u00e9curit\u00e9 de leur pays dans le cadre de son adaptation flexible aux tendances multipolaires de la r\u00e9gion.<\/p>\n<\/p>\n<p><p>Du point de vue des &Eacute;tats-Unis, il s&rsquo;agissait du meilleur sc\u00e9nario compte tenu des circonstances dans lesquelles se sont retrouv\u00e9s leurs d\u00e9cideurs politiques apr\u00e8s le coup d&rsquo;&Eacute;tat. Une invasion de la CEDEAO risquait de d\u00e9clencher une guerre plus large qui aurait pu cr\u00e9er davantage d&rsquo;opportunit\u00e9s pour l&rsquo;expansion de l&rsquo;influence russe parall\u00e8lement \u00e0 la d\u00e9stabilisation de l&rsquo;Europe si elle avait conduit \u00e0 une autre crise de r\u00e9fugi\u00e9s sur le mod\u00e8le de celle de 2015. Ils ont alors compris qu&rsquo;il valait mieux remplacer la France au Niger et ainsi contr\u00f4ler les tendances multipolaires.<\/p>\n<\/p>\n<p><p>Cette solution rentable a \u00e9videmment \u00e9t\u00e9 un choc pour la France et a entra&icirc;n\u00e9 l&rsquo;une des d\u00e9faites strat\u00e9giques les plus humiliantes de son histoire, mais les &Eacute;tats-Unis ont calcul\u00e9 que les dommages collat\u00e9raux ne condamneraient pas leurs relations puisque le scandale AUKUS a montr\u00e9 que la France continuerait \u00e0 ramper. De plus, le remplacement de la France dans sa &laquo; sph\u00e8re d&rsquo;influence &raquo; africaine permet aux &Eacute;tats-Unis de g\u00e9rer les cons\u00e9quences du d\u00e9part forc\u00e9 de leur &laquo; partenaire &raquo; et de renforcer la d\u00e9pendance de Paris \u00e0 l&rsquo;\u00e9gard de Washington.<\/p>\n<\/p>\n<p><p>En termes pratiques, les &Eacute;tats-Unis peuvent combler de mani\u00e8re proactive une partie du vide laiss\u00e9 par le retrait apparemment in\u00e9vitable de la France d&rsquo;Afrique au lieu de tout c\u00e9der volontairement \u00e0 l&rsquo;Entente sino-russe, tout en faisant en sorte que les ressources dont d\u00e9pend Paris passent par les r\u00e9seaux d&rsquo;influence am\u00e9ricains au lieu de leurs propres r\u00e9seaux. propre. Les seuls compromis que les &Eacute;tats-Unis doivent faire sont d&rsquo;accepter une certaine expansion de l&rsquo;influence sino-russe (puisqu&rsquo;ils ne peuvent pas l&#8217;emp\u00eacher totalement) et l&rsquo;optique soi-disant peu recommandable d&rsquo;un partenariat avec une junte.<\/p>\n<\/p>\n<p><p>Concernant le deuxi\u00e8me aspect mentionn\u00e9, des op\u00e9rations de gestion de la perception sont d\u00e9j\u00e0 en cours pour att\u00e9nuer les d\u00e9g\u00e2ts du soft power dans le pays. Le dernier article d&rsquo;Andreas Kluth pour Bloomberg d\u00e9clarait de fa\u00e7on dramatique que &laquo; si les &Eacute;tats-Unis quittent le Niger, les terroristes et les Russes gagneront &raquo; et affirmait qu&rsquo;il valait mieux y rester malgr\u00e9 la junte plut\u00f4t que de se retirer pour protester en faveur de la &laquo; d\u00e9mocratie &raquo;. Il a expliqu\u00e9 \u00e0 son public occidental cible qu&rsquo;il s&rsquo;agissait l\u00e0 d&rsquo;un soi-disant moindre mal compte tenu des pr\u00e9tendues alternatives.<\/p>\n<\/p>\n<p><p>Ce qui est nouveau dans ce r\u00e9cit, c&rsquo;est la franchise avec laquelle Kluth parle des int\u00e9r\u00eats am\u00e9ricains au Niger, qui, selon lui et dit ouvertement, n\u00e9cessitent des compromis comme ceux mentionn\u00e9s ci-dessus. Bien qu&rsquo;il se livre \u00e9galement \u00e0 des propos alarmistes \u00e0 propos de la Russie et des terroristes, tout comme ses pairs l&rsquo;ont fait tout au long de l&rsquo;\u00e9t\u00e9, la solution qu&rsquo;il propose ne consiste pas \u00e0 soutenir une invasion potentiellement tr\u00e8s co&ucirc;teuse de la CEDEAO, mais \u00e0 conclure de mani\u00e8re pragmatique des accords avec la junte. L&rsquo;article de Kluth est \u00e0 la fois rafra&icirc;chissant et inqui\u00e9tant car il montre avec quelle flexibilit\u00e9 les &Eacute;tats-Unis s&rsquo;adaptent aux tendances multipolaires.<\/p>\n<\/p>\n<p><p>D&rsquo;une part, il n&rsquo;est pas fr\u00e9quent que quelqu&rsquo;un parle aussi franchement au public occidental des int\u00e9r\u00eats am\u00e9ricains dans les pays du Sud, c&rsquo;est pourquoi c&rsquo;est rafra&icirc;chissant puisque la plupart des gestionnaires de perception pr\u00e9f\u00e8rent obscurcir et mentir sur ce sujet. Cela dit, c&rsquo;est \u00e9galement inqui\u00e9tant en raison de l&rsquo;efficacit\u00e9 objective de cette approche pour faire avancer les int\u00e9r\u00eats des &Eacute;tats-Unis, ce qui pose un d\u00e9fi bien plus important pour l&rsquo;Entente sino-russe que celui dont ils devaient s&rsquo;arranger auparavant.<\/p>\n<\/p>\n<p><p>Pour en revenir au renversement stup\u00e9fiant de la France, sa d\u00e9cision de se retirer finalement du Niger, alors qu&rsquo;elle avait d\u00e9clar\u00e9 il y a seulement deux mois qu&rsquo;elle y resterait au m\u00e9pris de la junte, \u00e9tait sans doute le r\u00e9sultat du fait que les &Eacute;tats-Unis avaient conclu un accord avec leurs autorit\u00e9s militaires int\u00e9rimaires et avaient donc pratiquement forc\u00e9 la France \u00e0 s&rsquo;en aller. Si la France soup\u00e7onnait que cela pourrait se produire, elle aurait pu partir selon ses propres conditions au d\u00e9but de l&rsquo;\u00e9t\u00e9, c&rsquo;est pourquoi cette \u00e9volution doit \u00eatre consid\u00e9r\u00e9e comme la deuxi\u00e8me trahison am\u00e9ricaine envers la France apr\u00e8s AUKUS.<\/p>\n<\/p>\n<p><h4>Andrew Korybko<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Belle comp\u00e9tition entre stupidit\u00e9 et servilit\u00e9 &bull; Macron est l&rsquo;incontestable m\u00e9daille d&rsquo;or pour les deux. &bull; Constat retir\u00e9 de la lecture de l&rsquo;analyse d&rsquo;Andrew Korybko sur l&rsquo;\u00e9viction de la France du Niger, par les USA. &bull; Deux ans apr\u00e8s l&rsquo;affaire AUKUS\/Australie. ________________________ Macron est certainement le &lsquo;plus-parfait&rsquo; des parfaits pr\u00e9sidents de notre temps. Nous l&rsquo;avons&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[4503,4255,2662,2747,2687,3090,2952,4802,22177,3068],"class_list":["post-80771","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-afrique","tag-defaite","tag-en","tag-francaise","tag-france","tag-influence","tag-korybko","tag-niger","tag-sino-russe","tag-strategique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80771"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80771\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}