{"id":80786,"date":"2023-10-15T13:44:00","date_gmt":"2023-10-15T13:44:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/10\/15\/un-chaos-hypersonique\/"},"modified":"2023-10-15T13:44:00","modified_gmt":"2023-10-15T13:44:00","slug":"un-chaos-hypersonique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/10\/15\/un-chaos-hypersonique\/","title":{"rendered":"Un chaos hypersonique"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Un chaos hypersonique<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Une vision hypersonique de la crise Hamas-Isra\u00ebl, o&ugrave; chacun, entre Isra\u00ebl, l&rsquo;Europe et les USA, en prend pour ce qu&rsquo;il vaut dans son action (hypersonique) dans cette crise. &bull; Avec un texte de Rachel Marsden.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Finalement, on a assez peu mis en \u00e9vidence ce qui a domin\u00e9 les r\u00e9actions de l&rsquo;Ouest-compulsif dans son entier, autour de la nouvelle guerre Hamas-Isra\u00ebl&#8230; Que ce soit l&rsquo;UE, bien s&ucirc;r et avant tout, mais aussi diverses situations, jusqu&rsquo;\u00e0 l&rsquo;hyst\u00e9rie des <em>neocon<\/em> qui tiennent l&rsquo;Iran en joue tandis qu&rsquo;Isra\u00ebl ne cesse de menacer tout en \u00e9voluant prudemment et en constatant le d\u00e9sordre de ses forces de r\u00e9serve et de son organisation (voyez <a href=\"https:\/\/sonar21.com\/is-israel-unprepared-to-fight-hamas\/\">Larry Johnson<\/a>). Finalement, un observateur de Sirius, un extra-terrestre si l&rsquo;on veut, finirait par conclure que la sp\u00e9cialit\u00e9 de la d\u00e9cadence-perversion de notre-civilisation est le d\u00e9sordre multipli\u00e9 par le chaos multipli\u00e9 par le d\u00e9sordre&#8230; Et ainsi de suite.<\/p>\n<\/p>\n<p><p>La chroniqueuse canadienne anglophone et excellente francophone Rachel Marsden (voir son site &lsquo;<em><a href=\"http:\/\/www.rachelmarsden.com\/\">rachelmarsden.com<\/a><\/em>&lsquo;) s&rsquo;est empar\u00e9e du sujet. Il faut la lire, elle qui a \u00e9t\u00e9 priv\u00e9e de sa chronique sur RT fran\u00e7ais gr\u00e2ce aux bons soins empress\u00e9s de l&rsquo;\u00e9quipe-censure de l&rsquo;UE, &ndash; von der Leyen, Breton &#038; Cie. Elle s&rsquo;est d\u00e9j\u00e0 empar\u00e9e du sujet Isra\u00ebl-Hamas en abordant le fond du probl\u00e8me, aussi r\u00e9cemment que <a href=\"https:\/\/www.msn.com\/en-us\/news\/opinion\/rachel-marsden-israel-palestine-and-the-elephant-in-the-room-that-no-one-s-talking-about\/ar-AA1hZAW8\">le 10 octobre 2023<\/a> o&ugrave; elle faisait une comparaison, avec le tr\u00e8s-grandiose double standard occidental \u00e0 l&rsquo;appui, de la diff\u00e9rence de traitement de deux crises qu&rsquo;elle juge tr\u00e8s proches, &ndash; entre Ukraine et Palestine.<\/p>\n<\/p>\n<p><p>Son article que nous donnons aujourd&rsquo;hui est donc plut\u00f4t celui de notre d\u00e9sordre et de nos incoh\u00e9rence, sur RT.com <a href=\"https:\/\/www.rt.com\/news\/584663-israel-warmongering-us-brussels\/\">le 11 octobre<\/a>. \u00ab\u00a0Hypersonique\u00a0\u00bb est un qualificatif qui sied si parfaitement au collectif des h\u00f4pitaux bruxellois o&ugrave; logent l&rsquo;UE et ses camps de travail&#8230; On embarque sur la nef des fous !<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_____________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Vertus hypersoniques de l&rsquo;UE pour Isra\u00ebl<\/h2>\n<\/p>\n<p><p> &laquo; Isra\u00ebl a le droit de se d\u00e9fendre &ndash; aujourd&rsquo;hui et dans les jours \u00e0 venir. L&rsquo;Union europ\u00e9enne est aux c\u00f4t\u00e9s d&rsquo;Isra\u00ebl &raquo;, a tweet\u00e9 dimanche dernier la pr\u00e9sidente de la Commission europ\u00e9enne, Ursula von der Leyen. Ce faisant, elle a effectivement donn\u00e9 carte blanche aux dirigeants isra\u00e9liens, notoirement mesur\u00e9s et retenus, en r\u00e9ponse aux attaques du Hamas.<\/p>\n<\/p>\n<p><p>&laquo; Qui pensez vous \u00eatre? Vous n&rsquo;\u00eates pas \u00e9lu et n&rsquo;avez aucune autorit\u00e9 pour d\u00e9terminer la politique \u00e9trang\u00e8re de l&rsquo;UE, qui est d\u00e9finie par le Conseil &raquo;, a r\u00e9pondu l&rsquo;eurod\u00e9put\u00e9e irlandaise Clare Daly. &laquo; L&rsquo;Europe n&rsquo;est PAS aux c\u00f4t\u00e9s d&rsquo;Isra\u00ebl. Nous d\u00e9fendons la paix. Vous ne parlez pas pour nous. Si vous n&rsquo;avez rien de constructif \u00e0 dire, et ce n&rsquo;est clairement pas le cas, alors fermez-l\u00e0. &raquo;<\/p>\n<\/p>\n<p><p>Dans un seul tweet, von der Leyen a r\u00e9ussi \u00e0 positionner toute l&rsquo;Europe comme plus militante que m\u00eame la r\u00e9daction de l&rsquo;un des principaux journaux nationaux isra\u00e9liens, Haaretz, qui a carr\u00e9ment imput\u00e9 la responsabilit\u00e9 des attaques au Premier ministre isra\u00e9lien Benjamin Netanyahu, l&rsquo;accusant d&rsquo;&laquo; annexion et de d\u00e9possession &raquo; qui &laquo; ignoraient ouvertement l&rsquo;existence et les droits des Palestiniens &raquo;. L&rsquo;implication est qu&rsquo;aucune action ne se produit dans le vide sans risque de d\u00e9clencher une r\u00e9action.<\/p>\n<\/p>\n<p><p>Le danger que la reine Ursule d&rsquo;Europe, non \u00e9lue, lance unilat\u00e9ralement des missiles hypersoniques de signalisation de vertu dans une r\u00e9ponse \u00e9motionnelle instinctive est qu&rsquo;elle ne peut en aucun cas se substituer \u00e0 la politique \u00e9trang\u00e8re d\u00e9cid\u00e9e dans des moments plus r\u00e9fl\u00e9chis. Pourtant, de nos jours, c&rsquo;est le plus souvent le seul type de politique \u00e9trang\u00e8re que nous obtenons, sur tout, d&rsquo;Isra\u00ebl \u00e0 l&rsquo;Ukraine.<\/p>\n<\/p>\n<p><p>Dans un autre exemple de symbolisme qui devance le pragmatisme politique, l&rsquo;UE a annonc\u00e9 le retrait de son soutien \u00e0 la Palestine&hellip; avant de revenir sur cette d\u00e9cision quelques heures plus tard. Lundi, le ministre isra\u00e9lien de la D\u00e9fense a annonc\u00e9 que Tsahal allait bloquer Gaza encore plus que d&rsquo;habitude en emp\u00eachant toute entr\u00e9e d&rsquo;eau, de nourriture, de carburant et d&rsquo;\u00e9lectricit\u00e9. Et quelques heures plus tard, le commissaire europ\u00e9en au voisinage et \u00e0 l&rsquo;\u00e9largissement, Oliver Varhelyi, a d\u00e9clar\u00e9 que le bloc se joignait \u00e0 la cause &ndash; en suspendant son financement humanitaire en faveur du peuple palestinien. L&rsquo;Allemagne et l&rsquo;Autriche ont \u00e9t\u00e9 les premi\u00e8res \u00e0 lancer le processus de retrait des financements. Cependant, quelques heures plus tard, le gel de l&rsquo;aide de l&rsquo;UE a \u00e9t\u00e9 annul\u00e9 par le chef de la politique \u00e9trang\u00e8re du bloc, Josep Borrell, apr\u00e8s une sorte de r\u00e9v\u00e9lation selon laquelle cela ne ferait que &laquo; punir tout le peuple palestinien &raquo; et n&rsquo;aurait &laquo; fait qu&rsquo;enhardir davantage les terroristes &raquo;. Il est impossible que Bruxelles ait financ\u00e9 ces terroristes par inadvertance, n&rsquo;est-ce pas ?<\/p>\n<\/p>\n<p><p>Bruxelles a accord\u00e9 2,5 milliards de dollars d&rsquo;aide budg\u00e9taire directe \u00e0 l&rsquo;Autorit\u00e9 palestinienne sur 12 ans \u00e0 partir de 2008, et a r\u00e9cemment annonc\u00e9 qu&rsquo;elle enverrait quelque 1,24 milliard de dollars de 2021 \u00e0 2024. Le financement n&rsquo;a m\u00eame pas \u00e9t\u00e9 r\u00e9duit ou interrompu &ndash; seulement pendant quelques mois. en 2021-2022, puis lib\u00e9r\u00e9 sans conditions pr\u00e9alables &ndash; lorsque les organismes de surveillance ont all\u00e9gu\u00e9 que les manuels scolaires palestiniens contenaient un contenu antis\u00e9mite promouvant et glorifiant le terrorisme. Et maintenant, le minist\u00e8re isra\u00e9lien des Affaires \u00e9trang\u00e8res pointe Bruxelles du doigt. &laquo; L&rsquo;Union europ\u00e9enne finan\u00e7ait des manuels scolaires des autorit\u00e9s palestiniennes qui \u00e9taient remplis d&rsquo;antis\u00e9mitisme et d&rsquo;incitation \u00e0 la violence et au terrorisme contre les Juifs &raquo;, a d\u00e9clar\u00e9 plus t\u00f4t cette semaine le porte-parole du minist\u00e8re isra\u00e9lien des Affaires \u00e9trang\u00e8res, Lior Haiat.<\/p>\n<\/p>\n<p><p>Lorsque la question a \u00e9t\u00e9 soulev\u00e9e pour la premi\u00e8re fois, le commissaire europ\u00e9en en charge de l&rsquo;\u00e9poque a rencontr\u00e9 le ministre isra\u00e9lien des Affaires \u00e9trang\u00e8res \u00e0 Bruxelles et lui a dit en gros : &laquo; &Eacute;coutez, nous veillerons simplement \u00e0 ce que cela ne se reproduise plus &raquo; &ndash; et a adopt\u00e9 une r\u00e9solution \u00e0 cet effet. Des rapports d&rsquo;ONG ont \u00e9galement \u00e9t\u00e9 publi\u00e9s plus t\u00f4t ce mois-ci, accusant Bruxelles de financer des subventions qui ont fini entre les mains du Front populaire de lib\u00e9ration de la Palestine, que l&rsquo;UE consid\u00e8re comme un groupe terroriste.<\/p>\n<\/p>\n<p><p>C&rsquo;est juste plus t\u00f4t cette ann\u00e9e, en f\u00e9vrier, que l&rsquo;UE a annonc\u00e9 un montant suppl\u00e9mentaire de plus de 300 millions de dollars pour le peuple palestinien en pr\u00e9sence du pr\u00e9sident Mahmoud Abbas &ndash; un financement pour les salaires, les retraites, les soins de sant\u00e9 et des choses comme &laquo; une entreprise agricole intelligente face au climat, &raquo; et &laquo; comp\u00e9titivit\u00e9 verte &raquo;. Et maintenant, tout \u00e0 coup, les responsables bruxellois semblent se demander : \u00ab\u00a0H\u00e9, attendez, avons-nous financ\u00e9 le Hamas\u00a0\u00bb&hellip; peut-\u00eatre ? Parce que c&rsquo;est ce que semblent sugg\u00e9rer leurs actions. Sinon, quel est le probl\u00e8me de continuer \u00e0 aider le peuple palestinien ?<\/p>\n<\/p>\n<p><p>Ou peut-\u00eatre qu&rsquo;au vu de tous les discours soucieux du climat attach\u00e9s \u00e0 l&rsquo;aide, l&rsquo;UE s&rsquo;est simplement mise en col\u00e8re contre le fait que les deltaplanes du Hamas soient motoris\u00e9s. Vous savez simplement qu&rsquo;un idiot \u00e0 Bruxelles regarde la couverture m\u00e9diatique de toutes les camionnettes \u00e9nergivores utilis\u00e9es par le Hamas pour attaquer les villages et kidnapper les gens et se demande : &laquo; Quelle est l&#8217;empreinte carbone de celles-ci ? &raquo;<\/p>\n<\/p>\n<p><p>Tous les signaux de vertu du monde ne peuvent d\u00e9sormais pas compenser le manque de diligence raisonnable que sugg\u00e8rent le retrait schizophr\u00e9nique et le r\u00e9tablissement ult\u00e9rieur du financement palestinien. Ce ne serait pas la premi\u00e8re fois que des innocents souffriraient de l&rsquo;incomp\u00e9tence de Bruxelles. Il suffit de demander aux peuples de l&rsquo;ensemble du bloc europ\u00e9en qui sont actuellement confront\u00e9s \u00e0 des probl\u00e8mes apparemment sans fin.<\/p>\n<\/p>\n<p><p>Et tout comme en Ukraine, Bruxelles ne semble pas vraiment int\u00e9ress\u00e9e \u00e0 profiter d&rsquo;une opportunit\u00e9 pour jouer un quelconque r\u00f4le d&rsquo;att\u00e9nuation ou de r\u00e9flexion dans ce conflit, mais prend plut\u00f4t sa place habituelle pour servir de fusil de chasse aux n\u00e9oconservateurs am\u00e9ricains, quelle que soit l&rsquo;issue du conflit. ce qui se passe actuellement.<\/p>\n<\/p>\n<p><p>M\u00eame si le secr\u00e9taire d&rsquo;&Eacute;tat Antony Blinken affirme qu&rsquo;il n&rsquo;y a pas de &laquo; preuve irr\u00e9futable &raquo; liant l&rsquo;Iran aux derni\u00e8res attaques du Hamas, cela n&rsquo;a pas non plus emp\u00each\u00e9 les bellicistes n\u00e9oconservateurs habituels du c\u00f4t\u00e9 am\u00e9ricain de l&rsquo;alliance transatlantique de substituer les slogans \u00e0 la politique r\u00e9elle &ndash; en en faveur d&rsquo;un changement de r\u00e9gime iranien, bien s&ucirc;r. &laquo; Il s&rsquo;agit de l&rsquo;un des meilleurs exemples de changement de r\u00e9gime \u00e0 faire de l&rsquo;histoire &raquo;, a d\u00e9clar\u00e9 l&rsquo;ancien conseiller am\u00e9ricain \u00e0 la s\u00e9curit\u00e9 nationale, John Bolton. Parce que, lorsqu&rsquo;il s&rsquo;agit de susciter un changement de r\u00e9gime iranien, les n\u00e9oconservateurs sont soudainement pr\u00eats \u00e0 croire sur parole le Hamas comme \u00e9tant leur source fiable sur l&rsquo;implication de l&rsquo;Iran. &laquo; L&rsquo;administration Biden devrait avoir un peu de courage et rejeter la faute sur T\u00e9h\u00e9ran, l\u00e0 o&ugrave; tout d\u00e9marre &raquo;, a ajout\u00e9 plus tard Bolton. Cela &laquo; d\u00e9marre &raquo;, au diable les faits et la politique, car cela correspond au r\u00e9cit n\u00e9oconservateur radical, m\u00eame si cela finit par se faire au d\u00e9triment des vies et des int\u00e9r\u00eats am\u00e9ricains.<\/p>\n<\/p>\n<p><p>&laquo; Il est grand temps que l&rsquo;&Eacute;tat terroriste iranien paie le prix de tous les bouleversements et de toutes les destructions sem\u00e9s dans la r\u00e9gion et dans le monde &raquo;, a d\u00e9clar\u00e9 le s\u00e9nateur Lindsey Graham (R-SC). D&rsquo;une mani\u00e8re ou d&rsquo;une autre, ces bellicistes ne parviennent jamais \u00e0 remarquer le r\u00f4le de parrainage interventionniste jou\u00e9 depuis longtemps par Washington et l&rsquo;Occident, qui a sans doute emp\u00each\u00e9 tous ces voisins du Moyen-Orient de trouver une solution entre eux.<\/p>\n<\/p>\n<p><p>Une rh\u00e9torique fracassante dans le feu de la crise est peu co&ucirc;teuse pour les g\u00e9n\u00e9raux occidentaux en fauteuil, mais potentiellement co&ucirc;teuse pour d&rsquo;innombrables autres. Ils parlent fort sans se soucier des r\u00e9percussions, dans l&rsquo;int\u00e9r\u00eat d&rsquo;apaiser leurs alli\u00e9s et leurs partisans. Et c&rsquo;est dans ces moments d\u00e9sesp\u00e9r\u00e9s, o&ugrave; la raison risque de passer au second plan face \u00e0 l&rsquo;\u00e9motion, qu&rsquo;ils ont les meilleures chances d&rsquo;imposer leur programme potentiellement catastrophique.<\/p>\n<\/p>\n<p><h4>Rachel Marsden<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un chaos hypersonique &bull; Une vision hypersonique de la crise Hamas-Isra\u00ebl, o&ugrave; chacun, entre Isra\u00ebl, l&rsquo;Europe et les USA, en prend pour ce qu&rsquo;il vaut dans son action (hypersonique) dans cette crise. &bull; Avec un texte de Rachel Marsden. Finalement, on a assez peu mis en \u00e9vidence ce qui a domin\u00e9 les r\u00e9actions de l&rsquo;Ouest-compulsif&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[8022,5111,2774,14550,3049,6157,3048,2609,2658],"class_list":["post-80786","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-der","tag-hamas","tag-israel","tag-layen","tag-marsden","tag-paix","tag-rachel","tag-ue","tag-von"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80786"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80786\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}