{"id":80795,"date":"2023-10-21T15:23:34","date_gmt":"2023-10-21T15:23:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/10\/21\/droite-gauche-desordre-de-la-grandecrise\/"},"modified":"2023-10-21T15:23:34","modified_gmt":"2023-10-21T15:23:34","slug":"droite-gauche-desordre-de-la-grandecrise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/10\/21\/droite-gauche-desordre-de-la-grandecrise\/","title":{"rendered":"Droite\u00a0! Gauche\u00a0! D\u00e9sordre de la GrandeCrise"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Droite ! Gauche ! D\u00e9sordre de la GrandeCrise<\/h2>\n<\/p>\n<p><p>21 octobre 2023 (15H30) &ndash; Le temps des \u00ab\u00a0camps\u00a0\u00bb politiques est bien d\u00e9pass\u00e9, &ndash; droite, gauche, toutes ces choses-l\u00e0 ne se reconnaissent plus dans la valse des miroirs d\u00e9formants de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>. Tout juste reste-t-il le \u00ab\u00a0Camp du Bien\u00a0\u00bb, cette impossible invention des esprits en jach\u00e8re et des \u00e2mes en dess\u00e8chement se roulant dans la b\u00eatise et la l\u00e2chet\u00e9 comme d&rsquo;autres invitent Charybde et Scylla \u00e0 leur table, &ndash; \u00e0 fuir absolument, par cons\u00e9quent.<\/p>\n<\/p>\n<p><p>L&rsquo;affaire \u00e9tait d\u00e9j\u00e0 chaude, br&ucirc;lante avec l&rsquo;Ukraine. Les autorit\u00e9s ill\u00e9gitimes tent\u00e8rent tant bien que mal, par la terreur notamment, et la censure pour les plus vertueuses, d&rsquo;imposer l&rsquo;id\u00e9e de l&rsquo;horreur du camp \u00ab\u00a0d&rsquo;en face\u00a0\u00bb. Avec Hamas-Isra\u00ebl, la digue a c\u00e9d\u00e9. Il n&rsquo;est plus possible de dissimuler les violentes, diverses et infiniment complexes contradictions, contre-pieds et contredits dans tous les camps. Droite, gauche, antiracisme, identit\u00e9, libert\u00e9 et ordre, plus rien ne marche, plus aucun mot de passe ne fonctionne.<\/p>\n<\/p>\n<p><p>Certes, dira-t-on, il suffit d&rsquo;admettre une fois pour toutes cette \u00e9vidence de l&rsquo;inacceptabilit\u00e9 du terrorisme ; certes, r\u00e9pondra-t-on, mais que fera-t-on de la Terreur-1793, des insurg\u00e9s espagnols tirant dans le dos des troupes de Napol\u00e9on, des Communards qui fusillaient et des Versaillaient qui ex\u00e9cutaient, des r\u00e9sistants autour de Jean Moulin et des partisans russes et ukrainiens attaquant par surprise les collabos des nazis, du FLN lib\u00e9rateur et de l&rsquo;OAS luttant pour l&rsquo;Alg\u00e9rie Fran\u00e7aise ? Que fera-t-on de tous les peuples opprim\u00e9s et contraints par la force si on leur refuse des moyens s\u00e9ditieux de s&rsquo;affirmer ? Toutes ces questions sans r\u00e9ponses, rassembl\u00e9es aujourd&rsquo;hui, forment le cimier improbable o&ugrave; se d\u00e9chirent les droites et les gauches.<\/p>\n<\/p>\n<p><p>Curieux, cela : il y a quarante ans, lors des attaques de l&rsquo;OLP, les regroupements s&rsquo;op\u00e9raient sans trop de difficult\u00e9s et sur ces questions embarrassantes, on tranchait, &ndash; et <em>basta<\/em> ! Aujourd&rsquo;hui, cette man&oelig;uvre \u00ab\u00a0de contrepied et de contredit\u00a0\u00bb raval\u00e9s en \u00ab\u00a0mordant sur sa chique\u00a0\u00bb est devenue impossible parce que chaque question se d\u00e9taille aussit\u00f4t en autant de r\u00e9f\u00e9rences oppos\u00e9es que toutes les crises prolifiques et contradictoires vous d\u00e9roulent avec insolence et insistance, et se range aussi vite sous une banni\u00e8re g\u00e9n\u00e9rale de principes (antiSyst\u00e8me, l\u00e9gitimit\u00e9, identit\u00e9, multipolarit\u00e9) qui interf\u00e8rent souvent et sans la moindre vergogne dans ce qui aurait d&ucirc; \u00eatre votre choix naturel. Ces <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situations<\/a> sont la cons\u00e9quence si complexes des ruines que sont devenues nos diverses id\u00e9es civilisatrices formant notre ancienne civilisation, r\u00e9pandues sous les coups de boutoir de la <a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">d\u00e9constructuration<\/a>, &ndash; qui, vous le voyez, n&rsquo;est pas si mauvaise puisqu&rsquo;elle force \u00e0 cet an\u00e9antissement de la pourriture que nous n&rsquo;osions r\u00e9aliser. Cela, &ndash; encore un signe absolument irr\u00e9fragable que nous sommes d\u00e9sormais entr\u00e9s dans les masses terrifiantes des for\u00eats aquatiques et coulantes autant que glissantes de la Mer des Sargasses que forme cette <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>.<\/p>\n<\/p>\n<p><p>La chose, cette prolif\u00e9ration des parcellisation des engagements si assur\u00e9s hier, se trouve assez bien affirm\u00e9e en France, o&ugrave; l&rsquo;on trouve des situations de contradictions internes extravagantes. Elle l&rsquo;est bien plus encore aux &Eacute;tats-Unis, avec toutes les antennes qu&rsquo;on sait dans le reste du monde, et dans la situation de crise et de morcellement hyst\u00e9rique du pays. <a href=\"https:\/\/korybko.substack.com\/p\/fierce-divisions-within-the-left\">Korybko<\/a> nous emm\u00e8ne faire une petite balade, un peu comme l&rsquo;on va au zoo, pour nous montrer ce que sont les m\u00e9andres devenus des peuples confront\u00e9s \u00e0 la n\u00e9cessit\u00e9 de l&rsquo;impossible choix au milieu du champ de ruines d&rsquo;une civilisation qui continue \u00e0 jouer la m\u00eame pi\u00e8ce, \u00e0 guichets ferm\u00e9s et sous le regard vide des spectateurs contraints depuis mille saisons, sous les bouches \u00e0 feu des d\u00e9fenseurs de l&rsquo;ordre dont eux-m\u00eames ne savent plus comment le d\u00e9finir ni son identit\u00e9.<\/p>\n<\/p>\n<p><p>Croyez bien \u00e0 l&rsquo;utilit\u00e9 et \u00e0 la vertu de l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">inconnaissance<\/a>.<\/p>\n<\/p>\n<p><h4>PhG &ndash; <em>Semper Phi<\/em>  <\/h4>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">F\u00e9roces divisions \u00e0 propos de Hamas-Isra\u00ebl<\/h2>\n<\/p>\n<p><p>La transition syst\u00e9mique mondiale a largement rendu la dichotomie traditionnelle gauche-droite hors de propos, chaque camp traditionnel comptant parmi ses partisans \u00e0 la fois l&rsquo;ordre unipolaire occidental et l&rsquo;ordre multipolaire \u00e9mergent men\u00e9 par la mont\u00e9e du Sud ces derni\u00e8res ann\u00e9es. N\u00e9anmoins, cela reste un cadre de r\u00e9f\u00e9rence pratique pour beaucoup puisqu&rsquo;il existe encore des diff\u00e9rences importantes entre la plupart de leurs membres sur les questions socioculturelles et \u00e9conomiques, d&rsquo;o&ugrave; la raison pour laquelle il est utilis\u00e9 dans cet article.<\/p>\n<\/p>\n<p><p>De f\u00e9roces divisions ont \u00e9clat\u00e9 au sein de chaque camp \u00e0 propos d&rsquo;Isra\u00ebl et du Hamas, comme le soulignent ces rapports :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>* \u00ab\u00a0<em><a href=\"https:\/\/substack.com\/redirect\/4be6365a-d9dd-422b-8b40-0e476972c440?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">Israel Violence Underscores the G.O.P. Divide on Foreign Policy<\/a><\/em>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>* \u00ab\u00a0<em><a href=\"https:\/\/substack.com\/redirect\/4da68f87-7e10-42f5-8a2a-3d61bf664fbb?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">The generational rift that explains Democrats&rsquo; angst over Israel<\/a><\/em>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>* \u00ab\u00a0<em><a href=\"https:\/\/substack.com\/redirect\/eac1e072-7f4f-42d8-871a-7726ee0ab4c0?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">The left faces a reckoning as Israel divides Democrats<\/a><\/em>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>* \u00ab\u00a0<em><a href=\"https:\/\/substack.com\/redirect\/db3f3076-c8f7-4622-ab30-86ca5be59a11?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">MAGA Divides Grow as Israel War Intensifies<\/a><\/em>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>* \u00ab\u00a0<a href=\"https:\/\/substack.com\/redirect\/0f4d0d6c-d842-459e-bdb6-9ac472ca4efb?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\"><em>MAGA Influencers Tearing Each Other Apart Over Israel-Hamas War<\/em><\/a>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>* \u00ab\u00a0<em><a href=\"https:\/\/substack.com\/redirect\/5915ad39-8fd1-4e01-ae59-441b6fa1d527?j=eyJ1IjoiYjlscDcifQ.pVyX_knIBhpqL_N_0ZcwZa0sFcIWYyh_9O1MMvRH1wc\">On Israel, Progressive Jews Feel Abandoned by Their Left-Wing Allies<\/a><\/em>\u00ab\u00a0<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est sans doute le r\u00e9sultat de factions concurrentes qui se disputent le contr\u00f4le de chaque camp, comme nous l&rsquo;expliquerons.<\/p>\n<\/p>\n<p><p>La g\u00e9opolitique et les principes sont au c&oelig;ur de ces nouvelles divisions intestines. En ce qui concerne ce qui peut \u00eatre d\u00e9crit au sens large, mais bien s&ucirc;r imparfaitement, comme la gauche, il existe traditionnellement une volont\u00e9 de lutter contre l&rsquo;h\u00e9g\u00e9monie en faveur des opprim\u00e9s, d&rsquo;o&ugrave; le soutien historique de ce camp \u00e0 la Palestine qui se refl\u00e8te \u00e9galement dans une large mesure \u00e0 travers ses repr\u00e9sentants de l&rsquo;establishment dans les deux pays. l&rsquo;Occident et le Sud global. Toutefois, au sein de ses branches occidentales, des diff\u00e9rends ont surgi sur les tactiques employ\u00e9es \u00e0 cette fin.<\/p>\n<\/p>\n<p><p>Certains membres am\u00e9ricains et europ\u00e9ens, notamment juifs, rejettent le recours au terrorisme par les Palestiniens. Ils consid\u00e8rent que cela va \u00e0 l&rsquo;encontre de leurs principes et croient fermement qu&rsquo;il faut s&rsquo;appuyer uniquement sur des moyens politiques et \u00e9conomiques, qui prennent respectivement la forme de fortes d\u00e9nonciations et du mouvement BDS, pour punir Isra\u00ebl et promouvoir la Palestine. Ces membres sont naturellement constern\u00e9s par le refus de leurs alli\u00e9s Antifa et BLM de condamner l&rsquo;attaque terroriste du Hamas d\u00e9but octobre.<\/p>\n<\/p>\n<p><p>Le soutien tacite de ces deux-l\u00e0 \u00e0 de telles tactiques n&rsquo;est pas surprenant puisqu&rsquo;ils les ont utilis\u00e9es dans une mesure beaucoup moins meurtri\u00e8re lors de la guerre de terreur hybride contre l&rsquo;Am\u00e9rique de l&rsquo;\u00e9t\u00e9 2020, encourag\u00e9e par l&rsquo;\u00e9lite &laquo; r\u00e9veill\u00e9e &raquo; apr\u00e8s la mort de George Floyd dans le cadre du pouvoir national de leur secte. jouer. Parce que cette attaque n&rsquo;a pas \u00e9t\u00e9 aussi meurtri\u00e8re que l&rsquo;attaque terroriste du Hamas, peu de gens ont r\u00e9alis\u00e9 qu&rsquo;Antifa et BLM sont faits d&rsquo;une m\u00eame \u00e9toffe, y compris bon nombre de ces m\u00eames sectaires &laquo; r\u00e9veill\u00e9s &raquo; qui sont maintenant constern\u00e9s par eux mais qui ont soutenu leurs troubles \u00e0 l&rsquo;\u00e9poque.<\/p>\n<\/p>\n<p><p>Aux yeux de ces gens, les Palestiniens sont toujours des combattants de la libert\u00e9 opprim\u00e9s et oppos\u00e9s \u00e0 l&rsquo;h\u00e9g\u00e9monie, et c&rsquo;est pourquoi leur cause reste juste. Mais dans le m\u00eame temps, les civils massacr\u00e9s par le Hamas au nom de cette cause sont \u00e9galement des victimes. Les rivaux de l&rsquo;establishment de cette faction ont cependant un avis diff\u00e9rent et insistent sur le fait que tous les Juifs d&rsquo;origine europ\u00e9enne en Isra\u00ebl sont des colonisateurs qui m\u00e9ritent ce qui leur est arriv\u00e9, ce qui a conduit \u00e0 un foss\u00e9 irr\u00e9parable entre ces deux factions sur les principes.<\/p>\n<\/p>\n<p><p>Des divisions similaires sont \u00e9galement perceptibles au sein de ce qui peut \u00eatre d\u00e9crit de mani\u00e8re large mais bien s&ucirc;r imparfaite comme la droite, qui a traditionnellement soutenu l&rsquo;unipolarit\u00e9 occidentale et s&rsquo;est donc montr\u00e9e solidaire d&rsquo;Isra\u00ebl. De nombreux membres consid\u00e8rent \u00e9galement que l&rsquo;&Eacute;tat juif est beaucoup plus similaire sur le plan civilisationnel \u00e0 celui des Palestiniens \u00e0 majorit\u00e9 musulmane, et ils appr\u00e9cient le r\u00f4le de ce pays en tant que &laquo; porte-avions insubmersible &raquo; de leur bloc en Asie occidentale riche en \u00e9nergie, ce qui perp\u00e9tue l&rsquo;h\u00e9g\u00e9monie occidentale.<\/p>\n<\/p>\n<p><p>Certains au sein de la faction de droite MAGA, qui porte des noms diff\u00e9rents selon les pays mais partage la priorit\u00e9 accord\u00e9e par ses membres aux int\u00e9r\u00eats conservateurs et nationalistes, remettent en question cette vision du monde. Ils croient que la multipolarit\u00e9 est in\u00e9vitable et que leurs gouvernements ne devraient pas gaspiller des vies pr\u00e9cieuses et des tr\u00e9sors en vain pour maintenir un ordre unipolaire en d\u00e9clin. C&rsquo;est pour cette raison que ces gens sont oppos\u00e9s \u00e0 l&rsquo;aide militaire et \u00e9conomique occidentale \u00e0 Isra\u00ebl, m\u00eame si cela ne signifie pas qu&rsquo;ils sympathisent tous avec le Hamas.<\/p>\n<\/p>\n<p><p>Certains le font v\u00e9ritablement, tout comme d&rsquo;autres membres de MAGA, comme la figure de proue am\u00e9ricaine du mouvement Donald Trump, sympathisent avec Isra\u00ebl, mais le sous-groupe dit &laquo; r\u00e9volutionnaire &raquo; au sein de cette faction consid\u00e8re le Hamas comme l&rsquo;un des nombreux chefs de l&rsquo;hydre &laquo; r\u00e9veill\u00e9e &raquo; aux c\u00f4t\u00e9s d&rsquo;Antifa, BLM. , DSA, etc. Ce point de vue est devenu populaire apr\u00e8s que des images du chef du Hamas Yahya Sinwar faisant l&rsquo;\u00e9loge de George Floyd en juin 2021 ont recommenc\u00e9 \u00e0 circuler, car de nombreux MAGA pensent que sa mort a \u00e9t\u00e9 exploit\u00e9e par les &laquo; r\u00e9veill\u00e9s &raquo; pour prendre le contr\u00f4le de l&rsquo;Am\u00e9rique.<\/p>\n<\/p>\n<p><p>Leurs principes conservateurs-nationalistes les emp\u00eachent naturellement de jamais soutenir le Hamas, surtout apr\u00e8s que le groupe a justifi\u00e9 ses actes de terreur sous des pr\u00e9textes de &laquo; d\u00e9colonisation &raquo; identiques \u00e0 la rh\u00e9torique pouss\u00e9e par BLM, ce qui fait craindre \u00e0 ces gens d&rsquo;\u00eatre ensuite pris pour cible. Ces inqui\u00e9tudes ont conduit \u00e0 un foss\u00e9 irr\u00e9parable entre eux et les MAGA qui sympathisent avec le Hamas, sans parler entre ces deux-l\u00e0 et l&rsquo;autre sous-groupe MAGA ainsi qu&rsquo;avec la droite \u00e9tablie qui sont tous deux aux c\u00f4t\u00e9s d&rsquo;Isra\u00ebl.<\/p>\n<\/p>\n<p><p>Toutes ces informations conduisent \u00e0 des observations intrigantes. Les \u00e9tablissements am\u00e9ricains de ces camps soutiennent Isra\u00ebl, \u00e0 l&rsquo;exception de la &laquo; Squad &raquo; des D\u00e9mocrates, qui est hyper-&laquo; r\u00e9veill\u00e9e &raquo; et soutient donc le Hamas, y compris son recours \u00e0 des tactiques terroristes (m\u00eame si certains ont tent\u00e9 de dissiper cette perception sous la pression). Cependant, l&rsquo;establishment de gauche de l&rsquo;UE et du Sud soutient le Hamas, tandis que l&rsquo;establishment de droite multipolaire du Sud, repr\u00e9sent\u00e9 par Poutine et Modi, est neutre, comme le prouve ici.<\/p>\n<\/p>\n<p><p>Certains membres de la faction multipolaire de MAGA partagent la position \u00e9quilibr\u00e9e de ces deux partis, tout comme certains (mais surtout pas tous) des gauchistes non &laquo; r\u00e9veill\u00e9s &raquo; dans les pays du Sud, tandis que d&rsquo;autres gauchistes non &laquo; r\u00e9veill\u00e9s &raquo; et des MAGA multipolaires soutiennent le Hamas (y compris son recours au terrorisme). tactique). En revanche, la faction unipolaire du MAGA, repr\u00e9sent\u00e9e par Trump, soutient Isra\u00ebl, ce qui le place du m\u00eame c\u00f4t\u00e9 que l&rsquo;establishment am\u00e9ricain des deux camps. Comme on peut le constater, la transition syst\u00e9mique mondiale a en effet rendu la dichotomie gauche-droite de moins en moins pertinente.<\/p>\n<\/p>\n<p><h4>Andrew Korybko, le <a href=\"https:\/\/korybko.substack.com\/p\/fierce-divisions-within-the-left\">21 octobre 2023<\/a><\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Droite ! Gauche ! D\u00e9sordre de la GrandeCrise 21 octobre 2023 (15H30) &ndash; Le temps des \u00ab\u00a0camps\u00a0\u00bb politiques est bien d\u00e9pass\u00e9, &ndash; droite, gauche, toutes ces choses-l\u00e0 ne se reconnaissent plus dans la valse des miroirs d\u00e9formants de la GrandeCrise. Tout juste reste-t-il le \u00ab\u00a0Camp du Bien\u00a0\u00bb, cette impossible invention des esprits en jach\u00e8re et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[12498,13688,3955,2774,2952],"class_list":["post-80795","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-andrew","tag-deconstructuration","tag-gaza","tag-israel","tag-korybko"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80795"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80795\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}