{"id":80817,"date":"2023-11-09T18:36:40","date_gmt":"2023-11-09T18:36:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/11\/09\/gaza-et-limplosion-des-elites-us\/"},"modified":"2023-11-09T18:36:40","modified_gmt":"2023-11-09T18:36:40","slug":"gaza-et-limplosion-des-elites-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/11\/09\/gaza-et-limplosion-des-elites-us\/","title":{"rendered":"Gaza et l&rsquo;implosion des \u00e9lites US"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Gaza et l&rsquo;implosion des \u00e9lites US<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Des \u00e9v\u00e8nements int\u00e9rieurs <strong>symboliques mais d&rsquo;une extr\u00eame puissance<\/strong> sont en train de <strong>bouleverser la situation int\u00e9rieure des &Eacute;tats-Unis<\/strong>. &bull; Il y a ainsi la r\u00e9apparition du r\u00e9publicain Varek Rawaswamy <strong>plein d&rsquo;id\u00e9es violemment isolationniste<\/strong>s et une prise de position de <strong>la communaut\u00e9 des \u00ab\u00a0artistes\u00a0\u00bb de Hollywood<\/strong>. &bull; Dans les deux cas qui sont deux camps absolument oppos\u00e9s mais tr\u00e8s influents, on arrive \u00e0 la  m\u00eame orientation : condamnation absolue de l&rsquo;action d&rsquo;Isra\u00ebl contre Gaza et, \u00e0 l&rsquo;horizon, <strong>mise en cause de facto de la <\/strong><strong><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a><\/strong>.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Brutalement, comme un incendie devenue incontr\u00f4lable, le domaine des \u00e9lites aux USA s&rsquo;enflamme pour \u00ab\u00a0la guerre de Gaza\u00a0\u00bb, essentiellement contre la strat\u00e9gie militaire isra\u00e9lienne  de plus en plus vigoureusement d\u00e9nonc\u00e9e comme \u00ab\u00a0g\u00e9nocidaire\u00a0\u00bb. Dans ce <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">tourbillon crisique<\/a><em> Made in USA <\/em>et au c&oelig;ur m\u00eame des \u00e9lites US, on n&rsquo;a pas le moindre souvenir (depuis le Vietnam) d&rsquo;une telle temp\u00eate de communication conduisant \u00e0 des reclassements inimaginables politiquement et socialement. C&rsquo;est sans aucun doute un ph\u00e9nom\u00e8ne temporaire, &ndash; celui des reclassements, &ndash; mais en attendant il a lieu avec une telle force qu&rsquo;il peut conduire \u00e0 des prolongements qu&rsquo;on ne peut pr\u00e9voir.<\/p>\n<\/p>\n<p><p>Il y a \u00e9norm\u00e9ment de domaines touch\u00e9s mais on s&rsquo;arr\u00eatera \u00e0 deux d&rsquo;entre eux, extr\u00eamement influents, extr\u00eamement prestigieux et disposant de moyens de communication sans \u00e9quivalent. Il s&rsquo;agit du domaines de l&rsquo;<em>entertainment<\/em>, essentiellement Hollywood, et du domaine politique o&ugrave; l&rsquo;intervention d&rsquo;un homme (d&rsquo;un jeune homme de 38 ans) secoue le parti r\u00e9publicain mais aussi indirectement le parti d\u00e9mocrate qui r\u00e9v\u00e8le \u00e0 cette occasion son extr\u00eame fragilit\u00e9 face \u00e0 la probl\u00e9matique arabo-isra\u00e9lienne imposant une tension extraordinaire \u00e0 l&rsquo;id\u00e9ologie progressiste-soci\u00e9tale que tous ces gens ch\u00e9rissent comme autant de missiles hypersoniques anti-Trump. Tout cela a lieu alors que ce qui est le pr\u00e9tendu pouvoir ex\u00e9cutif, la pr\u00e9sidence et l&rsquo;administration en place, navigue en aveugle ivre-mort, compl\u00e8tement en mode \u00ab\u00a0<em>Bateau ivre<\/em>\u00a0\u00bb sur le rythme du \u00ab\u00a0Hollandais Volant\u00a0\u00bb, entre l&rsquo;impuissance g\u00e2teuse de Joe Biden, les imperturbables mensonges du secr\u00e9taire \u00e0 la d\u00e9fense Austin au S\u00e9nat et les incroyables humiliations subies par le secr\u00e9taire d&rsquo;&Eacute;tat Blinken lors de ses diverses visites en Isra\u00ebl et dans les pays arabes.<\/p>\n<\/p>\n<p><p>Voici un commentaire typique sur les zigzags sans espoir de Blinken qui doivent arracher un petit rire sarcastique au v\u00e9n\u00e9rable centenaire Kissinger, en souvenir de ses navettes victorieuses des ann\u00e9es 1970, &ndash; celles des escales Tel Aviv-Le Caire-Damas-Ryad&#8230; Qu&rsquo;importe que Larry Johnson \u00e9crive cela <a href=\"https:\/\/sonar21.com\/what-is-happening-to-israels-offensive-in-gaza-and-blinkens-diplomacy\/\">le 4 novembre<\/a>, c&rsquo;est tous les jours la m\u00eame chose sauf que c&rsquo;est pire que la veille.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pendant ce temps, le secr\u00e9taire d&rsquo;&Eacute;tat am\u00e9ricain Blinken s&rsquo;est rendu \u00e0 Amman pour rencontrer certains des principaux dirigeants arabes et s&rsquo;assurer de leur soutien au plan am\u00e9ricain de cr\u00e9ation d&rsquo;un &Eacute;tat palestinien mythique. Pourquoi dis-je &quot;mythique&quot; ? Je ne crois pas que l&rsquo;administration Biden soit s\u00e9rieuse dans sa proposition. Personne ne fait confiance \u00e0 Biden ou \u00e0 son \u00e9quipe de s\u00e9curit\u00e9 nationale inepte. Netanyahou a dit \u00e0 Tony d&rsquo;aller se faire voir. Cette rebuffade a \u00e9t\u00e9 suivie par le bon vieux bras raide arabe que Blinken a re\u00e7u en Jordanie. Contrairement \u00e0 Netanyahou, qui a refus\u00e9 d&rsquo;appara&icirc;tre avec Blinken apr\u00e8s leur rencontre, les Arabes ont pris plaisir \u00e0 passer Blinken \u00e0 la moulinette devant la presse mondiale. Il n&rsquo;y a pas assez de Viagra dans le monde pour que Blinken ait l&rsquo;air puissant ou redoutable<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Blinken est en train de devenir le <a href=\"https:\/\/en.wikipedia.org\/wiki\/Rodney_Dangerfield\">Rodney Dangerfield<\/a><\/em> [comique d\u00e9c\u00e9d\u00e9, sp\u00e9cialiste des monologues &laquo; <em>Personne ne me respecte<\/em> &raquo;] <em>de l&rsquo;administration Biden (sauf qu&rsquo;il n&rsquo;y a rien de dr\u00f4le chez lui ou dans ses prescriptions politiques), &ndash; nulle part la moindre marque de respect. Il est malmen\u00e9 comme un volant de badminton dans un ouragan<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Encore ne parle-t-on pas des remous int\u00e9rieurs au d\u00e9partement d&rsquo;&Eacute;tat et \u00e0 la Maison-Blanche o&ugrave; de s\u00e9rieuses indications de r\u00e9voltes int\u00e9rieures commencent non seulement \u00e0 circuler mais <a href=\"https:\/\/www.zerohedge.com\/political\/white-house-aides-simply-cannot-stomach-bidens-israel-policy-dissent-memos-leak-revolt\">\u00e0 \u00eatre publi\u00e9es<\/a> avec des d\u00e9clarations \u00e0 l&rsquo;appui. C&rsquo;est l&rsquo;int\u00e9rieur m\u00eame de l&rsquo;\u00e9difice de la s\u00e9curit\u00e9 nationale, &ndash; ce fameux <em>DeepState<\/em>, vous savez ? &ndash;  qui tremble d\u00e9sormais, affaiblissant du coup et la position, et la politique si et quand il y en a une, des &Eacute;tats-Unis dans la crise de Gaza.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">RapSit-USA2023 : L&rsquo;offensive-\u00e9clair de Vivek<\/h3>\n<\/p>\n<p><p>Restons dans la politiquer et passons de ses structures \u00e0 sa dynamique \u00e9lectorale qui sugg\u00e8re les changements qui se pr\u00e9parent&#8230; Hier soir, \u00e0 Miami, le candidat r\u00e9publicain d&rsquo;origine indienne Vivek Ramaswamy a fait l&rsquo;essentiel du spectacle offensif avec des interventions tonitruantes contre le vieux GOP (&lsquo;<em>Great Old Party<\/em>&lsquo;), compl\u00e8tement acquis \u00e0 l&rsquo;<em>establishment<\/em>, aux<em>  neocon<\/em>, \u00e0 Wall Street, \u00e0 la pens\u00e9e-Syst\u00e8me et aux r\u00e9flexes qui vont avec. Il a re\u00e7u un accueil triomphal de la salle, tant son intervention \u00e9tait absolument calcul\u00e9e, &ndash; dans le sens du destin arrangeant les dynamiques pour les rendre tr\u00e8s efficaces, &ndash; pour s&rsquo;ins\u00e9rer dans le <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">tourbillon crisique<\/a> actuel des USA.<\/p>\n<\/p>\n<p><p>Ce qu&rsquo;on retient surtout, c&rsquo;est une plaidoirie vibrante pour le non-interventionnisme, l&rsquo;abandon des guerres h\u00e9g\u00e9moniques inutiles et co&ucirc;teuses, dans ce cas le soutien \u00e0 Isra\u00ebl dans les conditions qu&rsquo;on sait bien entendu, &ndash; tout cela va avec. A un aper\u00e7u de la soir\u00e9e, on ajoutera cette intervention personnelle du <a href=\"https:\/\/www.youtube.com\/watch?v=ZrX1m9ooTB0\">8 novembre 2023<\/a>, ainsi pr\u00e9sent\u00e9e sur &lsquo;<em>Yutube<\/em>&lsquo;, donc selon ses propres conceptions :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Vivek Ramaswamy, candidat r\u00e9publicain d&rsquo;origine indienne \u00e0 l&rsquo;\u00e9lection pr\u00e9sidentielle, devrait d\u00e9fendre une politique \u00e9trang\u00e8re non interventionniste lors du troisi\u00e8me d\u00e9bat des primaires du parti r\u00e9publicain \u00e0 Miami, mercredi soir. S&rsquo;adressant \u00e0 l&rsquo;agence de presse Reuters, Vivek Ramaswamy a d\u00e9clar\u00e9 qu&rsquo;il cherchait \u00e0 se positionner comme le candidat le moins susceptible de s&rsquo;engager dans une guerre \u00e9trang\u00e8re. Mardi, M. Ramaswamy a publi\u00e9 un engagement intitul\u00e9 \u00ab\u00a0Non aux neocon\u00a0\u00bb, que chaque personne nomm\u00e9e dans son administration devrait signer. Cet engagement repose sur trois principes : \u00ab\u00a0&Eacute;viter la troisi\u00e8me guerre mondiale est un objectif national vital ; la guerre n&rsquo;est jamais une pr\u00e9f\u00e9rence, seulement une n\u00e9cessit\u00e9 ; et le seul devoir des d\u00e9cideurs politiques am\u00e9ricains est envers les citoyens am\u00e9ricains\u00a0\u00bb<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Vous avez donc une petite id\u00e9e du candidat et de sa &lsquo;feuille de route&rsquo;. Le probl\u00e8me n&rsquo;est pas de trouver la r\u00e9ponse aux faits de savoir si Ramaswamy est franc, s&rsquo;il a une chance d&rsquo;\u00eatre d\u00e9sign\u00e9, d&rsquo;appliquer sa politique, s&rsquo;il est un g\u00e9nie strat\u00e9gique et un miracle de la m\u00e9taHistoire, s&rsquo;il est vendu, achet\u00e9, sold\u00e9, s&rsquo;il a bu et s&rsquo;il se drogue,&ndash; et ainsi, ainsi de suite, &ndash; toutes ces questions pratiques qui enchantent le lecteur friand de savoir ce que demain va encore nous ass\u00e9ner. La r\u00e9ponse au probl\u00e8me est que ce candidat qui sait manier le spectacle tombe \u00e0 pic \u00e9videmment, au moment o&ugrave; la question de Gaza explose litt\u00e9ralement, terrifiant et paralysant 99% des politiciens US, &ndash; mais pas lui, parce qu&rsquo;il a 38 ans, une fortune personnelle, un abattage de b\u00eate et une excellente perception du public, &ndash; et peut-\u00eatre, qui sait, une sorte d&rsquo;intuition de vivre au c&oelig;ur de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>.<\/p>\n<\/p>\n<p><p>Gr\u00e2ce \u00e0 lui, le probl\u00e8me, non seulement de Gaza ou \/et de l&rsquo;Ukraine, mais des engagements ext\u00e9rieurs US vient sur la table avec fracas. Ce probl\u00e8me p\u00e8se lourd, tr\u00e8s lourd, des tonnes de quincaillerie, de $milliards et de centaines de milliers de vies humaines liquid\u00e9es. Gr\u00e2ce \u00e0 lui, il s&rsquo;agit bien d&rsquo;une implosion au c&oelig;ur du monde politique US et de la campagne USA-2024 dont on ne pourra plus d\u00e9sormais se d\u00e9p\u00eatrer ; et cela, bien entendu, quel que soit l&rsquo;\u00e9lu, et cela que Vivek soit ou non retenu, ou qu&rsquo;il sombre dans les oubliettes de ses b\u00e9n\u00e9fices somptueux de milliardaires&#8230; On verra ! Pour l&rsquo;instant, il ne nous importe que de voir sur l&rsquo;instant.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">RapSit-USA2023 : Hollywood s&rsquo;en va-t&rsquo;en-paix<\/h3>\n<\/p>\n<p><p>Alors, on se tourne vers Hollywood ; symbole du fric, de \u00ab\u00a0l&rsquo;industrie du cin\u00e9ma\u00a0\u00bb, des &lsquo;<em>blockbusters<\/em>&lsquo;, des acteurs\/actrices \u00e0 $40 millions le r\u00f4le, du f\u00e9minisme &lsquo;<em>MeToo<\/em>&lsquo;, du transgenre changeant de sexe comme de chemises, et surtout d&rsquo;un progressisme-soci\u00e9tal \u00e0 toute \u00e9preuve avec une influence colossale du lobby isra\u00e9lo-sioniste depuis des d\u00e9cennies&#8230;<\/p>\n<\/p>\n<p><p>Eh bien, pour un jour au moins, tout cela s&rsquo;en va en fum\u00e9e, bien dans la mani\u00e8re hollywoodienne, au profit des habitants de Gaza en train d&rsquo;\u00eatre \u00e9cras\u00e9s  par les bombes isra\u00e9liennes, &ndash; pardon, plut\u00f4t, par les bombes am\u00e9ricanistes &lsquo;vendues&rsquo; aux Isra\u00e9liens. &lsquo;<em>WSWS.org<\/em>&lsquo;, qui n&rsquo;est pas particuli\u00e8rement wokeniste ni progressiste-soci\u00e9tal \u00e0 la mode hollywoodienne, d\u00e9glutit n\u00e9anmoins d&rsquo;une <a href=\"https:\/\/www.wsws.org\/en\/articles\/2023\/11\/08\/svwt-n08.html\">discr\u00e8te satisfaction<\/a> en mesurant l&rsquo;impact public et de communication de l&rsquo;initiative qui touche un nombre non n\u00e9gligeable de personnalit\u00e9s du bazar dit &lsquo;<em>show business<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Un groupe d&rsquo;acteurs, d&rsquo;\u00e9crivains et de musiciens de premier plan a sign\u00e9 une lettre ouverte exhortant le pr\u00e9sident Joe Biden et le Congr\u00e8s am\u00e9ricain \u00e0 \u00ab\u00a0appeler \u00e0 une d\u00e9sescalade imm\u00e9diate et \u00e0 un cessez-le-feu \u00e0 Gaza et en Isra\u00ebl avant qu&rsquo;une autre vie ne soit perdue\u00a0\u00bb. Le groupe \u00ab\u00a0<a href=\"https:\/\/www.artists4ceasefire.org\/\" target=\"_blank\">Artists Call for Ceasefire Now<\/a>,\u00a0\u00bb souligne le fait que \u00ab\u00a05 000 personnes ont \u00e9t\u00e9 tu\u00e9es au cours de la derni\u00e8re semaine et demie &ndash; un chiffre que toute personne de conscience sait \u00eatre catastrophique. Nous pensons que toute vie est sacr\u00e9e, quelle que soit la foi ou l&rsquo;origine ethnique et nous condamnons le meurtre de civils palestiniens et isra\u00e9liens.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les signataires comprennent les acteurs Andrew Garfield, Ben Affleck, Mahershala Ali, Mark Rylance, Bradley Cooper, Brian Cox, Cate Blanchett, Ewan McGregor, Florence Pugh, Jeremy Strong, Jessica Chastain, Richard Gere, Sandra Oh et Tom Hardy. Des musiciens et interpr\u00e8tes tels que Jennifer Lopez, Selena Gomez, Ani DiFranco, Boots Riley, Brian Eno, Cat Power, Drake et Michael Stipe ont \u00e9galement ajout\u00e9 leurs noms.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>La liste des signataires comprend \u00e9galement les cin\u00e9astes Adam McKay, Ryan Coogler, James Schamus, Mira Nair, Michael Moore, Peter Berg, Jordan Peele et Alfonso Cuar&oacute;n ; les \u00e9crivains Tony Kushner et Wallace Shawn ; les musiciens-interpr\u00e8tes Patti Smith, Peter Gabriel, Annie Lennox, Macklemore et Mandy Patinkin ; les bandes dessin\u00e9es Jon Stewart, Ramy Youssef, Rosie O&rsquo;Donnell, Mo Amer, Wanda Sykes, Margaret Cho et Judah Friedlander ; et le mannequin Gigi Hadid<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Isolationnistes et globalistes, main dans la main<\/h3>\n<\/p>\n<p><p>Bien, nous laissons de c\u00f4t\u00e9 le texte de la p\u00e9tition, les intentions de ses auteurs, peut-\u00eatre les calculs, des comploteurs et des contre-comploteurs, la durabilit\u00e9 de la chose, son importance r\u00e9elle ou fabriqsu\u00e9e&#8230; Ce qui nous importe est l&rsquo;\u00e9v\u00e9nement brut, c&rsquo;est-\u00e0-dire la chose brutale qui survient sans avertissement, sans complot de pr\u00e9paration ni de multiples articles pr\u00e9monitoires. Or, le choc est si brutal que sa force oblige, non pas \u00e0 un changement de politique qui nous importe peu, &ndash; on ne change pas la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, le saviez-vous ? &ndash;  mais \u00e0 une modification radicale de l&rsquo;\u00e9tat d&rsquo;esprit du public aux USA, du soudain int\u00e9r\u00eat forc\u00e9 du citoyen am\u00e9ricain si indiff\u00e9rent au reste du monde, justement \u00e0 tourner la t\u00eate ver ce \u00ab\u00a0reste du monde\u00a0\u00bb. Et s&rsquo;il le fait, quel sentiment na&icirc;tra alors, par exemple lorsque son regard parcourt <a href=\"https:\/\/www.leparisien.fr\/societe\/video-on-dirait-des-zombies-a-san-francisco-les-drogues-au-fentanyl-ont-investi-le-centre-ville-17-06-2023-H4FQYXJOOZBHBAYHQHEMICY5TY.php\">les rues de San Francisco<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Je crois que vous m\u00e9ritez un leader de ce pays qui place en premier les int\u00e9r\u00eats de ses propres citoyens. Qu&rsquo;est-ce que nous voyons  en Irak ? Un  pays bris\u00e9, 20 ans plus tard, avec un r\u00e9gime hostile et un r\u00e9gime anti-am\u00e9ricain en Afghanistan. $7 000 milliards d\u00e9pens\u00e9s dans ces deux guerres, des dizaines de milliers de morts, vingt ans plus tard les talibans sont toujours au pouvoir. Nous ne voulons pas commettre \u00e0 nouveau les m\u00eames erreurs pour notre pays. C&rsquo;\u00e9tait la vision de George Washington<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est du n\u00e9o-isolationnisme pur, de la part du milliardaire d&rsquo;origine indienne mais citoyen US 100%, Vivek Rawaswamy. Exactement la m\u00eame chose, \u00e0 part que c&rsquo;est exactement le contraire de ce que r\u00e9clament les hyper-vedettes friqu\u00e9es de Hollywood et Malibu, toutes plus globalistes les unes que les autres. Mais que nous importent ces positions pr\u00e9tendument id\u00e9ologiques (on a ses humeurs et ses pens\u00e9es n&rsquo;est-ce pas) et si totalement oppos\u00e9es jusqu&rsquo;\u00e0 la haine inexpugnable, &ndash; sentiment humain g\u00e9n\u00e9ral de Hollywood sur Trump, &ndash; puisque le r\u00e9sultat est le m\u00eame : l&rsquo;horreur soulev\u00e9e \u00e0 Hollywood par les attaques de Gaza conduit aussi in\u00e9vitablement que l&rsquo;argument de Rawaswamy pour s&rsquo;occuper d&rsquo;abord des rues de San Francisco \u00e0 une rupture de l&rsquo;aide et \u00e0 l&rsquo;approvisionnement en armes d&rsquo;Isra\u00ebl, avec la m\u00eame possibilit\u00e9 pour l&rsquo;Ukraine, qui suivra naturellement gr\u00e2ce au z\u00e8le exceptionnel de Mister Z. devenu entretemps virtuose de l&rsquo;h\u00e9ro\u00efsme non-r\u00e9compens\u00e9.<\/p>\n<\/p>\n<p><p>L&rsquo;essentiel qui se joue n&rsquo;a aucun rapport avec les intentions et les man&oelig;uvres des uns et des autres, les ambitions des politiciens ou les vanit\u00e9 d'\u00a0\u00bbartistes\u00a0\u00bb du cin\u00e9ma. Ce qui importe c&rsquo;est la rupture brutale, fondamentale de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, ce succ\u00e9dan\u00e9 diabolique enfant\u00e9 par le <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-politique-systeme\">\u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb<\/a>., ce masque monstrueux du d\u00e9mon dont la modernit\u00e9 s&rsquo;est affubl\u00e9e pour nous faire accroire \u00e0 sa tr\u00e8s haute spiritualit\u00e9.<\/p>\n<\/p>\n<p><p>Une certitude : si le front int\u00e9rieur craque aux USA, si le Syst\u00e8me, avec ses Biden, ses Blinken et autres \u00e9toiles lumineuses ne parvient pas \u00e0 aveugler les fuites gigantesques ouvertes dans le barrage, ce sera le d\u00e9ferlement.<\/p>\n<\/p>\n<p><p>Mon cher Watson, 2024 sera une ann\u00e9e int\u00e9ressante.<\/p>\n<\/p>\n<p><p>Mis en ligne le 9 novembre 2023 \u00e0 18H40<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gaza et l&rsquo;implosion des \u00e9lites US &bull; Des \u00e9v\u00e8nements int\u00e9rieurs symboliques mais d&rsquo;une extr\u00eame puissance sont en train de bouleverser la situation int\u00e9rieure des &Eacute;tats-Unis. &bull; Il y a ainsi la r\u00e9apparition du r\u00e9publicain Varek Rawaswamy plein d&rsquo;id\u00e9es violemment isolationnistes et une prise de position de la communaut\u00e9 des \u00ab\u00a0artistes\u00a0\u00bb de Hollywood. &bull; Dans les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[1235,4151,3889,3888,3371,2774,14220,3856,22145],"class_list":["post-80817","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-biden","tag-blinken","tag-detat","tag-departement","tag-hollywood","tag-israel","tag-rawaswamy","tag-revolte","tag-vivek"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80817"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80817\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}