{"id":80831,"date":"2023-11-21T17:27:41","date_gmt":"2023-11-21T17:27:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/11\/21\/rapsit-usa2023-il-doit-etre-elimine\/"},"modified":"2023-11-21T17:27:41","modified_gmt":"2023-11-21T17:27:41","slug":"rapsit-usa2023-il-doit-etre-elimine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/11\/21\/rapsit-usa2023-il-doit-etre-elimine\/","title":{"rendered":"RapSit-USA2023\u00a0: Il doit \u00eatre \u00e9limin\u00e9\u00a0!"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">RapSit-USA2023 : Il doit \u00eatre \u00e9limin\u00e9 !<\/h2>\n<\/p>\n<p><p>21 novembre 2023 (17H25) &ndash; Interview\u00e9 par Jan Psaki, sur MSNBC, le d\u00e9put\u00e9 d\u00e9mocrate Dan Goldman a eu des mots malheureux sur Trump, &ndash; en fait, un seul mot, mais qui a provoqu\u00e9 un bruit de tonnerre. Aussit\u00f4t repris sur Tweeter-X, la chose s&rsquo;est r\u00e9percut\u00e9e en cascade comme c&rsquo;est la coutume pour une circonstance de cette sorte, exactement taill\u00e9e pour en faire une explosion nucl\u00e9aire sans ach\u00e8vement, parcourant la labyrinthe sans fin du syst\u00e8me de la communication comme l&rsquo;on plonge dans un trou noir.<\/p>\n<\/p>\n<p><p>Ainsi allait la conversation, \u00e9videmment conduite dans un sens extr\u00eamement d\u00e9favorable \u00e0 Trump puisque venue de MSNBC, le r\u00e9seau le plus militant antiTrump aux USA. La conversation en pr\u00e9lude au mot d\u00e9sormais fameux est ainsi d\u00e9crite (sur &lsquo;<em><a href=\"https:\/\/redstate.com\/nick-arama\/2023\/11\/20\/dan-goldman-desperately-trying-to-walk-back-what-many-saw-as-disturbing-threat-to-trump-n2166595#google_vignette\">Red State<\/a><\/em>&lsquo; parmi beaucoup d&rsquo;autres) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nos amis du site &lsquo;Twitchy&rsquo;, <a href=\"https:\/\/twitchy.com\/samj\/2023\/11\/20\/goldman-trump-threat-n2389997\">ont repris<\/a> le commentaire. Goldman \u00e9tait sur MSNBC avec Jen Psaki. Ils parlaient d&rsquo;une interview de l&rsquo;ancien pr\u00e9sident Donald Trump avec Jonathan Karl, de la cha&icirc;ne ABC. Dans cette interview, Trump a d\u00e9clar\u00e9 \u00e0 Karl qu&rsquo;il avait voulu se rendre au Capitole pendant l&rsquo;\u00e9meute du 6 janvier pour essayer d&rsquo;arr\u00eater ce qui se passait. Trump a d\u00e9clar\u00e9 que les services secrets l&rsquo;en avaient dissuad\u00e9. L&rsquo;incrustation de MSNBC en bas de l&rsquo;\u00e9cran interpr\u00e9tait cela de cette fa\u00e7on \u00ab\u00a0New audio : Trump dit qu&rsquo;il voulait se joindre \u00e0 la foule<\/em> [de l'\u00a0\u00bb\u00e9meute\u00a0\u00bb] <em>du 6 janvier\u00a0\u00bb, ce qui ne correspond pas \u00e0 ce que Trump disait<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais cela n&rsquo;est pas l&rsquo;essentiel, comme l&rsquo;on s&rsquo;en doute ; on a l&rsquo;habitude des simulacres et des <em>narrative<\/em>-billeves\u00e9es qui vont avec. Il faut en venir au mot fameux (que nous mettons en gras), et pour le moins malheureux du d\u00e9put\u00e9 Goldman. Nous y sommes, selon la pr\u00e9sentation de &lsquo;<em>Red State<\/em>&lsquo;, site pro-r\u00e9publicain mais tr\u00e8s moyennement pro-Trump et souvent du c\u00f4t\u00e9 des dinosaures RINO du parti, &ndash; donc, une source qui ne dramatise certainement pas \u00e0 l&rsquo;avantage de Trump, &ndash; mais qui l\u00e0, pour le coup, en est rest\u00e9 interdit et le souffle coup\u00e9.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ensuite, Goldman a essay\u00e9 de pr\u00e9senter Trump comme une menace.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Sa rh\u00e9torique devient vraiment dangereuse&#8230; Il est incontestable \u00e0 ce stade que cet homme ne peut plus exercer de fonctions publiques. Il n&rsquo;est pas seulement inapte. Il est destructeur pour notre d\u00e9mocratie. Il doit \u00eatre, il doit \u00eatre <strong>\u00e9limin\u00e9<\/strong>.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il parle d&rsquo;incitation de la part de Trump, &ndash;  comment justifier une telle interpr\u00e9tation ! De nombreuses personnes sur X ont, \u00e0 juste titre, qualifi\u00e9 cette d\u00e9claration de menace. M\u00eame si beaucoup ne regardent pas l&rsquo;\u00e9mission de Psaki, la vid\u00e9o de ce passage a diffus\u00e9 la remarque en postant le clip sur X. Alors qui sait ce que les fous peuvent penser apr\u00e8s avoir vu et entendu ce genre de d\u00e9claration ? <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cela montre \u00e9galement \u00e0 quel point les d\u00e9mocrates sont inquiets \u00e0 l&rsquo;id\u00e9e qu&rsquo;ils puissent perdre, &ndash; que Trump puisse gagner. Ils doivent donc faire tout ce qu&rsquo;ils peuvent pour pr\u00e9senter l&rsquo;angle du &quot;danger pour la d\u00e9mocratie\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le lendemain (hier soir pour nous), Goldman a essay\u00e9 de revenir sur ce qu&rsquo;il avait dit apr\u00e8s avoir mesur\u00e9 l&rsquo;ampleur extraordinaire que l&rsquo;usage du mot \u00ab\u00a0\u00e9limin\u00e9\u00a0\u00bb, &ndash; un mot qui laisse fort peu de place \u00e0 l&rsquo;ambigu\u00eft\u00e9, surtout dans l&rsquo;actuel contexte, &ndash; avait suscit\u00e9 du fait de sa diffusion maximale sur Tweeter-X. <a href=\"https:\/\/twitter.com\/danielsgoldman\/status\/1726595276289581288?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1726595276289581288%7Ctwgr%5E2520f8ea531962ea5cb003232722dbc52d850796%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Fredstate.com%2Fnick-arama%2F2023%2F11%2F20%2Fdan-goldman-desperately-trying-to-walk-back-what-many-saw-as-disturbing-threat-to-trump-n2166595\">Piteuses explications<\/a>, mais comment faire autrement devant ce qui est, \u00e0 notre sens, au moins un lapsus \u00e9videmment r\u00e9v\u00e9lateur.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Hier, \u00e0 la t\u00e9l\u00e9vision, j&rsquo;ai utilis\u00e9 par erreur le mauvais mot pour exprimer l&rsquo;importance pour l&rsquo;Am\u00e9rique que Donald Trump ne redevienne pas pr\u00e9sident.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>M\u00eame s&rsquo;il doit \u00eatre vaincu, je ne lui souhaite certainement aucun mal et je ne tol\u00e8re pas la violence politique.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Je m&rsquo;excuse pour le mauvais choix des mots<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On pourrait \u00e9videmment traiter cet incident comme un fait isol\u00e9, un lapsus \u00ab\u00a0au pire\u00a0\u00bb, &ndash; mais c&rsquo;est malheureusement, comme \u00e9crit plus haut, comme \u00ab\u00a0un lapsus au mieux\u00a0\u00bb qu&rsquo;il faut le consid\u00e9rer. Les gens, la majorit\u00e9 du public le percevra ainsi, et m\u00eame le per\u00e7oit \u00e9videmment ainsi car le mal est fait et rien n&rsquo;y pourra rien changer. L&rsquo;id\u00e9e d&rsquo;un \u00ab\u00a0fou\u00a0\u00bb qui pourrait \u00eatre incit\u00e9 \u00e0 agir apr\u00e8s avoir entendu ce mot, comme \u00e9voqu\u00e9 par &lsquo;<em>Red State<\/em>&lsquo;, ce serait la r\u00e9action \u00e0 craindre la moins surprenante et la plus significative, mais cette \u00e9vidence n&rsquo;a aucune importance car elle n&rsquo;a aucune chance d&rsquo;\u00eatre retenue. M\u00eame s&rsquo;il s&rsquo;agit bien d&rsquo;un \u00ab\u00a0fou\u00a0\u00bb, un tireur isol\u00e9, un mauvais plaisantin et un type bourr\u00e9 de complexes antifascistes et de vertus populistes, &ndash; un nouveau Lee Harvey Oswald dira-t-on sur le ton d&rsquo;un humour sinistre, &ndash; cette explication n&rsquo;a aucune chance d&rsquo;\u00eatre accept\u00e9e avant m\u00eame qu&rsquo;une telle chose soit commise car la m\u00e9fiance, l&rsquo;hostilit\u00e9 la haine r\u00e8gnent aujourd&rsquo;hui dans la soci\u00e9t\u00e9 et dans les rapports de cette soci\u00e9t\u00e9 avec toutes les  formes hi\u00e9rarchiques d&rsquo;autorit\u00e9 pour mieux pouvoir distinguer des complots dans tous les sens.<\/p>\n<\/p>\n<p><p>Le plus extraordinaire de l&rsquo;\u00e9volution de la situation aux USA est ceci :  Dieu sait, Lui qui sait tant de choses, si Trump n&rsquo;est pas un personnage de trag\u00e9die mais on est en train de le transmuter en un personnage de trag\u00e9die. Bien, je le reconnais, &ndash; <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> dira-t-on, mais \u00ab\u00a0trag\u00e9die\u00a0\u00bb tout de m\u00eame dans des temps qui sont propices \u00e0 de subits changement de rythme et d&rsquo;orientation, o&ugrave; une situation-bouffe peut devenir une trag\u00e9die en l&rsquo;espace de l&rsquo;instant d&rsquo;un \u00e9clair ; et vous savez bien, \u00ab\u00a0trag\u00e9die\u00a0\u00bb dans le sens des Anciens, des Grecs immortels, dans le sens du Nietzsche de &lsquo;<em>La naissance de la trag\u00e9die<\/em>&lsquo;, ce sens-l\u00e0 qui nous transporte dans les origines immuables de l&rsquo;impossible naissance du monde puisque l&rsquo;\u00e9ternit\u00e9 projette notre destin dans les deux non-sens au-del\u00e0 des horizons.<\/p>\n<\/p>\n<p><p>Il nous semble, il me semble \u00e0 moi que ce personnage, Donald Trump, est du genre qui est capable de cr\u00e9er chez ses cohortes innombrables d&rsquo;ennemis des bouff\u00e9es terribles de rage impuissante, des \u00e9branlements sismiques de haines inou\u00efes et inutiles. De m\u00eame suscite-t-il chez ses partisans des attitudes et des sentiments semblables, \u00e0 part qu&rsquo;ils sont tout juste oppos\u00e9es \u00e0 cent quatre-vingts degr\u00e9s des pr\u00e9c\u00e9dents. A ce moment, comme vous le comprenez, comme cela est d\u00e9crit, rien, absolument rien n&rsquo;est r\u00e9solu.<\/p>\n<\/p>\n<p><p>Alors, que reste-t-il ? Liquider Trump comme l&rsquo;on abattit Kennedy ? La trag\u00e9die fait trembler mais l&rsquo;analogie fait involontairement sourire tant diff\u00e8rent les deux victimes. C&rsquo;est l\u00e0 que se situe le n&oelig;ud gordien, comme une impossibilit\u00e9 de trancher ce qui ne peut \u00eatre r\u00e9solu qu&rsquo;en \u00e9tant tranch\u00e9. Assassiner Trump ? Ce serait un immense \u00e9clat de rire (\u00ab\u00a0C&rsquo;est une blague ! Il veut encore faire parler de lui !\u00a0\u00bb) suivi ou m\u00eame accompagn\u00e9 d&rsquo;une \u00e9crasante pression d&rsquo;une angoisse sans limite, presque comme une fin du monde (\u00ab\u00a0Mais qu&rsquo;allons-nous faire sans lui, qui nous reste-t-il \u00e0 adorer et \u00e0 ha\u00efr ?\u00a0\u00bb). La <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> est que l&rsquo;on aurait tant de mal jusqu&rsquo;\u00e0 l&rsquo;impossible \u00e0 faire de cette circonstance un \u00e9v\u00e9nement politique alors qu&rsquo;elle bouleverserait toute la politique du monde jusqu&rsquo;\u00e0 en devenir l&rsquo;essence d&rsquo;un tournant m\u00e9tapolitique, &ndash; tant de mal, disais-je, que l&rsquo;\u00e9v\u00e9nement nous \u00e9craserait comme une torture universelle d&rsquo;incompr\u00e9hension et de contradiction.<\/p>\n<\/p>\n<p><p>Je plains ceux qui, comme moi par instant, sont touch\u00e9s par la possibilit\u00e9 d&rsquo;envisager une telle fracture pour notre raison elle-m\u00eame, et pour la rendre folle c&rsquo;est s&ucirc;r. En v\u00e9rit\u00e9, le monde deviendrait fou parce que lui, Trump, qui est le fou du monde serait entr\u00e9 dans le royaume des ombres en pr\u00e9tendant qu&rsquo;il en est le roi. Comme les poss\u00e9d\u00e9s autour du b&ucirc;cher de Jeanne d\u00e9couvrant \u00ab\u00a0Nous avons br&ucirc;l\u00e9 une Sainte !\u00a0\u00bb, les assassins, multiples et innombrables autant que les victimes, se prosterneraient en s&rsquo;arrachant les cheveux de contrition : \u00ab\u00a0Nous avons assassin\u00e9 le Roi du Monde !\u00a0\u00bb. Cela serait sa derni\u00e8re blague et ce ne serait pas la plus mauvaise.<\/p>\n<\/p>\n<p><p>En v\u00e9rit\u00e9, je suis au service de tout le s\u00e9rieux possible en moi pour reconna&icirc;tre qu&rsquo;envisager cette possibilit\u00e9 s\u00e9rieusement, comme nous y force le d\u00e9put\u00e9 Goldman, me laisse sans voix et comme coi, sans force devant la perspective d&rsquo;une \u00e9nigme extraordinaire. Que se passerait-il ? Que deviendrions-nous ?<\/p>\n<\/p>\n<p><p>Le Sphinx, je le reconnais bien l\u00e0, ne r\u00e9pond pas, comme s&rsquo;il semblait nous dire : \u00ab\u00a0C&rsquo;est vous qui avez fabriqu\u00e9 ce formidable <em>Kaos<\/em> cosmique, \u00e0 vous de vous en arranger\u00a0\u00bb.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2023 : Il doit \u00eatre \u00e9limin\u00e9 ! 21 novembre 2023 (17H25) &ndash; Interview\u00e9 par Jan Psaki, sur MSNBC, le d\u00e9put\u00e9 d\u00e9mocrate Dan Goldman a eu des mots malheureux sur Trump, &ndash; en fait, un seul mot, mais qui a provoqu\u00e9 un bruit de tonnerre. Aussit\u00f4t repris sur Tweeter-X, la chose s&rsquo;est r\u00e9percut\u00e9e en cascade comme&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[7029,2651,22217,8477,2711,2878,10137,2639],"class_list":["post-80831","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-assassinat","tag-du","tag-elimine","tag-goldman","tag-le","tag-monde","tag-roi","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80831"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80831\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}