{"id":80834,"date":"2023-11-23T02:48:47","date_gmt":"2023-11-23T02:48:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2023\/11\/23\/la-guerre-a-mille-temps\/"},"modified":"2023-11-23T02:48:47","modified_gmt":"2023-11-23T02:48:47","slug":"la-guerre-a-mille-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2023\/11\/23\/la-guerre-a-mille-temps\/","title":{"rendered":"La guerre \u00e0 mille-temps"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La guerre \u00e0 mille-temps<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Le signe d\u00e9sormais le plus \u00e9vident de la qualit\u00e9 m\u00eame des affrontements en cours est la n\u00e9cessit\u00e9 o&ugrave; nous nous trouvons, <strong>non pas de \u00ab\u00a0penser diff\u00e9remment la guerre\u00a0\u00bb mais bien de \u00ab\u00a0penser les diff\u00e9rents lignages de la guerre\u00a0\u00bb<\/strong>. &bull; Le terme \u00ab\u00a0lignage\u00a0\u00bb n&rsquo;est pas de l&rsquo;ordre du tactique-strat\u00e9gie, &ndash; m\u00eame si les effets sont \u00e9galement de cette sorte, &ndash; <strong>mais de l&rsquo;ordre du spirituel et du m\u00e9taphysique<\/strong>. &bull; D&rsquo;o&ugrave; la n\u00e9cessit\u00e9 de comprendre l&rsquo;importance du concept de <strong>la \u00ab\u00a0g\u00e9ographie sacr\u00e9e\u00a0\u00bb, valant<\/strong> <strong>pour la \u00ab\u00a0guerre de Gaza\u00a0\u00bb<\/strong>. &bull; Avec un texte d&rsquo;Alexander Markovics.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>23 novembre (03H45) &ndash; Notre intention ici n&rsquo;est pas de \u00ab\u00a0r\u00e9inventer la guerre\u00a0\u00bb en la pensant diff\u00e9remment mais de proposer un exemple de description d&rsquo;une cat\u00e9gorie diff\u00e9rente de guerre avec \u00e0 l&rsquo;esprit bien entendu le cas de \u00ab\u00a0la guerre de Gaza\u00a0\u00bb, avec ses exc\u00e8s, ses folies, ses \u00e9nigmes, &ndash; ou tout ce qui nous para&icirc;t en elle \u00eatre exc\u00e8s, folie et \u00e9nigme. Il s&rsquo;agit d&rsquo;avoir une pens\u00e9e capable de se vouloir eschatologique et capable de l&rsquo;audace d&rsquo;une telle tournure de l&rsquo;esprit pour \u00e9valuer des \u00e9v\u00e8nements que nous avons appris \u00e0 jauger plut\u00f4t que juger, selon des poids et des mesures diff\u00e9rentes d&rsquo;appr\u00e9ciation. Il s&rsquo;entend comme une \u00e9vidence qu&rsquo;une telle d\u00e9marche n&rsquo;a n\u00e9cessairement rien d&rsquo;id\u00e9ologique, de partisan, de missionnaire, et tout d&rsquo;une d\u00e9marche d&rsquo;enqu\u00eateur ayant bonne et pleine conscience des enjeux cosmiques de ce que nous nommons dans notre jargon la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>.<\/p>\n<\/p>\n<p><p>En effet, pour nous la proposition intellectuelle de nous d\u00e9tailler le r\u00f4le de la \u00ab\u00a0g\u00e9ographie sacr\u00e9e\u00a0\u00bb dans la guerre, &ndash; et cette guerre pr\u00e9cis\u00e9ment, &ndash; doit nourrir une enqu\u00eate pour appr\u00e9cier la pr\u00e9sence et la puissance du fait eschatologique qui est lui-m\u00eame une condition <em>sine qua non<\/em> de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>. Il est par ailleurs \u00e9vident que le travail effectu\u00e9 par l&rsquo;auteur le conduit \u00e0 nommer une manifestation de forces fondamentales qui s&rsquo;affrontent, qui sont elles-m\u00eames au c&oelig;ur de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, et dont nous parlons si souvent par ellipse et symboles. Par cons\u00e9quent, on en pourra conduire o&ugrave; peut \u00e9videmment nous conduire le simple et seul fait de consid\u00e9rer la d\u00e9finition, la structuration et l&rsquo;intentionnalit\u00e9 des guerres eschatologiques qui se font selon les imp\u00e9ratifs de la \u00ab\u00a0g\u00e9ographie sacr\u00e9e\u00a0\u00bb. Ce qui est \u00ab\u00a0g\u00e9ographie sacr\u00e9e\u00a0\u00bb chez certains et pas n\u00e9cessairement pour nous \u00e0 l&rsquo;origine, est aussi, \u00e0 partir d&rsquo;un certain moment de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, un ordre des n\u00e9cessit\u00e9s pour nous \u00e9galement, &ndash; un peu comme l&rsquo;on respire pour vivre, ou m\u00eame survivre, &ndash; simplement (fa\u00e7on d&rsquo;\u00e9crire !) pour tenter de mieux appr\u00e9hender cette guerre. Un tel langage, vers la conclusion mais en \u00e9vitant pourtant les engagements religieux contraignants, constitue un signal d&rsquo;alerte \u00e9vident pour nous, qui nous rappelle le combat o&ugrave; nous nous trouvons et que nous retrouvons dans ce qui nous est propos\u00e9 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Nous devons prouver au monde qu&rsquo;il y a une diff\u00e9rence entre les peuples d&rsquo;Europe et leurs \u00e9lites sataniques contr\u00f4l\u00e9es par les &Eacute;tats-Unis. Je ne parle pas ici de lutte arm\u00e9e. Notre lutte doit avant tout \u00eatre une protestation spirituelle et intellectuelle et \u00eatre port\u00e9e dans la rue. Nous devons nous d\u00e9barrasser de nos \u00e9lites pour pouvoir enfin reprendre le contr\u00f4le de nos vies. Dans cette lutte entre le bien et le mal, on ne peut pas rester neutre, il faut choisir son camp. Nous, membres de la R\u00e9sistance <\/em>[&#8230;]<em>, Europ\u00e9ens conscients de notre propre histoire, de notre g\u00e9ographie sacr\u00e9e et de notre eschatologie, ne pouvons que lutter pour un changement&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous devons \u00e9galement comprendre que notre absence d&rsquo;appr\u00e9ciation dynamique de la \u00ab\u00a0g\u00e9ographie sacr\u00e9e\u00a0\u00bb est sans doute \u00e9galement un manque similaire chez l&rsquo;adversaire. Notre avantage sur lui est pourtant d&rsquo;avoir laiss\u00e9 entendre, voir d&rsquo;avoir laiss\u00e9 nos plumes nous dire que les \u00e9v\u00e8nements que nous observons sont, d&rsquo;une part eschatologiques, et d&rsquo;autre part qu&rsquo;ils doivent rester ouverts \u00e0 la participation, peut-\u00eatre et m\u00eame probablement, de \u00ab\u00a0forces extrahumaines\u00a0\u00bb qui \u00e9chappent compl\u00e8tement et heureusement \u00e0 l&#8217;empire usurp\u00e9 de <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-crise-de-la-raison-subvertie\">notre raison-subvertie<\/a>.<\/p>\n<\/p>\n<p><p>Pour autant, il nous para&icirc;t n\u00e9cessaire, et finalement tr\u00e8s instructif, de pouvoir conserver une position, non pas de neutralit\u00e9 ni d&rsquo;indiff\u00e9rence inqui\u00e8te, mais d&rsquo; <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">inconnaissance<\/a> active donnant aussi bien l&rsquo;ouverture de l&rsquo;esprit, paradoxalement vers la connaissance lorsqu&rsquo;elle celle-ci nous convoque, et logiquement selon la plus compl\u00e8te ma&icirc;trise de soi. Nous devons pouvoir \u00eatre capable de reconna&icirc;tre ces \u00ab\u00a0forces suprahumaines\u00a0\u00bb sans les craindre en aucune fa\u00e7on tout en reconnaissant leur hauteur et capacit\u00e9 d&rsquo;\u00e9vitement gracieux et ironique des pi\u00e8ges et autres entreprises subversives des forces terrestres et telluriques dominantes, et maquill\u00e9es en une s\u00e9duction douteuse pour \u00eatre mieux cr\u00e9atrices de simulacres.<\/p>\n<\/p>\n<p><p>Il ne fait aucun doute que le langage que nous proposons est d&rsquo;un herm\u00e9tisme in\u00e9vitable sinon intuitif, correspondant aux obstacles que notre pens\u00e9e elle-m\u00eame rencontre pour tenter d&rsquo;assimiler sans succomber au vertige du verbiage les concepts qui nous sont propos\u00e9s ci-dessous. Celui qui juge ne pas savoir mais tente d&rsquo;approcher un concept de cette sorte, doit offrir un langage qui expose le mieux possible la position d\u00e9licate o&ugrave; il se trouve. \u00ab\u00a0Ne pas savoir et, sachant cela, tenter n\u00e9anmoins d&rsquo;approcher s\u00e9lectivement par intuition\u00a0\u00bb est un acte difficile qui est le fait d&rsquo;un esprit qui ne craint pas d&rsquo;exposer ses faiblesses pour les offrir \u00e0 des dons capables de les r\u00e9duire et de les r\u00e9former ; notre herm\u00e9tisme est une fa\u00e7on de dire, \u00e0 la mani\u00e8re d&rsquo;un Socrate qui se moquerait \u00e0 la fois du Sophisme et de Socrate : \u00ab\u00a0Nous aussi, nous savons que nous ne savons rien et notre incertitude est une vertu que m\u00eame les dieux doivent sans nul doute, eux, comprendre et respecter\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Entendre et voir se dessiner leur \u00ab\u00a0g\u00e9ographie sacr\u00e9e \u00ab\u00a0, c&rsquo;est leur dire : \u00ab\u00a0Si nous vous comprenons fort bien sans pour autant rien y comprendre, soyez assez loyal pour nous rendre la pareille\u00a0\u00bb. Peut-\u00eatre que, d&rsquo;ici l\u00e0, nous aurons commenc\u00e9 \u00e0 comprendre&#8230; Pour le reste, s&rsquo;il s&rsquo;agit d&rsquo;affronter le <em>Mordor <\/em>de la modernit\u00e9 que nous connaissons bien et qui sont bien les m\u00eames, nous avons d\u00e9j\u00e0 bien assez montr\u00e9 l&rsquo;alacrit\u00e9 de nos triomphantes trompettes sonnant la charge pour qu&rsquo;on veuille bien nous accorder le b\u00e9n\u00e9fice de notre incertitude.  <\/p>\n<\/p>\n<p><p> &#8230; Voici donc que se dessine la g\u00e9opolitique postmoderne \u00e0 l&rsquo;exemple de la Palestine, dans sa grandeur et sa gr\u00e2ce des formes de la g\u00e9ographie sacr\u00e9e et de l&rsquo;eschatologie. Le texte &laquo; <em>G\u00e9ographie sacr\u00e9e et eschatologie: la g\u00e9opolitique postmoderne \u00e0 l&rsquo;exemple de la Palestine<\/em> &raquo; est donc d&rsquo;Alexander Markovics, de &lsquo;<em><a href=\"source:%20https:\/\/www.geopolitika.ru\/de\/article\/sakrale-geographie-und-eschatologie-postmoderne-geopolitik-am-beispiel-von-palaestina\">geopolitika.ru<\/a><\/em>&lsquo;, sur &lsquo;<em><a href=\"http:\/\/euro-synergies.hautetfort.com\/archive\/2023\/11\/21\/geographie-sacree-et-eschatologie-la-geopolitique-postmoderne-a-l-exemple-d.html\">Euro-Synergies.Hautefort.com<\/a><\/em>&lsquo;<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">G\u00e9ographie sacr\u00e9e et eschatologie<\/h2>\n<\/p>\n<blockquote>\n<p><p><em>La g\u00e9opolitique postmoderne \u00e0 l&rsquo;exemple de la Palestine : comprendre le conflit autour de la Palestine<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p><strong>I.<\/strong> Si nous regardons le conflit actuel autour de la Palestine, nous pouvons voir certaines dichotomies utilis\u00e9es pour cat\u00e9goriser la guerre : Musulmans contre Juifs, Occident contre Islam, Occup\u00e9s contre Occupants et bien d&rsquo;autres. Certaines de ces paires d&rsquo;oppos\u00e9s sont plus vraies que d&rsquo;autres, mais elles omettent bien s&ucirc;r certains aspects importants, comme le fait tout moyen visant \u00e0 simplifier une situation. Bien s&ucirc;r, la guerre de Palestine est un conflit entre les Palestiniens occup\u00e9s et leurs occupants sionistes. Ce conflit est brutal, notamment en raison du fait que les Palestiniens sont un peuple colonis\u00e9 qui lutte pour sa survie contre un ennemi dont les repr\u00e9sentants officiels, comme le ministre isra\u00e9lien de la D\u00e9fense Joav Galant, le qualifient d&rsquo;&quot;animaux humains&quot;. De nombreux observateurs r\u00eavent d&rsquo;une v\u00e9ritable solution \u00e0 deux &Eacute;tats afin de cr\u00e9er une paix durable pour la Palestine. Compte tenu de la gravit\u00e9 du conflit, il semble que la guerre ne puisse se terminer que soit par la d\u00e9faite des Palestiniens et le nettoyage ethnique du peuple palestinien de Gaza, soit par une d\u00e9faite humiliante pour l&rsquo;\u00e9lite sioniste et ethno-nationaliste fanatique de Tel-Aviv. Pour l&rsquo;instant, les deux sc\u00e9narios sont du domaine du possible.<\/p>\n<\/p>\n<p><p><strong>II.<\/strong> En effet, les n\u00e9oconservateurs, les partisans de l&rsquo;&Eacute;cole de Francfort en Allemagne et m\u00eame certains populistes europ\u00e9ens de droite tentent de pr\u00e9senter la lutte comme un duel entre un &quot;Occident s\u00e9cularis\u00e9, civilis\u00e9 et \u00e9clair\u00e9&quot; et un &quot;Islam barbare, brutal et r\u00e9trograde&quot;. En \u00e9coutant cette propagande occidentale, nous nous souvenons imm\u00e9diatement de l&rsquo;ouvrage de Samuel Huntington &quot;Le choc des civilisations&quot;, dans lequel il anticipait la mont\u00e9e de la multipolarit\u00e9, mais aussi une possible escalade du conflit entre l&rsquo;Occident et la civilisation islamique. Dans l&rsquo;esprit des <em>neocon<\/em>, le possible choc des civilisations, d\u00e9crit dans l&rsquo;&oelig;uvre de Huntington, devient une proph\u00e9tie auto-r\u00e9alisatrice. Pourtant, le philosophe am\u00e9ricain nous a montr\u00e9 que le combat entre les civilisations n&rsquo;est qu&rsquo;une possibilit\u00e9 parmi d&rsquo;autres, les autres \u00e9tant la coop\u00e9ration et la paix.<\/p>\n<\/p>\n<p><p><strong>III.<\/strong> La dichotomie &quot;Juifs contre Musulmans&quot; n&rsquo;est pas tout \u00e0 fait correcte dans la mesure o&ugrave; le nationalisme sioniste, l&rsquo;id\u00e9ologie de l&rsquo;Etat d&rsquo;Isra\u00ebl, est en totale opposition avec le juda\u00efsme traditionnel, qui consid\u00e8re la pr\u00e9sence des Juifs en Palestine avant l&rsquo;arriv\u00e9e du Messie comme une h\u00e9r\u00e9sie et une violation de la volont\u00e9 de Dieu. De plus, la dimension de cette lutte n&rsquo;est pas r\u00e9ductible \u00e0 une confrontation entre les forces globalistes qui tentent de maintenir l&rsquo;unipolarit\u00e9 et l&rsquo;h\u00e9g\u00e9monie occidentale, et les forces qui pr\u00f4nent la mise en place d&rsquo;un ordre mondial multipolaire dans lequel l&rsquo;Occident n&rsquo;est qu&rsquo;un p\u00f4le parmi d&rsquo;autres. Si nous voulons comprendre la v\u00e9ritable dimension et l&rsquo;importance de cette guerre pour la Palestine, nous devons porter notre attention sur d&rsquo;autres aspects.<\/p>\n<\/p>\n<p><p><strong>IV.<\/strong> Il est \u00e9vident que les concepts et les formes de perception purement modernes ne peuvent pas mettre en \u00e9vidence l&rsquo;importance de l&rsquo;\u00e9ternit\u00e9 pour les cultures traditionnelles, comme dans le cas de la civilisation islamique. Les sectes postmodernes qui combinent des versions d\u00e9form\u00e9es de l&rsquo;eschatologie chr\u00e9tienne et juive dans des visions \u00e9vang\u00e9liques et sionistes de la fin du monde sont le v\u00e9ritable moteur de ce conflit, mais elles sont pour la plupart ignor\u00e9es en Occident.<\/p>\n<\/p>\n<p><p><strong>V.<\/strong> Il en va de m\u00eame pour l&rsquo;id\u00e9e de g\u00e9ographie sacr\u00e9e, anc\u00eatre de la g\u00e9opolitique moderne, qui est aujourd&rsquo;hui compl\u00e8tement \u00e9trang\u00e8re \u00e0 la majorit\u00e9 des Europ\u00e9ens, qui suivent un mode de vie ath\u00e9e d\u00e9pourvu de toute connaissance historique. En cons\u00e9quence, nous devons suivre le philosophe russe Alexandre Douguine et l&rsquo;\u00e9cole de philosophie traditionaliste si nous voulons aller au c&oelig;ur des choses en ce qui concerne la g\u00e9opolitique postmoderne, en prenant l&rsquo;exemple de la Palestine. Celui qui veut comprendre la guerre pour la Palestine doit comprendre qu&rsquo;elle n&rsquo;est pas men\u00e9e uniquement pour des objectifs g\u00e9opolitiques, la cr\u00e9ation d&rsquo;un monde multipolaire d&rsquo;un c\u00f4t\u00e9 et l&#8217;emp\u00eachement de la multipolarit\u00e9 de l&rsquo;autre, mais qu&rsquo;il s&rsquo;agit d&rsquo;une guerre fond\u00e9e sur la g\u00e9ographie et l&rsquo;eschatologie sacr\u00e9es. En bref, il s&rsquo;agit d&rsquo;une guerre sainte.<\/p>\n<\/p>\n<blockquote>\n<p><p><em>G\u00e9ographie sacr\u00e9e : un paysage dispose d&rsquo;une signification intrins\u00e8quement sacr\u00e9e, d\u00e9riv\u00e9e de Dieu ou des dieux, un type d&rsquo;espace rempli de divinit\u00e9<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p><strong>VI.<\/strong> Le terme de g\u00e9ographie sacr\u00e9e implique qu&rsquo;un paysage dispose d&rsquo;une signification intrins\u00e8quement sacr\u00e9e, d\u00e9riv\u00e9e de Dieu ou des dieux, selon le syst\u00e8me de croyance sous-jacent. Il s&rsquo;agit d&rsquo;un type d&rsquo;espace qui est rempli de divinit\u00e9. En cons\u00e9quence, la g\u00e9ographie sacr\u00e9e est une mani\u00e8re de voir le monde en relation avec les mythes et les croyances. Elle met \u00e9galement en \u00e9vidence des lieux sacr\u00e9s qui sont constamment consacr\u00e9s par des rituels. Alors que les &Eacute;gyptiens croyaient que les terres situ\u00e9es \u00e0 l&rsquo;ouest des colonnes d&rsquo;H\u00e9racl\u00e8s (l&rsquo;actuel Gibraltar) abritaient le royaume des morts, les Europ\u00e9ens du Moyen &Acirc;ge pensaient que l&rsquo;actuelle Scandinavie et l&rsquo;Europe de l&rsquo;Est \u00e9taient habit\u00e9es par des sorciers et des sauvages.<\/p>\n<\/p>\n<p><p><strong>VII.<\/strong> La Palestine est un tel espace sacr\u00e9. C&rsquo;est la Terre sainte pour les chr\u00e9tiens, les musulmans et les juifs. Dans la th\u00e9ologie chr\u00e9tienne, la Palestine est la terre o&ugrave; a eu lieu la r\u00e9v\u00e9lation du message de Dieu \u00e0 l&rsquo;humanit\u00e9. C&rsquo;est l\u00e0 que J\u00e9sus-Christ est n\u00e9, qu&rsquo;il a pr\u00each\u00e9, qu&rsquo;il a \u00e9t\u00e9 crucifi\u00e9 et qu&rsquo;il est ressuscit\u00e9 d&rsquo;entre les morts. Pour les chr\u00e9tiens, la ville de J\u00e9rusalem ne sert pas seulement d&rsquo;all\u00e9gorie \u00e0 l&rsquo;&Eacute;glise, mais contient \u00e9galement de nombreux lieux saints, dont l&rsquo;\u00e9glise du Saint-S\u00e9pulcre et le C\u00e9nacle du mont Sion, o&ugrave; a eu lieu la C\u00e8ne. En ce qui concerne les rituels, les chr\u00e9tiens orthodoxes c\u00e9l\u00e8brent chaque ann\u00e9e la c\u00e9r\u00e9monie du feu sacr\u00e9 le samedi avant P\u00e2ques. Dans le discours de la philosophie europ\u00e9enne, J\u00e9rusalem symbolisait en outre la primaut\u00e9 de la religion sur la rationalit\u00e9 pure et la raison, deux qualit\u00e9s associ\u00e9es \u00e0 la ville d&rsquo;Ath\u00e8nes. La primaut\u00e9 d&rsquo;Ath\u00e8nes qui pr\u00e9vaut actuellement dans la pens\u00e9e europ\u00e9enne est peut-\u00eatre la raison pour laquelle nous sommes aujourd&rsquo;hui aveugles au ph\u00e9nom\u00e8ne de la g\u00e9ographie sacr\u00e9e. Dans l&rsquo;islam, J\u00e9rusalem est appel\u00e9e Al-Quds ou Baitul-Maqdis (\u00ab\u00a0La place noble et sainte\u00a0\u00bb) et abrite la place du D\u00f4me du Rocher, la plus ancienne structure islamique en pierre. Selon la th\u00e9ologie musulmane, J\u00e9rusalem \u00e9tait la premi\u00e8re quiblah &ndash; le lieu o&ugrave; les musulmans priaient. Selon le proph\u00e8te Mahomet, la mosqu\u00e9e d&rsquo;Al-Aqsa (J\u00e9rusalem) est le troisi\u00e8me lieu saint de l&rsquo;islam, avec La Mecque et M\u00e9dine, et la destination des p\u00e8lerins musulmans du monde entier. Le juda\u00efsme, quant \u00e0 lui, consid\u00e8re la Palestine comme la \u00ab\u00a0Terre promise\u00a0\u00bb, mais les points de vue des juifs orthodoxes et des sionistes diff\u00e8rent radicalement lorsqu&rsquo;il s&rsquo;agit de revendiquer la Palestine. Dans la tradition juive, J\u00e9rusalem \u00e9tait le lieu o&ugrave; se trouvait le Temple, la capitale du royaume juif, le lieu de l&rsquo;Arche d&rsquo;Alliance. D&rsquo;un point de vue juif, il s&rsquo;agit \u00e9galement d&rsquo;un lieu de deuil, car le Temple juif y a \u00e9t\u00e9 d\u00e9truit \u00e0 deux reprises et les Juifs ont \u00e9t\u00e9 expuls\u00e9s de la ville \u00e0 plusieurs reprises. Les juifs orthodoxes la consid\u00e8rent comme le \u00ab\u00a0nombril du monde\u00a0\u00bb, J\u00e9rusalem symbolisant pour eux l&rsquo;espoir de l&rsquo;apparition du Messie tout autant que le lieu le plus sacr\u00e9.<\/p>\n<\/p>\n<p><p><strong>VIII.<\/strong> Lorsque les sionistes de Theodor Herzl sont entr\u00e9s \u00e0 J\u00e9rusalem en 1898, leur pens\u00e9e \u00e9tait manifestement influenc\u00e9e par Ath\u00e8nes et non par J\u00e9rusalem : ils ont \u00e9t\u00e9 choqu\u00e9s par le pr\u00e9tendu obscurantisme des habitants et la puanteur de la ville. Pour les sionistes radicaux &ndash; qui sont encore aujourd&rsquo;hui essentiellement des militants nationalistes qui consid\u00e8rent leur jud\u00e9it\u00e9 comme une cons\u00e9quence de leur h\u00e9ritage biologique plut\u00f4t que spirituel&ndash;- J\u00e9rusalem est une sorte de honte religieuse, associ\u00e9e \u00e0 la salet\u00e9 et \u00e0 la ferveur religieuse au milieu du d\u00e9sert qu&rsquo;ils ont transform\u00e9 en leur version du jardin d&rsquo;Eden. Bien s&ucirc;r, \u00e0 leurs yeux, la Palestine n&rsquo;est qu&rsquo;un lieu purement mondain, d\u00e9pourvu de toute trace de g\u00e9ographie sacr\u00e9e, qui doit \u00eatre pr\u00e9par\u00e9 \u00e0 l&rsquo;occidentalisation, \u00e0 la colonisation et \u00e0 toutes les autres merveilles noires et profanes du postmodernisme &ndash; drapeaux arc-en-ciel, \u00ab\u00a0mariages homosexuels\u00a0\u00bb et nationalisme domin\u00e9 par la seule soif de sang et de terre. Alors que les juifs orthodoxes consid\u00e8rent comme une h\u00e9r\u00e9sie la cr\u00e9ation d&rsquo;un &Eacute;tat juif en Palestine avant la fin des temps, le sionisme, issu de la secte sabbatiste et du mouvement juif d&rsquo;\u00e9ducation que fut la Haskala, a \u00e9t\u00e9 fond\u00e9 dans ce but. Ce dernier, avec le soutien explicite de l&rsquo;Occident, a connu un grand succ\u00e8s : l&rsquo;&Eacute;tat juif a \u00e9t\u00e9 cr\u00e9\u00e9 en 1948 et J\u00e9rusalem est devenue une ville contr\u00f4l\u00e9e par les Juifs en 1967.<\/p>\n<\/p>\n<blockquote>\n<p><p><em>L&rsquo;eschatologie consid\u00e9r\u00e9 comme outil politique : le Troisi\u00e8me Temple et le D\u00e9luge d&rsquo;Al-Aqsa<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p><strong>IX.<\/strong> Si nous regardons la r\u00e9cente escalade en Palestine \u00e0 travers le regard des m\u00e9dias occidentaux, les \u00e9v\u00e9nements semblent assez \u00e9tranges : tout \u00e0 coup, l&rsquo;aile militaire du Hamas, la Brigade Al-Qassem, lance une attaque contre Isra\u00ebl. De leur c\u00f4t\u00e9, les Isra\u00e9liens semblent riposter de mani\u00e8re disproportionn\u00e9e. Alors que l&rsquo;arm\u00e9e isra\u00e9lienne a \u00e9t\u00e9 prise au d\u00e9pourvu et a subi les pertes les plus importantes de son existence, des milliers de Palestiniens meurent \u00e0 la suite d&rsquo;attaques isra\u00e9liennes contre des zones civiles. Mais si nous regardons de plus pr\u00e8s ce qui se passe, nous d\u00e9couvrons que la v\u00e9ritable raison de la guerre actuelle est eschatologique.<\/p>\n<\/p>\n<p><p><strong>X.<\/strong> L&rsquo;eschatologie nous enseigne la fin de ce monde et la naissance d&rsquo;un nouveau. C&rsquo;est pr\u00e9cis\u00e9ment la fin de ce monde que les sionistes chr\u00e9tiens am\u00e9ricains et europ\u00e9ens ainsi que les sectes juives de Palestine tentent de d\u00e9clencher avec la construction du Troisi\u00e8me Temple \u00e0 J\u00e9rusalem. Le nom de l&rsquo;op\u00e9ration du Hamas &ndash; \u00ab\u00a0Al-Aqsa Flood\u00a0\u00bb &ndash; nous conduit directement \u00e0 la signification eschatologique et \u00e0 la v\u00e9ritable nature de cette guerre. Alors que m\u00eame sous l&rsquo;occupation isra\u00e9lienne, les rituels juifs \u00e0 la mosqu\u00e9e Al-Aqsa ont longtemps \u00e9t\u00e9 emp\u00each\u00e9s par Isra\u00ebl, des fanatiques juifs ont \u00e9t\u00e9 vus de plus en plus souvent \u00e0 l&rsquo;int\u00e9rieur de la mosqu\u00e9e depuis le d\u00e9but des ann\u00e9es 2000, lorsque la politique isra\u00e9lienne a d\u00e9riv\u00e9 de plus en plus vers les bouffonneries d&rsquo;une droite folle. Bien que les musulmans du monde entier consid\u00e8rent cela comme un sacril\u00e8ge, les juifs fanatiques consid\u00e8rent la mosqu\u00e9e Al-Aqsa, construite sur les ruines du Second Temple, comme un obstacle \u00e0 l&rsquo;\u00e9dification du Troisi\u00e8me Temple.<\/p>\n<\/p>\n<p><p><strong>XI.<\/strong> Le \u00ab\u00a0d\u00e9luge d&rsquo;Al-Aqsa\u00a0\u00bb a \u00e9t\u00e9 d\u00e9clench\u00e9 par la profanation de la mosqu\u00e9e Al-Aqsa par les Juifs. Des sectes juives comme le Temple Institute et Mount Faithful appellent \u00e0 sacrifier une g\u00e9nisse rouge immacul\u00e9e pour permettre la construction du Troisi\u00e8me Temple, qui d\u00e9clencherait l&rsquo;arriv\u00e9e du Messie et la fin du monde. Pour les musulmans pratiquants, ces actes de profanation de la mosqu\u00e9e Al-Aqsa repr\u00e9sentent l&rsquo;&oelig;uvre du Daddjal, l&rsquo;anti-Christ. Selon certaines sectes en Isra\u00ebl, la g\u00e9nisse rouge parfaite est d\u00e9j\u00e0 n\u00e9e et sera pr\u00eate \u00e0 \u00eatre sacrifi\u00e9e en 2024. La plupart des Juifs croient cependant que le Troisi\u00e8me Temple sera construit par Dieu lui-m\u00eame et le Messie, et que l&rsquo;intervention humaine directe dans ces affaires est un sacril\u00e8ge. Mais comme souvent dans l&rsquo;histoire, celle-ci est faite par des minorit\u00e9s radicales et pr\u00eates \u00e0 tout, et non par la majorit\u00e9. Cela explique les provocations persistantes des sectes juives et la volont\u00e9 des groupes musulmans radicaux comme le Hamas de d\u00e9fendre la mosqu\u00e9e Al-Aqsa, m\u00eame si cela implique le sacrifice de milliers de Palestiniens \u00e0 Gaza.<\/p>\n<\/p>\n<p><p><strong>XII.<\/strong> Alors que la Russie, l&rsquo;Iran, la Chine et m\u00eame l&rsquo;Arabie saoudite adoptent la position des Palestiniens et appellent \u00e0 une v\u00e9ritable solution \u00e0 deux &Eacute;tats, l&rsquo;Occident, en grande partie ath\u00e9e et postmoderne, se rassemble autour du drapeau d&rsquo;Isra\u00ebl et d\u00e9fend tous les crimes de guerre, m\u00eame les plus flagrants, commis par les Isra\u00e9liens. Mais ce jeu de vacherin pourrait mal tourner pour l&rsquo;Occident : alors que les Palestiniens de Gaza luttent d\u00e9sesp\u00e9r\u00e9ment pour leur survie et la pr\u00e9servation d&rsquo;Al-Aqsa, plus de 5 millions d&rsquo;hommes se sont port\u00e9s volontaires en Iran pour combattre pour la Palestine. Le Qatar menace Isra\u00ebl de sanctions dans le secteur de l&rsquo;\u00e9nergie et, pour la premi\u00e8re fois depuis 2013, des personnes ont manifest\u00e9 sur la place Tahrir au Caire pour appeler \u00e0 une intervention aux c\u00f4t\u00e9s de leurs fr\u00e8res musulmans en Palestine. Nous sommes d\u00e9j\u00e0 en pr\u00e9sence d&rsquo;une guerre sainte et, r\u00e9trospectivement, le politicien russe Jirinovski a peut-\u00eatre eu raison de dire que le conflit en Ukraine ferait p\u00e2le figure en comparaison de la guerre \u00e0 venir en Terre sainte.<\/p>\n<\/p>\n<p><p><strong>XIII.<\/strong> Alors que l&rsquo;Islam commence \u00e0 former une civilisation ind\u00e9pendante \u00e0 la suite de cette lutte et se bat pour un monde multipolaire aux c\u00f4t\u00e9s de la Russie et de la Chine, l&rsquo;Occident satanique, de l&rsquo;&icirc;le d&rsquo;Epstein \u00e0 Bruxelles, se range aux c\u00f4t\u00e9s d&rsquo;Isra\u00ebl. Le mot satanique peut d&rsquo;abord sembler trop fort pour d\u00e9crire l&rsquo;Occident moderne (qui n&rsquo;a rien \u00e0 voir avec la tradition et la culture occidentales de l&rsquo;Antiquit\u00e9 \u00e0 la fin de la Renaissance), mais si l&rsquo;on regarde la r\u00e9alit\u00e9 politique en son sein, les spectacles de drag <em>queens<\/em>, les chiffres de l&rsquo;avortement, les op\u00e9rations de \u00ab\u00a0r\u00e9assignation sexuelle\u00a0\u00bb, la destruction totale de la culture occidentale au nom du \u00ab\u00a0wokenisme\u00a0\u00bb, la violence dans nos rues et l&rsquo;impi\u00e9t\u00e9 dans le c&oelig;ur de nos peuples, je suis convaincu que ce qualificatif ne tombe pas vraiment comme un cheveu sur la soupe.<\/p>\n<\/p>\n<p><p><strong>XIV.<\/strong> Alors que les pays BRICS sont en train de former un <em>katekhon<\/em>, le butoir de l&rsquo;antichristianisme, la civilisation occidentale du diable s&rsquo;allie \u00e0 Isra\u00ebl, ce qui n&rsquo;est pas bon signe pour Isra\u00ebl lui-m\u00eame, comme l&rsquo;a d\u00e9j\u00e0 fait remarquer Alexandre Douguine. &Agrave; la lumi\u00e8re des \u00e9v\u00e9nements actuels, nous, Europ\u00e9ens, devons d\u00e9cider qui nous soutenons dans cette guerre. Nous pouvons choisir de soutenir l&rsquo;Occident satanique ou de former un <em>katekhon<\/em> avec tous les autres peuples du monde. Nous devons prouver au monde qu&rsquo;il y a une diff\u00e9rence entre les peuples d&rsquo;Europe et leurs \u00e9lites sataniques contr\u00f4l\u00e9es par les &Eacute;tats-Unis. Je ne parle pas ici de lutte arm\u00e9e. Notre lutte doit avant tout \u00eatre une protestation spirituelle et intellectuelle et \u00eatre port\u00e9e dans la rue. Nous devons nous d\u00e9barrasser de nos \u00e9lites pour pouvoir enfin reprendre le contr\u00f4le de nos vies. Dans cette lutte entre le bien et le mal, on ne peut pas rester neutre, il faut choisir son camp. Nous, membres de la R\u00e9sistance chr\u00e9tienne, Europ\u00e9ens conscients de notre propre histoire, de notre g\u00e9ographie sacr\u00e9e et de notre eschatologie, ne pouvons que lutter pour un changement, prier Dieu et former un <em>katekhon<\/em> contre cette civilisation infernale. Nous verrons quel c\u00f4t\u00e9 gagnera cette guerre sainte, Dieu seul le sait.<\/p>\n<\/p>\n<p><h4>Alexander Markovics<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerre \u00e0 mille-temps &bull; Le signe d\u00e9sormais le plus \u00e9vident de la qualit\u00e9 m\u00eame des affrontements en cours est la n\u00e9cessit\u00e9 o&ugrave; nous nous trouvons, non pas de \u00ab\u00a0penser diff\u00e9remment la guerre\u00a0\u00bb mais bien de \u00ab\u00a0penser les diff\u00e9rents lignages de la guerre\u00a0\u00bb. &bull; Le terme \u00ab\u00a0lignage\u00a0\u00bb n&rsquo;est pas de l&rsquo;ordre du tactique-strat\u00e9gie, &ndash; m\u00eame&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2857,7548,14024,6136],"class_list":["post-80834","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-alexander","tag-eschatologie","tag-markovics","tag-palestine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80834"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80834\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}