{"id":80929,"date":"2024-02-07T17:28:15","date_gmt":"2024-02-07T17:28:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/02\/07\/tucker-for-ever\/"},"modified":"2024-02-07T17:28:15","modified_gmt":"2024-02-07T17:28:15","slug":"tucker-for-ever","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/02\/07\/tucker-for-ever\/","title":{"rendered":"Tucker <em>for ever<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\"><strong>Tucker <em>for ever<\/em><\/strong><\/h2>\n<\/p>\n<p><p>7 f\u00e9vrier 2024 (17H20) &ndash; L&rsquo;aventure de Tucker Carlson \u00e0 Moscou a quelque chose de Tintin. (A part que &lsquo;Carlson chez Poutine&rsquo; n&rsquo;est vraiment pas dans le m\u00eame sens que &lsquo;<em>Tintin chez les Soviets<\/em>&lsquo; ! &ndash; si l&rsquo;on prend les choses id\u00e9ologiquement, d&rsquo;ailleurs d&rsquo;une fa\u00e7on compl\u00e8tement d\u00e9phas\u00e9e et sans le moindre rapport tant les temps id\u00e9ologiques diff\u00e8rent aujourd&rsquo;hui extraordinairement d&rsquo;il y a un si\u00e8cle, &ndash; tant c&rsquo;est piti\u00e9, PhG, de faire une telle comparaison !) Et pourtant j&rsquo;y tiens : Carlson nous para&icirc;t \u00eatre comme s&rsquo;il \u00e9tait parti, seul \u00e0 l&rsquo;aventure, contre tous et seul en d\u00e9pit de tous, avec les meutes des hy\u00e8nes-<em>neocon <\/em>hurlant \u00e0 la mort, le cul dans leur fauteuil en cuir de besoins massacr\u00e9s au XIX\u00e8me si\u00e8cle, le sang en concentr\u00e9 de tomates leur coulant de la commissures des l\u00e8vres exactement, sacr\u00e9s t\u00eates de <em>neocon<\/em>, les ceux qui osent tout c&rsquo;est-m\u00eame-\u00e0-\u00e7a-qu&rsquo;on-les-reconna&icirc;t ! Mais qu&rsquo;importe&#8230; Seul dis-je et r\u00e9p\u00e8te-je, le Carlson, compl\u00e8tement \u00e0 l&rsquo;aventure, pour lever un pan sur la v\u00e9rit\u00e9 (et m\u00eame sur la V\u00e9rit\u00e9 ?)&#8230; Ce dernier point, \u00e7a c&rsquo;est s&ucirc;r c&rsquo;est du Tintin,.<\/p>\n<\/p>\n<p><p>J&rsquo;ai trouv\u00e9 un texte qui a pour th\u00e8me le voyage de Carlson \u00e0 Moscou, \u00e9crit avant que l&rsquo;interview n&rsquo;ait eu lieu (officiellement, <a href=\"https:\/\/sputnikglobe.com\/20240207\/tucker-carlson-interviewed-putin-on-tuesday---kremlin-1116640244.html\">hier<\/a>). L&rsquo;auteur, Martin Jay, prend d&rsquo;ailleurs un exemple analogique qui me para&icirc;t tr\u00e8s contestable, parlant d&rsquo;une \u00ab\u00a0alerte\u00a0\u00bb (on disait &lsquo;<em>Red Scare<\/em>&lsquo; \u00e0 l&rsquo;\u00e9poque lorsqu&rsquo;il s&rsquo;agissait de \u00ab\u00a0ceux d&rsquo;en face\u00a0\u00bb) du Pentagone des ann\u00e9es 1970, alors que Rumsfeld \u00e9tait une premi\u00e8re fois secr\u00e9taire \u00e0 la d\u00e9fense (1975-1977), concernant les sous-marins sovi\u00e9tiques. J&rsquo;ai v\u00e9cu cette p\u00e9riode et ait fort peu entendu parler de cette vraie-\u00ab\u00a0fausse alerte\u00a0\u00bb, alors que d&rsquo;autres vraie-\u00ab\u00a0fausse alerte\u00a0\u00bb faisaient beaucoup plus de bruits. Par exemple, il y eut celle qui entoura l&rsquo;intercepteur MiG-25 mythique et volant trop haut et trop vite pour \u00eatre intercept\u00e9 (Le MiG-25, mes amis, a eu comme d\u00e9veloppement le MiG-31 lanceur de &lsquo;<em>Kinzhal<\/em>&lsquo;, qui est autrement du s\u00e9rieux.)<\/p>\n<\/p>\n<p><p>Le MiG-25, dont un exemplaire pilot\u00e9 par le lieutenant Belenko fit d\u00e9fection au Japon en 1976, s&rsquo;av\u00e9ra d&rsquo;ailleurs beaucoup moins effrayant qu&rsquo;il n&rsquo;y paraissait, &ndash; quoiqu&rsquo;aujourd&rsquo;hui, certains reconsid\u00e8rent le cas&#8230; Bref, on voit bien que tous ces divers cas portaient sur des mat\u00e9riels sp\u00e9cifiques qui ne constituaient pas \u00e0 eux seuls ni une politique, ni une puissance, et dont on usait de part et d&rsquo;autre pour se faire peur et entretenir le mythe de la Guerre Froide en m\u00eame temps que les budgets de d\u00e9fense.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p><strong><em>Note de PhG-Bis<\/em><\/strong><em> : &laquo; Il para&icirc;t que PhG s&rsquo;est laiss\u00e9 dire, le brave gar\u00e7on \u00e0 l&rsquo;oreille qui tra&icirc;ne, qu&rsquo;il existait une  v\u00e9ritable entente tacite entre le complexe militaro-industriel (CMI) US et celui de l&rsquo;URSS, pour entretenir avec des petites trouvailles de cette sorte des peurs r\u00e9ciproques l&rsquo;un chez l&rsquo;autre et vice-versa sans trop s&rsquo;en d\u00e9fendre, et obtenir chacun chez soi, des augmentations budg\u00e9taires. \u00ab\u00a0J&rsquo;dis \u00e7a, j&rsquo;dis rien\u00a0\u00bb, dit PhG. &raquo;<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Par contre, l\u00e0 o&ugrave; Jay a raison, c&rsquo;est sur la question de savoir si l&rsquo;interview de Carlson va modifier le sentiment des citoyens am\u00e9ricains sur Poutine et la Russie. Bien entendu, Carlson sera barr\u00e9 sur tous les r\u00e9seaux officiels, honni, d\u00e9nonc\u00e9, fustig\u00e9, tra&icirc;n\u00e9 devant l&rsquo;Inquisition des pr\u00eatres en soutane dor\u00e9 de la presseSyst\u00e8me. Il faut \u00e9couter la diatribe de Glenn Greenwald <a href=\"https:\/\/www.youtube.com\/watch?v=EqMO6Ckwgsg\">d&rsquo;hier soir<\/a>, d\u00e9non\u00e7ant tous ceux qui d\u00e9signent Carlson comme un tra&icirc;tre, jugent qu&rsquo;il faut interdire son retour, voire le faire assassiner. Greenwald, qui est un antiguerre compl\u00e8tement de gauche, p\u00e8se d&rsquo;un sacr\u00e9 poids dans le monde des &lsquo;dissidents&rsquo; et il est un exemple de cette man&oelig;uvre de &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/les-mythes-saffrontent\">slalom<\/a>&lsquo; comme je nomme l&rsquo;exercice o&ugrave; des gens de sensibilit\u00e9s diff\u00e9rentes voire oppos\u00e9es doivent s&rsquo;allier les uns aux autres avec la plus grande vigueur contre l&rsquo;ennemi commun qu&rsquo;est le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Enfin, Carlson est autre chose que le Tintin de 1927 en fait de communication. <a href=\"https:\/\/twitter.com\/TuckerCarlson\/status\/1754939251257475555\">La vid\u00e9o<\/a> o&ugrave; il annonce, mardi vers 19H00 son interview, sur son compte tweeterX, comptait ce mercredi \u00e0 17 heures pr\u00e8s de 80 millions de vues (79 millions en 21 heures de temps). Il est bien possible que son interview de Poutine soit la plus regard\u00e9e de l&rsquo;histoire de la communication. (Je dis cela sans conna&icirc;tre les chiffres existants, mais pour donner une id\u00e9e de l&rsquo;immense tour de Babel de causerie intercontinentale \u00e0 laquelle on va assister.) Cela vous fait mesurer les fantastiques changements que l&rsquo;\u00e9volution du syst\u00e8me de la communication a introduit dans notre vie quotidienne, dans nos affaires politiques, dans l&rsquo;histoire elle-m\u00eame, &ndash; ce qui en fait un \u00e9v\u00e9nement m\u00e9tahistorique, chose que je ne cesse de <a href=\"https:\/\/www.dedefensa.org\/article\/le-mensonge-proclame-createur-de-lhistoire\">proclamer haut et fort<\/a> \u00e0 chaque fois que l&rsquo;occasion fait le larron.<\/p>\n<\/p>\n<p><p>Et l\u00e0-dessus, vous pouvez estimer que Tucker Carlson est lui-m\u00eame, d\u00e9sormais sinon d\u00e9j\u00e0, un personnage d&rsquo;une telle puissance de communication qu&rsquo;on peut, \u00e0 lui aussi, lui donner une dimension m\u00e9tahistorique. Bien qu&rsquo;on puisse deviner vers o&ugrave; penchent mes sentiments, on comprendra que je ne dis pas cela par souci partisan mais pour bien faire mesurer la nature des forces qui font aujourd&rsquo;hui l&rsquo;histoire du monde, et comment un seul homme lui-m\u00eame, seul comme l&rsquo;\u00e9tait Tintin en 1927 para&icirc;t-il (vraiment, quelle dr\u00f4le de comparaison ! C&rsquo;est absolument pure dialectique de commentateur pseudo-pol\u00e9miste), &ndash; comment cet homme seul, en usant paradoxalement de son pouvoir quantitatif, balaye litt\u00e9ralement &lsquo;<em>Le r\u00e8gne de la quantit\u00e9<\/em>&lsquo; que d\u00e9non\u00e7ait Gu\u00e9non.<\/p>\n<\/p>\n<p><p>Et quant \u00e0 moi, avouez-le : mettre ensemble Carlson, Poutine, Gu\u00e9non et Tintin, ce n&rsquo;est pas commun ! Le texte que je vous pr\u00e9sente est, lui, de Martin Jay, sur &lsquo;<em>Strategic-Culture.org<\/em>&lsquo; de <a href=\"https:\/\/strategic-culture.su\/news\/2024\/02\/07\/carlson-interview-with-putin-could-topple-western-elites-end-ukraine-war\/\">ce 7 f\u00e9vrier 2024<\/a>, avec comme titre &laquo; <em>L&rsquo;interview de Poutine par Tucker Carlson peut renverser les \u00e9lites occidentales et terminer la guerre en Ukraine<\/em> &raquo;, et comme sous-titre &laquo; <em>Tucker Carlson est sur le point d&rsquo;apporter la v\u00e9rit\u00e9 au peuple am\u00e9ricain. Est-il pr\u00eat \u00e0 la recevoir ?<\/em>&raquo;, &ndash; ce qui, je crois, justifie le titre que je me suis permis de lui donner.<\/p>\n<\/p>\n<p><h4>PhG <em>&ndash; Semper Phi<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\"><strong>Les changera-t-il ?<\/strong><\/h2>\n<\/p>\n<p><p>Dans les ann\u00e9es 70, alors que la guerre froide atteignait son apog\u00e9e, Donald Rumsfeld \u00e9tait convaincu que l&rsquo;oc\u00e9an Atlantique, au large des c\u00f4tes am\u00e9ricaines, faisait \u00e9quipe avec les sous-marins russes. La marine am\u00e9ricaine ne pouvait pas les d\u00e9tecter car, il en \u00e9tait convaincu, les Sovi\u00e9tiques disposaient d&rsquo;une nouvelle &laquo; technologie acoustique &raquo; qui les rendait effectivement invisibles. Rumsfeld est all\u00e9 de l&rsquo;avant et a investi des milliards de dollars dans le d\u00e9veloppement d&rsquo;une nouvelle technologie capable de d\u00e9tecter les sous-marins non acoustiques. Mais cela a \u00e9chou\u00e9 et cela co&ucirc;te encore cher aux contribuables am\u00e9ricains. La v\u00e9rit\u00e9 \u00e9tait qu&rsquo;en fait, les sous-marins sovi\u00e9tiques n&rsquo;\u00e9taient tout simplement pas l\u00e0.<\/p>\n<\/p>\n<p><p>L&rsquo;erreur de Rumsfeld, pourrait-on dire, a quand m\u00eame port\u00e9 ses fruits, car effrayer le public am\u00e9ricain en lui faisant croire qu&rsquo;une menace est r\u00e9elle et imminente &ndash; \u00e0 votre porte en fait &ndash; est tr\u00e8s profitable pour un gouvernement qui souhaite atteindre deux objectifs clairs : verser des milliards dans les poches des entrepreneurs de la d\u00e9fense ; et deuxi\u00e8mement, attiser la peur d&rsquo;une guerre imminente avec un ennemi, dans le but affich\u00e9 de d\u00e9tourner l&rsquo;attention du public d&rsquo;une \u00e9conomie d\u00e9faillante et d&rsquo;une politique \u00e9trang\u00e8re \u00e9pouvantable.<\/p>\n<\/p>\n<p><p>Cela se produit aujourd&rsquo;hui. Si nous regardons les informations grand public, nous ne voyons que des discussions sur la guerre avec la Russie. Et pourtant, ces m\u00e9dias ne peuvent offrir la moindre information pour \u00e9tayer cette affirmation. Cela rappellera \u00e0 beaucoup les semaines qui ont pr\u00e9c\u00e9d\u00e9 l&rsquo;invasion de l&rsquo;Irak en 2003, lorsque les &Eacute;tats-Unis et le Royaume-Uni ont falsifi\u00e9 des informations pour montrer que Saddam Hussein poss\u00e9dait des armes de destruction massive.<\/p>\n<\/p>\n<p><p>Les \u00e9lites occidentales incitent les journalistes \u00e0 \u00e9crire ces absurdit\u00e9s, car leur plan principal est de susciter une fr\u00e9n\u00e9sie de discours de guerre afin de pr\u00e9parer le public \u00e0 des d\u00e9penses de d\u00e9fense bien plus importantes et, dans le cas du Royaume-Uni, \u00e0 la conscription elle-m\u00eame. Il s&rsquo;agit en r\u00e9alit\u00e9 de dissimuler l&rsquo;une des plus grandes erreurs de l&rsquo;histoire contemporaine commises par les gouvernements occidentaux &ndash; les sanctions contre la Russie et la campagne de l&rsquo;OTAN en Ukraine &ndash; qui se sont retourn\u00e9es contre eux de mani\u00e8re si spectaculaire que l&rsquo;administration Biden et un certain nombre de gouvernements de l&rsquo;UE sont unis dans cet alarmisme, croyant que c&rsquo;est la clef de la victoire.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, le &laquo; nous allons faire la guerre \u00e0 la Russie &raquo; vient de la Maison Blanche. De qui d&rsquo;autre? Seuls les &Eacute;tats-Unis disposent de ce genre de pouvoir, avec une UE de plus en plus l\u00e2che et path\u00e9tique, qui est d\u00e9sormais si servile vis-\u00e0-vis de l&rsquo;administration Biden qu&rsquo;elle commence \u00e0 faire ressembler le Royaume-Uni \u00e0 un caniche aux yeux des Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>Toute cette arnaque est am\u00e9ricaine et les Europ\u00e9ens s&rsquo;y pr\u00eatent largement. La seule possibilit\u00e9 r\u00e9elle de l&rsquo;\u00e9chec de ce plan peut venir de ce que, de quelques coins \u00e9loign\u00e9s et sauvages des m\u00e9dias, des non-conformistes qui ont \u00e9t\u00e9 licenci\u00e9s par les g\u00e9ants de la presseSyst\u00e8me prennent position et d\u00e9noncent le probl\u00e8me pour ce qu&rsquo;il est. C&rsquo;est pourquoi le voyage de Tucker Carlson \u00e0 Moscou, o&ugrave; il a l&rsquo;intention d&rsquo;interroger Poutine, est si important et constitue une telle menace pour l&rsquo;administration Biden et les \u00e9lites occidentales dans leur ensemble. Lorsque Carlson interviewera le dirigeant russe et qu&rsquo;il deviendra clair que les m\u00e9dias occidentaux mentent depuis si longtemps sur la guerre en Ukraine et m\u00eame sur cette derni\u00e8re ruse de la Russie qui veut envahir l&rsquo;Europe de l&rsquo;Est, alors toute l&rsquo;arnaque s&rsquo;effondrera.<\/p>\n<\/p>\n<p><p>Il est clair que l&rsquo;Occident s&rsquo;inqui\u00e8te de cette interview. Ils ont d\u00e9j\u00e0 fait venir suffisamment de membres du Congr\u00e8s sur les r\u00e9seaux sociaux pour tenter de pr\u00e9senter Carlson comme une sorte de tra&icirc;tre qui ne devrait pas \u00eatre autoris\u00e9 \u00e0 revenir aux &Eacute;tats-Unis. Les m\u00e9dias occidentaux ne rendront probablement pas compte de l&rsquo;interview, mais cela ne fera que lui donner un plus grand succ\u00e8s sur les r\u00e9seaux sociaux. L&rsquo;entretien est en r\u00e9alit\u00e9 la seule opportunit\u00e9 pour arr\u00eater cette folle machine de guerre, pour que les mensonges soient r\u00e9v\u00e9l\u00e9s et pour qu&rsquo;une approche plus marquante des relations Est-Ouest puisse commencer. Il ne faut pas le sous-estimer. Mais les couteaux sont sortis. Regardez en particulier les correspondants des m\u00e9dias occidentaux int\u00e9gr\u00e9s qui vivent \u00e0 Moscou enfoncer la lame dans le dos de Carlson et se moquer de l&rsquo;interview dans le but de discr\u00e9diter l&rsquo;ensemble. Des dizaines de millions d&rsquo;Am\u00e9ricains sont sur le point d&rsquo;\u00eatre \u00e9clair\u00e9s sur une multitude de questions sur lesquelles, jusqu&rsquo;\u00e0 pr\u00e9sent, leurs propres m\u00e9dias leur ont menti. Qualifier cette interview de bombe serait un euph\u00e9misme. Tucker Carlson est sur le point d&rsquo;apporter la v\u00e9rit\u00e9 au peuple am\u00e9ricain. Mais sont-ils pr\u00eats pour cela ?<\/p>\n<\/p>\n<p><h4>Martin Jay<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tucker for ever 7 f\u00e9vrier 2024 (17H20) &ndash; L&rsquo;aventure de Tucker Carlson \u00e0 Moscou a quelque chose de Tintin. (A part que &lsquo;Carlson chez Poutine&rsquo; n&rsquo;est vraiment pas dans le m\u00eame sens que &lsquo;Tintin chez les Soviets&lsquo; ! &ndash; si l&rsquo;on prend les choses id\u00e9ologiquement, d&rsquo;ailleurs d&rsquo;une fa\u00e7on compl\u00e8tement d\u00e9phas\u00e9e et sans le moindre rapport&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2972,13656,11295,3502,916,2730,8746],"class_list":["post-80929","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-carlson","tag-intereview","tag-jay","tag-martin","tag-poutine","tag-russie","tag-tucker"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80929"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80929\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}