{"id":80937,"date":"2024-02-15T08:26:35","date_gmt":"2024-02-15T08:26:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/02\/15\/ukraine-lindsey-graham-a-180\/"},"modified":"2024-02-15T08:26:35","modified_gmt":"2024-02-15T08:26:35","slug":"ukraine-lindsey-graham-a-180","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/02\/15\/ukraine-lindsey-graham-a-180\/","title":{"rendered":"Ukraine\u00a0: Lindsey Graham \u00e0 180\u00b0"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Ukraine : Lindsey Graham \u00e0 180&deg;<\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Surprise, surprise : le s\u00e9nateur r\u00e9publicain Graham, le plus pro-Zelenski des apparent\u00e9s <em>neocon<\/em>, est contre l&rsquo;aide que Biden et les <em>neocon <\/em>veulent envoyer \u00e0 Zelenski. &bull; La sc\u00e8ne politique US est fluide. &bull; Avec un texte de John Miles.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>On ne peut dissimuler le fait que cet \u00e9v\u00e9nement est une surprise consid\u00e9rable, une nouvelle tout \u00e0 fait inattendue. Comme les nouvelles r\u00e9elles et plut\u00f4t \u00e0 contre sens du Syst\u00e8me aujourd&rsquo;hui, elle met du temps \u00e0 \u00e9merger parce que la presseSyst\u00e8me n&rsquo;en fait pas ses choux gras.<\/p>\n<\/p>\n<p><p>D\u00e8s lundi, on crie victoire pour l&rsquo;aide de 61 $milliards pour l&rsquo;Ukraine (plus une trentaine de $milliards \u00e0 Isra\u00ebl) parce que le vote pr\u00e9liminaire au S\u00e9nat a \u00e9t\u00e9 positif, mais l&rsquo;on d\u00e9couvre (le lendemain) que le <em>Speaker <\/em>et pr\u00e9sident de la Chambre Johnson n&rsquo;est pas du tout d&rsquo;accord pour la faire voter par son assembl\u00e9e, et surtout (le surlendemain) que le s\u00e9nateur Lindsey Graham (avec un \u00ab\u00a0e\u00a0\u00bb et non un \u00ab\u00a0a\u00a0\u00bb comme nous l&rsquo;\u00e9crivons depuis des ann\u00e9es) n&rsquo;a pas vot\u00e9 cette loi et semble abandonner la cause ukrainienne. Le Washington &lsquo;<em>Post<\/em>&lsquo; lui-m\u00eame s&rsquo;est fendu d&rsquo;un article <a href=\"https:\/\/www.washingtonpost.com\/politics\/2024\/02\/14\/lindsey-graham-ukraine-trump\/\">vivement critique<\/a>, vitup\u00e9rant le s\u00e9nateur r\u00e9publicain tra&icirc;tre aux <em>neocon<\/em>.<\/p>\n<\/p>\n<p><p>Si l&rsquo;on accorde plus d&rsquo;importance, comme on le devine, \u00e0 la d\u00e9cision d&rsquo;un seul parlementaire (Graham) qu&rsquo;\u00e0 celle d&rsquo;un homme qui dirige la Chambre sans laquelle la loi voulue par le S\u00e9nat n&rsquo;a aucune chance, c&rsquo;est parce qu&rsquo;il s&rsquo;agit d&rsquo;un symbole consid\u00e9rable d&rsquo;une politique annon\u00e7ant une orientation peut-\u00eatre nouvelle pour cette politique. Nous avons souvent parl\u00e9 de Graham : lisez ce que nous en disions <a href=\"https:\/\/www.dedefensa.org\/article\/un-ami-du-genre-humain-facon-mister-z\">le 21 d\u00e9cembre 2023<\/a>, apr\u00e8s d&rsquo;autres textes du <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2023-un-ami-de-trump\">18 mai 2023<\/a> ou bien du <a href=\"https:\/\/www.dedefensa.org\/article\/les-quatre-minutes-de-verite-du-senateur-graham\">23 septembre 2018<\/a>.<\/p>\n<\/p>\n<p><p>Nous avons toujours mis en avant l&rsquo;ambivalence consid\u00e9rable du personnage, entre son soutien \u00e0 Trump et son action int\u00e9rieure furieuse contre les actions des d\u00e9mocrates pour d\u00e9truire Trump, et d&rsquo;autre part son soutien ind\u00e9fectible, hyst\u00e9rique, fou, au-del\u00e0 de toute mesure, aux guerres ext\u00e9rieures de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, si ch\u00e8re aux d\u00e9mocrates et d\u00e9nonc\u00e9e par Trump&#8230; L&rsquo;on pouvait ainsi \u00e9crire le 18 mai 2023 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le cas de Graham nous retient essentiellement par rapport \u00e0 ses positions favorables \u00e0 l&rsquo;Ukraine et f\u00e9rocement antirussistes, alors qu&rsquo;il d\u00e9nonce le &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/le-poids-colossal-du-simulacre-russiagate\">Russiagate<\/a>&lsquo; qui est la voie psychologique principale menant, aux USA, au soutien sinon au d\u00e9clenchement de la guerre en Ukraine. Certaines interpr\u00e9tations sont tentantes \u00e0 propos de Graham, sur base d&rsquo;une op\u00e9ration de d\u00e9sinformation, ou complotiste si l&rsquo;on veut. On en donne ici une esquisse sommaire mais tr\u00e8s significative, venue d&rsquo;un lecteur <a href=\"https:\/\/www.rt.com\/news\/576411-graham-says-mainstream-media-is-dead\/\">du texte de RT.com<\/a> dont nous avons donn\u00e9 un large extrait :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Graham est un homme rus\u00e9. Il parle comme un conservateur l\u00e9gitime sur les questions int\u00e9rieures pour s&rsquo;attirer les faveurs des conservateurs am\u00e9ricains, et c&rsquo;est son app\u00e2t ; cependant, il change constamment d&rsquo;objectif pour manipuler l&rsquo;\u00e9lan conservateur en soutenant des guerres malhonn\u00eates pour un gouvernement qui, sur le plan int\u00e9rieur, agit tra&icirc;treusement avec les conservateurs. Graham est un monstre. Il est comme un s\u00e9ducteur d&rsquo;enfants qui enseigne aux enfants de six ans \u00e0 aimer les adultes qui les violent\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais le cas est ici diff\u00e9rent de ces interpr\u00e9tations, soir interrogatives, soit diffamatoires. Graham affirme certes son soutien complet \u00e0 Trump qu&rsquo;il juge \u00eatre dans une position irr\u00e9sistible&#8230;. Rien de vraiment original dans une telle posture man&oelig;uvri\u00e8re. Mais il le fait en laissant tomber Zelenski et l&rsquo;Ukraine apr\u00e8s avoir soutenu quasi-hyst\u00e9riquement cette cause guerri\u00e8re, &ndash; et cela, voil\u00e0 qui est compl\u00e8tement nouveau (de m\u00eame que cela nous en dit beaucoup sur la d\u00e9termination de Trump de parvenir \u00e0 liquider le conflit ukrainien). L&rsquo;important au niveau du Congr\u00e8s, c&rsquo;est que la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> perd l&rsquo;un de ses principaux meneurs, l&rsquo;un des plus influents et des plus efficaces. Cela renforce notablement le courant anti-guerre chez les r\u00e9publicains ; pour l&rsquo;imm\u00e9diat, cela nous signifie que Zelenski est loin d&#8217;emporter la victoire pour cette aide de 61 $milliards des USA.<\/p>\n<\/p>\n<p><p>&#8230; Quant \u00e0 l&rsquo;explication du changement d&rsquo;attitude de Graham, outre le poids de l&rsquo;influence de Trump et la puissance de sa position chez les r\u00e9publicains, le champ reste ouvert \u00e0 des hypoth\u00e8ses moins conventionnelles tant cette <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> et les soutiens <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivistes<\/a> qu&rsquo;elle suscite restent en partie une \u00e9nigme pour la raison.<\/p>\n<\/p>\n<p><p>Ci-apr\u00e8s, un texte de John Miles <a href=\"https:\/\/sputnikglobe.com\/20240214\/lindsey-grahams-about-face-on-ukraine-shows-gop-patience-with-kiev-regime-has-run-out-1116788385.html\">du 14 f\u00e9vrier<\/a> sur l&rsquo;\u00e9v\u00e9nement de la prise de position de Lindsey Graham.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>__________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Zelenski perd un soutien de poids<\/strong><\/h2>\n<\/p>\n<p><p>Lindsey Graham (SC-R), longtemps consid\u00e9r\u00e9 comme l&rsquo;un des principaux d\u00e9fenseurs d&rsquo;une politique \u00e9trang\u00e8re am\u00e9ricaine muscl\u00e9e au S\u00e9nat am\u00e9ricain, a provoqu\u00e9 une grande sensation  cette semaine lorsqu&rsquo;il a vot\u00e9 \u00e0 plusieurs reprises contre une aide financi\u00e8re pour l&rsquo;armement de l&rsquo;Ukraine et d&rsquo;Isra\u00ebl.<\/p>\n<\/p>\n<p><p>Les observateurs ont \u00e9t\u00e9 surpris par la volte-face du l\u00e9gislateur de Caroline du Sud sur la question, \u00e9tant donn\u00e9 que Graham \u00e9tait l&rsquo;un des principaux n\u00e9gociateurs du projet de loi de compromis. Face aux inqui\u00e9tudes suscit\u00e9es par le grand nombre de migrants \u00e0 la fronti\u00e8re sud des &Eacute;tats-Unis, les conservateurs de base ont soutenu \u00e0 plusieurs reprises que la r\u00e9forme de l&rsquo;immigration \u00e9tait une pr\u00e9occupation plus urgente que la poursuite du financement des alli\u00e9s \u00e9trangers.<\/p>\n<\/p>\n<p><p>De longues discussions ont eu lieu au d\u00e9but de cette ann\u00e9e, au cours desquelles Graham a travaill\u00e9 avec un groupe bipartite de s\u00e9nateurs pour r\u00e9pondre aux probl\u00e8mes de s\u00e9curit\u00e9 aux fronti\u00e8res dans le cadre de l&rsquo;\u00e9volution du programme d&rsquo;aide \u00e9trang\u00e8re. Mais ces derniers jours, les politiques de l&rsquo;ann\u00e9e \u00e9lectorale ont apparemment fait d\u00e9railler la l\u00e9gislation de compromis, les r\u00e9publicains align\u00e9s sur Trump cherchant \u00e0 priver Biden d&rsquo;une victoire l\u00e9gislative per\u00e7ue avec l&rsquo;adoption d&rsquo;une r\u00e9forme de l&rsquo;immigration tant recherch\u00e9e.<\/p>\n<\/p>\n<p><p>Mais au-del\u00e0 des al\u00e9as capricieux de la politique am\u00e9ricaine, une autre dynamique est \u00e0 l&rsquo;&oelig;uvre, puisque m\u00eame les \u00ab\u00a0faucons\u00a0\u00bb de la politique \u00e9trang\u00e8re comme Graham ont fini par se rendre compte que la guerre par procuration de l&rsquo;Ukraine contre la Russie, soutenue par les &Eacute;tats-Unis, a \u00e9chou\u00e9.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9chec de cet effort sur le champ de bataille est \u00e9vident depuis longtemps, la fameuse \u00ab\u00a0contre-offensive\u00a0\u00bb ukrainienne de l&rsquo;ann\u00e9e derni\u00e8re dans le Donbass n&rsquo;ayant pas r\u00e9ussi \u00e0 progresser contre les forces russes. M\u00eame les m\u00e9dias am\u00e9ricains ont eu du mal \u00e0 d\u00e9crire de mani\u00e8re positive le d\u00e9clin de l&rsquo;arm\u00e9e ukrainienne.<\/p>\n<\/p>\n<p><p>Mais plus r\u00e9cemment, le conflit par procuration US en Ukraine a \u00e9galement connu un \u00e9chec politique.<\/p>\n<\/p>\n<p><p>&laquo; J&rsquo;ai parl\u00e9 au pr\u00e9sident [Donald] Trump aujourd&rsquo;hui et il est fermement oppos\u00e9 \u00e0 ce plan [d&rsquo;aide \u00e9trang\u00e8re] &raquo;, a expliqu\u00e9 Graham dimanche. &laquo; Il pense que nous devrions faire de ce genre de livraison d&rsquo;armes un pr\u00eat et non un don. &raquo;<\/p>\n<\/p>\n<p><p>Le tournant complet de Graham, qui avait insist\u00e9 il y a moins d&rsquo;un an pour que le pr\u00e9sident am\u00e9ricain Joe Biden redouble d&rsquo;efforts pour aider le pr\u00e9sident ukrainien en difficult\u00e9 Zelenski lors d&rsquo;une visite \u00e0 Kiev, sugg\u00e8re qu&rsquo;un changement sismique est en cours concernant le soutien am\u00e9ricain \u00e0 l&rsquo;Ukraine, et peut-\u00eatre la politique \u00e9trang\u00e8re am\u00e9ricaine dans son ensemble.<\/p>\n<\/p>\n<p><p>L&rsquo;ancien pr\u00e9sident Trump a remport\u00e9 la victoire en 2016 en partie gr\u00e2ce \u00e0 son programme \u00ab\u00a0America First\u00a0\u00bb, promettant de se concentrer sur les pr\u00e9occupations int\u00e9rieures plut\u00f4t que sur les guerres \u00e9trang\u00e8res. Trump a s\u00e9v\u00e8rement critiqu\u00e9 la guerre en Irak de 2003, contre l&rsquo;avis de l&rsquo;establishment r\u00e9publicain et des grands m\u00e9dias am\u00e9ricains. Au milieu de la lassitude suscit\u00e9e par l&rsquo;engagement militaire am\u00e9ricain au Moyen-Orient qui dure depuis des ann\u00e9es, le message a trouv\u00e9 un \u00e9cho aupr\u00e8s des \u00e9lecteurs.<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui, alors que le pr\u00e9sident d\u00e9mocrate Joe Biden pr\u00e9side les conflits soutenus par les &Eacute;tats-Unis en Ukraine et en Isra\u00ebl, le sentiment anti-guerre s&rsquo;est \u00e0 nouveau rassembl\u00e9 derri\u00e8re le mouvement MAGA de Trump.<\/p>\n<\/p>\n<p><p>&laquo; S&rsquo;opposer \u00e0 Trump [sur le financement de l&rsquo;Ukraine] en ce moment est une condamnation \u00e0 mort &raquo;, a fait remarquer un d\u00e9put\u00e9 r\u00e9publicain anonyme, soulignant le changement politique au sein de la base du parti contre le soutien \u00e0 Kiev. Le nouveau paradigme conservateur de politique \u00e9trang\u00e8re menace \u00e9galement de porter atteinte \u00e0 l&rsquo;OTAN, Trump insistant sur le fait que les pays europ\u00e9ens devraient contribuer davantage de leurs propres fonds \u00e0 l&rsquo;alliance militaire dirig\u00e9e par les &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Les n\u00e9oconservateurs am\u00e9ricains ne sont pas les seuls \u00e0 faire face r\u00e9cemment \u00e0 un rejet politique. Le pr\u00e9sident Zelenski est confront\u00e9 \u00e0 sa propre crise, avec des personnalit\u00e9s \u00e9minentes \u00e0 l&rsquo;int\u00e9rieur et \u00e0 l&rsquo;ext\u00e9rieur de son gouvernement signalant une opposition croissante \u00e0 l&rsquo;\u00e9chec de son effort de guerre. Les observateurs pensent qu&rsquo;un coup d&rsquo;&Eacute;tat de palais est imminent alors que le dirigeant ukrainien s&rsquo;efforce d&rsquo;\u00e9liminer l&rsquo;opposition au sein de son cabinet.<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.washingtonpost.com\/politics\/2024\/02\/14\/lindsey-graham-ukraine-trump\/\">Le m\u00e9contentement<\/a> du Washington Post face au revirement politique du s\u00e9nateur Graham n&rsquo;est pas surprenant, \u00e9tant donn\u00e9 que le propri\u00e9taire du m\u00e9dia, Jeff Bezos, est l&rsquo;un des plus grands sous-traitants de la Central Intelligence Agency des &Eacute;tats-Unis. Si Graham reconna&icirc;t apparemment que la victoire de la Russie n&rsquo;est qu&rsquo;une question de temps, Langley n&rsquo;aura sans doute plus d&rsquo;autres options que de critiquer les l\u00e9gislateurs par l&rsquo;interm\u00e9diaire de ses porte-parole m\u00e9diatiques.<\/p>\n<\/p>\n<p><p>Les r\u00e9publicains, quant \u00e0 eux, semblent pr\u00eats \u00e0 se pr\u00e9senter contre le pr\u00e9sident Biden, dans un contexte de crise \u00e0 la fronti\u00e8re sud des &Eacute;tats-Unis et \u00e0 Kiev.<\/p>\n<\/p>\n<p><h4>John Miles<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ukraine : Lindsey Graham \u00e0 180&deg; &bull; Surprise, surprise : le s\u00e9nateur r\u00e9publicain Graham, le plus pro-Zelenski des apparent\u00e9s neocon, est contre l&rsquo;aide que Biden et les neocon veulent envoyer \u00e0 Zelenski. &bull; La sc\u00e8ne politique US est fluide. &bull; Avec un texte de John Miles. _________________________ On ne peut dissimuler le fait que cet&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3005,3961,13239,6518,3531,11084,2639,1296,2829],"class_list":["post-80937","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-graham","tag-john","tag-lindsey","tag-miles","tag-senat","tag-tournant","tag-trump","tag-ukraine","tag-zelenski"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80937"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80937\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}