{"id":80944,"date":"2024-02-20T16:28:47","date_gmt":"2024-02-20T16:28:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/02\/20\/poutine-pourquoi-biden\/"},"modified":"2024-02-20T16:28:47","modified_gmt":"2024-02-20T16:28:47","slug":"poutine-pourquoi-biden","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/02\/20\/poutine-pourquoi-biden\/","title":{"rendered":"Poutine, pourquoi Biden\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Poutine, pourquoi Biden ?<\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; C&rsquo;est un d\u00e9bat qui nous para&icirc;t bien difficile \u00e0 trancher : pourquoi Poutine pr\u00e9f\u00e8re-t-il Biden \u00e0 Trump ? &bull; Andrew Korybko a une r\u00e9ponse assur\u00e9e : il juge ce choix comme celui de la raison m\u00eame. &bull; On l&rsquo;\u00e9coute mais on peut en douter.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>On d\u00e9bat toujours, <em>in fine <\/em>ou \u00e0 c&oelig;ur ouvert, sur les raisons pour lesquelles Poutine a d\u00e9clar\u00e9 \u00e0 Tucker Carlson, lors de la fameuse interview, qu&rsquo;il serait \u00ab\u00a0plus conforme aux int\u00e9r\u00eats russes\u00a0\u00bb que Biden soit r\u00e9\u00e9lu, plut\u00f4t que Trump (r\u00e9\u00e9lu aussi, mais en sautant un coup). Voici la th\u00e8se de <a href=\"https:\/\/korybko.substack.com\/p\/its-reasonable-for-putin-to-prefer\">Andrew Korybko<\/a>, qui juge tr\u00e8s logique le choix de Biden. On donne ici sa conclusion, qui reprend le corps de son article qu&rsquo;on trouve apr\u00e8s ce texte de pr\u00e9sentation.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;  <em>Pour r\u00e9sumer, le pr\u00e9sident Poutine pr\u00e9f\u00e8re Biden \u00e0 Trump parce que : 1) Biden a le soutien des lib\u00e9raux-globalistes au pouvoir au sein de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb ; 2) cette faction devrait rester au pouvoir m\u00eame si Trump gagne ; et 3) ils pourraient proc\u00e9der \u00e0 davantage de provocations antirusses pour le discr\u00e9diter dans cette affaire, tout comme la derni\u00e8re fois. Il est bien pr\u00e9f\u00e9rable pour la Russie de jouer la prudence et de formuler sa politique en partant du principe que ses liens avec les &Eacute;tats-Unis pourraient se d\u00e9t\u00e9riorer plut\u00f4t que de se livrer une fois de plus na\u00efvement \u00e0 des v&oelig;ux pieux selon lesquels ils pourraient s&rsquo;am\u00e9liorer<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Comme l&rsquo;on sait, Korybko est un homme de raison et de mesure. Il d\u00e9fend d&rsquo;une fa\u00e7on tr\u00e8s nette un choix qui a g\u00e9n\u00e9ralement \u00e9t\u00e9 incompris, ou vu comme une man&oelig;uvre de Poutine pour d\u00e9douaner Trump de toute accusation de prorussisme.<\/p>\n<\/p>\n<p><p>Pour notre compte, nous avions choisi la case \u00ab\u00a0\u00e9nigme\u00a0\u00bb pour juger de la r\u00e9ponse de Poutine. C&rsquo;est une r\u00e9ponse qui est une fa\u00e7on de ne pas r\u00e9pondre, ce qui correspond \u00e0 notre sentiment : non pas que le choix de Poutine soit incompr\u00e9hensible, mais parce qu&rsquo;il est compr\u00e9hensible de plusieurs fa\u00e7ons plus ou moins tordues et que nous ne distinguons pas laquelle nous para&icirc;t la plus acceptable ; comme PhG l&rsquo;\u00e9crivait <a href=\"https:\/\/www.dedefensa.org\/article\/le-ping-pong-poutine-trump\">le 16 f\u00e9vrier<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Mais enfin, tout cela reste du domaine de l&rsquo;hypoth\u00e8se, et certains peuvent \u00e0 juste titre les juger un peu trop complexes, un peu  trop sollicit\u00e9es, alors que les Russes nous ont habitu\u00e9s \u00e0 des politiques droites et claires. (Mais il faut voir aussi que Poutine affirme quelque part, voire \u00e0 deux reprises, \u00ab\u00a0Il peut se passer n&rsquo;importe quoi aux USA\u00a0\u00bb ; cela justifie \u00e9ventuellement qu&rsquo;on fasse un peu plus complexes qu&rsquo;\u00e0 l&rsquo;habitude&#8230;) Il n&rsquo;en reste pas moins, &ndash; constat d&rsquo;\u00e9vidence qui fait une bonne conclusion, &ndash; que l&rsquo;on reste devant cette \u00e9nigme du choix proclam\u00e9 du prochain pr\u00e9sident des USA, dans le chef du pr\u00e9sident de la F\u00e9d\u00e9ration de Russie<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les trois arguments donn\u00e9s par Korybko sont \u00e0 notre avis contestables ; pas mauvais ni faux mais pour le moins sollicit\u00e9s, et notamment parce qu&rsquo;ils s&rsquo;appuient des  \u00ab\u00a0faits\u00a0\u00bb dont nous savons tous qu&rsquo;ils sont ind\u00e9finissables, sinon insaisissables\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>1). Il est vrai que Biden est l&rsquo;homme des globalistes, mais est-il celui de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb ? Qu&rsquo;est-ce que c&rsquo;est pr\u00e9cis\u00e9ment que \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb ? Est-il assur\u00e9 que les globalistes y sont majoritaires ? Autant de questions impr\u00e9cises auxquelles il est bien difficile de donner une r\u00e9ponse pr\u00e9cise.<\/p>\n<\/p>\n<p><p>Si l&rsquo;on dit que Trump est ha\u00ef par l&rsquo;<em>establishment <\/em>politique, les salons new-yorkais et les d\u00e9mocrates, c&rsquo;est sans aucun doute vrai. Mais personne ne peut nous d\u00e9montrer que \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb se trouve dans ce seul cadre.<\/p>\n<\/p>\n<p><p>2) La deuxi\u00e8me affirmation (M\u00eame si Trump gagne, \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb reste au pouvoir et il ne pourra rien contre lui) rencontre le m\u00eame vague concernant la chose incertaine qu&rsquo;est \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb, \u00e0 laquelle on ajoute la contestation de l&rsquo;affirmation \u00ab\u00a0Ce sera comme la premi\u00e8re fois\u00a0\u00bb, &ndash; parce que Trump a acquis une certaine exp\u00e9rience, surtout dans le choix de ses collaborateurs, et parce que la division extraordinaire qui r\u00e8gne actuellement aux USA avec la mont\u00e9e du populisme chez les r\u00e9publicains, soutenu par des puissances non n\u00e9gligeables et des grosses fortunes, fait encore plus douter de l&rsquo;identit\u00e9, de l&rsquo;engagement, voire de ;l&rsquo;existence en tant que tel de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb comme chose unitaire.<\/p>\n<\/p>\n<p><p>Par ailleurs, s&rsquo;il s&rsquo;av\u00e8re vraiment comme le laisse entendre en partie Korybko que Poutine d\u00e9couvre l&rsquo;existence de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb , presque soixante ans aptes le discours d&rsquo;Eisenhower sur le complexe militaro-industriel  et la liquidation de Kennedy, ce n&rsquo;est plus de na\u00efvet\u00e9 qu&rsquo;il faut parler&#8230;<\/p>\n<\/p>\n<p><p>3) Questions \u00ab\u00a0provocations antirusses\u00a0\u00bb, Biden n&rsquo;est pas mal dans son genre, et m\u00eame sup\u00e9rieur \u00e0 Trump selon notre point de vue (dire dans un discours tonitruant, &ndash; Varsovie, mars 2022, &ndash; qu&rsquo;il faut aller jusqu&rsquo;\u00e0 Moscou pour balancer Poutine aux oubliettes). Par ailleurs, le &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/le-poids-colossal-du-simulacre-russiagate\"><em>Russiagate<\/em><\/a>&lsquo; lanc\u00e9 contre Trump l&rsquo;a \u00e9t\u00e9 en juillet 2016 par l&rsquo;\u00e9quipe d&rsquo;Hillary Clinton pour \u00e9touffer le scandale des courriels officiels d&rsquo;Hillary secr\u00e9taire d&rsquo;Etat, utilis\u00e9s pour ses affaires personnelles&#8230; Tout le reste est la routine des simulacres, aliment\u00e9e par le  z\u00e8le du couple CIA-MI6 et par la haine proprement extraordinaire qui s&rsquo;est d\u00e9velopp\u00e9e contre Trump, qui ne d\u00e9pend pas de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb mais de l&rsquo;h\u00f4pital psychiatrique&#8230;<\/p>\n<\/p>\n<p><p>Alors quoi ? Une \u00e9nigme, vous dit-on&#8230; Peut-\u00eatre Poutine croit-il vraiment les affabulations sur les emportements de Trump qui tirerait un ICBM \u00e0 t\u00eates nucl\u00e9aires pour animer sa partie de golf d&rsquo;un week-end ? Alors il pourrait s&rsquo;int\u00e9resser vraiment au comportement cognitif de Biden malgr\u00e9 son estime pour \u00ab\u00a0la vieille \u00e9cole\u00a0\u00bb dont Biden ne fait pourtant pas partie, n&rsquo;ayant fait partie d&rsquo;aucune \u00e9cole. On esp\u00e8re que le FSB lui en a tout de m\u00eame dit un peu plus sur Biden.<\/p>\n<\/p>\n<p><p>Finalement, l&rsquo;hypoth\u00e8se la plus passionnante et la plus s\u00e9duisante, mais la plus improbable si l&rsquo;on consid\u00e8re le caract\u00e8re de prudence de Poutine, nous l&rsquo;avons trouv\u00e9 dans un commentaire d&rsquo;un lecteur de RT.com, et surtout dans cet article (<a href=\"https:\/\/english.pravda.ru\/world\/158969-putin_biden_trump\/\">16 f\u00e9vrier<\/a>) de &lsquo;<em>Pravda.ru<\/em>&lsquo;. En gros, cela revient \u00e0 dire : gardons Joe encore quatre ans, et il foutra l&rsquo;Am\u00e9rique par terre, selon la fameuse sentence d&rsquo;Obama (&laquo; <em>Il ne faut jamais sous-estimer la capacit\u00e9 de Joe de foutre la merde<\/em> &raquo;), &ndash; titre et sous-titre de l&rsquo;article r\u00e9f\u00e9renc\u00e9 en toute libert\u00e9 de la presse :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Poutine veut que Biden reste au pouvoir pour provoquer la chute de l&#8217;empire am\u00e9ricain<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Poutine pr\u00e9f\u00e8re Biden parce qu&rsquo;il est en train de ruiner l&rsquo;Am\u00e9rique de l&rsquo;int\u00e9rieur<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Mais il ne faut pas trop r\u00eaver et bien mesurer la prudence de renard du pr\u00e9sident russe. Il est assez probable, &ndash; m\u00eame si cela n&rsquo;est pas assur\u00e9, &ndash; que Poutine serait plus inquiet que satisfait si les USA s&rsquo;effondraient&#8230; Ci-apr\u00e8s, le texte de Korybko de <a href=\"https:\/\/korybko.substack.com\/p\/its-reasonable-for-putin-to-prefer\">ce 20 f\u00e9vrier<\/a>.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Biden plut\u00f4t que Trump: un choix raisonnable<\/strong><\/h2>\n<\/p>\n<p><p>La plupart des m\u00e9dias grand public et de la communaut\u00e9 des m\u00e9dias alternatifs conviennent que la pr\u00e9f\u00e9rence du pr\u00e9sident Poutine pour Biden plut\u00f4t que pour Trump est un &laquo; plan directeur d&rsquo;\u00e9checs en 5D &raquo; visant \u00e0 discr\u00e9diter le pr\u00e9sident sortant en raison de son soutien secret au favori r\u00e9publicain. Le dirigeant russe a expliqu\u00e9 que &laquo; [Biden] est une personne plus exp\u00e9riment\u00e9e et plus pr\u00e9visible, c&rsquo;est un politicien de l&rsquo;ancien type &raquo;. Il a \u00e9galement d\u00e9fendu les capacit\u00e9s cognitives de son homologue en r\u00e9it\u00e9rant les arguments qu&rsquo;il avait avanc\u00e9s apr\u00e8s leur sommet de l&rsquo;\u00e9t\u00e9 2021.<\/p>\n<\/p>\n<p><p>M\u00eame si Biden supervise officiellement la guerre par procuration de l&rsquo;OTAN contre la Russie \u00e0 travers l&rsquo;Ukraine, contre laquelle Trump s&rsquo;est \u00e9lev\u00e9 depuis le d\u00e9but et a affirm\u00e9 qu&rsquo;elle prendrait fin imm\u00e9diatement s&rsquo;il revenait au pouvoir, le pr\u00e9sident Poutine le pr\u00e9f\u00e8re toujours \u00e0 son adversaire pour plusieurs raisons l\u00e9gitimes. Pour commencer, Biden est la figure de proue de ces membres puissants des bureaucraties militaires, de renseignement et diplomatiques permanentes (\u00ab\u00a0&Eacute;tat profond\u00a0\u00bb) qui formulent et mettent r\u00e9ellement en &oelig;uvre la politique am\u00e9ricaine, qui le soutiennent tout en s&rsquo;opposant \u00e0 Trump.<\/p>\n<\/p>\n<p><p>La d\u00e9cision de la faction lib\u00e9rale-globaliste au pouvoir de donner la priorit\u00e9 \u00e0 l&rsquo;endiguement de la Russie plut\u00f4t qu&rsquo;\u00e0 la Chine va \u00e9videmment \u00e0 l&rsquo;encontre des int\u00e9r\u00eats de Moscou, contrairement aux plans de leurs rivaux nationalistes conservateurs qui donnent la priorit\u00e9 \u00e0 l&rsquo;endiguement de la Chine plut\u00f4t qu&rsquo;\u00e0 la Russie, mais c&rsquo;est pr\u00e9cis\u00e9ment en raison de leur pouvoir qu&rsquo;ils sont pr\u00e9visibles. Le pr\u00e9sident Poutine a mis en garde les pr\u00e9visionnistes strat\u00e9giques russes contre les v&oelig;ux pieux \u00e0 l&rsquo;\u00e9t\u00e9 2022, apr\u00e8s quoi il a admis sa na\u00efvet\u00e9 \u00e0 l&rsquo;\u00e9gard de l&rsquo;Occident quelques mois en d\u00e9cembre dernier.<\/p>\n<\/p>\n<p><p>Ces observations nous am\u00e8nent au deuxi\u00e8me point, \u00e0 savoir que le Kremlin a probablement conclu que la faction lib\u00e9rale-globaliste au pouvoir, responsable de la guerre par procuration de l&rsquo;OTAN contre la Russie \u00e0 travers l&rsquo;Ukraine, resterait au pouvoir dans un avenir pr\u00e9visible, m\u00eame si Trump revenait. L&rsquo;ancien pr\u00e9sident s&rsquo;est montr\u00e9 incapable de purger \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb de ces forces subversives qui ont sabot\u00e9 son rapprochement envisag\u00e9 avec la Russie, cens\u00e9 faciliter l&rsquo;endiguement de la Chine. Le pr\u00e9c\u00e9dent sugg\u00e8re donc qu&rsquo;il \u00e9chouera \u00e0 nouveau.<\/p>\n<\/p>\n<p><p>Comme le dit le proverbe, &laquo; mieux vaut le diable que l&rsquo;on conna&icirc;t que le diable que l&rsquo;on ne conna&icirc;t pas &raquo;, et les dirigeants russes semblent prendre cet adage \u00e0 c&oelig;ur lorsqu&rsquo;il s&rsquo;agit des &Eacute;tats-Unis. Le pr\u00e9sident Poutine a d\u00e9j\u00e0 \u00e9t\u00e9 tromp\u00e9 \u00e0 maintes reprises par l&rsquo;Occident, au point qu&rsquo;il est extr\u00eamement sensible \u00e0 l&rsquo;id\u00e9e de se laisser duper une fois de plus. C&rsquo;est pourquoi il pr\u00e9f\u00e8re supposer que rien ne s&rsquo;am\u00e9liorera plut\u00f4t que d&rsquo;esp\u00e9rer pour rien. Il serait \u00e9galement tr\u00e8s irresponsable de formuler une politique bas\u00e9e \u00e9galement sur des v&oelig;ux pieux.<\/p>\n<\/p>\n<p><p>La derni\u00e8re raison pour laquelle le dirigeant russe soutient la r\u00e9\u00e9lection de son homologue am\u00e9ricain est qu&rsquo;il pourrait y avoir moins de risques de provocations inattendues que si Trump revenait au pouvoir. La seule cause pour laquelle la th\u00e9orie du complot farfelue du Russiagate a \u00e9t\u00e9 concoct\u00e9e par les mandataires d\u00e9mocrates de la faction lib\u00e9rale-globaliste au pouvoir et leurs alli\u00e9s britanniques \u00e9tait que l&rsquo;ancien pr\u00e9sident repr\u00e9sentait une menace pour leur programme. Ils ont donc cherch\u00e9 \u00e0 le discr\u00e9diter en pr\u00e9tendant qu&rsquo;il serait une marionnette russe.<\/p>\n<\/p>\n<p><p>La Russie n&rsquo;avait pas correctement \u00e9valu\u00e9 la dynamique de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb des &Eacute;tats-Unis pour comprendre ce qui se passait, pourquoi et \u00e0 quel point il \u00e9tait improbable que Trump sorte victorieux de cette lutte pour le pouvoir comme elle l&rsquo;esp\u00e9rait, ce qui explique pourquoi elle resta attach\u00e9e aux accords de Minsk que personne d&rsquo;autre ne respectait. Cependant, le pr\u00e9sident Poutine et son \u00e9quipe ont appris \u00e0 leurs d\u00e9pens les le\u00e7ons de la na\u00efvet\u00e9 et des v&oelig;ux pieux, et ne se laisseront pas tromper une nouvelle fois en pensant que tout changera exactement comme il l&rsquo;a dit \u00e0 Tucker.<\/p>\n<\/p>\n<p><p>Pour r\u00e9sumer, le pr\u00e9sident Poutine pr\u00e9f\u00e8re Biden \u00e0 Trump parce que : 1) Biden a le soutien des lib\u00e9raux-globalistes au pouvoir au sein de \u00ab\u00a0l&rsquo;&Eacute;tat profond\u00a0\u00bb ; 2) cette faction devrait rester au pouvoir m\u00eame si Trump gagne ; et 3) ils pourraient proc\u00e9der \u00e0 davantage de provocations antirusses pour le discr\u00e9diter dans cette affaire, tout comme la derni\u00e8re fois. Il est bien pr\u00e9f\u00e9rable pour la Russie de jouer la prudence et de formuler sa politique en partant du principe que ses liens avec les &Eacute;tats-Unis pourraient se d\u00e9t\u00e9riorer plut\u00f4t que de se livrer une fois de plus na\u00efvement \u00e0 des v&oelig;ux pieux selon lesquels ils pourraient s&rsquo;am\u00e9liorer.<\/p>\n<\/p>\n<p><h4>Andrew Korybko<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine, pourquoi Biden ? &bull; C&rsquo;est un d\u00e9bat qui nous para&icirc;t bien difficile \u00e0 trancher : pourquoi Poutine pr\u00e9f\u00e8re-t-il Biden \u00e0 Trump ? &bull; Andrew Korybko a une r\u00e9ponse assur\u00e9e : il juge ce choix comme celui de la raison m\u00eame. &bull; On l&rsquo;\u00e9coute mais on peut en douter. _________________________ On d\u00e9bat toujours, in fine&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3756,6705,12593,13022,2639],"class_list":["post-80944","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-etat","tag-naivete","tag-profond","tag-russiagate","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80944"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80944\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}