{"id":80971,"date":"2024-03-07T15:00:33","date_gmt":"2024-03-07T15:00:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/03\/07\/la-grace-iii-ukrisis-dans-la-grandecrise\/"},"modified":"2024-03-07T15:00:33","modified_gmt":"2024-03-07T15:00:33","slug":"la-grace-iii-ukrisis-dans-la-grandecrise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/03\/07\/la-grace-iii-ukrisis-dans-la-grandecrise\/","title":{"rendered":"<em>La Gr\u00e2ce-III<\/em>\u00a0: \u2018<em>Ukrisis<\/em>&lsquo; dans la GrandeCrise"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\"><em>La Gr\u00e2ce-III<\/em> : &lsquo;<em>Ukrisis<\/em>&lsquo; dans la GrandeCrise<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Pour suivre la voie trac\u00e9e par le texte sur le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb <a href=\"https:\/\/www.dedefensa.org\/article\/la-grace-iii-le-dechainement-de-la-matiere\">que l&rsquo;on peut trouver<\/a> dans cette m\u00eame rubrique, voici un nouvel <strong>extrait du livre en pr\u00e9paration se pr\u00e9tendant comme la suite de la s\u00e9rie de &lsquo;<em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>&lsquo;<\/strong>, et certainement toujours avec les m\u00eames r\u00e9serves concernant <strong>les capacit\u00e9s du v\u00e9n\u00e9rable capitaine PhG<\/strong> \u00e0 tenir ses engagements. &bull; Cet extrait n&rsquo;encha&icirc;ne nullement sur le pr\u00e9c\u00e9dent mais il nous semble que l&rsquo;on peut dire qu&rsquo;il forme un tout lisible qui permet de le lire <strong>d\u00e9tach\u00e9 du reste<\/strong>. &bull; Le \u00ab\u00a0concept\u00a0\u00bb pr\u00e9sent\u00e9 ici est finalement celui <strong>de ce que nous nommons  la <\/strong><strong><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a><\/strong>, et la m\u00e9canique m\u00e9taphysique <strong>qui agglom\u00e8re les diff\u00e9rentes sous-crises (ou \u00ab\u00a0subcrises\u00a0\u00bb) qui la composent<\/strong> : Trump et la crise aux USA depuis 2015-2016, le mouvement <em>Woke <\/em>et le wokenisme qui est peut-\u00eatre la repr\u00e9sentation la plus marquante par son effet de d\u00e9constructuration, le Covid, la crise ukrainienne ou &lsquo;<em>Ukrisis<\/em>&lsquo; depuis 2022 et m\u00eame depuis 2014, et au loin depuis 1991, la crise palestinienne&#8230; &bull; Le passage consid\u00e9r\u00e9 <strong>traite essentiellement de l&rsquo;int\u00e9gration d\u00a0\u00bb<em>Ukrisis<\/em>&lsquo; dans la GrandeCrise<\/strong>.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">&lsquo;<em>Ukrisis<\/em>&lsquo; dans la GrandeCrise<\/h2>\n<\/p>\n<p><p>L&rsquo;indiscutable caract\u00e8re exceptionnel du wokenisme se rencontre l\u00e0 encore dans le lien qu&rsquo;il \u00e9tablit entre la crise am\u00e9ricaniste [depuis 2015-2016] dans le sein de laquelle il a fleuri et l&rsquo;\u00e9v\u00e9nement &lsquo;<em>Ukrisis<\/em>&lsquo; que nous retrouvons ainsi. C&rsquo;est en effet notre intention de consid\u00e9rer cette crise majeure de la guerre en Ukraine comme un cha&icirc;non de plus dans cette sorte de \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb, un tour de fou suppl\u00e9mentaire du \u00ab\u00a0tourbillon crisique\u00a0\u00bb, &ndash; m\u00eames causes, m\u00eames effets, m\u00eames remous et m\u00eames cons\u00e9quences. L&rsquo;attaque du Syst\u00e8me contre l&rsquo;Ukraine pour d\u00e9structurer la Russie est effectivement un effort majeur de d\u00e9constructuration, une sorte de verrou d&rsquo;une puissance inou\u00efe qui saute, que nous abordons essentiellement comme une \u00ab\u00a0repr\u00e9sentation\u00a0\u00bb, un simulacre de la m\u00eame eau que la crise covidienne, sans nous attacher aux aspects g\u00e9opolitiques qui constituent une r\u00e9f\u00e9rence d\u00e9pass\u00e9e pour tenir un r\u00f4le important, et encore moins bien entendu le premier r\u00f4le.<\/p>\n<\/p>\n<p><p>Nous posons \u00e9videmment comme une \u00e9vidence de notre propos que nous sommes entr\u00e9s dans une autre dimension en fait de qualit\u00e9 et m\u00eame d&rsquo;essence de la crise, &ndash; qu&rsquo;on devrait plut\u00f4t nommer \u00ab\u00a0essence crisique\u00a0\u00bb, &ndash; en fait d&rsquo;aspect formel de cette dynamique, et par cons\u00e9quent quelque chose d&rsquo;autre pour ce qui est de la puissance et de l&rsquo;orientation de sa dimension m\u00e9tahistorique. Pour autant, et c&rsquo;est bien entendu le point qui importe le plus, le point d\u00e9cisif, le sch\u00e9ma du d\u00e9veloppement de cette crise, ou \u00ab\u00a0fraction de crise\u00a0\u00bb, reste compl\u00e8tement celui de la d\u00e9constructuration dont l&rsquo;universalit\u00e9 de la pr\u00e9sence est une \u00e9vidence. En ce sens, l&rsquo;on comprend ais\u00e9ment que le facteur de la communication tient une place absolument centrale ; c&rsquo;est lui qui permet toutes les man&oelig;uvres de repr\u00e9sentation, qui r\u00e8gle la perception, qui fausse les sens, mais aussi qui r\u00e9compense la lucidit\u00e9 et la ma&icirc;trise de soi, qui facilite pour celui qui sait s&rsquo;en saisir l&rsquo;acc\u00e8s \u00e0 l&rsquo;intuition ; la communication, ou Janus en action, dans son avers ou dans son envers.<\/p>\n<\/p>\n<p><p>N&rsquo;importe quel t\u00e9moin de l&rsquo;\u00e9v\u00e9nement, je m&rsquo;en souviens fort bien pour mon compte, \u00e9prouva \u00e0 un moment ou l&rsquo;autre du lancement de l&rsquo;op\u00e9ration russe, cette fameuse \u00ab\u00a0Op\u00e9ration Militaire Sp\u00e9ciale\u00a0\u00bb (OMS), le 24 f\u00e9vrier 2022, l&rsquo;une ou l&rsquo;autre surprise. On aurait pu dire que la Russie avait comme but, &ndash; involontaire ou pas qu&rsquo;importe, et plut\u00f4t involontairement si je suis ma pens\u00e9e, &ndash; de d\u00e9constructurer la notion m\u00eame de \u00ab\u00a0guerre\u00a0\u00bb, tant la man&oelig;uvre semblait ne correspondre \u00e0 rien de ce que l&rsquo;on pouvait envisager en fonction des effectifs engag\u00e9s. Il est extr\u00eamement probable selon mon jugement que, dans cette surprise et cette perception chaotique entraient un certain nombre d&rsquo;erreurs d&rsquo;ailleurs fort compr\u00e9hensibles des Russes, qui ne s&rsquo;attendaient certainement pas :<\/p>\n<\/p>\n<p><p>1)   D&rsquo;une part,  \u00e0 rencontrer une arm\u00e9e ukrainienne aussi forte et aussi bien organis\u00e9e ;<\/p>\n<\/p>\n<p><p>2)   D&rsquo;autre part, \u00e0 voir en face d&rsquo;eux une pr\u00e9sence de soutien, sinon plus, de forces de l&rsquo;OTAN, si bien qu&rsquo;on aurait pu d\u00e8s lors nommer cette guerre \u00ab\u00a0guerre de la Russie contre l&rsquo;OTAN\u00a0\u00bb (avec tous les \u00e9normes moyens notamment de communication [identification, localisation, etc.] que cela suppose, et non \u00ab\u00a0guerre de la Russie contre l&rsquo;Ukraine\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Il s&rsquo;ensuivit, d\u00e8s ces premiers heurts, une importance fondamentale de la communication justement, bien entendu en tant que perception, ou bien en \u00e9cho de la \u00ab\u00a0r\u00e9alit\u00e9\u00a0\u00bb, ou plus encore, en tant que fabrication de <em>narrative<\/em>, de simulacres. Cette importance s&rsquo;imposa irr\u00e9sistiblement ; on peut m\u00eame dire que ce fut, d\u00e8s l&rsquo;abord, l&rsquo;\u00e9l\u00e9ment essentiel de cette guerre et celui qui allait compl\u00e8tement la caract\u00e9riser. Mais puisque nous sommes dans ce domaine du constat de l&rsquo;imm\u00e9diat en fait de communication, on doit aussit\u00f4t r\u00e9p\u00e9ter qu&rsquo;il manquait \u00e9videmment, pour une caract\u00e9risation dans sa dimension ad\u00e9quate, la remarque, l\u00e0 aussi avec toutes les variations de justesse et de d\u00e9formations possibles, que l&rsquo;on a faite plus haut : c&rsquo;\u00e9tait au moins une \u00ab\u00a0guerre de la Russie contre l&rsquo;OTAN\u00a0\u00bb et nullement une \u00ab\u00a0guerre de la Russie contre l&rsquo;Ukraine\u00a0\u00bb&hellip; Quoi qu&rsquo;il en soit, il doit \u00eatre admis absolument que nous allons examiner cette guerre selon son caract\u00e8re d\u00a0\u00bb<em>Ukrisis<\/em>&lsquo;, essentiellement sinon uniquement du point de de vue de la communication, et non pas des points de vue habituels d&rsquo;une guerre (g\u00e9opolitique, militaire, etc.) qui ne sont dans ce cas que les outils de l&rsquo;\u00e9v\u00e9nement de communication.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Il y a une admirable le\u00e7on de synth\u00e8se,<\/h3>\n<\/p>\n<p><p>\u00e0 la fois de r\u00e9alisme et d&rsquo;interpr\u00e9tation m\u00e9tahistorique la plus haute, \u00e0 recevoir du philosophe de l&rsquo;histoire, le Russe Alexandre Douguine ; en effet, qui d&rsquo;autre qu&rsquo;un Russe pour cette t\u00e2che essentielle de donner \u00e0 &lsquo;<em>Ukrisis<\/em>&lsquo; la place essentielle d&rsquo;\u00e9v\u00e8nement \u00e0 la fois courant mais devenu tr\u00e8s original, et pass\u00e9 d&rsquo;une \u00ab\u00a0op\u00e9ration de police\u00a0\u00bb \u00e0 un \u00e9v\u00e9nement fondamentalement transcendant ? Douguine est celui qui a saisi le plus rapidement et le plus pr\u00e9cis\u00e9ment, je veux dire sans reculer devant la force des mots, ce caract\u00e8re transcendant. A ce moment, dans ces conditions d&rsquo;interpr\u00e9tation que le philosophe russe nous offre, on peut faire d\u00a0\u00bb<em>Ukrisis<\/em>&lsquo; le continuateur logique des incidents d\u00e9cadentiels pr\u00e9c\u00e9dents, sinon leur extension paroxystique avec une dimension de rupture.<\/p>\n<\/p>\n<p><p>Il fallut un certain temps, peut-\u00eatre bien une ann\u00e9e et plus alors qu&rsquo;on attendait en g\u00e9n\u00e9ral un conflit localis\u00e9 de quelques mois, pour que se dessinassent les contours assur\u00e9s de la dimension eschatologique de cette guerre. Il \u00e9tait bien entendu \u00e9vident que personne n&rsquo;aurait pu pr\u00e9voir raisonnablement la marche pr\u00e9cipit\u00e9e des \u00e9v\u00e8nements jusqu&rsquo;\u00e0 f\u00e9vrier 2022 et la crise &lsquo;<em>Ukrisis<\/em>&lsquo;, m\u00eame en se pla\u00e7ant du point de vue des \u00e9v\u00e8nements depuis f\u00e9vrier 2014 et le \u00ab\u00a0coup de Kiev\u00a0\u00bb. Il est bien autant \u00e9vident, et cela est encore plus remarquable, que nul n&rsquo;aurait pu pr\u00e9voir raisonnablement cette \u00ab\u00a0marche pr\u00e9cipit\u00e9e\u00a0\u00bb suivant une acc\u00e9l\u00e9ration suppl\u00e9mentaire, du point de vue de ces m\u00eames \u00e9v\u00e8nements depuis f\u00e9vrier 2022.<\/p>\n<\/p>\n<p><p>Il y a l\u00e0 un constat d\u00e9licat \u00e0 faire, qui concerne la substance de ces \u00e9v\u00e8nements, leur importance fondamentale, les forces qui les r\u00e9gissent et d&rsquo;une mani\u00e8re g\u00e9n\u00e9rale ce que nous jugions \u00eatre leur n\u00e9cessaire eschatologisation. Bient\u00f4t s&rsquo;imposa donc la question de la cause fondamentale, le passage de l&rsquo;interpr\u00e9tation d&rsquo;un \u00ab\u00a0simple\u00a0\u00bb affrontement pour la souverainet\u00e9 \u00e0 un \u00e9branlement civilisationnel d&rsquo;une immense grandeur, peut-\u00eatre d&rsquo;une grandeur in\u00e9dite et inconnue dans la civilisation courante qui est n\u00f4tre, peut-\u00eatre aussi colossal et important que la chute de l&rsquo;Empire romain&#8230; Et encore, &ndash; bien plus encore ! Avec la diff\u00e9rence extraordinairement aggravante d&rsquo;un \u00e9v\u00e9nement qui nous apparut extr\u00eamement rapide, que nous r\u00e9alis\u00e2mes et observ\u00e2mes quasiment en temps r\u00e9el, identifi\u00e9 directement pour ce qu&rsquo;il \u00e9tait ; et ce facteur essentiel de la rapidit\u00e9 semblant lui donner un \u00ab\u00a0suppl\u00e9ment d&rsquo;\u00e2me\u00a0\u00bb, c&rsquo;est-\u00e0-dire une m\u00e9taphysique encore plus imp\u00e9rative et \u00ab\u00a0op\u00e9rative\u00a0\u00bb \u00e0 la fois, d\u00e9passant celle de la chute de l&rsquo;Empire de Rome.<\/p>\n<\/p>\n<p><p>Ainsi parvenons-nous \u00e0 d\u00e9terminer une approche pour atteindre un point de vue d&rsquo;o&ugrave; cette crise &lsquo;<em>Ukrisis<\/em>&lsquo; devenue guerre du m\u00eame nom acquiert un sens qui lui donne compl\u00e8tement sa place dans la filiation des crises que nous avons vues d\u00e9filer depuis 2015-2016. Il est temps ici de reconna&icirc;tre, d&rsquo;identifier l&rsquo;\u00e2me et la plume qui nous ont guid\u00e9 dans cette qu\u00eate : le philosophe-g\u00e9opoliticien (selon le caract\u00e8re qu&rsquo;il se pla&icirc;t \u00e0 arborer) Alexander Douguine, le Russe Douguine. <\/p>\n<\/p>\n<p><p>Il nous semble, que l&rsquo;on soit ou non en accord avec lui, qu&rsquo;il apporte la vision la plus ample et la plus haute, le regard du \u00ab\u00a0philosophe de la spiritualit\u00e9\u00a0\u00bb, &ndash; qui nous int\u00e9resse plus que la g\u00e9opolitique, &ndash; c&rsquo;est-\u00e0-dire le philosophe qui cherche l&rsquo;explication centrale dans les mati\u00e8res les plus extr\u00eames dans l&rsquo;ordre de l&rsquo;ontologie et au-del\u00e0 des interdits du rationnel. Douguine, lui aussi, chose extr\u00eamement rare pour un observateur de cette trempe, d\u00e9crit \u00ab\u00a0en temps r\u00e9el\u00a0\u00bb des \u00e9v\u00e8nements qui se r\u00e9v\u00e8lent eschatologiques, qu&rsquo;il interpr\u00e8te dans l&rsquo;instant pour ce qu&rsquo;ils sont, &ndash; eschatologiques, justement. Par cons\u00e9quent, on prendra avec la plus grande gravit\u00e9 ce qu&rsquo;il dit \u00e0 propos de ce conflit d&rsquo;Ukraine, de son \u00e9volution, de sa transformation &ndash; non, de sa transmutation, \u00e0 partir de ce constat radical et terrible qui structure toute sa r\u00e9flexion, &ndash; ce constat que l&rsquo;Occident est \u00ab\u00a0monstrueux\u00a0\u00bb et qu&rsquo;il rompt avec une violence horrible &laquo; <em>avec l&rsquo;esp\u00e8ce humaine<\/em> &raquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ayant d\u00e9couvert que l&rsquo;Occident est monstrueux et se s\u00e9pare sous nos yeux de l&rsquo;esp\u00e8ce humaine, la Russie s&rsquo;en est \u00e9loign\u00e9e. Un probl\u00e8me local, le conflit avec l&rsquo;Ukraine, nous a soudain conduits \u00e0 des conclusions fondamentales : l&rsquo;Occident fait fausse route, il entra&icirc;ne l&rsquo;humanit\u00e9 dans l&rsquo;ab&icirc;me et nous devons l&rsquo;affronter. C&rsquo;est la nouvelle la plus importante, quelque chose d&rsquo;absolument incroyable, car auparavant nous nous \u00e9tions modestement limit\u00e9s \u00e0 la lutte pour la souverainet\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi Douguine entame-t-il son analyse de la crise que nous connaissons en la situant aussit\u00f4t, d&rsquo;ailleurs selon le th\u00e8me de la conversation qui nous est propos\u00e9e dans le titre de son intervention du <u>11 septembre 2023<\/u> (&laquo; <em>A l&rsquo;ombre de Satan<\/em> &raquo;), \u00e0 propos et selon la pr\u00e9sence, l&rsquo;influence et les pressions de Satan, &ndash; un Satan en r\u00e9f\u00e9rence \u00e0 la th\u00e9ologie religieuse, et non plus une simple imagerie passepartout. Pour Douguine, Satan est une entit\u00e9 essentielle du drame cosmique que nous vivons.<\/p>\n<\/p>\n<p><p>On le comprend donc clairement : cette d\u00e9marche de Douguine n&rsquo;est pas simplement symbolique, ni une parabole, ni une analogie, ni une  illustration de convenance ou un exc\u00e8s compr\u00e9hensible de langage, elle exprime clairement et directement ce qu&rsquo;elle entend d\u00e9crire. C&rsquo;est dire combien il est n\u00e9cessaire d&rsquo;avoir l&rsquo;esprit ouvert et le jugement large, car son expos\u00e9 sur un \u00ab\u00a0concept\u00a0\u00bb (?) si profond\u00e9ment irrationnel, nous renvoyant \u00e0 la fois dans les anciens temps de la Tradition, dans les myst\u00e8res de l&rsquo;Unit\u00e9 originelle et dans des c\u00e9l\u00e9brations consid\u00e9r\u00e9es comme primitives par rapport aux festivit\u00e9s du wokenisme, &ndash; car cet expos\u00e9-l\u00e0 est chez Douguine tout \u00e0 fait rationnel.<\/p>\n<\/p>\n<p><p>Bien entendu, dans le style, les images, les perspectives, il y a le feu et la fi\u00e8vre du slave et dans le regard de son \u00e2me l&rsquo;immensit\u00e9 des horizons russes. Mais la pens\u00e9e n&rsquo;est pas d\u00e9form\u00e9e par une expression si souvent mise \u00e0 l&rsquo;index, qui permet dans ce cas d&rsquo;autant mieux et au contraire de mesurer la puissance de la vision. On le comprend ais\u00e9ment lorsqu&rsquo;on voit que Douguine travaille pour une part non n\u00e9gligeable sous le magist\u00e8re de l&rsquo;un des m\u00e9taphysiciens les plus rigoureux, les plis f\u00e9rus d&rsquo;une logique de fer : le Fran\u00e7ais Ren\u00e9 Gu\u00e9non, qui nous a d\u00e9j\u00e0 averti de la pr\u00e9sence du satanisme et du simulacre auquel il conduit.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ren\u00e9 Gu\u00e9non, philosophe, partisan d&rsquo;une soci\u00e9t\u00e9 spirituelle traditionnelle, l&rsquo;a appel\u00e9e la Grande Parodie. C&rsquo;est \u00e0 cela que conduit la civilisation satanique. Si, au premier stade du mat\u00e9rialisme, il s&rsquo;agissait de nier toute spiritualit\u00e9,<\/em> [&#8230;] <em>progressivement, au fur et \u00e0 mesure que cette Grande Parodie prend forme, un nouveau projet \u00e9merge : non seulement le rejet de l&rsquo;&Eacute;glise, mais la construction d&rsquo;une anti-&Eacute;glise, non seulement l&rsquo;oubli de l&rsquo;esprit, mais la cr\u00e9ation d&rsquo;une nouvelle spiritualit\u00e9, invers\u00e9e.<\/em>.. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi sommes-nous convi\u00e9 \u00e0 cette pens\u00e9e qui tient Satan comme un facteur essentiel et d&rsquo;une r\u00e9elle et puissante existence de la terrible r\u00e9alit\u00e9 de notre malheur, voire, op\u00e9rationnellement comme son facteur exclusif, &ndash; Satan, ma&icirc;tre du Mal et de \u00ab\u00a0notre malheur\u00a0\u00bb . Ne pas accepter cette hypoth\u00e8se, c&rsquo;est justement tomber dans le pi\u00e8ge diabolique de cette entit\u00e9 qui sait si bien faire usage de son arme principale, cette \u00ab\u00a0Grande-Parodie\u00a0\u00bb, qui est \u00e9galement le montage du simulacre, l&rsquo;op\u00e9rationnalit\u00e9 de cette m\u00e9thode inf\u00e2me avec ses <em>narrative<\/em>, toutes ces tromperies qui nous accablent, nous serrent \u00e0 la gorge, qui font la circonstance essentielle, proche de la folie, de notre bataille.<\/p>\n<\/p>\n<p><p>La GrandeCrise est si bien devenue elle-m\u00eame, si &lsquo;Grande&rsquo; dans le sens d&rsquo;universel et collectif, si semeuse de malheur et de chaos, que nous avions et avons le besoin vital d&rsquo;une explication universelle et collective. Il n&rsquo;y en a aujourd&rsquo;hui plus aucune qui soit disponible. Plus encore, les derniers \u00e9v\u00e8nements ont rendu caducs, inop\u00e9rants, d\u00e9pass\u00e9s, les divers projets universels et collectifs, r\u00e9duisant \u00e0 n\u00e9ant toute perspective s\u00e9rieuse d&rsquo;une organisation humaine acceptable, les rempla\u00e7ant par l&rsquo;actuel chaos qui est pourtant lui-m\u00eame l&rsquo;enfant de formidables efforts d&rsquo;organisations humaines ambitieuses. La m\u00eame chose peut \u00eatre dit, bien entendu, sur les nombreux aspects insupportables du monde actuel qui orientent le jugement vers le constat de l&rsquo;existence du Mal sans en donner la moindre explication, justification, description, logique, etc.<\/p>\n<\/p>\n<p><p>M\u00eame l&rsquo;Ukraine a jou\u00e9 un r\u00f4le tr\u00e8s concret \u00e0 cet \u00e9gard, en relativisant compl\u00e8tement la symbolique jusqu&rsquo;alors triomphante du &lsquo;Mal&rsquo; [Hitler et le nazisme], tant utilis\u00e9e et brandie avec une sorte de soulagement puisque cantonn\u00e9e \u00e0 une id\u00e9ologie contraire au cat\u00e9chisme progressiste. On n&rsquo;a pas encore mesur\u00e9 la catastrophe symbolique et communicationnelle qu&rsquo;a constitu\u00e9 ce sacril\u00e8ge du Camp du Bien vis-\u00e0-vis du Camp du Bien ; ce sacril\u00e8ge, celui de retrouver dans les quartiers de Mister Z, personnage extraordinairement vulgaire et m\u00e9diocre devenu iconique de Camp du Bien, nombre d&rsquo;orientations et d&rsquo;\u00e9chapp\u00e9es vers le nazisme qui perdurent officiellement, \u00e0 ciel ouvert, sans aucune difficult\u00e9, sous les applaudissements des multitudes antirusses de nos \u00e9lites.<\/p>\n<\/p>\n<p><p>Tout cela, qui traduit une inconscience et un d\u00e9sordre extraordinaire de cette raison-subvertie qui pr\u00e9tend r\u00e9genter le monde en le r\u00e9gulant, explique que des conceptions jusqu&rsquo;alors mises \u00e0 l&rsquo;index par le m\u00e9pris et le sarcasme retrouvent la possibilit\u00e9 d&rsquo;une exposition richement document\u00e9e. Ainsi en est-il du travail, d&rsquo;une haute tenue intellectuelle, de ce philosophe singulier dans sa fi\u00e8vre apprivois\u00e9e qu&rsquo;est Alexander Douguine. Avec lui, le diable n&rsquo;est plus seulement \u00ab\u00a0dans les d\u00e9tails\u00a0\u00bb ; il est bel et bien Satan, au centre d&rsquo;un monde perverti, d&rsquo;une civilisation aux abois et sombrant sous le poids de son infamie. Cela est remarquablement  expos\u00e9 par un esprit vigoureux et fi\u00e9vreux, arm\u00e9 d&rsquo;une culture d\u00e9vastatrice pour le troupeau des nains qui pr\u00e9tendent nous mener, avec le pouvoir magique et presque po\u00e9tique de transformer l&rsquo;histoire courante en ce qu&rsquo;elle est aujourd&rsquo;hui, &ndash; et aujourd&rsquo;hui seulement : imm\u00e9diatement m\u00e9taphysique historique, nous passons de l&rsquo;\u00e9v\u00e8nement \u00e0 la m\u00e9tahistoire sans escale interm\u00e9diaire n\u00e9cessaire&#8230; Nous sommes \u00ab\u00a0\u00e0 l&rsquo;ombre de Satan\u00a0\u00bb et de la GrandeCrise.<\/p>\n<\/p>\n<p><p>(Notez que l&rsquo;intervention de Douguine qui nous fournit l&rsquo;essentiel de l&rsquo;argument sur la perception transformatrice de la guerre date du mois d&rsquo;<u>ao&ucirc;t 2023<\/u>, soit 18 mois apr\u00e8s le d\u00e9but de la guerre, ce qui nous donne un laps de temps acceptable pour accepter l&rsquo;int\u00e9gration de cet \u00e9v\u00e8nement dans notre propos.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Nous donnons ici le texte complet des r\u00e9ponses<\/h3>\n<\/p>\n<p><p>de Douguine aux trois premi\u00e8res questions qui lui sont pos\u00e9es Par Peter Vlasov, concernant la caract\u00e8re satanique de l&rsquo;adversaire auquel se confrontent les forces traditionnelles sur lesquelles il s&rsquo;appuie. Le mot d&rsquo;ordre du philosophe, pour fixer l&rsquo;intensit\u00e9 du combat spirituel ainsi en cours, est celui-ci : &laquo; Il faut laisser la guerre entrer en nous &raquo;. Cela veut dire qu&rsquo;il importe d&rsquo;ouvrir notre \u00e2me \u00e0 tous les domaines transcendants jusque-l\u00e0 interdits d&rsquo;acc\u00e8s par le gardien vigilant et impitoyable que constitue la raison-subvertie qui fait feu sans l&rsquo;aum\u00f4ne de la moindre sommation.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> <strong><em>Peter Vlasov<\/em><\/strong><em> : <\/em>&laquo; <em>Alexandre Douguine, nous entendons de plus en plus souvent les dirigeants du pays d\u00e9finir la civilisation occidentale moderne par le mot \u00ab\u00a0satanisme\u00a0\u00bb. Qu&rsquo;entendez-vous par l\u00e0, quel est votre avis ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong>Alexander Douguine<\/strong> : &laquo; <em>Le pr\u00e9sident a d\u00e9clar\u00e9 que l&rsquo;Occident \u00e9tait une &quot;civilisation satanique&quot; dans le discours qu&rsquo;il a prononc\u00e9 lors de l&rsquo;admission de nouveaux sujets au sein de la F\u00e9d\u00e9ration de Russie. Nous devrions prendre cela au s\u00e9rieux et essayer de comprendre ce qui se cache derri\u00e8re cette formulation, d&rsquo;autant plus qu&rsquo;elle a \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9e par la suite par de nombreuses personnalit\u00e9s politiques et publiques de haut rang. Il me semble qu&rsquo;il s&rsquo;agit d&rsquo;une d\u00e9claration tr\u00e8s s\u00e9rieuse et profonde.<\/em><\/p>\n<\/p>\n<p><p><em>Apr\u00e8s le d\u00e9but de l&rsquo;Op\u00e9ration militaire sp\u00e9ciale, nous avons commenc\u00e9 \u00e0 nous rendre compte de plus en plus clairement que quelque chose ne tournait pas rond en Occident. La civilisation occidentale moderne s&rsquo;est soit \u00e9gar\u00e9e, soit d\u00e9tourn\u00e9e de la voie qu&rsquo;elle suivait lorsque nous l&rsquo;avons accept\u00e9e, accueillie, imit\u00e9e, soit, ce qui est encore plus probable, quelque chose ne va pas depuis longtemps. Une civilisation que nous admirons, \u00e0 laquelle nous cherchons \u00e0 nous int\u00e9grer, dont nous partageons les valeurs et les r\u00e8gles et que nous embrassons de toute notre \u00e2me, ne peut-elle pas se r\u00e9v\u00e9ler soudainement satanique ? Parall\u00e8lement \u00e0 cela, nous voyons la question des valeurs se poser \u00e0 diff\u00e9rents niveaux dans notre Etat. Nous commen\u00e7ons \u00e0 le r\u00e9p\u00e9ter : nous d\u00e9fendons nos valeurs. Il y a un an, le Pr\u00e9sident a adopt\u00e9 un d\u00e9cret sur la d\u00e9fense des valeurs traditionnelles, parmi lesquelles la sup\u00e9riorit\u00e9 de l&rsquo;esprit sur la mati\u00e8re. C&rsquo;est une chose absolument \u00e9tonnante ! Les valeurs traditionnelles de la Russie sont reconnues comme \u00e9tant, si vous voulez, l&rsquo;id\u00e9alisme, la religiosit\u00e9, la domination de l&rsquo;esprit. Et bien s&ucirc;r, si nous commen\u00e7ons \u00e0 nous consid\u00e9rer &#8211; pas encore avec confiance, mais de plus en plus &#8211; comme des porteurs de valeurs traditionnelles, c&rsquo;est pr\u00e9cis\u00e9ment face \u00e0 ces valeurs traditionnelles, que nous d\u00e9couvrons tout juste en nous-m\u00eames, que nous commen\u00e7ons tout juste \u00e0 comprendre, \u00e0 appr\u00e9hender et \u00e0 d\u00e9fendre, face \u00e0 ces valeurs, bien s&ucirc;r, les valeurs occidentales ressemblent \u00e0 du satanisme pur et simple. Elles sont tout le contraire des n\u00f4tres. Elles reposent sur l&rsquo;id\u00e9e que la mati\u00e8re est primordiale par rapport \u00e0 l&rsquo;esprit, que l&rsquo;homme n&rsquo;est qu&rsquo;un \u00eatre biosocial qui est un reflet cognitif du monde ext\u00e9rieur. L&rsquo;Occident per\u00e7oit l&rsquo;homme comme un animal \u00e9volu\u00e9, qui a atteint son stade final pour passer l&rsquo;initiative \u00e0 une esp\u00e8ce posthumaine, aux constructions transhumanistes, aux cyborgs, \u00e0 l&rsquo;intelligence artificielle. Et la pr\u00e9paration, l&rsquo;\u00e9chauffement, c&rsquo;est la politique du genre, o&ugrave; l&rsquo;on change de sexe au gr\u00e9 de ses envies &#8211; voire de ses caprices &#8211; et bient\u00f4t d&rsquo;esp\u00e8ce, o&ugrave; l&rsquo;on choisit d&rsquo;appartenir au sexe homme, \u00e0 une cat\u00e9gories de machines ou \u00e0 une esp\u00e8ce animale, ce qui fait d\u00e9j\u00e0 l&rsquo;objet de discussions s\u00e9rieuses au plus haut niveau des personnalit\u00e9s occidentales.<\/em><\/p>\n<\/p>\n<p><p><em>Ayant d\u00e9couvert que l&rsquo;Occident est monstrueux et se s\u00e9pare sous nos yeux de l&rsquo;esp\u00e8ce humaine, la Russie s&rsquo;en est \u00e9loign\u00e9e. Un probl\u00e8me local, le conflit avec l&rsquo;Ukraine, nous a soudain conduits \u00e0 des conclusions fondamentales : l&rsquo;Occident fait fausse route, il entra&icirc;ne l&rsquo;humanit\u00e9 dans l&rsquo;ab&icirc;me et nous devons l&rsquo;affronter. C&rsquo;est la nouvelle la plus importante, quelque chose d&rsquo;absolument incroyable, car auparavant nous nous \u00e9tions modestement limit\u00e9s \u00e0 la lutte pour la souverainet\u00e9.<\/em><\/p>\n<\/p>\n<p><p><em>Et c&rsquo;est ici que le concept de &quot;satanisme&quot; acquiert pour la premi\u00e8re fois une signification tr\u00e8s s\u00e9rieuse. Il ne s&rsquo;agit pas seulement d&rsquo;un mouvement occulte marginal, le satanisme existe en Occident, il y a l&rsquo;&Eacute;glise de Satan d&rsquo;Anton LaVey, il y a m\u00eame le satanisme direct de l&rsquo;\u00e9crivain ultra-capitaliste Ayn Rand (Alice Rosenbaum) &#8211; qui \u00e9tait d&rsquo;ailleurs populaire parmi les oligarques et les lib\u00e9raux russes dans les ann\u00e9es quatre-vingt-dix. Mais il s&rsquo;agit dans l&rsquo;ensemble de ph\u00e9nom\u00e8nes marginaux, de sectes occultes et de productions th\u00e9\u00e2trales. Par &quot;le satanisme de la civilisation occidentale&quot;, Poutine entendait quelque chose d&rsquo;autre, de beaucoup plus profond. Le satanisme, c&rsquo;est la primaut\u00e9 de la mati\u00e8re sur l&rsquo;esprit, le relativisme postmoderne, c&rsquo;est-\u00e0-dire la relativit\u00e9 de toutes les valeurs, y compris celles de l&rsquo;\u00eatre humain et de l&rsquo;esprit. Et c&rsquo;est la voie que l&rsquo;Occident a emprunt\u00e9e, non pas hier, mais il y a environ 500 ans, avec le d\u00e9but du New Age.<\/em><\/p>\n<\/p>\n<p><p><em>Qui est Satan ? Il n&rsquo;y a pas de Satan quand il n&rsquo;y a pas de Dieu, pas de foi, pas de religion. Ce terme reste dans le vide, si pour nous les termes &quot;Dieu&quot;, &quot;foi&quot;, &quot;\u00e9ternit\u00e9&quot;, &quot;immortalit\u00e9&quot;, &quot;r\u00e9surrection des morts&quot;, &quot;jugement dernier&quot;, &quot;salut de l&rsquo;\u00e2me&quot;&#8230; sont tout aussi vides. Si nous suivons l&rsquo;image scientifique occidentale moderne du monde, il est bien s&ucirc;r ridicule de parler de satanisme, car il n&rsquo;y a ni Dieu, ni diable, ni foi, ni \u00e2me immortelle, ni vie post-mortelle, mais seulement un flottement d&rsquo;unit\u00e9s biologiques, d&rsquo;atomes, qui se collent les uns aux autres, se s\u00e9parent, puis disparaissent dans l&rsquo;ab&icirc;me de l&rsquo;espace noir et mort. C&rsquo;est \u00e0 peu pr\u00e8s cette image du monde qui s&rsquo;est impos\u00e9e en Occident il y a 500 ans, et que l&rsquo;on appelle g\u00e9n\u00e9ralement &quot;l&rsquo;image scientifique du monde&quot;. Elle s&rsquo;est accompagn\u00e9e d&rsquo;une d\u00e9christianisation progressive et compl\u00e8te de la culture occidentale. Ainsi, Satan en tant que ph\u00e9nom\u00e8ne a disparu de la &quot;repr\u00e9sentation scientifique du monde&quot; en m\u00eame temps que Dieu. Lorsque nous affirmons s\u00e9rieusement que la civilisation occidentale est satanique, nous attirons l&rsquo;attention sur le fait qu&rsquo;il s&rsquo;agit d&rsquo;une conclusion h\u00e2tive, incorrecte, pr\u00e9matur\u00e9e et, en fait, profond\u00e9ment erron\u00e9e. C&rsquo;est \u00e0 tort que l&rsquo;on s&rsquo;est \u00e9loign\u00e9 de la tradition, de l&rsquo;esprit, de Dieu, de la religion, et c&rsquo;est l\u00e0 que l&rsquo;\u00e2ge moderne de l&rsquo;Europe occidentale a commenc\u00e9. Nous l&rsquo;avons per\u00e7ue sans esprit critique d\u00e8s le XVIIIe si\u00e8cle, lorsque nous avons \u00e9t\u00e9 emport\u00e9s par les Lumi\u00e8res europ\u00e9ennes. Mais jusqu&rsquo;en 1917, nous avons maintenu d&rsquo;une certaine mani\u00e8re le caract\u00e8re religieux de notre soci\u00e9t\u00e9. Puis nous avons plong\u00e9 dans l&rsquo;ab&icirc;me du mat\u00e9rialisme, et apr\u00e8s l&rsquo;effondrement de l&rsquo;URSS, nous sommes descendus encore plus profond\u00e9ment dans cet ab&icirc;me &#8211; dans un mat\u00e9rialisme capitaliste lib\u00e9ral encore plus d\u00e9brid\u00e9 et flagrant. Et finalement, nous nous sommes retrouv\u00e9s \u00e0 la p\u00e9riph\u00e9rie de la civilisation satanique occidentale, en tant que sa province.<\/em><\/p>\n<\/p>\n<p><p><em>En d&rsquo;autres termes, le concept de Satan prend aujourd&rsquo;hui, dans le cadre de la guerre contre l&rsquo;Occident, une toute autre signification dans notre soci\u00e9t\u00e9 que le concept de Dieu. S&rsquo;il y a Dieu, s&rsquo;il y a la foi et l&rsquo;&Eacute;glise, la Tradition et les valeurs traditionnelles, cela signifie qu&rsquo;il y a aussi l&rsquo;antith\u00e8se de Dieu, celui qui s&rsquo;est rebell\u00e9 contre Dieu. C&rsquo;est alors que l&rsquo;histoire de l&rsquo;Occident, l&rsquo;histoire du soi-disant progr\u00e8s, l&rsquo;\u00e9poque de la modernit\u00e9 des 500 derni\u00e8res ann\u00e9es s&rsquo;ouvre sous un jour compl\u00e8tement nouveau. Il s&rsquo;av\u00e8re que l&rsquo;Occident a rejet\u00e9 Dieu, a dit : il n&rsquo;y a ni Dieu ni diable, et le diable, comme apr\u00e8s un certain temps, a object\u00e9 : il n&rsquo;y a pas de Dieu, mais c&rsquo;est moi, parce que c&rsquo;est moi qui vous ai dit qu&rsquo;il n&rsquo;y avait pas de Dieu<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Peter Vlasov<\/em><\/strong><em> : <\/em>&laquo; <em>Ce que vous appelez le satanisme peut-il \u00eatre consid\u00e9r\u00e9 comme une construction id\u00e9ologique, ou s&rsquo;agit-il simplement d&rsquo;un principe de n\u00e9gation, de destruction ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Alexander Douguine<\/em><\/strong> : &laquo; <em>Nous ne devrions pas commencer par le satanisme, mais par Satan, par la figure que l&rsquo;on appelle par ce nom, si nous sommes des croyants, c&rsquo;est pour nous un fait ontologique. Pour les non-croyants, le satanisme n&rsquo;a pas de sens.<\/em><\/p>\n<\/p>\n<p><p><em>Qui est Satan, qui est Lucifer ? C&rsquo;est un ange, c&rsquo;est-\u00e0-dire l&rsquo;esprit c\u00e9leste \u00e9ternel. C&rsquo;est la premi\u00e8re cr\u00e9ation supr\u00eame de Dieu qui s&rsquo;est rebell\u00e9e contre Dieu. C&rsquo;est l&rsquo;origine de toutes les attaques contre Dieu, du mat\u00e9rialisme, de l&rsquo;ath\u00e9isme, de toutes les notions selon lesquelles des personnes sans Dieu peuvent construire un monde meilleur. Nous retrouvons ce principe dans l&rsquo;humanisme, dans le d\u00e9veloppement de la science moderne et dans la doctrine sociale du progr\u00e8s. Satan n&rsquo;est pas seulement la destruction ou l&rsquo;entropie, mais une volont\u00e9 consciente de d\u00e9truire. C&rsquo;est la r\u00e9bellion, la destruction de l&rsquo;unit\u00e9 au nom du triomphe de la multiplicit\u00e9. Ce n&rsquo;est pas seulement un affaiblissement de l&rsquo;ordre divin, c&rsquo;est la volont\u00e9 de le briser. Quand le corps est affaibli, c&rsquo;est une chose, mais quand il y a une force, comme le cancer ou une autre maladie naturelle, qui pousse le corps \u00e0 la d\u00e9composition, c&rsquo;en est une autre. Satan est l&rsquo;esprit, la volont\u00e9 de se d\u00e9composer, pas seulement la d\u00e9composition elle-m\u00eame, qui est d\u00e9j\u00e0 une cons\u00e9quence. En un sens, il s&rsquo;agit d&rsquo;une croyance, d&rsquo;une religion, d&rsquo;une anti-\u00e9glise. C&rsquo;est l&rsquo;&quot;\u00e9glise noire&quot; qui s&rsquo;incarne dans la culture occidentale moderne, la science, l&rsquo;\u00e9ducation, la politique. Nous voyons ici non seulement la d\u00e9cadence, mais aussi le refus de construire l&rsquo;ordre, la hi\u00e9rarchie, d&rsquo;\u00e9lever les principes de la science, de l&rsquo;esprit, de la pens\u00e9e, de la culture \u00e0 l&rsquo;unit\u00e9 la plus \u00e9lev\u00e9e, comme dans la civilisation traditionnelle, au d\u00e9but de la hi\u00e9rarchie, &ndash; parce que la hi\u00e9rarchie terrestre imite le rang ang\u00e9lique. &Agrave; ce refus de faire le bien s&rsquo;ajoute la volont\u00e9 de faire quelque chose de directement oppos\u00e9, de faire le mal. Quand on regarde les Ukrainiens, Biden, Soros, Macron, on voit une volont\u00e9 de destruction active, agressive. Le satanisme pr\u00e9suppose n\u00e9cessairement une strat\u00e9gie consciente et une impulsion volontaire qui g\u00e9n\u00e8re un mouvement puissant des masses humaines. Les masses peuvent d\u00e9truire la culture traditionnelle par leur stupidit\u00e9, leur passivit\u00e9, leur inertie &#8211; c&rsquo;est la propri\u00e9t\u00e9 de la masse en tant que telle, mais quelqu&rsquo;un pousse cette masse dans une direction destructrice, quelqu&rsquo;un la dirige, l&rsquo;oriente. C&rsquo;est l\u00e0 qu&rsquo;appara&icirc;t le principe du sujet oppos\u00e9 \u00e0 Dieu (ainsi qu&rsquo;\u00e0 l&rsquo;homme dans son sens le plus \u00e9lev\u00e9). On le retrouve dans toutes les religions : il s&rsquo;agit de cette volont\u00e9 consciente du sujet de construire une civilisation anti-Dieu, invers\u00e9e. Il ne s&rsquo;agit pas seulement de d\u00e9truire l&rsquo;existant, mais de cr\u00e9er quelque chose de d\u00e9go&ucirc;tant, de pervers, comme les femmes LGBT barbues de l&rsquo;Occident<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Peter Vlasov<\/em><\/strong><em> : <\/em>&laquo; Y a-t-il l\u00e0 une image de l&rsquo;avenir ? &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Alexander Douguine<\/em><\/strong> : &laquo; <em>Ren\u00e9 Gu\u00e9non, philosophe, partisan d&rsquo;une soci\u00e9t\u00e9 spirituelle traditionnelle, l&rsquo;a appel\u00e9e la Grande Parodie. C&rsquo;est \u00e0 cela que conduit la civilisation satanique. Si, au premier stade du mat\u00e9rialisme, il s&rsquo;agissait de nier toute spiritualit\u00e9, c&rsquo;est-\u00e0-dire d&rsquo;affirmer qu&rsquo;il n&rsquo;y a pas d&rsquo;esprit, mais seulement la mati\u00e8re, l&rsquo;homme, le monde terrestre, progressivement, au fur et \u00e0 mesure que cette Grande Parodie prend forme, un nouveau projet \u00e9merge : non seulement le rejet de l&rsquo;&Eacute;glise, mais la construction d&rsquo;une anti-&Eacute;glise, non seulement l&rsquo;oubli de l&rsquo;esprit, mais la cr\u00e9ation d&rsquo;une nouvelle spiritualit\u00e9, invers\u00e9e. Nous commen\u00e7ons par la destruction de l&rsquo;\u00e9glise, nous comparons tout \u00e0 la terre, il ne reste que l&rsquo;homme, mais apr\u00e8s cela, nous commen\u00e7ons \u00e0 construire un temple souterrain vers le bas, dans la direction oppos\u00e9e, nous faisons un trou dans la mati\u00e8re. L&rsquo;\u00e9crivain fran\u00e7ais Raymond Abellio a \u00e9crit un roman intitul\u00e9 \u00ab\u00a0La fosse de Babylone\u00a0\u00bb, qui traite de la construction de la civilisation dans le sens souterrain. Cette hi\u00e9rarchie invers\u00e9e, ce pouvoir invers\u00e9, cette spiritualit\u00e9 invers\u00e9e, voil\u00e0 ce qu&rsquo;est le satanisme occidental. &raquo;<\/em><\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Ainsi en est-il de la \u00ab\u00a0guerre en Ukraine\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>pour notre propos qui est celui de la d\u00e9constructuration, de l&rsquo;eschatologie, de la m\u00e9tahistoire, et qui nourrit l&rsquo;explication qui nous fait lier cet \u00e9v\u00e9nement directement \u00e0 celui de la d\u00e9constructuration wokeniste bien que les deux \u00e9v\u00e9nements ne soient pas du tout de la m\u00eame facture ni du m\u00eame domaine, &ndash; en apparence, certes. Mais on l&rsquo;a vu, on l&rsquo;a intuitivement ressenti je pense, &ndash; \u00ab\u00a0ni de la m\u00eame facture ni du m\u00eame domaine\u00a0\u00bb mais de la m\u00eame essence satanique, de la m\u00eame GrandeCrise, et l\u00e0 directement li\u00e9s. La proximit\u00e9 est telle que l&rsquo;on pourrait finalement concevoir, notamment en les prenant du point de vue si essentiel de la communication, de ne pas faire de r\u00e9elle diff\u00e9rence entre eux.<\/p>\n<\/p>\n<p><p>C&rsquo;est cela que j&rsquo;ai \u00e0 l&rsquo;esprit en anticipant peut-\u00eatre une attente ou une  question que certains de ces lecteurs parmi les hommes de ces temps-devenus-fous, comprenant notre d\u00e9marche devant ce qu&rsquo;ils jugent \u00eatre un passage en revue des diverses &lsquo;subcrises&rsquo; de la GrandeCrise, &ndash; mais la comprenant je crois en partie d&rsquo;une fa\u00e7on erron\u00e9e, assez dans tous les cas pour nous objecter : \u00ab\u00a0Comment ? Apr\u00e8s tout ce brouhaha sur l&rsquo;Ukraine, rien sur Isra\u00ebl (et sur Gaza certes&hellip;) ?\u00a0\u00bb La r\u00e9ponse se dit d&rsquo;elle-m\u00eame \u00e0 partir d&rsquo;un texte que nous \u00e9crivions le <u>11 octobre 2023<\/u>, et qui constituait un r\u00e9sum\u00e9 de l&rsquo;argument :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&bull; Le drame du week-end en Isra\u00ebl doit d\u00e9sormais se poursuivre avec l&rsquo;action de riposte que pr\u00e9parent les Isra\u00e9liens, et qui peut \u00eatre terrible. &bull; En soi, la crise entre Isra\u00ebl et les Palestiniens r\u00e9pond toujours aux m\u00eames param\u00e8tres et blocages <\/em>[que l&rsquo;on conna&icirc;t depuis soixante-dix ans]<em>, <strong>et en cela l&rsquo;attaque de dimanche ne change rien<\/strong>. &bull; Ce qui peut amener un changement politique de nature, non pas de la crise elle-m\u00eame, mais de l&rsquo;importance de la crise, c&rsquo;est <strong>justement la nature et, au-del\u00e0, la puissance de la riposte isra\u00e9lienne<\/strong>. &bull; Dans ce cas, cette tr\u00e8s vieille crise <strong>s&rsquo;inscrirait dans la GrandeCrise<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>\u00ab\u00a0Dans ce cas, cette tr\u00e8s vieille crise\u00a0\u00bb prendrait une allure tout \u00e0 fait nouvelle, in\u00e9dite, en s&rsquo;inscrivant dans une continuit\u00e9 qui lui para&icirc;t pourtant si \u00e9trang\u00e8re : les \u00e9lections am\u00e9ricanistes, le Covid, le wokenisme, &lsquo;<em>Ukrisis<\/em>&lsquo;&hellip; Car nous y sommes, et c&rsquo;est effectivement bien le cas : cette crise qui, en elle-m\u00eame, utilise des \u00e9v\u00e9nements d&rsquo;un autre temps pour les poursuivre, en les poursuivant dans des conditions si particuli\u00e8res principalement au niveau de la perception et donc de la communication, entre effectivement dans La GrandeCrise, et elle y entre comme continuation d\u00a0\u00bb<em>Ukrisis<\/em>&lsquo;, comme une perle est enfil\u00e9e \u00e0 la suite de la pr\u00e9c\u00e9dente pour participer \u00e0 la manufacture du collier \u00e0 la sublime perfection.<\/p>\n<\/p>\n<p><p>A cet \u00e9gard et pour ce qui la concerne, tout est dit. Nous voulons signifier par l\u00e0 que nous avons suffisamment suivi le chemin des fracas de l&rsquo;accumulation des tourbillons crisiques accouchant de subcrises successives (\u00e9lections am\u00e9ricanistes, Covid, wokenisme, &lsquo;<em>Ukrisis<\/em>&lsquo;) pour conclure que nous sommes au c&oelig;ur de la GrandeCrise, qu&rsquo;il est inutile de poursuivre cette sorte de chronique \u00e9v\u00e9nementielle, que d\u00e9sormais tout ce qui se passe dans le fracas continu des catastrophes crisiques entrent dans l&#8217;empire de la GrandeCrise de l&rsquo;effondrement du Syst\u00e8me, dans le trou noir du naufrage civilisationnel, dans l&rsquo;hallali du &lsquo;<em>Kali Yuga<\/em>&lsquo;, l&rsquo;&Acirc;ge de Fer et des T\u00e9n\u00e8bres de la Fin des Temps du cycle accompli jusqu&rsquo;\u00e0 son terme.<\/p>\n<\/p>\n<p><p>Ainsi est-il temps de discourir du survol de ce champ d\u00e9vast\u00e9 de la Terre martyris\u00e9e pour y apercevoir l&rsquo;annonce des temps nouveaux qui suivent n\u00e9cessairement la Fin des Temps.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Gr\u00e2ce-III : &lsquo;Ukrisis&lsquo; dans la GrandeCrise &bull; Pour suivre la voie trac\u00e9e par le texte sur le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb que l&rsquo;on peut trouver dans cette m\u00eame rubrique, voici un nouvel extrait du livre en pr\u00e9paration se pr\u00e9tendant comme la suite de la s\u00e9rie de &lsquo;La Gr\u00e2ce de l&rsquo;Histoire&lsquo;, et certainement toujours avec&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[19],"tags":[2631,13688,2792,3969,8386,2622,13716,1296],"class_list":["post-80971","post","type-post","status-publish","format-standard","hentry","category-glossairedde","tag-de","tag-deconstructuration","tag-douguine","tag-grace","tag-lhistoire","tag-la","tag-satan","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=80971"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/80971\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=80971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=80971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=80971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}