{"id":81056,"date":"2024-05-02T01:37:01","date_gmt":"2024-05-02T01:37:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/05\/02\/emmanuel-todd-et-le-narcissisme-occidental\/"},"modified":"2024-05-02T01:37:01","modified_gmt":"2024-05-02T01:37:01","slug":"emmanuel-todd-et-le-narcissisme-occidental","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/05\/02\/emmanuel-todd-et-le-narcissisme-occidental\/","title":{"rendered":"Emmanuel Todd et le narcissisme occidental"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Emmanuel Todd et le narcissisme occidental<\/strong><\/h2>\n<\/p>\n<p><p>Pepe Escobar a bien r\u00e9sum\u00e9 r\u00e9cemment les observations d&rsquo;Emmanuel Todd. Elles me conduisent \u00e0 rapprocher cet auteur de Freud quand, dans son Inqui\u00e9tante \u00e9tranget\u00e9 (que j&rsquo;ai beaucoup \u00e9voqu\u00e9 dans mon livre sur Kubrick), ce dernier \u00e9voque les d\u00e9m\u00eal\u00e9s du narcissisme psychique avec la trop dure r\u00e9alit\u00e9 et &laquo; ses v\u00e9h\u00e9mentes protestations &raquo;&hellip;<\/p>\n<\/p>\n<p><p>Le plus important est l\u00e0, rappelle Escobar :<\/p>\n<\/p>\n<p><p>&laquo; 1. Au d\u00e9but de l&rsquo;op\u00e9ration militaire sp\u00e9ciale (SMO) en f\u00e9vrier 2022, le PIB combin\u00e9 de la Russie et de la Bi\u00e9lorussie ne repr\u00e9sente que 3,3% de celui de l&rsquo;Occident r\u00e9uni (en l&rsquo;occurrence la sph\u00e8re de l&rsquo;OTAN plus le Japon et la Cor\u00e9e du Sud). Todd s&rsquo;\u00e9tonne que ces 3,3%, capables de produire plus d&rsquo;armes que l&rsquo;ensemble du colosse occidental, non seulement gagnent la guerre, mais r\u00e9duisent \u00e0 n\u00e9ant les notions dominantes de l&rsquo;&laquo;\u00e9conomie politique n\u00e9olib\u00e9rale&raquo; (taux de PIB). &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est Kubrick qui fait dire dans Folamour \u00e0 un de ses g\u00e9n\u00e9raux g\u00e9nocidaires yankees qu&rsquo;on est face \u00e0 un tas de moujiks ignorants. Donc avec 3% du PNB des USA, ou de l&rsquo;Espagne (qui refile, Pierre d\u00e9shabillant Paul, ses Patriot \u00e0 Z.), ou de Monaco, la Russie tient t\u00eate \u00e0 tout l&rsquo;occident. On verra quand l&rsquo;Otan enverra ses troupes : leur \u00e9ni\u00e8me op\u00e9ration barbe roussie promet&#8230;<\/p>\n<\/p>\n<p><p>Puis on se rapproche de Freud :<\/p>\n<\/p>\n<p><p>&laquo; 2. La &laquo;solitude id\u00e9ologique&raquo; et le &laquo;narcissisme id\u00e9ologique&raquo; de l&rsquo;Occident &ndash; incapable de comprendre, par exemple, comment &laquo;l&rsquo;ensemble du monde musulman semble consid\u00e9rer la Russie comme un partenaire plut\u00f4t que comme un adversaire&raquo;. &raquo;<\/p>\n<\/p>\n<p><p>Je vais citer Freud (voyez mon texte sur Freud politiquement incorrect &ndash; et Dieu qu&rsquo;il l&rsquo;\u00e9tait, comme le rappela Onfray &ndash;exemplaire d\u00e9dicac\u00e9 \u00e0 Mussolini !) :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;analyse de ces divers cas d&rsquo;inqui\u00e9tante \u00e9tranget\u00e9 nous a ramen\u00e9s \u00e0 l&rsquo;ancienne conception du monde, \u00e0 l&rsquo;animisme, conception caract\u00e9ris\u00e9e par le peuplement du monde avec des esprits humains, par la surestimation narcissique de nos propres processus psychiques, par la toute-puissance des pens\u00e9es et la technique de la magie bas\u00e9e sur elle, par la r\u00e9partition de forces magiques soigneusement gradu\u00e9es entre des personnes \u00e9trang\u00e8res et aussi des choses (Mana), de m\u00eame que par toutes les cr\u00e9ations au moyen desquelles le narcissisme illimit\u00e9 de cette p\u00e9riode de l&rsquo;\u00e9volution se d\u00e9fendait contre la protestation \u00e9vidente de la r\u00e9alit\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est pareil pour tout : invasion migratoire, abolition des sexes, nazisme sanitaire, dette immonde, catastrophe ou sabotage \u00e9colo-politique : l&rsquo;occident veut nier toute r\u00e9alit\u00e9. Il est gnostique au sens bouffonnant du terme. Cette tendance ancienne (per\u00e7ue d\u00e9j\u00e0 par Poe, Nietzsche ou Tocqueville) s&rsquo;est acc\u00e9l\u00e9r\u00e9e avec Internet, comme je l&rsquo;avais montr\u00e9 dans mon bouquin publi\u00e9 en 2001 et qui s&rsquo;\u00e9tait retrouv\u00e9 (horresco referens&hellip;) Une du Monde des Livres. J&rsquo;avais aussi \u00e9voqu\u00e9 les techno-lords (notion qui m&rsquo;a \u00e9t\u00e9 froidement piqu\u00e9e depuis) et cette technognose qui doit d\u00e9boucher n&ucirc;ment sur leur homme-robot.<\/p>\n<\/p>\n<p><p>Continuons avec Todd r\u00e9sum\u00e9 par Escobar :<\/p>\n<\/p>\n<p><p>&laquo; 4. L&rsquo;implosion, \u00e9tape par \u00e9tape, de la culture WASP, qui a conduit, &laquo;depuis les ann\u00e9es 1960&raquo;, \u00e0 &laquo;un empire priv\u00e9 de centre et de projet, un organisme essentiellement militaire g\u00e9r\u00e9 par un groupe sans culture (au sens anthropologique)&raquo;. Voil\u00e0 comment Todd d\u00e9finit les n\u00e9ocons am\u00e9ricains. &raquo;<\/p>\n<\/p>\n<p><p>Cette implosion a \u00e9t\u00e9 d\u00e9crite par Kevin McDonald et surtout par Thomas Frank dans un livre demeur\u00e9 non traduit : la conqu\u00eate du cool. Frank \u00e9voque le r\u00f4le de la pub (et de Volkswagen) pour alt\u00e9rer le logiciel am\u00e9ricain. Pour moi l&rsquo;aspect le plus important est que &laquo;l&rsquo;on peut ne pas reconna&icirc;tre un peuple apr\u00e8s cinq ans de reprogrammation.&raquo; On fabrique du gastronome, du mangeur d&rsquo;insectes, du h\u00e9ros, du cr\u00e9tin, du l\u00e2che, de l&rsquo;\u00e9colo-antiraciste-f\u00e9ministe imb\u00e9cile en finalement peu de temps. C&rsquo;est ce qu&rsquo;explique g\u00e9nialement l&rsquo;Anglaise g\u00e9niale de Taine &hellip;<\/p>\n<\/p>\n<p><p>Pepe ajoute ensuite excellemment :<\/p>\n<\/p>\n<p><p>&laquo; 8. La critique acerbe de Todd sur l&rsquo;esprit de 1968 m\u00e9riterait un tout nouveau livre. Il \u00e9voque &laquo;l&rsquo;une des grandes illusions des ann\u00e9es 60 &ndash; entre la r\u00e9volution sexuelle anglo-am\u00e9ricaine et Mai 68 en France&raquo; : &laquo;croire que l&rsquo;individu serait plus grand s&rsquo;il \u00e9tait lib\u00e9r\u00e9 du collectif&raquo;. Cela a conduit \u00e0 une d\u00e9b\u00e2cle in\u00e9vitable : &laquo;Maintenant que nous sommes lib\u00e9r\u00e9s, en masse, des croyances m\u00e9taphysiques, fondatrices et d\u00e9riv\u00e9es, communistes, socialistes ou nationalistes, nous vivons l&rsquo;exp\u00e9rience du vide&raquo;. Et c&rsquo;est ainsi que nous sommes devenus &laquo;une multitude de nains mim\u00e9tiques qui n&rsquo;osent pas penser par eux-m\u00eames &ndash; mais se r\u00e9v\u00e8lent aussi capables d&rsquo;intol\u00e9rance que les croyants de l&rsquo;Antiquit\u00e9&raquo;.<\/p>\n<\/p>\n<p><p>Lipovetsky a tr\u00e8s bien d\u00e9crit cette \u00e8re du vide il y a d\u00e9j\u00e0 quarante ans. Et Debord parle d\u00e9j\u00e0 d&rsquo;un conglom\u00e9rat de solitudes sans illusions, et Pouchkine (dans Eug\u00e8ne On\u00e9guine, traduction de ma femme) \u00e9crit g\u00e9nialement \u00e0 vingt ans vars 1820 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em>&laquo; Mais nous n&rsquo;avons m\u00eame pas de l&rsquo;amiti\u00e9.<\/em><\/p>\n<\/p>\n<p><p><em>Nous avons d\u00e9truit tous les pr\u00e9jug\u00e9s ;<\/em><\/p>\n<\/p>\n<p><p><em>On prend pour les z\u00e9ros les autres gens<\/em><\/p>\n<\/p>\n<p><p><em>En se prenant pour le &laquo; un &raquo; s\u00e9rieusement.<\/em><\/p>\n<\/p>\n<p><p><em>Tous &ndash; nous tendons vers Napol\u00e9on,<\/em><\/p>\n<\/p>\n<p><p><em>Et les bip\u00e8des cr\u00e9atures, en millions,<\/em><\/p>\n<\/p>\n<p><p><em>Ne sont pour nous que des outils ;<\/em><\/p>\n<\/p>\n<p><p><em>Le sentiment pour nous est une \u00e9trange b\u00eatise. &raquo;<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Lignes extraordinaires. Disparition des corps interm\u00e9diaires ; l&rsquo;individu nu devant le march\u00e9 (Houellebecq, pour faire facile) ou devant l&rsquo;Etat (Jouvenel).<\/p>\n<\/p>\n<p><p>Sur les USA, sujet essentiel tout de m\u00eame :<\/p>\n<\/p>\n<p><p>&laquo; 5. Les &Eacute;tats-Unis en tant qu&rsquo;entit\u00e9 &laquo;post-imp\u00e9riale&raquo; : une simple coquille de machinerie militaire priv\u00e9e d&rsquo;une culture ax\u00e9e sur l&rsquo;intelligence, conduisant \u00e0 &laquo;une expansion militaire accentu\u00e9e dans une phase de contraction massive de sa base industrielle&raquo;. Comme le souligne Todd, &laquo;la guerre moderne sans industrie est un oxymore&raquo;. &raquo;<\/p>\n<\/p>\n<p><p>Notons que Baudrillard nie le d\u00e9clin US comme d&rsquo;autres : le pays au sens mat\u00e9riel  est liquid\u00e9 par son \u00e9lite gnostique (Yvan Blot avait beaucoup insist\u00e9 sur cette notion lors de nos entretiens), puissance militaire incluse, mais sa matrice informatique et m\u00e9diatique &ndash; et maintenant pharmaceutique &ndash; imbibe le monde. Elle tient l&rsquo;Inde et le Br\u00e9sil sous sa coupe par exemple, Brics ou pas Brics. Quant au pr\u00e9sident chinois, on sait qu&rsquo;il ne jure que par &laquo; son ami Bill Gates &raquo;&hellip; Avant de parler de Lib\u00e9ration&hellip;<\/p>\n<\/p>\n<p><p>Sur l&rsquo;Europe maintenant :<\/p>\n<\/p>\n<p><p>&laquo; 10. Le &laquo;suicide assist\u00e9&raquo; de l&rsquo;Europe. Todd rappelle que l&rsquo;Europe, au d\u00e9part, c&rsquo;\u00e9tait le couple franco-allemand. Puis, apr\u00e8s la crise financi\u00e8re de 2007\/2008, ce couple s&rsquo;est transform\u00e9 en &laquo;un mariage patriarcal, avec l&rsquo;Allemagne comme \u00e9poux dominant qui n&rsquo;\u00e9coute plus son compagnon&raquo;. L&rsquo;UE a abandonn\u00e9 toute pr\u00e9tention \u00e0 d\u00e9fendre les int\u00e9r\u00eats de l&rsquo;Europe en se coupant de l&rsquo;\u00e9nergie et du commerce avec son partenaire, la Russie, et en se sanctionnant elle-m\u00eame. Todd identifie, \u00e0 juste titre, l&rsquo;axe Paris-Berlin remplac\u00e9 par l&rsquo;axe Londres-Varsovie-Kiev : ce fut &laquo;la fin de l&rsquo;Europe en tant qu&rsquo;acteur g\u00e9opolitique autonome&raquo;. Et cela s&rsquo;est produit seulement 20 ans apr\u00e8s l&rsquo;opposition commune de la France et de l&rsquo;Allemagne \u00e0 la guerre n\u00e9oconservatrice contre l&rsquo;Irak. &raquo;<\/p>\n<\/p>\n<p><p>Rappelons que Todd sur ce sujet comme sur d&rsquo;autres s&rsquo;est compl\u00e8tement tromp\u00e9, qui annon\u00e7ait sans preuves une Europe libre et vive dans son Apr\u00e8s l&rsquo;Empire. Ce titre \u00e9tait faux aussi : l&rsquo;Empire cro&icirc;t et se multiplie &ndash; \u00e0 chaque clic pour commencer. Malheur \u00e0 celui qui rec\u00e8le des d\u00e9serts, dit Zarathoustra&hellip;<\/p>\n<\/p>\n<p><p>Enfin, on enfonce une porte ouverte :<\/p>\n<\/p>\n<p><p>&laquo; 11. Todd d\u00e9finit correctement l&rsquo;OTAN en plongeant dans &laquo;leur inconscient&raquo; : &laquo;Nous constatons que son dispositif militaire, id\u00e9ologique et psychologique n&rsquo;existe pas pour prot\u00e9ger l&rsquo;Europe occidentale, mais pour la contr\u00f4ler&raquo;. &raquo;<\/p>\n<\/p>\n<p><p>On verra si la r\u00e9alit\u00e9 (qui vit encore en contact avec elle, terrestre ou c\u00e9leste ?) peut encore quelque chose contre le monde virtuel que notre &laquo; amer Ca\u00efn &raquo; a mis en place pour contr\u00f4ler le monde ou ce qui reste de nos vieilles et fain\u00e9antes nations europ\u00e9ennes. Le triomphe de l&rsquo;OMS dans quelques semaines va nous rappeler qui est le ma&icirc;tre.<\/p>\n<\/p>\n<p><p>Priez fort.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Sources<\/strong><\/h3>\n<\/p>\n<p><p><a href=\"https:\/\/reseauinternational.net\/comment-loccident-a-ete-vaincu\/\">https:\/\/reseauinternational.net\/comment-loccident-a-ete-vaincu\/<\/a><\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.amazon.fr\/Internet-nouvelle-initiatique-Nicolas-Bonnal\/dp\/2251441689\/ref=sr_1_3?__mk_fr_FR=\u00c5M\u00c5\u00d5\u00d1&#038;crid=2ESYWLE3FUBGU&#038;dib=eyJ2IjoiMSJ9.l632GJRCHjZU1j9_7yuzSa5KFsxSYcm1AFUEYsTGC1PO1WBuL8My1sQe9wkJVNTSRikme6HXrHnuj3jYRRh3iA.ncLC0XzvlbVHRCF3Hwg0u2upv6_FZ8cqMnZrFz7TaZg&#038;dib_tag=se&#038;keywords=bonnal+internet&#038;qid=1714202695&#038;s=books&#038;sprefix=bonnal+internet%2Cstripbooks%2C140&#038;sr=1-3\">Internet,<\/a> la voie i,itiatique<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.amazon.fr\/Conquest-Cool-Business-Counterculture-Consumerism\/dp\/0226260127\/ref=sr_1_1?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;crid=3LZDL32ZTYY4X&#038;dib=eyJ2IjoiMSJ9.pV_1HySFT2DopP9h9YZieUp4XLmMeMHeYpfBSfT3alTALRF1hk5_wuxQBCFjbJdH4GTfq3fGYQ6FmZ0JfNkGU5iVn6s0R0tHP5klRWKVt7c.sN9m55ckpWgT6L-5EEgXVf0A7-gdPuEKKorCF5ZubyY&#038;dib_tag=se&#038;keywords=thomas+frank+cool&#038;qid=1714202723&#038;s=books&#038;sprefix=thomas+frank+cool%2Cstripbooks%2C141&#038;sr=1-1\">The Conquest of Cool: Business Culture, Counterculture, and the Rise of Hip Consumerism<\/a><\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.amazon.fr\/EUGENE-ONEGUINE-Bilingue-Traduction-Popova-Bonnal\/dp\/B09L4X46G1\/ref=sr_1_1?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;crid=22GLK6519JYZX&#038;dib=eyJ2IjoiMSJ9.t7me4ro0e_-fjJ5u4108Cw.--dcHZKssHbEzA5khEEl7RAC3hgM1O6TcaraY_BtkVk&#038;dib_tag=se&#038;keywords=pouchkine+bonnal+oneguine&#038;qid=1714202763&#038;s=books&#038;sprefix=pouchkine+bonnal+oneguine%2Cstripbooks%2C142&#038;sr=1-1\">Eug\u00e8ne On\u00e9guine (bilingue, traduction: Tatyana popova-Bonnal)<\/a><\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.amazon.fr\/D%C3%A9faite-lOccident-Emmanuel-Todd\/dp\/2073041132\/ref=sr_1_1?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;crid=EWF3MRAI9EHB&#038;dib=eyJ2IjoiMSJ9.DIOk_n9NlGEXHp25MYnBL_mfgWmOtVBZLgqreBU3ANTM9f1-TDBYpy9eHBY-fgjF7YRNK07gdGlehJAur2EBilhz78DvY6RqPJ-T5_rpcoQSbSRzJjZF0kkhSNHvwUhLw472bqxbrutrtQIKSmsoL85QQ3SUoRa9uK6Ko8gXT_tVaKVuatjozB6E_ZTslB_ysCHMmfbeSvtdtigUQ7WOd4tDhpm4JZCpc2axjTOKpCE.iyzPTtNozOxWHB4auezRqkor8msFJ9-MxB5l-o7qXbc&#038;dib_tag=se&#038;keywords=todd+occident&#038;qid=1714202784&#038;s=books&#038;sprefix=todd+occident%2Cstripbooks%2C115&#038;sr=1-1\">La d\u00e9faite de l&rsquo;Occident<\/a><\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.amazon.fr\/Apr%C3%A8s-lempire-d%C3%A9composition-syst%C3%A8me-am%C3%A9ricain\/dp\/207031300X\/ref=sr_1_1?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;crid=1SACBQPYTC7K2&#038;dib=eyJ2IjoiMSJ9.sd3SI1aP-2Id0YlgKf_yiwPNsiCTeKJOUB9fr6i1TVbDgKxKi8JaHIH3AkXrpQaunwZ-r8S0tivTChzuDkiUxg5cOX9UDTgrd-Et9ihPzHw2XEJVCLSFpQISe2ITTX1J9p36YN9pIxA54j4Wxk8wlPhdo7RONNvtN4Km339AuP6UeuaO86EO5LeHPZyNEvpwYQiJu8egWzw6i7Zq3dMfUo3KdsliVtjStEjATv3vqgI.TNbzCgKCosWddOHb91BAk5NAbu4LyyTHhwsygxpdrvI&#038;dib_tag=se&#038;keywords=todd+empire&#038;qid=1714202794&#038;s=books&#038;sprefix=todd+empire%2Cstripbooks%2C120&#038;sr=1-1\">Apr\u00e8s l&#8217;empire, essai sur la d\u00e9compositiondu syst\u00e8me am\u00e9ricain<\/a><\/p>\n<\/p>\n<p><p><a href=\"https:\/\/nicolasbonnal.wordpress.com\/2023\/10\/20\/michel-foucault-et-le-dressage-des-hommes-machines-aux-temps-modernes\/\">https:\/\/nicolasbonnal.wordpress.com\/2023\/10\/20\/michel-foucault-et-le-dressage-des-hommes-machines-aux-temps-modernes\/<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emmanuel Todd et le narcissisme occidental Pepe Escobar a bien r\u00e9sum\u00e9 r\u00e9cemment les observations d&rsquo;Emmanuel Todd. Elles me conduisent \u00e0 rapprocher cet auteur de Freud quand, dans son Inqui\u00e9tante \u00e9tranget\u00e9 (que j&rsquo;ai beaucoup \u00e9voqu\u00e9 dans mon livre sur Kubrick), ce dernier \u00e9voque les d\u00e9m\u00eal\u00e9s du narcissisme psychique avec la trop dure r\u00e9alit\u00e9 et &laquo; ses&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2769,13844,2640,2631,2985,2986,4389,3625],"class_list":["post-81056","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-americain","tag-baudrouillard","tag-bonnal","tag-de","tag-fin","tag-lempire","tag-leurope","tag-todd"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81056"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81056\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}