{"id":81063,"date":"2024-05-07T18:06:54","date_gmt":"2024-05-07T18:06:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/05\/07\/tout-se-deroule-selon-le-plan-imprevu\/"},"modified":"2024-05-07T18:06:54","modified_gmt":"2024-05-07T18:06:54","slug":"tout-se-deroule-selon-le-plan-imprevu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/05\/07\/tout-se-deroule-selon-le-plan-imprevu\/","title":{"rendered":"Tout se d\u00e9roule selon le plan impr\u00e9vu"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Tout se d\u00e9roule selon le plan impr\u00e9vu<\/strong><\/h2>\n<\/p>\n<p><p>7 mai 2024 (18H15) &ndash; Cela \u00e9tait bien pr\u00e9vu et assur\u00e9, essentiellement du c\u00f4t\u00e9 am\u00e9ricaniste-occidentaliste o&ugrave; il suffisait d&rsquo;attendre l&rsquo;effondrement \u00e9conomique de la Russie (et la chute de Poutine qui s&rsquo;en serait suivie) du fait des sanctions prises les 24-26 f\u00e9vrier 2022, pour voir la victorieuse arm\u00e9e ukrainienne \u00e9ventuellement entrer dans Moscou dans la liesse d&rsquo;une foule enfin lib\u00e9r\u00e9e de son tyran. Cela promettait de ce fait :<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;absence d&rsquo;une \u00ab\u00a0internationalisation\u00a0\u00bb du conflit, et la non-implication de l&rsquo;OTAN ;<\/p>\n<\/p>\n<p><p>&bull; et, bien entendu, cela \u00e9cartait tout recours \u00e0 l&rsquo;arme nucl\u00e9aire et donc les risques d&rsquo;une v\u00e9ritable Troisi\u00e8me Guerre mondiale.<\/p>\n<\/p>\n<p><p>Ainsi \u00e9tait le \u00ab\u00a0plan\u00a0\u00bb pr\u00e9vu. Actuellement, on se trouve \u00e0 peu pr\u00e8s, grossi\u00e8rement r\u00e9sum\u00e9e,  dans une situation telle que la d\u00e9crit  &lsquo;<em><a href=\"https:\/\/www.wsws.org\/en\/articles\/2024\/05\/07\/qtgn-m07.html\">WSWS.org<\/a><\/em>&lsquo;, effectivement selon la parfaite \u00ab\u00a0situation impr\u00e9vue\u00a0\u00bb : d\u00e9faite de l&rsquo;Ukraine, possibilit\u00e9 d&rsquo;une \u00ab\u00a0guerre pan-europ\u00e9enne\u00a0\u00bb, possibilit\u00e9 de l&#8217;emploi du nucl\u00e9aire<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>De plus en plus d&rsquo;\u00e9l\u00e9ments indiquent que la guerre de l&rsquo;OTAN contre la Russie entre dans une nouvelle phase d&rsquo;escalade qui menace de conduire \u00e0 l&rsquo;utilisation d&rsquo;armes nucl\u00e9aires. De hauts responsables de l&rsquo;OTAN parlent publiquement de recourir \u00e0 des frappes de missiles et \u00e0 une guerre terrestre contre la Russie, tandis que les responsables russes avertissent qu&rsquo;ils pourraient lancer des contre-attaques contre les pays de l&rsquo;OTAN.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>La semaine derni\u00e8re, 100 artilleurs et sp\u00e9cialistes de la surveillance de la L\u00e9gion \u00e9trang\u00e8re fran\u00e7aise ont \u00e9t\u00e9 d\u00e9ploy\u00e9s sur les lignes de front \u00e0 Slavyansk en Ukraine, selon un rapport de l&rsquo;ancien sous-secr\u00e9taire am\u00e9ricain \u00e0 la d\u00e9fense, Stephen Bryen, publi\u00e9 dans le Asia Times. M. Bryen a d\u00e9clar\u00e9 que 1 500 autres l\u00e9gionnaires \u00e9trangers fran\u00e7ais pourraient bient\u00f4t \u00eatre d\u00e9ploy\u00e9s en Ukraine. Il a \u00e9crit qu&rsquo;une des cons\u00e9quences de ce d\u00e9ploiement est \u00ab\u00a0le d\u00e9clenchement potentiel d&rsquo;une guerre paneurop\u00e9enne\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On conna&icirc;t les diff\u00e9rentes \u00e9tapes qui ont men\u00e9 \u00e0 cette situation totalement impr\u00e9vue, qui s&rsquo;est construite sur des d\u00e9cisions cat\u00e9goriques emp\u00eachant tout engagement de l&rsquo;Occident-corruptif dans la bataille et se terminant par son contraire et donc en engagement de plus en plus net. Ainsi Macron, &ndash; bien connu pour sa fr\u00e9quentation des servilit\u00e9s aveugles et de la moutonnerie humaine, &ndash; confiait-il alors qu&rsquo;on lui reprochait, en avril, de se mettre \u00e0 dos tout le reste de l&rsquo;OTAN et de risquer une guerre avec sa remarque sur la possibilit\u00e9 de d\u00e9ployer des troupes en Ukraine, quelque chose comme \u00e7a (on cite approximativement) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Vous verrez, comme pour le reste, les chars, les missiles, tout \u00e7a, ils finiront par y venir<\/em> &raquo;&#8230;.<\/p>\n<\/p>\n<p><p><strong><em>Note de PhG-Bis<\/em><\/strong> : &laquo; <em>Macron, ou l&rsquo;accointance avec le Diable, lequel sait bien qu&rsquo;il n&rsquo;y a nulle trahison \u00e0 craindre d&rsquo;un \u00eatre aussi corrompu (je parle l\u00e0 de Macron)<\/em>. <em>Son serviteur fera toujours ce qu&rsquo;il (je parle ici du Diable) lui enjoint de faire.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il se d\u00e9duit de tout cela que le \u00ab\u00a0plan impr\u00e9vu\u00a0\u00bb \u00e9tait hautement pr\u00e9visible et que de vilains esprits annoncent depuis deux ans que les choses tourneraient de cette fa\u00e7on en Ukraine. Nul n&rsquo;est capable, en aucune fa\u00e7on, de comprendre pourquoi, dans quel but strat\u00e9gique, avec quels moyens politiques et militaires, cette affaire \u00e9volue dans le sens qu&rsquo;on lui voit. Rien, aucune vision conceptuelle, et m\u00eame aucun machiav\u00e9lisme montrant une certaine habilet\u00e9 de la pens\u00e9e&#8230; Aucun \u00ab\u00a0plan\u00a0\u00bb (justement), m\u00eame pas <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2024-dc-la-folle-sous-biden-vu-par-hersh)\">une NIE<\/a> pour savoir o&ugrave; l&rsquo;on va&#8230; Mais l&rsquo;on y va !<\/p>\n<\/p>\n<p><p>Je vous ai parl\u00e9 du Diable en vous parlent du petit t\u00e9l\u00e9graphiste (je veux dire Macron) des consignes diaboliques du patron. Je vous en reparle devant ce grand \u00e9v\u00e9nement qu&rsquo;aucune raison ne se risque \u00e0 nous expliquer. Il y a, en marche, une dynamique d&rsquo;une puissance d\u00e9structurante \u00e9pouvantable, hors de notre port\u00e9e et de notre compr\u00e9hension, qui r\u00e9serve \u00e0  notre civilisation maudite un sort bien peu enviable. Qu&rsquo;importe si ceux qui figurent dans cette immense <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> soient de si petit format ; d&rsquo;ailleurs, c&rsquo;est ce qui passe le mieux inaper\u00e7u.<\/p>\n<\/p>\n<p><p>Notez d&rsquo;ailleurs la parfaite coordination avec d&rsquo;autres \u00ab\u00a0subcrises\u00a0\u00bb en cours, en Palestine avec le d\u00e9but de l &lsquo;attaque de Rafah, et aux USA m\u00eame o&ugrave; la r\u00e9volte des \u00e9tudiants des campus atteint des dimensions terribles et fait penser aux \u00e9v\u00e9nements des ann\u00e9es 1960 (\u00e9coutez donc Mercouris et Jeffrey Sachs <a href=\"https:\/\/theduran.com\/campus-protests-and-biden-policy-w-jeffrey-sachs-live\/\">l\u00e0-dessus<\/a>).<\/p>\n<\/p>\n<p><p>C&rsquo;est \u00e0 croire que le Diable avait tout pr\u00e9vu pour son \u00ab\u00a0plan impr\u00e9vu\u00a0\u00bb. J&rsquo;esp\u00e8re que nul ne s&rsquo;en \u00e9tonnera, parmi nous qui sommes habitu\u00e9s aux explications tordus des complotistes de nos gouvernants. Rien de plus simple que le plan du Diable, toujours \u00ab\u00a0impr\u00e9vu\u00a0\u00bb pour que nous n&rsquo;y comprenions rien, nous laissant aux complotismes institutionnalis\u00e9es et aux bataillons de collabos qui peuplent nos salons et nos boudoirs.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout se d\u00e9roule selon le plan impr\u00e9vu 7 mai 2024 (18H15) &ndash; Cela \u00e9tait bien pr\u00e9vu et assur\u00e9, essentiellement du c\u00f4t\u00e9 am\u00e9ricaniste-occidentaliste o&ugrave; il suffisait d&rsquo;attendre l&rsquo;effondrement \u00e9conomique de la Russie (et la chute de Poutine qui s&rsquo;en serait suivie) du fait des sanctions prises les 24-26 f\u00e9vrier 2022, pour voir la victorieuse arm\u00e9e ukrainienne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2645,2617,3851,13849,1296],"class_list":["post-81063","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-guerre","tag-macron","tag-mondiale","tag-pan-europeenne","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81063"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81063\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}