{"id":81080,"date":"2024-05-19T17:45:20","date_gmt":"2024-05-19T17:45:20","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/05\/19\/la-logique-orwellienne-de-leur-guerre-antirusse\/"},"modified":"2024-05-19T17:45:20","modified_gmt":"2024-05-19T17:45:20","slug":"la-logique-orwellienne-de-leur-guerre-antirusse","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/05\/19\/la-logique-orwellienne-de-leur-guerre-antirusse\/","title":{"rendered":"La logique orwellienne de leur guerre antirusse"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>La logique orwellienne de leur guerre antirusse<\/strong><\/h2>\n<\/p>\n<p><p>Guerre interminable ? George Orwell : &laquo; La guerre est engag\u00e9e par chaque groupe dirigeant contre ses propres sujets et l&rsquo;objet de la guerre n&rsquo;est pas de faire ou d&#8217;emp\u00eacher des conqu\u00eates de territoires, mais de maintenir intacte la structure de la soci\u00e9t\u00e9. &raquo;.<\/p>\n<\/p>\n<p><p>Certains se demandent ce que font les russes, d&rsquo;autres se demandent m\u00eame s&rsquo;ils perdent. Les plus enflamm\u00e9s des antisyst\u00e8mes prorusses crient au g\u00e9nie \u00e9chiquier et judoka de Poutine puis traitent d&rsquo;agents de l&rsquo;Otan ceux qui ne sont pas d&rsquo;accord. Parfois il y en a qui observent que le patron de l&rsquo;Otan voudrait une guerre orwellienne et donc interminable.<\/p>\n<\/p>\n<p><p>Le g\u00e9n\u00e9ral Delawarde avait \u00e9crit un texte o&ugrave; il posait les vraies questions :<\/p>\n<\/p>\n<p><p>&laquo; D\u00e8s le d\u00e9but de l&rsquo;op\u00e9ration en Ukraine, j&rsquo;ai commenc\u00e9 \u00e0 me poser de nombreuses questions sur ses buts, ses objectifs et son r\u00e9sultat final. Les actions de notre arm\u00e9e et de nos autorit\u00e9s ont clairement indiqu\u00e9 que la Russie ne s&rsquo;effor\u00e7ait pas d&rsquo;achever rapidement l&rsquo;op\u00e9ration.<\/p>\n<p>Voyez comme c&rsquo;est \u00e9trange :<\/p>\n<p>&ndash; Retrait volontaire des troupes pr\u00e8s de Kiev ;<\/p>\n<p>&ndash; Refus de la prise d&rsquo;initiative ;<\/p>\n<p>&ndash; Arr\u00eat des op\u00e9rations offensives et passage en d\u00e9fensif ;<\/p>\n<p>&ndash; N\u00e9gociations d\u00e9lib\u00e9r\u00e9ment d\u00e9nu\u00e9es de sens ;<\/p>\n<p>&ndash; &Eacute;tranges \u00e9changes de prisonniers ;<\/p>\n<p>&ndash; Frappes quasi-exclusivement contre des cibles militaires ;<\/p>\n<p>&ndash; Refus cat\u00e9gorique d&rsquo;endommager les infrastructures strat\u00e9giques \u00ab\u00a0civiles\u00a0\u00bb ;<\/p>\n<p>&ndash; R\u00e9f\u00e9rendums organis\u00e9s \u00e0 la h\u00e2te ;<\/p>\n<p>&ndash; Refus d&rsquo;attaquer les QG et centres de d\u00e9cision ennemis.<\/p>\n<\/p>\n<p><p>Rasoir d&rsquo;Ockham aidant, la r\u00e9ponse viendrait vite :<\/p>\n<\/p>\n<p><p>&laquo; &Eacute;videmment, l&rsquo;option la plus simple est de consid\u00e9rer que nos autorit\u00e9s (russes) sont des imb\u00e9ciles. Bien s&ucirc;r, qu&rsquo;elles sont capables de mener une guerre normale. Pourquoi ne le font-elles pas ? &raquo;<\/p>\n<\/p>\n<p><p>Alors le g\u00e9n\u00e9ral fait une audacieuse observation :<\/p>\n<\/p>\n<p><p>&laquo; De longues r\u00e9flexions m&rsquo;ont amen\u00e9 \u00e0 la conclusion suivante :<\/p>\n<p>Si l&rsquo;on consid\u00e8re que l&rsquo;op\u00e9ration n&rsquo;est qu&rsquo;une des \u00e9tapes de la lutte contre l&rsquo;Occident, il s&rsquo;av\u00e8re que la Russie n&rsquo;a vraiment pas besoin d&rsquo;une victoire rapide et d\u00e9cisive en Ukraine. L&rsquo;arm\u00e9e est inutile trop en avant. Une d\u00e9faite rapide et compl\u00e8te de l&rsquo;Ukraine ne changera rien pour nous en termes g\u00e9opolitiques. Nous aurons de nouveaux territoires et de nouvelles populations, mais l&rsquo;alignement g\u00e9opolitique mondial restera le m\u00eame. &raquo;<\/p>\n<\/p>\n<p><p>On fabriquerait donc \u00e0 Moscou donc une guerre qui dure :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;objectif semble \u00eatre compl\u00e8tement diff\u00e9rent : forcer l&rsquo;Occident \u00e0 jeter autant de ressources financi\u00e8res et militaires que possible dans le brasier. Dans la partie d&rsquo;\u00e9checs, une pi\u00e8ce est sacrifi\u00e9e afin d&rsquo;attirer un adversaire dans un pi\u00e8ge dont il ne pourra plus sortir. Et si nous gardons cet objectif \u00e0 l&rsquo;esprit, il devient clair pourquoi les &Eacute;tats-Unis ont fait sauter nos gazoducs : sans eux, l&rsquo;importance des gazoducs ukrainiens augmente consid\u00e9rablement. Il s&rsquo;agit d&rsquo;une tentative d&rsquo;engager davantage les europ\u00e9ens dans le conflit. &raquo;<\/p>\n<\/p>\n<p><p>H\u00e9las cette guerre entre Eurasie et Oc\u00e9anie qui dure ind\u00e9finiment et qui nous ruine nous le peuple offre de f\u00e2cheux relents orwelliens. Car 1984 reste notre Apocalypse sinon notre livre d&rsquo;Enoch.<\/p>\n<\/p>\n<p><p>On cite le mage sur cette vraie-fausse guerre qui dure (1984, p. 290, je donne le lien en fran\u00e7ais):<\/p>\n<\/p>\n<p><p>&laquo; La guerre donc, si nous la jugeons sur le mod\u00e8le des guerres ant\u00e9rieures, est une simple imposture. Elle ressemble aux batailles entre certains ruminants dont les cornes sont plant\u00e9es \u00e0 un angle tel qu&rsquo;ils sont incapables de se blesser l&rsquo;un l&rsquo;autre. &raquo;<\/p>\n<\/p>\n<p><p>La guerre a chang\u00e9 de cible : on tue son camp, pas l&rsquo;autre. Orwell :<\/p>\n<\/p>\n<p><p>&laquo; Mais, bien qu&rsquo;irr\u00e9elle, elle n&rsquo;est pas sans signification. Elle d\u00e9vore le surplus des produits de consommation et elle aide \u00e0 pr\u00e9server l&rsquo;atmosph\u00e8re mentale sp\u00e9ciale dont a besoin une soci\u00e9t\u00e9 hi\u00e9rarchis\u00e9e. Ainsi qu&rsquo;on le verra, la guerre est une affaire purement int\u00e9rieure. Anciennement, les groupes dirigeants de tous les pays, bien qu&rsquo;il leur f&ucirc;t possible de reconna&icirc;tre leur int\u00e9r\u00eat commun et, par cons\u00e9quent, de limiter les d\u00e9g\u00e2ts de la guerre, luttaient r\u00e9ellement les uns contre les autres, et celui qui \u00e9tait victorieux pillait toujours le vaincu. De nos jours, ils ne luttent pas du tout les uns contre les autres. La guerre est engag\u00e9e par chaque groupe dirigeant contre ses propres sujets et l&rsquo;objet de la guerre n&rsquo;est pas de faire ou d&#8217;emp\u00eacher des conqu\u00eates de territoires, mais de maintenir intacte la structure de la soci\u00e9t\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est la vieille anguille De Closets qui se f\u00e9licitait du r\u00f4le retrouv\u00e9 de l&rsquo;&Eacute;tat avec la crise du Covid. Ce r\u00f4le se renforce pour Bruxelles et pour Paris avec la guerre contre la Russie qui permet d&rsquo;acc\u00e9l\u00e9rer le Reset et l&rsquo;autoritarisme euro-mondialiste. Les deux premi\u00e8res guerres mondiales ont \u00e9tabli le mondialisme, celle-ci va num\u00e9riser le troupeau et liquider la vieille race blanche et \u00e9tablir le Reset voulu par les gnostiques de Davos, lieu de la Montage magique de Thomas Mann. Relisez ce livre \u00e9tincelant et programmatique et incompris, o&ugrave; les personnages sont d\u00e9j\u00e0 des malades et moribonds entour\u00e9s de m\u00e9decins inefficaces&hellip;<\/p>\n<\/p>\n<p><p>Orwell poursuit sur ce mot incompris de guerre (devenue n\u00e9oconne) &ndash; et l\u00e0 il a vraiment de l&rsquo;avance :<\/p>\n<\/p>\n<p><p>&laquo; Le mot &laquo; guerre &raquo;, lui-m\u00eame, est devenu erron\u00e9. Il serait probablement plus exact de dire qu&rsquo;en devenant continue, la guerre a cess\u00e9 d&rsquo;exister. La pression particuli\u00e8re qu&rsquo;elle a exerc\u00e9e sur les \u00eatres humains entre l&rsquo;\u00e2ge n\u00e9olithique et le d\u00e9but du vingti\u00e8me si\u00e8cle a disparu et a \u00e9t\u00e9 remplac\u00e9e par quelque chose de tout \u00e0 fait diff\u00e9rent. L&rsquo;effet aurait \u00e9t\u00e9 exactement le m\u00eame si les trois super-&Eacute;tats, au lieu de se battre l&rsquo;un contre l&rsquo;autre, s&rsquo;entendaient pour vivre dans une paix perp\u00e9tuelle, chacun inviol\u00e9 \u00e0 l&rsquo;int\u00e9rieur de ses fronti\u00e8res. Dans ce cas, en effet, chacun serait encore un univers clos, lib\u00e9r\u00e9 \u00e0 jamais de l&rsquo;influence assoupissante du danger ext\u00e9rieur. Une paix qui serait vraiment permanente serait exactement comme une guerre permanente. Cela, bien que la majorit\u00e9 des membres du Parti ne le comprenne que dans un sens superficiel, est la signification profonde du slogan du Parti : La guerre, c&rsquo;est la Paix. &raquo;<\/p>\n<\/p>\n<p><p>Cette guerre euro-russe doit \u00eatre perp\u00e9tuelle. C&rsquo;est une guerre que nos dirigeants livrent contre nous : le football, la bi\u00e8re et le jeu contr\u00f4lent le troupeau. C&rsquo;est Orwell qui le dit aussi :<\/p>\n<\/p>\n<p><p>&laquo;&hellip;ils mouraient, pour la plupart, \u00e0 soixante ans. Le dur labeur physique, la garde du foyer et des enfants, les querelles de voisinage, les films, le football, la bi\u00e8re, et, par-dessus tout, les paris, \u00e9taient leurs seuls horizons. Il n&rsquo;\u00e9tait pas difficile de les contr\u00f4ler. Quelques agents de la Police des Pens\u00e9es \u00e9voluaient parmi eux, propageant de fausses rumeurs, rep\u00e9rant et \u00e9liminant les quelques individus qui \u00e9taient jug\u00e9s capables de devenir dangereux.&raquo;<\/p>\n<\/p>\n<p><p>&laquo; Il n&rsquo;\u00e9tait pas difficile de les contr\u00f4ler. &raquo; Il avait tout dit George Orwell&hellip;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><\/p>\n<p><strong>Source<\/strong><\/h3>\n<\/p>\n<p><p><a href=\"http:\/\/www.bouquineux.com\/index.php?telecharger=898&#038;Orwell-1984\">http:\/\/www.bouquineux.com\/index.php?telecharger=898&#038;Orwell-1984<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La logique orwellienne de leur guerre antirusse Guerre interminable ? George Orwell : &laquo; La guerre est engag\u00e9e par chaque groupe dirigeant contre ses propres sujets et l&rsquo;objet de la guerre n&rsquo;est pas de faire ou d&#8217;emp\u00eacher des conqu\u00eates de territoires, mais de maintenir intacte la structure de la soci\u00e9t\u00e9. &raquo;. Certains se demandent ce&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,13866,3283,3341,1296],"class_list":["post-81080","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-delawarde","tag-general","tag-orwell","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81080"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81080\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}