{"id":81131,"date":"2024-06-22T13:27:27","date_gmt":"2024-06-22T13:27:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/06\/22\/le-vice-fondateur-de-woke\/"},"modified":"2024-06-22T13:27:27","modified_gmt":"2024-06-22T13:27:27","slug":"le-vice-fondateur-de-woke","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/06\/22\/le-vice-fondateur-de-woke\/","title":{"rendered":"Le vice fondateur de <em>Woke<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Le vice fondateur de <em>Woke<\/em><\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Notre id\u00e9e que ce que nous avions tendance \u00e0 prendre comme un d\u00e9lire temporaire s&rsquo;av\u00e8re compl\u00e8tement <strong>fausse devant ce ph\u00e9nom\u00e8ne<\/strong> <strong>de plus en plus fortement implant\u00e9<\/strong>. &bull; Pour nous, l&rsquo;aspect informationnel et de simulacre de la guerre d&rsquo;Ukraine <strong>est typiquement <em>Woke<\/em><\/strong>, et c&rsquo;est principalement <strong>sur ce terrain que se poursuivra l&rsquo;affrontement avec la Russie et ses alli\u00e9s<\/strong>. &bull; Ici, un texte nous invite \u00e0 explorer les racines m\u00e9taphysiques du <em>Woke <\/em>qui font fondamentalement partie de la cr\u00e9ation de la modernit\u00e9 nihiliste jusqu&rsquo;\u00e0 en \u00eatre les g\u00e9niteurs.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Il est vrai que nous mettons un deuxi\u00e8me texte important sur le mouvement <em>Woke <\/em>(wokisme ou wokenisme, c&rsquo;est selon), sans raison, ext\u00e9rieure n\u00e9cessaire (\u00e9v\u00e9nement, prise de position). Il s&rsquo;agit du signe de l&rsquo;importance de ce mouvement, une importance r\u00e9volutionnaire et civilisationnelle (ou anti-civilisationnelle) qui n&rsquo;a plus besoin de causes ext\u00e9rieures pour se signaler.<\/p>\n<\/p>\n<p><p>De m\u00eame, notre appr\u00e9ciation est que le <em>Woke <\/em>a domin\u00e9 indirectement le sens de la guerre en Ukraine en introduisant l&rsquo;interpr\u00e9tation d&rsquo;une guerre culturelle dont <em>Woke <\/em>est \u00e0 la fois un composant essentiel et le v\u00e9ritable \u00e9tendard. Cela doit aussi nous faire comprendre que  les v\u00e9ritables anti<em>Woke <\/em>sont \u00e0 l&rsquo;Est, ce qui posera bien des soucis et des interrogations angoiss\u00e9es \u00e0 ceux qui, en Occident, du c\u00f4t\u00e9 des conservateurs et des traditionnalistes, ont \u00e9pous\u00e9 avec enthousiasme la cause antirusse.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Note de PhG-Bis<\/em><\/strong><em> : &laquo; Chez nous, excusez-nous de parler \u00e0 notre avantage, ce n&rsquo;est pas vraiment nouveau. Rappelez-vous le <a href=\"https:\/\/www.dedefensa.org\/article\/lukraine-aux-couleurs-du-wokenisme\">6 avril 2021<\/a> un texte intitul\u00e9 \u00ab\u00a0L&rsquo;Ukraine aux couleurs du wokenisme\u00a0\u00bb, et pardonnez-moi pour cette citation un peu longuette :<\/em><\/p>\n<\/p>\n<p><p>&laquo; <em>\u00ab\u00a0Je comprends mal, pour mon compte, pourquoi et comment l&rsquo;on ne fait pas le lien entre cette soudaine r\u00e9surgence du sentiment de guerre (et non la r\u00e9surgence des neocons ou des warmongers qui n&rsquo;ont jamais cess\u00e9 d&rsquo;exister), qui s&rsquo;exerce contre la Russie, mais \u00e9galement contre la Chine, contre l&rsquo;Iran, contre la Syrie, etc., &ndash; et la d\u00e9mence qui s&rsquo;exprime dans le mouvement du <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-le-wokenisme-seul-ii\">wokenisme<\/a>. La folie n&rsquo;est pas une pand\u00e9mie qui se limite \u00e0 telle ou telle cat\u00e9gorie, c&rsquo;est au contraire la pand\u00e9mie la plus universelle qui soit lorsqu&rsquo;elle se d\u00e9clare dans un milieu, dans un segment de pens\u00e9e, dans un courant id\u00e9ologique, dans un sentiment collectif d'\u00a0\u00bbexceptionnalit\u00e9\u00a0\u00bb comme celui qui continue \u00e0 entretenir, \u00e0 bercer, et m\u00eame \u00e0 renforcer l&rsquo;addiction de Washington D.C. dans son simulacre<\/em>.<\/p>\n<\/p>\n<p><p>&laquo;<em> \u00ab\u00a0Oui, j&rsquo;ai du mal \u00e0 comprendre pourquoi l&rsquo;on ne fait pas le lien entre cette soudaine renaissance d&rsquo;un d\u00e9sir de guerre dans le champ clos, pourri et corrompu, et <a href=\"https:\/\/www.dedefensa.org\/article\/lalerte-ukrainienne-et-lami-joe\">si familier<\/a> au nouveau pr\u00e9sident, de l&rsquo;Ukraine, et la dynamique du wokenisme qui bouleverse absolument les fondements sociaux, soci\u00e9taux, psychologiques. Pour moi, l&rsquo;un ne va pas sans l&rsquo;autre, et aucun ne demande d&rsquo;explication \u00ab\u00a0rationnelle\u00a0\u00bb, ou m\u00eame \u00ab\u00a0id\u00e9ologique\u00a0\u00bb, ou ethnique et religieuse, etc. ; au contraire, cette sorte d&rsquo;explication diminue l&rsquo;id\u00e9e m\u00eame de la d\u00e9mence et nous fait rater la v\u00e9ritable ampleur et la signification de la situation ; bref, elle nous fait rater la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>. <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il faut donc s&rsquo;attendre \u00e0 des effets parall\u00e8les ou communs aussi bien dans la posture antirusse que pour les mouvements <em>Woke <\/em>lorsque la tournure de la guerre en Ukraine, comme on la voit \u00e9voluer, deviendra de plus en plus critique pour l&rsquo;Ukraine. C&rsquo;est effectivement \u00e0 ce moment que les conservateurs-tradi ayant choisi le camp ukrainien (comme c&rsquo;est surtout le cas en France) feront face \u00e0 des n\u00e9cessit\u00e9s de r\u00e9visions d\u00e9chirantes.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Le <em>Woke<\/em>, facteur de l&rsquo;histoire de l&rsquo;esprit<\/strong><\/h3>\n<\/p>\n<p><p>Le texte que nous vous proposons ci-dessous s&rsquo;attache notamment \u00e0 placer le mouvement <em>Woke <\/em>dans le cours de l&rsquo;histoire des id\u00e9es et des civilisations. Il le d\u00e9finit selon les normes philosophiques g\u00e9n\u00e9rales et, &ndash; notamment et particuli\u00e8rement, &ndash; selon les normes de l&rsquo;esth\u00e9tique en montrant combien le mouvement <em>Woke <\/em>favorise la laideur en toutes choses et dans tous les arts, &ndash; certes, aux d\u00e9pens de la beaut\u00e9, mais par la force des choses, comme \u00ab\u00a0sans le vouloir\u00a0\u00bb, parce que le <em>Woke <\/em>semble en fait n&rsquo;avoir aucune consid\u00e9ration pour la beaut\u00e9  jusqu&rsquo;\u00e0 ignorer son existence.<\/p>\n<\/p>\n<p><p> C&rsquo;est une id\u00e9e qui nous int\u00e9resse depuis longtemps que cette \u00e9volution invasive et irr\u00e9sistible de la laideur comme <a href=\"https:\/\/www.dedefensa.org\/article\/la-subversion-de-la-laideur\">instrument de subversion<\/a> caract\u00e9risant la modernit\u00e9, notamment par le biais de la d<a href=\"https:\/\/www.dedefensa.org\/article\/deconstructuration-du-deconstructeur\">\u00e9constructuration,<\/a> et qui finalement pr\u00e9c\u00e9da largement le mouvement <em>Woke<\/em>. De ce point de vue, <em>Woke<\/em> est un d\u00e9veloppement maximal dans ce sens qui nous conduisit \u00e0 le consid\u00e9rer comme une pathologie de la psychologie, \u00e0 l&rsquo;image de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, dont il est un reflet dans d&rsquo;autres domaines que ceux de la violence guerri\u00e8re de toutes les sortes. Tout cela correspond bien au jugement g\u00e9n\u00e9ral que l&rsquo;on peut porter sur la modernit\u00e9 lorsqu&rsquo;on est capable d&rsquo;en mesurer les effets.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong><em>Woke <\/em>int\u00e9gr\u00e9 jusqu&rsquo;\u00e0 l&rsquo;explosion<\/strong><\/h3>\n<\/p>\n<p><p>Comme nous l&rsquo;avons vu, l&rsquo;abondance des analyses du mouvement <em>Woke<\/em> montre la puissance de sa pr\u00e9sence, voire de son int\u00e9gration. Il est vrai que ce mouvement b\u00e9n\u00e9ficie du m\u00eame simulacre que celui dont a b\u00e9n\u00e9fici\u00e9 la guerre en Ukraine, ce qui autorise tous les exc\u00e8s de la folie sans qu&rsquo;il soit autoris\u00e9 par les polices des pens\u00e9es de les d\u00e9signer comme tels. Mais nous croyons, comme dans le cas ukrainien, que c&rsquo;est l&rsquo;exc\u00e8s lui-m\u00eame qui va porter \u00e0 ce mouvement les coups les plus fatals.<\/p>\n<\/p>\n<p><p>Il ne faut bien entendu pas compter sur les institutions dites-d\u00e9mocratiques, toutes parties prenantes, ni sur les restes agonisants du christianisme pour la moindre d\u00e9fense, d&rsquo;autant que le christianisme notamment porte une tr\u00e8s lourde responsabilit\u00e9 dans le d\u00e9veloppement de tels mouvements depuis <a href=\"https:\/\/www.dedefensa.org\/article\/la-grace-iii-renaissance-modernite\">la Renaissance<\/a>. (Il nous semble plus logique de mettre en cause le christianisme dans certaines de ses origines, plut\u00f4t que Nietzsche, adepte d&rsquo;un haut esprit aristocratique et adversaire r\u00e9solu de l&rsquo;\u00e9galit\u00e9 tant ch\u00e9ri par <em>Woke<\/em>, &ndash; comme le fait l&rsquo;auteur.)<\/p>\n<\/p>\n<p><p>D&rsquo;une certaine fa\u00e7on, si la guerre en Ukraine \u00e9volue comme elle le fait, soit une victoire russe, soit une d\u00e9composition des am\u00e9ricanistes-occidentalistes devant l&rsquo;absence de victoire ukrainienne, le cas du <em>Woke<\/em> reviendra au premier plan jusqu&rsquo;\u00e0 susciter lui aussi des \u00e9pisodes agressifs. Les Russes et tous les pays du \u00ab\u00a0Sud global\u00a0\u00bb qui s&rsquo;opposent \u00e0 lui, finiront par en faire un argument d&rsquo;affrontement de premi\u00e8re importance. Notre civilisation poursuivra donc avec z\u00e8le son processus d&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>(Le <a href=\"https:\/\/www.arktosjournal.com\/p\/the-terror-of-woke\">texte original<\/a> est de Sietze Bosman, publi\u00e9 dans sa version fran\u00e7aise par &lsquo;<em>euro-synergie.hautfort.com<\/em>&lsquo;.)<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p><em>_________________________<\/em><\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>La terreur <em>Woke<\/em><\/strong><\/h2>\n<\/p>\n<p><p>Sietze Bosman affirme que les normes traditionnelles de l&rsquo;Europe sont attaqu\u00e9es sans rel\u00e2che par le mouvement Woke, et appelle passionn\u00e9ment l&rsquo;Europe \u00e0 se lever et \u00e0 r\u00e9sister farouchement pour d\u00e9fendre ses valeurs fondamentales.<\/p>\n<\/p>\n<p><p>Dans la gu\u00e9rilla id\u00e9ologique en cours, les normes traditionnelles sont encore et toujours victimes de la soif nihiliste et sanguinaire de l&rsquo;id\u00e9ologie Woke. Les normes, dit le mantra, sont oppressives. &quot;Les normes ne sont pas atteignables pour beaucoup de gens&quot;, scande la tribu Woke dans une parfaite harmonie gr\u00e9gorienne, et c&rsquo;est pourquoi les normes doivent \u00eatre ajust\u00e9es \u00e0 la baisse ou carr\u00e9ment abolies. Les normes sont exclusives et contredisent la religion d&rsquo;une minorit\u00e9 bruyante, convaincue d&rsquo;\u00eatre la seule \u00e0 poss\u00e9der un sens moral pur et puissant &#8211; une morale qui d\u00e9ifie l&rsquo;individu, aussi grotesque qu&rsquo;il\/elle\/iel\/iels\/ielles\/wolfkin puisse \u00eatre dans l&rsquo;expression de son individualit\u00e9.<\/p>\n<\/p>\n<p><p>Des penseurs naturalistes et romantiques tels que Jean-Jacques Rousseau partent du principe que l&rsquo;homme est intrins\u00e8quement bon et que les institutions de la soci\u00e9t\u00e9 occidentale moderne ne peuvent que le corrompre. Les \u00e9glises, les \u00e9coles et m\u00eame la structure familiale traditionnelle sont des institutions qui ne peuvent qu&rsquo;\u00e9loigner les gens de leur nature naturellement bonne, selon Rousseau. Ainsi, toutes les normes issues des institutions occidentales traditionnelles sont par d\u00e9finition r\u00e9pressives et \u00e9loignent l&rsquo;homme de sa bont\u00e9 naturelle.<\/p>\n<\/p>\n<p><p>Des penseurs comme Foucault et Derrida, penseurs d\u00e9constructionnistes postmodernes, ont \u00e9galement eu une forte influence sur la substance de l&rsquo;id\u00e9ologie Woke. Avec eux, nous trouvons l&rsquo;origine des id\u00e9es sur l&rsquo;absence de v\u00e9ritable v\u00e9rit\u00e9 objective et sur le fait que les institutions d\u00e9crites par des penseurs comme Rousseau ne sont que des constructions sociales. Plus rien n&rsquo;a de sens profond et m\u00eame la morale qui ne concerne que l&rsquo;individu dispara&icirc;t dans la poubelle id\u00e9ologique Woke.<\/p>\n<\/p>\n<p><p>La pens\u00e9e postmoderniste affirme que la r\u00e9alit\u00e9 peut \u00eatre interpr\u00e9t\u00e9e d&rsquo;un nombre infini de fa\u00e7ons. C&rsquo;est vrai, mais cela ne tient pas compte du fait que nous vivons dans une r\u00e9alit\u00e9 partag\u00e9e dans laquelle les lois de la nature s&rsquo;appliquent \u00e0 tous et qu&rsquo;une v\u00e9rit\u00e9 objective \u00e9merge de ces lois. La mani\u00e8re dont chacun interpr\u00e8te cette r\u00e9alit\u00e9 objective fa\u00e7onn\u00e9e par les lois est certes sujette \u00e0 de grandes diff\u00e9rences, mais la r\u00e9alit\u00e9 objective traverse n\u00e9anmoins les diff\u00e9rentes interpr\u00e9tations individuelles de la r\u00e9alit\u00e9 comme un fil conducteur contraignant.<\/p>\n<\/p>\n<p><p>Les normes sont, selon l&rsquo;id\u00e9ologie Woke, des constructions parce que chacun a une interpr\u00e9tation diff\u00e9rente de la r\u00e9alit\u00e9. Les normes sont donc impos\u00e9es \u00e0 un individu d\u00e9j\u00e0 bon par nature. Ce qui est un homme pour l&rsquo;un est une femme pour l&rsquo;autre. Ce qui est une vertu pour moi est un p\u00e9ch\u00e9 pour d&rsquo;autres. M\u00eame les r\u00e9alit\u00e9s biologiques telles que la dichotomie des sexes sont rejet\u00e9es en tant qu&rsquo;oppression &quot;blanche, masculine et cisgenre&quot;. En fait, le langage lui-m\u00eame est consid\u00e9r\u00e9 comme une norme oppressive qui doit \u00eatre transcend\u00e9e et surmont\u00e9e, ou d\u00e9truite. Ainsi, le moyen m\u00eame par lequel chacun peut s&rsquo;exprimer sera tellement d\u00e9figur\u00e9 qu&rsquo;il ne pourra plus servir de moyen de communication, ce qui nous ram\u00e8nera \u00e0 l&rsquo;\u00e2ge de pierre.<\/p>\n<\/p>\n<p><p>Tout ce qui fait de la soci\u00e9t\u00e9 occidentale la plus prosp\u00e8re de l&rsquo;histoire connue repose sur des sables mouvants. La tradition, le lien avec la terre natale, la fiert\u00e9 nationale et le fait de laisser quelque chose derri\u00e8re soi pour la post\u00e9rit\u00e9 sont autant d&rsquo;id\u00e9es r\u00e9pr\u00e9hensibles qui ne sont que des fant\u00f4mes id\u00e9ologiques de la pens\u00e9e occidentale chr\u00e9tienne, laquelle est toxique, selon le &quot;pens\u00e9e&quot; Woke. En particulier, le fondement chr\u00e9tien des soci\u00e9t\u00e9s occidentales est consid\u00e9r\u00e9 comme un mal absolu. Tout ce qui d\u00e9coule de la doctrine chr\u00e9tienne est digne d&rsquo;\u00eatre arros\u00e9 d&rsquo;excr\u00e9ments verbaux et de vitriol violent.<\/p>\n<\/p>\n<p><p>Dieu en tant qu&rsquo;\u00eatre transcendant, ou l&rsquo;id\u00e9e m\u00eame de Dieu, est l&rsquo;ennemi absolu de l&rsquo;id\u00e9ologie woke. Dieu est la norme ultime, le standard ultime. Dieu a cr\u00e9\u00e9 Adam et Eve \u00e0 partir de sa c\u00f4te &#8211; l&rsquo;homme et la femme, une division objective des sexes. En tant qu&rsquo;id\u00e9ologie, Woke a d\u00e9clar\u00e9 la guerre \u00e0 toutes les normes, et le cr\u00e9ateur des normes doit donc \u00eatre d\u00e9truit. Lorsque l&rsquo;on tue l&rsquo;id\u00e9e de Dieu, l&rsquo;homme doit devenir comme Dieu et \u00e9tablir ses propres normes, selon Nietzsche. L&rsquo;\u00e9thique devient alors une approche purement personnelle du bien et du mal. La morale, de facto, cesse d&rsquo;exister parce qu&rsquo;elle n&rsquo;appara&icirc;t que dans le contexte des groupes sociaux.<\/p>\n<\/p>\n<p><p>L&rsquo;id\u00e9e que tout doit \u00eatre fluide et cat\u00e9goris\u00e9 uniquement sur la base d&rsquo;un sentiment que l&rsquo;on \u00e9prouve fait que l&rsquo;on \u00e9change le beau contre le laid, que l&rsquo;on qualifie les faits de d\u00e9testables, que l&rsquo;on veut appauvrir le langage et l&rsquo;utiliser comme un instrument militant d&rsquo;encadrement. Le r\u00e9sultat de cette fluidit\u00e9, ce sont des magasins avec des mannequins ob\u00e8ses dans les vitrines, des publicit\u00e9s Calvin Klein avec des femmes rong\u00e9es par la cellulite et des hommes grassouillets v\u00eatus de soutiens-gorge de sport, des promotions de bi\u00e8res transgenres et beaucoup de cheveux color\u00e9s au n\u00e9on. De nombreux adeptes du wokisme semblent faire un effort conscient pour se rendre aussi laids que possible. Tels des adolescents r\u00e9calcitrants qui se rebellent contre leurs parents, ils se d\u00e9tournent de tout id\u00e9al de beaut\u00e9. Apr\u00e8s tout, une norme n&rsquo;est qu&rsquo;une question de perception, pas d&rsquo;aspiration &#8211; ainsi chantent les hordes woke.<\/p>\n<\/p>\n<p><p>De nombreux Europ\u00e9ens ont le sentiment inn\u00e9 que nous ne devrions pas accepter les absurdit\u00e9s woke &#8211; qu&rsquo;il est, en quelque sorte, anti-europen d&rsquo;aller dans le sens du wokisme.<\/p>\n<\/p>\n<p><p>Woke semble \u00eatre un ph\u00e9nom\u00e8ne relativement nouveau, mais le d\u00e9clin des id\u00e9aux est perceptible et visible depuis longtemps. L&rsquo;architecture occidentale moderne est un exemple clair de ce d\u00e9clin des id\u00e9aux.<\/p>\n<\/p>\n<p><p>L&rsquo;architecture traditionnelle, avec son sens sublime des proportions et sa capacit\u00e9 \u00e0 impressionner le spectateur, a \u00e9t\u00e9 remplac\u00e9e par des constructions d&rsquo;acier et de verre froides et sans \u00e2me, qui n&rsquo;impressionnent ni n&rsquo;inspirent. Les villes occidentales modernes sont devenues des lieux st\u00e9riles, o&ugrave; l&rsquo;architecture moderne est soigneusement incis\u00e9e dans et parmi les perles classiques sporadiques qui existent encore. Lorsque Notre Dame a perdu son toit \u00e0 la suite d&rsquo;un incendie, un concours d&rsquo;architectes a \u00e9t\u00e9 organis\u00e9 pour trouver une solution de remplacement. Parmi les id\u00e9es soumises figurait une v\u00e9ritable piscine au sommet de l&rsquo;\u00e9glise, je ne vous le fais pas dire (photo, ci-dessous). Le fait qu&rsquo;un lieu d&rsquo;une telle importance historique et culturelle puisse \u00eatre viol\u00e9 par des architectes modernes, f\u00e9tichistes et laids, est clairement r\u00e9v\u00e9lateur de la folie moderne.<\/p>\n<\/p>\n<p><p>Un autre bon exemple est le Forum de Groningue, aux Pays-Bas (photo, ci-dessus). Le visage du magnifique centre historique de la ville a \u00e9t\u00e9 d\u00e9figur\u00e9 au point d&rsquo;\u00eatre m\u00e9connaissable par un b\u00e2timent qui se caract\u00e9rise par une laideur qui ne peut \u00eatre exprim\u00e9e par des mots. C&rsquo;est un exploit en soi que de concevoir un b\u00e2timent avec autant d&rsquo;angles qui ne peuvent \u00eatre appr\u00e9ci\u00e9s pour quoi que ce soit qui ressemble de pr\u00e8s ou de loin \u00e0 de la beaut\u00e9, quel que soit l&rsquo;angle.<\/p>\n<\/p>\n<p><p>La beaut\u00e9 en tant qu&rsquo;id\u00e9al semble avoir \u00e9t\u00e9 express\u00e9ment d\u00e9sign\u00e9e comme un \u00e9l\u00e9ment \u00e0 exclure de la mission de l&rsquo;architecte. Le b\u00e2timent a \u00e9t\u00e9 d\u00e9pouill\u00e9 de tout ce qui peut plaire \u00e0 l&rsquo;&oelig;il, et ses fa\u00e7ades nues et lisses ne peuvent que le tourmenter par leur \u00e9chec architectural flagrant.<\/p>\n<\/p>\n<p><p>L&rsquo;art moderne est aussi depuis longtemps le th\u00e9\u00e2tre du d\u00e9clin des id\u00e9aux. L&rsquo;art n&rsquo;est aussi que ce que le spectateur en fait, dit-on. L&rsquo;art ne s&rsquo;interpr\u00e8te donc qu&rsquo;\u00e0 travers une histoire. C&rsquo;est ainsi que nous avons aujourd&rsquo;hui des mus\u00e9es qui exposent des tampons usag\u00e9s et des nouilles peintes en or en tant qu&rsquo;&oelig;uvres d&rsquo;art.<\/p>\n<\/p>\n<p><p>L&rsquo;artiste vous expliquera l&rsquo;art avec une histoire creuse sur &quot;la recherche nerveuse des limites&quot;, &quot;la rupture des tabous&quot;, ou &quot;Il repr\u00e9sente une concentration herm\u00e9neutique sur l&rsquo;interpr\u00e9tation psychosociale de l&rsquo;entrelacement de la souffrance subconsciente et de la glorification de l&rsquo;\u00e9ph\u00e9m\u00e8re, combin\u00e9e \u00e0 un reflet plastique-graphique du paradigme du pouvoir cisgenre&quot;. En d&rsquo;autres termes, l&rsquo;art ne peut \u00eatre expliqu\u00e9 que par une salade de mots relativiste &#8211; zum kotzen.<\/p>\n<\/p>\n<p><p>La croisade d\u00e9vorante vers l&rsquo;\u00e9galitarisme absolu a pour cons\u00e9quence directe que, pour n&rsquo;exclure personne, toutes les normes doivent \u00eatre ajust\u00e9es au plus petit d\u00e9nominateur commun, voire compl\u00e8tement d\u00e9truites. Il ne peut y avoir de norme de beaut\u00e9 physique, car une personne ayant une composition g\u00e9n\u00e9tique malheureuse et les attributs physiques r\u00e9pulsifs qui en d\u00e9coulent se sentira exclue \u00e0 cause de cela. Les examens d&rsquo;entr\u00e9e \u00e0 l&rsquo;\u00e9cole sont assouplis pour permettre une plus grande diversit\u00e9 dans les \u00e9coles, et les entreprises recrutent en fonction des caract\u00e9ristiques de la diversit\u00e9 et non d&rsquo;une norme d&rsquo;aptitude. La recherche aveugle de toujours plus d&rsquo;inclusivit\u00e9 est le moteur du wokisme. Le wokisme est pr\u00eat \u00e0 sacrifier tout ce qu&rsquo;il consid\u00e8re comme r\u00e9pressif, m\u00eame si cela signifie d\u00e9truire l&rsquo;\u00e9conomie et, par cons\u00e9quent, sa propre capacit\u00e9 \u00e0 prosp\u00e9rer.<\/p>\n<\/p>\n<p><p>Le wokisme n&rsquo;est pas une tendance, c&rsquo;est l&rsquo;aboutissement d&rsquo;une intrusion ignoble d&rsquo;un poison id\u00e9ologique mondialiste dont le but n&rsquo;est rien d&rsquo;autre que de vaincre l&rsquo;Occident id\u00e9ologiquement puisqu&rsquo;il est tr\u00e8s difficile de le faire militairement. Et parce que nous avons r\u00e9solument ferm\u00e9 la porte au christianisme, l&rsquo;Occident ne peut opposer aucune r\u00e9sistance. Nous n&rsquo;avons pas remplac\u00e9 Dieu par quelque chose qui offre suffisamment de substance pour unir les peuples d&rsquo;Europe.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9cho du marteau qui a forg\u00e9 la culture europ\u00e9enne sur l&rsquo;enclume de l&rsquo;histoire r\u00e9sonne encore dans le c&oelig;ur des Europ\u00e9ens. De nombreux Europ\u00e9ens ont le sentiment inn\u00e9 que nous ne devrions pas accepter les absurdit\u00e9s du wokisme &#8211; qu&rsquo;il est, d&rsquo;une certaine mani\u00e8re, anti-europ\u00e9en de suivre la mode woke. Mais c&rsquo;est la tactique de la honte, si astucieusement d\u00e9ploy\u00e9e par le wokisme, qui maintient les gens dans le silence. De peur d&rsquo;\u00eatre stigmatis\u00e9s et \u00e9tiquet\u00e9s, les gens se taisent, sans se rendre compte que l&rsquo;utilisation comp\u00e9tente de cette m\u00eame langue a constitu\u00e9 le fondement de la culture europ\u00e9enne. La libert\u00e9 d&rsquo;expression est l&rsquo;\u00e9pine dorsale de la culture europ\u00e9enne et doit \u00eatre d\u00e9fendue. Heureusement, en raison de l&rsquo;utilisation abondante de termes p\u00e9joratifs et de l&rsquo;application gauchiste des \u00e9tiquettes, celles-ci semblent perdre de leur force. Le fait d&rsquo;\u00eatre trait\u00e9 de nazi n&rsquo;est pas tr\u00e8s grave si de nombreuses personnes sont appel\u00e9es ainsi. Cela offre une perspective.<\/p>\n<\/p>\n<p><p>L&rsquo;heure est venue de ne plus se pr\u00e9occuper de l&rsquo;\u00e9tiquetage et de la stigmatisation. Il est temps d&rsquo;assumer notre devoir naturel de d\u00e9fendre notre peuple, de revendiquer notre avenir et d&rsquo;expulser l&rsquo;ennemi de nos vies et de nos territoires. Une grande opportunit\u00e9 s&rsquo;offre aux peuples d&rsquo;Europe qui voient le projet mondialiste se d\u00e9ployer sous leurs yeux. Le terrain est pr\u00eat \u00e0 \u00eatre labour\u00e9 et ensemenc\u00e9 avec les id\u00e9es du traditionalisme, d&rsquo;un retour aux normes et aux r\u00e8gles qui garantissent la sortie de notre peuple du d\u00e9sert id\u00e9ologique qu&rsquo;est devenu notre continent.<\/p>\n<\/p>\n<p><p>Debout, l&rsquo;Europe ! L\u00e8ve-toi ! D\u00e9barrassez-vous de vos cha&icirc;nes et arrachez votre museli\u00e8re. Parlez avec feu et vertu, et ne laissez jamais l&rsquo;esprit europ\u00e9en qui est en vous \u00eatre diminu\u00e9 par des forces spirituelles inf\u00e9rieures. Respirez profond\u00e9ment l&rsquo;air europ\u00e9en impr\u00e9gn\u00e9 de l&rsquo;esprit glorieux de nos nobles et intr\u00e9pides anc\u00eatres. Ouvrez votre esprit \u00e0 l&rsquo;h\u00e9ritage inestimable que nous avons re\u00e7u et laissez vos c&oelig;urs se gonfler de l&rsquo;amour de nos id\u00e9aux. Laissez les forces de mar\u00e9e de l&rsquo;histoire, du sang et de l&rsquo;honneur d\u00e9ferler dans votre corps jusqu&rsquo;\u00e0 ce que tout ce que vous puissiez sortir de votre bouche dans une d\u00e9votion extatique soit : Europe ! L&rsquo;Europe ! Debout, l&rsquo;Europe !<\/p>\n<\/p>\n<p><h4>Sietze Bosman<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vice fondateur de Woke &bull; Notre id\u00e9e que ce que nous avions tendance \u00e0 prendre comme un d\u00e9lire temporaire s&rsquo;av\u00e8re compl\u00e8tement fausse devant ce ph\u00e9nom\u00e8ne de plus en plus fortement implant\u00e9. &bull; Pour nous, l&rsquo;aspect informationnel et de simulacre de la guerre d&rsquo;Ukraine est typiquement Woke, et c&rsquo;est principalement sur ce terrain que se&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[13939,4020,2655,4280,13938,1296,13670],"class_list":["post-81131","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-bosman","tag-folie","tag-modernite","tag-pathologie","tag-sietze","tag-ukraine","tag-ukrisis"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81131"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81131\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}