{"id":81152,"date":"2024-07-07T14:42:47","date_gmt":"2024-07-07T14:42:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/07\/07\/ue-kiev-la-fete-aux-vermines\/"},"modified":"2024-07-07T14:42:47","modified_gmt":"2024-07-07T14:42:47","slug":"ue-kiev-la-fete-aux-vermines","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/07\/07\/ue-kiev-la-fete-aux-vermines\/","title":{"rendered":"UE-Kiev, la f\u00eate aux vermines"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>UE-Kiev, la f\u00eate aux vermines<\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Un rapide coup d&rsquo;&oelig;il, mais tout de m\u00eame fort bien d\u00e9taill\u00e9, sur les circuits de circulation, notamment autour de l&rsquo;Ukraine, dans les couloirs de l&rsquo;UE. &bull; Une bonne mise en bouche de l&rsquo;effondrement, avec Rachel Marsden.<\/p>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>L&rsquo;UE s&rsquo;est d\u00e9finitivement install\u00e9e comme une sorte de monstre \u00e9norme cr\u00e9\u00e9 par le docteur Frank-Einstein, et qui rec\u00e8le toutes les productions de la globalisation et de la d\u00e9constructuration. Nous craignons grandement que cette visibilit\u00e9 et l&rsquo;inconscience arrogante des \u00e9litesZombie qui peuplent ses labyrinthes obscurcissent de plus en plus la perception minimale d&rsquo;une r\u00e9alit\u00e9 qui souffre de moins en moins de devoir supporter son infamie. La fa\u00e7on dont ils ont \u00e9t\u00e9 incapables de pr\u00e9voir le coup de Orban pour d\u00e9buter sa pr\u00e9sidence (escapade Kiev-Moscou) n&rsquo;est pas bon signe dans le genre \u00ab\u00a0ils ne voient rien venir\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>On conna&icirc;t Rachel Marsden, on l&rsquo;a d\u00e9j\u00e0 lue \u00e0 diverses reprises. Cette fois, elle a pris sa plume pour d\u00e9crire plusieurs aspects des monstrueux gaspillages, avec leur part substantielle de corruption, En t\u00eate, bien entendu, l&rsquo;Ukraine et la f\u00eate aux achats d&rsquo;armement.<\/p>\n<\/p>\n<p><p>Lisez le texte dans le d\u00e9tail et vous voyez confirm\u00e9s les arcanes d&rsquo;une crise \u00e9norme, ce que nous nommons bien entendu la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> qui pourrait bien, qui devrait certainement emporter (dans l&rsquo;ordre ? C&rsquo;est selon) l&rsquo;UE, l&rsquo;OTAN, les USA, la civilisation am\u00e9ricaniste-occidentaliste.<\/p>\n<\/p>\n<p><p>Sur RT-Fran\u00e7ais, le <a href=\"https:\/\/francais.rt.com\/opinions\/112146-pourquoi-electeurs-europeens-se-cabrent\">7 juillet 2024<\/a>.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Les racines de la r\u00e9bellion<\/strong><\/h2>\n<\/p>\n<p><p>Une vague anti-establishment lors des \u00e9lections europ\u00e9ennes a incit\u00e9 le pr\u00e9sident fran\u00e7ais Emmanuel Macron \u00e0 appeler \u00e0 des \u00e9lections nationales quitte ou double, dont le premier tour, \u00e0 lui seul, a vu l&rsquo;establishment du pays, synonyme de &laquo;r\u00e9volution&raquo;, jet\u00e9 dans le bac \u00e0 compost historique tel une entrec\u00f4te p\u00e9rim\u00e9e.<\/p>\n<\/p>\n<p><p>Les temps sont durs au sein de l&rsquo;UE pour ceux qui sont connus, par exemple, comme la &laquo;reine Ursula&raquo;, ou encore sa garde pr\u00e9torienne : le bataillon des gratte-papiers aveugl\u00e9ment soumis, fragile comme du verre, de la bureaucratie europ\u00e9enne.<\/p>\n<\/p>\n<p><p>M\u00eame le chancelier allemand Olaf Scholz a admis dans une r\u00e9cente interview que les r\u00e9sultats des derni\u00e8res \u00e9lections europ\u00e9ennes refl\u00e9taient le d\u00e9saccord des citoyens avec les sanctions antirusses et le soutien \u00e0 l&rsquo;Ukraine. Il devient donc flagrant que l&rsquo;UE a tout un programme \u00e0 faire passer avant qu&rsquo;il ne devienne trop \u00e9vident qu&rsquo;elle se fiche compl\u00e8tement de la d\u00e9mocratie si celle-ci ne s&rsquo;aligne pas sur ses int\u00e9r\u00eats. Et le temps presse. Ainsi l&rsquo;UE, ou la &laquo;voiture clown&raquo;, a mis le pied au plancher fon\u00e7ant \u00e0 toute vitesse sur l&rsquo;autoroute de l&rsquo;\u00e2nerie.<\/p>\n<\/p>\n<p><p>En t\u00eate de leur agenda figure le transfert massif de l&rsquo;argent des contribuables vers les coffres d&rsquo;int\u00e9r\u00eats particuliers, tant que le pr\u00e9sident ukrainien Volodymyr Zelenski peut passer pour le bonimenteur de la cause. <\/p>\n<\/p>\n<p><p>L&rsquo;un de ces grands int\u00e9r\u00eats particuliers est le complexe militaro-industriel de l&rsquo;Occident. La &laquo;Team Bruxelles&raquo; a annonc\u00e9 un transfert de 1,4 milliards suppl\u00e9mentaires de sa &laquo;Facilit\u00e9 pour la paix en Ukraine&raquo; vers la production d&rsquo;armes. En effet, rien ne dit mieux &laquo;paix&raquo; que la fabrication d&rsquo;armes pour une guerre. S&rsquo;ils l&rsquo;avaient appel\u00e9 &laquo;Facilit\u00e9 pour la guerre en Ukraine&raquo;, les \u00e9lecteurs qui ne sont pas encore \u00e9veill\u00e9s pourraient peut-\u00eatre y voir plus clair. Et l&rsquo;UE a d\u00e9j\u00e0 plus qu&rsquo;assez d&rsquo;\u00e9lecteurs conscients, qui lui reprochent ses escroqueries comme, par exemple, l&rsquo;id\u00e9e de remplacer l&rsquo;argent de la &laquo;Facilit\u00e9 pour la paix&raquo;, qu&rsquo;elle largue elle-m\u00eame pour produire davantage d&rsquo;armes occidentales que la Russie d\u00e9truira en Ukraine, en volant simplement les int\u00e9r\u00eats des 260 milliards de dollars d&rsquo;actifs russes gel\u00e9s en Occident.<\/p>\n<\/p>\n<p><p>M\u00eame la pr\u00e9sidente de la Banque centrale europ\u00e9enne Christine Lagarde a d\u00e9clar\u00e9 que cette initiative &laquo;de g\u00e9nie&raquo; de faire payer la Russie pour les deux c\u00f4t\u00e9s du conflit ukrainien \u00e9tait juridiquement douteuse et cr\u00e9ait un mauvais pr\u00e9c\u00e9dent pour ceux qui voudraient encore consid\u00e9rer l&rsquo;UE comme un endroit digne de confiance pour faire des affaires. Mais elle a manifestement manqu\u00e9 le m\u00e9mo dans lequel Bruxelles et Washington dictaient que l&rsquo;ordre international \u00e9tait ce qu&rsquo;ils d\u00e9cidaient, \u00e0 n&rsquo;importe quel moment.<\/p>\n<\/p>\n<p><p>La Hongrie s&rsquo;est oppos\u00e9e au blanchiment de l&rsquo;argent des contribuables en profits de guerre. La raison reste-t-elle un grand myst\u00e8re ? Ce n&rsquo;est pas comme si un missile de fabrication am\u00e9ricaine avait r\u00e9cemment tu\u00e9 et bless\u00e9 un bon nombre de civils sur une plage en Crim\u00e9e, ou que certains dirigeants europ\u00e9ens, tels que Macron, faisaient imprudemment d\u00e9g\u00e9n\u00e9rer le conflit en une \u00e9ventuelle Troisi\u00e8me guerre mondiale en se vantant d&rsquo;envoyer des troupes en Ukraine. Alors, il n&rsquo;est pas surprenant que le Premier ministre hongrois Viktor Orban voulait mettre son veto \u00e0 toute nouvelle initiative.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Vite, allouer des fonds aux achats d&rsquo;armes<\/strong><\/h3>\n<\/p>\n<p><p> Par chance, un des avantages de la diversit\u00e9 au sein de l&rsquo;Union europ\u00e9enne est le fait qu&rsquo;elle soit compos\u00e9e de 27 pays diff\u00e9rents capables de mener chacun leur propre recherche et d&rsquo;\u00e9mettre leurs propres arguments, ou d&rsquo;exprimer leurs dissensions afin d&rsquo;\u00e9viter un d\u00e9sastre. Chacun d&rsquo;eux b\u00e9n\u00e9ficie du droit de veto. La Hongrie \u00e9tait un de ces pays dissidents sur le blanchiment de l&rsquo;argent &laquo;pour l&rsquo;Ukraine&raquo;.<\/p>\n<\/p>\n<p><p>La derni\u00e8re fois qu&rsquo;Orban s&rsquo;est oppos\u00e9 \u00e0 la pression de Bruxelles, \u00e9tait en d\u00e9cembre dernier, lorsqu&rsquo;il s&rsquo;\u00e9tait oppos\u00e9 \u00e0 l&rsquo;ouverture des n\u00e9gociations d&rsquo;adh\u00e9sion de l&rsquo;Ukraine \u00e0 l&rsquo;UE. Le chancelier allemand Olaf Scholz l&rsquo;avait alors convaincu de sortir dans le couloir afin qu&rsquo;ils puissent pr\u00e9tendre avoir l&rsquo;unanimit\u00e9 n\u00e9cessaire pour faire passer le projet. Mais seraient-ils parvenus \u00e0 lui faire prendre une autre pause pipi au bon moment pour voter \u00e0 nouveau \u00e0 l&rsquo;unanimit\u00e9 ? Cela aurait \u00e9t\u00e9 compliqu\u00e9. Qu&rsquo;ont donc fait les dirigeants de l&rsquo;UE ? Ils ont tout simplement trouv\u00e9 un argument juridique pour ignorer totalement les dispositions du trait\u00e9 ainsi que le vote de la Hongrie, le chef de la diplomatie europ\u00e9enne Josep Borrell d\u00e9clarant que l&rsquo;excuse, selon laquelle la Hongrie n&rsquo;avait pas vot\u00e9 pr\u00e9c\u00e9demment sur la question, \u00e9tait juridiquement ambig\u00fce, mais que &laquo;\u00e7a passe&raquo;. Les dirigeants de l&rsquo;UE sont tr\u00e8s press\u00e9s de d\u00e9bloquer cet argent pour la seule industrie manufacturi\u00e8re qu&rsquo;ils ne semblent pas avoir totalement d\u00e9truite avant que la musique ne s&rsquo;arr\u00eate, et que ces m\u00eames contribuables spoli\u00e9s ne votent d\u00e9mocratiquement pour les partis anti-establishment \u00e0 travers l&rsquo;Europe, dans une tentative d\u00e9sesp\u00e9r\u00e9e de mettre fin \u00e0 toute cette mascarade de financement de l&rsquo;Ukraine, qui d\u00e9truit efficacement leurs portefeuilles.<\/p>\n<\/p>\n<p><p>Les Europ\u00e9ens n&rsquo;ont pas non plus vot\u00e9 pour que leurs dirigeants \u00e9lus utilisent l&rsquo;argent des contribuables europ\u00e9ens afin que les banques europ\u00e9ennes renflouent la dette de l&rsquo;Ukraine. Or, puisque les contribuables et des nations enti\u00e8res paient d\u00e9j\u00e0 pour ce bourbier ukrainien, pourquoi ne pas jeter les banques de l&rsquo;UE dans ce bateau en naufrage?<\/p>\n<\/p>\n<p><p>La pr\u00e9sidente de la Commission europ\u00e9enne, Ursula von der Leyen, a annonc\u00e9, au d\u00e9but du mois \u00e0 Berlin, que les banques europ\u00e9ennes pourraient recevoir un &laquo;soutien budg\u00e9taire&raquo; d&rsquo;un montant total de 1,4 milliard d&rsquo;euros de la part des contribuables europ\u00e9ens lorsqu&rsquo;ils investissent dans des fonds d&rsquo;actions actifs en Ukraine, ce qui \u00e9liminerait les risques pour les banques. Et par &laquo;risques \u00e9limin\u00e9s&raquo;, elle sous-entend &laquo;risques transf\u00e9r\u00e9s&raquo; &hellip; aux contribuables europ\u00e9ens.<\/p>\n<\/p>\n<p><p>Pendant ce temps, Kiev promeut la n\u00e9cessit\u00e9 d&rsquo;obtenir davantage d&rsquo;argent \u00e9tranger pour &laquo;reconstruction&raquo;. Ces plaisantins pensent probablement que le grand public, apr\u00e8s avoir entendu le mot &laquo;reconstruction&raquo;, dans un \u00e9lan de compassion, ne r\u00e9aliserait pas que l&rsquo;argent est \u00e9galement utilis\u00e9 pour combler le trou de 20 milliards de dollars creus\u00e9 par l&rsquo;\u00e9quipe de Zelensky : qu&rsquo;attendiez-vous d&rsquo;un gars qui se pr\u00e9sente aux sommets mondiaux habill\u00e9 comme si son m\u00e9tier \u00e9tait litt\u00e9ralement de creuser des trous, et dont les remboursements des obligations internationales aux pays occidentaux arrivent \u00e0 \u00e9ch\u00e9ance cet \u00e9t\u00e9 ? Ainsi, la dette de l&rsquo;UE paierait effectivement la dette de l&rsquo;Ukraine, qui, \u00e0 son tour, rembourserait les obligations des &Eacute;tats-Unis et des 22 pays du Club de Paris, qui sont eux aussi endett\u00e9s. C&rsquo;est comme le film &laquo;Inception&raquo;, mais avec une dette : &laquo;Detteception&raquo;.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Crise des agriculteurs ? Kiev avant les Europ\u00e9ens<\/strong><\/h3>\n<\/p>\n<p><p>Et quel meilleur moyen de racketter les contribuables, que pour l&rsquo;Ukraine, l&rsquo;une des brebis galeuses de l&rsquo;Indice de perception de la corruption, de promouvoir la n\u00e9cessit\u00e9 de collecter des fonds pour une reconstruction en pleine guerre ? Pour que les gens puissent payer pour construire ce qui sera d\u00e9truit ? Un d\u00e9tail mineur apr\u00e8s que toutes les poches priv\u00e9es concern\u00e9es ont \u00e9t\u00e9 remplies, je suppose.<\/p>\n<\/p>\n<p><p>L&rsquo;UE peut cependant enti\u00e8rement faire confiance \u00e0 Kiev. Ce n&rsquo;est pas comme si Bruxelles avait introduit le 6 juin des lois imposant des droits de douane \u00e0 l&rsquo;importation de certains produits agricoles ukrainiens entrant dans l&rsquo;UE (par exemple, le sucre et les &oelig;ufs, pas m\u00eame les c\u00e9r\u00e9ales ukrainiennes \u00e0 destination de l&rsquo;Afrique, que l&rsquo;UE a renvers\u00e9es sur elle-m\u00eame), si les exportations de Kiev d\u00e9passaient un certain volume, seulement pour voir Kiev d\u00e9passer la limite fix\u00e9e en quelques jours. Cette mesure a \u00e9t\u00e9 prise en mars, en premier lieu pour r\u00e9pondre aux demandes de la Pologne, dont les agriculteurs, \u00e9tant juste \u00e0 la fronti\u00e8re, ont le plus p\u00e2ti du tsunami des importations ukrainiennes, ainsi qu&rsquo;aux demandes de la France, dont le pr\u00e9sident Macron avait fui les agriculteurs en col\u00e8re lors du Salon International de l&rsquo;Agriculture de Paris plus t\u00f4t cette ann\u00e9e, tandis que la police anti-\u00e9meute aspergeait de gaz lacrymog\u00e8ne les vaches tenues responsables du changement climatique.<\/p>\n<\/p>\n<p><p>Ainsi, l&rsquo;UE a en fait vendu ses propres agriculteurs pour jeter une bou\u00e9e de sauvetage \u00e0 l&rsquo;Ukraine. Mais le truc avec les bou\u00e9es de sauvetage c&rsquo;est de ne pas laisser le gars qui se noie s&rsquo;accrocher \u00e0 vous et vous entra&icirc;ner avec lui, ce que Kiev a vite r\u00e9ussi \u00e0 faire. Donc, soit Kiev est ignorant, soit imprudent. &Agrave; vous de choisir. C&rsquo;est le bon moment pour donner officiellement le feu vert aux n\u00e9gociations sur l&rsquo;adh\u00e9sion de l&rsquo;Ukraine \u00e0 l&rsquo;UE afin qu&rsquo;elle n&rsquo;ait plus \u00e0 faire face \u00e0 des tarifs ! Et pour que ces agriculteurs radicaux d&rsquo;extr\u00eame droite ne puissent pas dire qu&rsquo;ils ont \u00e9t\u00e9 inond\u00e9s de produits agricoles bon march\u00e9, douteux et \u00e9trangers ! Et c&rsquo;est exactement ce que les dirigeants du bloc ont fait vendredi dernier en votant pour le d\u00e9but officiel des n\u00e9gociations sur l&rsquo;adh\u00e9sion de l&rsquo;Ukraine \u00e0 l&rsquo;UE, malgr\u00e9 le fait que Kiev \u00e9tait occup\u00e9 \u00e0 donner l&rsquo;impression d&rsquo;\u00eatre un cas \u00e9conomique d\u00e9sesp\u00e9r\u00e9 sur la sc\u00e8ne mondiale.<\/p>\n<\/p>\n<p><p>Bruxelles continue de chercher des croquemitaines russes ou &laquo;d&rsquo;extr\u00eame droite&raquo; chaque fois que le peuple s&rsquo;oppose d\u00e9mocratiquement \u00e0 elle. Il est plut\u00f4t clair maintenant que les seuls qui s&rsquo;opposent \u00e0 la volont\u00e9 d\u00e9mocratique des \u00e9lecteurs sont les dirigeants de l&rsquo;UE. Et il semble qu&rsquo;\u00e0 l&rsquo;heure actuelle, ils font tout ce qui est en leur pouvoir pour que, quoi qu&rsquo;il arrive, leurs int\u00e9r\u00eats particuliers trouvent des radeaux de sauvetage et ne coulent pas avec le navire de l&rsquo;establishment.<\/p>\n<\/p>\n<p><h4>Rachel Marsden<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UE-Kiev, la f\u00eate aux vermines &bull; Un rapide coup d&rsquo;&oelig;il, mais tout de m\u00eame fort bien d\u00e9taill\u00e9, sur les circuits de circulation, notamment autour de l&rsquo;Ukraine, dans les couloirs de l&rsquo;UE. &bull; Une bonne mise en bouche de l&rsquo;effondrement, avec Rachel Marsden. ________________________ L&rsquo;UE s&rsquo;est d\u00e9finitivement install\u00e9e comme une sorte de monstre \u00e9norme cr\u00e9\u00e9 par&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3858,13969,3049,3048,1296,12093,2829],"class_list":["post-81152","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-corruption","tag-darmements","tag-marsden","tag-rachel","tag-ukraine","tag-ventes","tag-zelenski"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81152"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81152\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}