{"id":81181,"date":"2024-07-27T08:11:45","date_gmt":"2024-07-27T08:11:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/07\/27\/vous-etes-woke-alors-signez-au-fbi\/"},"modified":"2024-07-27T08:11:45","modified_gmt":"2024-07-27T08:11:45","slug":"vous-etes-woke-alors-signez-au-fbi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/07\/27\/vous-etes-woke-alors-signez-au-fbi\/","title":{"rendered":"Vous\u00a0 \u00eates <em>Woke\u00a0<\/em>? Alors, signez au FBI"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Vous  \u00eates <em>Woke <\/em>? Alors, signez au FBI<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Une <strong>temp\u00eate impressionnante est en train de s&#8217;emparer des services  de s\u00e9curit\u00e9 US<\/strong> \u00e0 la suite de la tentative d&rsquo;assassinat de Trump, et en corr\u00e9lation avec la mise en \u00e9vidence de la p\u00e9n\u00e9tration tr\u00e8s importante de certains services (le FBI) par l&rsquo;id\u00e9ologie <em>Woke <\/em>(DEI\/CRT). &bull; <strong>Le Secret Service (USSS) est en complet d\u00e9sarroi<\/strong> avec la d\u00e9mission de sa directrice et les questions pos\u00e9es sur son efficacit\u00e9, voire sur la p\u00e9n\u00e9tration subversive. &bull; Nombre de policiers locaux et des &Eacute;tats <strong>refusent d\u00e9sormais de coop\u00e9rer avec le FBI \u00e0 cause de son biais id\u00e9ologique<\/strong>.<\/p>\n<\/p>\n<p><p>_______________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Ce qu&rsquo;on nomme aux USA la \u00ab\u00a0communaut\u00e9 de s\u00e9curit\u00e9 nationale\u00a0\u00bb, qui regroupe tous les services de s\u00e9curit\u00e9 US et qui concerne \u00e9galement le champ d&rsquo;action g\u00e9n\u00e9ral am\u00e9ricaniste-occidentaliste, notamment les pays europ\u00e9ens o&ugrave; ces services US sont un peu \u00ab\u00a0comme  chez eux\u00a0\u00bb, &ndash; cette communaut\u00e9 est entr\u00e9e dans une s\u00e9v\u00e8re zone de turbulence, et m\u00eame d&rsquo;ores et d\u00e9j\u00e0 une temp\u00eate. Cette communaut\u00e9 fait partie du complexe militaro-industriel, lequel tend \u00e0 prendre la position id\u00e9ologique de la gauche globaliste en se parant du manteau du progressisme soci\u00e9tal et de l&rsquo;antiracisme.<\/p>\n<\/p>\n<p><p>Plusieurs \u00e9v\u00e9nements, notamment autour de l&rsquo;attentat contre Trump, ont d\u00e9clench\u00e9 un courant g\u00e9n\u00e9ral de protestation, notamment \u00e0 partir du Congr\u00e8s et de l&rsquo;entourage de Trump, contre plusieurs services de s\u00e9curit\u00e9. Il s&rsquo;agit de la concr\u00e9tisation d&rsquo;un courant de contestation venant des conservateurs, des populistes et des r\u00e9publicains (trumpistes), contre la p\u00e9n\u00e9tration dans les bureaucraties et les organismes publics du courant id\u00e9ologique progressiste-globaliste appuy\u00e9 sur la vague du mouvement &lsquo;<em>Woke<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>On reprend ci-dessous plusieurs de ces \u00e9v\u00e9nements au sein de services de s\u00e9curit\u00e9, en ayant \u00e0 l&rsquo;esprit qu&rsquo;un tr\u00e8s s\u00e9rieux antagonisme existe entre Trump, puis entre les populistes et les r\u00e9publicains d&rsquo;une part, et certains organes de s\u00e9curit\u00e9 depuis 2016-2019, et d&rsquo;une fa\u00e7on tr\u00e8s appuy\u00e9e, depuis 2020 (contestation de Trump, le mouvement de r\u00e9volte BLM [&lsquo;<em>Black Lives Matter<\/em>&lsquo;], \u00e9lection de Biden et troubles du 6 janvier 2021 au Capitole, etc.).<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, le Secret Service (USSS : United States Secret Service), dont la t\u00e2che principale est la protection des personnalit\u00e9s expos\u00e9es, se trouve gravement mis en cause \u00e0 la suite des erreurs gravissimes constat\u00e9es lors de l&rsquo;attaque contre Trump. Les erreurs sont telles qu&rsquo;elles ont largement nourri une <em>narrative <\/em>d&rsquo;un complot ourdi contre Trump. Elles ont de toutes les fa\u00e7ons provoqu\u00e9 <a href=\"https:\/\/www.rt.com\/news\/601657-us-task-force-trump-shooting\/\">une r\u00e9action ferme<\/a> du Congr\u00e8s (r\u00e9publicains et d\u00e9mocrates unis, chose rarissime et \u00e9ventuellement singuli\u00e8re), avec un rapport attendu pour la fin 2024, &ndash; juste apr\u00e8s l&rsquo;\u00e9lection pr\u00e9sidentielle&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;  <em>Les l\u00e9gislateurs am\u00e9ricains ont autoris\u00e9 la formation d&rsquo;un groupe de travail bipartisan pour enqu\u00eater sur la tentative d&rsquo;assassinat de l&rsquo;ancien pr\u00e9sident Donald Trump, selon une annonce publi\u00e9e mercredi soir sur le site Internet du Congr\u00e8s am\u00e9ricain.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Selon la r\u00e9solution publi\u00e9e sur le site Internet du Congr\u00e8s, les d\u00e9mocrates et les r\u00e9publicains de la Chambre des repr\u00e9sentants ont vot\u00e9 \u00e0 l&rsquo;unanimit\u00e9 en faveur de la cr\u00e9ation d&rsquo;un groupe de travail charg\u00e9 d&rsquo;enqu\u00eater sur la fusillade de Trump. Le pr\u00e9sident de la Chambre, Mike Johnson, a d\u00e9clar\u00e9 apr\u00e8s le vote que &laquo; prot\u00e9ger la s&ucirc;ret\u00e9 et la s\u00e9curit\u00e9 des dirigeants de notre pays est une responsabilit\u00e9 qui transcende les lignes de parti &raquo;.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le nouveau groupe de travail enqu\u00eatera sur les \u00e9checs en mati\u00e8re de s\u00e9curit\u00e9 aux niveaux f\u00e9d\u00e9ral, \u00e9tatique et local des forces de l&rsquo;ordre qui ont conduit \u00e0 la tentative d&rsquo;assassinat. Il sera compos\u00e9 de 13 membres, dont sept r\u00e9publicains et six d\u00e9mocrates. Le panel aura le pouvoir d&rsquo;assigner une assignation \u00e0 compara&icirc;tre et devrait pr\u00e9senter son rapport final sur la fusillade d&rsquo;ici le 13 d\u00e9cembre. Le rapport devrait inclure \u00ab\u00a0des recommandations sur les r\u00e9formes l\u00e9gislatives n\u00e9cessaires pour pr\u00e9venir de futures failles de s\u00e9curit\u00e9\u00a0\u00bb<\/em> &raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; En attendant, comme l&rsquo;on sait, la directrice de l&rsquo;USSS, Kimberly Cheattle, r\u00e9put\u00e9e pour avoir une tr\u00e8s faible exp\u00e9rience, sinon inexistante, de cette sorte de mission, a d&ucirc; reconna&icirc;tre devant le Congr\u00e8s que l&rsquo;attentat \u00e9tait &laquo; <em>un \u00e9chec colossal<\/em> &raquo; de l&rsquo;USSS, sinon le plus grave jamais connu. Entendue le 22 juillet et reconnaissant sa responsabilit\u00e9 propre du bout des l\u00e8vres, elle a ensuite \u00e9t\u00e9 assaillie de pressions et <a href=\"https:\/\/www.rt.com\/news\/601550-secret-service-director-resigns\/\">a d&ucirc; d\u00e9missionner<\/a> le 23 juillet. Cheattle \u00e9tait d&rsquo;abord un avatar des doctrines DEI\/CRT (\u00ab\u00a0il faut une femme \u00e0 ce poste !\u00a0\u00bb) suivies imp\u00e9rativement par Biden.<\/p>\n<\/p>\n<p><p>&bull; Parmi les premiers t\u00e9moins entendus en m\u00eame temps que Cheattle, il y avait le directeur du FBI, qui montra une grande humilit\u00e9, disant ne rien savoir ou presque, pour ne pas d\u00e9clencher l&rsquo;ire des d\u00e9put\u00e9s  (r\u00e9publicains et d\u00e9mocrates unis, oui !). Justement le FBI&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le FBI, organisation subversive<\/h3>\n<\/p>\n<p><p>&bull; En effet, c&rsquo;est peut-\u00eatre la nouvelle la plus int\u00e9ressante et la plus prometteuse. La commission qui m\u00e8ne cette enqu\u00eate vient de mettre <a href=\"https:\/\/www.scribd.com\/document\/753162523\/Final-Report-v07182024#fullscreen&#038;from_embed\">en ligne<\/a> un document re\u00e7u par elle-m\u00eame et \u00e9galement envoy\u00e9 au New York &lsquo;<em>Post<\/em>&lsquo;.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un rapport de 230 pages r\u00e9alis\u00e9 par une association nationale regroupant d&rsquo;anciens officiers du FBI et des officiers toujours en activit\u00e9. Leur enqu\u00eate a port\u00e9 sur l&rsquo;attitude des services locaux et r\u00e9gionaux de police vis-\u00e0-vis de leur coop\u00e9ration avec le FBI en tant que service national (f\u00e9d\u00e9ral). Trente sources sont cit\u00e9es, qualifi\u00e9es d&rsquo;&laquo; <em>ind\u00e9pendantes et hautement cr\u00e9dibles<\/em> &raquo;, &ndash; il s&rsquo;agit de lanceurs d&rsquo;alerte, &ndash; et leur sentiment est ainsi d\u00e9crit :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><em>&laquo; Ils ne sont pas seulement r\u00e9ticents \u00e0 travailler avec le FBI, mais ils semblent avoir d\u00e9cid\u00e9 de ne plus partager d&rsquo;informations substantielles et exploitables sur les activit\u00e9s criminelles et autres activit\u00e9s li\u00e9es au renseignement avec le Bureau, parce qu&rsquo;ils estiment qu&rsquo;il \u00ab\u00a0fonctionne\u00a0\u00bb comme une agence f\u00e9d\u00e9rale partisane motiv\u00e9e par un agenda politique\u00a0\u00bb depuis ces derni\u00e8res ann\u00e9es.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il s&rsquo;agit d&rsquo;un rapport consid\u00e9rable rassemblant des t\u00e9moignages de lanceurs d&rsquo;alerte qui semblent avoir accept\u00e9 le regroupement de leurs t\u00e9moignages pour obtenir un document d&rsquo;un poids beaucoup plus important que des t\u00e9moignages \u00e9pars. Ce qui est d\u00e9crit l\u00e0 est une &laquo; <em>crise de confiance<\/em> &raquo; dans les groupes dirig\u00e9s par le FBI et une &laquo; <em>perte de confiance inqui\u00e9tante<\/em> &raquo; dans le Bureau dans son ensemble. (Devant le Congr\u00e8s le directeur du FBI, t\u00e9moignant le 24 juillet, a effectivement parl\u00e9 d&rsquo;un &laquo; <em>environnement de menaces complexes<\/em> &raquo; comme il n&rsquo;en a jamais connu dans sa carri\u00e8re.) D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, c&rsquo;est le comportement du FBI durant les \u00e9v\u00e9nements du 6 janvier 2021 (&lsquo;J6&rsquo;) au Capitole qui a constitu\u00e9 un signe essentiel de ce basculement du FBI en un service totalement infiltr\u00e9 par l&rsquo;id\u00e9ologie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;une des sources a d\u00e9crit le comportement du FBI comme \u00ab\u00a0celui d&rsquo;un pays du tiers monde\u00a0\u00bb et a estim\u00e9 qu&rsquo;il \u00ab\u00a0devrait \u00eatre d\u00e9mantel\u00e9 et son personnel poursuivi en justice et condamn\u00e9 \u00e0 de longues peines de prison\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les pressions exerc\u00e9es pour apporter leur aide dans les affaires &lsquo;J6&rsquo; ont conduit \u00e0 croire que le Bureau est anim\u00e9 par un \u00ab\u00a0agenda politique partisan\u00a0\u00bb. Une source a d\u00e9clar\u00e9 qu&rsquo;elle ne comprenait pas pourquoi le FBI ne s&rsquo;en prenait pas \u00e0 d&rsquo;autres groupes avec la m\u00eame ferveur. Un autre a d\u00e9clar\u00e9 que les officiers locaux craignaient d&rsquo;\u00eatre cibl\u00e9s \u00ab\u00a0en raison de leur amour pour les Etats-Unis\u00a0\u00bb et per\u00e7us comme des \u00ab\u00a0terroristes nationaux\u00a0\u00bb&lsquo; en raison de leur vote.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les nouveaux agents du FBI \u00ab\u00a0ne prennent pas la peine de cacher leur d\u00e9go&ucirc;t\u00a0\u00bb pour les opinions politiques ou religieuses traditionnelles et s&rsquo;identifient ouvertement comme \u00ab\u00a0\u00e9veill\u00e9s <\/em>[&lsquo;<em>Woke<\/em>&lsquo;] <em>ou progressistes\u00a0\u00bb, a d\u00e9clar\u00e9 le chef d&rsquo;un groupe de travail multi-agences. Embauch\u00e9s sur la base des lignes directrices \u00ab\u00a0diversit\u00e9, \u00e9quit\u00e9 et inclusion\u00a0\u00bb (DEI), ils sont \u00ab\u00a0totalement sans valeur\u00a0\u00bb et \u00ab\u00a0constituent les pires recrues possibles\u00a0\u00bb, ont d\u00e9clar\u00e9 les lanceurs d&rsquo;alerte<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Enfin, dans ce tableau impressionnant, on peut ajouter en post-scriptum, comme on <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2024-larmee-pulverisee-par-le-woke\">l&rsquo;a vu hier<\/a>, les remous extr\u00eamement graves quoique discr\u00e8tement ignor\u00e9s, qui secouent les forces arm\u00e9es confront\u00e9e \u00e0 une attaque totale contre leur identit\u00e9 et leur orientation professionnelles par le biais des doctrines DEI\/CRT impos\u00e9es par une bureaucratie nouvelle install\u00e9e au Pentagone.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La temp\u00eate qui \u00e9branle la s\u00e9curit\u00e9 nationale<\/h3>\n<\/p>\n<p><p>Mis bout \u00e0 bout, et tenant compte de ce qui n&rsquo;est pas encore sorti au grand jour, il faut conclure qu&rsquo;une \u00e9norme crise est en train de saisir tout l&rsquo;appareil de s\u00e9curit\u00e9 nationale, des diverses polices aux forces arm\u00e9es. La m\u00eame situation doit exister dans des agences comme la CIA, bien entendu.<\/p>\n<\/p>\n<p><p>Ce qui nous importe ici est ce qu&rsquo;on peut constater au niveau des diff\u00e9rentes services de s\u00e9curit\u00e9 civils et para-militaires, en relevant ici l&rsquo;extraordinaire vitesse de diffusion de ce qu&rsquo;il importe absolument, par rapport aux missions de maintien de l&rsquo;ordre national, de d\u00e9signer comme une subversion. Lorsqu&rsquo;on songe \u00e0 ce qu&rsquo;\u00e9tait le FBI de J. Edgar Hoover, l&rsquo;organisation f\u00e9d\u00e9rale la plus conservatrice et r\u00e9actionnaire, raciste, homophobe (bien que Hoover ait \u00e9t\u00e9 sans doute lui-m\u00eame homosexuel), et qu&rsquo;elle devait \u00eatre encore jusqu&rsquo;aux premi\u00e8res ann\u00e9es 2010, l&rsquo;\u00e9volution est stup\u00e9fiante. Qui plus est et selon la m\u00eame m\u00e9thode, la subversion s&rsquo;insinue par l&rsquo;\u00e9ducation que le Bureau (comme les autres agence et services) dispense aux nouvelles recrues comme au personnel courant. Elle (la subversion) est donc structurelle et identifi\u00e9e \u00e0 la mission centrale de ces services et agences.<\/p>\n<\/p>\n<p><p>D&rsquo;ores et d\u00e9j\u00e0, cela pose des probl\u00e8mes pressants. L&rsquo;USSS peut-il encore assurer sa mission de protection des personnalit\u00e9s politiques, notamment des candidats, et sans doute notamment des candidats d\u00e9nonc\u00e9s par le parti d\u00e9mocrate, grand Parrain du &lsquo;<em>Woke<\/em>&lsquo; ? Qui plus est, comme on le comprend, cette position id\u00e9ologique qui se r\u00e9pand comme une subversion est radicale, r\u00e9volutionnaire, sans espoir d&rsquo;aucune \u00e9volution d&rsquo;apaisement. Tout cela est verrouill\u00e9, comme on l&rsquo;a vu hier pour les forces arm\u00e9es, par la sp\u00e9cialit\u00e9 de la d\u00e9mocratie am\u00e9ricaniste qui retrouve dans ce domaine \u00e9galement la formule de l&rsquo;URSS en cours d&rsquo;effondrement, qui est une bureaucratie absolument totalitaire.<\/p>\n<\/p>\n<p><p>Mais c&rsquo;est certainement l&rsquo;affaire du rapport sur la situation interne du FBI et la position de policiers d&rsquo;&Eacute;tats divers qui disent leur malaise, voire leur refus de coop\u00e9rer avec le FBI. Il est vrai que certains &Eacute;tats sont violemment hostiles aux doctrines wokenistes et leurs policiers nomm\u00e9s ou \u00e9lus par les autorit\u00e9s et la population locales, partagent ces positions qui les mettent en confrontation directe avec le FBI. Le conflit devient alors un classique des USA, d&rsquo;une opposition entre les pouvoirs r\u00e9gionaux et locaux et le pouvoir f\u00e9d\u00e9ral. C&rsquo;est une \u00e9volution centrifuge qui s&rsquo;alimente \u00e0 un domaine de plus, et un domaine vital, du fait de la  crise int\u00e9rieure des USA et de la fracture de ce pays en deux factions absolument hostiles. Bien entendu, le fait que cela affecte les probl\u00e8mes de s\u00e9curit\u00e9 et de protection des citoyens nous renvoie au fondement de la fragilit\u00e9 am\u00e9ricaine, celle de l&rsquo;Union, du pouvoir f\u00e9d\u00e9ral par rapport aux &Eacute;tats.<\/p>\n<\/p>\n<p><p>De toutes les fa\u00e7ons, il faut bien que la crise du syst\u00e8me de l&rsquo;am\u00e9ricanisme, qui s&rsquo;exprime notamment sinon au niveau culturel et psychologique avec la querelle du wokenisme, parvienne \u00e0 son point de rupture. Le probl\u00e8me expos\u00e9 ici para&icirc;t une bonne voie, sinon une voie d\u00e9cisive, pour acc\u00e9l\u00e9rer cette \u00e9volution.<\/p>\n<\/p>\n<p><p>Mis en ligne le 27 juillet 2024 \u00e0 08H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates Woke ? Alors, signez au FBI &bull; Une temp\u00eate impressionnante est en train de s&#8217;emparer des services de s\u00e9curit\u00e9 US \u00e0 la suite de la tentative d&rsquo;assassinat de Trump, et en corr\u00e9lation avec la mise en \u00e9vidence de la p\u00e9n\u00e9tration tr\u00e8s importante de certains services (le FBI) par l&rsquo;id\u00e9ologie Woke (DEI\/CRT). &bull; Le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[13977,14007,14006,2949,6008,7436,8049,13976,2639,14005],"class_list":["post-81181","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-dassassinat","tag-locales-fbi","tag-polices","tag-secession","tag-secret","tag-service","tag-subversion","tag-tentative","tag-trump","tag-usss"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81181"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81181\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}