{"id":81206,"date":"2024-08-14T01:28:32","date_gmt":"2024-08-14T01:28:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/08\/14\/pourquoi-les-ukrainiens-ont-ils-attaque-koursk\/"},"modified":"2024-08-14T01:28:32","modified_gmt":"2024-08-14T01:28:32","slug":"pourquoi-les-ukrainiens-ont-ils-attaque-koursk","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/08\/14\/pourquoi-les-ukrainiens-ont-ils-attaque-koursk\/","title":{"rendered":"Pourquoi les Ukrainiens ont-ils attaqu\u00e9 Koursk ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Pourquoi les Ukrainiens ont-ils attaqu\u00e9 Koursk ?<\/strong><\/h2>\n<\/p>\n<p><p>Alors que le monde entier commen\u00e7ait \u00e0 oublier b\u00e9atement l&rsquo;existence de l&rsquo;&Eacute;tat failli mis\u00e9rable, anciennement connu sous le nom d&rsquo;Ukraine, celui-ci nous a rappel\u00e9 son existence en attaquant la r\u00e9gion de Koursk, en Russie, dont elle est frontali\u00e8re. Plus d&rsquo;un millier de soldats ukrainiens, dont beaucoup appartiennent \u00e0 des formations nazies ayant fait leurs preuves au combat et dont beaucoup se sont retir\u00e9s de certaines parties du front existant de 1 000 km, le long duquel la partie ukrainienne est actuellement en train de battre m\u00e9thodiquement en retraite, ont \u00e9t\u00e9 \u00e9quip\u00e9s des chars et de l&rsquo;artillerie restants, pour la plupart fournis par l&rsquo;Occident \u00e0 ce stade, et ont re\u00e7u l&rsquo;ordre d&rsquo;attaquer une partie du territoire russe d\u00e9fendue faiblement et auparavant paisible, dans le cadre d&rsquo;une attaque de type terroriste. Quelques mercenaires polonais et fran\u00e7ais et quelques \u00e9gorgeurs g\u00e9orgiens bien connus ont \u00e9galement \u00e9t\u00e9 rep\u00e9r\u00e9s.<\/p>\n<\/p>\n<p><p>Au cours des deux jours suivants, ils ont perdu la plupart de leurs blind\u00e9s et de leur artillerie ainsi qu&rsquo;un bon tiers de leurs hommes, leurs voies de r\u00e9approvisionnement ont \u00e9t\u00e9 coup\u00e9es et ils sont maintenant bloqu\u00e9s et sur le point d&rsquo;\u00eatre d\u00e9truits par des troupes russes fra&icirc;ches qui ont \u00e9t\u00e9 d\u00e9p\u00each\u00e9es en urgence \u00e0 la fronti\u00e8re ukrainienne. Mais l&rsquo;arm\u00e9e ukrainienne perd actuellement environ 2 000 hommes par jour, souvent \u00e0 cause de bombardements de pr\u00e9cision (les bombes de l&rsquo;aviation russe, dont un tr\u00e8s grand nombre a \u00e9t\u00e9 stock\u00e9 \u00e0 l&rsquo;\u00e9poque sovi\u00e9tique, ont r\u00e9cemment \u00e9t\u00e9 dot\u00e9es d&rsquo;ailes courtes et de syst\u00e8mes de guidage de pr\u00e9cision), de sorte que le fiasco de Koursk n&rsquo;est qu&rsquo;un simple incident dans les statistiques. Par contre, le fait de retirer les nazis du front existant risque de le faire s&rsquo;effondrer encore plus rapidement.<\/p>\n<\/p>\n<p><p>Depuis ce matin, la Russie a instaur\u00e9 un r\u00e9gime d&rsquo;exception anti-terroriste \u00e0 Koursk et dans deux r\u00e9gions voisines, ce qui permettra aux autorit\u00e9s de s&rsquo;affranchir de certaines subtilit\u00e9s juridiques dans la gestion de l&rsquo;incursion. Bien que les dommages caus\u00e9s par ces attaques aient \u00e9t\u00e9 assez limit\u00e9s, la t\u00e9l\u00e9vision d&rsquo;&Eacute;tat russe a produit des rapports d\u00e9taill\u00e9s et accablants \u00e0 ce sujet.<\/p>\n<\/p>\n<p><p>En particulier, un correspondant militaire tr\u00e8s respect\u00e9, Yevgeny Poddubny, a subi de graves br&ucirc;lures lorsqu&rsquo;un drone kamikaze ukrainien a percut\u00e9 la voiture qu&rsquo;il conduisait (les op\u00e9rateurs de drones ukrainiens ciblent sp\u00e9cifiquement les journalistes). Plusieurs milliers de civils ont d&ucirc; \u00eatre \u00e9vacu\u00e9s des r\u00e9gions frontali\u00e8res (les Ukrainiens leur ont tir\u00e9 dessus alors qu&rsquo;ils fuyaient), re\u00e7oivent de l&rsquo;aide et sont h\u00e9berg\u00e9s ailleurs. Nombre d&rsquo;entre eux ont d&ucirc; laisser derri\u00e8re eux leurs animaux de compagnie et leur b\u00e9tail &ndash; un aspect qui semble avoir mis en col\u00e8re les t\u00e9l\u00e9spectateurs russes plus que toute autre chose.<\/p>\n<\/p>\n<p><p>Bien qu&rsquo;il semble trop t\u00f4t pour dire quel sera le r\u00e9sultat final de l&rsquo;incursion de Koursk, par analogie avec l&rsquo;incursion de Belgorod, qui s&rsquo;est produite il y a quelque temps et a entra&icirc;n\u00e9 la cr\u00e9ation d&rsquo;une zone tampon de l&rsquo;autre c\u00f4t\u00e9 de la fronti\u00e8re dans la r\u00e9gion de Kharkov, nous sommes amen\u00e9s \u00e0 penser que la r\u00e9gion de Sumy subira le m\u00eame sort : les Russes organiseront une g\u00e9n\u00e9reuse bande de territoire ennemi, compl\u00e8tement d\u00e9peupl\u00e9e, massivement min\u00e9e et soigneusement surveill\u00e9e \u00e0 la recherche de tout signe d&rsquo;activit\u00e9 humaine pour se pr\u00e9munir contre de nouvelles incursions.<\/p>\n<\/p>\n<p><p>Le 10 Ao&ucirc;t 2024, <a href=\"https:\/\/boosty.to\/cluborlov\/posts\/02bdf4c5-e5d0-4584-ac27-cc9bde3b8e78\">Club Orlov<\/a> &ndash; Traduction du &lsquo;<em><a href=\"https:\/\/lesakerfrancophone.fr\/pourquoi-les-ukrainiens-ont-ils-attaque-koursk\">Sakerfrancophone<\/a><\/em>&lsquo;<\/p>\n<\/p>\n<p><h4><\/p>\n<p><em>Note du Saker Francophone<\/em><\/h4>\n<\/p>\n<p><p><em>Depuis quelques temps, des gens ind\u00e9licats retraduisent \u00ab\u00a0mal\u00a0\u00bb en anglais nos propres traductions sans l&rsquo;autorisation de l&rsquo;auteur qui vit de ses publications. Dmitry Orlov nous faisait l&rsquo;amiti\u00e9 depuis toutes ses ann\u00e9es de nous laisser publier les traductions fran\u00e7aises de ses articles, m\u00eame ceux payant pour les anglophones. Dans ces nouvelles conditions, en accord avec l&rsquo;auteur, on vous propose la 1ere partie de l&rsquo;article ici. Vous pouvez lire la suite en fran\u00e7ais <a href=\"https:\/\/boosty.to\/cluborlov\/posts\/ffd059c5-8a13-4d3d-aed0-68ff3e64d147\">derri\u00e8re ce lien<\/a> en vous abonnant au site <a href=\"https:\/\/boosty.to\/cluborlov\">Boosty<\/a> de Dmitry Orlov.<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi les Ukrainiens ont-ils attaqu\u00e9 Koursk ? Alors que le monde entier commen\u00e7ait \u00e0 oublier b\u00e9atement l&rsquo;existence de l&rsquo;&Eacute;tat failli mis\u00e9rable, anciennement connu sous le nom d&rsquo;Ukraine, celui-ci nous a rappel\u00e9 son existence en attaquant la r\u00e9gion de Koursk, en Russie, dont elle est frontali\u00e8re. Plus d&rsquo;un millier de soldats ukrainiens, dont beaucoup appartiennent \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[2870,2631,14035,2668,1296],"class_list":["post-81206","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-attaque","tag-de","tag-kourk","tag-orlov","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81206"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81206\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}