{"id":81287,"date":"2024-10-15T15:46:47","date_gmt":"2024-10-15T15:46:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/10\/15\/russie-usa-cest-du-brutal\/"},"modified":"2024-10-15T15:46:47","modified_gmt":"2024-10-15T15:46:47","slug":"russie-usa-cest-du-brutal","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/10\/15\/russie-usa-cest-du-brutal\/","title":{"rendered":"Russie-USA\u00a0: \u201cC&rsquo;est du brutal\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Russie-USA : \u00ab\u00a0C&rsquo;est du brutal\u00a0\u00bb<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Dimanche, l&rsquo;excellent Joe Biden, sorti de ses cendres diverses, fit un beau discours o&ugrave; il exalta la n\u00e9cessit\u00e9 d&rsquo;accords de contr\u00f4le des armements, surtout nucl\u00e9aires et strat\u00e9giques. &bull; La r\u00e9ponse de Moscou \u00e0 plusieurs voix : <strong>chacun son bras d&rsquo;honneur, \u00e0 commencer par Medvedev<\/strong> (&laquo; [Ce] <em>ne serait pas plus utile que n\u00e9gocier une tr\u00eave avec<\/em> <em>Hitler en 1945<\/em> &raquo;). &bull; Il s&rsquo;agit certes d&rsquo;un sujet sans espoir ni perspective pour l&rsquo;instant mais une <strong>r\u00e9ponse si brutale des Russes indiquent que<\/strong> <strong>la Russie ne veut plus traiter<\/strong> dans l&rsquo;actuel contexte mondial. &bull; <strong>Il faut tout changer<\/strong>.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Dimanche, donc, Biden fait une d\u00e9claration assez peu attendue ni pr\u00e9vue en faveur de n\u00e9gociations pour un trait\u00e9 de r\u00e9duction des armes nucl\u00e9aires. Comme si l&rsquo;on \u00e9tait cinquante ans (Nixon qui n&rsquo;aurait pas d\u00e9missionn\u00e9) ou soixante ans (JFK qui aurait remise son voyage \u00e0 Dallas) plus t\u00f4t. On conviendra pourtant que le temps ne se trouve plus, \u00e0 Washington, aux roucoulades comme colombe sur une branche, rameau d&rsquo;olivier dans le bec. Pourtant, <a href=\"https:\/\/www.rt.com\/news\/605721-putin-world-order-germany\/\">c&rsquo;est bien lui qui parle<\/a> avec cette platitude assur\u00e9e :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Dans une d\u00e9claration faite dimanche, le pr\u00e9sident am\u00e9ricain Joe Biden a affirm\u00e9 que le monde doit continuer \u00e0 progresser vers un d\u00e9sarmement nucl\u00e9aire complet. \u00ab\u00a0Les &Eacute;tats-Unis sont pr\u00eats \u00e0 engager des n\u00e9gociations avec la Russie, la Chine et la Cor\u00e9e du Nord sans conditions pr\u00e9alables pour r\u00e9duire la menace nucl\u00e9aire\u00a0\u00bb, a-t-il soulign\u00e9. Biden a \u00e9galement affirm\u00e9 qu&rsquo;il n&rsquo;y avait aucune raison d&#8217;emp\u00eacher les progr\u00e8s dans la r\u00e9duction des arsenaux nucl\u00e9aires<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il n&rsquo;y a pas eu de r\u00e9action formelle du gouvernement russe \u00e0 cette d\u00e9claration, qui n&rsquo;en demandait d&rsquo;ailleurs, peut-\u00eatre pas de r\u00e9action directe. Il y a eu des commentaires, mais dits de mani\u00e8re tr\u00e8s officielle et de voix importantes dans la structure du pouvoir ; uniquement desd r\u00e9actions n\u00e9gatives, voire tr\u00e8s n\u00e9gatives&#8230;<\/p>\n<\/p>\n<p><p>A tout seigneur, tout honneur. Medvedev ne pouvait pas rater celle-l\u00e0, il s&rsquo;en est donc occup\u00e9, dans des termes ravageurs qui comparent Biden \u00e0 Hitler, en 1945 dans son bunker.<\/p>\n<\/p>\n<p><p>&bull; Dimitri Medvedev, ancien pr\u00e9sident de la F\u00e9d\u00e9ration de Russie et actuel vice-pr\u00e9sident du Conseil de S\u00e9curit\u00e9 de la F\u00e9d\u00e9ration. Le rejet est brutal.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Selon l&rsquo;ancien pr\u00e9sident russe, la proposition est encore \u00ab\u00a0un autre exemple d&rsquo;insolence\u00a0\u00bb de la part des &Eacute;tats-Unis<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Pensez-y : les &Eacute;tats-Unis m\u00e8nent une guerre presque totale (et certainement pas hybride) contre nous et cherchent \u00e0 vaincre strat\u00e9giquement notre pays&hellip; N\u00e9gocier une r\u00e9duction des armes nucl\u00e9aires avec l&rsquo;Am\u00e9rique ne serait pas plus utile que n\u00e9gocier une tr\u00eave avec<\/em> [le leader nazi Adolf] <em>Hitler en 1945<\/em><strong>.<\/strong> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le porte-parole officiel du pr\u00e9sident Poutine, Dimitri Pechkov, d&rsquo;habitude tr\u00e8s mod\u00e9r\u00e9 dans ses formulations. On remarquera qu&rsquo;il l&rsquo;est certainement un peu moins, avec des termes tels que \u00ab\u00a0absolument impossible\u00a0\u00bb, et selon l&rsquo;id\u00e9e que tant que les &Eacute;tats-Unis continueront \u00e0 jouer un r\u00f4le en Ukraine, l'\u00a0\u00bbabsolument impossible\u00a0\u00bb perdurera :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pechkov a \u00e9galement \u00e9mis des doutes sur la possibilit\u00e9 de n\u00e9gociations nucl\u00e9aires, soulignant qu'\u00a0\u00bbil est absolument impossible de discuter du sujet sans le lier \u00e0 tous les autres aspects de s\u00e9curit\u00e9\u00a0\u00bb, \u00e9tant donn\u00e9 qu'\u00a0\u00bbune guerre est men\u00e9e contre la Russie avec l&rsquo;implication indirecte et m\u00eame directe de puissances nucl\u00e9aires telles que les &Eacute;tats-Unis, le Royaume-Uni et la France\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Troisi\u00e8me r\u00e9action du s\u00e9nateur russe Konstantin Kosachev :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La d\u00e9claration du &lsquo;canard boiteux&rsquo; et son d\u00e9sir de marquer des points en mati\u00e8re de relations publiques sur le th\u00e8me du prix Nobel ne devraient gu\u00e8re \u00eatre consid\u00e9r\u00e9es comme une invitation s\u00e9rieuse \u00e0 des n\u00e9gociations<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Pourquoi jugent-ils que Biden lance une telle proposition maintenant ?<\/p>\n<\/p>\n<p><p>&bull; Medvedev sugg\u00e8re que Biden destine cette d\u00e9claration  pour montrer sa volont\u00e9, comme on le lui a demand\u00e9 avec empressement, d&rsquo;&laquo; <em>aider  sa prot\u00e9g\u00e9e sans cervelle <\/em>&raquo;, la joyeuse Kamala.<\/p>\n<\/p>\n<p><p>&bull; Pechkov n&rsquo;a rien expliqu\u00e9, car ce qui se con\u00e7oit bien s&rsquo;\u00e9nonce clairement, &ndash; m\u00eame par le silence.<\/p>\n<\/p>\n<p><p>&bull; Kosachev, on l&rsquo;a lu, parle du Prix Nobel que Biden, qui ne doute de rien dans le grand vide de l&rsquo;univers, esp\u00e8re d\u00e9crocher \u00e0 Stockholm, pour la paix dans le monde. Kosachev rappelle que Biden a fait ce discours pour f\u00e9liciter le groupe &lsquo;Nihon Hidankyo&rsquo;, groupe japonais voulant abolir les armes nucl\u00e9aires et a re\u00e7u pour cela le Prix Nobel de la Paix. Peut-\u00eatre effectivement les restes de l'\u00a0\u00bb\u00e9quipe Biden\u00a0\u00bb songe-t-elle \u00e0 des calculs aussi sordides, aussi enfantins, aussi grotesques-bouffe &ndash; peut-\u00eatre, peut-\u00eatre&#8230; Et peut-\u00eatre bien qu&rsquo;on le lui donnera le Prix Nobel de la Paix pour que nous nous enfoncions encore plus dans le marigot de mati\u00e8re en putr\u00e9faction qu&rsquo;est devenue notre civilisation.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le temps perdu du d\u00e9couplage<\/h3>\n<\/p>\n<p><p>Sans le moindre doute, prise s\u00e9par\u00e9ment, ces d\u00e9clarations n&rsquo;ont rien d&rsquo;exceptionnelle, dans le simulacre courant dans de na\u00efves habilet\u00e9s mensong\u00e8res ou dans la violence coutumi\u00e8re de la guerre. Ce n&rsquo;est donc pas elles qui nous int\u00e9ressent au point d&rsquo;en faire un texte de commentaire, mais que la seconde cat\u00e9gorie (la violence coutumi\u00e8re de la guerre) r\u00e9ponde d&rsquo;une seule voix \u00e0 la premi\u00e8re (les na\u00efves habilet\u00e9s mensong\u00e8res).<\/p>\n<\/p>\n<p><p>Manifestement, les trois voix russes sont \u00e0 l&rsquo;unisson, dont l&rsquo;une du porte-parole de Poutine avec des remarques d\u00e9cisives (l'\u00a0\u00bbabsolument impossible\u00a0\u00bb de Pechkov) ; c&rsquo;est-\u00e0-dire qu&rsquo;\u00e0 elles trois, elles r\u00e9sument la r\u00e9action de Poutine qui a estim\u00e9 ne pas devoir prendre la peine d&rsquo;y r\u00e9pondre personnellement, dans tous les cas aussit\u00f4t. On pourra d\u00e8s lors interpr\u00e9ter cette situation comme une indication que la direction russe n&rsquo;a vraiment plus aucune confiance dans la possibilit\u00e9 de la moindre entente avec les USA dans la situation o&ugrave; ils se trouvent (corruption, <em>DeepState<\/em>, extr\u00e9misme pathologique, communication syst\u00e9matiquement mensong\u00e8re).<\/p>\n<\/p>\n<p><p>Jusqu&rsquo;ici, y compris dans les pires moments de tension, Moscou ne rejetait jamais d&rsquo;une fa\u00e7on aussi cat\u00e9gorique une offre de n\u00e9gociation sur le plus haut de l&rsquo;armement nucl\u00e9aire (strat\u00e9gique nucl\u00e9aire). M\u00eame si toutes les r\u00e9serves du monde \u00e9taient dites, tous les obstacles \u00e9vidents, etc., il n&rsquo;y avait pas de ces attitudes brutales comme on les sent ici. Plus encore, la r\u00e9ponse de Pechkov sous-entend qu&rsquo;il existe chez les Russes un \u00ab\u00a0couplage\u00a0\u00bb des questions militaires et strat\u00e9giques : \u00ab\u00a0Nous ne traiterons avec vous (sur le nucl\u00e9aire strat\u00e9gique) que lorsque les autres domaines (s\u00e9curit\u00e9 europ\u00e9enne, situation tactique des bases US, etc.) seront trait\u00e9s, ou en voie de l&rsquo;\u00eatre, ou consid\u00e9r\u00e9s comme pouvant \u00eatre r\u00e9gl\u00e9s.<\/p>\n<\/p>\n<p><p>A cette \u00e9poque ancienne, <em>in illo tempore<\/em>, du temps de JFK-McNamara ou de Nixon-Kissinger, existait le concept de \u00ab\u00a0d\u00e9couplage\u00a0\u00bb : on ne fait pas d\u00e9pendre des n\u00e9gociations sur le plus haut niveau strat\u00e9gique nucl\u00e9aire de la situation dans les autres domaines de la s\u00e9curit\u00e9. Aujourd&rsquo;hui, cette situation raisonnable, accept\u00e9e par les Russes et les Am\u00e9ricains, n&rsquo;existent plus.<\/p>\n<\/p>\n<p><p>Pour les Russes, cela ne date certainement pas, ni de f\u00e9vrier 2022, du de f\u00e9vrier 2014 (Ma\u00efdan). Cela date de1991-1992, de l&rsquo;\u00e9poque de promesses des Bush-Baker sur un non-\u00e9largissement de l&rsquo;OTAN. Lorsque le g\u00e9n\u00e9ral polonais <a href=\"https:\/\/www.rt.com\/news\/605600-poland-threat-attack-petersburg\/\">Rajmund Andrzejczak<\/a> a annonc\u00e9 il y a une semaine que l&rsquo;arm\u00e9e polonaise avait des plans pour tirer sur Saint-Petersbourg si la Russie p\u00e9n\u00e9trait de \u00ab\u00a0<em>one inch<\/em>\u00a0\u00bb dans les territoires polonais et baltes, on aurait pu, &ndash; on pourrait, on le fait, lui rappeler et lui r\u00e9torquer que le secr\u00e9taire d&rsquo;&Eacute;tat Baker avait promis \u00e0 Gorbatchev que l&rsquo;OTAN ne s&rsquo;\u00e9largirait pas de \u00ab\u00a0<em>one inch<\/em>\u00a0\u00bb vers l&rsquo;Est de la fronti\u00e8re de l&rsquo;ex-RDA (dans l&rsquo;Allemagne r\u00e9unifi\u00e9e), apr\u00e8s que la Russie ait accept\u00e9 la r\u00e9unification \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;OTAN. Ce genre de m\u00e9moire en forme de perspective o&ugrave; la <a href=\"https:\/\/www.dedefensa.org\/article\/2016-notre-verdun-et-ma-nostalgie-infinie-1\">nostalgie<\/a> joue un r\u00f4le de p\u00e9dagogie pour l&rsquo;\u00e9ternit\u00e9 est la cause principale pour laquelle toute confiance de la Russie dans les USA et ses vassaux a disparu, et avec elle la perspective d&rsquo;un accord.<\/p>\n<\/p>\n<p><p>D&rsquo;un point de vue plus large et plus profond, cela nous conduit \u00e0 constater que cette attitude compl\u00e8tement n\u00e9gative implique que Poutine et la Russie n&rsquo;acceptent plus l&rsquo;actuel arrangement du monde, que Poutine veut bel et bien, et avec  lui selon des engagements plus ou moins fermes l&rsquo;essentiel du \u00ab\u00a0Sud Global\u00a0\u00bb, par BRICS et SCO interpos\u00e9s, un <a href=\"https:\/\/www.rt.com\/news\/605721-putin-world-order-germany\/\">nouvel \u00ab\u00a0ordre du monde\u00a0\u00bb<\/a>. (Tout le monde pense bien entendu avec force <a href=\"https:\/\/www.dedefensa.org\/article\/la-multipolarite-a-lecole-de-guiguzi\">\u00e0 la multipolarit\u00e9<\/a>.)<\/p>\n<\/p>\n<p><p>Au reste, l&rsquo;\u00e9tat actuel de l&rsquo;Occident-facultatif, remu\u00e9 en tous sens par les crises isra\u00e9liennes et ukrainiennes (voir aujourd&rsquo;hui, &ndash; chaque jour apporte son lot, &ndash; l&rsquo;<a href=\"https:\/\/www.rt.com\/news\/605722-eu-urged-cut-trade-israel\">Espagne<\/a> et l&rsquo;<a href=\"https:\/\/www.rt.com\/news\/605720-germany-asks-israel-genocide-assurance\/\">Allemagne<\/a> vis-\u00e0-vis d&rsquo;Isra\u00ebl), laisse voir un rel\u00e2chement consid\u00e9rable des liens entre alli\u00e9s  et vassaux, jusqu&rsquo;\u00e0 des ruptures probables. Cela nous dit que ce nouvel ordre du monde ne r\u00e9sultera pas n\u00e9cessairement d&rsquo;une bataille, mais possiblement de la n\u00e9cessit\u00e9 m\u00eame de l&rsquo;effondrement de l&rsquo;actuel \u00ab\u00a0ordre du monde\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Mis en ligne le 15 octobre 2024 \u00e0 15H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russie-USA : \u00ab\u00a0C&rsquo;est du brutal\u00a0\u00bb &bull; Dimanche, l&rsquo;excellent Joe Biden, sorti de ses cendres diverses, fit un beau discours o&ugrave; il exalta la n\u00e9cessit\u00e9 d&rsquo;accords de contr\u00f4le des armements, surtout nucl\u00e9aires et strat\u00e9giques. &bull; La r\u00e9ponse de Moscou \u00e0 plusieurs voix : chacun son bras d&rsquo;honneur, \u00e0 commencer par Medvedev (&laquo; [Ce] ne serait pas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7420,2651,2858,2878,4866,4673,3004,6456,8798,2730],"class_list":["post-81287","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-desarmement","tag-du","tag-medvedev","tag-monde","tag-multiculturalisme","tag-nouvel","tag-nucleaire","tag-ordre","tag-refus","tag-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81287"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81287\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}