{"id":81288,"date":"2024-10-16T11:21:06","date_gmt":"2024-10-16T11:21:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/10\/16\/chaos-incontrole-2\/"},"modified":"2024-10-16T11:21:06","modified_gmt":"2024-10-16T11:21:06","slug":"chaos-incontrole-2","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/10\/16\/chaos-incontrole-2\/","title":{"rendered":"\u201c<em>Chaos incontr\u00f4l\u00e9<\/em>\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>\u00ab\u00a0<em>Chaos incontr\u00f4l\u00e9<\/em>\u00ab\u00a0<\/strong><\/h2>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un d\u00e9sastre qui se pr\u00e9pare depuis 80 ans, depuis la victoire am\u00e9ricaine de la Seconde Guerre mondiale, dont les cons\u00e9quences ont donn\u00e9 aux &Eacute;tats-Unis le privil\u00e8ge exorbitant d&rsquo;imprimer de l&rsquo;argent sans limite, renforc\u00e9 par des bombardements et des invasions pratiquement ininterrompus. Depuis l&rsquo;invasion de l&rsquo;Afghanistan en octobre 2001, tout ce que l&rsquo;arm\u00e9e am\u00e9ricaine a touch\u00e9 au cours de ces ann\u00e9es a \u00e9t\u00e9 r\u00e9duit en poussi\u00e8re.<\/p>\n<\/p>\n<p><p>Les \u00e9checs des &Eacute;tats-Unis \u00e0 fomenter le chaos ne se sont pas limit\u00e9s \u00e0 la sph\u00e8re militaire : leurs tentatives de semer le chaos politique ont \u00e9t\u00e9 tout aussi inefficaces. Le lancement de l&rsquo;op\u00e9ration militaire sp\u00e9ciale russe visant \u00e0 d\u00e9militariser et \u00e0 d\u00e9nazifier l&rsquo;Ukraine au d\u00e9but de 2022 a \u00e9t\u00e9 un signal pour le monde entier : plus personne n&rsquo;a besoin d&rsquo;ob\u00e9ir aux &Eacute;tats-Unis ! Mais perdre le contr\u00f4le de ses adversaires est, dans une certaine mesure, pr\u00e9visible et ce n&rsquo;est m\u00eame pas le pire. Ce qui est encore plus grave, c&rsquo;est que les Washingtoniens sont en train de perdre le contr\u00f4le de leurs alli\u00e9s, sur les ressources desquels ils se sont appuy\u00e9s dans leur qu\u00eate d\u00e9sormais frustr\u00e9e de domination mondiale.<\/p>\n<\/p>\n<p><p>Compte tenu de cette \u00e9volution, le plus logique pour les &Eacute;tats-Unis serait d&rsquo;essayer de limiter leurs pertes. Ils devraient essayer de trouver un compromis mutuellement acceptable avec leurs alli\u00e9s et laisser leurs adversaires s&rsquo;occuper de ceux qui \u00e9chappent totalement \u00e0 leur contr\u00f4le. Mais une telle gestion g\u00e9opolitique exige un leadership sobre, pragmatique et bien inform\u00e9, qui n&rsquo;existe pas aux &Eacute;tats-Unis. L&rsquo;alternative est d&rsquo;attendre que le pire des sc\u00e9narios se r\u00e9alise. Le dernier endroit o&ugrave; le chaos deviendra incontr\u00f4lable sera peut-\u00eatre Washington. L&rsquo;\u00e2ge sombre am\u00e9ricain qui s&rsquo;ensuivra constituera une \u00e9tude de cas int\u00e9ressante pour de futures recherches.<\/p>\n<\/p>\n<p><p>13 Octobre 2024, <a href=\"https:\/\/boosty.to\/cluborlov\/posts\/46214375-8583-47d8-acb9-3ade6b5cb712\">Club Orlov<\/a> &ndash; Traduction du &lsquo;<em><a href=\"https:\/\/lesakerfrancophone.fr\/chaos-incontrole\">Sakerfrancophone<\/a><\/em>&lsquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Note<\/strong><\/h3>\n<\/p>\n<p><p>La version papier du nouveau livre de Dimitri Orlov, &lsquo;<em>Uncontrolled Chaos<\/em>&lsquo;, est <a href=\"https:\/\/www.amazon.com\/dp\/B0DJZ55NWH\">disponible<\/a> en anglais.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Chaos incontr\u00f4l\u00e9\u00ab\u00a0 Il s&rsquo;agit d&rsquo;un d\u00e9sastre qui se pr\u00e9pare depuis 80 ans, depuis la victoire am\u00e9ricaine de la Seconde Guerre mondiale, dont les cons\u00e9quences ont donn\u00e9 aux &Eacute;tats-Unis le privil\u00e8ge exorbitant d&rsquo;imprimer de l&rsquo;argent sans limite, renforc\u00e9 par des bombardements et des invasions pratiquement ininterrompus. Depuis l&rsquo;invasion de l&rsquo;Afghanistan en octobre 2001, tout ce que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[5173,2647,2668],"class_list":["post-81288","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-livre","tag-nouveau","tag-orlov"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81288"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81288\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}