{"id":81340,"date":"2024-11-23T18:08:25","date_gmt":"2024-11-23T18:08:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/11\/23\/les-surprises-dorechnik\/"},"modified":"2024-11-23T18:08:25","modified_gmt":"2024-11-23T18:08:25","slug":"les-surprises-dorechnik","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/11\/23\/les-surprises-dorechnik\/","title":{"rendered":"Les surprises d&rsquo;\u2018<em>Orechnik<\/em>&lsquo;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les surprises d\u00a0\u00bb<em>Orechnik<\/em>&lsquo;<\/h2>\n<\/p>\n<p><p>23 novembre 2024 (18H00) &ndash; Le tir d&rsquo;un missile IRBM (jusqu&rsquo;\u00e0 5 000 kilom\u00e8tres de port\u00e9e) russe de type nouveau, dit &lsquo;<em>Orechnik<\/em>&lsquo;, produit un formidable effet de communication aux multiples nuances, &ndash; mais en aucune fa\u00e7on le silence dont nous savons tous qu&rsquo;il est l&rsquo;arme principale du simulacre. Donc, &lsquo;<em>Orechnik<\/em>&lsquo; existe et l&rsquo;on en a grand&rsquo;peur. Il faut dire aussi que, pour la grande presse, dites-presseSyst\u00e8me, c&rsquo;est une \u00ab\u00a0premi\u00e8re\u00a0\u00bb des barbares de l&rsquo;Est. Prenez &lsquo;<em>Les &Eacute;chos<\/em>&lsquo; du <a href=\"https:\/\/www.lesechos.fr\/monde\/enjeux-internationaux\/le-fil-info-les-principales-informations-de-ce-jeudi-21-novembre-2132920\">21 novembre 2024<\/a> par exemple, rien de plus chic et de mieux inform\u00e9 :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Un tir de missile hypersonique a \u00e9t\u00e9 lanc\u00e9 pour la premi\u00e8re fois sur l&rsquo;Ukraine par la Russie. Celle-ci l&rsquo;a revendiqu\u00e9, affirmant avoir pr\u00e9venu les Etats-Unis 30 minutes avant le lancement. Washington a d\u00e9nonc\u00e9 une \u00ab\u00a0escalade\u00a0\u00bb du conflit<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je ne veux pas avoir l&rsquo;air de donner des le\u00e7ons \u00e0 des gens si bien \u00e9lev\u00e9s et relevant avec fiert\u00e9 d&rsquo;une subvention publique cons\u00e9quente, mais non, le &laquo; <em>premi\u00e8re fois<\/em> &raquo;, \u00e7a ne passe pas ; comme une ar\u00eate de poisson fich\u00e9e dans la gorge, un bobard install\u00e9 devant vos yeux et trop institutionnalis\u00e9 pour qu&rsquo;on puisse avoir l&rsquo;audace de l&rsquo;ignorer&#8230; Quoi qu&rsquo;il en soit, et malgr\u00e9 que je ne puisse heureusement pr\u00e9tendre \u00eatre une r\u00e9f\u00e9rence pour ces gens-l\u00e0, &lsquo;<em>dedefensa.org<\/em>&lsquo; \u00e9crivait dans un article du <a href=\"https:\/\/www.dedefensa.org\/article\/message-hypersonique-en-pleine-ukrisis\">22 mars 2022<\/a> ce qui suit :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pour la premi\u00e8re fois, &ndash; si l&rsquo;on met \u00e0 part des rumeurs d&#8217;emploi op\u00e9rationnel exp\u00e9rimental d&rsquo;un exemplaire en Syrie en 2021, &ndash; des missiles hypersoniques Kh-47M2 &lsquo;Kinzhal&rsquo; (ou &lsquo;Kinjal&rsquo;, comme employ\u00e9 par <a href=\"https:\/\/francais.rt.com\/international\/97240-russie-annonce-nouvelles-frappes-hypersoniques-infrastructures-militaires-ukraine\">RT-France<\/a> et les commentateurs-spotters fran\u00e7ais ?) ont \u00e9t\u00e9 utilis\u00e9s en Ukraine, sans doute \u00e0 partir d&rsquo;avions lanceurs MiG-31K op\u00e9rant \u00e0 partir de la Crim\u00e9e<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230;Et il y en eut bien d&rsquo;autres. Mais non, pour ces gens-l\u00e0, type-&lsquo;<em>Les &Eacute;chos<\/em>&lsquo;, c&rsquo;est la premi\u00e8re fois. Je ne vais pas m&rsquo;amuser \u00e0 monter un proc\u00e8s couru d&rsquo;avance, pour des gens comme \u00ab\u00a0ces gens-l\u00e0\u00a0\u00bb, mais il se trouve qu&rsquo;il faut comprendre pourquoi on parle avec tant de tintamarre d&rsquo;un missile hypersonique russe, alors que bien d&rsquo;autres ont \u00e9t\u00e9 tir\u00e9s, qui ont fait, eux aussi, des d\u00e9g\u00e2ts consid\u00e9rables. On <a href=\"https:\/\/www.dedefensa.org\/article\/comme-au-temps-des-ss-20\">l&rsquo;a vu hier<\/a>, je pense que le \u00ab\u00a0coup\u00a0\u00bb a \u00e9t\u00e9 bien suivi et entretenu (je ne dis pas \u00ab\u00a0provoqu\u00e9\u00a0\u00bb) par les Russes et Poutine une fois qu&rsquo;ils aient senti qu&rsquo;il y avait cette fois un effet public transnational consid\u00e9rable.<\/p>\n<\/p>\n<p><p>Cette fois, le Syst\u00e8me n&rsquo;accueillit plus la nouvelle par le silence. De nombreuses indications furent donn\u00e9es, auxquelles Poutine en rajouta solennellement quelques couches. On en parla \u00e0 trouille ouverte et l&rsquo;Europe d\u00e9couvrit qu&rsquo;elle \u00e9tait nue, &ndash; \u00e0 part quelque dingue anglo-saxon, ici et l\u00e0. Je dis bien \u00ab\u00a0l&rsquo;Europe\u00a0\u00bb car on sait bien que &lsquo;<em>Orechnik<\/em>&lsquo; est taill\u00e9 aux petits oignons pour atteindre tous les coins et recoins de l&rsquo;Europe. C&rsquo;est simple, pour moi l&rsquo;analogie avec <a href=\"https:\/\/www.dedefensa.org\/article\/comme-au-temps-des-ss-20\">le SS-20<\/a> et la trouille grandiose que ce missile mythique infligea au continent dans les ann\u00e9es 1977-1987, s&rsquo;imposa aussit\u00f4t : et l&rsquo;engin, et la trouille&#8230; Ainsi retrouve-t-on les chemins du r\u00e9el.<\/p>\n<\/p>\n<p><p>Pourquoi maintenant, pourquoi &lsquo;<em>Orechnik<\/em>&lsquo; et pas <em>&lsquo;Kinzhal&rsquo; <\/em>? La censure, l&rsquo;autocensure, la trouille et la b\u00eatise sont une explication insuffisante. &lsquo;<em>Orechnik<\/em>&lsquo; a perc\u00e9 une cuirasse, ouvert une br\u00e8che mortelle dans le mur de pierre, perc\u00e9 une voie d&rsquo;eau \u00e9pouvantable dans la coque du &lsquo;<em>Titanic<\/em>&lsquo;. Je ne veux pas d&rsquo;explications techniques et politiques, car je suis s&ucirc;r qu&rsquo;on en trouverait autant dans d&rsquo;autres circonstances, pour la m\u00e8me sorte d&rsquo;incident. Reste cette chose essentielle que le Simulacre, perc\u00e9 en un point comme s&rsquo;il \u00e9tait perc\u00e9 de toutes parts, agonise en se vidant presque comme fait une obsc\u00e9nit\u00e9. Je suis s&ucirc;r d&rsquo;avoir lu, sous la plume d&rsquo;un commentateur anonyme, d&rsquo;un texte ou un autre, cette \u00e9bauche de po\u00e8me venu d&rsquo;un po\u00e8te inconnu, qui nous dit tout, &ndash; dr\u00f4le d&rsquo;id\u00e9e mais belle id\u00e9e d&rsquo;introduire la po\u00e9sie dans le d\u00e9bat ukrainien comme partie int\u00e9grante de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Sous leurs yeux brutalement d\u00e9cill\u00e9s,<\/p>\n<p>Leur regard embrasse un spectacle<\/p>\n<p>Qu&rsquo;ils pensaient relever de l&rsquo;imposture des sens,<\/p>\n<p>Et qu&rsquo;ils m\u00e9prisaient en le regardant sans le voir<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Bien entendu, rien n&rsquo;est fini et l&rsquo;on dirait plus volontiers que tout commence. Tout le monde est d\u00e9sormais \u00e0 d\u00e9couvert. L&rsquo;on sait quel est l&rsquo;enjeu, quelles sont les positions des uns et des autres, quels sont les risques jusqu&rsquo;aux plus terribles. Les deux mois qui nous attendent sont comme une immense temp\u00eate que les dieux nous obligent \u00e0 subir au large du Cap Horn, comme une initiation.<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.rt.com\/news\/608097-putin-adult-ukraine-conflict\/\">RT.com<\/a> a fait appel au \u00ab\u00a0<em>progressive pundit<\/em>\u00ab\u00a0, expert \u00ab\u00a0progressiste\u00a0\u00bb mais superbement ind\u00e9pendant Jimmy Dore, pour nous r\u00e9sumer la situation :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Joe Biden et les n\u00e9oconservateurs de son administration n&rsquo;ont cess\u00e9 d&rsquo;intensifier la guerre&hellip; Ce qu&rsquo;ils essaient de faire, c&rsquo;est d&rsquo;aggraver la guerre de fa\u00e7on \u00e0 ce que Donald Trump ne puisse pas l&rsquo;arr\u00eater\u00a0\u00bb, a d\u00e9clar\u00e9 Dore, avertissant que le r\u00e9sultat final de leurs actions pourrait \u00eatre une nouvelle guerre mondiale.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Le seul espoir que nous avons est que Poutine fasse preuve de retenue, qu&rsquo;il soit le seul adulte dans la salle et qu&rsquo;il puisse attendre d&rsquo;une mani\u00e8re ou d&rsquo;une autre jusqu&rsquo;\u00e0 ce que Donald Trump devienne pr\u00e9sident\u00a0\u00bb, a-t-il d\u00e9clar\u00e9. Trump sera investi fin janvier et s&rsquo;est engag\u00e9 \u00e0 mettre rapidement fin au conflit ukrainien d\u00e8s son entr\u00e9e en fonction.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0C&rsquo;est pourquoi l&rsquo;establishment d\u00e9teste Trump&hellip; pourquoi ils l&rsquo;ont accus\u00e9 sans cesse d&rsquo;\u00eatre un tra&icirc;tre et de travailler avec Poutine &ndash; c&rsquo;\u00e9tait la seule carte qu&rsquo;ils avaient \u00e0 jouer, car il a \u00e9t\u00e9 \u00e9lu sur la promesse de mettre fin \u00e0 nos guerres interventionnistes de changement de r\u00e9gime \u00e0 l&rsquo;\u00e9tranger\u00a0\u00bb, a d\u00e9clar\u00e9 Dore<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Entr\u00e9e dans la dissuasion<\/strong><\/h3>\n<\/p>\n<p><p>L\u00e0-dessus, je vais me faire plus technique pour donner un argument \u00e0 ceux qui esp\u00e8rent qu&rsquo;on \u00e9vitera l&rsquo;in\u00e9vitable. C&rsquo;est la terrible &lsquo;<em>Orechnik<\/em>&lsquo; qui nous l&rsquo;apporte, et il s&rsquo;agit d&rsquo;une confirmation des plus int\u00e9ressantes car l&rsquo;on voit alors les Russes occuper une place bien plus confortable dans la partie. Il s&rsquo;agit du constat immanquable selon nous que l&rsquo;hypersonique offre un degr\u00e9 de plus dans la dissuasion, entre la guerre conventionnelle du plus haut niveau et la guerre nucl\u00e9aire. Il permet en effet de faire basculer la situation militaire et politique comme on voit faire dans les diff\u00e9rents \u00e9tapes de la dissuasion. Jusqu&rsquo;ici, il s&rsquo;agissait d&rsquo;une hypoth\u00e8se op\u00e9rationnelle que nous d\u00e9veloppons depuis le <a href=\"https:\/\/www.dedefensa.org\/article\/message-hypersonique-en-pleine-ukrisis\">22 mars 2022<\/a>, lorsqu&rsquo;il fut ainsi \u00e9crit :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ce que montrent les frappes de &lsquo;Kinzhal&rsquo;, c&rsquo;est qu&rsquo;avec des ogives conventionnelles et des objectifs bien pr\u00e9cis, le missile hypersonique devient effectivement, comme l&rsquo;observait Gour\u00e9, une nouvelle arme transformatrice du champ op\u00e9rationnel conventionnel. De telles frappes peuvent porter des coups gravissimes sinon fatals \u00e0 des bases militaires, des r\u00e9serves strat\u00e9giques souterraines importantes, &ndash; et il n&rsquo;en manque pas du c\u00f4t\u00e9 US, avec leur myriade de bases autour de la Russie, en Europe et au Moyen-Orient. On esp\u00e8re que les services d&rsquo;\u00e9valuation militaires occidentaux tireront les conclusions n\u00e9cessaires de ces frappes, qui sont parfaitement contraires aux sottises de circonstance dont on a \u00e9voqu\u00e9 un exemple plus haut. Le missile hypersonique doit \u00eatre consid\u00e9r\u00e9 au moins autant comme une arme conventionnelle nouvelle d&rsquo;une extr\u00eame puissante (et alors sa vitesse, avec son \u00e9nergie cin\u00e9tique, agit comme un multiplicateur consid\u00e9rable de la force de destruction \u00e0 l&rsquo;impact), que comme une arme nucl\u00e9aire (\u00e0 ogives nucl\u00e9aires) tr\u00e8s rapide et ind\u00e9tectable mais qui n&rsquo;a que faire de l&rsquo;\u00e9nergie cin\u00e9tique puisque l&rsquo;arme nucl\u00e9aire se d\u00e9clenche elle-m\u00eame hors de tout choc d&rsquo;impact<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Apr\u00e8s plusieurs r\u00e9flexions de nouveau sur cette capacit\u00e9 de l&rsquo;hypersonique \u00e0 s&rsquo;inscrire dans la dissuasion, passant ainsi \u00e0 volont\u00e9 du tactique au strat\u00e9gique, il y eut encore ceci, du <a href=\"https:\/\/www.dedefensa.org\/article\/lhypersonique-entre-dans-la-dissuasion\">10 d\u00e9cembre 2022<\/a> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em> \u00ab\u00a0&lsquo;Des capacit\u00e9s non nucl\u00e9aires d\u00e9velopp\u00e9es par des concurrents pourraient infliger des dommages de niveau strat\u00e9gique aux Etats-Unis et \u00e0 leurs alli\u00e9s et partenaires&rsquo;, note le Pentagone, admettant en filigrane la supr\u00e9matie des armes non nucl\u00e9aires russes (hypersoniques), et bient\u00f4t chinoises&#8230;\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> Cette remarque rejoint ce que nous avons d\u00e9j\u00e0 not\u00e9 \u00e0 plusieurs reprises \u00e0 propos des armes hypersoniques dont la flexibilit\u00e9 extr\u00eame (autonomie, emport de charge, vols avec man&oelig;uvres et altitudes diff\u00e9rentes, extr\u00eame vitesse et incapacit\u00e9 d&rsquo;interception, \u00e9norme puissance \u00e0 l&rsquo;impact du fait de l&rsquo;\u00e9nergie cin\u00e9tique suscit\u00e9e par la vitesse) leur donne des capacit\u00e9s de frappe strat\u00e9gique \u00e9quivalentes \u00e0 celle d&rsquo;une arme nucl\u00e9aire de d\u00e9capitation et de destruction cibl\u00e9e. Notre analyse nous conduisait \u00e0 consid\u00e9rer l&rsquo;hypersonique dans toutes ses capacit\u00e9s comme installant un nouvel \u00e9chelon dans l&rsquo;\u00e9chelle de la dissuasion, un \u00e9chelon o&ugrave; le conventionnel devient aussi important que des frappes nucl\u00e9aires interm\u00e9diaires, y compris strat\u00e9giques. (Voir notamment <a href=\"https:\/\/www.dedefensa.org\/article\/message-hypersonique-en-pleine-ukrisis\">le 22 mars 2022<\/a> et <a href=\"https:\/\/www.dedefensa.org\/article\/%C2%AB%2520...Cela%2520implique%2520la%2520possibilit%C3%A9,%2520dans%2520le%2520cas%2520d%E2%80%99une%2520escalade,%2520de%2520la%2520mise%2520en%2520place%2520et%2520de%2520l%E2%80%99existence%2520d%E2%80%99un%2520%C3%A9chelon%2520interm%C3%A9diaire%2520entre%2520la%2520guerre%2520conventionnelle%2520de%2520haut%2520niveau%2520et%2520la%2520guerre%2520nucl%C3%A9aire%2520avec%2520son%2520encha%C3%AEnement%2520quasiment%2520in%C3%A9luctable%2520du%2520tactique%2520au%2520strat%C3%A9gique%2520(guerre%2520totale%2520d%E2%80%99an%C3%A9antissement).%2520Dans%2520l%E2%80%99%C3%A9tat%2520actuel%2520des%2520forces,%2520cette%2520novation%2520serait%2520au%2520seul%2520avantage%2520des%2520Russes,%2520gr%C3%A2ce%2520%C3%A0%2520leur%2520missiles%2520hypersoniques%2520qui,%2520dans%2520certaines%2520conditions,%2520pourraient%2520frapper%2520avec%2520pr%C3%A9cision%2520une%2520cible%2520militaire%2520aux%2520USA%2520(bases,%2520centre%2520de%2520commandement,%2520etc.)%2520sans%2520provoquer%2520les%2520d%C3%A9g%C3%A2ts%2520collat%C3%A9raux%2520catastrophiques%2520d%E2%80%99une%2520frappe%2520nucl%C3%A9aire.\">le 9 octobre 2022<\/a>.)<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> \u00ab\u00a0&#8230;Cela implique la possibilit\u00e9, dans le cas d&rsquo;une escalade, de la mise en place et de l&rsquo;existence d&rsquo;un \u00e9chelon interm\u00e9diaire entre la guerre conventionnelle de haut niveau et la guerre nucl\u00e9aire avec son encha&icirc;nement quasiment in\u00e9luctable du tactique au strat\u00e9gique (guerre totale d&rsquo;an\u00e9antissement). Dans l&rsquo;\u00e9tat actuel des forces, cette novation serait au seul avantage des Russes, gr\u00e2ce \u00e0 leur missiles hypersoniques qui, dans certaines conditions, pourraient frapper avec pr\u00e9cision une cible militaire aux USA (bases, centre de commandement, etc.) sans provoquer les d\u00e9g\u00e2ts collat\u00e9raux catastrophiques d&rsquo;une frappe nucl\u00e9aire\u00a0\u00bb.<\/em> &raquo; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;arriv\u00e9e tonitruante d\u00a0\u00bb<em>Orechnik<\/em>&lsquo; constitue une affirmation de la m\u00eame tonalit\u00e9 de sa fonction royale dans l&rsquo;univers de la dissuasion. Il faut dire qu&rsquo;\u00e0 Mach 10, la masse qui heurte rassemble 475 fois l&rsquo;\u00e9nergie cin\u00e9tique d&rsquo;un missile &lsquo;<em>Tomahawk<\/em>&lsquo; volant \u00e0 Mach 1. Si vous voulez, c&rsquo;est comme un m\u00e9t\u00e9orite de belle taille. Alors, une fois admis que cela est bien r\u00e9el, il y a de quoi r\u00e9duire \u00e0 n\u00e9ant l&rsquo;\u00e9norme Simulacre gonfl\u00e9 comme une bulle funeste et licencieuse dans lequel nous avons v\u00e9cu ces deux derni\u00e8res ann\u00e9es.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les surprises d\u00a0\u00bbOrechnik&lsquo; 23 novembre 2024 (18H00) &ndash; Le tir d&rsquo;un missile IRBM (jusqu&rsquo;\u00e0 5 000 kilom\u00e8tres de port\u00e9e) russe de type nouveau, dit &lsquo;Orechnik&lsquo;, produit un formidable effet de communication aux multiples nuances, &ndash; mais en aucune fa\u00e7on le silence dont nous savons tous qu&rsquo;il est l&rsquo;arme principale du simulacre. Donc, &lsquo;Orechnik&lsquo; existe et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2929,14208,2730,1296],"class_list":["post-81340","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-dissuasion","tag-hyersonique","tag-russie","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81340"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81340\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}