{"id":81372,"date":"2024-12-18T14:50:49","date_gmt":"2024-12-18T14:50:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2024\/12\/18\/discours-et-intrigues-de-guerre\/"},"modified":"2024-12-18T14:50:49","modified_gmt":"2024-12-18T14:50:49","slug":"discours-et-intrigues-de-guerre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2024\/12\/18\/discours-et-intrigues-de-guerre\/","title":{"rendered":"Discours et intrigues de guerre"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Discours et intrigues de guerre<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; D&rsquo;un c\u00f4t\u00e9, il y a un complet durcissement de la direction russe, jusqu&rsquo;\u00e0 Poutine lui-m\u00eame qui fait d\u00e9sormais <strong>ce que Mercouris nomme des \u00ab\u00a0discours de guerre\u00a0\u00bb<\/strong>. &bull; Si l&rsquo;orientation des choses ne changent pas ra-di-ca-le-ment, <strong>la Russie fera la guerre, comme tout le monde, \u00e0 l&rsquo;OTAN, semble \u00e9trangement le souhaiter<\/strong>. &bull; D&rsquo;autre part, l&rsquo;assassinat du g\u00e9n\u00e9ral Kirillov, \u00e0 Moscou, est vu par certains comme <strong>une op\u00e9ration du Syst\u00e8me contre les changements politiques possibles avec Trump<\/strong>. &bull; Autrement dit : Kirillov comme <strong>avertissement pour Trump<\/strong>.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Deux r\u00e9unions importantes en Russie, rassemblant des cadres politiques (le parti Russie Unie) et militaires (le Conseil de D\u00e9fense) mais destin\u00e9es \u00e0 avoir un \u00e9cho populaire en Russie, ont eu lieu ce week-end \u00e0 Moscou. Il y a surtout eu Poutine, bien s&ucirc;r, mais aussi d&rsquo;autres dirigeants, et tous ont suivi la m\u00eame ligne qui est, plus qu&rsquo;une dramatisation de la guerre, l&rsquo;annonce d&rsquo;une nouvelle p\u00e9riode sur la voie d&rsquo;un conflit d\u00e9sormais in\u00e9vitable.<\/p>\n<\/p>\n<p><p>Lisons Mercouris qui a pass\u00e9 en revue, avec sa <a href=\"https:\/\/www.youtube.com\/watch?v=iEhu1NrHFag&#038;t=214s\">maestria coutumi\u00e8re<\/a>, la tonalit\u00e9, le \u00ab\u00a0climat\u00a0\u00bb de ces discours, et ce qu&rsquo;ils signifient dans la situation g\u00e9n\u00e9rale. Il parle ici du discours de Poutine devant le parti Union pour la Russie qui est le parti pr\u00e9sidentiel qui le soutient.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Poutine a parl\u00e9 de mani\u00e8re plus g\u00e9n\u00e9rale \u00e0 certains \u00e9gards que Medvedev, mais ils ont tous deux parl\u00e9 d&rsquo;une Russie qui est en fait en guerre. Si vous lisez les commentaires de Poutine dans leur ensemble, il a mis l&rsquo;accent sur la guerre et sur le r\u00f4le que la guerre joue et a sur la soci\u00e9t\u00e9 russe, le genre d&rsquo;effet de consolidation que la guerre suscite dans la soci\u00e9t\u00e9 russe, la fa\u00e7on dont la soci\u00e9t\u00e9 russe a \u00e9volu\u00e9 derri\u00e8re la guerre, le r\u00f4le qu&rsquo;elle y joue, ses attitudes envers l&rsquo;arm\u00e9e que la guerre a cr\u00e9\u00e9es au sein de la soci\u00e9t\u00e9 russe&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Donc moi, moi je ne dirais pas que c&rsquo;\u00e9tait compl\u00e8tement  un discours de guerre, mais c&rsquo;\u00e9tait bien plus proche de cela que tout ce que Poutine a dit jusqu&rsquo;\u00e0 maintenant. G\u00e9n\u00e9ralement quand il parlait de de la situation globale en Russie, il avait tendance \u00e0 mettre l&rsquo;accent sur le type de vie civile en cours, le fait que la Russie donnait l&rsquo;impression que la vie normale se d\u00e9roulait comme si de rien n&rsquo;\u00e9tait. Cette fois, c&rsquo;est diff\u00e9rent et encore une fois, je pense que cela vise en partie \u00e0 garantir que<\/em> [le parti] <em>Russie Unie ne soit pas seulement attel\u00e9e \u00e0 la t\u00e2che de soutenir la guerre, mais soit attel\u00e9e \u00e0 la t\u00e2che de maintenir la volont\u00e9 de la faire, d&rsquo;y participer \u00e0 sa fa\u00e7on&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le lendemain, Poutine a donn\u00e9 un autre discours, \u00e9videmment <a href=\"https:\/\/www.rt.com\/russia\/609425-west-pushing-russia-red-line-putin\/\">sur le m\u00eame sujet<\/a> mais s&rsquo;adressant plus pr\u00e9cis\u00e9ment aux militaires puisqu&rsquo;il s&rsquo;agissait des membres du Conseil de D\u00e9fense.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le soutien de l&rsquo;Occident \u00e0 l&rsquo;Ukraine pousse la Russie \u00e0 un point o&ugrave; elle ne peut s&#8217;emp\u00eacher de riposter, a d\u00e9clar\u00e9 le pr\u00e9sident Vladimir Poutine, tout en mettant en garde les &Eacute;tats-Unis contre le d\u00e9ploiement de missiles \u00e0 moyenne port\u00e9e <\/em>[en Allemagne].<\/p>\n<\/p>\n<p><p>&raquo; <em>S&rsquo;exprimant lors d&rsquo;une r\u00e9union de hauts responsables du minist\u00e8re russe de la D\u00e9fense lundi, Poutine a accus\u00e9 les &Eacute;tats-Unis de chercher \u00e0 \u00ab\u00a0affaiblir notre pays et \u00e0 infliger une d\u00e9faite strat\u00e9gique\u00a0\u00bb \u00e0 Moscou en continuant \u00e0 d\u00e9livrer des armes et de l&rsquo;argent au r\u00e9gime ill\u00e9gitime de facto au pouvoir \u00e0 Kiev\u00a0\u00bb et \u00ab\u00a0en envoyant des mercenaires et des conseillers militaires, encourageant ainsi une nouvelle escalade du conflit\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le discours du ministre de la d\u00e9fense Belousov, qui a pr\u00e9c\u00e9d\u00e9 Poutine, a certes \u00e9t\u00e9 dans la m\u00eame ligne, mais il a donn\u00e9 des indications de temps et de choix de th\u00e9\u00e2tres <a href=\"https:\/\/www.rt.com\/news\/609440-belousov-nato-conflict-putin\/\">beaucoup plus pr\u00e9cises<\/a>. Assurant la gestion directe  des affaires militaires, il a parl\u00e9 \u00e0 ses auditeurs selon des perspectives op\u00e9rationnelles affirm\u00e9es : pour lui, la guerre d&rsquo;Ukraine est pratiquement finie, et le gros morceau est \u00e0 suivre.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;  <em>Belousov a d\u00e9clar\u00e9 que l&rsquo;arm\u00e9e russe avait accompli sa mission dans le conflit en Ukraine et ailleurs cette ann\u00e9e dans le contexte d&rsquo;une \u00ab\u00a0lutte difficile avec l&rsquo;Occident collectif\u00a0\u00bb. Le conflit actuel entre Moscou, les &Eacute;tats-Unis et leurs alli\u00e9s \u00ab\u00a0continue de s&rsquo;intensifier et de s&rsquo;\u00e9tendre\u00a0\u00bb, a-t-il averti<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Dans de telles conditions, l&rsquo;un des principaux objectifs du minist\u00e8re russe de la D\u00e9fense \u00ab\u00a0est d&rsquo;assurer une pr\u00e9paration totale \u00e0 toute \u00e9volution de la situation \u00e0 moyen terme\u00a0\u00bb, a d\u00e9clar\u00e9 le ministre. Cela inclut \u00ab\u00a0un \u00e9ventuel conflit militaire avec l&rsquo;OTAN en Europe au cours de la prochaine d\u00e9cennie\u00a0\u00bb, a-t-il ajout\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette vision dramatique des \u00e9v\u00e9nements est nouvelle, surtout de  la part de Poutine qui, depuis le 22 f\u00e9vrier 2022, insistait pour placer cette guerre dans le cadre d&rsquo;une simple \u00ab\u00a0Op\u00e9ration Militaire Sp\u00e9ciale\u00a0\u00bb. Les interventions que nous signalons, qui placent pour la premi\u00e8re fois sur la m\u00eame ligne le belliciste Medvedev comme on l&rsquo;a entendu samedi, et le pr\u00e9sident Poutine, signalent donc une \u00e9volution tr\u00e8s nette de la perception du danger. Surtout, il marque une conviction russe qu&rsquo;un grand affrontement avec l&rsquo;OTAN, avec le bloc am\u00e9ricaniste-occidentaliste, semble appara&icirc;tre d\u00e9sormais in\u00e9vitable aux yeux de la direction russe.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Du g\u00e9n\u00e9ral Kirillov \u00e0 Trump<\/h3>\n<\/p>\n<p><p>Bien entendu, l&rsquo;assassinat du g\u00e9n\u00e9ral Kirillov a pr\u00e9cipit\u00e9 cette atmosph\u00e8re dans l&rsquo;imm\u00e9diatet\u00e9 op\u00e9rationnelle d&rsquo;une th\u00e9orique impossibilit\u00e9 compl\u00e8te d&rsquo;une entente sur l &lsquo;Ukraine pour une d\u00e9sescalation.<\/p>\n<\/p>\n<p><p>Certains Russes estiment au reste que cet attentat  contre un haut dignitaire russe est bel et bien l&rsquo;&oelig;uvre du renseignement ukrainien, engag\u00e9 dans une campagne totale destin\u00e9e \u00e0 pulv\u00e9riser toutes les possibilit\u00e9s d&rsquo;accords et d&rsquo;entente entre la Russie et les USA de Trump. Le durcissement total des Russes interdirait la moindre concession de fa\u00e7ade de leur part pour permettre \u00e0 Trump, &ndash; si c&rsquo;est son intention de liquider l&rsquo;affaire ukrainienne, &ndash; d&rsquo;att\u00e9nuer un tel choc aupr\u00e8s des groupes bellicistes.<\/p>\n<\/p>\n<p><p>On voit <a href=\"https:\/\/usa.news-pravda.com\/usa\/2024\/12\/17\/56484.html\">cette hypoth\u00e8se d\u00e9velopp\u00e9e<\/a> par le colonel de r\u00e9serve Pinchouk, \u00e0 l&rsquo;intention d&rsquo;un Trump dont sait clairement qu&rsquo;il entretient \u00e0 l&rsquo;encontre de Zelenski une haine consid\u00e9rable, &ndash; cet ensemble de pressions politiques et psychologiques entretenant un climat d&rsquo;une \u00e9trange ambigu\u00eft\u00e9, sinon d&rsquo;une contradiction compl\u00e8te, entre une Russie pr\u00eate \u00e0 affronter les USA dans le cadre du complot am\u00e9ricaniste-occidentaliste, et une menace commune des Ukrainiens contre les directions de Moscou et de l&rsquo;\u00e9quipe Trump&#8230; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;assassinat du g\u00e9n\u00e9ral Igor Kirillov est une op\u00e9ration des services sp\u00e9ciaux. Les enqu\u00eateurs ont qualifi\u00e9 l&rsquo;incident d&rsquo;attaque terroriste. Bien que l&rsquo;on puisse plut\u00f4t parler de sabotage. Et \u00e0 cet \u00e9gard,<\/em> <em>Pinchouk souligne que la mort de notre g\u00e9n\u00e9ral est \u00e9galement un avertissement pour Trump<\/em>. [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo; <em>En bref, ce qui s&rsquo;est pass\u00e9 \u00e9tait une grande op\u00e9ration sp\u00e9ciale, o&ugrave; les activistes de Kiev sont devenus de simples outils. Et cet outil, comme l&rsquo;a ajout\u00e9 Andrei Pinchouk, colonel de r\u00e9serve, premier ministre de la s\u00e9curit\u00e9 d&rsquo;&Eacute;tat de la RPD, observateur politique de &lsquo;Tsargrad&rsquo;, dans une interview \u00e0 &lsquo;Tsargrad&rsquo;, peut \u00e9galement \u00eatre utilis\u00e9 contre le pr\u00e9sident \u00e9lu des &Eacute;tats-Unis, Donald Trump :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Trump doit penser que si une autre tentative plus r\u00e9ussie est faite contre lui, alors cette fois, contrairement \u00e0 Kennedy, par exemple, ce ne seront plus les services sp\u00e9ciaux am\u00e9ricains, mais ceux ukrainiens.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>&Eacute;tant donn\u00e9 que l&rsquo;actuel pr\u00e9sident de l&rsquo;Ukraine, Vladimir Zelenski, a d\u00e9j\u00e0 r\u00e9ussi \u00e0 se montrer grossier envers Trump apr\u00e8s l&rsquo;avoir rencontr\u00e9, le r\u00e9gime de Kiev ne parie clairement pas sur le pr\u00e9sident \u00e9lu des &Eacute;tats-Unis. Et il est probable que des saboteurs ukrainiens ou des terroristes pro-ukrainiens tenteront \u00e0 nouveau d&rsquo;\u00eatre utilis\u00e9s. Cette fois \u00e0 Washington<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 18 d\u00e9cembre 2024 \u00e0 14H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discours et intrigues de guerre &bull; D&rsquo;un c\u00f4t\u00e9, il y a un complet durcissement de la direction russe, jusqu&rsquo;\u00e0 Poutine lui-m\u00eame qui fait d\u00e9sormais ce que Mercouris nomme des \u00ab\u00a0discours de guerre\u00a0\u00bb. &bull; Si l&rsquo;orientation des choses ne changent pas ra-di-ca-le-ment, la Russie fera la guerre, comme tout le monde, \u00e0 l&rsquo;OTAN, semble \u00e9trangement le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3525,3283,14254,2707,916,2639],"class_list":["post-81372","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-attentat","tag-general","tag-kirillov","tag-moscou","tag-poutine","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81372"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81372\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}