{"id":81403,"date":"2025-01-13T14:42:37","date_gmt":"2025-01-13T14:42:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/13\/trump-bibi-un-froid-polaire\/"},"modified":"2025-01-13T14:42:37","modified_gmt":"2025-01-13T14:42:37","slug":"trump-bibi-un-froid-polaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/13\/trump-bibi-un-froid-polaire\/","title":{"rendered":"Trump-Bibi\u00a0: un froid polaire"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Trump-Bibi : un froid polaire<\/strong><\/h2>\n<\/p>\n<p><p>13 janvier 2025 (14H50) &ndash;<em> Mea Culpa<\/em>, Mea Maxima Culpa&hellip; On conna&icirc;t la chanson. Pour ce cas, elle me convient sans doute parfaitement, par rapport \u00e0 ce que je croyais et ce que j&rsquo;ai \u00e9crit dans pour un des aspects abord\u00e9s dans mon <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2025-tempetes-usa\">texte d&rsquo;hier<\/a>.<\/p>\n<\/p>\n<p><p>J&rsquo;ai rencontr\u00e9 aujourd&rsquo;hui quelques \u00e9claircissements d&rsquo;une de mes sources les plus assur\u00e9es  qui contredisent une interpr\u00e9tation que j&rsquo;avais pr\u00e9sent\u00e9 hier. Cela concerne les relations de Trump et de Netanyahou. Je m&rsquo;\u00e9tais appuy\u00e9 sur les d\u00e9clarations de la commentatrice indienne <a href=\"https:\/\/www.youtube.com\/watch?v=gMkxAjJGYVk\">Palki Sharma<\/a> pour encore  me laisser aller \u00e0 ce qu&rsquo;il reste de ce c\u00f4t\u00e9 mi-sarcastique mi-d\u00e9daigneux du regard que je porte sur Trump&#8230; Il est possible qu&rsquo;il soit devenu vraiment plus s\u00e9rieux, &ndash; vraiment encore plus s\u00e9rieux que je ne le pense, par rapport \u00e0 Trump-2016.<\/p>\n<\/p>\n<p><p>J&rsquo;\u00e9crivais donc hier, certes en nuan\u00e7ant mon avis faisant de l&rsquo;incident du passage de la vid\u00e9o du professeur Sachs d\u00e9non\u00e7ant Netanyahou une simple erreur d&rsquo;inattention de Trump, &ndash; mais tout de m\u00eame en cautionnant cette version :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Sharma qui note que Trump s&rsquo;est montr\u00e9 tr\u00e8s chaleureux directement ou indirectement pour Isra\u00ebl jusqu&rsquo;\u00e0 mercredi, s&rsquo;interroge sur ce \u00ab\u00a0changement d&rsquo;attitude\u00a0\u00bb :<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Que s&rsquo;est-il pass\u00e9 en 24 heures ? Trump a-t-il compl\u00e8tement change de politique ou bien n&rsquo;a-t-il pas \u00e9cout\u00e9 toute l&rsquo;intervention puisque le r\u00e9sum\u00e9 \u00e9crit ne mentionne pas cette diatribe contre Netanyahou. Dans les deux cas, ce n&rsquo;est pas rassurant : soit une politique changeante avec brutalit\u00e9, soit la mise en ligne de post sans v\u00e9rification&#8230;\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&raquo; <em>Bref, du vrai Trump ; et, je le reconnais, je serais plut\u00f4t pour l&rsquo;erreur de trajectoire. D\u00e8s lors, faisons une hypoth\u00e8se : une mani\u00e8re de rattraper le coup aurait \u00e9t\u00e9 <a href=\"https:\/\/www.rt.com\/news\/610763-trump-envoy-iran-pressure\/\">la violente diatribe<\/a> du g\u00e9n\u00e9ral Kellogg, envoy\u00e9 sp\u00e9cial de Trump un peu partout dans les crises de la zone, contre l&rsquo;Iran, ennemi \u00ab\u00a0obsessionnel\u00a0\u00bb de Netanyahou<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Tout au contraire, nous dit Mercouris dans son programme <a href=\"https:\/\/www.youtube.com\/watch?v=lCIJ5N2a1ik&#038;t=2596s\">d&rsquo;hier soir<\/a>, le passage de cette vid\u00e9o a \u00e9t\u00e9 voulue par Trump et son \u00e9quipe parce qu&rsquo;ils jugent que l&rsquo;avis extr\u00eamement ferme et d\u00e9vastateur du professeur Sachs exprime tr\u00e8s pr\u00e9cis\u00e9ment ce que Trump pense de Netanyahou. Le commentateur gr\u00e9co-britannique s&rsquo;attache tr\u00e8s longuement (autour de 20 minutes au d\u00e9but du programme) \u00e0 cette affaire, qu&rsquo;il lie \u00e0 l&rsquo;\u00e9volution des tensions entre Isra\u00ebl et l&rsquo;Iran, brusquement en baisse depuis quelques jours.<\/p>\n<\/p>\n<p><p>Je vous en donne un extrait substantiel pour montrer la minutie et l&rsquo;assurance du propos. Finalement, il s&rsquo;agit moins de savoir s&rsquo;il y a un froid intense entre Trump et Netanyahou que de savoir pourquoi il y a un froid intense jusqu&rsquo;\u00e0 en \u00eatre polaire, &ndash; un froid de Groenland aux plus fortes saisons&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le pr\u00e9sident Trump et les autres doivent \u00eatre extr\u00eamement prudents dans leurs relations avec le premier ministre Netanyahou parce que Netanyahou est beaucoup de choses mais il est aussi tr\u00e8s intelligent et extr\u00eamement manipulateur. Si vous donnez l&rsquo;impression que vous \u00eates d&rsquo;accord avec lui sur n&rsquo;importe quoi, alors vous pouvez vous retrouver dans de s\u00e9rieux probl\u00e8mes&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Je devrais dire au passage que c&rsquo;est absolument dans l&rsquo;int\u00e9r\u00eat de tout le monde d&rsquo;aller aux commentaires originaux du professeur Sachs pour voir ce qu&rsquo;il a \u00e0 dire en g\u00e9n\u00e9ral mais de toute fa\u00e7on il se pourrait que ce qui a attir\u00e9 le pr\u00e9sident Trump vers les commentaires du professeur Sachs \u00e9tait justement cette caract\u00e9risation de Netanyahou&#8230; C&rsquo;est  une v\u00e9rit\u00e9 objective que le premier ministre Netanyahou peut ainsi \u00eatre ext\u00e9rieurement tr\u00e8s charmant et comme beaucoup de gens qui veulent appara&icirc;tre comme tr\u00e8s charmant, la r\u00e9alit\u00e9 est qu&rsquo;il est extr\u00eamement manipulateur comme le disent de nombreux politiciens et dirigeants \u00e9trangers. Je pense que c&rsquo;est peut-\u00eatre quelque chose que Trump a remarqu\u00e9, cette caract\u00e9risation de Netanyahou par Sachs, et qu&rsquo;il a voulu publier cette vid\u00e9o parce qu&rsquo;elle lui permettait de dire sans le dire ce qu&rsquo;il en pense..<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il se pourrait que tout cela soit un signe que Trump est tr\u00e8s en col\u00e8re contre Netanyahou \u00e0 cause de la fa\u00e7on dont ce dernier a essay\u00e9 au cours des deux derni\u00e8res semaines de l&rsquo;impliquer indirectement dans une guerre contre l&rsquo;Iran, ce dont Donald Trump ne veut absolument pas entendre parler en ce moment.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il y a maintenant un autre probl\u00e8me possible entre Netanyahou et Trump auquel j&rsquo;ai vu un certain nombre de personnes faire r\u00e9f\u00e9rence, y compris en Isra\u00ebl m\u00eame. Il n&rsquo;y a aucun doute que pendant le premier mandat de Trump, Netanyahou et Trump avaient une relation tr\u00e8s amicale, mais je me souviens qu&rsquo;apr\u00e8s les \u00e9lections de novembre 2020, dont Trump a contest\u00e9 les r\u00e9sultats, Trump \u00e9tait profond\u00e9ment furieux et s&rsquo;est apparemment senti trahi par le fait que son ami Netanyahou, le Premier ministre d&rsquo;Isra\u00ebl, ait f\u00e9licit\u00e9 Biden pour sa victoire aux \u00e9lections de novembre 2020. J&rsquo;ai entendu et j&rsquo;ai r\u00e9cemment vu dire \u00e0 plus d&rsquo;un endroit que depuis lors, Trump n&rsquo;a pas oubli\u00e9 ni pris \u00e0 la l\u00e9g\u00e8re ce qu&rsquo;il consid\u00e8re comme une trahison. C&rsquo;est ce qui expliquerait en bonne partie, disent-ils, la froideur actuelle entre les deux hommes.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Maintenant, j&rsquo;avoue me sentir un petit peu sceptique devant cette estimation car je pense qu&rsquo;elle joue trop dans la caricature commun\u00e9ment accept\u00e9e de Donald Trump, que nous lisons tous les jours dans presque tous les journaux, selon laquelle il est une personnalit\u00e9 \u00e9go\u00efste et trop sensible, quelqu&rsquo;un qui n&rsquo;oublie jamais une l\u00e9g\u00e8re rancune et ce genre de choses. Pour m\u00e9moire, je n&rsquo;ai jamais vu de preuve r\u00e9elle de cela dans les propres actions de Donald Trump. Je veux dire, il a dit diverses choses \u00e0 propos de diverses personnes qui l&rsquo;ont trahi. il a souvent exprim\u00e9 sa col\u00e8re \u00e0 leur \u00e9gard, mais je n&rsquo;ai jamais eu le sentiment r\u00e9el de quelqu&rsquo;un qui garde rancune et qui pr\u00e9pare une vengeance de la fa\u00e7on dont les gens parlent,<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Mais ayant dit cela, j&rsquo;ajoute que je ne connais pas personnellement pour autant Donald Trump et qu&rsquo;il est possible qu&rsquo;il se soit senti profond\u00e9ment trahi&#8230; Personnellement, j&rsquo;esp\u00e8re que ce n&rsquo;est pas la raison principale de la froideur actuelle bien r\u00e9elle de ses relations avec Netanyahou, que c&rsquo;est plut\u00f4t le fait que Trump r\u00e9alise que se lancer dans une guerre contre l&rsquo;Iran aujourd&rsquo;hui est une id\u00e9e \u00e9pouvantable&#8230; &raquo;<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et enfin, cette conclusion qui est particuli\u00e8rement significative par la force de son affirmation. Pour un commentateur aussi mod\u00e9r\u00e9 dans les propos que l&rsquo;est Mercouris, aussi attentif \u00e0 peser tous les termes employ\u00e9s, bref un commentateur aussi attentif aux mani\u00e8res de la diplomatie, le poids de ce que nous dit ici Mercouris est absolument consid\u00e9rable et introduit un \u00e9l\u00e9ment extr\u00eamement important dans les perspectives de la situation crisique au Moyen-Orient, et sur toute la politique terriblement agressive d&rsquo;Isra\u00ebl :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>&#8230;<\/em>[M]<em>ais dans un sens, \u00e0 ce moment pr\u00e9cis, cela n&rsquo;a pas d&rsquo;importance. Je pense que nous avons maintenant suffisamment de preuves, certainement, avec la publication par Trump de cette vid\u00e9o, qu&rsquo;il y a tout aussi certainement des tensions entre ces deux hommes, ce qui nous am\u00e8ne \u00e0 nous demander ce qui va se passer dans les prochaines semaines et les prochains mois. Pour le moment, il semble qu&rsquo;il y ait eu, de mani\u00e8re assez surprenante, une d\u00e9sescalade des tensions entre Isra\u00ebl et l&rsquo;Iran dont on a beaucoup parl\u00e9<\/em> [et qui est caus\u00e9e par le durcissement anti-guerre de Trump] &raquo;<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Trump-Bibi : un froid polaire 13 janvier 2025 (14H50) &ndash; Mea Culpa, Mea Maxima Culpa&hellip; On conna&icirc;t la chanson. Pour ce cas, elle me convient sans doute parfaitement, par rapport \u00e0 ce que je croyais et ce que j&rsquo;ai \u00e9crit dans pour un des aspects abord\u00e9s dans mon texte d&rsquo;hier. J&rsquo;ai rencontr\u00e9 aujourd&rsquo;hui quelques \u00e9claircissements&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2631,2774,13785,14296,9666,14295,2766,8478,2710,9242,14294,5092],"class_list":["post-81403","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-de","tag-israel","tag-jeffrey","tag-lattaque","tag-liran","tag-perspectves","tag-relations","tag-sachs","tag-sur","tag-tensions","tag-trump-netanyahou","tag-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81403"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81403\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}