{"id":81405,"date":"2025-01-14T15:16:01","date_gmt":"2025-01-14T15:16:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/14\/rapsit-usa2025-la-navy-contre-le-virus-woke\/"},"modified":"2025-01-14T15:16:01","modified_gmt":"2025-01-14T15:16:01","slug":"rapsit-usa2025-la-navy-contre-le-virus-woke","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/14\/rapsit-usa2025-la-navy-contre-le-virus-woke\/","title":{"rendered":"RapSit-USA2025\u00a0: La Navy contre le virus-<em>Woke<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2025 : La Navy contre le virus-<em>Woke<\/em><\/h2>\n<\/p>\n<p><p>L&rsquo;U.S. Navy a pris une mesure de mise \u00e0 l&rsquo;\u00e9cart de la Commander (capitaine de vaisseau) Cayenne McFarland, officier commandant le Naval Information Warfare Training Group de la grande base de l&rsquo;US Navy de San Diego, observant qu&rsquo;il y avait &laquo; <em>une perte de confiance dans ses capacit\u00e9s d&rsquo;effectuer un tel commandement <\/em>&raquo;. McFairland assurait cette fonction depuis avril 2023 ; elle a \u00e9t\u00e9 r\u00e9affect\u00e9e aux forces navales d&rsquo;information, sans autre pr\u00e9cision.<\/p>\n<\/p>\n<p><p>Elle est le second officier de l&rsquo;US Navy de haut rang <a href=\"https:\/\/www.youtube.com\/shorts\/u2VHOWed5Us\">subissant cette semaine<\/a> une r\u00e9affectation traduisant un bl\u00e2me pour perte de confiance selon le jugement d&rsquo;incapacit\u00e9. Auparavant, le Captain (capitaine de corvette) Lester Brown Junior, assurant le &lsquo;<em>Ethic Command<\/em>&lsquo; (\u00ab\u00a0Commandement &Eacute;thique\u00a0\u00bb) de l&rsquo;US Navy, \u00e9galement \u00e0 San Diego, a \u00e9galement \u00e9t\u00e9 \u00e9cart\u00e9 de sa fonction pour &laquo; <em>une perte de confiance dans ses capacit\u00e9s d&rsquo;effectuer un tel commandement <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>C&rsquo;est la premi\u00e8re fois depuis les graves remous de 1970-72, avec des mutineries \u00e0 bord de vaisseaux en op\u00e9ration, &ndash; du fait de l&rsquo;effroyable crise de discipline, d&rsquo;insubordination et de m\u00e9contentement dans les forces arm\u00e9es US dans le cadre du \u00ab\u00a0d\u00e9sengagement\u00a0\u00bb du Vietnam, &ndash; que de telles sanctions sont appliqu\u00e9es \u00e0 quelques jours d&rsquo;intervalles. (C&rsquo;est la proximit\u00e9 chronologique de ces mesures qui est remarquable.) Il est difficile de ne pas remarquer :<\/p>\n<\/p>\n<p><p>1) Que McFairland est une femme ;<\/p>\n<\/p>\n<p><p>2) Que Brown est un Africain-Am\u00e9ricain ;<\/p>\n<\/p>\n<p><p>3) Que leurs deux commandements concernent des activit\u00e9s li\u00e9es plus ou moins directement au wokenisme, ou DEI (\u00ab\u00a0<em>Diversity, Equity, and Inclusion<\/em>\u00ab\u00a0), qui couvrent notamment les activit\u00e9s \u00ab\u00a0\u00e9thiques\u00a0\u00bb li\u00e9es au f\u00e9minisme et au racialisme.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un signe tr\u00e8s grave de la crise qu&rsquo;on tente de dissimuler, que subissent les forces arm\u00e9es depuis l&rsquo;application syst\u00e9matique de la doctrine DEI. La question n&rsquo;est pas de savoir si une femme ou un Noir sont capables ou non d&rsquo;exercer de tels commandements, mais celle bien entendu de savoir s&rsquo;ils n&rsquo;ont pas \u00e9t\u00e9 nomm\u00e9s \u00e0 ces postes parce qu&rsquo;ils \u00e9taient une femme et un Noir. Leurs fonctions \u00e9tant li\u00e9es directement ou indirectement \u00e0 des services impliqu\u00e9s dans la crise-DEI, on peut poursuivre par une autre hypoth\u00e8se plus pr\u00e9cise selon lesquelles les officiers appartenant \u00e0 des minorit\u00e9s agissent ou non selon les caract\u00e8res de genres et d&rsquo;ethnicit\u00e9, et non selon des caract\u00e8res de comp\u00e9tence et de qualit\u00e9. <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Note de PhGBis<\/em><\/strong><em> : &laquo; La question vaut bien s&ucirc;r dans l&rsquo;autre sens, mais pour l&rsquo;instant c&rsquo;est le premier cas qui a le vent en poupe, et comment ! La v\u00e9ritable question est bien entendu : faut-il nommer un officier pour ses qualit\u00e9s et sa comp\u00e9tence, ou pour son genre et son appartenance \u00e0 une communaut\u00e9 raciale\/ethnique ? Le \u00ab\u00a0Ethnic Command\u00a0\u00bb est l&rsquo;une des plus importantes monstruosit\u00e9s-DEI institu\u00e9e au sein de la bureaucratie r\u00e9pressive de la Navy (et des autres armes, qui sont plus discr\u00e8tes). La doctrine-DEI est en g\u00e9n\u00e9ral consid\u00e9r\u00e9e par les mauvais esprits comme un v\u00e9ritable virus. Il nous faut donc un COVID-25 contre le Woke, &ndash; une mission qui plairait conjointement, pour des raisons parfaitement inverses, \u00e0 Bill Gates et \u00e0 Robert Kennedy Jr<\/em>. <em>&raquo;<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le nouveau secr\u00e9taire \u00e0 la d\u00e9fense Pete Hegseth, s&rsquo;il est confirm\u00e9 (audition devant le S\u00e9nat aujourd&rsquo;hui, avec des <a href=\"https:\/\/www.breitbart.com\/politics\/2025\/01\/13\/hundreds-of-navy-seals-veterans-to-march-in-d-c-to-support-pete-hegseths-confirmation-as-defense-secretary\/\">manifestations de soutien<\/a>) aura pour mission essentielle  de purger radicalement les forces arm\u00e9es infect\u00e9es par le virus-<em>Woke <\/em>introduit en masse par l&rsquo;administration Biden. Le port du masque n&rsquo;y suffira pas.<\/p>\n<\/p>\n<p><p>Mis en ligne le 14 janvier 2025 \u00e0 15H20<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2025 : La Navy contre le virus-Woke L&rsquo;U.S. Navy a pris une mesure de mise \u00e0 l&rsquo;\u00e9cart de la Commander (capitaine de vaisseau) Cayenne McFarland, officier commandant le Naval Information Warfare Training Group de la grande base de l&rsquo;US Navy de San Diego, observant qu&rsquo;il y avait &laquo; une perte de confiance dans ses capacit\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[5468,3067,2939,14300,14188,2646],"class_list":["post-81405","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-dei","tag-doctrine","tag-hegseth","tag-pentagine","tag-pete","tag-wokenisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81405"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81405\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}