{"id":81414,"date":"2025-01-22T10:26:51","date_gmt":"2025-01-22T10:26:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/22\/limperialisme-us-fond-a-vue-doeil\/"},"modified":"2025-01-22T10:26:51","modified_gmt":"2025-01-22T10:26:51","slug":"limperialisme-us-fond-a-vue-doeil","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/22\/limperialisme-us-fond-a-vue-doeil\/","title":{"rendered":"L&rsquo;imp\u00e9rialisme US fond \u00e0 vue d&rsquo;\u0153il"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\"><strong>L&rsquo;imp\u00e9rialisme US fond \u00e0 vue d&rsquo;&oelig;il<\/strong><\/h2>\n<\/p>\n<p><p>Cinq jours \u00e0 peine nous s\u00e9parent du d\u00e9but du r\u00e8gne de l&#8217;empereur Donald Ier et de sa <a href=\"https:\/\/lesakerfrancophone.fr\/place-aux-milliardaires\">joyeuse bande de milliardaires<\/a>, et le monde entier est en proie \u00e0 de folles attentes quant \u00e0 ses nouvelles et excellentes aventures. Donald Ier a d\u00e9j\u00e0 annonc\u00e9 qu&rsquo;il pr\u00e9voyait d&rsquo;\u00e9tendre son domaine au Canada, au Groenland, au canal de Panama et peut-\u00eatre aux &Eacute;tats du nord du Mexique. Partout dans le monde, les gens se grattent la t\u00eate, se demandant ce que tout cela peut bien signifier. Qu&rsquo;en est-il de l&rsquo;inviolabilit\u00e9 des fronti\u00e8res nationales ? Qu&rsquo;en est-il de la souverainet\u00e9 nationale ? Quelqu&rsquo;un a-t-il lu la charte des Nations unies r\u00e9cemment ? Vaut-elle encore la peine d&rsquo;\u00eatre lue ?<\/p>\n<\/p>\n<p><p>Ils ne devraient pas s&rsquo;en pr\u00e9occuper. L&#8217;empereur \u00e9lu Donald est une pipelette, un vantard et un moulin \u00e0 paroles connu dans le monde entier et tout ce qui sort de sa bouche doit \u00eatre divis\u00e9 par au moins mille. Ass\u00e9cher le marais de Washington ? Non, il est toujours aussi f\u00e9cond et f\u00e9tide et ne cesse de s&rsquo;\u00e9tendre. Mettre fin \u00e0 la guerre en Ukraine dans les 24 heures ? Non, la derni\u00e8re promesse est de le faire en six mois. Rendre \u00e0 l&rsquo;Am\u00e9rique sa grandeur ? Peut-\u00eatre, mais les Am\u00e9ricains sont beaucoup trop ignorants, gros et paresseux, alors donnons des visas 1HB \u00e0 un million d&rsquo;Indiens et laissons-les essayer. Et ainsi de suite&hellip;<\/p>\n<\/p>\n<p><p>Mais tout cela n&rsquo;est que poudre aux yeux et grandiloquence, ce qui, en Am\u00e9rique, est consid\u00e9r\u00e9 comme cascher en tant qu&rsquo;ingr\u00e9dient principal des campagnes politiques. Apr\u00e8s tout, personne en Am\u00e9rique n&rsquo;a jamais \u00e9t\u00e9 abattu pour avoir rompu ses promesses \u00e9lectorales et mentir en se pr\u00e9sentant \u00e0 une \u00e9lection est consid\u00e9r\u00e9 comme&hellip; eh bien&hellip; mentir en se pr\u00e9sentant \u00e0 une \u00e9lection parce que les candidats qui ne mentent pas ne sont m\u00eame pas pris au s\u00e9rieux. C&rsquo;est la culture politique de l&rsquo;endroit. Certains appellent \u00e7a la <em>&laquo; d\u00e9mocratie &raquo;<\/em>. Pas moi.<\/p>\n<\/p>\n<p><p>Ce qui se passe en r\u00e9alit\u00e9 est tout \u00e0 fait d\u00e9sastreux. Trump b\u00e9n\u00e9ficiera de la plus mince des majorit\u00e9s \u00e0 la Chambre et au S\u00e9nat au cours des deux prochaines ann\u00e9es et deviendra tr\u00e8s probablement un canard boiteux par la suite. Au cours de cette p\u00e9riode, il sera confront\u00e9 au plus grand des fiascos en mati\u00e8re de limite de la dette, \u00e9tant donn\u00e9 que le taux d&rsquo;int\u00e9r\u00eat fix\u00e9 par le march\u00e9 sur les bons du Tr\u00e9sor \u00e0 10 ans a fait ses adieux au taux fix\u00e9 par la R\u00e9serve f\u00e9d\u00e9rale, alors que le Tr\u00e9sor doit rouler un tiers de la dette f\u00e9d\u00e9rale totale, qui s&rsquo;\u00e9l\u00e8ve \u00e0 plus de 36 000 milliards de dollars. Comme les \u00e9trangers rechignent \u00e0 acheter encore plus de papier de la dette am\u00e9ricaine, les seuls choix restants sont la planche \u00e0 billets, qui fait grimper l&rsquo;inflation, et des coupes tr\u00e8s importantes et politiquement suicidaires dans les programmes de d\u00e9fense et les programmes sociaux.<\/p>\n<\/p>\n<p><p>Les &Eacute;tats-Unis sont en faillite et doivent \u00eatre r\u00e9organis\u00e9s. Toutefois, une telle r\u00e9organisation n\u00e9cessiterait un minimum d&rsquo;unit\u00e9 nationale, ce qui est loin d&rsquo;\u00eatre le cas. La moiti\u00e9 du pays applaudit chaque fois que quelqu&rsquo;un dit qu&rsquo;il y a deux sortes d&rsquo;Am\u00e9ricains : les hommes et les femmes, et l&rsquo;autre moiti\u00e9 du pays croit qu&rsquo;ils ont un couteau suisse entre les jambes et que les lesbiennes font d&rsquo;excellents chefs de pompiers.<\/p>\n<\/p>\n<p><p>Mais il y a une chose sur laquelle tous les Am\u00e9ricains sont d&rsquo;accord : ils veulent tous devenir riches. Un nombre relativement minime d&rsquo;entre eux est d\u00e9j\u00e0 ridiculement riche et le reste veut simplement devenir ridiculement riche, peu importe comment. Vivek Ramaswamy s&rsquo;est enrichi en vendant un m\u00e9dicament contre la maladie d&rsquo;Alzheimer qui ne fonctionne pas &ndash; mais il est riche, le salaud, et c&rsquo;est tout ce qui compte, alors s&rsquo;il vous pla&icirc;t, laissez-le r\u00e9former la bureaucratie de Washington. Ne va-t-il pas essayer de s&rsquo;enrichir un peu plus au passage ? Ne sera-ce pas amusant \u00e0 regarder ? Peut-\u00eatre trouvera-t-il un moyen d&rsquo;\u00e9conomiser quelques centaines de milliards en confiant des fonctions gouvernementales \u00e0 des Indiens d\u00e9tenteurs de visas H1B&hellip; <em>Bienkvenue \u00e0 Vashington<\/em> !<\/p>\n<\/p>\n<p><p>Mais pourquoi Donald veut-il le Canada, le Groenland et le canal de Panama ? Il semble y avoir deux raisons plausibles \u00e0 ce d\u00e9sir ardent. Aucune n&rsquo;a \u00e0 voir avec ce qu&rsquo;on appelle la <em>&laquo; g\u00e9opolitique &raquo;<\/em>. Cette notion a \u00e9t\u00e9 imagin\u00e9e par un Britannique qui pr\u00e9tendait que <em>&laquo; celui qui contr\u00f4le le heartland contr\u00f4le le monde &raquo;<\/em> (comme s&rsquo;il \u00e9tait th\u00e9oriquement possible de contr\u00f4ler le monde entier). Le <em>heartland<\/em> est, grosso modo, la Russie, qui se contr\u00f4le elle-m\u00eame. Par cons\u00e9quent, le contr\u00f4le du centre par quiconque n&rsquo;est m\u00eame pas th\u00e9oriquement possible. Nous en avons fini avec la <em>&laquo; g\u00e9opolitique &raquo;<\/em>. Revenons maintenant \u00e0 la raison pour laquelle Trump veut les territoires C, G et P.<\/p>\n<\/p>\n<p><p>Tout d&rsquo;abord, l&rsquo;Am\u00e9rique n&rsquo;est plus en lice pour des territoires tels que l&rsquo;ancienne Ukraine, la province chinoise de Ta\u00efwan ou tout autre prix g\u00e9opolitique que l&rsquo;on pensait auparavant \u00eatre en s\u00e9curit\u00e9 dans le giron du grand empire mondial am\u00e9ricain. C&rsquo;est comme si le seigneur du manoir, \u00e0 l&rsquo;\u00e2ge m&ucirc;r et se dirigeant inexorablement vers la faillite, d\u00e9cidait de renoncer \u00e0 ses droits sur les champs, les p\u00e2turages, les moulins et les terrains de chasse, mais souhaitait garder les bois, la glaci\u00e8re et l&rsquo;\u00e9tang \u00e0 poissons. Il supplie ses cr\u00e9anciers de lui laisser ces biens.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, disent les Chinois, mais Ta\u00efwan et les &icirc;les Spratleys sont \u00e0 nous et, s&rsquo;il vous pla&icirc;t, retirez vos militaires de la Cor\u00e9e du Sud, du Japon, de Guam et des Philippines. Bien s&ucirc;r, disent les Russes, mais l&rsquo;ancienne Ukraine est \u00e0 nous et nous vous demandons de ramener l&rsquo;OTAN \u00e0 son niveau d&rsquo;avant la r\u00e9unification de l&rsquo;Allemagne. Oh, et la Su\u00e8de doit \u00eatre militairement neutre et les pays baltes sont notre territoire, conform\u00e9ment au trait\u00e9 de Nystad du 10 septembre 1721, et la Finlande doit \u00eatre militairement neutre, conform\u00e9ment au trait\u00e9 de Paris du 3 f\u00e9vrier 1947. Bien s&ucirc;r, dit l&rsquo;Iran, mais \u00e9loignez d&rsquo;abord vos bases militaires de nos fronti\u00e8res.<\/p>\n<\/p>\n<p><p>Si Lord Donald fait tout cela, il pourra \u00e9conomiser d&rsquo;\u00e9normes sommes d&rsquo;argent sur la d\u00e9fense (plus de bases militaires \u00e9trang\u00e8res, plus de porte-avions) et pourra garder le bois (Canada), la glaci\u00e8re (Groenland) et l&rsquo;\u00e9tang \u00e0 poissons (Panama). Il pourra alors s&rsquo;installer dans une s\u00e9nescence confortable, en allumant la chemin\u00e9e avec le bois de son lot et en mangeant du poisson congel\u00e9. Avec ce petit coup de pouce, il pourra commencer \u00e0 s&rsquo;habiller de fa\u00e7on minable et changer son nom en <em>Frump<\/em> <em>[une femme peu attirante qui porte des v\u00eatements d\u00e9mod\u00e9s., NdT]<\/em>.<\/p>\n<\/p>\n<p><p>Il existe une deuxi\u00e8me raison de s&#8217;emparer de ces actifs immenses mais non rentables : ils peuvent servir de garantie pour un nouvel emprunt, afin de compenser la perte des champs, des mines et des usines ukrainiens. Un petit tour de passe-passe financier (les Am\u00e9ricains sont si dou\u00e9s) permettra de r\u00e9\u00e9valuer la valeur collat\u00e9rale des glaciers du Groenland en tant qu&rsquo;eau en bouteille et celle des pins des for\u00eats bor\u00e9ales canadiennes en tant que meubles de chambre \u00e9l\u00e9gants. Cette nouvelle r\u00e9serve de faux collat\u00e9raux permettra de relancer temporairement la planche \u00e0 billets, \u00e9vitant ainsi l&rsquo;effondrement financier suffisamment longtemps pour que Trump puisse terminer son mandat. &Eacute;tant donn\u00e9 l&rsquo;\u00e9tat lamentable de son domaine, qu&rsquo;est-ce que cet homme pourrait bien demander de plus ?<\/p>\n<\/p>\n<p><p>Le 6 Janvier 202, <a href=\"https:\/\/boosty.to\/cluborlov\/posts\/44508869-8223-4a8e-b0b5-231cfb3930fc\">Club Orlov<\/a> &ndash; Traduction de &lsquo;<em><a href=\"https:\/\/lesakerfrancophone.fr\/limperialisme-nord-americain-fond-a-vue-doeil\">Sakerfrancophone<\/a><\/em>&lsquo;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p><em>Ce billet est ouvert au public. N&rsquo;h\u00e9sitez pas \u00e0 le partager. Vous pouvez \u00e9galement <a href=\"https:\/\/boosty.to\/cluborlov\/single-payment\/donation\/665804\/target?share=target_link\">faire un don<\/a> \u00e0 mon fonds pour que davantage de mes articles soient ouverts au public.<\/em><\/p>\n<\/p>\n<\/blockquote><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;imp\u00e9rialisme US fond \u00e0 vue d&rsquo;&oelig;il Cinq jours \u00e0 peine nous s\u00e9parent du d\u00e9but du r\u00e8gne de l&#8217;empereur Donald Ier et de sa joyeuse bande de milliardaires, et le monde entier est en proie \u00e0 de folles attentes quant \u00e0 ses nouvelles et excellentes aventures. Donald Ier a d\u00e9j\u00e0 annonc\u00e9 qu&rsquo;il pr\u00e9voyait d&rsquo;\u00e9tendre son domaine&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3708,708,9359,14289,2668,7080,2639,2671],"class_list":["post-81414","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-canada","tag-empire","tag-expansionnisme","tag-groenland","tag-orlov","tag-panama","tag-trump","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81414"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81414\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}