{"id":81417,"date":"2025-01-25T18:15:23","date_gmt":"2025-01-25T18:15:23","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/25\/le-reve-de-vladimir-vladimirovitch\/"},"modified":"2025-01-25T18:15:23","modified_gmt":"2025-01-25T18:15:23","slug":"le-reve-de-vladimir-vladimirovitch","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/01\/25\/le-reve-de-vladimir-vladimirovitch\/","title":{"rendered":"Le r\u00eave de Vladimir Vladimirovitch"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Le r\u00eave de Vladimir Vladimirovitch<\/strong><\/h2>\n<\/p>\n<p><p>25 janvier 2025 (18H15) &ndash; Les d\u00e9buts de Trump-II sont extraordinairement agit\u00e9es, rapides jusqu&rsquo;\u00e0 para&icirc;tre hors de contr\u00f4le, et d&rsquo;une complexit\u00e9 telle dans les contradictions, affirmations fantaisistes, envol\u00e9es de Trump. Les Russes, d&rsquo;abord sur leurs gardes, en arrivent d\u00e9sormais \u00e0 tenter de suivre presqu&rsquo;avec fascination pour comprendre exactement ce que veut le pr\u00e9sident Trump et quelle est si politique, et s&rsquo;il a une politique, etc. Ils ont d\u00e9pass\u00e9 le stade des erreurs grossi\u00e8res o&ugrave; Trump se prenait les neurones dans les millions de morts ; Pechkov et Zakharova se sont charg\u00e9s de le remettre au pas&#8230;<\/p>\n<\/p>\n<p><p>Poutine, lui, a fait un usage remarquable de ses vertus de calme, de patience et de bienveillance diplomatique. Il n&rsquo;a cess\u00e9 de d\u00e9clarer qu&rsquo;il \u00e9tait int\u00e9ress\u00e9 \u00e0 parler dans tous les cas avec Trump, tout en renouvelant les conditions inflexibles des Russes sur l&rsquo;Ukraine. Mais j&rsquo;en viens \u00e0 me demander si Poutine lui-m\u00eame n&rsquo;est pas d\u00e9sorient\u00e9 par Trump et s&rsquo;il ne songe pas \u00e0 une autre tactique que celle du simple \u00ab\u00a0tenir, sourire, attendre et voir\u00a0\u00bb. La bienveillance et l&rsquo;amabilit\u00e9 du pr\u00e9sident russe \u00e9voluent avec une telle insistance que je crois qu&rsquo;il est permis de se demander s&rsquo;il n&rsquo;y a pas chez lui une tactique plus \u00e9labor\u00e9e, qui voit plus loin, qui se permet m\u00eame d&rsquo;imaginer qu&rsquo;il entr&rsquo;aper\u00e7oit de quelle strat\u00e9gie il s&rsquo;agit.<\/p>\n<\/p>\n<p><p>Je songe notamment \u00e0 l&rsquo;intervention de Poutine dans une interview o&ugrave; il a <a href=\"https:\/\/www.rt.com\/russia\/611582-trump-putin-stolen-election\/\">compl\u00e8tement appuy\u00e9<\/a> la th\u00e8se de la fraude antiTrump lors des \u00e9lections de 2020 et abond\u00e9 dans le sens trumpiste du \u00ab\u00a0si l&rsquo;on ne m&rsquo;avait pas vol\u00e9 la victoire, il n&rsquo;y aurait pas eu la guerre en Ukraine parce que je n&rsquo;en voulais pas\u00a0\u00bb. C&rsquo;est tout de m\u00eame, de la part de Poutine, soutenir avec une fougue et une nettet\u00e9 qui changent beaucoup de sa prudence habituelle, l&rsquo;une des th\u00e8ses les plus contest\u00e9es, les plus d\u00e9test\u00e9es, les plus honnies et ha\u00efes du Trump de 2020-2024&#8230; Que l&rsquo;on prenne bien garde \u00e0 mon propos, o&ugrave; il ne m&rsquo;int\u00e9resse pas de savoir si la chose est vraie ou fausse, mais o&ugrave; il m&rsquo;int\u00e9resse de voir que Poutine-le-prudent, soudainement pris d&#8217;emportement, soutient sans la moindre h\u00e9sitation le Trump le plus pol\u00e9mique que l&rsquo;on puisse imaginer  dans les impressionnants c\u00e9nacles de la diplomatie hautement morale du bloc am\u00e9ricaniste-occidentaliste :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Je ne peux pas \u00eatre en d\u00e9saccord avec lui sur le fait que s&rsquo;il avait \u00e9t\u00e9 pr\u00e9sident, si sa victoire n&rsquo;avait pas \u00e9t\u00e9 vol\u00e9e en 2020, peut-\u00eatre que la crise en Ukraine qui a \u00e9clat\u00e9 en 2022 n&rsquo;aurait pas eu lieu\u00a0\u00bb, a d\u00e9clar\u00e9 Poutine dans une interview publi\u00e9e vendredi par le journaliste de la t\u00e9l\u00e9vision Russe-1 Pavel Zarubine sur &lsquo;Telegram&rsquo;.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En 2023, Trump a d\u00e9clar\u00e9 \u00e0 l&rsquo;animateur de radio am\u00e9ricain Hugh Hewitt que le conflit ukrainien n&rsquo;aurait jamais commenc\u00e9 si les \u00e9lections am\u00e9ricaines de 2020 n&rsquo;avaient pas \u00e9t\u00e9 \u00ab\u00a0truqu\u00e9es\u00a0\u00bb et si Joe Biden ne l&rsquo;avait pas remplac\u00e9 dans son bureau ovale.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0<\/em>[Poutine] <em>n&rsquo;aurait jamais fait cela si l&rsquo;\u00e9lection n&rsquo;avait pas \u00e9t\u00e9 truqu\u00e9e, notre \u00e9lection. Elle a \u00e9t\u00e9 truqu\u00e9e et vol\u00e9e. Si cette \u00e9lection n&rsquo;avait pas \u00e9t\u00e9 truqu\u00e9e, si j&rsquo;\u00e9tais pr\u00e9sident, vous auriez actuellement des millions de personnes vivantes qui sont mortes\u00a0\u00bb, selon une transcription de l&rsquo;interview<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Poutine ne fait rien sans avoir effectu\u00e9 un calcul rationnel sur les prolongements de l&rsquo;acte qu&rsquo;il pose, et les avantages \u00e9ventuels. Dans le cas qui nous occupe, a-t-il vraiment besoin d&rsquo;en rajouter pour \u00ab\u00a0s\u00e9duire\u00a0\u00bb Trump, alors que le nouveau pr\u00e9sident des &Eacute;tats-Unis se pr\u00e9cipite dans ses bras en jetant des compliments \u00e0 son \u00e9gard de tous c\u00f4t\u00e9s, dont certains incroyablement maladroits comme \u00e0 son habitude ?<\/p>\n<\/p>\n<p><p>Quel est ce calcul et o&ugrave; le m\u00e8ne-t-il, Poutine ? On peut raisonnablement poser la question, sans crainte d&rsquo;une r\u00e9ponse paralysante, pour faire d\u00e9marrer mon hypoth\u00e8se.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>La &lsquo;<em>perestro\u00efka<\/em>&lsquo; de Trump<\/strong><\/h3>\n<\/p>\n<p><p>Celle-ci, mon hypoth\u00e8se, \u00e9tait d\u00e9j\u00e0 dans <a href=\"https:\/\/www.dedefensa.org\/article\/gorbatchev-etait-il-un-trump-russe\">le texte d&rsquo;hier<\/a>, dont elle formait l&rsquo;\u00e9pine dorsale. Il s&rsquo;agit d&rsquo;une remarque faite par &laquo; <em>le cin\u00e9aste et politologue Karen Shakhnazarov<\/em> &raquo;, qui surprit tant Dimitri Simes, que nous connaissons bien, qui organisait le d\u00e9bat sur la cha&icirc;ne russe &lsquo;<em>Channel-One<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La conclusion la plus inattendue a peut-\u00eatre \u00e9t\u00e9 tir\u00e9e mardi soir<\/em> [21 janvier]<em> dans l&rsquo;\u00e9mission &lsquo;The Big Game&rsquo; de la cha&icirc;ne Channel One par le cin\u00e9aste et politologue Karen Shakhnazarov. \u00ab\u00a0Vous savez, a-t-il dit, en r\u00e9pondant \u00e0 une question de Dimitri Simes, le pr\u00e9sentateur, qui lui demandait de parler de ses impressions sur le discours d&rsquo;investiture de Donald Trump, il m&rsquo;a rappel\u00e9 \u00e0 certains \u00e9gards notre Mikha\u00efl Sergue\u00efevitch Gorbatchev\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Pour expliquer cette comparaison inattendue et m\u00eame choquante, qui a quelque peu surpris le politologue chevronn\u00e9 qu&rsquo;est Simes, Shakhnazarov a not\u00e9 que ce que Trump allait faire \u00e9tait en fait une sorte de restructuration <\/em>[ou &lsquo;<em>perestro\u00efka<\/em>&lsquo;],<em> notant que l&rsquo;Am\u00e9rique est au bord de changements majeurs. Ainsi, \u00e0 l&rsquo;\u00e9poque de Gorbatchev, les changements \u00e9taient attendus en URSS. &Agrave; l&rsquo;\u00e9poque aussi, tout le monde &ndash; les gauchistes comme les droitiers, les lib\u00e9raux comme les conservateurs &ndash; applaudissait Gorbatchev. Alors, selon Shakhnazarov, ce que Trump a promis pourrait conduire les &Eacute;tats-Unis \u00e0 de gros probl\u00e8mes<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Rappelez-vous \u00e9galement qu&rsquo;\u00e0 la fin, <a href=\"https:\/\/usa.news-pravda.com\/world\/2025\/01\/22\/96820.html\">ce m\u00eame texte<\/a> sur Trump, que je trouve \u00e9crit sur ce ton mi-figue mi-raisin  (&laquo; <em>Trump&rsquo;s Discouraging speech <\/em>&raquo;) qui nous donne peut-\u00eatre une <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>, on trouve quelques lignes qui constatent que, jusqu&rsquo;ici, la seule d\u00e9marche claire et assur\u00e9e de Trump-II, c&rsquo;est sa lutte contre le &lsquo;<em>DeepState<\/em>&lsquo;. C&rsquo;est le domaine qui est per\u00e7u comme le plus explicitement affirm\u00e9 dans le discours inaugural, et cela justement est un facteur important qui fait penser \u00e0 Gorbatchev et \u00e0 sa lutte contre la bureaucratie communiste et ses diverses tentacules (le &lsquo;<em>DeepState<\/em>&lsquo; de l&rsquo;URSS).<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>En bref, le discours d&rsquo;investiture de Donald Trump a montr\u00e9 qu&rsquo;il avait s\u00e9rieusement d\u00e9cid\u00e9 de combattre l\u00a0\u00bb&Eacute;tat profond &lsquo;, ces forces qui dirigent le monde occidental et pr\u00e9f\u00e8rent rester dans l&rsquo;ombre. Et cela, en g\u00e9n\u00e9ral, n&rsquo;a pas \u00e9t\u00e9 une surprise<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Quand je reviendrai dans le Bureau ovale\u00a0\u00bb, a d\u00e9clar\u00e9 Trump avant son investiture, \u00ab\u00a0nous d\u00e9truirons compl\u00e8tement l&rsquo;&Eacute;tat profond. Nous cr\u00e9erons une commission de v\u00e9rit\u00e9 et de r\u00e9conciliation qui d\u00e9classifiera et publiera tous les documents sur l&rsquo;espionnage d&rsquo;&Eacute;tat, la censure et la corruption !\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Trump est devenu une menace apr\u00e8s de tels mots. Les \u00e9lites supranationales de l\u00a0\u00bb&Eacute;tat profond&rsquo; ne lui pardonneront pas de telles d\u00e9clarations, et encore moins ses actes. Comment ne le ferait-il pas ?<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; L&rsquo;hypoth\u00e8se devenant alors : n&rsquo;est-ce pas la m\u00eame ligne de pens\u00e9e qui traverse l&rsquo;esprit de Poutine ?<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Un Gorbatchev am\u00e9ricaniste<\/strong><\/h3>\n<\/p>\n<p><p>Poutine est un homme enclin \u00e0 envisager cette sorte d&rsquo;hypoth\u00e8se. Il vient du KGB qui, malgr\u00e9 les cris d&rsquo;horreur et d&rsquo;orfraie de nos gardiens de la vigilance morale, n&rsquo;avait plus dans le dernier quart du XX\u00e8me si\u00e8cle les pratiques monstrueuses du NKVD de Staline, &ndash; et peut-\u00eatre m\u00eame pas, en ampleur, celles de la CIA courante. Il s&rsquo;agissait d&rsquo;un tr\u00e8s puissant service de renseignement, avec sa bureaucratie, ses \u00ab\u00a0op\u00e9rationnels\u00a0\u00bb de la manipulation et ses quelques groupes de choc.<\/p>\n<\/p>\n<p><p>Poutine \u00e9tait un \u00ab\u00a0op\u00e9rationnel\u00a0\u00bb (en RDA, dans les ann\u00e9es 1985-1989), c&rsquo;est-\u00e0-dire un officier d&rsquo;action mais attentif \u00e0 \u00e9viter toutes sortes d&rsquo;op\u00e9rations brutales pour privil\u00e9gier les recrutements classiques, sources de renseignement et de manipulation. D&rsquo;o&ugrave; il \u00e9tait, il pouvait mesurer le poids de la bureaucratie par rapport aux op\u00e9rations de renseignement et d&rsquo;action ; c&rsquo;est-\u00e0-dire qu&rsquo;il pouvait mesurer le poids du d\u00e9labrement de l&rsquo;URSS dans les ann\u00e9es 1970-1980, et s&rsquo;il a toujours consid\u00e9r\u00e9 que, de c&oelig;ur, il regrettait l&rsquo;URSS, il a toujours ajout\u00e9 que, de raison, il jugeait in\u00e9vitable son effondrement.<\/p>\n<\/p>\n<p><p>Au-dessus de ces observations internes, le KGB constituait le service de s\u00e9curit\u00e9 le plus avanc\u00e9 de l&rsquo;URSS sur les mondes ext\u00e9rieurs, en un sens avec l&rsquo;\u00e9tat d&rsquo;esprit qu&rsquo;on pourrait dire le plus \u00ab\u00a0progressiste\u00a0\u00bb (en pesant avec pr\u00e9caution le qualificatif). Ainsi, le KGB fut le seul service de s\u00e9curit\u00e9 important \u00e0 exprimer de tr\u00e8s-graves r\u00e9serves contre l&rsquo;invasion de l&rsquo;Afghanistan. Andropov fut chef du KGB pendant une quinzaine d&rsquo;ann\u00e9es avant de devenir le Secr\u00e9taire G\u00e9n\u00e9ral du PC en 1982 (mort un an plus tard). Dans ce cadre, c&rsquo;est Andropov qui avait mis Gorbatchev sur une orbite de r\u00e9formes profondes qui d\u00e9boucha sur la direction du Parti en mars 1985. D&rsquo;une certaine fa\u00e7on, les destins de Gorbatchev et de Poutine se compl\u00e8tent, le premier effectuant les r\u00e9formes que le second jugeait n\u00e9cessaires, mais en allant trop loin du point de vue politique pour le second, jusqu&rsquo;\u00e0 l&rsquo;effondrement de1991.<\/p>\n<\/p>\n<p><p>Mon hypoth\u00e8se est que c&rsquo;est peut-\u00eatre \u00e0 tout cela que songe Poutine observant Trump, selon un raisonnement qui rejoint celui de Karen Shakhnazarov&#8230; Pourquoi Trump ne serait-il pas un Gorbatchev am\u00e9ricaniste ?<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><strong>Une \u00e9volution gorbatch\u00e9vienne ?<\/strong><\/h3>\n<\/p>\n<p><p>Je songe \u00e0 cette hypoth\u00e8se parce que, malgr\u00e9 toutes les c\u00e2lineries actuelles sur la reprise du dialogue USA-Russie et des n\u00e9gociations d&rsquo;une paix ukrainienne dont les esprits mesur\u00e9s savent bien qu&rsquo;elle se fera au rythme des victoires russes, il me semble que Poutine a acquis comme les autres dirigeants russes, apr\u00e8s trois ann\u00e9es du traitement am\u00e9ricaniste-occidentaliste inflig\u00e9 \u00e0 la Russie, la conviction d\u00e9sormais de l&rsquo;in\u00e9vitabilit\u00e9 d&rsquo;un affrontement avec l&rsquo;Ouest dans le cadre d&rsquo;un conflit civilisationnel.<\/p>\n<\/p>\n<p><p>On comprend alors que pour lui, tout au fond de sa conscience, juste \u00e0 la limite de l&rsquo;inconscient qui, dans notre fonctionnement, fait le lien avec la philosophie de l&rsquo;histoire, le concept d&rsquo;une \u00e9volution gorbatch\u00e9vienne des USA serait, et de tr\u00e8s loin, la meilleure voie \u00e0 prendre, \u00e0 suivre, \u00e0 arpenter&#8230; S&rsquo;il faut l&rsquo;encourager en applaudissant aux exploits de Trump-II, applaudissons-le, Folleville !<\/p>\n<\/p>\n<p><p>&#8230; Apr\u00e8s tout, hein, une hypoth\u00e8se, pour nous autres qui nous targuons d&rsquo;encore go&ucirc;ter la po\u00e9sie, une hypoth\u00e8se dans ces conditions c&rsquo;est presqu&rsquo;un r\u00eave pr\u00e9monitoire<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00eave de Vladimir Vladimirovitch 25 janvier 2025 (18H15) &ndash; Les d\u00e9buts de Trump-II sont extraordinairement agit\u00e9es, rapides jusqu&rsquo;\u00e0 para&icirc;tre hors de contr\u00f4le, et d&rsquo;une complexit\u00e9 telle dans les contradictions, affirmations fantaisistes, envol\u00e9es de Trump. Les Russes, d&rsquo;abord sur leurs gardes, en arrivent d\u00e9sormais \u00e0 tenter de suivre presqu&rsquo;avec fascination pour comprendre exactement ce que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3066,2631,3483,7201,916,5600,2639],"class_list":["post-81417","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-americaniste","tag-de","tag-gorbatchev","tag-perestroika","tag-poutine","tag-tactique","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81417"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81417\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}