{"id":81465,"date":"2025-03-01T17:41:40","date_gmt":"2025-03-01T17:41:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/03\/01\/le-18-juin-2026-de-mister-z\/"},"modified":"2025-03-01T17:41:40","modified_gmt":"2025-03-01T17:41:40","slug":"le-18-juin-2026-de-mister-z","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/03\/01\/le-18-juin-2026-de-mister-z\/","title":{"rendered":"Le 18 juin (2026) de Mister Z."},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le 18 juin (2026) de Mister Z.<\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Difficile, on en conviendra, de ne pas parler de <strong>l&rsquo;\u00e9tonnante rencontre t\u00e9l\u00e9vis\u00e9e<\/strong> entre Zelenski et la direction US (bien autant <strong>Vance, &ndash; excellent en tous points, &ndash; que Trump<\/strong>). &bull; D&rsquo;ailleurs, les derniers mots du pr\u00e9sident des &Eacute;tats-Unis, qui est un excellent sp\u00e9cialiste de la t\u00e9l\u00e9-r\u00e9alit\u00e9, nous disent tout : &laquo; <em>Ce sera <strong>une excellente \u00e9mission de t\u00e9l\u00e9vision, je peux le dire<\/strong><\/em>. &raquo; &bull; Que va faire Mister Z. d\u00e9sormais ? <strong>Rallier l&rsquo;Europe o&ugrave; l&rsquo;on pourrait l&rsquo;investir comme chef de guerre<\/strong> de l&rsquo;Union Europ\u00e9enne ? &bull; <strong>Certains lui voit un destin gaullien<\/strong>, \u00e9videmment avec l&rsquo;aide des Britanniques qui conservent pieusement leur l\u00e9gendaire perfidie.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Ce fut un remarquable moment de grande parade, presque h\u00e9ro\u00efque, un formidable th\u00e9\u00e2tre mettant en sc\u00e8ne le sort du monde sans trop nous accabler de d\u00e9tails angoissants. Le <em>deus ex machina <\/em>avait manifestement pris une forte dose de coca\u00efne mondaine et jappait les mots autant qu&rsquo;il les mangeait, semblable \u00e0 la fameuse &lsquo;<em>souris qui rugissait<\/em>&lsquo; mais \u00e0 l&rsquo;<em>apex<\/em> de son \u00e9pisode maniaque plut\u00f4t que particuli\u00e8rement habile. Le pr\u00e9sident Trump eut un instant de grave d\u00e9pression, une sorte d&rsquo;abattement devant l&rsquo;incroyable tournure de l&rsquo;\u00e9v\u00e9nement o&ugrave; on lui d\u00e9crivait les USA mieux prot\u00e9g\u00e9s par l&rsquo;Ukraine que par le &laquo; <em>nice ocean<\/em> &raquo; Atlantique. Pendant ce temps, son vice-pr\u00e9sident, &ndash; l&rsquo;incontestable vedette, l&rsquo;esprit-phare de cette rencontre, l&rsquo;homme de 2028, &ndash; tenait Mister Z. \u00e0 distance et par le col avec la fermet\u00e9 du verbe et la droiture du regard.<\/p>\n<\/p>\n<p><p>Mister Z. quitta la Maison-Blanche en claquant la porte derri\u00e8re lui, tandis que les \u00e9quipes de conseillers se pr\u00e9cipitaient sur le fastueux en-cas, ou \u00ab\u00a0d\u00e9jeuner de travail\u00a0\u00bb, auquel Zelenski n&rsquo;avait pas touch\u00e9. La s\u00e9quence \u00e9tait termin\u00e9e.<\/p>\n<\/p>\n<p><p>Il est inutile de se pr\u00e9cipiter sur les lieux communs de circonstance : oui, il est probable sinon plus que probable, et m\u00eame sans aucun doute \u00e9vident pour ne pas dire certain qu&rsquo;on n&rsquo;a jamais vu, &ndash; dans tous les cas dans l&rsquo;\u00e8re de la radio et de l&rsquo;image de communication, &ndash; une telle sc\u00e8ne. M\u00eame avec le monstrueux Adolph fascinateur ou l&rsquo;\u00e9nigmatiquement sanglant Joseph Vissarionovich Yougachvili, on n&rsquo;eut jamais rien de pareil, d&rsquo;aussi baroque, d&rsquo;aussi grotesque et monstrueux, avec d&rsquo;incroyables moments de vaudeville-bouffe,  comme si on avait fourr\u00e9 du Labiche au c&oelig;ur d&rsquo;une tirade de Corneille.<\/p>\n<\/p>\n<p><p>Voici ce que certains en disent, donc : des exemples plut\u00f4t que des exceptions, on le comprend \u00e9videmment&#8230; <a href=\"https:\/\/www.rt.com\/news\/613538-zelensky-humiliated-trump-vance\/\">Tarik Cyril Amar<\/a> en a cit\u00e9 quelques-uns :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Un \u00e9chec grandiose\u00a0\u00bb &ndash; c&rsquo;est ce qu&rsquo;a d\u00e9clar\u00e9 le meilleur site d&rsquo;information ukrainien. C&rsquo;est ainsi que &lsquo;strana.ua&rsquo; a r\u00e9sum\u00e9 la visite de Vladimir Zelenski, ancien dirigeant de Kiev, \u00e0 Washington<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Et tous ceux qui ont assist\u00e9 \u00e0 la joute sans retenue entre Zelenski, d&rsquo;un c\u00f4t\u00e9, et le pr\u00e9sident am\u00e9ricain Donald Trump et le vice-pr\u00e9sident J.D. Vance, de l&rsquo;autre, ne peuvent \u00eatre en d\u00e9saccord. En fait, personne ne tente m\u00eame de le contester : ind\u00e9pendamment de tout parti pris politique, il y a unanimit\u00e9 dans les m\u00e9dias grand public occidentaux pour dire qu&rsquo;il s&rsquo;agit d&rsquo;une catastrophe historique pour Zelenski et sa version de l&rsquo;Ukraine<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Un d\u00e9sastre\u00a0\u00bb et un \u00ab\u00a0chaos amer\u00a0\u00bb (The Economist) ; un \u00ab\u00a0effondrement\u00a0\u00bb qui \u00ab\u00a0n&rsquo;aurait pu \u00eatre pire\u00a0\u00bb (Financial Times) ; une \u00ab\u00a0escalade historique\u00a0\u00bb (Spiegel) ; un \u00ab\u00a0d\u00e9sastre pour l&rsquo;Ukraine\u00a0\u00bb et une \u00ab\u00a0confrontation spectaculaire\u00a0\u00bb (Le Monde) ; un \u00ab\u00a0reproche\u00a0\u00bb et une \u00ab\u00a0d\u00e9b\u00e2cle\u00a0\u00bb pour Zelenski (New York Times) et ainsi de suite&hellip; Vous avez compris l&rsquo;essentiel<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">&laquo; <em>Ce sera une excellente \u00e9mission de t\u00e9l\u00e9vision <\/em>&raquo;<\/h3>\n<\/p>\n<p><p>Pour avoir une bonne vision de l&rsquo;extraordinaire entretien (RT.com en donne <a href=\"https:\/\/www.rt.com\/news\/613490-zelensky-trump-hostile-confrontation\/\">le <em>verbatim<\/em><\/a> et part m\u00eame \u00e0 la recherche du &lsquo;<em>cyka blyat<\/em>&lsquo; [sorte de \u00ab\u00a0fils de pute\u00a0\u00bb en russo-ukrainien] chuchot\u00e9 par Z \u00e0 l&rsquo;intention de JD), on peut regarder <a href=\"https:\/\/www.youtube.com\/watch?v=mPu9R04jT5Q\">la vid\u00e9o<\/a> de Pascal, analyste de l&rsquo;excellent &lsquo;<em>Neutrality Studies Fran\u00e7ais<\/em>&lsquo; qui donne l&rsquo;int\u00e9gralit\u00e9 des sept minutes du segment pol\u00e9mique avec une excellente traduction vocale, des voix diff\u00e9rentes traduisant les propos des diff\u00e9rents acteurs.<\/p>\n<\/p>\n<p><p>Pascal donne apr\u00e8s son interpr\u00e9tation de cette affaire. Il juge que Zelenski en suscitant ou en acceptant cette \u00e9trange \u00ab\u00a0n\u00e9gociation\u00a0\u00bb r\u00e9alis\u00e9e comme s&rsquo;il s&rsquo;agissait d&rsquo;une rencontre formelle transform\u00e9e en \u00e9mission de t\u00e9l\u00e9-r\u00e9alit\u00e9, et tout cela devant une presse empress\u00e9e, est tomb\u00e9 dans un pi\u00e8ge tendu par Trump-Vance. Leur but ? Montrer au plus grand public du monde qu&rsquo;il sont bloqu\u00e9s dans leur tentative d&rsquo;aller vers un cessez-le-feu \u00e0 cause de l&rsquo;ent\u00eatement de Zelenski (en \u00e9vitant de pr\u00e9ciser que, de toutes les fa\u00e7ons, les Russes refuseraient ce cessez-le-feu puisqu&rsquo;ils veulent un accord de paix ultra-verrouill\u00e9 : mais autant ne pas trop les provoquer pour m\u00e9nager l&rsquo;avenir).<\/p>\n<\/p>\n<p><p>Sur la fin de la \u00ab\u00a0performance\u00a0\u00bb-TV, Trump le signifie nettement \u00e0 Zelenski, en \u00e9voquant le blocage si \u00ab\u00a0les attitudes\u00a0\u00bb (celle de l&rsquo;Ukraine) ne changent pas.  :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Mais vous voyez, je pense que c&rsquo;est bien que le peuple am\u00e9ricain voie ce qui se passe. Je pense que c&rsquo;est tr\u00e8s important. C&rsquo;est pourquoi j&rsquo;ai continu\u00e9 \u00e0 faire \u00e7a si longtemps. Vous devez \u00eatre reconnaissants, vous n&rsquo;avez pas les cartes en main<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zelenski<\/em><\/strong> : &laquo; <em>Je suis reconnaissant<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Vous \u00eates enterr\u00e9s l\u00e0-bas. Des gens meurent. Vous manquez de soldats. &Eacute;coutez, vous manquez de soldats. Ce serait une sacr\u00e9e bonne nouvelle<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zelenski<\/em><\/strong> : &laquo; <em>S&rsquo;il vous pla&icirc;t, Monsieur le Pr\u00e9sident<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Alors vous nous dites : \u00ab\u00a0Je ne veux pas de cessez-le-feu, je ne veux pas de cessez-le-feu, je veux y aller et je voulais \u00e7a.\u00a0\u00bb &Eacute;coutez, si vous pouviez obtenir un cessez-le-feu tout de suite, je vous le dis, vous l&rsquo;accepteriez, pour que les balles cessent de voler et que vous, les hommes, cessiez de vous faire tuer<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zelenski<\/em><\/strong> : &laquo; <em>Bien s&ucirc;r, nous voulons arr\u00eater la guerre<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Mais vous dites que vous ne voulez pas de cessez-le-feu. Je veux un cessez-le-feu<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zelenski<\/em><\/strong> : &laquo; <em>Mais je vous ai dit : o&ugrave; sont les garanties ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Parce que vous obtenez un cessez-le-feu plus rapidement qu&rsquo;un accord.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Zelenski<\/em><\/strong><em> : &laquo; Demandez \u00e0 nos gens ce qu&rsquo;ils pensent du cessez-le-feu. Peu vous importe ce qu&rsquo;ils disent ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Ce n&rsquo;\u00e9tait pas avec moi. C&rsquo;\u00e9tait avec un type nomm\u00e9 Biden, qui n&rsquo;\u00e9tait pas une personne intelligente. C&rsquo;\u00e9tait avec Obama. Excusez-moi. C&rsquo;\u00e9tait avec Obama, qui vous a donn\u00e9 des b\u00e2ches et je vous ai donn\u00e9 des Javelins<\/em> [syst\u00e8mes antichars portables].<em> Oui, je vous ai donn\u00e9 les Javelins pour d\u00e9truire tous ces chars. Obama vous a donn\u00e9 des b\u00e2ches. En fait, la d\u00e9claration dit qu&rsquo;Obama a donn\u00e9 des b\u00e2ches et Trump a donn\u00e9 des Javelins. Vous devez \u00eatre plus reconnaissant parce que laissez-moi vous dire que vous n&rsquo;avez pas les cartes. Avec nous, vous avez les cartes, mais sans nous, vous n&rsquo;avez aucune carte&#8230; Ce sera un accord difficile \u00e0 conclure car les attitudes doivent changer<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Journaliste<\/em><\/strong> : &laquo; <em>Et si la Russie rompt le cessez-le-feu ? &raquo;<\/em><\/p>\n<\/p>\n<p><p><strong><em>Trump<\/em><\/strong> : &laquo; <em>Et si quelque chose se passe ? Et si la bombe tombait sur votre t\u00eate maintenant ? OK ? Et s&rsquo;ils l&rsquo;avaient bris\u00e9e ? Je ne sais pas. Ils l&rsquo;ont bris\u00e9e avec Biden parce qu&rsquo;ils ne le respectaient pas. Ils ne respectaient pas Obama. Ils me respectent<\/em>.<\/p>\n<\/p>\n<p><p><em>Laissez-moi vous dire, Poutine a travers\u00e9 beaucoup d&rsquo;\u00e9preuves avec moi. Il a travers\u00e9 une fausse chasse aux sorci\u00e8res quand ils l&rsquo;ont utilis\u00e9 avec la Russie. La Russie, la Russie, la Russie !<\/em> [allusion au &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/le-poids-colossal-du-simulacre-russiagate\"><em>Russiagate<\/em><\/a>&lsquo;] [&#8230;] <em>Il a peut-\u00eatre rompu les accords avec Obama et Bush et il a peut-\u00eatre rompu les accords avec Biden. Il l&rsquo;a fait. Peut-\u00eatre, peut-\u00eatre pas. Je ne sais pas ce qui s&rsquo;est pass\u00e9, mais il ne l&rsquo;a pas rompu avec moi. Il<\/em> [Poutine] <em>veut conclure un accord. Je ne sais pas si vous, Zelenski, pouvez conclure un accord<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Trump <\/em><\/strong><strong>[directement \u00e0 Zelenski] <\/strong>: &laquo; <em>Le probl\u00e8me, c&rsquo;est que je vous ai donn\u00e9 le pouvoir d&rsquo;\u00eatre un dur \u00e0 cuire, et je ne pense pas que vous le seriez sans les &Eacute;tats-Unis. Et votre peuple est tr\u00e8s courageux. Mais soit vous allez conclure un accord, soit nous nous retirerons. Et si nous nous retirons, vous vous battrez. Je ne pense pas que ce sera joli, mais vous vous battrez.<\/em><\/p>\n<\/p>\n<p><p><em>Vous n&rsquo;avez pas les cartes en main. Une fois que nous aurons sign\u00e9 cet accord, vous serez dans une bien meilleure position. Mais vous vous ne montrez aucune reconnaissance, et ce n&rsquo;est pas une bonne chose. Je vais \u00eatre honn\u00eate, ce n&rsquo;est pas une bonne chose<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et l\u00e0-dessus r\u00e9appara&icirc;t, triomphant, avec sa derni\u00e8re phrase,, l&rsquo;homme du show t\u00e9l\u00e9vis\u00e9 plut\u00f4t qu&rsquo;une sorte d&rsquo;Hitler r\u00e9incarn\u00e9&#8230; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Bon, je pense que nous en avons assez dit. Qu&rsquo;en pensez-vous ? Ce sera une excellente \u00e9mission de t\u00e9l\u00e9vision, je peux le dire<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">18 juin 2026, \u00ab\u00a0Ici Radio-Londres\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Tout de m\u00eame, il ne faut pas se d\u00e9courager. Certains jugent que Zelinski n&rsquo;a pas fait seulement que glisser sur de la coca\u00efne r\u00e9pandue par m\u00e9garde devant lui pour tomber, t\u00eate la premi\u00e8re, dans le trou du pi\u00e8ge trumpiste. Le politologue russe <a href=\"https:\/\/usa.news-pravda.com\/world\/2025\/02\/28\/166476.html\">Mikhail Pavlov<\/a> donne une version plus sophistiqu\u00e9e : en  fait, Zelenski s&rsquo;est suicid\u00e9 (tout le monde est d&rsquo;accord), mais pour mieux rena&icirc;tre&#8230; En 2026, lorsque Trump aura \u00e9t\u00e9 r\u00e9duit par ses erreurs, et gr\u00e2ce au soutien des Britanniques qui restent les inalt\u00e9rables boutefeus et producteurs de haine antirusse dans cette affaire (cette donn\u00e9e-l\u00e0 est loin d&rsquo;\u00eatre fausse).<\/p>\n<\/p>\n<p><p>Donc, il y a \u00ab\u00a0Plan B\u00a0\u00bb, \u00e9labor\u00e9 en d\u00e9cembre 2024 par Zelenski et les Britanniques, selon Mikhail Pavlov. Il commence par cet avertissement expliquant qu&rsquo;il n&rsquo;est nullement surpris par ce qui s&rsquo;est pass\u00e9, et qu&rsquo;en qualifiant ce segment d&rsquo;&laquo; <em>excellente \u00e9mission de t\u00e9l\u00e9vision<\/em> &raquo;, Trump est plus proche de la v\u00e9rit\u00e9 qu&rsquo;il ne le croit :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Pavlov pense qu&rsquo;en fait, il n&rsquo;y a rien de surprenant dans ce qui s&rsquo;est pass\u00e9. Le politologue a rappel\u00e9 que Zelenski est avant tout un acteur, un ma&icirc;tre du genre conversationnel, et non un politicien<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Pavlov affirme que Zelenski et les gens de son cabinet sont en constant contact avec les Britanniques depuis d\u00e9cembre 2024, parce qu&rsquo;alors, m\u00eame avant l&rsquo;investiture du pr\u00e9sident et ses premi\u00e8res d\u00e9clarations, Zelenski avait admis que rien ne serait possible avec lui.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Avec les Britanniques, un ensemble de mesures a \u00e9t\u00e9 \u00e9labor\u00e9. Le 4 d\u00e9cembre, <\/em>[le chef de cabinet de Z.]<em> Ermak a rencontr\u00e9 le vice-pr\u00e9sident am\u00e9ricain Jay D. Vance \u00e0 Washington, puis il s&rsquo;est envol\u00e9 directement pour Londres. Formellement, il a assist\u00e9 \u00e0 un \u00e9v\u00e9nement au minist\u00e8re des Affaires \u00e9trang\u00e8res de l\u00e0-bas. Mais, en fait, il a rencontr\u00e9 un conseiller \u00e0 la s\u00e9curit\u00e9. Et ils ont discut\u00e9 du \u00ab\u00a0Plan B\u00a0\u00bb, dit le politologue.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le \u00ab\u00a0Plan B\u00a0\u00bb est le suivant. Il est peu probable que Zelenski attende le r\u00e9sultat des urnes. Peut-\u00eatre qu&rsquo;il d\u00e9missionnera, ou autre chose : il y a des options. Mais l&rsquo;histoire concerne pr\u00e9cis\u00e9ment la 26e ann\u00e9e du mill\u00e9naire, avec les \u00e9lections au Congr\u00e8s des &Eacute;tats-Unis. Comme le croient Zelenski et ses partisans, la majorit\u00e9 du Congr\u00e8s va changer et Trump sera beaucoup plus faible.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>D&rsquo;autre part, on suppose que quel que soit le gouvernement qui viendra en Ukraine, il aura d&rsquo;\u00e9normes probl\u00e8mes. Le pays est d\u00e9truit, tout comme l&rsquo;\u00e9conomie. Par cons\u00e9quent, tout gouvernement fera faillite.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Et l&rsquo;id\u00e9e est que Zelenski se rende \u00e0 Londres, y formant, relativement parlant, encore une fois, selon les mod\u00e8les britanniques, un cabinet fant\u00f4me de ministres. Et il commencera \u00e0 critiquer tout ce qui se passe en Ukraine, pour y revenir triomphalement<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On comprend qu&rsquo;il faut vivre d&rsquo;espoir et que Zelenski reste malgr\u00e9 tout la meilleure carte, ou plut\u00f4t la seule carte des antiTrump en Ukraine et contre les Russes. Ce jugement contredit celui de Trump qui affirme \u00e0 Zelenski n&rsquo;a aucune carte en main. (\u00ab\u00a0Si, moi !\u00a0\u00bb, a pens\u00e9 Zelenski en insultant tout bas JD Vance.)<\/p>\n<\/p>\n<p><p>L&rsquo;id\u00e9e d&rsquo;un Trump perdant ses moyens d&rsquo;action en 2026 est du pur arch\u00e9o-globalisme, se r\u00e9f\u00e9rant aux rythmes de la politique US du temps de la stabilit\u00e9 du Syst\u00e8me et du &lsquo;<em>DeepState<\/em>&lsquo;. Parvenir \u00e0 faire des plans pour le 18 juin 2026 (la date est choisie, cela est s&ucirc;r, c&rsquo;est m\u00eame ce choix qui pr\u00e9cipitera le d\u00e9clin de Trump) est une id\u00e9e tr\u00e8s-lunatique de la part des globalistes en d\u00e9route.C&rsquo;est aussi une grande d\u00e9monstration de la finesse politique des Europ\u00e9ens qui ont unanimement soutenu Mister Z.<\/p>\n<\/p>\n<p><p>Pour nous, c&rsquo;est une \u00e9vidence, la seule certitude nous est venu du ma&icirc;tre en r\u00e9alisation des s\u00e9ries t\u00e9l\u00e9vis\u00e9es qu&rsquo;est le pr\u00e9sident Trump :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ce fut une excellente \u00e9mission de t\u00e9l\u00e9vision<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Mis en ligne le 1<sup>Er<\/sup> mars 2025 \u00e0 17H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 18 juin (2026) de Mister Z. &bull; Difficile, on en conviendra, de ne pas parler de l&rsquo;\u00e9tonnante rencontre t\u00e9l\u00e9vis\u00e9e entre Zelenski et la direction US (bien autant Vance, &ndash; excellent en tous points, &ndash; que Trump). &bull; D&rsquo;ailleurs, les derniers mots du pr\u00e9sident des &Eacute;tats-Unis, qui est un excellent sp\u00e9cialiste de la t\u00e9l\u00e9-r\u00e9alit\u00e9, nous&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2600,11563,13395,2639,2601,2829],"class_list":["post-81465","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-jd","tag-pascal","tag-tele-realite","tag-trump","tag-vance","tag-zelenski"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81465"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81465\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}