{"id":81526,"date":"2025-04-17T17:15:47","date_gmt":"2025-04-17T17:15:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/04\/17\/rencontre-avec-lotan-zombie\/"},"modified":"2025-04-17T17:15:47","modified_gmt":"2025-04-17T17:15:47","slug":"rencontre-avec-lotan-zombie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/04\/17\/rencontre-avec-lotan-zombie\/","title":{"rendered":"Rencontre avec l&rsquo;OTAN-zombie"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Rencontre avec l&rsquo;OTAN-zombie<\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Une remarquable interview d&rsquo;un esprit remarquable, celui du contre-amiral turc (\u00e0 la retraite) Cem Gurdeniz. &bull; Il d\u00e9crit l&rsquo;effondrement US et  la r\u00e9duction au zombie de ce qu&rsquo;elle fut de l&rsquo;OTAN sans les USA.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>17 avril 2025 (17H20) &ndash; On s&rsquo;arr\u00eate longuement \u00e0 une interview qu&rsquo;un contre-amiral turc hors du service, et devenu un \u00e9minent commentateur en m\u00eame temps qu&rsquo;un promoteur de sa doctrine dite &lsquo;<em><a href=\"https:\/\/thecradle.co\/articles-id\/28676\">Blue Homeland<\/a><\/em>&lsquo;. Il s&rsquo;agit du contre-amiral Cem Gurdeniz, que nous d\u00e9signerons comme \u00ab\u00a0amiral\u00a0\u00bb comme c&rsquo;est la coutume dans les marines militaires. &lsquo;<em><a href=\"https:\/\/www.zerohedge.com\/geopolitical\/turkish-admiral-nato-has-become-reckless-zombie-alliance\">ZeroHedge.com<\/a><\/em>, qui a rep\u00e9r\u00e9 l&rsquo;interview que Gurdeniz a donn\u00e9 \u00e0 la publication libanaise &lsquo;<em><a href=\"https:\/\/thecradle.co\/articles\/blue-homeland-architect-warns-nato-has-failed-and-the-eu-wants-turkiye-on-its-knees\">The Castle<\/a><\/em>&lsquo;, par l&rsquo;interm\u00e9diaire d&rsquo;un journaliste turc c\u00e9l\u00e8bre dans son pays, <a href=\"https:\/\/x.com\/ceydak\">Ceyda Karan<\/a>, fait la pr\u00e9sentation suivante :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Le contre-amiral \u00e0 la retraite Cem Gurdeniz est l&rsquo;architecte de la doctrine maritime de la &lsquo;Blue Homeland&rsquo; et demeure un \u00e9minent commentateur g\u00e9opolitique de la soci\u00e9t\u00e9 turque et de la r\u00e9gion. &lsquo;Blue Homeland&rsquo; symbolise les revendications maritimes \u00e9largies d&rsquo;Ankara en M\u00e9diterran\u00e9e orientale ces derni\u00e8res ann\u00e9es.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce concept controvers\u00e9 inclut les eaux entourant l&rsquo;int\u00e9gralit\u00e9 de Chypre, &Eacute;tat membre de l&rsquo;UE (en raison de l&rsquo;occupation turque du nord de Chypre pendant des d\u00e9cennies), ce qui donne \u00e0 la Turquie acc\u00e8s \u00e0 d&rsquo;importants gisements de gaz naturel. Ces revendications ont raviv\u00e9 le bras de fer g\u00e9opolitique de longue date entre la Turquie et la Gr\u00e8ce et Chypre, l&rsquo;UE soutenant leur argument selon lequel la Turquie viole leur souverainet\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>La doctrine de la &lsquo;Blue Homeland&rsquo; a ainsi dress\u00e9 les puissances de l&rsquo;OTAN les unes contre les autres, la Turquie poss\u00e9dant la deuxi\u00e8me plus grande arm\u00e9e au sein de l&rsquo;Alliance. Le pays reste une source d&rsquo;irritation pour l&rsquo;Alliance, \u00e9tant en d\u00e9saccord avec les &Eacute;tats-Unis sur de nombreux fronts, notamment la politique dans le nord de la Syrie et la question kurde<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais ce ne sont pas ces affaires r\u00e9gionales ni m\u00eame intra-OTAN qui nous int\u00e9resse, mais bien la remarquable interview de l&rsquo;amiral Gurdeniz qui embrasse tous les probl\u00e8mes de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> par rapport \u00e0 l&rsquo;OTAN et au basculement civilisationnel que nous connaissons actuellement, &ndash; \u00ab\u00a0suite \u00e0 l&rsquo;\u00e9lection de Trump\u00a0\u00bb, pourrait-on interroger ? Justement, comme nous avons coutume de le faire, nous ne donnerons pas cette r\u00e9ponse qui ferait de Trump un <em>deus ex machina <\/em>qu&rsquo;il n&rsquo;est certainement pas. Ainsi, nous ne pouvons qu&rsquo;applaudir \u00e0 la r\u00e9ponse que donne Gurdeniz \u00e0 cette question :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Trump n&rsquo;est pas l&rsquo;architecte de cet effondrement ; il en est le produit. Lui et son \u00e9quipe comprennent que le mod\u00e8le post-1945 ne sert plus les int\u00e9r\u00eats des &Eacute;tats-Unis. Le secteur manufacturier est d\u00e9vast\u00e9. La dette a atteint 34 000 milliards de dollars<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Pour le reste, l&rsquo;amiral expose avec une pr\u00e9cision remarquable son \u00e9valuation de la crise transatlantique actuelle, et notamment du processus d&rsquo;effondrement de la puissance des USA. Il s&rsquo;ensuit \u00e9videmment que l&rsquo;OTAN est devenue une \u00ab\u00a0OTAN-zombie\u00a0\u00bb, sans aucune capacit\u00e9, exactement comme <a href=\"https:\/\/www.dedefensa.org\/article\/ah-dieu-que-les-plans-sont-jolis\">le colonel McGregor la d\u00e9crivait<\/a>.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;OTAN est d\u00e9sormais une alliance zombie. Elle existe davantage comme un mythe que comme un bloc militaire fonctionnel. Son expansion a \u00e9t\u00e9 inconsid\u00e9r\u00e9e. Ses op\u00e9rations &ndash; des Balkans \u00e0 la Libye en passant par l&rsquo;Ukraine &ndash; ont d\u00e9stabilis\u00e9 des r\u00e9gions enti\u00e8res et sa cr\u00e9dibilit\u00e9 s&rsquo;effondre.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;UE, quant \u00e0 elle, promeut une restructuration militaire de 800 milliards d&rsquo;euros (environ 864 milliards de dollars) sous le nom de \u00ab\u00a0R\u00e9armer l&rsquo;Europe\u00a0\u00bb. Mais cela n\u00e9cessite une aust\u00e9rit\u00e9 massive sur son territoire. Les gouvernements europ\u00e9ens pr\u00e9parent leurs populations \u00e0 la guerre, et non \u00e0 la paix. Ils ont besoin d&rsquo;ennemis pour justifier ces d\u00e9penses.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Mais sans le leadership am\u00e9ricain, l&rsquo;OTAN ne peut survivre en tant que structure coh\u00e9rente. L&rsquo;Am\u00e9rique de Trump ne combattra pas pour l&rsquo;Estonie et n&rsquo;enverra pas de troupes en Moldavie. L&rsquo;Europe devra se d\u00e9fendre &ndash; et elle n&rsquo;est pas pr\u00eate<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Toutes ces reprises et citations de &lsquo;<em>ZeroHedge.com<\/em>&lsquo; sont accompagn\u00e9es du commentaire suivant&#8230; Il faut le laisser \u00e0 l&rsquo;appr\u00e9ciation des valses d&rsquo;\u00e9toiles, de g\u00e9n\u00e9raux et d&rsquo;amiraux, qui constellent les couloirs du commandement supr\u00eame SHAPE, \u00e0 Mons, en Belgique.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>On ne s&rsquo;attendrait pas \u00e0 un commentaire aussi cinglant de la part d&rsquo;un amiral d&rsquo;un pays de l&rsquo;OTAN, mais cela est un peu moins surprenant<\/em> <em>venant de quelqu&rsquo;un qui a fait carri\u00e8re dans l&rsquo;arm\u00e9e turque.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Ce qui nous ram\u00e8ne irr\u00e9sistiblement, pour ceux qui ont quelque m\u00e9moire, <a href=\"https:\/\/www.dedefensa.org\/article\/evidences-cachees-contradictoires-et-irresistibles\">\u00e0 un propos<\/a> de l&rsquo;ambassadeur russe \u00e0 l&rsquo;OTAN Dimitri Rogozine, &ndash; en ce temps-l\u00e0, il y avait un ambassadeur russe, &ndash; le 28 juillet 2008&#8230; Certes, les aspects structurels et supra-humains ont pu \u00eatre appr\u00e9ci\u00e9s diff\u00e9remment depuis, mais il y a bien un sch\u00e9ma de l&#8217;emprisonnement des esprits, d&rsquo;une fa\u00e7on m\u00e9canique, chose qu&rsquo;a \u00e9videmment \u00e9vit\u00e9e l&rsquo;amiral turc.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;  <em>En pr\u00e9sentant la proposition Medvedev pour une nouvelle architecture paneurop\u00e9enne et transatlantique \u00e0 l&rsquo;OTAN le 28 juillet, l&rsquo;ambassadeur russe Dimitri Rogozine a employ\u00e9 le n\u00e9ologisme de \u00ab\u00a0technologisme\u00a0\u00bb pour qualifier certaines actions occidentales en Europe que les Russes critiquent, &ndash; que ce soit l&rsquo;\u00e9largissement de l&rsquo;OTAN ou le syst\u00e8me BMDE. Il faisait allusion \u00e0 une sorte de \u00ab\u00a0d\u00e9terminisme technologique\u00a0\u00bb qui serait le moteur caract\u00e9ristique de la \u00ab\u00a0politique\u00a0\u00bb occidentale, qui serait en fait la simple description d&rsquo;une situation o&ugrave; le syst\u00e8me, assemblage de \u00ab\u00a0syst\u00e8me de syst\u00e8mes\u00a0\u00bb plus ou moins humains ou bureaucratiques, dont les r\u00e9f\u00e9rences sont essentiellement technologiques, a bel et bien pris le pouvoir. La soi-disant politique est alors l&rsquo;entra&icirc;nement de la simple dynamique de son poids, investissant sans buts politiques les domaines qui l&rsquo;int\u00e9ressent. La d\u00e9finition est absolument acceptable; elle montre que les Russes, instruits par l&rsquo;exp\u00e9rience, comprennent bien des choses<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_______________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Interview du contre-amiral Cem Gurdeniz<\/strong><\/h2>\n<\/p>\n<p><p><strong><em>The Cradle<\/em><\/strong> : Avec le retour au pouvoir du pr\u00e9sident am\u00e9ricain Donald Trump et la guerre en Ukraine r\u00e9v\u00e9lant les faiblesses de l&rsquo;OTAN, comment comprendre la rupture de l&rsquo;ordre mondial dirig\u00e9 par l&rsquo;Occident ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : Nous assistons au deuxi\u00e8me grand effondrement de l&rsquo;ordre mondial de s\u00e9curit\u00e9 depuis la Seconde Guerre mondiale. Le premier est survenu apr\u00e8s 1990, lorsque l&rsquo;Union sovi\u00e9tique s&rsquo;est volontairement dissoute et que Washington a rapidement \u00e9tendu son influence en Europe de l&rsquo;Est. Mais aujourd&rsquo;hui, 80 ans apr\u00e8s la fin de cette guerre, les &Eacute;tats-Unis entament leur propre repli, d\u00e9pla\u00e7ant leur centre de gravit\u00e9 strat\u00e9gique de l&rsquo;Europe vers l&rsquo;Asie-Pacifique.<\/p>\n<\/p>\n<p><p>L&rsquo;administration Trump en est consciente. Sa strat\u00e9gie ne vise plus le contr\u00f4le mondial, mais le repli sur soi et la pr\u00e9paration \u00e0 une rivalit\u00e9 entre grandes puissances dans le Pacifique, notamment avec la Chine. Il ne s&rsquo;agit pas d&rsquo;un ajustement tactique, mais d&rsquo;un effondrement syst\u00e9mique. La d\u00e9faite de l&rsquo;OTAN en Ukraine n&rsquo;a pas \u00e9t\u00e9 une simple d\u00e9faite sur le champ de bataille, mais la fin d&rsquo;une illusion.<\/p>\n<\/p>\n<p><p><strong><em>The Cradle<\/em><\/strong> : Qu&rsquo;est-ce qui a bris\u00e9 le consensus post-Guerre froide port\u00e9 par les n\u00e9oconservateurs ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : L&rsquo;ordre post-1990 reposait sur l&rsquo;illusion de l&rsquo;unipolarit\u00e9. Les &Eacute;tats-Unis ont proclam\u00e9 la d\u00e9mocratie capitaliste lib\u00e9rale comme mod\u00e8le universel. Dans ce syst\u00e8me, l&rsquo;Occident contr\u00f4lait la finance, la Chine \u00e9tait charg\u00e9e de l&rsquo;industrie manufacturi\u00e8re et les &Eacute;tats riches en ressources naturelles \u00e9taient cens\u00e9s fournir l&rsquo;\u00e9nergie et les mati\u00e8res premi\u00e8res.<\/p>\n<\/p>\n<p><p>Mais ce mod\u00e8le s&rsquo;est heurt\u00e9 \u00e0 des contradictions fatales. La puissance militaire am\u00e9ricaine a \u00e9chou\u00e9 en Irak, en Libye et en Afghanistan. Au lieu d&rsquo;apporter la stabilit\u00e9, elle a apport\u00e9 la destruction. La Russie a repris ses droits militaires apr\u00e8s 2008. La Chine a connu une ascension \u00e9conomique et technologique, remettant en cause l&rsquo;h\u00e9g\u00e9monie occidentale.<\/p>\n<\/p>\n<p><p>Et ensemble, ils ont construit un contrepoids eurasien. Plus important encore, le Sud global a perc\u00e9 \u00e0 jour la fa\u00e7ade. Le g\u00e9nocide isra\u00e9lien \u00e0 Gaza, ouvertement soutenu par Washington, a an\u00e9anti toute l\u00e9gitimit\u00e9 restante. Le syst\u00e8me occidental est d\u00e9sormais expos\u00e9 : surendett\u00e9 \u00e9conomiquement, isol\u00e9 diplomatiquement et militairement vuln\u00e9rable.<\/p>\n<\/p>\n<p><p><strong><em>The Cradle<\/em><\/strong> : Comment interpr\u00e9tez-vous la position de l&rsquo;administration Trump face \u00e0 cet effondrement ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : Trump n&rsquo;est pas l&rsquo;architecte de cet effondrement ; il en est le produit. Lui et son \u00e9quipe comprennent que le mod\u00e8le post-1945 ne sert plus les int\u00e9r\u00eats des &Eacute;tats-Unis. Le secteur manufacturier est d\u00e9vast\u00e9. La dette a atteint 34 000 milliards de dollars.<\/p>\n<\/p>\n<p><p>Le dollar est contourn\u00e9 dans le commerce mondial. La puissance am\u00e9ricaine se contracte. Trump propose un repli d\u00e9guis\u00e9 en force. Il veut mettre fin aux errements de l&rsquo;Am\u00e9rique et se concentrer sur la restauration de l&rsquo;industrie nationale. Il sait que l&rsquo;OTAN est un fardeau, pas un atout. Son d\u00e9fi n&rsquo;est pas id\u00e9ologique, mais existentiel. Il veut maintenir l&#8217;empire am\u00e9ricain en vie en le r\u00e9duisant \u00e0 une taille soutenable.<\/p>\n<\/p>\n<p><p><strong><em>The Cradle<\/em><\/strong> : Quel est le sort de l&rsquo;OTAN dans cette \u00e9quation ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : L&rsquo;OTAN est d\u00e9sormais une alliance zombie. Elle existe davantage comme un mythe que comme un bloc militaire fonctionnel. Son expansion a \u00e9t\u00e9 inconsid\u00e9r\u00e9e. Ses op\u00e9rations &ndash; des Balkans \u00e0 la Libye en passant par l&rsquo;Ukraine &ndash; ont d\u00e9stabilis\u00e9 des r\u00e9gions enti\u00e8res et sa cr\u00e9dibilit\u00e9 s&rsquo;effondre.<\/p>\n<\/p>\n<p><p>L&rsquo;UE, quant \u00e0 elle, promeut une restructuration militaire de 800 milliards d&rsquo;euros (environ 864 milliards de dollars) sous le nom de &laquo; R\u00e9armer l&rsquo;Europe &raquo;. Mais cela n\u00e9cessite une aust\u00e9rit\u00e9 massive sur son territoire. Les gouvernements europ\u00e9ens pr\u00e9parent leurs populations \u00e0 la guerre, et non \u00e0 la paix. Ils ont besoin d&rsquo;ennemis pour justifier ces d\u00e9penses.<\/p>\n<\/p>\n<p><p>Mais sans le leadership am\u00e9ricain, l&rsquo;OTAN ne peut survivre en tant que structure coh\u00e9rente. L&rsquo;Am\u00e9rique de Trump ne combattra pas pour l&rsquo;Estonie et n&rsquo;enverra pas de troupes en Moldavie. L&rsquo;Europe devra se d\u00e9fendre &ndash; et elle n&rsquo;est pas pr\u00eate.<\/p>\n<\/p>\n<p><p><strong><em>The Cradle<\/em><\/strong> : Le monde \u00e9volue-t-il r\u00e9ellement vers un ordre multipolaire &ndash; ou est-ce encore pr\u00e9matur\u00e9 ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : La transition est r\u00e9elle et irr\u00e9versible. Les BRICS se d\u00e9veloppent. L&rsquo;Organisation de coop\u00e9ration de Shanghai s&rsquo;\u00e9tend. Les \u00e9changes commerciaux s&rsquo;\u00e9loignent du dollar. Des puissances r\u00e9gionales comme l&rsquo;Iran, l&rsquo;Inde, le Br\u00e9sil et la Turquie s&rsquo;affirment. Il ne s&rsquo;agit pas d&rsquo;un retour aux blocs de la Guerre froide. Il s&rsquo;agit d&rsquo;un r\u00e9\u00e9quilibrage &ndash; un monde o&ugrave; aucun centre ne domine.<\/p>\n<\/p>\n<p><p>La multipolarit\u00e9 n&rsquo;est pas une utopie. C&rsquo;est une question de souverainet\u00e9. Elle permet aux nations de s&rsquo;aligner sur la base de leurs int\u00e9r\u00eats, et non de la coercition. Le d\u00e9fi consiste d\u00e9sormais \u00e0 b\u00e2tir des institutions qui refl\u00e8tent cette r\u00e9alit\u00e9 : de nouveaux syst\u00e8mes commerciaux, des cadres de s\u00e9curit\u00e9 et des banques de d\u00e9veloppement non contr\u00f4l\u00e9s par l&rsquo;Occident.<\/p>\n<\/p>\n<p><\/p>\n<p><strong><em>The Cradle <\/em><\/strong>: Vous d\u00e9fendez depuis longtemps la doctrine maritime de la &lsquo;<em>Blue Homeland<\/em>&lsquo;. Comment cela s&rsquo;inscrit-il dans l&rsquo;avenir de la Turquie en Eurasie ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : &lsquo;<em>Blue Homeland<\/em>&lsquo; n&rsquo;est pas un slogan, c&rsquo;est notre imp\u00e9ratif g\u00e9opolitique. La Turquie est entour\u00e9e d&rsquo;eaux contest\u00e9es : la mer &Eacute;g\u00e9e, la M\u00e9diterran\u00e9e orientale et la mer Noire. Si nous c\u00e9dons ces espaces, nous deviendrons enclav\u00e9s et sans importance.<\/p>\n<\/p>\n<p><p>Les puissances occidentales, notamment la Gr\u00e8ce et Chypre, veulent nous pi\u00e9ger en Anatolie. La Carte de S\u00e9ville, soutenue par l&rsquo;UE, r\u00e9duirait notre espace maritime de 90 %. C&rsquo;est une condamnation \u00e0 mort g\u00e9opolitique.<\/p>\n<\/p>\n<p><p>&lsquo;<em>Blue Homeland<\/em>&lsquo; affirme nos droits, notre pr\u00e9sence navale et nos int\u00e9r\u00eats \u00e9nerg\u00e9tiques. Associ\u00e9e au Corridor central, qui nous relie \u00e0 l&rsquo;Asie centrale et \u00e0 la Chine, nous formons un axe continental-maritime. C&rsquo;est l&rsquo;\u00e9pine dorsale de la strat\u00e9gie de la Turquie pour le XXIe si\u00e8cle.<\/p>\n<\/p>\n<p><\/p>\n<p><strong><em>The Cradle<\/em><\/strong> : Quelle est votre \u00e9valuation de l&rsquo;orientation \u00e9conomique de la Turquie dans ce nouvel ordre mondial ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : Nous devons abandonner l&rsquo;illusion que les investissements directs \u00e9trangers et l&rsquo;int\u00e9gration \u00e0 l&rsquo;UE nous sauveront. Ce mod\u00e8le a \u00e9chou\u00e9. Il a engendr\u00e9 dettes, privatisations et d\u00e9pendance. Notre \u00e9conomie doit \u00eatre fond\u00e9e sur la production, et non sur la sp\u00e9culation.<\/p>\n<\/p>\n<p><p>Cela implique la r\u00e9industrialisation, la souverainet\u00e9 alimentaire et \u00e9nerg\u00e9tique, et le commerce r\u00e9gional en monnaies locales. Nous devons prot\u00e9ger les secteurs strat\u00e9giques de la propri\u00e9t\u00e9 \u00e9trang\u00e8re. Notre Banque centrale doit \u00eatre ind\u00e9pendante non seulement du gouvernement, mais aussi de toute influence \u00e9trang\u00e8re.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est qu&rsquo;\u00e0 ce moment-l\u00e0 que nous pourrons parler de souverainet\u00e9 \u00e9conomique.<\/p>\n<\/p>\n<p><\/p>\n<p><strong><em>The Cradle<\/em><\/strong> : Qu&rsquo;en est-il de la diplomatie ? La Turquie doit-elle s&rsquo;aligner sur un bloc particulier ou privil\u00e9gier le non-alignement ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : Nous devons privil\u00e9gier ce que j&rsquo;appelle le &laquo; non-alignement affirm\u00e9 &raquo;. Cela signifie refuser d&rsquo;\u00eatre le satellite de qui que ce soit. Nous gardons nos options ouvertes. Nous coop\u00e9rons avec la Russie, la Chine et les pays du Sud, mais nous nous engageons \u00e9galement avec l&rsquo;Europe et les &Eacute;tats-Unis lorsque nos int\u00e9r\u00eats convergent.<\/p>\n<\/p>\n<p><p>Mais il existe des lignes rouges. Nous ne participerons pas aux r\u00e9gimes de sanctions contre nos voisins. Nous n&rsquo;h\u00e9bergerons pas de bases \u00e9trang\u00e8res ciblant d&rsquo;autres &Eacute;tats. Et nous ne nous laisserons pas entra&icirc;ner dans les guerres d\u00e9faillantes de l&rsquo;OTAN.<\/p>\n<\/p>\n<p><p>Notre diplomatie doit servir notre g\u00e9ographie : \u00e9quilibr\u00e9e, ferme et souveraine.<\/p>\n<\/p>\n<p><\/p>\n<p><strong><em>The Cradle <\/em><\/strong>: L&rsquo;UE se pr\u00e9sente comme un projet &laquo; fond\u00e9 sur des valeurs &raquo;. Que r\u00e9pondez-vous \u00e0 cette affirmation ?<\/p>\n<\/p>\n<p><p><strong>Amiral Cem Gurdeniz<\/strong> : Les valeurs de l&rsquo;UE sont s\u00e9lectives. Concernant les droits maritimes de la Turquie, elle soutient le maximalisme grec. Concernant la Palestine, elle reste muette. Concernant les crimes d&rsquo;Isra\u00ebl, elle parle de &laquo; l\u00e9gitime d\u00e9fense &raquo;.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas de valeurs, mais de puissance. L&rsquo;UE veut que la Turquie soit une zone tampon, un entrep\u00f4t de r\u00e9fugi\u00e9s et une source de main-d&rsquo;&oelig;uvre bon march\u00e9. Elle ne nous acceptera jamais comme ses \u00e9gaux. Et nous ne devrions pas vouloir rejoindre un tel club.<\/p>\n<\/p>\n<p><p>Notre dignit\u00e9 n&rsquo;est pas \u00e0 vendre.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rencontre avec l&rsquo;OTAN-zombie &bull; Une remarquable interview d&rsquo;un esprit remarquable, celui du contre-amiral turc (\u00e0 la retraite) Cem Gurdeniz. &bull; Il d\u00e9crit l&rsquo;effondrement US et la r\u00e9duction au zombie de ce qu&rsquo;elle fut de l&rsquo;OTAN sans les USA. _________________________ 17 avril 2025 (17H20) &ndash; On s&rsquo;arr\u00eate longuement \u00e0 une interview qu&rsquo;un contre-amiral turc hors du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2610,2611,2612,2614,2613],"class_list":["post-81526","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-amiral","tag-cem","tag-gurdeniz","tag-rogozine","tag-turquie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81526"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81526\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}