{"id":81529,"date":"2025-04-19T16:59:42","date_gmt":"2025-04-19T16:59:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/04\/19\/de-quel-cote-le-destin\/"},"modified":"2025-04-19T16:59:42","modified_gmt":"2025-04-19T16:59:42","slug":"de-quel-cote-le-destin","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/04\/19\/de-quel-cote-le-destin\/","title":{"rendered":"De quel c\u00f4t\u00e9 le destin\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>De quel c\u00f4t\u00e9 le destin ?<\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>&bull; Un autre texte sur la mort de la globalisation, d\u00e9sormais largement autopsi\u00e9e et authentifi\u00e9e. &bull; L&rsquo;\u00e9v\u00e9nement m\u00e9rite de servir de cimier \u00e0 tous nos commentaires et recherches concernant ce qui vient vers nous.<\/p>\n<\/p>\n<p><p>______________________<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>19 avril 2025 (17H00) &ndash; Il est vrai, et il doit \u00eatre compr\u00e9hensible, que malgr\u00e9 la pression extraordinaire de l&rsquo;actualit\u00e9 nous devons mettre l&rsquo;accent sur les interrogations, les r\u00e9flexions, les m\u00e9ditations sur l&rsquo;avenir \u00e9nigmatique qui nous est r\u00e9serv\u00e9. Il importe de quitter les rives du folklore complotiste comme disent les globalistes aux abois, aussi bien que les batailles sans fin ni profit sur la validit\u00e9 des d\u00e9tails d&rsquo;une pseudo-<em>fakenews. <\/em>Il est temps d&rsquo;abandonner les duels sans fin, sans foi ni loi, sans grandeur ni honneur, des id\u00e9ologistes dogmatiques et manich\u00e9ens. Il est vital de cesser de s&rsquo;aventurer dans les folles galopades des sables mouvants des <em>narrative <\/em>et des simulacres, f&ucirc;t-ce pour les pourfendre et pour les d\u00e9truire.<\/p>\n<\/p>\n<p><p>Comme \u00e9crit l&rsquo;auteur Mario Bozzi Sentieri, encore un Italien, dans ce texte qui nous offre une autre version de l&rsquo;enterrement de la globalisation (et <a href=\"https:\/\/www.dedefensa.org\/article\/globalisation-mondialisation-1\">non de la mondialisation<\/a>, &ndash; une fois encore, j&rsquo;y reviendrai), &ndash; comme il l&rsquo;\u00e9crit, nous le ressentons nous-m\u00eame \u00e0 chaque instant :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La partie est encore \u00e0 jouer<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>En \u00eatre conscient est le premier pas, tout en gardant \u00e0 l&rsquo;esprit, face \u00e0 la fin du globalisme id\u00e9ologique, la n\u00e9cessit\u00e9 d&rsquo;un nouveau finalisme, politique, social et culturel, qui ne peut na&icirc;tre que d&rsquo;une s\u00e9rie de questions \u00ab\u00a0de base\u00a0\u00bb.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>&Agrave; quel mod\u00e8le socio-\u00e9conomique, une fois les anciennes r\u00e9f\u00e9rences disparues, faudra-t-il se r\u00e9f\u00e9rer ? Selon quelle vision g\u00e9opolitique ? Vers o&ugrave; regarder ? Travailler pour quelles alliances ?<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il est vrai que le dernier espoir de nous entra&icirc;ner vers le n\u00e9ant, eux les globalistes qui sont en fait <em>volens nolens <\/em>les messagers du Diable et qui sont \u00e9cras\u00e9s par l&rsquo;effondrement de leur simulacre, est bien de nous enferrailler dans des combats o&ugrave; ils sont perdus d&rsquo;avance mais o&ugrave; leur victoire est de nous faire croire qu&rsquo;il faut encore les embrocher pour les prendre au s\u00e9rieux. D&rsquo;o&ugrave; la difficult\u00e9 du commentateur de poursuivre sa t\u00e2che r\u00e9p\u00e9titive de faire tomber son masque au Diable chaque fois que l&rsquo;autre le remet. Mais qu&rsquo;il sache bien, le commentateur, &ndash; j&rsquo;en sais quelque chose dans toutes mes convictions, &ndash; que cette bataille qui est celle de l&rsquo;esquive du pi\u00e8ge est conduite de tous temps depuis l&rsquo;\u00e9ternit\u00e9 car cet enjeu (\u00ab\u00a0le pi\u00e8ge\u00a0\u00bb) est celui-l\u00e0 m\u00eame qui est tendu \u00e0 toute entreprise civilisatrice, \u00e0 toute justification de l&rsquo;existence.<\/p>\n<\/p>\n<p><p>Ainsi doit-on suivre une fois de plus un auteur, Mario Bozzi Sentieri, qui nous propose une r\u00e9flexion interrogative sur notre destin\u00e9e, en \u00e9cartant comme \u00e9vidents le sens des batailles en cours et les arguments qui soutiennent ce sens. Cette fois, c&rsquo;est-\u00e0-dire une fois de plus, il s&rsquo;agit donc de l&rsquo;enterrement de la globalisation, un des plus \u00e9normes et grossiers, un des plus r\u00e9cents pi\u00e8ges que l&rsquo;Ange Noirs nous ait tendu. &Eacute;tant d&rsquo;ailleurs d\u00e9chu, il finit par d\u00e9choir dans sa puissance et par cons\u00e9quent dans notre estime de sa puissance, satisfaisant ainsi une des maximes tant de fois r\u00e9p\u00e9t\u00e9e par nous (l\u00e0 aussi, l&rsquo;art r\u00e9p\u00e9titif), d&rsquo;une profonde sagesse, de Ren\u00e9 Gu\u00e9non :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>L&rsquo;on dit m\u00eame que le diable, quand il veut, est fort bon th\u00e9ologien ; il est vrai, pourtant, qu&rsquo;il ne peut s&#8217;emp\u00eacher de laisser \u00e9chapper toujours <strong>quelque <\/strong><\/em><strong>[b\u00eatise]<\/strong><em>, qui est comme sa signature&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le texte original de Mario Bozzi Sentieri est \u00e9dit\u00e9 sur le site &lsquo;<em><a href=\"https:\/\/www.barbadillo.it\/120771-il-tramonto-del-globalis...\">barbadillo.it<\/a><\/em>&lsquo; ; en traduction et daptation fran\u00e7aises, sur le site &lsquo;<em><a href=\"http:\/\/euro-synergies.hautetfort.com\/archive\/2025\/04\/18\/le-crepuscule-du-mondialisme-et-l-ecriture-de-nouveaux-equilibres.html\">euro-synergies.heutetfort.com<\/a><\/em>&lsquo;.<\/p>\n<\/p>\n<p><p><em>dde.org<\/em><\/p>\n<\/p>\n<p><p>_____________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Au-del\u00e0 du cr\u00e9puscule de la globalisation<\/strong><\/h2>\n<\/p>\n<blockquote>\n<p><p>Le cr\u00e9puscule du globalisme et l&rsquo;\u00e9criture de nouveaux \u00e9quilibres<\/p>\n<p>La lin\u00e9arit\u00e9 progressive d&rsquo;une globalisation inconditionnelle est aujourd&rsquo;hui en train de s&rsquo;estomper. Tout comme diminue l&rsquo;illusion de la \u00ab\u00a0fin de l&rsquo;Histoire\u00a0\u00bb.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La d\u00e9globalisation n&rsquo;est plus un tabou. Entre de nombreux arr\u00eats et red\u00e9marrages, annonces, espoirs et peurs, le fait nouveau qu&rsquo;est la guerre des tarifs nous confronte au grand th\u00e8me de la fin d&rsquo;un cycle, celui de la globalisation, et de son v\u00e9ritable d\u00e9passement. Tout doit \u00eatre repens\u00e9 et discut\u00e9, et pas seulement sur la base des actions lanc\u00e9es par Trump. En effet, les initiatives du pr\u00e9sident am\u00e9ricain ne doivent pas \u00eatre consid\u00e9r\u00e9es comme la cause des tensions sur les march\u00e9s, de la finance et des relations commerciales entre les &Eacute;tats, mais plut\u00f4t comme l&rsquo;effet d&rsquo;une crise plus profonde et subtile, qui dure depuis des ann\u00e9es et qui a maintenant \u00e9clat\u00e9 comme un bubon arriv\u00e9 \u00e0 maturation.<\/p>\n<\/p>\n<p><p>Il y avait d\u00e9j\u00e0 eu quelques signaux dans les ann\u00e9es pr\u00e9c\u00e9dentes, \u00e0 la suite de la d\u00e9t\u00e9rioration, durant l&rsquo;urgence Covid, des cha&icirc;nes d&rsquo;approvisionnement mondiales, de la comp\u00e9tition pour les mati\u00e8res premi\u00e8res et du reshoring, c&rsquo;est-\u00e0-dire du retour des productions industrielles dans les pays d&rsquo;origine des entreprises.<\/p>\n<\/p>\n<p><p>La lin\u00e9arit\u00e9 progressive d&rsquo;une globalisation inconditionnelle est aujourd&rsquo;hui en train de s&rsquo;estomper. De m\u00eame que diminue l&rsquo;illusion de la &quot;fin de l&rsquo;Histoire&quot;, th\u00e9oris\u00e9e en 1989 par Francis Fukuyama suite \u00e0 la chute du mur de Berlin, au point qu&rsquo;il imaginait un monde pleinement pacifi\u00e9 et &quot;int\u00e9gr\u00e9&quot;, sous l&rsquo;\u00e9gide de la r\u00e9volution technologique, du triomphe du capitalisme et du nouvel ordre lib\u00e9ral-d\u00e9mocratique.<\/p>\n<\/p>\n<p><p>Comme l&rsquo;a soulign\u00e9 Aldo Di Lello (&quot;Ascension et d\u00e9clin de la globalisation&quot;, dans l&rsquo;ouvrage collectif intitul\u00e9 &quot;Souverainisme &#8211; Les racines et le projet&quot;, Giubilei Regnani 2019), &quot;la globalisation ne d\u00e9coule pas tant de processus \u00e9conomiques que de choix politiques, en ce sens qu&rsquo;elle est le r\u00e9sultat d&rsquo;une accumulation extraordinaire de pouvoir rendue possible par la complaisance des gouvernements et des parlements d&rsquo;Europe et d&rsquo;Am\u00e9rique&quot;. Avec pour r\u00e9sultat &ndash; \u00e0 l&rsquo;\u00e9preuve des faits &ndash; de polariser les richesses (\u00e0 l&rsquo;int\u00e9rieur des &Eacute;tats et entre eux), de construire de v\u00e9ritables monopoles de production (concentr\u00e9s dans les soi-disant pays \u00e9mergents, gr\u00e2ce \u00e0 une main-d&rsquo;&oelig;uvre \u00e0 bas co&ucirc;t), de d\u00e9manteler les classes moyennes (favorisant l&rsquo;expansion de nouvelles formes de pr\u00e9carit\u00e9 et de prol\u00e9tarisation).<\/p>\n<\/p>\n<p><p>Les acc\u00e9l\u00e9rations de Trump en mati\u00e8re de tarifs s&rsquo;inscrivent dans ce contexte.<\/p>\n<\/p>\n<p><p>Au fond, il ne s&rsquo;agit pas tant (ou pas seulement) de pr\u00e9figurer une possible sortie de l&rsquo;imbroglio (face \u00e0 un d\u00e9ficit am\u00e9ricain d&rsquo;environ 1200 milliards de dollars et donc \u00e0 la n\u00e9cessit\u00e9 de &quot;remplir les caisses&quot;) que surtout de favoriser les entreprises qui produisent aux &Eacute;tats-Unis, en encourageant le retour des productions sur le territoire national.<\/p>\n<\/p>\n<p><p>Le fait certain &ndash; \u00e0 la lumi\u00e8re de ces indications sommaires &ndash; est que nous sommes tomb\u00e9s dans un futur inattendu, qui change les perspectives. La partie est encore \u00e0 jouer. C&rsquo;est l\u00e0 le grand d\u00e9fi de la culture, des institutions repr\u00e9sentatives et du monde du travail. C&rsquo;est ici que se joue le d\u00e9fi de l&rsquo;avenir. En \u00eatre conscient est le premier pas, tout en gardant \u00e0 l&rsquo;esprit, face \u00e0 la fin du globalisme id\u00e9ologique, la n\u00e9cessit\u00e9 d&rsquo;un nouveau finalisme, politique, social et culturel, qui ne peut na&icirc;tre que d&rsquo;une s\u00e9rie de questions &quot;de base&quot;.<\/p>\n<\/p>\n<p><p>&Agrave; quel mod\u00e8le socio-\u00e9conomique, une fois les anciennes r\u00e9f\u00e9rences disparues, faudra-t-il se r\u00e9f\u00e9rer ? Selon quelle vision g\u00e9opolitique? Vers o&ugrave; regarder ? Travailler pour quelles alliances ?<\/p>\n<\/p>\n<p><p>Reviennent \u00e0 l&rsquo;esprit les analyses provocatrices mais lucides de Guillaume Faye, jeune repr\u00e9sentant de la Nouvelle Droite, qui, dans la premi\u00e8re moiti\u00e9 des ann\u00e9es 80, dans son petit ouvrage intitul\u00e9 Contre l&rsquo;\u00e9conomisme, pr\u00e9figurait d\u00e9j\u00e0 une \u00e9conomie non plus dans un cadre plan\u00e9taire et\/ou national, mais subcontinental, une \u00e9conomie organis\u00e9e en zones homog\u00e8nes du point de vue historique et culturel ; avec une Europe technologiquement \u00e0 la pointe, dans un syst\u00e8me de march\u00e9 intra-europ\u00e9en soumis aux principes du surplus, de la &quot;cr\u00e9ation mon\u00e9taire directe&quot;, de l&rsquo;autarcie des grands espaces ; avec &quot;un &Eacute;tat qui ne soit ni totalitaire, ni mercantile, ni paternaliste, ni socialisateur, qui laisse &lsquo;agir&rsquo; pleinement les forces cr\u00e9atives du march\u00e9, mais en leur assignant des limites bien d\u00e9finies, en bref, un &Eacute;tat qui ne fasse pas l&rsquo;\u00e9conomie, mais qui la dirige politiquement et juridiquement, mais plus sur un mode plus \u00e9conomique et plus social&quot;. Au centre, l&rsquo;id\u00e9e d&rsquo;un syst\u00e8me dans lequel les individus se sentent mobilis\u00e9s par des objectifs politiques, nationaux, collectifs, &quot;lyriques&quot;, etc. Du marxisme &ndash; disait Faye &ndash; je conserve l&rsquo;id\u00e9e de la planification, du lib\u00e9ralisme je conserve l&rsquo;id\u00e9e du march\u00e9 (qui ne lui appartient cependant pas en exclusivit\u00e9). &quot;Provocations&quot; d&rsquo;un jeune et transgressif intellectuel hors des sch\u00e9mas courants, d&rsquo;hier et d&rsquo;aujourd&rsquo;hui ? Peut-\u00eatre, mais dans un climat de stagnation id\u00e9ale et projectuelle (avec des gouvernements contraints d&rsquo;activer des interventions &quot;tampons&quot; plut\u00f4t que d&rsquo;imaginer des r\u00e9volutions \u00e9pocales), l&rsquo;espoir est que le temps des re-discussions &quot;globales&quot; arrive enfin, adapt\u00e9es au changement d&rsquo;\u00e9poque et marqu\u00e9es par un &quot;pragmatisme intelligent&quot; capable de se mesurer sans r\u00e9serve aux nouveaux sc\u00e9narios internationaux.<\/p>\n<\/p>\n<p><p>Dans le bouleversement des cartes de la globalisation, sous la pouss\u00e9e du protagonisme am\u00e9ricain, prendre acte que l&rsquo;Europe, aujourd&rsquo;hui, repr\u00e9sente l&rsquo;aire la plus faible et la plus expos\u00e9e aux vents de la crise signifie aller au-del\u00e0 des pol\u00e9miques contingentes et des interventions \u00e0 court terme. Pour prendre conscience des nouveaux \u00e9quilibres mondiaux et de la complexit\u00e9 des d\u00e9fis qui se profilent : g\u00e9opolitiques et productifs, \u00e9nerg\u00e9tiques et financiers, commerciaux et militaires. C&rsquo;est ici que se joue notre destin. En \u00eatre conscient est le premier pas pour activer les contre-mesures n\u00e9cessaires, \u00e9vitant d&rsquo;\u00eatre emport\u00e9s par une crise qui se pr\u00e9voit dramatique. Stimuler des d\u00e9bats (et des lectures inhabituelles de la r\u00e9alit\u00e9) en sortant enfin des sch\u00e9mas du vieux mondialisme, est un premier pas essentiel pour commencer \u00e0 construire les nouveaux \u00e9quilibres politiques et socio-\u00e9conomiques d&rsquo;un monde \u00e0 repenser, capable de faire face aux d\u00e9fis du changement.<\/p>\n<\/p>\n<p><h4>Mario Bozzi Sentieri<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De quel c\u00f4t\u00e9 le destin ? &bull; Un autre texte sur la mort de la globalisation, d\u00e9sormais largement autopsi\u00e9e et authentifi\u00e9e. &bull; L&rsquo;\u00e9v\u00e9nement m\u00e9rite de servir de cimier \u00e0 tous nos commentaires et recherches concernant ce qui vient vers nous. ______________________ 19 avril 2025 (17H00) &ndash; Il est vrai, et il doit \u00eatre compr\u00e9hensible, que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2636,2631,2630,2634,2632,2633,2622,2635,2637,2638,2639],"class_list":["post-81529","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-bozzi","tag-de","tag-enterrement","tag-faye","tag-globalisation","tag-guillaume","tag-la","tag-mario","tag-sentieri","tag-tarifs","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81529"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81529\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}