{"id":81604,"date":"2025-06-17T09:30:32","date_gmt":"2025-06-17T09:30:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/06\/17\/nietzsche-contre-le-fonctionnaire-de-lopinion\/"},"modified":"2025-06-17T09:30:32","modified_gmt":"2025-06-17T09:30:32","slug":"nietzsche-contre-le-fonctionnaire-de-lopinion","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/06\/17\/nietzsche-contre-le-fonctionnaire-de-lopinion\/","title":{"rendered":"Nietzsche contre le fonctionnaire de l&rsquo;opinion"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\"><strong>Nietzsche contre le fonctionnaire de l&rsquo;opinion<\/strong><\/h2>\n<\/p>\n<p><p>Stupide dix-neuvi\u00e8me si\u00e8cle : cette expression incorrecte de L\u00e9on Daudet, qui fait fi de dizaines de critiques g\u00e9niaux de la modernit\u00e9 tombe \u00e0 pic pour David Strauss, biographe du pauvre J\u00e9sus et inventeur du style journalistique teuton, style qui a le don d&rsquo;\u00e9nerver Nietzsche dans une de ses consid\u00e9rations inactuelles. Strauss incarne le cr\u00e9tin moderne avec son arrogance et sa l\u00e9g\u00e8ret\u00e9, sa chutzpah et sa vulgarit\u00e9.<\/p>\n<\/p>\n<p><p>Nietzsche, qui n&rsquo;est pas pr\u00e9cis\u00e9ment chr\u00e9tien, \u00e9crit sur cette mont\u00e9e de la &laquo; l\u00e9g\u00e8ret\u00e9 imb\u00e9cile &raquo; qui se moque par exemple du Christ et de la civilisation chr\u00e9tienne : <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>J\u00e9sus devrait \u00eatre pr\u00e9sent\u00e9 comme un exalt\u00e9 qui, de nos jours, \u00e9chapperait difficilement au cabanon, et l&rsquo;anecdote de la r\u00e9surrection du Christ m\u00e9riterait d&rsquo;\u00eatre qualifi\u00e9 de &laquo; charlatanisme historique &raquo;. &mdash;Laissons passer, pour une fois, tout cela pour y \u00e9tudier la fa\u00e7on particuli\u00e8re de courage dont Strauss, notre &laquo; philistin classique &raquo;, est capable<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Remarquons que Nerval \u00e9crivait la m\u00eame chose quarante ans avant : on enfermerait le Christ \u00e0 Bic\u00eatre. Et Nietzsche comme Nerval a fini \u00e0 l&rsquo;asile. Et d&rsquo;\u00e9voquer ce fameux philistin (Strauss toujours) qui manque de respect \u00e0 Schopenhauer :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>C&rsquo;est ainsi que David Strauss, un v\u00e9ritable satisfait en face de nos conditions de culture, un philistin-type, parle une fois, avec des tournures de phrases caract\u00e9ristiques, de la &laquo; philosophie d&rsquo;Arthur Schopenhauer, pleine d&rsquo;esprit, il est vrai, mais souvent malsaine et peu profitable &raquo;. Car une circonstance f\u00e2cheuse veut que ce soit surtout sur ce qui est &laquo; malsain et peu profitable &raquo; que &laquo; l&rsquo;esprit &raquo; aime \u00e0 descendre avec une particuli\u00e8re sympathie et que le philistin lui-m\u00eame, lorsqu&rsquo;il lui arrive d&rsquo;\u00eatre loyal envers lui-m\u00eame, \u00e9prouve en face des produits philosophiques que ses semblables mettent au jour quelque chose qui ressemble beaucoup \u00e0 du manque d&rsquo;esprit, bien que ce soit d&rsquo;une philosophie saine et profitable.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p> On voit aussi appara&icirc;tre le charabia de la langue. Nietzsche continue de se moquer de Strauss &ndash; qui est l&rsquo;auteur alors de bestsellers en Allemagne (c&rsquo;est le d\u00e9but du r\u00e9tr\u00e9cissement spirituel allemand pr\u00e9vu, constat\u00e9 plut\u00f4t par Goethe lors d&rsquo;un entretien avec Eckermann) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>&Agrave; vrai dire, il ne se pique pas v\u00e9ritablement, mais il se sert d&rsquo;un moyen plus violent encore qu&rsquo;il d\u00e9crit ainsi : &laquo; Nous ouvrons Schopenhauer qui frappe notre id\u00e9e au visage \u00e0 chaque occasion &raquo; (p. 143). Or, une id\u00e9e n&rsquo;ayant pas de visage &mdash; f&ucirc;t-elle m\u00eame l&rsquo;id\u00e9e de Strauss par rapport \u00e0 l&rsquo;univers &mdash; mais le visage pouvant tout au plus appartenir \u00e0 celui qui a l&rsquo;id\u00e9e, le proc\u00e9d\u00e9 se d\u00e9compose en plusieurs actions. Strauss ouvre Schopenhauer lequel le frappe&hellip; au visage. Alors Strauss &laquo; r\u00e9agit &raquo; dans un sens &laquo; religieux &raquo;, c&rsquo;est-\u00e0-dire qu&rsquo;il se met \u00e0 frapper \u00e0 son tour sur Schopenhauer, il se r\u00e9pand en injures, parle d&rsquo;absurdit\u00e9s, de blasph\u00e8mes, de sc\u00e9l\u00e9ratesses, d\u00e9clare m\u00eame que Schopenhauer n&rsquo;avait pas toute sa raison<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p> Strauss incarne selon Nietzsche notre descente aux enfers intellectuelle : le journalisme. Macron qui file un milliard ou presque \u00e0 la presse a instinctivement compris de quoi il en retourne : pour imposer l&rsquo;horreur, financer les journaux, ces &laquo; fonctionnaires de l&rsquo;opinion &raquo;. Le journalisme comme plus tard la t\u00e9l\u00e9 (cf. Godard ou Fellini alors) va recouvrir le monde:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Et, comme Strauss s&rsquo;entend bien \u00e0 employer les circonlocutions ! Que veut-il dire, quand il parle des \u00e9tudes historiques qui aident \u00e0 notre compr\u00e9hension de la situation politique, si ce n&rsquo;est ceci qu&rsquo;il recommande la lecture des journaux ? Et en parlant de notre participation vivante \u00e0 l&rsquo;\u00e9dification de l&rsquo;Etat allemand, entend-t-il autre chose que notre s\u00e9jour quotidien \u00e0 la brasserie ? Une promenade au jardin zoologique n&rsquo;est-elle pas le meilleur moyen vulgarisateur, par quoi nous \u00e9largissons notre connaissance de la nature ? Et enfin, le th\u00e9\u00e2tre et le concert o&ugrave; nous puisons &laquo; des stimulants pour notre imagination et notre humour &raquo; qui nous satisfont &laquo; d&rsquo;une fa\u00e7on parfaite &raquo;. Comme cela est dit avec esprit et dignit\u00e9 ! Voil\u00e0 notre homme ! car son ciel est notre ciel. C&rsquo;est ainsi que triomphe le philistin<\/em>&hellip; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nietzsche avec son coutumier &laquo; g\u00e9nie visionnaire &raquo; d\u00e9crit d\u00e9j\u00e0 la vie ordinaire au sens gu\u00e9nonien de nos philistins (guerre, vaccin, v\u00e9g\u00e9tarisme) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Mais de l\u00e0 nous nous dirigeons, heureux plus que jamais, dans le logis confortable des habitants de la villa. Nous trouvons ceux-ci au milieu de leurs femmes et de leurs enfants, lisant leurs journaux, occup\u00e9s aux conversations politiques de tous les jours. Nous les entendons discourir durant un certain temps sur le mariage et le suffrage universel, la peine de mort ou les gr\u00e8ves ouvri\u00e8res, et il ne nous semble pas qu&rsquo;il f&ucirc;t possible de d\u00e9filer plus vite le chapelet des opinions publiques<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p> La presse oppresse ; elle fabrique et programme un citoyen m\u00e9canis\u00e9 et dangereux ; et l&rsquo;usure de la langue prostitu\u00e9e des journaux aide \u00e0 la fabrication de ce cr\u00e9tin ordinaire (pas de pain, pas de gaz, du vaccin, et luttons \u00e0 mort contre la Russie !) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p> &laquo; <em>Il est certain qu&rsquo;un Allemand d&rsquo;aujourd&rsquo;hui puise la majeure partie de ses lectures quotidiennes dans les \u00e9crits p\u00e9riodiques, journaux et revues, dont le langage s&rsquo;insinue dans son oreille goutte \u00e0 goutte, avec un perp\u00e9tuel rappel des m\u00eames mots et des m\u00eames tournures de phrases. Et comme il utilise g\u00e9n\u00e9ralement pour cette lecture les heures o&ugrave; son esprit fatigu\u00e9, de toute fa\u00e7on, n&rsquo;est pas pr\u00e9dispos\u00e9 \u00e0 la r\u00e9sistance, son sens du langage se familiarise peu \u00e0 peu avec cet allemand quotidien, et il lui arrive par ailleurs d&rsquo;en regretter l&rsquo;absence avec douleur. Mais les fabricants de ces journaux, d&rsquo;accord en cela avec la nature de leurs occupations, sont le plus habitu\u00e9s \u00e0 l&rsquo;\u00e9cume de ce langage journalistique<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p> La prostitution du go&ucirc;t intellectuel rejoint le d\u00e9clin du go&ucirc;t gastronomique ou musical (NDLR : que de critiques culinaires ou musicaux&hellip;) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Au sens propre du mot, ils ont perdu toute esp\u00e8ce de go&ucirc;t, et il arrive tout au plus \u00e0 leur palais de go&ucirc;ter, avec une sorte de volupt\u00e9, ce qui est tout \u00e0 fait corrompu et arbitraire. C&rsquo;est ce qui explique le tutti unisono que l&rsquo;on entonne, malgr\u00e9 ce rel\u00e2chement et cet \u00e9nervement g\u00e9n\u00e9ral, chaque fois qu&rsquo;un nouveau sol\u00e9cisme a \u00e9t\u00e9 invent\u00e9. Avec ces impertinentes corruptions du langage, on exerce sa vengeance contre celui-ci, \u00e0 cause de l&rsquo;incroyable ennui qu&rsquo;il provoque peu \u00e0 peu chez ceux qui sont \u00e0 sa solde.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est la fin de la grammaire :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>La faute grammaticale, et c&rsquo;est l\u00e0 ce qu&rsquo;il y a de singulier, ne choque donc pas notre philistin, il la salue au contraire comme un charmant d\u00e9lassement dans le d\u00e9sert aride de l&rsquo;allemand de tous les jours. Mais ce qui le blesse, c&rsquo;est ce qui est v\u00e9ritablement productif. Chez l&rsquo;\u00e9crivain-mod\u00e8le ultra-moderne la syntaxe contourn\u00e9e, guind\u00e9e ou compl\u00e8tement effiloch\u00e9e, le n\u00e9ologisme ridicule sont non seulement accept\u00e9s, on les lui compte encore comme un m\u00e9rite, comme quelque chose de piquant.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p> Le retournement des valeurs peut alors avoir lieu &ndash; dans le domaine grammatical :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Quand tout ce qui est plat, us\u00e9, sans force, vulgaire est accept\u00e9 comme la r\u00e8gle, ce qui est mauvais et corrompu comme exception charmante, alors tout ce qui est vigoureux, noble et beau tombe dans le d\u00e9cri<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Et cela rend impossible l&rsquo;acc\u00e8s aux classiques :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>S&rsquo;il est absolument impossible de faire de m\u00eame avec l&rsquo;allemand de Strauss, cela ne tient probablement pas au fait que sa langue est plus allemande que celle des deux autres, mais simplement \u00e0 ceci qu&rsquo;elle est embrouill\u00e9e et illogique, tandis que chez Kant et chez Schopenhauer elle est pleine de simplicit\u00e9 et de grandeur<\/em>&hellip; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans Zarathoustra l&rsquo;esprit aigu temp\u00eatera aussi contre les journaux. &laquo; Ils rendent leur bile et appellent cela des journaux &raquo;&hellip;<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/fr.wikisource.org\/wiki\/David_Strauss,_sectateur_et_%C3%A9crivain\">https:\/\/fr.wikisource.org\/wiki\/David_Strauss,_sectateur_et_%C3%A9crivain<\/a><\/p>\n<\/p>\n<p><p><a href=\"http:\/\/www.philotextes.info\/spip\/IMG\/pdf\/zarathoustra.pdf\">http:\/\/www.philotextes.info\/spip\/IMG\/pdf\/zarathoustra.pdf<\/a><\/p>\n<\/p>\n<p><p><a href=\"http:\/\/www.dedefensa.org\/article\/de-platon-a-cnn-lenchainement-par-les-infos\">http:\/\/www.dedefensa.org\/article\/de-platon-a-cnn-lenchainement-par-les-infos<\/a><\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.amazon.fr\/Chroniques-sur-lHistoire-Nicolas-Bonnal\/dp\/1521035520\/ref=sr_1_1?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;crid=3NJDJOXZIYBVG&#038;dib=eyJ2IjoiMSJ9.BHlv3hbrn1UQQfIR8O0f1g._0WAhOepA8SFPvXymVPWaXmlR5Qrt0_LL1z-JjRvqbU&#038;dib_tag=se&#038;keywords=BONNAL+CHRONIQUES+FIN&#038;qid=1749464797&#038;sprefix=bonnal+chroniques+fin%2Caps%2C106&#038;sr=8-1\">Chroniques sur la fin de l&rsquo;histoire<\/a>, Nicolas Bonnal <\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.dedefensa.org\/article\/goethe-et-les-entropies-du-monde-moderne\">https:\/\/www.dedefensa.org\/article\/goethe-et-les-entropies-du-monde-moderne<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nietzsche contre le fonctionnaire de l&rsquo;opinion Stupide dix-neuvi\u00e8me si\u00e8cle : cette expression incorrecte de L\u00e9on Daudet, qui fait fi de dizaines de critiques g\u00e9niaux de la modernit\u00e9 tombe \u00e0 pic pour David Strauss, biographe du pauvre J\u00e9sus et inventeur du style journalistique teuton, style qui a le don d&rsquo;\u00e9nerver Nietzsche dans une de ses consid\u00e9rations&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,2990,2991,867],"class_list":["post-81604","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-davis","tag-journalisme","tag-strauss"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81604"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81604\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}